{"id":20000,"date":"2006-04-24T23:22:00","date_gmt":"2006-04-24T23:22:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/complejidad\/archive\/2006\/04\/25\/20000.aspx"},"modified":"2006-04-24T23:22:00","modified_gmt":"2006-04-24T23:22:00","slug":"simplificando-la-complejidad-biologica-mediante-la-fisica","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000","title":{"rendered":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica"},"content":{"rendered":"<div align=\"justify\">En los \u00faltimos a\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\u00f3gicos. De hecho algunos de los acontecimeintos de los \u00faltimos a\u00f1os como la gen\u00f3mica, la prote\u00f3mica o la metabol\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\u00f3n acerca de la complejidad a diferentes niveles de la biolog\u00eda es manifiesta.<\/div>\n<p><!--more--><\/p>\n<div align=\"justify\">Uno de los principales retos lo constituye por tanto identificar donde se esconde la sencillez de la complejidad observada. Es ah\u00ed donde la f\u00edsica te\u00f3rica puede aportar conceptos, m\u00e9todos y herramientas para entender los procesos biol\u00f3gicos a trav\u00e9s de sus numerosas escalas. Estas son algunas de las ideas fundamentales que se discuten en el art\u00edculo <a href=\"http:\/\/www.escet.urjc.es\/%7Efisica\/msanjuan\/complejidad\/simplify_complex06.pdf\"><i>Simplifying Biological Complexity<\/i><\/a>&nbsp; escrito por bi\u00f3logos y f\u00edsicos de la Pennsylvania State University y que ha aparecido en el \u00faltimo n\u00famero de <i>Nature Physics<\/i>. Lo que supone un programa para las mutuas relaciones e interacciones entre bi\u00f3logos y f\u00edsicos en este siglo XXI.<\/p>\n<p>Miguel A. F. Sanju\u00e1n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\u00f3gicos. De hecho algunos de los acontecimeintos de los \u00faltimos a\u00f1os como la gen\u00f3mica, la prote\u00f3mica o la metabol\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\u00f3n acerca de la complejidad a diferentes niveles de la biolog\u00eda es manifiesta.<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[192,194,201,204,202],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En los \u00faltimos a\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\u00f3gicos. De hecho algunos de los acontecimeintos de los \u00faltimos a\u00f1os como la gen\u00f3mica, la prote\u00f3mica o la metabol\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\u00f3n acerca de la complejidad a diferentes niveles de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel A. F. Sanju\u00e1n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica - Complejidad\" \/>\n\t\t<meta property=\"og:description\" content=\"En los \u00faltimos a\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\u00f3gicos. De hecho algunos de los acontecimeintos de los \u00faltimos a\u00f1os como la gen\u00f3mica, la prote\u00f3mica o la metabol\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\u00f3n acerca de la complejidad a diferentes niveles de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-04-24T23:22:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-04-24T23:22:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica - Complejidad\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En los \u00faltimos a\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\u00f3gicos. De hecho algunos de los acontecimeintos de los \u00faltimos a\u00f1os como la gen\u00f3mica, la prote\u00f3mica o la metabol\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\u00f3n acerca de la complejidad a diferentes niveles de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000#blogposting\",\"name\":\"Simplificando la complejidad biol\\u00f3gica mediante la f\\u00edsica - Complejidad\",\"headline\":\"Simplificando la complejidad biol\\u00f3gica mediante la f\\u00edsica\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-04-24T23:22:00+01:00\",\"dateModified\":\"2006-04-24T23:22:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000#webpage\"},\"articleSection\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas, Complejidad y Biolog\\u00eda Molecular y Celular, Complejidad y Vida, F\\u00edsica Biol\\u00f3gica, F\\u00edsica, Matem\\u00e1ticas y Biolog\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas#listItem\",\"name\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas#listItem\",\"position\":2,\"name\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000#listItem\",\"name\":\"Simplificando la complejidad biol\\u00f3gica mediante la f\\u00edsica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000#listItem\",\"position\":3,\"name\":\"Simplificando la complejidad biol\\u00f3gica mediante la f\\u00edsica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas#listItem\",\"name\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad\",\"name\":\"Miguel A. F. Sanju\\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel A. F. Sanju\\u00e1n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000\",\"name\":\"Simplificando la complejidad biol\\u00f3gica mediante la f\\u00edsica - Complejidad\",\"description\":\"En los \\u00faltimos a\\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\\u00f3gicos. De hecho algunos de los acontecimeintos de los \\u00faltimos a\\u00f1os como la gen\\u00f3mica, la prote\\u00f3mica o la metabol\\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\\u00f3n acerca de la complejidad a diferentes niveles de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/04\\\/24\\\/20000#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"datePublished\":\"2006-04-24T23:22:00+01:00\",\"dateModified\":\"2006-04-24T23:22:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica - Complejidad","description":"En los \u00faltimos a\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\u00f3gicos. De hecho algunos de los acontecimeintos de los \u00faltimos a\u00f1os como la gen\u00f3mica, la prote\u00f3mica o la metabol\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\u00f3n acerca de la complejidad a diferentes niveles de","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000#blogposting","name":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica - Complejidad","headline":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#articleImage","width":217,"height":72},"datePublished":"2006-04-24T23:22:00+01:00","dateModified":"2006-04-24T23:22:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000#webpage"},"articleSection":"Biolog\u00eda Sint\u00e9tica y de Sistemas, Complejidad y Biolog\u00eda Molecular y Celular, Complejidad y Vida, F\u00edsica Biol\u00f3gica, F\u00edsica, Matem\u00e1ticas y Biolog\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas#listItem","name":"Biolog\u00eda Sint\u00e9tica y de Sistemas"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas#listItem","position":2,"name":"Biolog\u00eda Sint\u00e9tica y de Sistemas","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000#listItem","name":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000#listItem","position":3,"name":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas#listItem","name":"Biolog\u00eda Sint\u00e9tica y de Sistemas"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad","name":"Miguel A. F. Sanju\u00e1n","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel A. F. Sanju\u00e1n"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000","name":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica - Complejidad","description":"En los \u00faltimos a\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\u00f3gicos. De hecho algunos de los acontecimeintos de los \u00faltimos a\u00f1os como la gen\u00f3mica, la prote\u00f3mica o la metabol\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\u00f3n acerca de la complejidad a diferentes niveles de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"datePublished":"2006-04-24T23:22:00+01:00","dateModified":"2006-04-24T23:22:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos","og:type":"article","og:title":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica - Complejidad","og:description":"En los \u00faltimos a\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\u00f3gicos. De hecho algunos de los acontecimeintos de los \u00faltimos a\u00f1os como la gen\u00f3mica, la prote\u00f3mica o la metabol\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\u00f3n acerca de la complejidad a diferentes niveles de","og:url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000","og:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","article:published_time":"2006-04-24T23:22:00+00:00","article:modified_time":"2006-04-24T23:22:00+00:00","twitter:card":"summary","twitter:title":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica - Complejidad","twitter:description":"En los \u00faltimos a\u00f1os se ha multiplicado por un factor de escala enorme la cantidad de datos biol\u00f3gicos. De hecho algunos de los acontecimeintos de los \u00faltimos a\u00f1os como la gen\u00f3mica, la prote\u00f3mica o la metabol\u00f3mica, son algunos de los casos visibles donde la cantidad de informaci\u00f3n acerca de la complejidad a diferentes niveles de","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"20000","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:23:24","updated":"2023-06-19 08:49:03","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas\" title=\"Biolog\u00eda Sint\u00e9tica y de Sistemas\">Biolog\u00eda Sint\u00e9tica y de Sistemas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSimplificando la complejidad biol\u00f3gica mediante la f\u00edsica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad"},{"label":"Biolog\u00eda Sint\u00e9tica y de Sistemas","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas"},{"label":"Simplificando la complejidad biol\u00f3gica mediante la f\u00edsica","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/04\/24\/20000"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/20000"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/comments?post=20000"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/20000\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/media?parent=20000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/categories?post=20000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/tags?post=20000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}