{"id":48712,"date":"2006-10-30T17:28:00","date_gmt":"2006-10-30T17:28:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/complejidad\/archive\/2006\/10\/30\/48712.aspx"},"modified":"2006-10-30T17:28:00","modified_gmt":"2006-10-30T17:28:00","slug":"computacion-grid-y-sistemas-complejos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712","title":{"rendered":"Computaci\u00f3n Grid y sistemas complejos"},"content":{"rendered":"<div align=\"justify\">Hablabamos hace unos dias sobre el uso de las <A href=\"http:\/\/weblogs.madrimasd.org\/complejidad\/archive\/2006\/10\/25\/47905.aspx\">tecnolog\u00edas grid en la exploraci\u00f3n del espacio<\/a>. Y tambi\u00e9n hace poco sobre <A href=\"http:\/\/weblogs.madrimasd.org\/complejidad\/archive\/2006\/03\/24\/16697.aspx\">Computaci\u00f3n, Ciencia y Futuro<\/a>, donde se pon\u00eda de manifiesto el uso de distintas tecnolog\u00edas nuevas de computaci\u00f3n a la hora de afrontar soluciones a problemas complejos.<\/div>\n<p><!--more--><\/p>\n<div align=\"justify\">Precisamente en el servicio notiweb de madrimasd correspondiente al 30 de octubre de 2006 aparece la noticia <a href=\"http:\/\/www.madrimasd.org\/informacionIDI\/noticias\/noticia.asp?id=27864\">Computaci\u00f3n Grid: M\u00e1s all\u00e1 de los superordenadores<\/a> que puede ser de sumo inter\u00e9s para todos los aquellos interesados en el uso de las tecnolog\u00edas de computaci\u00f3n en el an\u00e1lisis de los sistemas complejos. En el art\u00edculo <a href=\"http:\/\/www.aip.org\/tip\/INPHFA\/vol-9\/iss-4\/p31.html\">Grid computing made simple,<\/a> publicado por el Industrial Physicist, que edita el American Institute of Physics, se analiza entre otras cosas la relaci\u00f3n entre la tecnolog\u00eda grid y la simulaci\u00f3n de sistemas complejos.<\/p>\n<p>Miguel A. F. Sanju\u00e1n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hablabamos hace unos dias sobre el uso de las tecnolog\u00edas grid en la exploraci\u00f3n del espacio. Y tambi\u00e9n hace poco sobre Computaci\u00f3n, Ciencia y Futuro, donde se pon\u00eda de manifiesto el uso de distintas tecnolog\u00edas nuevas de computaci\u00f3n a la hora de afrontar soluciones a problemas complejos.<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[206],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hablabamos hace unos dias sobre el uso de las tecnolog\u00edas grid en la exploraci\u00f3n del espacio. Y tambi\u00e9n hace poco sobre Computaci\u00f3n, Ciencia y Futuro, donde se pon\u00eda de manifiesto el uso de distintas tecnolog\u00edas nuevas de computaci\u00f3n a la hora de afrontar soluciones a problemas complejos. Precisamente en el servicio notiweb de madrimasd correspondiente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel A. F. Sanju\u00e1n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Computaci\u00f3n Grid y sistemas complejos - Complejidad\" \/>\n\t\t<meta property=\"og:description\" content=\"Hablabamos hace unos dias sobre el uso de las tecnolog\u00edas grid en la exploraci\u00f3n del espacio. Y tambi\u00e9n hace poco sobre Computaci\u00f3n, Ciencia y Futuro, donde se pon\u00eda de manifiesto el uso de distintas tecnolog\u00edas nuevas de computaci\u00f3n a la hora de afrontar soluciones a problemas complejos. Precisamente en el servicio notiweb de madrimasd correspondiente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-10-30T17:28:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-10-30T17:28:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Computaci\u00f3n Grid y sistemas complejos - Complejidad\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hablabamos hace unos dias sobre el uso de las tecnolog\u00edas grid en la exploraci\u00f3n del espacio. Y tambi\u00e9n hace poco sobre Computaci\u00f3n, Ciencia y Futuro, donde se pon\u00eda de manifiesto el uso de distintas tecnolog\u00edas nuevas de computaci\u00f3n a la hora de afrontar soluciones a problemas complejos. Precisamente en el servicio notiweb de madrimasd correspondiente\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712#blogposting\",\"name\":\"Computaci\\u00f3n Grid y sistemas complejos - Complejidad\",\"headline\":\"Computaci\\u00f3n Grid y sistemas complejos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-10-30T17:28:00+01:00\",\"dateModified\":\"2006-10-30T17:28:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712#webpage\"},\"articleSection\":\"Computaci\\u00f3n y futuro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/computacion-y-futuro#listItem\",\"name\":\"Computaci\\u00f3n y futuro\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/computacion-y-futuro#listItem\",\"position\":2,\"name\":\"Computaci\\u00f3n y futuro\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/computacion-y-futuro\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712#listItem\",\"name\":\"Computaci\\u00f3n Grid y sistemas complejos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712#listItem\",\"position\":3,\"name\":\"Computaci\\u00f3n Grid y sistemas complejos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/computacion-y-futuro#listItem\",\"name\":\"Computaci\\u00f3n y futuro\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad\",\"name\":\"Miguel A. F. Sanju\\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel A. F. Sanju\\u00e1n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712\",\"name\":\"Computaci\\u00f3n Grid y sistemas complejos - Complejidad\",\"description\":\"Hablabamos hace unos dias sobre el uso de las tecnolog\\u00edas grid en la exploraci\\u00f3n del espacio. Y tambi\\u00e9n hace poco sobre Computaci\\u00f3n, Ciencia y Futuro, donde se pon\\u00eda de manifiesto el uso de distintas tecnolog\\u00edas nuevas de computaci\\u00f3n a la hora de afrontar soluciones a problemas complejos. Precisamente en el servicio notiweb de madrimasd correspondiente\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/10\\\/30\\\/48712#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"datePublished\":\"2006-10-30T17:28:00+01:00\",\"dateModified\":\"2006-10-30T17:28:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Computaci\u00f3n Grid y sistemas complejos - Complejidad","description":"Hablabamos hace unos dias sobre el uso de las tecnolog\u00edas grid en la exploraci\u00f3n del espacio. Y tambi\u00e9n hace poco sobre Computaci\u00f3n, Ciencia y Futuro, donde se pon\u00eda de manifiesto el uso de distintas tecnolog\u00edas nuevas de computaci\u00f3n a la hora de afrontar soluciones a problemas complejos. Precisamente en el servicio notiweb de madrimasd correspondiente","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712#blogposting","name":"Computaci\u00f3n Grid y sistemas complejos - Complejidad","headline":"Computaci\u00f3n Grid y sistemas complejos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#articleImage","width":217,"height":72},"datePublished":"2006-10-30T17:28:00+01:00","dateModified":"2006-10-30T17:28:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712#webpage"},"articleSection":"Computaci\u00f3n y futuro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/computacion-y-futuro#listItem","name":"Computaci\u00f3n y futuro"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/computacion-y-futuro#listItem","position":2,"name":"Computaci\u00f3n y futuro","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/computacion-y-futuro","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712#listItem","name":"Computaci\u00f3n Grid y sistemas complejos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712#listItem","position":3,"name":"Computaci\u00f3n Grid y sistemas complejos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/computacion-y-futuro#listItem","name":"Computaci\u00f3n y futuro"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad","name":"Miguel A. F. Sanju\u00e1n","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel A. F. Sanju\u00e1n"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712","name":"Computaci\u00f3n Grid y sistemas complejos - Complejidad","description":"Hablabamos hace unos dias sobre el uso de las tecnolog\u00edas grid en la exploraci\u00f3n del espacio. Y tambi\u00e9n hace poco sobre Computaci\u00f3n, Ciencia y Futuro, donde se pon\u00eda de manifiesto el uso de distintas tecnolog\u00edas nuevas de computaci\u00f3n a la hora de afrontar soluciones a problemas complejos. Precisamente en el servicio notiweb de madrimasd correspondiente","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"datePublished":"2006-10-30T17:28:00+01:00","dateModified":"2006-10-30T17:28:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos","og:type":"article","og:title":"Computaci\u00f3n Grid y sistemas complejos - Complejidad","og:description":"Hablabamos hace unos dias sobre el uso de las tecnolog\u00edas grid en la exploraci\u00f3n del espacio. Y tambi\u00e9n hace poco sobre Computaci\u00f3n, Ciencia y Futuro, donde se pon\u00eda de manifiesto el uso de distintas tecnolog\u00edas nuevas de computaci\u00f3n a la hora de afrontar soluciones a problemas complejos. Precisamente en el servicio notiweb de madrimasd correspondiente","og:url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712","og:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","article:published_time":"2006-10-30T17:28:00+00:00","article:modified_time":"2006-10-30T17:28:00+00:00","twitter:card":"summary","twitter:title":"Computaci\u00f3n Grid y sistemas complejos - Complejidad","twitter:description":"Hablabamos hace unos dias sobre el uso de las tecnolog\u00edas grid en la exploraci\u00f3n del espacio. Y tambi\u00e9n hace poco sobre Computaci\u00f3n, Ciencia y Futuro, donde se pon\u00eda de manifiesto el uso de distintas tecnolog\u00edas nuevas de computaci\u00f3n a la hora de afrontar soluciones a problemas complejos. Precisamente en el servicio notiweb de madrimasd correspondiente","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"48712","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:56:17","updated":"2023-06-19 09:15:53","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/computacion-y-futuro\" title=\"Computaci\u00f3n y futuro\">Computaci\u00f3n y futuro<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tComputaci\u00f3n Grid y sistemas complejos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad"},{"label":"Computaci\u00f3n y futuro","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/computacion-y-futuro"},{"label":"Computaci\u00f3n Grid y sistemas complejos","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/10\/30\/48712"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/48712"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/comments?post=48712"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/48712\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/media?parent=48712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/categories?post=48712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/tags?post=48712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}