{"id":64965,"date":"2007-05-05T08:08:00","date_gmt":"2007-05-05T08:08:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/complejidad\/archive\/2007\/05\/05\/64965.aspx"},"modified":"2007-05-05T08:08:00","modified_gmt":"2007-05-05T08:08:00","slug":"el-mundo-de-los-fractales","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965","title":{"rendered":"El mundo de los fractales"},"content":{"rendered":"<div align=\"justify\">Basta observar la naturaleza para percatarse que la geometr\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\u00eda euclidea.<\/div>\n<p><!--more--><\/p>\n<div align=\"justify\">Precisamente tras los trabajos de Benoit Mandelbrot, entre otros, se ha desarrollado la llamada geometr\u00eda fractal, que entre otras pretensiones intenta representar la geometr\u00eda escondida de la naturaleza. El reciente libro <i>Le monde des fractales-La g\u00e9om\u00e9trie cach\u00e9e de la nature<\/i> que ha sido editado por Ellipses, Paris, 2006 es un intento de presentar las cuestiones fundamentales de la geometr\u00eda fractal a <\/p>\n<div align=\"justify\"><\/div>\n<div align=\"center\"><img decoding=\"async\" src=\"\/blogs\/complejidad\/wp-content\/blogs.dir\/52\/files\/184\/o_monde_fractales.gif\"> <\/div>\n<p>un p\u00fablico diverso, mostrando no solamente la influencia de los fractales en las ciencias de la naturaleza, sino tambi\u00e9n las artes y las ciencias sociales. El libro est\u00e1 escrito por Jacques Dubois, geof\u00edsico y profesor em\u00e9rito del Instituto de F\u00edsica del Globo de Paris y Jean Chaline, paleontologo y director de investigaci\u00f3n eme\u00e9rito en el Laboratorio de Biogeociencias de la Universidad de la Borgo\u00f1a en Dijon. Adem\u00e1s el libro cuenta con el pr\u00f3logo de Claude All\u00e8gre, geof\u00edsico y antiguo ministro de educaci\u00f3n nacional franc\u00e9s. Sin duda, una excelente obra para recorrer el mundo de los fractales y sus aplicaciones, un concepto importante en las ciencias de la complejidad.<\/p>\n<p>Miguel A. F. Sanju\u00e1n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Basta observar la naturaleza para percatarse que la geometr\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\u00eda euclidea.<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[207,196],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Basta observar la naturaleza para percatarse que la geometr\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\u00eda euclidea. Precisamente tras los trabajos de Benoit Mandelbrot, entre otros, se ha desarrollado la llamada geometr\u00eda fractal, que entre otras\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel A. F. Sanju\u00e1n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El mundo de los fractales - Complejidad\" \/>\n\t\t<meta property=\"og:description\" content=\"Basta observar la naturaleza para percatarse que la geometr\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\u00eda euclidea. Precisamente tras los trabajos de Benoit Mandelbrot, entre otros, se ha desarrollado la llamada geometr\u00eda fractal, que entre otras\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2007-05-05T08:08:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2007-05-05T08:08:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El mundo de los fractales - Complejidad\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Basta observar la naturaleza para percatarse que la geometr\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\u00eda euclidea. Precisamente tras los trabajos de Benoit Mandelbrot, entre otros, se ha desarrollado la llamada geometr\u00eda fractal, que entre otras\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965#blogposting\",\"name\":\"El mundo de los fractales - Complejidad\",\"headline\":\"El mundo de los fractales\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/complejidad\\\/wp-content\\\/blogs.dir\\\/52\\\/files\\\/184\\\/o_monde_fractales.gif\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965\\\/#articleImage\"},\"datePublished\":\"2007-05-05T08:08:00+01:00\",\"dateModified\":\"2007-05-05T08:08:00+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965#webpage\"},\"articleSection\":\"Complejidad, Ciencias de la Tierra y Medio Ambiente, Fractales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/fractales#listItem\",\"name\":\"Fractales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/fractales#listItem\",\"position\":2,\"name\":\"Fractales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/fractales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965#listItem\",\"name\":\"El mundo de los fractales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965#listItem\",\"position\":3,\"name\":\"El mundo de los fractales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/fractales#listItem\",\"name\":\"Fractales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad\",\"name\":\"Miguel A. F. Sanju\\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel A. F. Sanju\\u00e1n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965\",\"name\":\"El mundo de los fractales - Complejidad\",\"description\":\"Basta observar la naturaleza para percatarse que la geometr\\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\\u00eda euclidea. Precisamente tras los trabajos de Benoit Mandelbrot, entre otros, se ha desarrollado la llamada geometr\\u00eda fractal, que entre otras\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2007\\\/05\\\/05\\\/64965#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"datePublished\":\"2007-05-05T08:08:00+01:00\",\"dateModified\":\"2007-05-05T08:08:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El mundo de los fractales - Complejidad","description":"Basta observar la naturaleza para percatarse que la geometr\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\u00eda euclidea. Precisamente tras los trabajos de Benoit Mandelbrot, entre otros, se ha desarrollado la llamada geometr\u00eda fractal, que entre otras","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965#blogposting","name":"El mundo de los fractales - Complejidad","headline":"El mundo de los fractales","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/complejidad\/wp-content\/blogs.dir\/52\/files\/184\/o_monde_fractales.gif","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965\/#articleImage"},"datePublished":"2007-05-05T08:08:00+01:00","dateModified":"2007-05-05T08:08:00+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965#webpage"},"articleSection":"Complejidad, Ciencias de la Tierra y Medio Ambiente, Fractales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/fractales#listItem","name":"Fractales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/fractales#listItem","position":2,"name":"Fractales","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/fractales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965#listItem","name":"El mundo de los fractales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965#listItem","position":3,"name":"El mundo de los fractales","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/fractales#listItem","name":"Fractales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad","name":"Miguel A. F. Sanju\u00e1n","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel A. F. Sanju\u00e1n"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965","name":"El mundo de los fractales - Complejidad","description":"Basta observar la naturaleza para percatarse que la geometr\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\u00eda euclidea. Precisamente tras los trabajos de Benoit Mandelbrot, entre otros, se ha desarrollado la llamada geometr\u00eda fractal, que entre otras","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"datePublished":"2007-05-05T08:08:00+01:00","dateModified":"2007-05-05T08:08:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos","og:type":"article","og:title":"El mundo de los fractales - Complejidad","og:description":"Basta observar la naturaleza para percatarse que la geometr\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\u00eda euclidea. Precisamente tras los trabajos de Benoit Mandelbrot, entre otros, se ha desarrollado la llamada geometr\u00eda fractal, que entre otras","og:url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965","og:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","article:published_time":"2007-05-05T08:08:00+00:00","article:modified_time":"2007-05-05T08:08:00+00:00","twitter:card":"summary","twitter:title":"El mundo de los fractales - Complejidad","twitter:description":"Basta observar la naturaleza para percatarse que la geometr\u00eda asociada a ella no es tan simple como nos la han podido contar o nos la hemos imaginado de acuerdo con las premisas de la geometr\u00eda euclidea. Precisamente tras los trabajos de Benoit Mandelbrot, entre otros, se ha desarrollado la llamada geometr\u00eda fractal, que entre otras","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"64965","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:56:17","updated":"2023-06-19 09:18:04","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/fractales\" title=\"Fractales\">Fractales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl mundo de los fractales\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad"},{"label":"Fractales","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/fractales"},{"label":"El mundo de los fractales","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2007\/05\/05\/64965"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/64965"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/comments?post=64965"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/64965\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/media?parent=64965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/categories?post=64965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/tags?post=64965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}