{"id":947,"date":"2013-12-12T12:20:20","date_gmt":"2013-12-12T11:20:20","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/?p=947"},"modified":"2013-12-12T12:21:50","modified_gmt":"2013-12-12T11:21:50","slug":"conexiones-entre-la-dieta-y-la-demencia","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/2013\/12\/12\/947\/","title":{"rendered":"Conexiones entre la dieta y la demencia"},"content":{"rendered":"<p><a title=\"omega 3 fatty acids por malloreigh, en Flickr\" href=\"http:\/\/www.flickr.com\/photos\/malloreigh\/161251281\/\"><img decoding=\"async\" class=\"alignleft\" style=\"margin: 10px;\" src=\"http:\/\/farm1.staticflickr.com\/56\/161251281_7ff7e8011e.jpg\" alt=\"omega 3 fatty acids\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">La enfermedad de Alzheimer es una afecci\u00f3n degenerativa que supone entre un 50-70% de todos los casos de demencia. Se caracteriza por un proceso de muerte neuronal lento y progresivo que provoca p\u00e9rdida de memoria y confusi\u00f3n y que se agrava con el tiempo.<br \/>\nUn <strong>proyecto de investigaci\u00f3n europeo<\/strong> est\u00e1 logrando <strong>progresos importantes<\/strong> con los que frenar la enfermedad a trav\u00e9s de la <strong>dieta<\/strong>.<\/p>\n<p>Este proyecto, financiado con fondos europeos y titulado <a href=\"http:\/\/www.lipididiet.eu\" target=\"_blank\">LIPIDIDIET<\/a> (\u00ab<em>Trapeutic and preventive impact of nutritional lipids on neuronal and cognitive performance in ageing, Alzheimer&#8217;s disease and vascular dementia<\/em>\u00bb), est\u00e1 desarrollando una dieta lip\u00eddica que podr\u00eda retrasar o prevenir la aparici\u00f3n del Alzheimer y de otras demencias.\u00a0Una dieta de este tipo, basada por ejemplo en l\u00edpidos omega-3, tambi\u00e9n contribuir\u00eda a mantener la funci\u00f3n cognitiva normal durante el proceso de envejecimiento y reducir el riesgo de padecer afecciones cerebrovasculares, seg\u00fan afirmaron los socios del proyecto.<br \/>\nDesde su puesta en marcha en 2008, LIPIDIDIET ha descrito en detalle <strong>varios factores de riesgo gen\u00e9ticos, del estilo de vida y de la dieta<\/strong> y combinaciones de ellos que se corresponden con un aumento del riesgo de padecer demencia.<\/p>\n<p>Los socios del proyecto, coordinados por la <a href=\"http:\/\/www.uni-saarland.de\/en\/\" target=\"_blank\">Universidad del Sarre<\/a> (Alemania), tambi\u00e9n han ampliado considerablemente el conocimiento que se posee sobre las rutas moleculares y celulares que conducen a la demencia. Los genes, el metabolismo de l\u00edpidos y la inflamaci\u00f3n se han descubierto como factores en este grupo.\u00a0El innovador planteamiento adoptado por el equipo le permiti\u00f3 aislar nuevos mecanismos por los que las mol\u00e9culas amiloides, responsables de la demencia, interfieren en la transmisi\u00f3n sin\u00e1ptica (el traspaso de un impulso neuronal de una fibra nerviosa a otra) y la diferenciaci\u00f3n y la funci\u00f3n celulares. De sus resultados destaca la capacidad de los l\u00edpidos ingeridos en la dieta para reducir dicha interferencia.<br \/>\nEl conocimiento extra\u00eddo de este estudio contribuy\u00f3 a que el equipo de LIPIDIDIET crease formulaciones y <strong>m\u00e9todos diet\u00e9ticos<\/strong> en principio capaces de <strong>reducir el riesgo<\/strong> de afrontar un mayor declive cognitivo con el paso de los a\u00f1os.<\/p>\n<p>Los datos obtenidos por LIPIDIDIET redundar\u00e1n en beneficio de pacientes y m\u00e9dicos y adem\u00e1s resultar\u00e1n \u00fatiles para la <strong>industria alimentaria<\/strong> al aportar una justificaci\u00f3n cient\u00edfica a los beneficios sanitarios de algunos productos. Una dieta m\u00e1s sana adem\u00e1s aumenta el bienestar entre los m\u00e1s mayores.<\/p>\n<p>El equipo trabaja ahora en nuevas dietas experimentales que someter\u00e1n a ensayo cl\u00ednico y para las que ya cuentan con sujetos dispuestos a someterse a estudio.<\/p>\n<p>Este proyecto recibi\u00f3 de la UE una financiaci\u00f3n cercana a los 6 millones de euros.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Para m\u00e1s informaci\u00f3n, consulte la ficha del proyecto, <a href=\"http:\/\/cordis.europa.eu\/projects\/rcn\/88395_es.html\" target=\"_blank\">aqu\u00ed<\/a>.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><span style=\"font-size: 13px;\">Fuente: <\/span><a style=\"font-size: 13px;\" href=\"http:\/\/cordis.europa.eu\/news\/home_es.html\" target=\"_blank\">Cordis<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La enfermedad de Alzheimer es una afecci\u00f3n degenerativa que supone entre un 50-70% de todos los casos de demencia. Se caracteriza por un proceso de muerte neuronal lento y progresivo que provoca p\u00e9rdida de memoria y confusi\u00f3n y que se agrava con el tiempo. Un proyecto de investigaci\u00f3n europeo est\u00e1 logrando progresos importantes con los que frenar la enfermedad a trav\u00e9s de la dieta. Este proyecto, financiado con fondos europeos y titulado LIPIDIDIET (\u00abTrapeutic and preventive impact of nutritional lipids on neuronal and cognitive performance in ageing, Alzheimer&#8217;s disease and vascular dementia\u00bb), est\u00e1 desarrollando una dieta lip\u00eddica que podr\u00eda retrasar\u2026<\/p>\n","protected":false},"author":156,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[294],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/posts\/947"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/users\/156"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/comments?post=947"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/posts\/947\/revisions"}],"predecessor-version":[{"id":950,"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/posts\/947\/revisions\/950"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/media?parent=947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/categories?post=947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/envejecer-positivo\/wp-json\/wp\/v2\/tags?post=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}