{"id":318,"date":"2016-10-10T15:27:09","date_gmt":"2016-10-10T14:27:09","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/fisicateorica\/?p=318"},"modified":"2016-10-10T15:27:09","modified_gmt":"2016-10-10T14:27:09","slug":"el-canal-de-youtube-del-ift-supera-el-millon-de-visualizaciones","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/2016\/10\/10\/318\/","title":{"rendered":"El canal de YouTube del IFT supera el mill\u00f3n de visualizaciones"},"content":{"rendered":"<div>\n<div>\n<div>\n<div><img decoding=\"async\" src=\"http:\/\/www.ift.uam-csic.es\/sites\/default\/files\/styles\/panopoly_image_full\/public\/featured\/ift_youtube_0.jpg?itok=n-eE-Ei5\" alt=\"\" width=\"300\" height=\"111\" \/><\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>El canal de YouTube del IFT supera el mill\u00f3n de visualizaciones\u00a0y cuenta con m\u00e1s de 42.000 suscriptores. En este canal se a\u00f1ade peri\u00f3dicamente material de divulgaci\u00f3n de producci\u00f3n propia sobre las l\u00edneas de investigaci\u00f3n del IFT, charlas de sus investigadores, y una serie de v\u00eddeos de animaci\u00f3n elaborados en colaboraci\u00f3n con Quantum Fracture.<\/p>\n<p>M\u00e1s informaci\u00f3n\u00a0<a href=\"https:\/\/www.youtube.com\/IFTMadrid\">aqu\u00ed<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El canal de YouTube del IFT supera el mill\u00f3n de visualizaciones\u00a0y cuenta con m\u00e1s de 42.000 suscriptores. En este canal se a\u00f1ade peri\u00f3dicamente material de divulgaci\u00f3n de producci\u00f3n propia sobre las l\u00edneas de investigaci\u00f3n del IFT, charlas de sus investigadores, y una serie de v\u00eddeos de animaci\u00f3n elaborados en colaboraci\u00f3n con Quantum Fracture. M\u00e1s informaci\u00f3n\u00a0aqu\u00ed<\/p>\n","protected":false},"author":201,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[7197],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts\/318"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/users\/201"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/comments?post=318"}],"version-history":[{"count":1,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts\/318\/revisions"}],"predecessor-version":[{"id":319,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts\/318\/revisions\/319"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/media?parent=318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/categories?post=318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/tags?post=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}