{"id":376,"date":"2017-02-03T16:34:52","date_gmt":"2017-02-03T15:34:52","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/fisicateorica\/?p=376"},"modified":"2017-02-03T16:34:52","modified_gmt":"2017-02-03T15:34:52","slug":"ift-responde-edicion-especial-dia-internacional-de-la-mujer-y-la-nina-en-la-ciencia","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/2017\/02\/03\/376\/","title":{"rendered":"IFT Responde: Edici\u00f3n Especial D\u00eda Internacional de la Mujer y la Ni\u00f1a en la Ciencia"},"content":{"rendered":"<div>\n<div>\n<div><a href=\"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/files\/2017\/02\/myc.001.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-377\" title=\"myc.001\" src=\"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/files\/2017\/02\/myc.001-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/files\/2017\/02\/myc.001-300x225.jpg 300w, https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/files\/2017\/02\/myc.001.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>El Instituto de F\u00edsica Te\u00f3rica IFT UAM-CSIC se sumar\u00e1 a las actividades organizadas con motivo del D\u00eda Internacional de la Mujer y la Ni\u00f1a en la Ciencia,\u00a0que tendr\u00e1 lugar el d\u00eda 11 de Febrero de 2017.<\/div>\n<p>Durante la semana del 6 al 11 de febrero, investigadoras del Instituto de F\u00edsica Te\u00f3rica de Madrid participar\u00e1n en una edici\u00f3n especial de IFT Responde, publicando v\u00eddeos en el\u00a0<a href=\"https:\/\/www.youtube.com\/IFTMadrid\">canal de YouTube del IFT<\/a>\u00a0en los que responden a las mejores preguntas recibidas sobre sus temas de investigaci\u00f3n, en los campos de la F\u00edsica de Part\u00edculas, las Astroparticulas y la Cosmolog\u00eda.<\/p>\n<p>Se publicar\u00e1n varios v\u00eddeos diarios, cubriendo temas que abarcan desde el bos\u00f3n de Higgs y la teor\u00eda de cuerdas hasta el origen del universo y los agujeros negros.<\/p>\n<p>Las preguntas se pueden formular como comentarios en este\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=-vutxoeoUV4\">v\u00eddeo<\/a>.<\/p>\n<p>M\u00e1s informaci\u00f3n:<\/p>\n<p>&#8211;\u00a0<a href=\"https:\/\/11defebrero.org\/2017\/01\/16\/ift-responde-edicion-especial\/\">P\u00e1gina web del 11 de Febrero<\/a><\/p>\n<p>&#8211;\u00a0<a href=\"http:\/\/www.ift.uam-csic.es\/es\/file\/1305\/download?token=gm4ZLN4UzJMdDFnHwx8BBZsL4BKnazK07AX1MF38l3U\">Nota de prensa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto de F\u00edsica Te\u00f3rica IFT UAM-CSIC se sumar\u00e1 a las actividades organizadas con motivo del D\u00eda Internacional de la Mujer y la Ni\u00f1a en la Ciencia,\u00a0que tendr\u00e1 lugar el d\u00eda 11 de Febrero de 2017. Durante la semana del 6 al 11 de febrero, investigadoras del Instituto de F\u00edsica Te\u00f3rica de Madrid participar\u00e1n en una edici\u00f3n especial de IFT Responde, publicando v\u00eddeos en el\u00a0canal de YouTube del IFT\u00a0en los que responden a las mejores preguntas recibidas sobre sus temas de investigaci\u00f3n, en los campos de la F\u00edsica de Part\u00edculas, las Astroparticulas y la Cosmolog\u00eda. Se publicar\u00e1n varios v\u00eddeos diarios,\u2026<\/p>\n","protected":false},"author":201,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[7197],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts\/376"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/users\/201"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/comments?post=376"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts\/376\/revisions"}],"predecessor-version":[{"id":379,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts\/376\/revisions\/379"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/media?parent=376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/categories?post=376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/tags?post=376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}