{"id":948,"date":"2021-05-05T14:02:35","date_gmt":"2021-05-05T13:02:35","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/fisicateorica\/?p=948"},"modified":"2021-05-05T14:07:31","modified_gmt":"2021-05-05T13:07:31","slug":"se-estan-rebelando-los-muones","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/2021\/05\/05\/948\/","title":{"rendered":"\u00bfSe est\u00e1n REBELANDO los muones?"},"content":{"rendered":"<p>Entre el ruido y la furia sobre los muones y su desaf\u00edo al Modelo Est\u00e1ndar, Carlos Pena, experto en F\u00edsica de Part\u00edculas e interacciones fuertes del IFT, nos aclara qu\u00e9 es el momento magn\u00e9tico an\u00f3malo de los muones, el revuelo que han montado y las sorpresas que nos puede traer en los pr\u00f3ximos a\u00f1os.<\/p>\n<p>[youtube]https:\/\/youtu.be\/v-nSdBbUAqg [\/youtube]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre el ruido y la furia sobre los muones y su desaf\u00edo al Modelo Est\u00e1ndar, Carlos Pena, experto en F\u00edsica de Part\u00edculas e interacciones fuertes del IFT, nos aclara qu\u00e9 es el momento magn\u00e9tico an\u00f3malo de los muones, el revuelo que han montado y las sorpresas que nos puede traer en los pr\u00f3ximos a\u00f1os. [youtube]https:\/\/youtu.be\/v-nSdBbUAqg [\/youtube]<\/p>\n","protected":false},"author":201,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[7197],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts\/948"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/users\/201"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/comments?post=948"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts\/948\/revisions"}],"predecessor-version":[{"id":951,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/posts\/948\/revisions\/951"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/media?parent=948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/categories?post=948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/fisicateorica\/wp-json\/wp\/v2\/tags?post=948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}