{"id":347,"date":"2012-03-25T10:37:44","date_gmt":"2012-03-25T09:37:44","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/?p=347"},"modified":"2012-05-25T22:30:13","modified_gmt":"2012-05-25T21:30:13","slug":"los-nanotubos-de-carbono-y-la-ingenieria-de-tejidos-i","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/","title":{"rendered":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I)"},"content":{"rendered":"<p style=\"text-align: center;\">Por <strong><a title=\"Rafael Daza\" href=\"http:\/\/mater.upm.es\/Directorio\/Investigadores\/PreDoc\/Daza.asp\" target=\"_blank\">Rafael Daza<\/a> <\/strong>(Universidad Polit\u00e9cnica de Madrid)<\/p>\n<p>La Ingenier\u00eda de tejidos es una disciplina que persigue remplazar tejido da\u00f1ado o enfermo por un sustituto biol\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \u00e1reas tan dispares como las relativas al trasplante de c\u00e9lulas y \u00f3rganos y la ciencia de materiales o la ingenier\u00eda, han contribuido al continuo desarrollo de la ingenier\u00eda de tejidos y la medicina regenerativa.<br \/>\nAl igual que la regeneraci\u00f3n tisular, la cual supone el empleo de c\u00e9lulas para formar estructuras de mayores dimensiones, la nanotecnolog\u00eda es una disciplina \u201cbottom-up\u201d (de abajo a arriba) cuyo fundamento es el ensamble de elementos simples para constituir estructuras complejas. Recordemos que en un post anterior defin\u00edamos la nanotecnolog\u00eda como el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es el nan\u00f3metro, 1 nm equivale a 10-9 m, esto es, la millon\u00e9sima parte del mil\u00edmetro), y la explotaci\u00f3n de fen\u00f3menos y propiedades de la propia materia a dicha escala. Entonces vimos que los principales \u201cladrillos de la vida\u201d existen en esta escala nanom\u00e9trica de la que hablamos.<\/p>\n<p>La presencia de nano-dimensionalidad en la naturaleza ha llevado a los investigadores a plantearse la viabilidad de emplear nanomateriales tambi\u00e9n en la ingenier\u00eda de tejidos. De hecho, en los \u00faltimos a\u00f1os son numerosos los estudios que muestran la poderosa influencia de una topograf\u00eda nanoestructurada en el comportamiento celular, observ\u00e1ndose su repercusi\u00f3n sobre procesos celulares tan vitales como la adhesi\u00f3n, proliferaci\u00f3n y\/o reorganizaci\u00f3n del citoesqueleto e incluso en la regulaci\u00f3n de la expresi\u00f3n de sus genes.<br \/>\nDe entre todos los nanomateriales que actualmente est\u00e1n en proceso de investigaci\u00f3n, aqu\u00ed nos centraremos en los nanotubos de carbono debido al enorme abanico de aplicaciones que se les atribuye en el \u00e1mbito de la medicina regenerativa. Los nanotubos son una de las formas alotr\u00f3picas del carbono cuya geometr\u00eda cil\u00edndrica es el resultado del enrollamiento sobre s\u00ed mismas de una o varias l\u00e1minas de grafeno. Cuando se trata de una sola l\u00e1mina (Figura 1A), los nanotubos reciben el nombre de singlewalled carbon nanotubes (SWNT) mientras que el enrollamiento conc\u00e9ntrico de varias l\u00e1minas (Figura 1B), da lugar a la formaci\u00f3n de los multiwalled carbon nanotubes (MWNT).<\/p>\n<p style=\"text-align: center;\">&nbsp;<\/p>\n<figure id=\"attachment_349\" aria-describedby=\"caption-attachment-349\" style=\"width: 518px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-1.jpg\"><img decoding=\"async\" class=\"size-full wp-image-349   \" title=\"carbon nanotubes 1\" src=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-1.jpg\" alt=\"\" width=\"518\" height=\"326\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-1.jpg 1800w, https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-1-300x188.jpg 300w, https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-1-1024x644.jpg 1024w\" sizes=\"(max-width: 518px) 100vw, 518px\" \/><\/a><figcaption id=\"caption-attachment-349\" class=\"wp-caption-text\">Figura 1. Diagrama de un SWNT (A) y de un MWNT (B) con sus dimensiones caracter\u00edsticas.<\/figcaption><\/figure>\n<p>Desde su origen [1], los nanotubos de carbono han despertado el inter\u00e9s de la comunidad cient\u00edfica como consecuencia de las extraordinarias propiedades que exhiben. Poseen un amplio rango de caracter\u00edsticas electr\u00f3nicas, t\u00e9rmicas y estructurales en funci\u00f3n de su di\u00e1metro, longitud y quiralidad (\u00e1ngulo de enrollamiento respecto de la direcci\u00f3n axial del cilindro resultante). Menci\u00f3n especial merecen sus propiedades mec\u00e1nicas (Figura 2): los nanotubos de carbono presentan el m\u00f3dulo de rigidez y la tensi\u00f3n de rotura mayor de cuantos materiales conoce el hombre (1.5 TPa y 150 GPa, respectivamente).<\/p>\n<figure id=\"attachment_351\" aria-describedby=\"caption-attachment-351\" style=\"width: 480px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-2.jpg\"><img decoding=\"async\" class=\"size-full wp-image-351 \" title=\"carbon nanotubes 2\" src=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-2.jpg\" alt=\"\" width=\"480\" height=\"300\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-2.jpg 600w, https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-2-300x187.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/a><figcaption id=\"caption-attachment-351\" class=\"wp-caption-text\">Figura 2. Debido a sus solicitaciones mec\u00e1nicas, la idea ut\u00f3pica de construir un ascensor espacial que comunicara la Tierra con su sat\u00e9lite s\u00f3lo ser\u00eda estructuralmente viable si se construyera mediante nanotubos de carbono.<\/figcaption><\/figure>\n<p>A pesar de su reciente inclusi\u00f3n en el mundo de la ingenier\u00eda de tejidos (2004), son cuatro las \u00e1reas en las que se espera que los nanotubos tengan gran presencia: marcado y seguimiento de c\u00e9lulas, sensores del comportamiento celular, promotores del comportamiento celular y constituyentes de soportes estructurales o scaffolds. Mientras que las dos primeras \u00e1reas est\u00e1n encaminadas a analizar c\u00f3mo responden las c\u00e9lulas al tejido dise\u00f1ado, las dos \u00faltimas tienen por objetivo actuar sobre las propias c\u00e9lulas y el medio que las sustenta con el fin de mejorar los tejidos dise\u00f1ados y favorecer la proliferaci\u00f3n y diferenciaci\u00f3n de las c\u00e9lulas en ellos. Dedicaremos las \u00faltimas l\u00edneas de este post a las dos primeras \u00e1reas remitiendo al lector a un siguiente post en el que abordaremos las dos \u00faltimas.<\/p>\n<p><span style=\"text-decoration: underline;\">1.\tMarcado y seguimiento de c\u00e9lulas implantadas.<\/span><br \/>\nLa capacidad para rastrear las c\u00e9lulas implantadas y observar su progresi\u00f3n en la formaci\u00f3n de tejido in vivo de manera no invasiva es de importancia capital, especialmente, cuando las construcciones artificiales son de tama\u00f1os biol\u00f3gicamente significativos. Marcando las c\u00e9lulas implantadas se podr\u00eda, no solamente evaluar la viabilidad del tejido dise\u00f1ado sino, adem\u00e1s, mejorar el conocimiento acerca de la biodistribuci\u00f3n y rutas de migraci\u00f3n de las c\u00e9lulas trasplantadas. Sin embargo, para tales fines, es preciso que el agente de contraste in vivo tenga buena biocompatibilidad, alta capacidad de producir contraste y estabilidad.<\/p>\n<p>Los nanotubos de carbono han demostrado poseer varias de estas propiedades. Pondremos un ejemplo. El grupo del profesor Strano de la Universidad de Illinois encapsul\u00f3 \u00e1cidos nucl\u00e9icos en varios SWNTs y los introdujo en el interior de un tipo de c\u00e9lula madre, los mioblastos. Mediante espectroscop\u00eda Raman observaron la supervivencia de la estructura en el interior de las c\u00e9lulas durante repetidas divisiones celulares lo que sugiere que tales sondas podr\u00edan ser empleadas para estudiar la proliferaci\u00f3n y diferenciaci\u00f3n de c\u00e9lulas madre [2], paso clave en la regeneraci\u00f3n de tejidos. Adem\u00e1s, dado que la espectroscop\u00eda Raman es muy sensible a la presencia de grupos funcionales en las mol\u00e9culas, esta t\u00e9cnica puede proporcionar informaci\u00f3n valiosa acerca del microambiente de la c\u00e9lula. Este es uno de los m\u00e1s prometedores m\u00e9todos para usar los nanotubos de carbono como biosensores \u00f3pticos in vivo y puede servir como una t\u00e9cnica b\u00e1sica para el desarrollo de otros sensores m\u00e1s complejos. Esta sofisticaci\u00f3n a\u00f1adida puede ser implementada modificando los nanotubos con sondas adicionales o agentes marcadores.<\/p>\n<p><span style=\"text-decoration: underline;\">2.\tSensores del comportamiento celular.<\/span><br \/>\nEn este caso se persigue obtener informaci\u00f3n acerca de las caracter\u00edsticas f\u00edsico-qu\u00edmicas y biol\u00f3gicas que rodean a las c\u00e9lulas en su entorno tisular. La capacidad para monitorizar procesos fisiol\u00f3gicos celulares como el transporte i\u00f3nico, las interacciones enzima-cofactor o la secreci\u00f3n de prote\u00ednas y metabolitos o mecanismos de respuesta celular como la adhesi\u00f3n a la matriz extracelular podr\u00edan ofrecer informaci\u00f3n valios\u00edsima que permitir\u00eda dise\u00f1ar mejores tejidos artificiales.<\/p>\n<p>Un posible m\u00e9todo para llevar a cabo estas monitorizaciones consiste en implantar sensores capaces de transmitir informaci\u00f3n desde el interior del organismo al exterior; tales sensores proporcionar\u00edan datos en tiempo real de par\u00e1metros fisiol\u00f3gicos tan importantes como el pH, la presi\u00f3n de ox\u00edgeno o los niveles de glucosa. Emplear nanosensores para este fin tiene principalmente dos ventajas: el tama\u00f1o reducido del sensor disminuye su impacto sobre el tejido dise\u00f1ado en el que va a ser introducido y su elevada proporci\u00f3n \u00e1rea\/volumen le dota de una gran \u00e1rea efectiva en la que inmovilizar numerosos compuestos qu\u00edmicos y biol\u00f3gicos incluyendo ADN y prote\u00ednas que mejoran su sensibilidad.<\/p>\n<p>Mientras que la transmisi\u00f3n de informaci\u00f3n extracorp\u00f3reamente desde los nanosensores est\u00e1 a\u00fan en fase de desarrollo, los sensores basados en nanotubos de carbono ya han demostrado su capacidad para medir varios factores biol\u00f3gicos muy relevantes. Pongamos alg\u00fan ejemplo. MWNTs han sido empleados como electrodos para medir los procesos de electrooxidaci\u00f3n de la insulina y para estimar su concentraci\u00f3n v\u00eda determinaci\u00f3n amperom\u00e9trica. Este hecho sugiere un m\u00e9todo para evaluar la calidad de los islotes pancre\u00e1ticos (regi\u00f3n del p\u00e1ncreas encargada de la producci\u00f3n de hormonas como la insulina y el glucag\u00f3n, Figura 3) previa a su implante en el organismo receptor. Adem\u00e1s, se ha demostrado que podr\u00edamos medir la cantidad de colesterol libre en sangre usando un MWNT montado sobre un sustrato biocompatible [3] o monitorizar el pH mediante sensores compuestos de nanotubos de carbono y un pol\u00edmero como la polianilina [4].<\/p>\n<figure id=\"attachment_352\" aria-describedby=\"caption-attachment-352\" style=\"width: 427px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-3.jpg\"><img decoding=\"async\" class=\"size-full wp-image-352\" title=\"carbon nanotubes 3\" src=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-3.jpg\" alt=\"\" width=\"427\" height=\"321\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-3.jpg 427w, https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-3-300x225.jpg 300w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/a><figcaption id=\"caption-attachment-352\" class=\"wp-caption-text\">Figura 3. Imagen de microscop\u00eda confocal de una secci\u00f3n de p\u00e1ncreas de rat\u00f3n. En rojo se muestran las c\u00e9lulas productoras de insulina, en verde los vasos sangu\u00edneos que rodean a los islotes pancre\u00e1ticos y en azul se marcan todos los n\u00facleos celulares.<\/figcaption><\/figure>\n<p>Acabamos de presentar dos de las prometedoras aplicaciones que los nanotubos de carbono pueden tener en la ingenier\u00eda de tejidos. Sin embargo, como veremos en un pr\u00f3ximo post dedicado fundamentalmente a la utilizaci\u00f3n de nanotubos para la creaci\u00f3n de scaffolds, la implantaci\u00f3n de estos nanotubos o materiales basados en ellos en el interior de un organismo vivo no est\u00e1 exenta de problemas que a\u00fan no est\u00e1n resueltos y cuya soluci\u00f3n transcurre inevitablemente por la senda de un trabajo multidisciplinar de f\u00edsicos, qu\u00edmicos, bi\u00f3logos e ingenieros de materiales.<\/p>\n<p>Referencias<br \/>\n[1] S. Iijima, \u201cHelical microtubules of graphitic carbon\u201d. Nature 354, 56 (1991)<br \/>\n[2] D.A. Heller, S. Baik, T.E. Eurell and M.S. Strano. \u201cSingle-walled carbon nanotube spectroscopy in live cells: towards long-term labels and optical sensors\u201d. Advanced Materials 2793, 17 (2005)<br \/>\n[3] X. Tan, M. Lin, P. Cai, L. Luo and X. Zou. \u201cAn amperometric colesterol biosensor base don multiwalled carbon nanotubes and organically modified sol-gel\/chitosan hybrid composite films\u201d. Analytical Biochemistry, 117, 337 (2005)<br \/>\n[4] M. Kraempgen and S. Roth. \u201cTransparent and flexible carbon nanotube\/polyaniline pH sensors\u201d. Journal of Electroanalytical Chemistry, 72, 586 (2006)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rafael Daza (Universidad Polit\u00e9cnica de Madrid) La Ingenier\u00eda de tejidos es una disciplina que persigue remplazar tejido da\u00f1ado o enfermo por un sustituto biol\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \u00e1reas tan dispares como las relativas al trasplante de c\u00e9lulas y \u00f3rganos y la ciencia de materiales o la ingenier\u00eda, han contribuido al continuo desarrollo de la ingenier\u00eda de tejidos y la medicina regenerativa. Al igual que la regeneraci\u00f3n tisular, la cual supone el empleo de c\u00e9lulas para formar estructuras de mayores dimensiones, la nanotecnolog\u00eda es una disciplina \u201cbottom-up\u201d (de abajo\u2026<\/p>\n","protected":false},"author":187,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[16829,2468,2399,16825],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Por Rafael Daza (Universidad Polit\u00e9cnica de Madrid) La Ingenier\u00eda de tejidos es una disciplina que persigue remplazar tejido da\u00f1ado o enfermo por un sustituto biol\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \u00e1reas tan dispares como las relativas al trasplante de c\u00e9lulas y \u00f3rganos y la ciencia de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dep. Ciencia de Materiales - UPM\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"UPMateriales - Donde se Materializan las Ideas\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I) - UPMateriales\" \/>\n\t\t<meta property=\"og:description\" content=\"Por Rafael Daza (Universidad Polit\u00e9cnica de Madrid) La Ingenier\u00eda de tejidos es una disciplina que persigue remplazar tejido da\u00f1ado o enfermo por un sustituto biol\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \u00e1reas tan dispares como las relativas al trasplante de c\u00e9lulas y \u00f3rganos y la ciencia de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-03-25T09:37:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-05-25T21:30:13+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I) - UPMateriales\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Por Rafael Daza (Universidad Polit\u00e9cnica de Madrid) La Ingenier\u00eda de tejidos es una disciplina que persigue remplazar tejido da\u00f1ado o enfermo por un sustituto biol\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \u00e1reas tan dispares como las relativas al trasplante de c\u00e9lulas y \u00f3rganos y la ciencia de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#blogposting\",\"name\":\"Los nanotubos de carbono y la ingenier\\u00eda de tejidos (I) - UPMateriales\",\"headline\":\"Los nanotubos de carbono y la ingenier\\u00eda de tejidos (I)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/files\\\/2012\\\/03\\\/carbon-nanotubes-1.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#articleImage\",\"width\":1800,\"height\":1133,\"caption\":\"Figura 1. Diagrama de un SWNT (A) y de un MWNT (B) con sus dimensiones caracter\\u00edsticas.\"},\"datePublished\":\"2012-03-25T10:37:44+01:00\",\"dateModified\":\"2012-05-25T22:30:13+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":4,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#webpage\"},\"articleSection\":\"Autor: R. Daza, Biomateriales, Carbono, Nanomateriales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/category\\\/carbono\\\/#listItem\",\"name\":\"Carbono\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/category\\\/carbono\\\/#listItem\",\"position\":2,\"name\":\"Carbono\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/category\\\/carbono\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#listItem\",\"name\":\"Los nanotubos de carbono y la ingenier\\u00eda de tejidos (I)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#listItem\",\"position\":3,\"name\":\"Los nanotubos de carbono y la ingenier\\u00eda de tejidos (I)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/category\\\/carbono\\\/#listItem\",\"name\":\"Carbono\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#organization\",\"name\":\"Materiales al d\\u00eda - Novedades en Ingenier\\u00eda de Materiales\",\"description\":\"Donde se Materializan las Ideas\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/\",\"name\":\"Dep. Ciencia de Materiales - UPM\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1f88773aaaa202a71346096826ed2d9?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dep. Ciencia de Materiales - UPM\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/\",\"name\":\"Los nanotubos de carbono y la ingenier\\u00eda de tejidos (I) - UPMateriales\",\"description\":\"Por Rafael Daza (Universidad Polit\\u00e9cnica de Madrid) La Ingenier\\u00eda de tejidos es una disciplina que persigue remplazar tejido da\\u00f1ado o enfermo por un sustituto biol\\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \\u00e1reas tan dispares como las relativas al trasplante de c\\u00e9lulas y \\u00f3rganos y la ciencia de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/03\\\/25\\\/347\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/#author\"},\"datePublished\":\"2012-03-25T10:37:44+01:00\",\"dateModified\":\"2012-05-25T22:30:13+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/\",\"name\":\"Materiales al d\\u00eda - Novedades en Ingenier\\u00eda de Materiales\",\"description\":\"Donde se Materializan las Ideas\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I) - UPMateriales","description":"Por Rafael Daza (Universidad Polit\u00e9cnica de Madrid) La Ingenier\u00eda de tejidos es una disciplina que persigue remplazar tejido da\u00f1ado o enfermo por un sustituto biol\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \u00e1reas tan dispares como las relativas al trasplante de c\u00e9lulas y \u00f3rganos y la ciencia de","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#blogposting","name":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I) - UPMateriales","headline":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/03\/carbon-nanotubes-1.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#articleImage","width":1800,"height":1133,"caption":"Figura 1. Diagrama de un SWNT (A) y de un MWNT (B) con sus dimensiones caracter\u00edsticas."},"datePublished":"2012-03-25T10:37:44+01:00","dateModified":"2012-05-25T22:30:13+01:00","inLanguage":"es-ES","commentCount":4,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#webpage"},"articleSection":"Autor: R. Daza, Biomateriales, Carbono, Nanomateriales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/carbono\/#listItem","name":"Carbono"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/carbono\/#listItem","position":2,"name":"Carbono","item":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/carbono\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#listItem","name":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#listItem","position":3,"name":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/carbono\/#listItem","name":"Carbono"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#organization","name":"Materiales al d\u00eda - Novedades en Ingenier\u00eda de Materiales","description":"Donde se Materializan las Ideas","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/#author","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/","name":"Dep. Ciencia de Materiales - UPM","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a1f88773aaaa202a71346096826ed2d9?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dep. Ciencia de Materiales - UPM"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/","name":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I) - UPMateriales","description":"Por Rafael Daza (Universidad Polit\u00e9cnica de Madrid) La Ingenier\u00eda de tejidos es una disciplina que persigue remplazar tejido da\u00f1ado o enfermo por un sustituto biol\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \u00e1reas tan dispares como las relativas al trasplante de c\u00e9lulas y \u00f3rganos y la ciencia de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/#author"},"datePublished":"2012-03-25T10:37:44+01:00","dateModified":"2012-05-25T22:30:13+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/","name":"Materiales al d\u00eda - Novedades en Ingenier\u00eda de Materiales","description":"Donde se Materializan las Ideas","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#organization"}}]},"og:locale":"es_ES","og:site_name":"UPMateriales - Donde se Materializan las Ideas","og:type":"article","og:title":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I) - UPMateriales","og:description":"Por Rafael Daza (Universidad Polit\u00e9cnica de Madrid) La Ingenier\u00eda de tejidos es una disciplina que persigue remplazar tejido da\u00f1ado o enfermo por un sustituto biol\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \u00e1reas tan dispares como las relativas al trasplante de c\u00e9lulas y \u00f3rganos y la ciencia de","og:url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/","og:image":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png","article:published_time":"2012-03-25T09:37:44+00:00","article:modified_time":"2012-05-25T21:30:13+00:00","twitter:card":"summary","twitter:title":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I) - UPMateriales","twitter:description":"Por Rafael Daza (Universidad Polit\u00e9cnica de Madrid) La Ingenier\u00eda de tejidos es una disciplina que persigue remplazar tejido da\u00f1ado o enfermo por un sustituto biol\u00f3gico capaz de restaurar y mantener la funcionalidad del tejido original. Los avances realizados en \u00e1reas tan dispares como las relativas al trasplante de c\u00e9lulas y \u00f3rganos y la ciencia de","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"347","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 22:26:30","updated":"2026-07-03 22:14:49","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/carbono\/\" title=\"Carbono\">Carbono<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos nanotubos de carbono y la ingenier\u00eda de tejidos (I)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales"},{"label":"Carbono","link":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/carbono\/"},{"label":"Los nanotubos de carbono y la ingenier\u00eda de tejidos (I)","link":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/03\/25\/347\/"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/posts\/347"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/users\/187"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/comments?post=347"}],"version-history":[{"count":10,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/posts\/347\/revisions"}],"predecessor-version":[{"id":475,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/posts\/347\/revisions\/475"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/media?parent=347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/categories?post=347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/tags?post=347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}