{"id":37,"date":"2012-01-12T20:21:10","date_gmt":"2012-01-12T19:21:10","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/?p=37"},"modified":"2012-05-25T22:35:04","modified_gmt":"2012-05-25T21:35:04","slug":"nanobiomateriales-la-nanotecnologia-al-servicio-de-la-salud","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/","title":{"rendered":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud"},"content":{"rendered":"<p style=\"text-align: center;\">Por <strong><a title=\"Rafael Daza Garc\u00eda\" href=\"http:\/\/www.mater.upm.es\/Directorio\/Investigadores\/PreDoc\/Daza.asp\" target=\"_blank\">Rafael Daza Garc\u00eda <\/a>, <\/strong> Licenciado en Ciencias F\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\u00e9cnica de Madrid)<\/p>\n<p>La nanotecnolog\u00eda es el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es el nan\u00f3metro,       1 nm equivale a 10-9 m, esto es, la millon\u00e9sima parte del mil\u00edmetro), y la explotaci\u00f3n de fen\u00f3menos y propiedades de la propia materia a dicha escala.<\/p>\n<p>A pesar de que la idea conceptual de nanotecnolog\u00eda surgi\u00f3 hace m\u00e1s de medio siglo (Richard P. Feynman en su ponencia <a href=\"http:\/\/calteches.library.caltech.edu\/1976\/1\/1960Bottom.pdf\">There&#8217;s plenty of room at the bottom<\/a> ante la Sociedad Americana de F\u00edsica), es en los \u00faltimos a\u00f1os cuando ha experimentado un crecimiento vertiginoso que ha transformado el concepto en una realidad para la que constantemente se hallan nuevas aplicaciones y mercados. Como no pod\u00eda ser de otra manera, ciencias tan relevantes para el ser humano como la biolog\u00eda y la medicina no han quedado al margen del proceso expansivo de la nanotecnolog\u00eda, de manera que, en la actualidad, son numerosas las aplicaciones nano que se estudian en varios de los mejores laboratorios bio del mundo.<\/p>\n<p>Cuando las dimensiones de la materia se reducen a la escala nanom\u00e9trica, esto es, abandonamos el mundo macrosc\u00f3pico cotidiano, las leyes de la f\u00edsica tal y como las conocemos en este dejan de ser v\u00e1lidas. Abandonamos la f\u00edsica de Newton o Einstein y nos adentramos en el universo de la mec\u00e1nica cu\u00e1ntica y las propiedades \u00abm\u00e1gicas\u00bb que esta impone. Veamos un ejemplo: el oro es un material diamagn\u00e9tico inerte ante la presencia de un campo magn\u00e9tico; sin embargo, cuando tomamos una fracci\u00f3n nanom\u00e9trica de ese mismo elemento, el nanomaterial resultante presenta actividad magn\u00e9tica (y esto \u00ab\u00fanicamente\u00bb por el hecho de haber reducido sus dimensiones). Junto con la aparici\u00f3n de estas nuevas propiedades, los nanomateriales presentan otra caracter\u00edstica que les hace id\u00f3neos para su uso en el \u00e1mbito biosanitario. Los nanomateriales son materiales con tama\u00f1os en el rango de 1 a 100 nm. Dado que la mayor\u00eda de macromol\u00e9culas y agentes biol\u00f3gicamente activos, tales como virus, complejos prote\u00ednicos o membranas, son nanoestructuras naturales, se asume que los materiales nanoestructurados ser\u00e1n capaces de establecer una mejor interacci\u00f3n con los principales ladrillos de la vida.<\/p>\n<p>En la actualidad son muchas y diferentes las aplicaciones que los nanomateriales tienen en el \u00e1mbito de la salud, tanto a nivel de diagnosis como de terap\u00e9utica. Entre las que son ya una realidad, podemos destacar:<\/p>\n<ul>\n<li>Nanosensores que circulan dentro del cuerpo para monitorizar los niveles de glucosa, colesterol u hormonas.<\/li>\n<li>Nanopart\u00edculas inteligentes que buscan una localizaci\u00f3n espec\u00edfica dentro del cuerpo humano para suministrar con precisi\u00f3n una dosis programada de medicamento en dicha localizaci\u00f3n.<\/li>\n<li>Nanopart\u00edculas que destruyen microbios resistentes a los antibi\u00f3ticos.<\/li>\n<li>Armazones tridimensionales (scaffolds) nanoestructurados para crecimiento de nuevo tejido y \u00f3rganos humanos.<\/li>\n<li>Nanopart\u00edculas para destrucci\u00f3n de c\u00e9lulas tumorales v\u00eda calentamiento (Hipertermia).<\/li>\n<li>Nanomateriales para la separaci\u00f3n y purificaci\u00f3n de mol\u00e9culas biol\u00f3gicas y c\u00e9lulas.<\/li>\n<li>Nanomateriales para la mejora del contraste en pruebas de Resonancia Magn\u00e9tica Nuclear.<\/li>\n<\/ul>\n<p>Si bien todas las l\u00edneas anteriores est\u00e1n en pleno auge, las mayores esperanzas est\u00e1n depositadas en las vinculadas al suministro local de medicamentos y a la hipertermia. Los materiales nanoestructurados se han convertido en un mecanismo para el suministro local de macromol\u00e9culas en tejidos u \u00f3rganos de inter\u00e9s. Los nuevos desarrollos en ciencia de materiales y en nanoingenier\u00eda est\u00e1n permitiendo la producci\u00f3n de nanocomposites (materiales compuestos de dimensiones nano) biocompatibles que albergan, bien en su interior, bien sobre su superficie, agentes terap\u00e9uticos. Para esta aplicaci\u00f3n suelen emplearse nanopart\u00edculas de origen polim\u00e9rico cuya superficie es funcionalizada con diversas sustancias: se emplea una capa de origen biol\u00f3gico que asegura la biocompatibilidad de la nanopart\u00edcula (por ejemplo, las capas biol\u00f3gicas pueden incluir anticuerpos, biopol\u00edmeros como el col\u00e1geno, &#8230;), si la nanopart\u00edcula tiene que unirse a una estructura para realizar su funci\u00f3n, se pueden disponer lugares de anclaje de alta especificidad; adem\u00e1s, se pueden emplear agentes de contraste que permitan localizar la ubicaci\u00f3n de la nanopart\u00edcula una vez esta ha sido introducida en el organismo. La figura muestra el esquema de una nanopart\u00edcula con algunas de las funcionalizaciones posibles. Actualmente, existen numerosas t\u00e9cnicas para sintetizar diferentes sets de nanopart\u00edculas seg\u00fan el tipo de agente terap\u00e9utico a usar, y el \u00f3rgano objeto y el mecanismo de liberaci\u00f3n de aquel que se desee emplear.<\/p>\n<p>La quimioterapia es una de las terapias m\u00e1s extendidas en la lucha contra determinados tipos de c\u00e1nceres. B\u00e1sicamente, consiste en el empleo de una combinaci\u00f3n de medicamentos que destruye las c\u00e9lulas tumorales o inhibe su proliferaci\u00f3n. Sin embargo, este tipo de terapia presenta unos importantes efectos secundarios debidos a que los medicamentos no reconocen el punto exacto en el que deben actuar, esto es, la quimioterapia afecta a todas las c\u00e9lulas del cuerpo, no s\u00f3lo a las tumorales. Estas c\u00e9lulas presentan una serie de receptores espec\u00edficos en su membrana. El empleo de nanopart\u00edculas en cuya superficie se han depositado los ligandos complementarios a aquellos receptores (equivalente a un sistema llave-cerradura) permite la uni\u00f3n de estas a las c\u00e9lulas tumorales de manera que el suministro del medicamento o agente terap\u00e9utico se puede realizar sobre el lugar exacto en el que es requerido, esto es, la c\u00e9lula tumoral.<\/p>\n<figure id=\"attachment_21\" aria-describedby=\"caption-attachment-21\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/01\/nanoparticle2-e1326395397337.jpg\"><img decoding=\"async\" class=\"size-full wp-image-21 \" title=\"Esquema de una nanopart\u00edcula. Adaptada de (2)\" src=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/01\/nanoparticle2-e1326395397337.jpg\" alt=\"\" width=\"300\" height=\"170\" \/><\/a><figcaption id=\"caption-attachment-21\" class=\"wp-caption-text\">Esquema de una nanopart\u00edcula. Adaptada de (2)<\/figcaption><\/figure>\n<p>Las c\u00e9lulas son entidades muy sensibles a las condiciones f\u00edsico-qu\u00edmicas del ambiente en el que se encuentran de manera que agentes como la temperatura, el pH, etc. pueden modificar dr\u00e1sticamente el desarrollo de sus funciones e incluso producirles la muerte. Esta es la idea que subyace en el empleo de la hipertermia como terapia en la lucha contra el c\u00e1ncer. En este caso se suelen emplear nanopart\u00edculas magn\u00e9ticas para producir calor bajo un campo magn\u00e9tico alterno v\u00eda las p\u00e9rdidas irreversibles durante el proceso de imanaci\u00f3n.<\/p>\n<p>No debe escapar al lector el hecho de que a\u00fan hay muchos problemas por resolver e interrogantes que desvelar antes de lograr una implantaci\u00f3n completa de estas nuevas terapias en el \u00e1mbito sanitario. Cuestiones como la eliminaci\u00f3n de las nanopart\u00edculas o el deterioro de las propiedades mec\u00e1nicas de los scaffolds (por ejemplo, en la regeneraci\u00f3n del tejido \u00f3seo) est\u00e1n por resolver. En este sentido, es fundamental que muchas disciplinas como la f\u00edsica, la qu\u00edmica, la microbiolog\u00eda, la biolog\u00eda celular, la ciencia de materiales o la ingenier\u00eda, entre otras, trabajen de la mano y contribuyan al dise\u00f1o, s\u00edntesis y fabricaci\u00f3n de dispositivos funcionales y biocompatibles a escala nano cada vez mejores.<\/p>\n<p>Referencias<\/p>\n<p>(1) Nanotecnolog\u00eda y biomedicina. A. Ortiz. 2009.<br \/>\n(2) Biodegradable nanoparticles are excellent vehicle for site directed in-vivo delivery of drugs and vaccines. A. Mahapatro. 2011.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rafael Daza Garc\u00eda , Licenciado en Ciencias F\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\u00e9cnica de Madrid) La nanotecnolog\u00eda es el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es el nan\u00f3metro, 1 nm equivale a 10-9 m, esto es, la millon\u00e9sima parte del mil\u00edmetro), y la explotaci\u00f3n de fen\u00f3menos y propiedades de la propia materia a dicha escala. A pesar de que la idea conceptual de nanotecnolog\u00eda surgi\u00f3 hace m\u00e1s de medio siglo (Richard\u2026<\/p>\n","protected":false},"author":187,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[16829,2468,16825],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Por Rafael Daza Garc\u00eda , Licenciado en Ciencias F\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\u00e9cnica de Madrid) La nanotecnolog\u00eda es el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dep. Ciencia de Materiales - UPM\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"UPMateriales - Donde se Materializan las Ideas\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud - UPMateriales\" \/>\n\t\t<meta property=\"og:description\" content=\"Por Rafael Daza Garc\u00eda , Licenciado en Ciencias F\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\u00e9cnica de Madrid) La nanotecnolog\u00eda es el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-01-12T19:21:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-05-25T21:35:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud - UPMateriales\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Por Rafael Daza Garc\u00eda , Licenciado en Ciencias F\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\u00e9cnica de Madrid) La nanotecnolog\u00eda es el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#blogposting\",\"name\":\"Nanobiomateriales: la Nanotecnolog\\u00eda al servicio de la Salud - UPMateriales\",\"headline\":\"Nanobiomateriales: la Nanotecnolog\\u00eda al servicio de la Salud\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/files\\\/2012\\\/01\\\/nanoparticle2-e1326395397337.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#articleImage\",\"width\":300,\"height\":170,\"caption\":\"Esquema de una nanopart\\u00edcula. Adaptado de [2]\"},\"datePublished\":\"2012-01-12T20:21:10+01:00\",\"dateModified\":\"2012-05-25T22:35:04+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#webpage\"},\"articleSection\":\"Autor: R. Daza, Biomateriales, Nanomateriales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/category\\\/biomateriales\\\/#listItem\",\"name\":\"Biomateriales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/category\\\/biomateriales\\\/#listItem\",\"position\":2,\"name\":\"Biomateriales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/category\\\/biomateriales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#listItem\",\"name\":\"Nanobiomateriales: la Nanotecnolog\\u00eda al servicio de la Salud\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#listItem\",\"position\":3,\"name\":\"Nanobiomateriales: la Nanotecnolog\\u00eda al servicio de la Salud\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/category\\\/biomateriales\\\/#listItem\",\"name\":\"Biomateriales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#organization\",\"name\":\"Materiales al d\\u00eda - Novedades en Ingenier\\u00eda de Materiales\",\"description\":\"Donde se Materializan las Ideas\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/\",\"name\":\"Dep. Ciencia de Materiales - UPM\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1f88773aaaa202a71346096826ed2d9?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dep. Ciencia de Materiales - UPM\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/\",\"name\":\"Nanobiomateriales: la Nanotecnolog\\u00eda al servicio de la Salud - UPMateriales\",\"description\":\"Por Rafael Daza Garc\\u00eda , Licenciado en Ciencias F\\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\\u00e9cnica de Madrid) La nanotecnolog\\u00eda es el estudio, dise\\u00f1o, creaci\\u00f3n, s\\u00edntesis, manipulaci\\u00f3n y aplicaci\\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\\u00e9trica (aquella en la que la unidad de longitud de referencia es\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/2012\\\/01\\\/12\\\/37\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/author\\\/ingenieriamateriales\\\/#author\"},\"datePublished\":\"2012-01-12T20:21:10+01:00\",\"dateModified\":\"2012-05-25T22:35:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/\",\"name\":\"Materiales al d\\u00eda - Novedades en Ingenier\\u00eda de Materiales\",\"description\":\"Donde se Materializan las Ideas\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ingenieriamateriales\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud - UPMateriales","description":"Por Rafael Daza Garc\u00eda , Licenciado en Ciencias F\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\u00e9cnica de Madrid) La nanotecnolog\u00eda es el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#blogposting","name":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud - UPMateriales","headline":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2012\/01\/nanoparticle2-e1326395397337.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#articleImage","width":300,"height":170,"caption":"Esquema de una nanopart\u00edcula. Adaptado de [2]"},"datePublished":"2012-01-12T20:21:10+01:00","dateModified":"2012-05-25T22:35:04+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#webpage"},"articleSection":"Autor: R. Daza, Biomateriales, Nanomateriales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/biomateriales\/#listItem","name":"Biomateriales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/biomateriales\/#listItem","position":2,"name":"Biomateriales","item":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/biomateriales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#listItem","name":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#listItem","position":3,"name":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/biomateriales\/#listItem","name":"Biomateriales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#organization","name":"Materiales al d\u00eda - Novedades en Ingenier\u00eda de Materiales","description":"Donde se Materializan las Ideas","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/#author","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/","name":"Dep. Ciencia de Materiales - UPM","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a1f88773aaaa202a71346096826ed2d9?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dep. Ciencia de Materiales - UPM"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/","name":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud - UPMateriales","description":"Por Rafael Daza Garc\u00eda , Licenciado en Ciencias F\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\u00e9cnica de Madrid) La nanotecnolog\u00eda es el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/author\/ingenieriamateriales\/#author"},"datePublished":"2012-01-12T20:21:10+01:00","dateModified":"2012-05-25T22:35:04+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/","name":"Materiales al d\u00eda - Novedades en Ingenier\u00eda de Materiales","description":"Donde se Materializan las Ideas","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/#organization"}}]},"og:locale":"es_ES","og:site_name":"UPMateriales - Donde se Materializan las Ideas","og:type":"article","og:title":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud - UPMateriales","og:description":"Por Rafael Daza Garc\u00eda , Licenciado en Ciencias F\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\u00e9cnica de Madrid) La nanotecnolog\u00eda es el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es","og:url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/","og:image":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png","article:published_time":"2012-01-12T19:21:10+00:00","article:modified_time":"2012-05-25T21:35:04+00:00","twitter:card":"summary","twitter:title":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud - UPMateriales","twitter:description":"Por Rafael Daza Garc\u00eda , Licenciado en Ciencias F\u00edsicas (Departamento de Ciencia de Materiales, Universidad Polit\u00e9cnica de Madrid) La nanotecnolog\u00eda es el estudio, dise\u00f1o, creaci\u00f3n, s\u00edntesis, manipulaci\u00f3n y aplicaci\u00f3n de materiales, aparatos y sistemas funcionales mediante el control de la materia a escala nanom\u00e9trica (aquella en la que la unidad de longitud de referencia es","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"37","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 21:34:31","updated":"2026-07-03 22:04:22","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/biomateriales\/\" title=\"Biomateriales\">Biomateriales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales"},{"label":"Biomateriales","link":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/category\/biomateriales\/"},{"label":"Nanobiomateriales: la Nanotecnolog\u00eda al servicio de la Salud","link":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/2012\/01\/12\/37\/"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/posts\/37"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/users\/187"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":16,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/posts\/37\/revisions"}],"predecessor-version":[{"id":480,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/posts\/37\/revisions\/480"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/media?parent=37"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/categories?post=37"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ingenieriamateriales\/wp-json\/wp\/v2\/tags?post=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}