{"id":140691,"date":"2016-02-26T09:43:58","date_gmt":"2016-02-26T08:43:58","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/?p=140691"},"modified":"2016-02-26T09:45:20","modified_gmt":"2016-02-26T08:45:20","slug":"obsesiones-matematicas","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691","title":{"rendered":"Obsesiones matem\u00e1ticas"},"content":{"rendered":"<p><strong>La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n&#8230; la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo real. Manuel de Le\u00f3n, investigador del ICMAT, habla en esta entrada de este fuerte estado mental, en relaci\u00f3n con la creaci\u00f3n matem\u00e1tica.<\/strong><\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-140703\" title=\"160224_laberinto\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-300x225.jpg 300w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-1024x768.jpg 1024w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: right;\"><em>One way or another I&#8217;m gonna find ya<\/em><br \/>\n<em> I&#8217;m gonna getcha getcha getcha getcha<\/em><br \/>\n<em> One way or another I&#8217;m gonna win ya<\/em><br \/>\n<em> I&#8217;m gonna getcha getcha getcha getcha<\/em><br \/>\n<em> One way or another I&#8217;m gonna see ya<\/em><br \/>\n<em> I&#8217;m gonna meetcha meetcha meetcha meetcha<\/em><br \/>\n<em> One day, maybe next week<\/em><br \/>\n<em> I&#8217;m gonna meetcha, I&#8217;m gonna meetcha, I&#8217;ll meetcha<\/em><br \/>\n<em> I will drive past your house<\/em><br \/>\n<em> And if the lights are all down<\/em><br \/>\n<em> I&#8217;ll see who&#8217;s around<\/em><\/p>\n<p style=\"text-align: right;\"><em> One way or another I&#8217;m gonna find ya<\/em><br \/>\n<em> I&#8217;m gonna getcha getcha getcha getcha<\/em><br \/>\n<em> One way or another I&#8217;m gonna win ya<\/em><br \/>\n<em> I&#8217;ll getcha, I&#8217;ll getcha<\/em><br \/>\n<em> One way or another I&#8217;m gonna see ya<\/em><br \/>\n<em> I&#8217;m gonna meetcha meetcha meetcha meetcha<\/em><br \/>\n<em> One day, maybe next week<\/em><br \/>\n<em> I&#8217;m gonna meetcha, I&#8217;ll meetcha<\/em><\/p>\n<p style=\"text-align: right;\">Blondie, <a href=\"https:\/\/www.youtube.com\/watch?v=1VFuHj9_Tgw&amp;list=RD1VFuHj9_Tgw\">One way or another<\/a><\/p>\n<p>Las obsesiones son miradas muchas veces como algo malo, pero para los matem\u00e1ticos pueden ser algo bueno. Dej\u00e9nme explicarme. Imag\u00ednense que usted es un joven matem\u00e1tico al que le han introducido en los grandes desaf\u00edos que permanecen abiertos en la disciplina (atenci\u00f3n, cada d\u00eda aparecen nuevos retos, las matem\u00e1ticas no est\u00e1n ancladas en el pasado). Por ejemplo, la conjetura de Poincar\u00e9, que dice algo tan tonto como que \u201csi algo se parece mucho a una esfera, es una esfera\u201d. Y pongamos que en este tema se implica un matem\u00e1tico como Richard Hamilton,\u00a0 que inventa un instrumento llamado los flujos de Ricci, y que no acaba de llegar al resultado final. Se necesitaba m\u00e1s obsesi\u00f3n y m\u00e1s genio, y eso lo puso uno de nuestros obsesos favoritos, Grigori Perelman.<\/p>\n<p>Otra de las m\u00e1s conocidas obsesiones matem\u00e1tica es la prueba de la hip\u00f3tesis de Riemann (para los que no se crean la importancia de la misma, le\u00e1nse la novela de Matt Haig,<em>\u00a0Los humanos<\/em>). Por ahora, no se ha resuelto, as\u00ed que seguir\u00e1 atormentando las mentes de todas las personas que han ca\u00eddo en sus garras.<\/p>\n<figure id=\"attachment_140695\" aria-describedby=\"caption-attachment-140695\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/384px-Perelman_Grigori_1966.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-140695\" title=\"384px-Perelman,_Grigori_(1966)\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/384px-Perelman_Grigori_1966-300x219.jpg\" alt=\"\" width=\"300\" height=\"219\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/384px-Perelman_Grigori_1966-300x219.jpg 300w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/384px-Perelman_Grigori_1966.jpg 384w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-140695\" class=\"wp-caption-text\">Grigori Perelman<\/figcaption><\/figure>\n<p>La obsesi\u00f3n puede llevar al resultado, pero tambi\u00e9n a espejismos del mismo. \u00bfCu\u00e1ntos matem\u00e1ticos no se han obsesionado con la prueba hasta el extremo de anunciar pruebas que luego se rebelaron falsas? Tambi\u00e9n puede\u00a0conducir a caminos peligrosos, recordemos por ejemplo la locura transfinita de Cantor; su creaci\u00f3n (o descubrimiento, si nuestra concepci\u00f3n del universo matem\u00e1tica es plat\u00f3nica) cre\u00f3 un para\u00edso del que David Hilbert declar\u00f3, \u201cnadie nos expulsar\u00e1\u201d, pero a cambio, su mente abandon\u00f3 la cordura.<\/p>\n<figure id=\"attachment_140696\" aria-describedby=\"caption-attachment-140696\" style=\"width: 228px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/Georg_Cantor2.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-140696\" title=\"Georg_Cantor2\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/Georg_Cantor2-228x300.jpg\" alt=\"\" width=\"228\" height=\"300\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/Georg_Cantor2-228x300.jpg 228w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/Georg_Cantor2.jpg 587w\" sizes=\"(max-width: 228px) 100vw, 228px\" \/><\/a><figcaption id=\"caption-attachment-140696\" class=\"wp-caption-text\">Georg Cantor<\/figcaption><\/figure>\n<p>La obsesi\u00f3n es sin duda una de las caracter\u00edsticas mas t\u00edpicas de las matem\u00e1ticas, especialmente en sus aspectos de investigaci\u00f3n b\u00e1sica. Y aunque no creo en los estereotipos, s\u00ed debo reconocer que sin una dosis de obsesi\u00f3n es imposible atacar problemas de esta envergadura (unas buenas dosis de caf\u00e9 tambi\u00e9n son imprescindibles).<\/p>\n<p>Y esta obsesi\u00f3n quiz\u00e1s no muy sana para sus protagonistas, s\u00ed lo es para las matem\u00e1ticas en particular y para la ciencia en general. As\u00ed que ya saben, cuando vean a alg\u00fan matem\u00e1tico, \u00a1preg\u00fantenle por sus obsesiones!<\/p>\n<p>__________<\/p>\n<p><strong>Manuel de Le\u00f3n<\/strong> (CSIC, Real Academia de Ciencias, Academia Canaria de Ciencias, ICSU)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n&#8230; la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo real. Manuel de Le\u00f3n, investigador del ICMAT, habla en esta entrada de este fuerte estado mental, en relaci\u00f3n con la creaci\u00f3n matem\u00e1tica. One way or another I&#8217;m gonna find ya I&#8217;m gonna getcha getcha getcha getcha One way or another I&#8217;m gonna win ya I&#8217;m\u2026<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n... la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Matem\u00e1ticas y sus fronteras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta property=\"og:description\" content=\"La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n... la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-26T08:43:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-26T08:45:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n... la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691#blogposting\",\"name\":\"Obsesiones matem\\u00e1ticas - Matem\\u00e1ticas y sus fronteras\",\"headline\":\"Obsesiones matem\\u00e1ticas\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2016\\\/02\\\/160224_laberinto-300x225.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691\\\/#articleImage\"},\"datePublished\":\"2016-02-26T09:43:58+01:00\",\"dateModified\":\"2016-02-26T09:45:20+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691#listItem\",\"name\":\"Obsesiones matem\\u00e1ticas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691#listItem\",\"position\":3,\"name\":\"Obsesiones matem\\u00e1ticas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Matem\\u00e1ticas y sus fronteras\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691\",\"name\":\"Obsesiones matem\\u00e1ticas - Matem\\u00e1ticas y sus fronteras\",\"description\":\"La investigaci\\u00f3n matem\\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \\u00fanica, herramienta. Requiere dedicaci\\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\\u00f3n... la obsesi\\u00f3n puede convertirse en el motor que impulsa la soluci\\u00f3n, pero tambi\\u00e9n llevar al cient\\u00edfico a perder el contacto con el mundo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2016\\\/02\\\/26\\\/140691#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"datePublished\":\"2016-02-26T09:43:58+01:00\",\"dateModified\":\"2016-02-26T09:45:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras","description":"La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n... la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#blogposting","name":"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras","headline":"Obsesiones matem\u00e1ticas","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-300x225.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691\/#articleImage"},"datePublished":"2016-02-26T09:43:58+01:00","dateModified":"2016-02-26T09:45:20+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#listItem","name":"Obsesiones matem\u00e1ticas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#listItem","position":3,"name":"Obsesiones matem\u00e1ticas","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization","name":"Matem\u00e1ticas y sus fronteras","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","width":96,"height":96,"caption":"Matem\u00e1ticas y sus fronteras"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691","name":"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras","description":"La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n... la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"datePublished":"2016-02-26T09:43:58+01:00","dateModified":"2016-02-26T09:45:20+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Matem\u00e1ticas y sus fronteras -","og:type":"article","og:title":"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras","og:description":"La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n... la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo","og:url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691","og:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","article:published_time":"2016-02-26T08:43:58+00:00","article:modified_time":"2016-02-26T08:45:20+00:00","twitter:card":"summary","twitter:title":"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras","twitter:description":"La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n... la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"140691","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-04 15:27:50","updated":"2026-05-28 10:34:38","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tObsesiones matem\u00e1ticas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general"},{"label":"Obsesiones matem\u00e1ticas","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"og:description\" content=\"La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n&#8230; la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo real. Manuel de Le\u00f3n, investigador del ICMAT, habla en esta entrada de este fuerte estado mental, en relaci\u00f3n con la creaci\u00f3n matem\u00e1tica. One way or another I&#8217;m gonna find ya I&#8217;m gonna getcha getcha getcha getcha One way or another I&#8217;m gonna win ya I&#8217;m\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691\" \/>\n<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-26T08:43:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-26T08:45:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-300x225.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#primaryimage\",\"inLanguage\":\"es\",\"url\":\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-300x225.jpg\",\"contentUrl\":\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-300x225.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#webpage\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691\",\"name\":\"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras\",\"isPartOf\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#primaryimage\"},\"datePublished\":\"2016-02-26T08:43:58+00:00\",\"dateModified\":\"2016-02-26T08:45:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obsesiones matem\u00e1ticas\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"caption\":\"Matem\u00e1ticas y sus fronteras\"},\"description\":\"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691","og_locale":"es_ES","og_type":"article","og_title":"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras","og_description":"La investigaci\u00f3n matem\u00e1tica implica enfrentarse a un problema sin resolver, con la propia mente como principal, en muchos casos \u00fanica, herramienta. Requiere dedicaci\u00f3n, perseverancia, darle mil vueltas diferentes a la misma cuesti\u00f3n&#8230; la obsesi\u00f3n puede convertirse en el motor que impulsa la soluci\u00f3n, pero tambi\u00e9n llevar al cient\u00edfico a perder el contacto con el mundo real. Manuel de Le\u00f3n, investigador del ICMAT, habla en esta entrada de este fuerte estado mental, en relaci\u00f3n con la creaci\u00f3n matem\u00e1tica. One way or another I&#8217;m gonna find ya I&#8217;m gonna getcha getcha getcha getcha One way or another I&#8217;m gonna win ya I&#8217;m\u2026","og_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691","og_site_name":"Matem\u00e1ticas y sus fronteras","article_published_time":"2016-02-26T08:43:58+00:00","article_modified_time":"2016-02-26T08:45:20+00:00","og_image":[{"url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-300x225.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Matem\u00e1ticas y sus fronteras","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#primaryimage","inLanguage":"es","url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-300x225.jpg","contentUrl":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2016\/02\/160224_laberinto-300x225.jpg"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691","name":"Obsesiones matem\u00e1ticas - Matem\u00e1ticas y sus fronteras","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#primaryimage"},"datePublished":"2016-02-26T08:43:58+00:00","dateModified":"2016-02-26T08:45:20+00:00","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2016\/02\/26\/140691#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"@type":"ListItem","position":2,"name":"Obsesiones matem\u00e1ticas"}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","caption":"Matem\u00e1ticas y sus fronteras"},"description":"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas"}]}},"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/140691"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/comments?post=140691"}],"version-history":[{"count":10,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/140691\/revisions"}],"predecessor-version":[{"id":140707,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/140691\/revisions\/140707"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/media?parent=140691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/categories?post=140691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/tags?post=140691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}