{"id":143161,"date":"2017-01-30T10:16:46","date_gmt":"2017-01-30T09:16:46","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/?p=143161"},"modified":"2017-01-30T10:16:46","modified_gmt":"2017-01-30T09:16:46","slug":"get-the-girl-to-check-the-numbers","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161","title":{"rendered":"\u201cGet the girl to check the numbers\u201d"},"content":{"rendered":"<blockquote><p>Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres<\/p><\/blockquote>\n<p>El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata de combatir esta invisibilidad.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-143163\" title=\"lead_960\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960-300x200.jpg 300w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>En este blog hemos contado historias de mujeres matem\u00e1ticas que tuvieron que realizar grandes esfuerzos para cultivar la ciencia que les gustaba, mujeres que han tenido que ocultar su condici\u00f3n bajo un seud\u00f3nimo, mujeres a las que no les estaba permitido asistir a las universidades o impartir docencia, mujeres, en definitiva, que han tenido que romper tab\u00fas.<\/p>\n<p><em>Figuras ocultas<\/em> narra la historia de unas mujeres que sufrieron una doble disciminaci\u00f3n, por mujeres y negras. Son tres mujeres, Katherine Globe Johnson, Mary Jackson y Dorothy Vaughan. Las tres participaron en el proyecto Mercurio, el primer programa espacial tripulado de los Estados Unidos, desarrollado entre 1961 y 1963. Los sovi\u00e9ticos hab\u00edan puesto en \u00f3rbita el Sputnik 1, lanzado el 4 de octubre de 1957. Estados Unidos no pod\u00eda quedarse atr\u00e1s, y primero Alan Shephard y despu\u00e9s John Glenn, repet\u00edan la haza\u00f1a de Yuri Gagarin, qui\u00e9n fue lanzado al espacio exterior a bordo de la nave Vostok 1 el 12 de abril de 1961.<\/p>\n<figure id=\"attachment_143165\" aria-describedby=\"caption-attachment-143165\" style=\"width: 237px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/440px-Katherine_Johnson_at_NASA_in_19661.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-143165\" title=\"440px-Katherine_Johnson_at_NASA,_in_1966\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/440px-Katherine_Johnson_at_NASA_in_19661-237x300.jpg\" alt=\"\" width=\"237\" height=\"300\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/440px-Katherine_Johnson_at_NASA_in_19661-237x300.jpg 237w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/440px-Katherine_Johnson_at_NASA_in_19661.jpg 440w\" sizes=\"(max-width: 237px) 100vw, 237px\" \/><\/a><figcaption id=\"caption-attachment-143165\" class=\"wp-caption-text\">Katherine Globe-Johnson<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>La protagonista es, sin duda, Katherine Globe, qui\u00e9n en la vida real desarroll\u00f3 un importante trabajo como investigadora matem\u00e1tica. Conocedora de que la National Advisory Committee for Aeronautics (NACA, luego NASA) necesitaba matem\u00e1ticas, se incorpor\u00f3 como calculadora. Las calculadoras (las de raza negra eran las\u00a0 \u00abColored Computers\u00bb) eran mujeres que hac\u00edan los tediosos c\u00e1lculos necesarios para las trayectorias de los lanzamientos del proyecto Mercurio. Al final, son elipses, par\u00e1bolas, hip\u00e9rboals, o sea, las c\u00f3nicas de Apolonio, combinadas con las leyes de Kepler y las de Newton las que proporcionan las respuestas. De ah\u00ed las referencias a la geometr\u00eda anal\u00edtica.<\/p>\n<figure id=\"attachment_143166\" aria-describedby=\"caption-attachment-143166\" style=\"width: 224px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/dorothy-vaughan_0.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-143166\" title=\"Dorothy Vaughan in her twenties.\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/dorothy-vaughan_0-224x300.jpg\" alt=\"\" width=\"224\" height=\"300\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/dorothy-vaughan_0-224x300.jpg 224w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/dorothy-vaughan_0-765x1024.jpg 765w\" sizes=\"(max-width: 224px) 100vw, 224px\" \/><\/a><figcaption id=\"caption-attachment-143166\" class=\"wp-caption-text\">Dorothy Vaughan<\/figcaption><\/figure>\n<p>Las otras dos protagonistas matem\u00e1ticas son Dorothy Vaughan (que supervisa a las calculadoras) y Mary Jackson (que quiere y consigue ser ingeniera). Las tres mujeres, Globe, Vaughan y Jackson van a ser sin duda un ejemplo para muchas chicas que aprender\u00e1n que nada est\u00e1 escrito, y que ellas tienen la capacidad para hacer cualquier cosa que pueda hacer un hombre.<\/p>\n<figure id=\"attachment_143167\" aria-describedby=\"caption-attachment-143167\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/NASA-human-computers-e1457738114444-1.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-143167\" title=\"NASA-human-computers-e1457738114444-1\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/NASA-human-computers-e1457738114444-1-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/NASA-human-computers-e1457738114444-1-300x199.jpg 300w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/NASA-human-computers-e1457738114444-1.jpg 751w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-143167\" class=\"wp-caption-text\">Mary Winston Jackson<\/figcaption><\/figure>\n<p>La pel\u00edcula est\u00e1 inspirada en el libro <em>Hidden Figures: The Story of the African-American Women Who Helped Win the Space Race<\/em>, el primero de Margot Lee Shetterly, publicado el a\u00f1o pasado. La pel\u00edcula narra la historia novelada, y como ocurre en estos casos, tiene que resaltar algunos detalles para hacerla comprensible y agradable. Y lo consigue. El t\u00edtulo puede entenderse de varias maneras: las figuras\/personajes matem\u00e1ticas detr\u00e1s del escenario que no se ven, y tambi\u00e9n los n\u00fameros ocultos detr\u00e1s de la ingenier\u00eda que hace posible el lanzamiento.<\/p>\n<p>Como matem\u00e1tico, es gratificante ver que se le da un peso decisivo a la disciplina, no se puede ir al espacio sin las ecuaciones y los c\u00e1lculos matem\u00e1ticos, y es precisamente el conocimiento y el talento de Globe para las matem\u00e1ticas, lo que permite ir m\u00e1s all\u00e1. Y es interesante el ver la evoluci\u00f3n de los c\u00e1lculos a mano para integrar (resolver) unas ecuaciones con la potencia que proporcionan los ordenadores, en este caso, un IBM 7090. \u00a1Y hasta se cita el m\u00e9todo de Euler para la integraci\u00f3n!<\/p>\n<p>[youtube]https:\/\/www.youtube.com\/watch?v=XetHU_pAWOo[\/youtube]<\/p>\n<p>Los ordenadores han supuesto un cambio brutal en la manera de investigar y aplicar las matem\u00e1ticas, y estos son los primeros indicios. La pel\u00edcula exhibe otro gui\u00f1o a la tecnolog\u00eda: los ordenadores nos pueden quitar el trabajo, pero hay que programarlos. Y Dorothy Vaughan entiende que si aprende FORTRAN, estar\u00e1 en ventaja para entender la m\u00e1quina, y as\u00ed ocurrir\u00e1 con las mujeres calculadoras que ella entrena.<\/p>\n<p>Pero, \u00bfpodemos fiarnos de las computadoras? El \u00faltimo gui\u00f1o se debe a John Glenn: la m\u00e1quina est\u00e1 fallando, y el solo est\u00e1 dispuesto a ser lanzado si la chica comprueba los c\u00e1lculos.<\/p>\n<p>______<\/p>\n<p><strong><strong>Manuel de Le\u00f3n<\/strong>\u00a0<\/strong>(CSIC, Fundador del ICMAT, Real Academia de Ciencias, Real Academia Canaria de Ciencias, ICSU)<strong><\/strong><strong><strong><strong><\/strong><\/strong><\/strong>.<strong><strong><strong><br \/>\n<\/strong><\/strong><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata de combatir esta invisibilidad. En este blog hemos contado historias de mujeres matem\u00e1ticas que tuvieron que realizar grandes esfuerzos para cultivar la ciencia que les gustaba, mujeres que han tenido que ocultar su condici\u00f3n bajo un seud\u00f3nimo, mujeres a las que no les estaba permitido\u2026<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[33660,36915,1589,8683,36917],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Matem\u00e1ticas y sus fronteras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta property=\"og:description\" content=\"Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-01-30T09:16:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-01-30T09:16:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161#blogposting\",\"name\":\"\\u201cGet the girl to check the numbers\\u201d - Matem\\u00e1ticas y sus fronteras\",\"headline\":\"\\u201cGet the girl to check the numbers\\u201d\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2017\\\/01\\\/lead_960-300x200.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161\\\/#articleImage\"},\"datePublished\":\"2017-01-30T10:16:46+01:00\",\"dateModified\":\"2017-01-30T10:16:46+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":4,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161#webpage\"},\"articleSection\":\"General, Euler, geometr\\u00eda anal\\u00edtica, NASA, Newton, proyecto Mercurio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161#listItem\",\"name\":\"\\u201cGet the girl to check the numbers\\u201d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161#listItem\",\"position\":3,\"name\":\"\\u201cGet the girl to check the numbers\\u201d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Matem\\u00e1ticas y sus fronteras\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161\",\"name\":\"\\u201cGet the girl to check the numbers\\u201d - Matem\\u00e1ticas y sus fronteras\",\"description\":\"Esta entrada est\\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\\u00f3n cient\\u00edfica. Hemos tenido la oportunidad de asistir a una pel\\u00edcula, \\u201cFiguras ocultas\\u201d, que trata\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/01\\\/30\\\/143161#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"datePublished\":\"2017-01-30T10:16:46+01:00\",\"dateModified\":\"2017-01-30T10:16:46+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras","description":"Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#blogposting","name":"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras","headline":"\u201cGet the girl to check the numbers\u201d","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960-300x200.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161\/#articleImage"},"datePublished":"2017-01-30T10:16:46+01:00","dateModified":"2017-01-30T10:16:46+01:00","inLanguage":"es-ES","commentCount":4,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#webpage"},"articleSection":"General, Euler, geometr\u00eda anal\u00edtica, NASA, Newton, proyecto Mercurio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#listItem","name":"\u201cGet the girl to check the numbers\u201d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#listItem","position":3,"name":"\u201cGet the girl to check the numbers\u201d","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization","name":"Matem\u00e1ticas y sus fronteras","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","width":96,"height":96,"caption":"Matem\u00e1ticas y sus fronteras"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161","name":"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras","description":"Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"datePublished":"2017-01-30T10:16:46+01:00","dateModified":"2017-01-30T10:16:46+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Matem\u00e1ticas y sus fronteras -","og:type":"article","og:title":"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras","og:description":"Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata","og:url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161","og:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","article:published_time":"2017-01-30T09:16:46+00:00","article:modified_time":"2017-01-30T09:16:46+00:00","twitter:card":"summary","twitter:title":"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras","twitter:description":"Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"143161","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 18:14:44","updated":"2026-05-28 10:56:37","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u201cGet the girl to check the numbers\u201d\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general"},{"label":"\u201cGet the girl to check the numbers\u201d","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"og:description\" content=\"Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata de combatir esta invisibilidad. En este blog hemos contado historias de mujeres matem\u00e1ticas que tuvieron que realizar grandes esfuerzos para cultivar la ciencia que les gustaba, mujeres que han tenido que ocultar su condici\u00f3n bajo un seud\u00f3nimo, mujeres a las que no les estaba permitido\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161\" \/>\n<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-30T09:16:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960-300x200.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#primaryimage\",\"inLanguage\":\"es\",\"url\":\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960-300x200.jpg\",\"contentUrl\":\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960-300x200.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#webpage\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161\",\"name\":\"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras\",\"isPartOf\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#primaryimage\"},\"datePublished\":\"2017-01-30T09:16:46+00:00\",\"dateModified\":\"2017-01-30T09:16:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cGet the girl to check the numbers\u201d\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"caption\":\"Matem\u00e1ticas y sus fronteras\"},\"description\":\"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161","og_locale":"es_ES","og_type":"article","og_title":"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras","og_description":"Esta entrada est\u00e1 dedicada a mi amiga Victoria, que observa todos los amaneceres El debate sobre el techo de cristal est\u00e1 cada vez mas vivo, y una de sus facetas es la falta de visibilidad de las mujeres en la investigaci\u00f3n cient\u00edfica. Hemos tenido la oportunidad de asistir a una pel\u00edcula, \u201cFiguras ocultas\u201d, que trata de combatir esta invisibilidad. En este blog hemos contado historias de mujeres matem\u00e1ticas que tuvieron que realizar grandes esfuerzos para cultivar la ciencia que les gustaba, mujeres que han tenido que ocultar su condici\u00f3n bajo un seud\u00f3nimo, mujeres a las que no les estaba permitido\u2026","og_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161","og_site_name":"Matem\u00e1ticas y sus fronteras","article_published_time":"2017-01-30T09:16:46+00:00","og_image":[{"url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960-300x200.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Matem\u00e1ticas y sus fronteras","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#primaryimage","inLanguage":"es","url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960-300x200.jpg","contentUrl":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/01\/lead_960-300x200.jpg"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161","name":"\u201cGet the girl to check the numbers\u201d - Matem\u00e1ticas y sus fronteras","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#primaryimage"},"datePublished":"2017-01-30T09:16:46+00:00","dateModified":"2017-01-30T09:16:46+00:00","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/01\/30\/143161#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"@type":"ListItem","position":2,"name":"\u201cGet the girl to check the numbers\u201d"}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","caption":"Matem\u00e1ticas y sus fronteras"},"description":"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas"}]}},"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/143161"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/comments?post=143161"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/143161\/revisions"}],"predecessor-version":[{"id":143174,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/143161\/revisions\/143174"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/media?parent=143161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/categories?post=143161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/tags?post=143161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}