{"id":144267,"date":"2017-09-09T10:23:20","date_gmt":"2017-09-09T09:23:20","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/?p=144267"},"modified":"2017-09-09T10:23:20","modified_gmt":"2017-09-09T09:23:20","slug":"construyendo-la-catedral-de-la-inteligencia-artificial","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267","title":{"rendered":"Construyendo la catedral de la Inteligencia Artificial"},"content":{"rendered":"<p>Traemos hoy a <em>Matem\u00e1ticas y sus fronteras<\/em> un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n <em>\u00bfQu\u00e9 sabemos de?<\/em> que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-144271\" title=\"35ffedd03b7794a83de08ad79ebbdb2e08d12419\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png\" alt=\"\" width=\"150\" height=\"231\" \/><\/a><\/p>\n<p>La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos. Sabemos que eso que llamamos inteligencia no es exclusiva de los seres humanos, que los animales exhiben comportamientos inteligentes, y que se deber\u00eda hablar de inteligencias en plural. Y quiz\u00e1s lo que estamos construyendo como IA podr\u00eda llegar a ser considerado como un tipo nuevo de inteligencia.<\/p>\n<p>La IA se divide en la IA d\u00e9bil (dise\u00f1ar y programar ordenadores que requieran inteligencia) y la IA fuerte (que esas m\u00e1quinas repliquen la inteligencia humana). Estamos lejos de la IA fuerte pero convivimos ya con la IA d\u00e9bil. Esta distinci\u00f3n fue introducida por el fil\u00f3sofo John Searle, en 1980, en un art\u00edculo que levant\u00f3 una gran pol\u00e9mica.<\/p>\n<p>Lejos quedan aquellos pioneros trabajos de Alan Turing, desarrollando primero el concepto de m\u00e1quina de Turing y luego pregunt\u00e1ndose si las m\u00e1quinas pueden pensar, desarrollando programas de ordenador para el juego de ajedrez o el famoso test de Turing para decidir si estamos conversando con una m\u00e1quina o con un ser humano. No sabemos de lo que hubiera sido capaz Turing sin su tr\u00e1gica muerte en 1954. Poco despu\u00e9s, en 1956, se produjo el encuentro de Dartmouth (New Hampshire), con John McCarthy, Marvin Minsky y Claude Shannon, entre otros, que supuso un lanzamiento de la investigaci\u00f3n en IA. Fue John McCarthy qui\u00e9n acu\u00f1\u00f3 el t\u00e9rmino <em>inteligencia artificial<\/em>, como \u00ab&#8230;la ciencia e ingenio de hacer m\u00e1quinas inteligentes, especialmente programas de c\u00f3mputo inteligentes\u00bb.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/ejemplo-del-concepto-de-la-inteligencia-artificial-29416986.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-144276\" title=\"ejemplo-del-concepto-de-la-inteligencia-artificial-29416986\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/ejemplo-del-concepto-de-la-inteligencia-artificial-29416986-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/ejemplo-del-concepto-de-la-inteligencia-artificial-29416986-300x225.jpg 300w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/ejemplo-del-concepto-de-la-inteligencia-artificial-29416986.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Este libro, del que llama la atenci\u00f3n una hermosa portada, hace un recorrido por la inteligencia artificial, desde sus or\u00edgenes hasta el d\u00eda de hoy, analizando los logros pero tambi\u00e9n las limitaciones encontradas, y analizando el posible futuro del tema.<\/p>\n<p>Recuerdan los autores del libro \u201cInteligencia Artificial\u201d lo que se conoce en su campo como la met\u00e1fora de la catedral: construir una IA de prop\u00f3sito general es como construir una catedral. La construcci\u00f3n de la primera catedral requiri\u00f3 de varias generaciones y muchos de los que trabajaron en ellas murieron sin llegar a ver terminada la obra. Cada artesano que trabajaba para la catedral constru\u00eda ladrillos cada vez m\u00e1s perfectos. As\u00ed se ven ahora los investigadores en inteligencia artificial, construyendo los ladrillos (algoritmos en este caso) que conformar\u00e1n la catedral.<\/p>\n<figure id=\"attachment_144272\" aria-describedby=\"caption-attachment-144272\" style=\"width: 150px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/e976b6feb2e0a0045d8681701a1c96d74f7f323a.jpg\"><img decoding=\"async\" class=\"size-full wp-image-144272\" title=\"e976b6feb2e0a0045d8681701a1c96d74f7f323a\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/e976b6feb2e0a0045d8681701a1c96d74f7f323a.jpg\" alt=\"\" width=\"150\" height=\"229\" \/><\/a><figcaption id=\"caption-attachment-144272\" class=\"wp-caption-text\">Ram\u00f3n L\u00f3pez de M\u00e1ntaras Badia<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_144273\" aria-describedby=\"caption-attachment-144273\" style=\"width: 150px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/db5d9eccf9e44768a8f79b713d7717b1ea8394c9.jpg\"><img decoding=\"async\" class=\"size-full wp-image-144273\" title=\"db5d9eccf9e44768a8f79b713d7717b1ea8394c9\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/db5d9eccf9e44768a8f79b713d7717b1ea8394c9.jpg\" alt=\"\" width=\"150\" height=\"235\" \/><\/a><figcaption id=\"caption-attachment-144273\" class=\"wp-caption-text\">Pedro Messeguer Gonz\u00e1lez<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Los autores<\/strong><\/p>\n<p><strong>Ramon L\u00f3pez de M\u00e1ntaras Badia<\/strong> es Profesor de Investigaci\u00f3n del CSIC y director del Instituto de Investigaci\u00f3n en Inteligencia Artificial. Es uno de los pioneros de la inteligencia artificial en Espa\u00f1a. Actualmente investiga en razonamiento y aprendizaje basado en casos, en robots aut\u00f3nomos capaces de aprender interactuando con su entorno f\u00edsico y en inteligencia artificial aplicada a la m\u00fasica.<\/p>\n<p><strong>Pedro Meseguer Gonz\u00e1lez<\/strong> es Investigador cient\u00edfico del CSIC en el Instituto de Investigaci\u00f3n en Inteligencia Artificial, donde es jefe del Departamento de L\u00f3gica. Sus principales temas de investigaci\u00f3n son el razonamiento con restricciones (con especial atenci\u00f3n a la versi\u00f3n distribuida) y la b\u00fasqueda heur\u00edstica.<\/p>\n<p>______<\/p>\n<p><strong><strong>Manuel de Le\u00f3n<\/strong>\u00a0<\/strong>(CSIC, Fundador y Director del ICMAT, Real Academia de Ciencias, Real Academia Canaria de Ciencias, ICSU)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos. Sabemos que eso que llamamos inteligencia no es exclusiva de los seres humanos, que los animales exhiben comportamientos inteligentes, y que se deber\u00eda hablar de inteligencias en plural. Y quiz\u00e1s lo que estamos construyendo como IA podr\u00eda llegar a ser considerado como un tipo nuevo\u2026<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[23624,28497],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Matem\u00e1ticas y sus fronteras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta property=\"og:description\" content=\"Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-09-09T09:23:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-09-09T09:23:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267#blogposting\",\"name\":\"Construyendo la catedral de la Inteligencia Artificial - Matem\\u00e1ticas y sus fronteras\",\"headline\":\"Construyendo la catedral de la Inteligencia Artificial\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2017\\\/09\\\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267\\\/#articleImage\",\"width\":150,\"height\":231},\"datePublished\":\"2017-09-09T10:23:20+01:00\",\"dateModified\":\"2017-09-09T10:23:20+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267#webpage\"},\"articleSection\":\"General, algoritmo, inteligencia artificial\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267#listItem\",\"name\":\"Construyendo la catedral de la Inteligencia Artificial\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267#listItem\",\"position\":3,\"name\":\"Construyendo la catedral de la Inteligencia Artificial\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Matem\\u00e1ticas y sus fronteras\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267\",\"name\":\"Construyendo la catedral de la Inteligencia Artificial - Matem\\u00e1ticas y sus fronteras\",\"description\":\"Traemos hoy a Matem\\u00e1ticas y sus fronteras un interesante libro reci\\u00e9n salido de la imprenta: \\u201cInteligencia Artificial\\u201d, la \\u00faltima entrega de la colecci\\u00f3n \\u00bfQu\\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\\u00edficas y La Catarata llevan adelante con mucho \\u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\\u00e1s apasionantes de nuestros tiempos.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2017\\\/09\\\/09\\\/144267#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"datePublished\":\"2017-09-09T10:23:20+01:00\",\"dateModified\":\"2017-09-09T10:23:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras","description":"Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos.","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#blogposting","name":"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras","headline":"Construyendo la catedral de la Inteligencia Artificial","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267\/#articleImage","width":150,"height":231},"datePublished":"2017-09-09T10:23:20+01:00","dateModified":"2017-09-09T10:23:20+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#webpage"},"articleSection":"General, algoritmo, inteligencia artificial"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#listItem","name":"Construyendo la catedral de la Inteligencia Artificial"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#listItem","position":3,"name":"Construyendo la catedral de la Inteligencia Artificial","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization","name":"Matem\u00e1ticas y sus fronteras","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","width":96,"height":96,"caption":"Matem\u00e1ticas y sus fronteras"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267","name":"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras","description":"Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"datePublished":"2017-09-09T10:23:20+01:00","dateModified":"2017-09-09T10:23:20+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Matem\u00e1ticas y sus fronteras -","og:type":"article","og:title":"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras","og:description":"Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos.","og:url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267","og:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","article:published_time":"2017-09-09T09:23:20+00:00","article:modified_time":"2017-09-09T09:23:20+00:00","twitter:card":"summary","twitter:title":"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras","twitter:description":"Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos.","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"144267","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 23:09:51","updated":"2026-05-28 11:07:40","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tConstruyendo la catedral de la Inteligencia Artificial\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general"},{"label":"Construyendo la catedral de la Inteligencia Artificial","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"og:description\" content=\"Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos. Sabemos que eso que llamamos inteligencia no es exclusiva de los seres humanos, que los animales exhiben comportamientos inteligentes, y que se deber\u00eda hablar de inteligencias en plural. Y quiz\u00e1s lo que estamos construyendo como IA podr\u00eda llegar a ser considerado como un tipo nuevo\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267\" \/>\n<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-09T09:23:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#primaryimage\",\"inLanguage\":\"es\",\"url\":\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png\",\"contentUrl\":\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#webpage\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267\",\"name\":\"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras\",\"isPartOf\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#primaryimage\"},\"datePublished\":\"2017-09-09T09:23:20+00:00\",\"dateModified\":\"2017-09-09T09:23:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Construyendo la catedral de la Inteligencia Artificial\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"caption\":\"Matem\u00e1ticas y sus fronteras\"},\"description\":\"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267","og_locale":"es_ES","og_type":"article","og_title":"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras","og_description":"Traemos hoy a Matem\u00e1ticas y sus fronteras un interesante libro reci\u00e9n salido de la imprenta: \u201cInteligencia Artificial\u201d, la \u00faltima entrega de la colecci\u00f3n \u00bfQu\u00e9 sabemos de? que el Consejo Superior de Investigaciones Cient\u00edficas y La Catarata llevan adelante con mucho \u00e9xito. La Inteligencia Artificial (IA) es uno de los temas m\u00e1s apasionantes de nuestros tiempos. Sabemos que eso que llamamos inteligencia no es exclusiva de los seres humanos, que los animales exhiben comportamientos inteligentes, y que se deber\u00eda hablar de inteligencias en plural. Y quiz\u00e1s lo que estamos construyendo como IA podr\u00eda llegar a ser considerado como un tipo nuevo\u2026","og_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267","og_site_name":"Matem\u00e1ticas y sus fronteras","article_published_time":"2017-09-09T09:23:20+00:00","og_image":[{"url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Matem\u00e1ticas y sus fronteras","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#primaryimage","inLanguage":"es","url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png","contentUrl":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2017\/09\/35ffedd03b7794a83de08ad79ebbdb2e08d12419.png"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267","name":"Construyendo la catedral de la Inteligencia Artificial - Matem\u00e1ticas y sus fronteras","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#primaryimage"},"datePublished":"2017-09-09T09:23:20+00:00","dateModified":"2017-09-09T09:23:20+00:00","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2017\/09\/09\/144267#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"@type":"ListItem","position":2,"name":"Construyendo la catedral de la Inteligencia Artificial"}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","caption":"Matem\u00e1ticas y sus fronteras"},"description":"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas"}]}},"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/144267"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/comments?post=144267"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/144267\/revisions"}],"predecessor-version":[{"id":144279,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/144267\/revisions\/144279"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/media?parent=144267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/categories?post=144267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/tags?post=144267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}