{"id":148622,"date":"2020-12-04T14:04:28","date_gmt":"2020-12-04T13:04:28","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/?p=148622"},"modified":"2020-12-04T14:05:04","modified_gmt":"2020-12-04T13:05:04","slug":"creado-el-comite-de-la-diversidad-en-la-union-matematica-internacional","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622","title":{"rendered":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional"},"content":{"rendered":"<p>Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas).<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-148629\" title=\"cod\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg\" alt=\"\" width=\"486\" height=\"479\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg 486w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2-300x295.jpg 300w\" sizes=\"(max-width: 486px) 100vw, 486px\" \/><\/a>En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones de la diversidad y la inclusi\u00f3n. Muchos pa\u00edses, instituciones y organizaciones han reconocido la necesidad de reevaluar su relaci\u00f3n con estas cuestiones. Muchas instituciones se han dado cuenta de que hay que reconsiderar las antiguas pol\u00edticas y que hay que adoptar muchas m\u00e1s medidas activas para abordar la diversidad y la inclusi\u00f3n, y asegurarse de que el tratamiento de estas cuestiones se incorpore plenamente en sus actividades y en su proceso de adopci\u00f3n de decisiones.\u201d El CdD se estableci\u00f3 a finales de agosto de 2020.<\/p>\n<p>No es algo nuevo en IMU, porque la preocupaci\u00f3n por la igualdad, la diversidad, la situaci\u00f3n en los pa\u00edses en v\u00edas de desarrollo, es una constante en la Uni\u00f3n. Por eso se cre\u00f3 en su momento la Comisi\u00f3n de Pa\u00edses en Desarrollo (CDC) , y m\u00e1s recientemente el Comit\u00e9 para las Mujeres en las Matem\u00e1ticas (CWM). Pero ahora IMU ha visto que hab\u00eda que dar un paso m\u00e1s en la nueva sociedad que se est\u00e1 construyendo, en la que temas como la diversidad \u00a0y la inclusi\u00f3n est\u00e1n en primera fila de la agenda. No olvidemos tampoco la labor que IMU desarrolla en la ense\u00f1anza de las matem\u00e1ticas a trav\u00e9s de la Comisi\u00f3n Internacional para la Instrucci\u00f3n Matem\u00e1tica (ICMI). Educaci\u00f3n e investigaci\u00f3n son dos \u00e1reas donde acciones para fomentar estos dos valores, igualdad e inclusi\u00f3n, son particularmente eficaces.<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/IMU1.png\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-148632\" title=\"IMU\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/IMU1-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/IMU1-300x300.png 300w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/IMU1-150x150.png 150w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/IMU1.png 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: left;\">A veces no se entiende bien a lo que nos referimos cuando hablamos de diversidad, pero Carlos Kenig lo deja muy claro: \u201cPor diversidad entendemos aqu\u00ed las cuestiones relativas a la raza, el g\u00e9nero, la identidad de g\u00e9nero y la orientaci\u00f3n sexual, la etnia, las discapacidades, la geograf\u00eda, los antecedentes desfavorecidos, as\u00ed como las creencias pol\u00edticas y religiosas y cuestiones conexas.\u201d<\/p>\n<p>Las tareas que se le ha encargado al CdD son:<\/p>\n<p>1. una evaluaci\u00f3n de c\u00f3mo se desempe\u00f1a IMU en cuanto a la diversidad e inclusi\u00f3n.<\/p>\n<p>2. un asesoramiento sobre c\u00f3mo IMU puede mejorar sus actividades con respecto a la diversidad y la inclusi\u00f3n en sus actividades.<\/p>\n<p>3. hacer recomendaciones a IMU sobre c\u00f3mo se puede asesorar y ayudar a sus miembros en relaci\u00f3n con la diversidad y la inclusi\u00f3n.<\/p>\n<p>Este Comit\u00e9 es<em> ad hoc<\/em>, su misi\u00f3n de momento es elaborar un informe que ser\u00e1 sometido para su aprobaci\u00f3n en la pr\u00f3xima Asamblea General de IMU, previa al Congreso Internacional de Matem\u00e1ticos (ICM) a celebrar en San Petersburgo (Rusia) en 2022.<\/p>\n<p>IMU hace un llamamiemnto p\u00fablico a que matem\u00e1ticos de todo el mundo contacten con los miembros del CdD para enviar sugerencias y propuestas de acciones (a Robert Bryant, Chair, USA (chair@cod.mathunion.org). El Presidente de este Comit\u00e9 es Robert Bryant, de los Estados Unidos y el resto de los miembros son:<\/p>\n<p>Gugu Moreira, Brazil<\/p>\n<p>Ngo Bao Chau, USA\/Vietnam<\/p>\n<p>Tatiana Toro, USA\/Colombia<\/p>\n<p>Philibert Nang, Gabon<\/p>\n<p>Elena V\u00e1zquez Abal, Spain<\/p>\n<p>Anjum Halai, Pakistan<\/p>\n<p>Sophie Dabo-Niang, France\/Senegal<\/p>\n<p>Edy Tri Baskoro, Indonesia<\/p>\n<p>Edray Goins, USA<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_148626\" aria-describedby=\"caption-attachment-148626\" style=\"width: 410px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/elena.jpg\"><img decoding=\"async\" class=\" wp-image-148626 \" title=\"elena\" src=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/elena.jpg\" alt=\"\" width=\"410\" height=\"410\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/elena.jpg 512w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/elena-150x150.jpg 150w, https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/elena-300x300.jpg 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/><\/a><figcaption id=\"caption-attachment-148626\" class=\"wp-caption-text\">Elena V\u00e1zquez Abal<\/figcaption><\/figure>\n<p>Entre ellos es una satisfacci\u00f3n encontrar a nuestra colega Elena V\u00e1zquez Abal, profesora de la Universidad de Santiago de Compostela, especialista en Geometr\u00eda Diferencial y muy activa en tareas de divulgaci\u00f3n de las matem\u00e1ticas.<\/p>\n<p>___________<\/p>\n<p><strong>Manuel de Le\u00f3n<\/strong> (CSIC, Fundador del ICMAT, Real Academia de Ciencias, Real Academia Canaria de Ciencias, Real Academia Galega de Ciencias).<\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones de la diversidad y la inclusi\u00f3n. Muchos pa\u00edses, instituciones y organizaciones han reconocido la necesidad de reevaluar su relaci\u00f3n con estas cuestiones. Muchas instituciones se han dado cuenta de que hay que reconsiderar las antiguas pol\u00edticas y que hay que adoptar muchas m\u00e1s medidas activas\u2026<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1,28531],"tags":[43000,28543],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Matem\u00e1ticas y sus fronteras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta property=\"og:description\" content=\"Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-12-04T13:04:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-12-04T13:05:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622#blogposting\",\"name\":\"Creado el Comit\\u00e9 de la Diversidad en la Uni\\u00f3n Matem\\u00e1tica Internacional - Matem\\u00e1ticas y sus fronteras\",\"headline\":\"Creado el Comit\\u00e9 de la Diversidad en la Uni\\u00f3n Matem\\u00e1tica Internacional\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2020\\\/12\\\/cod2.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622\\\/#articleImage\",\"width\":486,\"height\":479},\"datePublished\":\"2020-12-04T14:04:28+01:00\",\"dateModified\":\"2020-12-04T14:05:04+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622#webpage\"},\"articleSection\":\"General, Mujeres matem\\u00e1ticas, Comit\\u00e9 patra la Diversidad, IMU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622#listItem\",\"name\":\"Creado el Comit\\u00e9 de la Diversidad en la Uni\\u00f3n Matem\\u00e1tica Internacional\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622#listItem\",\"position\":3,\"name\":\"Creado el Comit\\u00e9 de la Diversidad en la Uni\\u00f3n Matem\\u00e1tica Internacional\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Matem\\u00e1ticas y sus fronteras\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622\",\"name\":\"Creado el Comit\\u00e9 de la Diversidad en la Uni\\u00f3n Matem\\u00e1tica Internacional - Matem\\u00e1ticas y sus fronteras\",\"description\":\"Nos hacemos eco en Matem\\u00e1ticas y sus fronteras del reci\\u00e9n creado Comit\\u00e9 para la Diversidad (CdD) en el seno de la Uni\\u00f3n Matem\\u00e1tica Internacional (IMU en sus siglas inglesas). En el \\u00faltimo bolet\\u00edn electr\\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \\u201cEste a\\u00f1o ha atra\\u00eddo una mayor atenci\\u00f3n, en todo el mundo, a las cuestiones\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2020\\\/12\\\/04\\\/148622#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"datePublished\":\"2020-12-04T14:04:28+01:00\",\"dateModified\":\"2020-12-04T14:05:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras","description":"Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#blogposting","name":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras","headline":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622\/#articleImage","width":486,"height":479},"datePublished":"2020-12-04T14:04:28+01:00","dateModified":"2020-12-04T14:05:04+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#webpage"},"articleSection":"General, Mujeres matem\u00e1ticas, Comit\u00e9 patra la Diversidad, IMU"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#listItem","name":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#listItem","position":3,"name":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization","name":"Matem\u00e1ticas y sus fronteras","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","width":96,"height":96,"caption":"Matem\u00e1ticas y sus fronteras"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622","name":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras","description":"Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"datePublished":"2020-12-04T14:04:28+01:00","dateModified":"2020-12-04T14:05:04+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Matem\u00e1ticas y sus fronteras -","og:type":"article","og:title":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras","og:description":"Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones","og:url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622","og:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","article:published_time":"2020-12-04T13:04:28+00:00","article:modified_time":"2020-12-04T13:05:04+00:00","twitter:card":"summary","twitter:title":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras","twitter:description":"Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"148622","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:08:24","updated":"2026-05-28 11:58:43","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCreado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general"},{"label":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"og:description\" content=\"Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones de la diversidad y la inclusi\u00f3n. Muchos pa\u00edses, instituciones y organizaciones han reconocido la necesidad de reevaluar su relaci\u00f3n con estas cuestiones. Muchas instituciones se han dado cuenta de que hay que reconsiderar las antiguas pol\u00edticas y que hay que adoptar muchas m\u00e1s medidas activas\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622\" \/>\n<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-04T13:04:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-04T13:05:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#primaryimage\",\"inLanguage\":\"es\",\"url\":\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg\",\"contentUrl\":\"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#webpage\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622\",\"name\":\"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras\",\"isPartOf\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#primaryimage\"},\"datePublished\":\"2020-12-04T13:04:28+00:00\",\"dateModified\":\"2020-12-04T13:05:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"caption\":\"Matem\u00e1ticas y sus fronteras\"},\"description\":\"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622","og_locale":"es_ES","og_type":"article","og_title":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras","og_description":"Nos hacemos eco en Matem\u00e1ticas y sus fronteras del reci\u00e9n creado Comit\u00e9 para la Diversidad (CdD) en el seno de la Uni\u00f3n Matem\u00e1tica Internacional (IMU en sus siglas inglesas). En el \u00faltimo bolet\u00edn electr\u00f3nico de IMU, su Presidente, Carlos Kenig dice: \u201cEste a\u00f1o ha atra\u00eddo una mayor atenci\u00f3n, en todo el mundo, a las cuestiones de la diversidad y la inclusi\u00f3n. Muchos pa\u00edses, instituciones y organizaciones han reconocido la necesidad de reevaluar su relaci\u00f3n con estas cuestiones. Muchas instituciones se han dado cuenta de que hay que reconsiderar las antiguas pol\u00edticas y que hay que adoptar muchas m\u00e1s medidas activas\u2026","og_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622","og_site_name":"Matem\u00e1ticas y sus fronteras","article_published_time":"2020-12-04T13:04:28+00:00","article_modified_time":"2020-12-04T13:05:04+00:00","og_image":[{"url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Matem\u00e1ticas y sus fronteras","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#primaryimage","inLanguage":"es","url":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg","contentUrl":"http:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2020\/12\/cod2.jpg"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622","name":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional - Matem\u00e1ticas y sus fronteras","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#primaryimage"},"datePublished":"2020-12-04T13:04:28+00:00","dateModified":"2020-12-04T13:05:04+00:00","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2020\/12\/04\/148622#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"@type":"ListItem","position":2,"name":"Creado el Comit\u00e9 de la Diversidad en la Uni\u00f3n Matem\u00e1tica Internacional"}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","caption":"Matem\u00e1ticas y sus fronteras"},"description":"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas"}]}},"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/148622"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/comments?post=148622"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/148622\/revisions"}],"predecessor-version":[{"id":148636,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/148622\/revisions\/148636"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/media?parent=148622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/categories?post=148622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/tags?post=148622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}