{"id":29474,"date":"2006-06-12T10:50:00","date_gmt":"2006-06-12T10:50:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/matematicas\/archive\/2006\/06\/12\/29474.aspx"},"modified":"2006-06-12T10:50:00","modified_gmt":"2006-06-12T10:50:00","slug":"inauguracion-del-blog-sobre-matematicas-y-sus-fronteras","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474","title":{"rendered":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras"},"content":{"rendered":"<p align=\"justify\"><span style=\"FONT-SIZE: 12pt; COLOR: #222222; FONT-FAMILY: Times; mso-fareast-font-family: 'Times New Roman'; mso-ansi-language: ES; mso-fareast-language: ES; mso-bidi-language: AR-SA\">Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la <\/span><span style=\"FONT-SIZE: 12pt; FONT-FAMILY: 'Times New Roman'; mso-fareast-font-family: 'Times New Roman'; mso-ansi-language: ES; mso-fareast-language: ES; mso-bidi-language: AR-SA\">modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda<\/span><span style=\"FONT-SIZE: 12pt; COLOR: #222222; FONT-FAMILY: Times; mso-fareast-font-family: 'Times New Roman'; mso-ansi-language: ES; mso-fareast-language: ES; mso-bidi-language: AR-SA\">, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog se har\u00e1 de manera colegiada, con aportaciones de un grupo de investigaci\u00f3n interinstitucional que recientemente se ha constituido en Madrid para trabajar sobre estas l\u00edneas. Se puede consultar m\u00e1s sobre este grupo llamado <A href=\"http:\/\/weblogs.madrimasd.org\/matematicas\/archive\/2006\/06\/13\/29719.aspx\">SIMUMAT<\/a><\/span><\/p>\n<p><!--more--><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"COLOR: #222222; FONT-FAMILY: Times\">El siglo XX ha sido sumamente fruct\u00edfero en todos los campos de las matem\u00e1ticas, y ha visto surgir, desarrollarse y diversificarse lo que hoy se conoce como matem\u00e1tica aplicada que, con el vertiginoso desarrollo de las computadoras, se ha convertido en un nuevo paradigma cient\u00edfico. Los avances que se han producido en las Matem\u00e1ticas han sido espectaculares y las aplicaciones a las que \u00e9stas han dado lugar han sido definitivas en muchos campos. Pero este \u00e9xito rotundo parece no ser m\u00e1s que la antesala de lo que ocurrir\u00e1 en el siglo XXI, cuando la sinergia entre las Matem\u00e1ticas y las dem\u00e1s ciencias se generalice gracias a las ideas de modelizaci\u00f3n y simulaci\u00f3n: si el siglo pasado fue el del maridaje entre Matem\u00e1ticas y F\u00edsica, del que tanto se beneficiaron ambas, \u00e9ste ser\u00e1 el de las Matem\u00e1ticas y la Biolog\u00eda, las Matem\u00e1ticas y la Ciencia de Materiales, o las Matem\u00e1ticas y las Ciencias Sociales.<?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"COLOR: #222222; FONT-FAMILY: Times\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"COLOR: #222222; FONT-FAMILY: Times\">Los nuevos resultados de las Matem\u00e1ticas son cada vez m\u00e1s inesperados y sus aplicaciones m\u00e1s impactantes, y surgen, casi siempre, en los \u00e1mbitos de investigaci\u00f3n multidisciplinares como el propuesto por el grupo <A href=\"http:\/\/weblogs.madrimasd.org\/matematicas\/archive\/2006\/06\/13\/29719.aspx\">SIMUMAT<\/a>, es decir, en la interacci\u00f3n entre las Matem\u00e1ticas y los problemas reales. Por un lado, las necesidades de otras ciencias exigen a las Matem\u00e1ticas empujar sus fronteras cada vez m\u00e1s lejos y, por otro, las Matem\u00e1ticas, a trav\u00e9s de los modelos y su simulaci\u00f3n, sugieren nuevas aplicaciones en los campos m\u00e1s diversos. As\u00ed, las Matem\u00e1ticas pasan de los \u00e1ridos libros y art\u00edculos de los especialistas a la vida cotidiana, y est\u00e1n detr\u00e1s de desarrollos fundamentales que van, por ejemplo, desde la nanotecnolog\u00eda a las finanzas pasando por el dise\u00f1o aeron\u00e1utico. Problemas como estos, entre otros, son el objetivo de <A href=\"http:\/\/weblogs.madrimasd.org\/matematicas\/archive\/2006\/06\/13\/29719.aspx\">SIMUMAT<\/a>.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"COLOR: #222222; FONT-FAMILY: Times\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify; mso-layout-grid-align: none\"><span style=\"FONT-FAMILY: Times; mso-bidi-font-family: Arial\">SIMUMAT pretende convertirse en punta de lanza en estas direcciones. Hasta hace muy poco los matem\u00e1ticos espa\u00f1oles, y en particular los madrile\u00f1os, no han comenzado a adentrarse en este nuevo mundo que se abre por delante. Para conseguir una aut\u00e9ntica transferencia del conocimiento matem\u00e1tico a los sectores tecnol\u00f3gicos, productivos y financieros, los matem\u00e1ticos necesitan ser conscientes de las nuevas oportunidades, reflexionando sobre sus respectivos campos de trabajo, intentando dar una panor\u00e1mica de las Matem\u00e1ticas del siglo XXI, identificando los grandes problemas y mostrando los campos que est\u00e1n esperando para su desarrollo. En este sentido, la celebraci\u00f3n en Madrid del pr\u00f3ximo Congreso Internacional de Matem\u00e1ticos <a href=\"http:\/\/www.icm2006.org\/\">[link]<\/a> ser\u00e1 una ocasi\u00f3n \u00fanica para tales reflexiones, para discutir y dar a conocer el futuro de esta apasionante ciencia que son las Matem\u00e1ticas. Eso es lo que este nuevo blog de Madri+d pretende (modestamente) mostrar, complementando con esta particular visi\u00f3n de frontera otras iniciativas como <a href=\"http:\/\/www.divulgamat.net\/\">divulgamat<\/a>, <a href=\"http:\/\/www.matematicalia.net\/\">matematicalia<\/a>.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify; mso-layout-grid-align: none\"><span style=\"FONT-FAMILY: Times; mso-bidi-font-family: Arial\"><\/span>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify; mso-layout-grid-align: none\"><span style=\"FONT-FAMILY: Times; mso-bidi-font-family: Arial\">El Grupo SIMUMAT<\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"COLOR: #222222; FONT-FAMILY: Times\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog se har\u00e1 de manera colegiada, con aportaciones de un grupo de investigaci\u00f3n interinstitucional que recientemente se ha constituido en Madrid para trabajar sobre estas l\u00edneas. Se puede consultar m\u00e1s sobre este grupo llamado SIMUMAT<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Matem\u00e1ticas y sus fronteras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta property=\"og:description\" content=\"Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-06-12T10:50:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-06-12T10:50:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474#blogposting\",\"name\":\"Inauguraci\\u00f3n del blog sobre Matem\\u00e1ticas y sus Fronteras - Matem\\u00e1ticas y sus fronteras\",\"headline\":\"Inauguraci\\u00f3n del blog sobre Matem\\u00e1ticas y sus Fronteras\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-06-12T10:50:00+01:00\",\"dateModified\":\"2006-06-12T10:50:00+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":18,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474#listItem\",\"name\":\"Inauguraci\\u00f3n del blog sobre Matem\\u00e1ticas y sus Fronteras\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474#listItem\",\"position\":3,\"name\":\"Inauguraci\\u00f3n del blog sobre Matem\\u00e1ticas y sus Fronteras\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Matem\\u00e1ticas y sus fronteras\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474\",\"name\":\"Inauguraci\\u00f3n del blog sobre Matem\\u00e1ticas y sus Fronteras - Matem\\u00e1ticas y sus fronteras\",\"description\":\"Hoy estrenamos este nuevo blog sobre las Matem\\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\\u00f3n actual y accesible sobre la modelizaci\\u00f3n matem\\u00e1tica y la simulaci\\u00f3n num\\u00e9rica en Ciencia y Tecnolog\\u00eda, incidiendo particularmente en aquellos problemas que est\\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\\u00f3n del blog\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/2006\\\/06\\\/12\\\/29474#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/author\\\/matematicas#author\"},\"datePublished\":\"2006-06-12T10:50:00+01:00\",\"dateModified\":\"2006-06-12T10:50:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/\",\"name\":\"Matem\\u00e1ticas y sus fronteras\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/matematicas\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras","description":"Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#blogposting","name":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras","headline":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#articleImage","width":217,"height":72},"datePublished":"2006-06-12T10:50:00+01:00","dateModified":"2006-06-12T10:50:00+01:00","inLanguage":"es-ES","commentCount":18,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#listItem","name":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#listItem","position":3,"name":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization","name":"Matem\u00e1ticas y sus fronteras","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","width":96,"height":96,"caption":"Matem\u00e1ticas y sus fronteras"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474","name":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras","description":"Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas#author"},"datePublished":"2006-06-12T10:50:00+01:00","dateModified":"2006-06-12T10:50:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Matem\u00e1ticas y sus fronteras -","og:type":"article","og:title":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras","og:description":"Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog","og:url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474","og:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png","article:published_time":"2006-06-12T10:50:00+00:00","article:modified_time":"2006-06-12T10:50:00+00:00","twitter:card":"summary","twitter:title":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras","twitter:description":"Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"29474","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-04 11:22:01","updated":"2026-05-28 08:13:47","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tInauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/category\/general"},{"label":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras","link":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"og:description\" content=\"Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog se har\u00e1 de manera colegiada, con aportaciones de un grupo de investigaci\u00f3n interinstitucional que recientemente se ha constituido en Madrid para trabajar sobre estas l\u00edneas. Se puede consultar m\u00e1s sobre este grupo llamado SIMUMAT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474\" \/>\n<meta property=\"og:site_name\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n<meta property=\"article:published_time\" content=\"2006-06-12T10:50:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matem\u00e1ticas y sus fronteras\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#webpage\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474\",\"name\":\"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras\",\"isPartOf\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website\"},\"datePublished\":\"2006-06-12T10:50:00+00:00\",\"dateModified\":\"2006-06-12T10:50:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230\",\"name\":\"Matem\u00e1ticas y sus fronteras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g\",\"caption\":\"Matem\u00e1ticas y sus fronteras\"},\"description\":\"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.\",\"url\":\"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474","og_locale":"es_ES","og_type":"article","og_title":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras","og_description":"Hoy estrenamos este nuevo blog sobre las Matem\u00e1ticas y sus fronteras, que pretende ser un canal de informaci\u00f3n actual y accesible sobre la modelizaci\u00f3n matem\u00e1tica y la simulaci\u00f3n num\u00e9rica en Ciencia y Tecnolog\u00eda, incidiendo particularmente en aquellos problemas que est\u00e1n en la frontera del conocimiento y en la frontera entre conocimientos. La edici\u00f3n del blog se har\u00e1 de manera colegiada, con aportaciones de un grupo de investigaci\u00f3n interinstitucional que recientemente se ha constituido en Madrid para trabajar sobre estas l\u00edneas. Se puede consultar m\u00e1s sobre este grupo llamado SIMUMAT","og_url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474","og_site_name":"Matem\u00e1ticas y sus fronteras","article_published_time":"2006-06-12T10:50:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Matem\u00e1ticas y sus fronteras","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/","name":"Matem\u00e1ticas y sus fronteras","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474","name":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras - Matem\u00e1ticas y sus fronteras","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#website"},"datePublished":"2006-06-12T10:50:00+00:00","dateModified":"2006-06-12T10:50:00+00:00","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/2006\/06\/12\/29474#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.madrimasd.org\/blogs\/matematicas"},{"@type":"ListItem","position":2,"name":"Inauguraci\u00f3n del blog sobre Matem\u00e1ticas y sus Fronteras"}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#\/schema\/person\/15722bca1b77eece37f4c192bd1b5230","name":"Matem\u00e1ticas y sus fronteras","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50eb6cc40d97cb9ad268a3471c7e2492?s=96&d=mm&r=g","caption":"Matem\u00e1ticas y sus fronteras"},"description":"Manuel de Le\u00f3n es Profesor de Investigaci\u00f3n del CSIC, acad\u00e9mico de la Real Academia de Ciencias y su Tesorero, fundador del ICMAT (CSIC), acad\u00e9mico de la Real Academia Canaria de Ciencias y de la Real Academia Galega de Ciencias. Es adem\u00e1s Director del programa Estalmat.","url":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/author\/matematicas"}]}},"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/29474"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/comments?post=29474"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/posts\/29474\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/media?parent=29474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/categories?post=29474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/matematicas\/wp-json\/wp\/v2\/tags?post=29474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}