{"id":106359,"date":"2015-03-09T13:23:10","date_gmt":"2015-03-09T12:23:10","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/medioambiente\/?p=106359"},"modified":"2015-03-09T13:23:10","modified_gmt":"2015-03-09T12:23:10","slug":"por-que-se-inundan-las-riberas-de-los-rios","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359","title":{"rendered":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos?"},"content":{"rendered":"<p>Las cuencas de los r\u00edos est\u00e1n formadas por un n\u00famero considerable de valles que abocan todos al valle principal.<\/p>\n<p>Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo.<\/p>\n<p>Si llueve fuertemente, de manera torrencial, los suelos no pueden empapar el agua si en las laderas no hay \u00e1rboles. Si las laderas de los valles est\u00e1n cubiertas de bosques, el agua se frena al chocar con las hojas, o incluso con las ramas, y se retiene en las ra\u00edces, de manera que tambi\u00e9n empapa el suelo.<\/p>\n<p>Pero hay situaciones en las que hay escaso arbolado, o el suelo est\u00e1 helado: las lluvias intensas de finales del invierno sin posibilidad de empape por el suelo.\u00a0 Si al mismo tiempo se produce un deshielo brusco por elevaci\u00f3n de la temperatura en zonas donde la nieve no ha sido apelmazada, se genera una muy considerable cantidad de agua que no entra en el subsuelo y fluye hacia los valles.<\/p>\n<p>Los c\u00e1lculos son sencillos: Con lluvias mantenidas que produzcan una precipitaci\u00f3n de 25 litros por metro cuadrado y d\u00eda, en una cuenca de un peque\u00f1o arroyo de 10 x 15 km, tenemos 150 km2, es decir 150 millones de metros cuadrados que por 25 litros suponen 3.75 millones de metros c\u00fabicos, o 3.75 hect\u00f3metros c\u00fabicos. Esto es agua que cae en 24 horas. Dividiendo los metros c\u00fabicos por los segundos en un d\u00eda tenemos 43,4 metros c\u00fabicos o 43.400 litros por segundo en el extremo del valle de ese arroyo.\u00a0 Si pensamos en 10 valles por afluente del r\u00edo y 5 afluentes, tenemos 50 descargas de 43.4 m3\/s es decir, 2160 m3\/s.<\/p>\n<p>Un cauce de un r\u00edo de 100 metros de anchura y 5 de profundidad fuerza al ese caudal de agua a moverse a 4.32 m\/s o 15 km\/h, y los baj\u00edos, las islas y los obst\u00e1culos en un cauce mal conservado producen frenazos en el agua que se acumula, supera las barreras de las orillas y desborda el cauce.<\/p>\n<p>En el Ebro las riadas se producen entre Noviembre y Junio, con la mayor frecuencia en Junio. \u00a0En invierno las descargas son fuertes, pero sobre todo el suelo no empapa el agua de la lluvia y se a\u00f1ade a esto el deshielo de las zonas de mediana altura. En Junio tenemos el deshielo de los neveros de altura generalmente estimulado por lluvias torrenciales derivadas de meandros fuertes del chorro polar.<\/p>\n<p>Como en todas las cuestiones de medio ambiente, los fen\u00f3menos naturales se ven modificados por la acci\u00f3n humana. \u00a0Lo razonable en r\u00edos propensos a crecidas es construir diques permanentes en piedra u hormig\u00f3n, en los bordes del cauce, en las zonas de inter\u00e9s econ\u00f3mico.\u00a0 Esos diques deben tener en cuenta el m\u00e1ximo caudal medido en las series hist\u00f3ricas de cada punto del r\u00edo y deben dise\u00f1arse con un factor generoso de incertidumbre. As\u00ed, si el m\u00e1ximo caudal medido en las series hist\u00f3ricas de la localidad de Zaragoza ha sido de 3000 m3\/s, y se quiere mantener una anchura de 100 metros entre las orillas, con puentes colgantes para eliminar los estrechamientos del cauce, se deben dise\u00f1ar diques para 4000 m3\/s lo que significa, con una profundidad uniforme de 10 metros, una velocidad m\u00e1xima de 4 m\/s, que no es peligrosa.<\/p>\n<p>Pero como con los bosques, si estos est\u00e1n cuidados, sin sotobosque, sin ramas secas por los suelos, los incendios forestales no se producen, de la misma manera en un r\u00edo canalizado el agua no desborda si se mantienen los par\u00e1metros del dise\u00f1o. Si por el contrario se deja de dragar el canal, se permiten en el cauce los obst\u00e1culos, se descuida el mantenimiento de las paredes, el canal deja de funcionar y se repiten las inundaciones.<\/p>\n<p>Mantener el medio ambiente supone destinar al mismo una cierta cantidad de la riqueza de los ciudadanos. Es un destino de va y viene, pues la riqueza empleada consiste, en su mayor\u00eda, en salarios de los trabajadores que mantienen en buen estado ese medio ambiente: Es un flujo de riqueza y no una disipaci\u00f3n, con el a\u00f1adido de prevenir la disipaci\u00f3n real de riqueza que se produce en las cat\u00e1strofes.<\/p>\n<p>Pero es una opci\u00f3n. Uno puede aceptar vivir en casas ennegrecidas por el humo, con los cristales rotos y los s\u00f3tanos inundados. Se puede vivir as\u00ed, y destinar la riqueza\u00a0que se tenga (reducida, pues en ese tipo de hogares no se genera mucho de ella)\u00a0 a botell\u00f3n, fiestas, coches oficiales y sueldos de par\u00e1sitos.<\/p>\n<p>O se puede mantener la casa en perfecto estado, eliminar la disipaci\u00f3n, y al mismo tiempo producir riqueza.<\/p>\n<p>Es perfectamente posible controlar las cat\u00e1strofes naturales, y esta posibilidad elimina la disipaci\u00f3n de riqueza y si se hace bien, aumenta la producci\u00f3n de la misma.<\/p>\n<p>Pero es una decisi\u00f3n voluntaria.<\/p>\n<p>Se puede elegir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las cuencas de los r\u00edos est\u00e1n formadas por un n\u00famero considerable de valles que abocan todos al valle principal. Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo. Si llueve fuertemente, de manera torrencial, los suelos no pueden empapar el agua si en las laderas no hay \u00e1rboles. Si las laderas de los valles est\u00e1n cubiertas de bosques, el agua se frena al chocar con las hojas, o incluso con las ramas, y se retiene en las ra\u00edces, de\u2026<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las cuencas de los r\u00edos est\u00e1n formadas por un n\u00famero considerable de valles que abocan todos al valle principal. Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo. Si llueve fuertemente, de manera torrencial,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Ruiz de Elvira\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Medio Ambiente y Ciencia -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos? - Medio Ambiente y Ciencia\" \/>\n\t\t<meta property=\"og:description\" content=\"Las cuencas de los r\u00edos est\u00e1n formadas por un n\u00famero considerable de valles que abocan todos al valle principal. Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo. Si llueve fuertemente, de manera torrencial,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-03-09T12:23:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-03-09T12:23:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos? - Medio Ambiente y Ciencia\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las cuencas de los r\u00edos est\u00e1n formadas por un n\u00famero considerable de valles que abocan todos al valle principal. Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo. Si llueve fuertemente, de manera torrencial,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#blogposting\",\"name\":\"\\u00bfPor qu\\u00e9 se inundan las riberas de los r\\u00edos? - Medio Ambiente y Ciencia\",\"headline\":\"\\u00bfPor qu\\u00e9 se inundan las riberas de los r\\u00edos?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/author\\\/medioambiente#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#articleImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cbedec93ecb29aafe4331e5085f005b0?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio Ruiz de Elvira\"},\"datePublished\":\"2015-03-09T13:23:10+01:00\",\"dateModified\":\"2015-03-09T13:23:10+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#listItem\",\"name\":\"\\u00bfPor qu\\u00e9 se inundan las riberas de los r\\u00edos?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#listItem\",\"position\":3,\"name\":\"\\u00bfPor qu\\u00e9 se inundan las riberas de los r\\u00edos?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/author\\\/medioambiente#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/author\\\/medioambiente\",\"name\":\"Antonio Ruiz de Elvira\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cbedec93ecb29aafe4331e5085f005b0?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Antonio Ruiz de Elvira\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359\",\"name\":\"\\u00bfPor qu\\u00e9 se inundan las riberas de los r\\u00edos? - Medio Ambiente y Ciencia\",\"description\":\"Las cuencas de los r\\u00edos est\\u00e1n formadas por un n\\u00famero considerable de valles que abocan todos al valle principal. Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo. Si llueve fuertemente, de manera torrencial,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/2015\\\/03\\\/09\\\/106359#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/author\\\/medioambiente#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/author\\\/medioambiente#author\"},\"datePublished\":\"2015-03-09T13:23:10+01:00\",\"dateModified\":\"2015-03-09T13:23:10+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/\",\"name\":\"Medio Ambiente y Ciencia\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/medioambiente\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos? - Medio Ambiente y Ciencia","description":"Las cuencas de los r\u00edos est\u00e1n formadas por un n\u00famero considerable de valles que abocan todos al valle principal. Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo. Si llueve fuertemente, de manera torrencial,","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#blogposting","name":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos? - Medio Ambiente y Ciencia","headline":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/author\/medioambiente#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/#person"},"image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#articleImage","url":"https:\/\/secure.gravatar.com\/avatar\/cbedec93ecb29aafe4331e5085f005b0?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio Ruiz de Elvira"},"datePublished":"2015-03-09T13:23:10+01:00","dateModified":"2015-03-09T13:23:10+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/medioambiente","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#listItem","name":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#listItem","position":3,"name":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/author\/medioambiente#author","url":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/author\/medioambiente","name":"Antonio Ruiz de Elvira","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/cbedec93ecb29aafe4331e5085f005b0?s=96&d=mm&r=g","width":96,"height":96,"caption":"Antonio Ruiz de Elvira"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359","name":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos? - Medio Ambiente y Ciencia","description":"Las cuencas de los r\u00edos est\u00e1n formadas por un n\u00famero considerable de valles que abocan todos al valle principal. Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo. Si llueve fuertemente, de manera torrencial,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/author\/medioambiente#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/author\/medioambiente#author"},"datePublished":"2015-03-09T13:23:10+01:00","dateModified":"2015-03-09T13:23:10+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/","name":"Medio Ambiente y Ciencia","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/#person"}}]},"og:locale":"es_ES","og:site_name":"Medio Ambiente y Ciencia -","og:type":"article","og:title":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos? - Medio Ambiente y Ciencia","og:description":"Las cuencas de los r\u00edos est\u00e1n formadas por un n\u00famero considerable de valles que abocan todos al valle principal. Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo. Si llueve fuertemente, de manera torrencial,","og:url":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359","og:image":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/files\/2022\/02\/logo.png","article:published_time":"2015-03-09T12:23:10+00:00","article:modified_time":"2015-03-09T12:23:10+00:00","twitter:card":"summary","twitter:title":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos? - Medio Ambiente y Ciencia","twitter:description":"Las cuencas de los r\u00edos est\u00e1n formadas por un n\u00famero considerable de valles que abocan todos al valle principal. Mientras llueve de forma suave, los suelos empapan el agua, que unas semanas despu\u00e9s empieza a percolar por el subsuelo hacia los cursos fluviales. El proceso es lento, ordenado, tranquilo. Si llueve fuertemente, de manera torrencial,","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"106359","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 11:20:38","updated":"2026-05-26 12:54:36","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/medioambiente\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/medioambiente"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/category\/general"},{"label":"\u00bfPor qu\u00e9 se inundan las riberas de los r\u00edos?","link":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/2015\/03\/09\/106359"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/posts\/106359"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/comments?post=106359"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/posts\/106359\/revisions"}],"predecessor-version":[{"id":106363,"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/posts\/106359\/revisions\/106363"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/media?parent=106359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/categories?post=106359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/medioambiente\/wp-json\/wp\/v2\/tags?post=106359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}