{"id":110445,"date":"2008-12-31T11:29:00","date_gmt":"2008-12-31T11:29:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/microbiologia\/archive\/2008\/12\/31\/110445.aspx"},"modified":"2010-01-27T00:12:50","modified_gmt":"2010-01-26T23:12:50","slug":"la-venganza-de-los-sith-%c2%bflograremos-tener-nuevos-antibioticos-a-tiempo-episodio-iii","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445","title":{"rendered":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III)"},"content":{"rendered":"<div>autor: <a href=\"http:\/\/www.madrimasd.org\/cienciaysociedad\/entrevistas\/quien-es-quien\/detalleGrupo.asp?id=103\">Miguel Vicente<\/a><strong> <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Mientras las bacterias pat\u00f3genas han adquirido m\u00e1s resistencias a los antibi\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \u00edndole que entra\u00f1a el descubrimiento de nuevos antibi\u00f3ticos, lleva a que muchos cient\u00edficos planteemos si en el pr\u00f3ximo futuro estaremos inermes frente a las infecciones.<br \/>\n<\/strong><\/p>\n<hr size=\"2\" \/><span style=\"color: #008000;\"><strong><img decoding=\"async\" src=\"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/910\/o_StarWarsEpisodeIII_1.jpg\" alt=\"\" width=\"450\" height=\"289\" \/><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\"><strong>La cara oculta de las bacterias pat\u00f3genas. <\/strong>A mediados del siglo XX la inmensa mayor\u00eda de las infecciones causadas por bacterias se pod\u00edan curar con los antibi\u00f3ticos reci\u00e9n descubiertos, como la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Penicilina\">penicilina<\/a> y la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Estreptomicina\">estreptomicina<\/a>. Paulatinamente, tanto por la extensi\u00f3n en el uso de estos antibi\u00f3ticos de primera generaci\u00f3n, como por el abuso y el mal uso de ellos, las bacterias infecciosas se hicieron resistentes a ellos y a los derivados semisint\u00e9ticos, dise\u00f1ados para superar las resistencias. La evoluci\u00f3n del ingenuo joven Anakin Skywalker hasta el malvado Darth Vader en el Episodio III de <em>Star Wars <\/em>es lenta pero imparable, como lo son la aparici\u00f3n de cepas resistentes entre las bacterias pat\u00f3genas.<\/span><\/p>\n<hr size=\"2\" \/><\/div>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong><span style=\"color: #008000;\"><span style=\"color: #000000;\">\u00bfPor qu\u00e9 cada vez se encuentran menos antibi\u00f3ticos nuevos?<\/span><\/span><\/strong><br \/>\n<span style=\"color: #008000;\"><span style=\"color: #000000;\">Cuando se empezaron a usar, en la segunda mitad del siglo XX, se consider\u00f3 a los antibi\u00f3ticos como la bala m\u00e1gica que nos libraba de las plagas y enfermedades infecciosas producidas por diversa bacterias y que, a lo largo de la Historia, hab\u00edan sido el azote de la humanidad. Pero tan solo cincuenta a\u00f1os despu\u00e9s de su descubrimiento se observ\u00f3 que los antibi\u00f3ticos iban siendo cada vez <a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/05\/15\/91941.aspx\">menos eficaces<\/a>.<br \/>\nLos primeros antibi\u00f3ticos se encontraron en experimentos intensivos y como fruto de afortunadas coincidencias bien aprovechadas por investigadores muy preparados como <a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/03\/09\/86219.aspx\">Alexander Fleming<\/a> (penicilina), <a href=\"http:\/\/nobelprize.org\/nobel_prizes\/medicine\/laureates\/1952\/waksman-bio.html\">Selman Waksman<\/a> (estreptomicina) y <a href=\"http:\/\/pacs.unica.it\/brotzu\/\">Giuseppe Brotzu <\/a>(<a href=\"http:\/\/es.wikipedia.org\/wiki\/Cefalosporina\">cefalosporina<\/a>), los tres empleados en instituciones p\u00fablicas de investigaci\u00f3n. <\/span><\/span><br \/>\n<span style=\"color: #008000;\"><span style=\"color: #000000;\">Los beneficios generados por su uso como medicamentos fueron un acicate para que la industria farmac\u00e9utica desarrollase extensos programas de ensayo para seleccionar nuevos antibi\u00f3ticos partiendo de muy variadas colecciones de extractos obtenidos de numerosas muestras procedentes de ambientes muy diversos. As\u00ed se podr\u00eda decir que ya poco queda sobre la faz de la tierra y en las profundidades del mar que no haya sido analizado para intentar encontrar nuevas medicinas.<\/span><\/span><span style=\"color: #008000;\"><span style=\"color: #000000;\"> El resultado es que es cada vez dif\u00edcil encontrar nuevos antibi\u00f3ticos mediante\u00a0 coincidencias afortunadas, la inmensa mayor\u00eda, si no todos los antibi\u00f3ticos f\u00e1ciles de encontrar ya est\u00e1n en uso.<\/span><\/span><\/p>\n<p><strong><span style=\"color: #008000;\"><span style=\"color: #000000;\">\u00bfCu\u00e1nto cuesta descubrir un antibi\u00f3tico?<\/span><\/span><\/strong><br \/>\n<span style=\"color: #008000;\"><span style=\"color: #000000;\">Conseguir un nuevo antibi\u00f3tico, considerando poco probable que alguno pueda todav\u00eda encontrarse por casualidad, va a necesitar un esfuerzo considerable, por lo que los recursos intelectuales y econ\u00f3micos a invertir son cada vez mayores. En l\u00edneas generales la industria farmac\u00e9utica estima que se necesita invertir unos 900 millones de d\u00f3lares (al cambio actual unos 650 millones de euros) para que un nuevo compuesto pase de ser una idea a convertirse en una medicina. <\/span><\/span><br \/>\n<span style=\"color: #008000;\"><span style=\"color: #000000;\">Desde el campo de la investigaci\u00f3n se proponen numerosas ideas muy razonables para encontrar nuevos antibi\u00f3ticos, aqu\u00ed voy a comentar dos y en concreto me referir\u00e9 a prote\u00ednas que participan en la proliferaci\u00f3n de las bacterias, sin las que no pueden sobrevivir. Por un lado se pueden buscar nuevos compuestos para inhibir la actividad de una de ellas. La dificultad no es s\u00f3lo encontrar un compuesto que la inactive, sino que adem\u00e1s debe ser inocuo para nuestras c\u00e9lulas. Por ejemplo la prote\u00edna FtsZ es imprescindible para la proliferaci\u00f3n de la mayor\u00eda de las bacterias, pero como ya se coment\u00f3 en otro art\u00edculo, es hom\u00f3loga de la Tubulina y tiene una actividad bioqu\u00edmica similar. Si el inhibidor que se encontrase no fuese por completo selectivo, en vez de un antibi\u00f3tico se conseguir\u00eda un veneno. Por fortuna esto no tiene por qu\u00e9 ser as\u00ed y se ha podido encontrar un nuevo <a href=\"http:\/\/www.ncbi.nlm.nih.gov\/sites\/entrez?orig_db=PubMed&amp;db=pubmed&amp;cmd=Search&amp;term=%22Science%20%28New%20York%2C%20N.Y.%29%22%5BJour%5D%20AND%202008%5Bpdat%5D%20AND%20Errington%20J%5Bauthor%5D\">compuesto<\/a> que puede matar a <em>Staphylococcus<\/em> pero no es da\u00f1ino para las c\u00e9lulas de animales. Este nuevo compuesto no es, sin embargo, activo frente a las bacterias Gram-negativas, que son un peligro cada d\u00eda mayor en las infecciones hospitalarias.<\/span><\/span><\/p>\n<hr size=\"2\" \/><img decoding=\"async\" src=\"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/910\/o_FtsZ_tubulin.jpg\" alt=\"\" width=\"367\" height=\"566\" \/><\/p>\n<p><span style=\"color: #008000;\"><strong>La actividad de FtsZ se localiza en el hueco que queda entre dos mol\u00e9culas cuando se encajan una a continuaci\u00f3n de la otra. <\/strong>Este hueco (el espacio entre los dos tonos de color azul) lo ocupa una mol\u00e9cula, el GTP (las barras de color azul, blanco, rojo y amarillo) , que proporciona a FtsZ la energ\u00eda necesaria para realizar su funci\u00f3n. Ese hueco es algo diferente en la Tubulina (en verde), el hom\u00f3logo de FtsZ en nuestras c\u00e9lulas, y esas diferencias pueden utilizarse para obtener inhibidores espec\u00edficos para una o la otra. Esta es la base de parte de las investigaciones que realiza el programa <a href=\"http:\/\/www.cnb.uam.es\/%7Ecombact\/combact\/\">COMBACT<\/a><span style=\"color: #008000;\">.<\/span><\/span><span style=\"color: #008000;\"> <a href=\"http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/11454202?ordinalpos=3&amp;itool=EntrezSystem2.PEntrez.Pubmed.Pubmed_ResultsPanel.Pubmed_DefaultReportPanel.Pubmed_RVDocSum\">Mingorance <em>et al.<\/em> 2001. <em>Mol. Microbiol<\/em>. <strong>41<\/strong>:83-91.<\/a><br \/>\n<\/span><\/p>\n<hr size=\"2\" \/><span style=\"color: #008000;\"><span style=\"color: #000000;\">Otra alternativa posible es bloquear las interacciones entre dos o m\u00e1s prote\u00ednas. Las prote\u00ednas que intervienen en la septaci\u00f3n no act\u00faan de una en una, sino que varias prote\u00ednas de distinto tipo forman un anillo en el centro de la c\u00e9lula, por ejemplo en el <a href=\"http:\/\/www.cnb.uam.es\/%7Emvicente\/buildblocks.html\">anillo de <em>Escherichia coli<\/em><\/a> se ensamblan como m\u00ednimo diez prote\u00ednas diferentes, todas imprescindibles para que el anillo funcione y de cada una se colocan varias copias. Si se consiguiese estorbar la interacci\u00f3n entre una o m\u00e1s de ellas el anillo no funcionar\u00eda. Aunque este camino es de todas maneras m\u00e1s complicado de llevar a buen t\u00e9rmino, puede a la larga tener alguna ventaja importante ya que los compuestos que se dise\u00f1en para bloquear las interacciones pueden construirse de forma que no se asemejen a compuestos presentes en la Naturaleza. Si esto se logra, las posibilidades de que exista un mecanismo natural de resistencia podr\u00eda no ser tan alta.<\/span><\/span><\/p>\n<p><strong><span style=\"color: #008000;\"><span style=\"color: #000000;\">\u00bfPor qu\u00e9 los antibi\u00f3ticos son \u00abmalas\u00bb medicinas?<\/span><\/span><\/strong><br \/>\n<span style=\"color: #008000;\"><span style=\"color: #000000;\">Si lo examinamos desde el punto de vista de su uso y de su venta no es una pregunta, como parece a primera vista, tan sorprendente. A consecuencia de la propagaci\u00f3n de resistencias ya existentes en la Naturaleza los antibi\u00f3ticos, a diferencia de otras medicinas, comienzan a dejar de ser eficaces en el mismo momento en que comienza su uso. Pero a\u00fan peores resultan los antibi\u00f3ticos cuando consideramos sus caracter\u00edsticas como productos de consumo. Como resultado de\u00a0 sus indudables virtudes terap\u00e9uticas el consumidor de antibi\u00f3ticos, el enfermo, solo tiene dos pron\u00f3sticos, o bien se cura y deja de comprarlos, o bien se muere y obviamente tambi\u00e9n deja de usarlos. Las compa\u00f1\u00edas farmac\u00e9uticas estiman que un antibi\u00f3tico genera beneficios anuales cercanos a los 400 millones de euros, frente a los m\u00e1s de mil que se obtienen de la venta de un medicamento de consumo diario, como son por ejemplo los antihipertensivos. <\/span><\/span><br \/>\n<strong><br \/>\n<span style=\"color: #008000;\"><span style=\"color: #000000;\">\u00bfEstamos siendo eficaces para encontrar nuevos antibi\u00f3ticos?<\/span><\/span><\/strong><br \/>\n<span style=\"color: #008000;\"><span style=\"color: #000000;\">Francamente la respuesta no puede ser por ahora positiva. Empezando por el esfuerzo empresarial, las grandes industrias farmac\u00e9uticas surgidas de las fusiones entre empresas tradicionales que se realizaron en la d\u00e9cada que solap\u00f3 los siglos XX y XXI necesitan incentivos que solo se los proporcionan los medicamentos de uso diario y no los antibi\u00f3ticos. En consecuencia el inter\u00e9s de estas grandes empresas para invertir en la\u00a0 investigaci\u00f3n de nuevos antibi\u00f3ticos es decreciente, y ya son pocas las que la mantienen y en todo caso la prioridad que le asignan es baja.<\/span><\/span><br \/>\n<span style=\"color: #008000;\"><span style=\"color: #000000;\">Desde el campo de la investigaci\u00f3n b\u00e1sica, se\u00f1aladas ya alguna de las dificultades que entra\u00f1a encontrar nuevos antibacterianos, ser\u00eda necesario un esfuerzo extenso y sostenido de varios programas de b\u00fasqueda de nuevas estrategias y de nuevos compuestos para bloquear a los pat\u00f3genos. La realidad no es as\u00ed, y esto se ve desde su visibilidad en los medios de comunicaci\u00f3n, que prestan poca atenci\u00f3n a las infecciones bacterianas por creerlas algo del pasado, y por ello poco noticiable, hasta en las prioridades que asignan los organismos que financian la investigaci\u00f3n, que se mueven m\u00e1s por el inter\u00e9s de potenciar al mundo empresarial, cosa l\u00f3gica ya que los gobiernos necesitan se generen nuevos beneficios que ingresen impuestos y creen puestos de trabajo.<\/span><\/span><br \/>\n<span style=\"color: #008000;\"><span style=\"color: #000000;\">Y frente a este panorama poco halag\u00fce\u00f1o nos enfrentamos a que, como ya se coment\u00f3 en el <a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/09\/09\/100531.aspx\">primer episodio<\/a> de esta serie, la probabilidad de fallecer por causa de una infecci\u00f3n de las v\u00edas respiratorias es mayor que la de morir de c\u00e1ncer de pulm\u00f3n o tr\u00e1quea.<\/span><\/span><\/p>\n<hr size=\"2\" \/><img decoding=\"async\" src=\"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/910\/o_Threatofskywalker.jpg\" alt=\"\" width=\"473\" height=\"201\" \/><\/p>\n<p><span style=\"color: #008000;\"><strong>El lado oscuro.<\/strong> La amenaza de las infecciones (<a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/09\/09\/100531.aspx\">EPISODIO I<\/a>) a\u00fan no la percibimos en toda su gravedad porque por ahora se pueden curar en muchos casos. Sin embargo para los casos <a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/07\/04\/96121.aspx\">que no se curan<\/a>, y sobre todo si en el futuro no se logra encontrar nuevos antibi\u00f3ticos no cabe duda de que seg\u00fan las resistencias se vayan extendiendo de un pat\u00f3geno a otro (<a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/12\/25\/110204.aspx\">EPISODIO II<\/a>), el peligro aumentar\u00e1 hasta l\u00edmites que no podemos predecir pero que seguramente no nos gustar\u00eda sufrir.<\/span><\/p>\n<hr size=\"2\" \/><strong><span style=\"color: #a52a2a;\">EN LOS EPISODIOS ANTERIORES<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/09\/09\/100531.aspx\"><strong>EPISODIO I<\/strong><\/a><\/span><br \/>\n<span style=\"color: #a52a2a;\"><strong>La amenaza fantasma: \u00bfPor qu\u00e9 necesitamos nuevos antibi\u00f3ticos?<\/strong><\/span><br \/>\n\u00bfQu\u00e9 es un antibi\u00f3tico?<br \/>\n\u00bfPor qu\u00e9 los antibi\u00f3ticos pierden su eficacia?<\/p>\n<p><span style=\"color: #000000;\"><a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/12\/25\/110204.aspx\"><strong>EPISODIO II<\/strong><\/a><\/span><br \/>\n<span style=\"color: #a52a2a;\"><strong>El ataque de los clones: Expansi\u00f3n de las resistencias<\/strong><\/span><br \/>\n\u00bfPor qu\u00e9 se extienden las resistencias a los antibi\u00f3ticos?<br \/>\n\u00bfQu\u00e9 propiedades ha de tener un antibi\u00f3tico?<br \/>\n\u00bfC\u00f3mo se encuentra un antibi\u00f3tico?<br \/>\n\u00bfPor qu\u00e9 las vacunas no pueden reemplazar a los antibi\u00f3ticos?<\/p>\n<hr size=\"2\" \/><span style=\"color: #a52a2a;\"><strong>REFERENCIA<\/strong><\/span><\/p>\n<p>M. Vicente, J. Hodgson, O. Massidda, T. Tonjum, B. Henriques-Normark, and E. Z. Ron. 2006. The Fallacies of Hope: will we discover new antibiotics to combat pathogenic bacteria in time? <a href=\"http:\/\/www.ncbi.nlm.nih.gov\/sites\/entrez?orig_db=PubMed&amp;db=pubmed&amp;cmd=Search&amp;term=%22FEMS%20microbiology%20reviews%22%5BJour%5D%20AND%20Vicente%20M%5Bauthor%5D\"><em>FEMS Microbiol. Rev.<\/em> <strong>30<\/strong>: 841-852<\/a>.<\/p>\n<hr size=\"2\" \/><span style=\"color: #0000ff;\"><img decoding=\"async\" src=\"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/910\/t_blogdia.jpg\" alt=\"\" \/><br \/>\n<strong><span style=\"color: #000080;\">Foro del d\u00eda 7 de enero de 2009 en <a href=\"http:\/\/www.madridiario.es\/index.html\">madridiario<\/a><\/span><\/strong><br \/>\n<\/span><\/p>\n<hr size=\"2\" \/>\n<hr size=\"2\" \/><\/div>\n<p><span style=\"color: #008000;\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>autor: Miguel Vicente Mientras las bacterias pat\u00f3genas han adquirido m\u00e1s resistencias a los antibi\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \u00edndole que entra\u00f1a el descubrimiento de nuevos antibi\u00f3ticos, lleva a que muchos cient\u00edficos planteemos si en el pr\u00f3ximo futuro estaremos inermes frente a las infecciones. La cara oculta de las bacterias pat\u00f3genas. A mediados del siglo XX la inmensa mayor\u00eda de las infecciones causadas por bacterias se pod\u00edan curar con los antibi\u00f3ticos\u2026<\/p>\n","protected":false},"author":87,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[257,254],"tags":[795,854,859,796,791,863,809],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"autor: Miguel Vicente Mientras las bacterias pat\u00f3genas han adquirido m\u00e1s resistencias a los antibi\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \u00edndole que entra\u00f1a el descubrimiento de nuevos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel Vicente\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"microbichitos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III) - microbichitos\" \/>\n\t\t<meta property=\"og:description\" content=\"autor: Miguel Vicente Mientras las bacterias pat\u00f3genas han adquirido m\u00e1s resistencias a los antibi\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \u00edndole que entra\u00f1a el descubrimiento de nuevos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-12-31T11:29:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-26T23:12:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III) - microbichitos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"autor: Miguel Vicente Mientras las bacterias pat\u00f3genas han adquirido m\u00e1s resistencias a los antibi\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \u00edndole que entra\u00f1a el descubrimiento de nuevos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445#blogposting\",\"name\":\"La venganza de los Sith: \\u00bfLograremos tener nuevos antibi\\u00f3ticos a tiempo? (EPISODIO III) - microbichitos\",\"headline\":\"La venganza de los Sith: \\u00bfLograremos tener nuevos antibi\\u00f3ticos a tiempo? (EPISODIO III)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/microbiologia\\\/wp-content\\\/blogs.dir\\\/110\\\/files\\\/910\\\/o_StarWarsEpisodeIII_1.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445\\\/#articleImage\"},\"datePublished\":\"2008-12-31T11:29:00+01:00\",\"dateModified\":\"2010-01-27T00:12:50+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":9,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445#webpage\"},\"articleSection\":\"Enfermedad, Foro del d\\u00eda en Madridiario, antibi\\u00f3ticos, E. coli, Fleming, FtsZ, infecci\\u00f3n, pat\\u00f3geno, resistencia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/foro-del-dia-en-madridiario#listItem\",\"name\":\"Foro del d\\u00eda en Madridiario\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/foro-del-dia-en-madridiario#listItem\",\"position\":2,\"name\":\"Foro del d\\u00eda en Madridiario\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/foro-del-dia-en-madridiario\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445#listItem\",\"name\":\"La venganza de los Sith: \\u00bfLograremos tener nuevos antibi\\u00f3ticos a tiempo? (EPISODIO III)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445#listItem\",\"position\":3,\"name\":\"La venganza de los Sith: \\u00bfLograremos tener nuevos antibi\\u00f3ticos a tiempo? (EPISODIO III)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/foro-del-dia-en-madridiario#listItem\",\"name\":\"Foro del d\\u00eda en Madridiario\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\",\"name\":\"microbichitos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia\",\"name\":\"Miguel Vicente\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel Vicente\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445\",\"name\":\"La venganza de los Sith: \\u00bfLograremos tener nuevos antibi\\u00f3ticos a tiempo? (EPISODIO III) - microbichitos\",\"description\":\"autor: Miguel Vicente Mientras las bacterias pat\\u00f3genas han adquirido m\\u00e1s resistencias a los antibi\\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \\u00edndole que entra\\u00f1a el descubrimiento de nuevos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2008\\\/12\\\/31\\\/110445#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"datePublished\":\"2008-12-31T11:29:00+01:00\",\"dateModified\":\"2010-01-27T00:12:50+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"name\":\"microbichitos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III) - microbichitos","description":"autor: Miguel Vicente Mientras las bacterias pat\u00f3genas han adquirido m\u00e1s resistencias a los antibi\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \u00edndole que entra\u00f1a el descubrimiento de nuevos","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445#blogposting","name":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III) - microbichitos","headline":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/910\/o_StarWarsEpisodeIII_1.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445\/#articleImage"},"datePublished":"2008-12-31T11:29:00+01:00","dateModified":"2010-01-27T00:12:50+01:00","inLanguage":"es-ES","commentCount":9,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445#webpage"},"articleSection":"Enfermedad, Foro del d\u00eda en Madridiario, antibi\u00f3ticos, E. coli, Fleming, FtsZ, infecci\u00f3n, pat\u00f3geno, resistencia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/foro-del-dia-en-madridiario#listItem","name":"Foro del d\u00eda en Madridiario"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/foro-del-dia-en-madridiario#listItem","position":2,"name":"Foro del d\u00eda en Madridiario","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/foro-del-dia-en-madridiario","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445#listItem","name":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445#listItem","position":3,"name":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/foro-del-dia-en-madridiario#listItem","name":"Foro del d\u00eda en Madridiario"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization","name":"microbichitos","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia","name":"Miguel Vicente","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel Vicente"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445","name":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III) - microbichitos","description":"autor: Miguel Vicente Mientras las bacterias pat\u00f3genas han adquirido m\u00e1s resistencias a los antibi\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \u00edndole que entra\u00f1a el descubrimiento de nuevos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"datePublished":"2008-12-31T11:29:00+01:00","dateModified":"2010-01-27T00:12:50+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","name":"microbichitos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"microbichitos -","og:type":"article","og:title":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III) - microbichitos","og:description":"autor: Miguel Vicente Mientras las bacterias pat\u00f3genas han adquirido m\u00e1s resistencias a los antibi\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \u00edndole que entra\u00f1a el descubrimiento de nuevos","og:url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445","og:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","article:published_time":"2008-12-31T11:29:00+00:00","article:modified_time":"2010-01-26T23:12:50+00:00","twitter:card":"summary","twitter:title":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III) - microbichitos","twitter:description":"autor: Miguel Vicente Mientras las bacterias pat\u00f3genas han adquirido m\u00e1s resistencias a los antibi\u00f3ticos en uso, ha crecido la dificultad para encontrar nuevos antibacterianos que renueven el arsenal terap\u00e9utico con el que se combaten las infecciones. La gravedad del problema, que se complica por las dificultades de diversa \u00edndole que entra\u00f1a el descubrimiento de nuevos","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"110445","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-05 03:38:55","updated":"2026-05-29 23:14:05","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/foro-del-dia-en-madridiario\" title=\"Foro del d\u00eda en Madridiario\">Foro del d\u00eda en Madridiario<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia"},{"label":"Foro del d\u00eda en Madridiario","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/foro-del-dia-en-madridiario"},{"label":"La venganza de los Sith: \u00bfLograremos tener nuevos antibi\u00f3ticos a tiempo? (EPISODIO III)","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2008\/12\/31\/110445"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/110445"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/comments?post=110445"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/110445\/revisions"}],"predecessor-version":[{"id":130576,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/110445\/revisions\/130576"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/media?parent=110445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/categories?post=110445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/tags?post=110445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}