{"id":117104,"date":"2009-04-26T11:15:00","date_gmt":"2009-04-26T11:15:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/microbiologia\/archive\/2009\/04\/26\/117104.aspx"},"modified":"2010-01-26T23:12:57","modified_gmt":"2010-01-26T22:12:57","slug":"deconstruyendo-las-bacterias-nueva-cocina-en-la-microbiologia","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104","title":{"rendered":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda"},"content":{"rendered":"<p>autor: <a href=\"http:\/\/www.madrimasd.org\/cienciaysociedad\/mediateca\/default.asp?mostrar=VIDEO&amp;ciclo=investigadores&amp;videoid=1315&amp;reproducir=si\">Miguel Vicente<\/a><\/p>\n<div><strong>Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\u00eda sint\u00e9tica, en su sentido m\u00e1s estricto, ha permitido <a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/06\/08\/94117.aspx\">reproducir en el tubo de ensayo<\/a> algunas de las funciones de la divisi\u00f3n celular bacteriana partiendo de varios elementos, ves\u00edculas de l\u00edpidos y una forma modificada de la prote\u00edna FtsZ. Sorprendentemente esa FtsZ constri\u00f1e a las ves\u00edculas reproduciendo lo que creemos es una de las etapas iniciales de la divisi\u00f3n. El abordaje contrario, el anal\u00edtico, tambi\u00e9n hace progresos, la deconstrucci\u00f3n de <em>Bacillus subtilis <\/em>priv\u00e1ndole de pared celular, e incluso de FtsZ, demuestra que no solo es posible mantener c\u00e9lulas privadas de pared en estado vivo, sino que en esas condiciones se puede generar descendencia incluso sin que FtsZ\u00a0 participe en la constricci\u00f3n de la membrana. No solo se han producido as\u00ed las llamadas formas L de <em>B. subtilis,<\/em> sino que adem\u00e1s se vislumbra c\u00f3mo se pudo, quiz\u00e1s, realizar la multiplicaci\u00f3n de unos seres vivos ancestrales que pudieran ser los antecesores de las c\u00e9lulas.<\/strong><\/p>\n<hr size=\"2\" \/><img decoding=\"async\" src=\"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/1431\/o_wild_vs_L.jpg\" alt=\"\" width=\"468\" height=\"289\" \/><\/p>\n<p><span style=\"color: #008000;\"><strong>Comparaci\u00f3n de c\u00e9lulas normales de <em>Bacillus subtilis<\/em> a la izaquierda con las respectivas formas L a la derecha.<\/strong><\/span><\/p>\n<hr size=\"2\" \/><\/div>\n<p><!--more--><\/p>\n<div><strong>Las formas L<\/strong> son variantes deformes, redondas o casi, de las bacterias, se conocen desde 1930, son osm\u00f3ticamente inestables porque han perdido la pared celular, la <a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2009\/01\/11\/110986.aspx\">estructura<\/a> que, como se coment\u00f3 en un <a href=\"http:\/\/weblogs.madrimasd.org\/microbiologia\/archive\/2008\/08\/17\/98871.aspx\">art\u00edculo <\/a>anterior, impide que la membrana estalle por la presi\u00f3n de turgor del concentrado citoplasma bacteriano. Las formas L no sobreviven en ambientes no protegidos, pero se pueden encontrar en sitios rec\u00f3nditos del cuerpo en donde permanecen a veces como bombas de relojer\u00eda dispuestas a desencadenar una infecci\u00f3n a la mas m\u00ednima provocaci\u00f3n. Las formas L son dif\u00edciles de erradicar, ya que al carecer de peptidoglicano no son muy susceptibles a antibi\u00f3ticos como la penicilina, cuya eficacia se basa precisamente en bloquear la s\u00edntesis de esta macromol\u00e9cula. Hay adem\u00e1s pat\u00f3genos como los <em>Mycoplasma<\/em> que viven en el interior de las c\u00e9lulas a las que parasitan, y que no tienen peptidoglicano, por no tener no tienen casi ninguno de los genes del grupo <em>dcw,<\/em> que en otras bacterias alberga gran parte de los genes necesarios para la divisi\u00f3n y la s\u00edntesis de la pared.<\/p>\n<p>Un <a href=\"http:\/\/www.nature.com\/nature\/journal\/v457\/n7231\/abs\/nature07742.html\">grupo<\/a> de investigadores de la <a href=\"http:\/\/www.ncl.ac.uk\/camb\/\">Universidad de Newcastle<\/a> ha logrado producir formas L de <em>B. subtilis<\/em> y al observarlas se ha encontrado con alguna sorpresa, estos engendros no solo pueden crecer, incluso se multiplican y lo hacen sin recurrir a los mecanismos que las bacterias normales utilizan. Se construyeron formas L de <em>B. subtilis<\/em> conteniendo una fusi\u00f3n de FtsZ con la prote\u00edna fluorescente de medusa (la GFP) y se observ\u00f3 que aunque se llegaban a formaban arcos fluorescentes, nunca llegaban a completar un anillo, la estructura de FtsZ que interviene en la divisi\u00f3n bacteriana. El paso siguiente fue construir una estirpe en la que se puede forzar la p\u00e9rdida del gen <em>ftsZ<\/em> en determinadas condiciones. Lo sorprendente fue encontrar que esas formas L no solo crec\u00edan, sino que pod\u00edan proliferar.<\/p>\n<hr size=\"2\" \/><img decoding=\"async\" src=\"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/1431\/o_Lform_division.jpg\" alt=\"\" width=\"467\" height=\"189\" \/><\/p>\n<p><span style=\"color: #008000;\"><strong>Secuencia de im\u00e1genes en las que se observa la partici\u00f3n de formas L de <em>Bacillus subtili<\/em>s.<\/strong><\/span><\/p>\n<hr size=\"2\" \/><strong>Hace poco m\u00e1s de un a\u00f1o<\/strong> <a href=\"http:\/\/jb.asm.org\/cgi\/content\/abstract\/189\/18\/6512\">autores de Francia y Espa\u00f1a<\/a> publicaron que algo parecido a las formas L se pod\u00eda obtener a partir de <em>Escherichia col<\/em>i, pero en este caso su multiplicaci\u00f3n depend\u00eda de una cantidad residual, un 7%, de peptidpoglicano, ya que la inhibici\u00f3n de la prote\u00edna PBP3, que sintetiza el peptidoglicano del septo bloquea por completo su divisi\u00f3n. \u00bfA qu\u00e9 se puede deber esta discrepancia? En primer lugar a que la receta para producir las formas L usada por los dos grupos es diferente, en el caso de <em>Bacillus<\/em> se obtienen bloqueando por completo la s\u00edntesis del peptidoglicano sustituyendo la expresi\u00f3n natural del oper\u00f3n <em>murE<\/em>, que contiene genes para codificar varias enzimas necesarias para sintetizar sus precursores, y haciendo que se puedan dejar de transcribir a voluntad, y a la vez bloqueando la s\u00edntesis del precursor bactoprenol. Por el contrario lo que se hizo en <em>E. coli <\/em>fue bloquear la producci\u00f3n de peptidoglicano a\u00f1adiendo cefsulodina, un antibi\u00f3tico que bloquea dos de las enzimas, las llamadas PBPs 1A y 1B, que intervienen en el ensamblaje de los precursores del petidoglicano. Pero tambi\u00e9n debe tenerse en cuenta que nos encontramos ante dos tipos de bacteria muy diferentes con respecto a la composici\u00f3n de su pared, <em>Bacillus<\/em> es una Gram-positiva, con una pared m\u00e1s sencilla compuesta por una membrana \u00fanica rodeada de una gruesa capa de peptidoglicano. <em>E. coli<\/em> por su parte es una Gram-negativa, con dos membranas entre las que hay una capa delgada de peptidoglicano.<\/p>\n<p><strong>Nos quedan algunos interrogantes<\/strong>, uno es c\u00f3mo se la arreglan las formas L de <em>Bacillus<\/em> para efectuar la constricci\u00f3n de su membrana. Los autores brit\u00e1nicos piensan que quiz\u00e1s intervengan otras mol\u00e9culas del citoesqueleto bacteriano, como MreB, hom\u00f3loga de la Actina, y que el proceso pueda funcionar de forma parecida a la emisi\u00f3n de seud\u00f3podos. \u00bfEra este un mecanismo de divisi\u00f3n en los ancestros de las bacterias?<\/p>\n<hr size=\"2\" \/><span style=\"color: #a52a2a;\"><strong>REFERENCIAS<\/strong><\/span><br \/>\nM. Leaver, P. Dom\u00ednguez-Cuevas, J. M. Coxhead, R. A. Daniel and J. Errington. 2009. Life without a wall or division machine in <em>Bacillus subtilis<\/em>. <a href=\"http:\/\/www.nature.com\/nature\/journal\/v457\/n7231\/abs\/nature07742.html\"><em>Nature<\/em> <strong>457<\/strong>: 849-853<\/a>.<\/p>\n<p>D. Joseleau-Petit, JC. Li\u00e9bart, JA. Ayala, and R. D\u2019Ari. 2007. Unstable <em>Escherichia coli<\/em> L-forms revisited: growth requires peptidoglycan synthesis. <a href=\"http:\/\/jb.asm.org\/cgi\/content\/abstract\/189\/18\/6512\"><em>J Bacteriol<\/em> <strong>189<\/strong>: 6512\u20136520<\/a>.<\/p>\n<hr size=\"2\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>autor: Miguel Vicente Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\u00eda sint\u00e9tica, en su sentido m\u00e1s estricto, ha permitido reproducir en el tubo de ensayo algunas de las funciones de la divisi\u00f3n celular bacteriana partiendo de varios elementos, ves\u00edculas de l\u00edpidos y una forma modificada de la prote\u00edna FtsZ. Sorprendentemente esa FtsZ constri\u00f1e a las ves\u00edculas reproduciendo lo que creemos es una de las etapas iniciales de la divisi\u00f3n. El abordaje contrario, el anal\u00edtico, tambi\u00e9n hace progresos, la deconstrucci\u00f3n de\u2026<\/p>\n","protected":false},"author":87,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[250,247],"tags":[801,854,796],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"autor: Miguel Vicente Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\u00eda sint\u00e9tica, en su sentido m\u00e1s estricto, ha permitido reproducir en el tubo de ensayo algunas de las funciones de la divisi\u00f3n celular bacteriana partiendo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel Vicente\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"microbichitos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda - microbichitos\" \/>\n\t\t<meta property=\"og:description\" content=\"autor: Miguel Vicente Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\u00eda sint\u00e9tica, en su sentido m\u00e1s estricto, ha permitido reproducir en el tubo de ensayo algunas de las funciones de la divisi\u00f3n celular bacteriana partiendo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2009-04-26T11:15:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-26T22:12:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda - microbichitos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"autor: Miguel Vicente Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\u00eda sint\u00e9tica, en su sentido m\u00e1s estricto, ha permitido reproducir en el tubo de ensayo algunas de las funciones de la divisi\u00f3n celular bacteriana partiendo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104#blogposting\",\"name\":\"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\\u00eda - microbichitos\",\"headline\":\"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\\u00eda\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/microbiologia\\\/wp-content\\\/blogs.dir\\\/110\\\/files\\\/1431\\\/o_wild_vs_L.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104\\\/#articleImage\"},\"datePublished\":\"2009-04-26T11:15:00+01:00\",\"dateModified\":\"2010-01-26T23:12:57+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104#webpage\"},\"articleSection\":\"Maravillas del micromundo, Trabajo cient\\u00edfico, Bacillus, E. coli, FtsZ\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/trabajo-cientifico#listItem\",\"name\":\"Trabajo cient\\u00edfico\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/trabajo-cientifico#listItem\",\"position\":2,\"name\":\"Trabajo cient\\u00edfico\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/trabajo-cientifico\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104#listItem\",\"name\":\"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\\u00eda\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104#listItem\",\"position\":3,\"name\":\"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\\u00eda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/trabajo-cientifico#listItem\",\"name\":\"Trabajo cient\\u00edfico\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\",\"name\":\"microbichitos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia\",\"name\":\"Miguel Vicente\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel Vicente\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104\",\"name\":\"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\\u00eda - microbichitos\",\"description\":\"autor: Miguel Vicente Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\\u00eda sint\\u00e9tica, en su sentido m\\u00e1s estricto, ha permitido reproducir en el tubo de ensayo algunas de las funciones de la divisi\\u00f3n celular bacteriana partiendo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2009\\\/04\\\/26\\\/117104#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"datePublished\":\"2009-04-26T11:15:00+01:00\",\"dateModified\":\"2010-01-26T23:12:57+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"name\":\"microbichitos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda - microbichitos","description":"autor: Miguel Vicente Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\u00eda sint\u00e9tica, en su sentido m\u00e1s estricto, ha permitido reproducir en el tubo de ensayo algunas de las funciones de la divisi\u00f3n celular bacteriana partiendo","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104#blogposting","name":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda - microbichitos","headline":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/1431\/o_wild_vs_L.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104\/#articleImage"},"datePublished":"2009-04-26T11:15:00+01:00","dateModified":"2010-01-26T23:12:57+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104#webpage"},"articleSection":"Maravillas del micromundo, Trabajo cient\u00edfico, Bacillus, E. coli, FtsZ"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/trabajo-cientifico#listItem","name":"Trabajo cient\u00edfico"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/trabajo-cientifico#listItem","position":2,"name":"Trabajo cient\u00edfico","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/trabajo-cientifico","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104#listItem","name":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104#listItem","position":3,"name":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/trabajo-cientifico#listItem","name":"Trabajo cient\u00edfico"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization","name":"microbichitos","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia","name":"Miguel Vicente","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel Vicente"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104","name":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda - microbichitos","description":"autor: Miguel Vicente Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\u00eda sint\u00e9tica, en su sentido m\u00e1s estricto, ha permitido reproducir en el tubo de ensayo algunas de las funciones de la divisi\u00f3n celular bacteriana partiendo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"datePublished":"2009-04-26T11:15:00+01:00","dateModified":"2010-01-26T23:12:57+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","name":"microbichitos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"microbichitos -","og:type":"article","og:title":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda - microbichitos","og:description":"autor: Miguel Vicente Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\u00eda sint\u00e9tica, en su sentido m\u00e1s estricto, ha permitido reproducir en el tubo de ensayo algunas de las funciones de la divisi\u00f3n celular bacteriana partiendo","og:url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104","og:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","article:published_time":"2009-04-26T11:15:00+00:00","article:modified_time":"2010-01-26T22:12:57+00:00","twitter:card":"summary","twitter:title":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda - microbichitos","twitter:description":"autor: Miguel Vicente Vivimos unos tiempos en los que diversas, y a veces opuestas, formas de abordar la experimentaci\u00f3n coexisten en el estudio de los microbios. Por un lado la biolog\u00eda sint\u00e9tica, en su sentido m\u00e1s estricto, ha permitido reproducir en el tubo de ensayo algunas de las funciones de la divisi\u00f3n celular bacteriana partiendo","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"117104","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 01:48:00","updated":"2026-05-29 23:15:44","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/trabajo-cientifico\" title=\"Trabajo cient\u00edfico\">Trabajo cient\u00edfico<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDeconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia"},{"label":"Trabajo cient\u00edfico","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/trabajo-cientifico"},{"label":"Deconstruyendo las bacterias: nueva cocina en la Microbiolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2009\/04\/26\/117104"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/117104"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/comments?post=117104"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/117104\/revisions"}],"predecessor-version":[{"id":130531,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/117104\/revisions\/130531"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/media?parent=117104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/categories?post=117104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/tags?post=117104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}