{"id":131266,"date":"2011-02-20T20:41:36","date_gmt":"2011-02-20T19:41:36","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/microbiologia\/?p=131266"},"modified":"2011-02-20T20:52:55","modified_gmt":"2011-02-20T19:52:55","slug":"conversacion-sobre-la-sintesis-de-un-genoma","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266","title":{"rendered":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma"},"content":{"rendered":"<p>autor: <a href=\"http:\/\/www.madrimasd.org\/cienciaysociedad\/mediateca\/default.asp?videoID=1315\">Miguel Vicente<\/a><\/p>\n<p style=\"text-align: justify\"><strong><\/p>\n<p>El  viernes 4 de febrero de 2011 el programa \u201c<a href=\"http:\/\/www.rtve.es\/radio\/20090825\/futuro-abierto\/290040.shtml\">Futuro Abierto<\/a>\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\u00f3n, nos reuni\u00f3 a cuatro cient\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \u201cvida artificial\u201d. Los tertulianos fueron Jes\u00fas del Mazo, del <a href=\"http:\/\/www.cib.csic.es\/es\/\">Centro de Investigaciones Biol\u00f3gicas<\/a> del CSIC, C\u00e9sar Nombela de la <a href=\"http:\/\/www.ucm.es\/pags.php?tp=Facultades&amp;a=centros&amp;d=entidad-14.php\">Facultad de Farmacia<\/a> de la Univeridad Complutense, Luis Serrano del <a href=\"http:\/\/pasteur.crg.es\/portal\/page\/portal\/Internet\/\">Centro de Regulaci\u00f3n Gen\u00f3mica<\/a> de Barcelona y Miguel Vicente del <a href=\"http:\/\/www.cnb.csic.es\/\">Centro Nacional de Biotecnolog\u00eda<\/a> del CSIC.<!--more--><\/strong><\/p>\n<p>En la conversaci\u00f3n se trataron diversos aspectos relacionados con la s\u00edntesis del genoma de una bacteria y su introducci\u00f3n en otra, lo que se suele llamar \u201c<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2010\/05\/23\/130908\">experimento de Venter<\/a>\u201d que ya se ha descrito en este foro. Entre ellos se dedic\u00f3 bastante tiempo a debatir sobre las implicaciones \u00e9ticas del trabajo.<\/p>\n<p>El programa completo se puede encontrar en la p\u00e1gina de \u201cFuturo Abierto\u201d emitido el domingo 13 de febrero.<\/p>\n<p style=\"font:bold 23px\/24px arial, sans-serif;letter-spacing:-0.5px;color:#333333;margin:4px 0 5px\"><a href=\"http:\/\/www.rtve.es\/mediateca\/audios\/20110213\/futuro-abierto---vida-artificial-realidad-ficcion---13-02-11\/1007302.shtml\">Futuro abierto &#8211; Vida artificial, \u00bfrealidad o ficci\u00f3n? &#8211; 13\/02\/11<\/a><\/p>\n<p><code><\/code><code><\/p>\n","protected":false},"excerpt":{"rendered":"<p>autor: Miguel Vicente El viernes 4 de febrero de 2011 el programa \u201cFuturo Abierto\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\u00f3n, nos reuni\u00f3 a cuatro cient\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \u201cvida artificial\u201d. Los tertulianos fueron Jes\u00fas del Mazo, del Centro de Investigaciones Biol\u00f3gicas del CSIC, C\u00e9sar Nombela de la Facultad de Farmacia de la Univeridad Complutense, Luis Serrano del Centro de Regulaci\u00f3n Gen\u00f3mica de Barcelona y Miguel Vicente del Centro Nacional de Biotecnolog\u00eda del CSIC.<\/p>\n","protected":false},"author":87,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[256,252],"tags":[862,2353,46171],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"autor: Miguel Vicente El viernes 4 de febrero de 2011 el programa \u201cFuturo Abierto\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\u00f3n, nos reuni\u00f3 a cuatro cient\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \u201cvida artificial\u201d. Los tertulianos fueron Jes\u00fas del Mazo, del Centro de Investigaciones Biol\u00f3gicas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel Vicente\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"microbichitos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Conversaci\u00f3n sobre la s\u00edntesis de un genoma - microbichitos\" \/>\n\t\t<meta property=\"og:description\" content=\"autor: Miguel Vicente El viernes 4 de febrero de 2011 el programa \u201cFuturo Abierto\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\u00f3n, nos reuni\u00f3 a cuatro cient\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \u201cvida artificial\u201d. Los tertulianos fueron Jes\u00fas del Mazo, del Centro de Investigaciones Biol\u00f3gicas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-02-20T19:41:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-02-20T19:52:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Conversaci\u00f3n sobre la s\u00edntesis de un genoma - microbichitos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"autor: Miguel Vicente El viernes 4 de febrero de 2011 el programa \u201cFuturo Abierto\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\u00f3n, nos reuni\u00f3 a cuatro cient\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \u201cvida artificial\u201d. Los tertulianos fueron Jes\u00fas del Mazo, del Centro de Investigaciones Biol\u00f3gicas\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266#blogposting\",\"name\":\"Conversaci\\u00f3n sobre la s\\u00edntesis de un genoma - microbichitos\",\"headline\":\"Conversaci\\u00f3n sobre la s\\u00edntesis de un genoma\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2011-02-20T20:41:36+01:00\",\"dateModified\":\"2011-02-20T20:52:55+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266#webpage\"},\"articleSection\":\"genoma, Opiniones, ADN, \\u00e9tica, genoma\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/opiniones#listItem\",\"name\":\"Opiniones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/opiniones#listItem\",\"position\":2,\"name\":\"Opiniones\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/opiniones\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266#listItem\",\"name\":\"Conversaci\\u00f3n sobre la s\\u00edntesis de un genoma\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266#listItem\",\"position\":3,\"name\":\"Conversaci\\u00f3n sobre la s\\u00edntesis de un genoma\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/opiniones#listItem\",\"name\":\"Opiniones\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\",\"name\":\"microbichitos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia\",\"name\":\"Miguel Vicente\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel Vicente\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266\",\"name\":\"Conversaci\\u00f3n sobre la s\\u00edntesis de un genoma - microbichitos\",\"description\":\"autor: Miguel Vicente El viernes 4 de febrero de 2011 el programa \\u201cFuturo Abierto\\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\\u00f3n, nos reuni\\u00f3 a cuatro cient\\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \\u201cvida artificial\\u201d. Los tertulianos fueron Jes\\u00fas del Mazo, del Centro de Investigaciones Biol\\u00f3gicas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2011\\\/02\\\/20\\\/131266#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"datePublished\":\"2011-02-20T20:41:36+01:00\",\"dateModified\":\"2011-02-20T20:52:55+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"name\":\"microbichitos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma - microbichitos","description":"autor: Miguel Vicente El viernes 4 de febrero de 2011 el programa \u201cFuturo Abierto\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\u00f3n, nos reuni\u00f3 a cuatro cient\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \u201cvida artificial\u201d. Los tertulianos fueron Jes\u00fas del Mazo, del Centro de Investigaciones Biol\u00f3gicas","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266#blogposting","name":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma - microbichitos","headline":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#articleImage","width":217,"height":72},"datePublished":"2011-02-20T20:41:36+01:00","dateModified":"2011-02-20T20:52:55+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266#webpage"},"articleSection":"genoma, Opiniones, ADN, \u00e9tica, genoma"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/opiniones#listItem","name":"Opiniones"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/opiniones#listItem","position":2,"name":"Opiniones","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/opiniones","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266#listItem","name":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266#listItem","position":3,"name":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/opiniones#listItem","name":"Opiniones"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization","name":"microbichitos","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia","name":"Miguel Vicente","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel Vicente"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266","name":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma - microbichitos","description":"autor: Miguel Vicente El viernes 4 de febrero de 2011 el programa \u201cFuturo Abierto\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\u00f3n, nos reuni\u00f3 a cuatro cient\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \u201cvida artificial\u201d. Los tertulianos fueron Jes\u00fas del Mazo, del Centro de Investigaciones Biol\u00f3gicas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"datePublished":"2011-02-20T20:41:36+01:00","dateModified":"2011-02-20T20:52:55+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","name":"microbichitos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"microbichitos -","og:type":"article","og:title":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma - microbichitos","og:description":"autor: Miguel Vicente El viernes 4 de febrero de 2011 el programa \u201cFuturo Abierto\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\u00f3n, nos reuni\u00f3 a cuatro cient\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \u201cvida artificial\u201d. Los tertulianos fueron Jes\u00fas del Mazo, del Centro de Investigaciones Biol\u00f3gicas","og:url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266","og:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","article:published_time":"2011-02-20T19:41:36+00:00","article:modified_time":"2011-02-20T19:52:55+00:00","twitter:card":"summary","twitter:title":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma - microbichitos","twitter:description":"autor: Miguel Vicente El viernes 4 de febrero de 2011 el programa \u201cFuturo Abierto\u201d de RNE, dirigido por Tato Puerto, con Carmen Gomar en la redacci\u00f3n, nos reuni\u00f3 a cuatro cient\u00edficos para hablar de lo que los periodistas insiten en seguir llamando \u201cvida artificial\u201d. Los tertulianos fueron Jes\u00fas del Mazo, del Centro de Investigaciones Biol\u00f3gicas","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"131266","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 10:23:32","updated":"2026-05-29 23:30:54","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/opiniones\" title=\"Opiniones\">Opiniones<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tConversaci\u00f3n sobre la s\u00edntesis de un genoma\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia"},{"label":"Opiniones","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/opiniones"},{"label":"Conversaci\u00f3n sobre la s\u00edntesis de un genoma","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2011\/02\/20\/131266"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/131266"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/comments?post=131266"}],"version-history":[{"count":13,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/131266\/revisions"}],"predecessor-version":[{"id":131279,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/131266\/revisions\/131279"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/media?parent=131266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/categories?post=131266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/tags?post=131266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}