{"id":131401,"date":"2013-02-26T16:23:01","date_gmt":"2013-02-26T15:23:01","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401"},"modified":"2013-02-26T16:23:01","modified_gmt":"2013-02-26T15:23:01","slug":"no-solo-los-virus-matan","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401","title":{"rendered":"No solo los virus matan"},"content":{"rendered":"<p style=\"text-align: justify\">Hace poco m\u00e1s de un a\u00f1o que se dio por <a href=\"http:\/\/www.polioeradication.org\/\" target=\"_blank\">erradicada la poliomielitis<\/a> en la India, sin ning\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el <a href=\"http:\/\/blogs.elpais.com\/microbichitos\/2012\/01\/polio-otro-virus-expulsado-al-zool\u00f3gico.html#more\" target=\"_blank\">comentario<\/a> que publiqu\u00e9 en microbichitos ya indicaba que la polio segu\u00eda activa en tres pa\u00edses, Afganist\u00e1n, Pakist\u00e1n y Nigeria en donde la vacunaci\u00f3n, que ha dado tan buenos resultados en el resto del mundo para eliminar un virus que deja secuelas permanentes en los enfermos infectados, no es bien aceptada precisamente en los lugares donde m\u00e1s necesaria es, all\u00ed donde m\u00e1s reinan la pobreza, la falta de higiene y la desnutrici\u00f3n. Si a esos tres azotes les a\u00f1adimos la ignorancia nos podemos empezar a imaginar las tragedias que en diciembre y a primeros de febrero han supuesto los asesinatos de personal sanitario que trabajaba en los programas de vacunaci\u00f3n contra la polio, cinco personas  en <a href=\"http:\/\/internacional.elpais.com\/internacional\/2012\/12\/18\/actualidad\/1355825389_977746.html\" target=\"_blank\">Pakist\u00e1n<\/a>&#160;y nueve en <a href=\"http:\/\/sociedad.elpais.com\/sociedad\/2013\/02\/08\/actualidad\/1360324347_980010.html\" target=\"_blank\">Nigeria<\/a>. Si ning\u00fan asesinato tiene explicaci\u00f3n, estos casos a\u00fan parecen m\u00e1s irracionales.<\/p>\n<p style=\"text-align: justify\">\n<a class=\"asset-img-link\" href=\"http:\/\/blogs.elpais.com\/.a\/6a00d8341bfb1653ef017d414a710b970c-pi\"><img decoding=\"async\" alt=\"1956_october_28_polio_shot_4\" class=\"asset  asset-image at-xid-6a00d8341bfb1653ef017d414a710b970c\" src=\"http:\/\/blogs.elpais.com\/.a\/6a00d8341bfb1653ef017d414a710b970c-550wi\" style=\"width: 530px\" \/><\/a><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #a94a76\"><strong>28 de octubre de 1956.<\/strong>&#160;Elvis Presley es vacunado contra la polio. Fuente: <\/span><a href=\"http:\/\/www.elvispresleymusic.com.au\/pictures\/1956_october_28_polio_shot.html\" target=\"_blank\"><span style=\"color: #a94a76\">enlace<\/span><\/a><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #a94a76\"><br \/>\n<\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify\">La poliomielitis es una enfermedad producida por un virus que inicia la infecci\u00f3n en el aparato digestivo y puede acabar invadiendo el sistema nervioso. En uno de cada doscientos casos la invasi\u00f3n del sistema nervioso provoca la destrucci\u00f3n de neuronas que controlan el funcionamiento de los m\u00fasculos. El resultado es la paralizaci\u00f3n de zonas del cuerpo, que es mas o menos grave seg\u00fan lo extenso de los grupos musculares afectados, desde la par\u00e1lisis de las extremidades con importantes secuelas en la movilidad del enfermo, hasta la par\u00e1lisis respiratoria que puede ser fatal. La enfermedad ha sido uno de los grandes azotes de la humanidad hasta que se encontr\u00f3 una vacuna para prevenirla. La primera vacuna fue la obtenida en 1954 por Jonas Salk, que utiliza un virus inactivado y se administra por inyecci\u00f3n. Tras ella Albert Sabin obtuvo en 1960 otra vacuna, que utiliza virus atenuados pero no inactivados, y que se inocula por v\u00eda oral, lo que la hace m\u00e1s f\u00e1cil de administrar. Tambi\u00e9n la vacuna Sabin es m\u00e1s barata de producir, pero, por tratarse de virus vivos y al contrario de la vacuna Salk puede en un m\u00ednimo porcentaje producir la enfermedad. Vistas las graves secuelas que produce la poliomielitis y la existencia de vacunas eficaces para prevenirla, es l\u00f3gico que, cuando los pa\u00edses m\u00e1s desarrollados la eliminaron, se plantease la conveniencia de erradicar tan indeseable enfermedad a nivel mundial.\n<\/p>\n<p style=\"text-align: justify\">No es una empresa f\u00e1cil, adem\u00e1s del coste de las vacunas y de las campa\u00f1as para llevarla hasta los sitios m\u00e1s rec\u00f3nditos, otros problemas han hecho complicado conseguir la eliminaci\u00f3n del virus en el planeta. El virus de la polio no es un virus \u00fanico, sino que se presenta en tres variedades, por lo que para erradicarlo es necesario eliminar los tres y por eso la vacuna oral suele contener una mezcla de tres vacunas contra cada uno de los tipos de virus. Aunque ocurre en muy pocos casos, los virus atenuados pueden reactivarse, despu\u00e9s de su tr\u00e1nsito por el tubo digestivo. Por eso en la campa\u00f1a de erradicaci\u00f3n en Egipto se tuvo que revacunar con vacuna inyectable contra uno de los tipos porque empezaron a circular virus reactivados de ese tipo. <\/p>\n<p style=\"text-align: justify\">\nPero no es la malignidad del virus lo \u00fanico que impide que la poliomielitis sea vencida, como han demostrado los irracionales asesinatos. El problema es una mezcla de pobreza, fanatismo, y recelo potenciados por la ignorancia. Visto lo complejo de sus causas, ser\u00eda muy simplista culpabilizar a uno solo de los elementos, y particularmente a los l\u00edderes religiosos radicales por extender la falacia de que la vacunaci\u00f3n es un complot para propagar el VIH o esterilizar a los j\u00f3venes islamistas. Las campa\u00f1as de vacunaci\u00f3n, de indudable valor humanitario, en las que participa personal de la Organizaci\u00f3n Mundial de la Salud y de UNICEF est\u00e1n en parte financiadas por iniciativas filantr\u00f3picas, en concreto por el Club Internacional Rotario y la fundaci\u00f3n Bill y Melinda Gates. Puede ser dif\u00edcil que a estas entidades se las puedan disociar de su contexto sociopol\u00edtico y que sean aceptadas con entusiasmo en pa\u00edses donde los valores del occidente cristiano no son la norma. Y tampoco ayuda en nada el rumor que asoci\u00f3 la recogida de informaci\u00f3n para el ataque al refugio de Usama ben Ladin por el ej\u00e9rcito estadounidense con la campa\u00f1a de vacunaci\u00f3n. <\/p>\n<p style=\"text-align: justify\">\nQue el virus no sea erradicado por completo en los pa\u00edses donde a\u00fan permanece no deja de ser una espada de Damocles suspendida sobre nuestras cabezas, ya que su contagio es f\u00e1cil y no conoce fronteras. Por eso, como no puede garantizarse que no infecte a las personas no vacunadas, se registran casos de la enfermedad en los pa\u00edses lim\u00edtrofes, donde en teor\u00eda ya se elimin\u00f3. Se necesita as\u00ed seguir la campa\u00f1a de vacunaci\u00f3n masiva en 2013, pues no se considera que el virus se haya eliminado por completo de la poblaci\u00f3n hasta que no pasa un a\u00f1o sin nuevos casos registrados.\n<\/p>\n<p style=\"text-align: justify\">Hay que hacer, pese a todo ello, una lectura optimista de la situaci\u00f3n, gracias a las campa\u00f1as de vacunaci\u00f3n y a quienes las financian y ejecutan, la poliomielitis ha pasado de provocar 350.000 muertes en 1988 a afectar tan solo a <a href=\"http:\/\/www.polioeradication.org\/Dataandmonitoring\/Poliothisweek.aspx\" target=\"_blank\">223 pacientes en 2012<\/a>. Se mire como se quiera, esto no puede considerarse m\u00e1s que como un espectacular \u00e9xito de las vacunas y de las campa\u00f1as, y en definitiva del conocimiento cient\u00edfico. \u00bfPor qu\u00e9 sin embargo hay un rechazo a la vacunaci\u00f3n? No olvidemos que incluso dentro de sociedades supuestamente m\u00e1s instruidas que la nigeriana o la pakistan\u00ed, en concreto en Espa\u00f1a, hay personas que se posicionan contra la vacunaci\u00f3n en general, ignorando que los riesgos de la inmunizaci\u00f3n, que como nada en esta vida es seguro al cien por cien, son \u00ednfimos si se comparan con los de padecer una enfermedad que puede dejar graves secuelas de por vida. No puede obligarse a nadie a dar m\u00e1s cr\u00e9dito a los conocimientos cient\u00edficos que a las creencias, a las supersticiones o a los rumores, esto solo se logra a nivel individual por medio de la educaci\u00f3n, la informaci\u00f3n, el esp\u00edritu cr\u00edtico y el raciocinio. Pero en definitiva es la ignorancia, y a\u00fan peor la falsa ilusi\u00f3n de saber, lo que por encima de todo acaba haciendo m\u00e1s da\u00f1o al ser humano. Aunque sea urgente verse libre de enfermedades peligrosas, quiz\u00e1s deb\u00eda ser al menos igual de importante eliminar la ignorancia que solo a veces es provocada por la pobreza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace poco m\u00e1s de un a\u00f1o que se dio por erradicada la poliomielitis en la India, sin ning\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el comentario que publiqu\u00e9 en microbichitos ya indicaba que la polio segu\u00eda activa en tres pa\u00edses, Afganist\u00e1n, Pakist\u00e1n y Nigeria en donde la vacunaci\u00f3n, que ha dado tan buenos resultados en el resto del mundo para eliminar un virus que deja secuelas permanentes en los enfermos infectados, no es bien aceptada precisamente en los lugares donde m\u00e1s necesaria es, all\u00ed donde m\u00e1s reinan la pobreza, la falta de higiene\u2026<\/p>\n","protected":false},"author":87,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[4808,257],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hace poco m\u00e1s de un a\u00f1o que se dio por erradicada la poliomielitis en la India, sin ning\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el comentario que publiqu\u00e9 en microbichitos ya indicaba que la polio segu\u00eda activa en tres pa\u00edses, Afganist\u00e1n, Pakist\u00e1n y Nigeria en donde la vacunaci\u00f3n,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel Vicente\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"microbichitos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"No solo los virus matan - microbichitos\" \/>\n\t\t<meta property=\"og:description\" content=\"Hace poco m\u00e1s de un a\u00f1o que se dio por erradicada la poliomielitis en la India, sin ning\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el comentario que publiqu\u00e9 en microbichitos ya indicaba que la polio segu\u00eda activa en tres pa\u00edses, Afganist\u00e1n, Pakist\u00e1n y Nigeria en donde la vacunaci\u00f3n,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-02-26T15:23:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-02-26T15:23:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"No solo los virus matan - microbichitos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hace poco m\u00e1s de un a\u00f1o que se dio por erradicada la poliomielitis en la India, sin ning\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el comentario que publiqu\u00e9 en microbichitos ya indicaba que la polio segu\u00eda activa en tres pa\u00edses, Afganist\u00e1n, Pakist\u00e1n y Nigeria en donde la vacunaci\u00f3n,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401#blogposting\",\"name\":\"No solo los virus matan - microbichitos\",\"headline\":\"No solo los virus matan\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/blogs.elpais.com\\\/.a\\\/6a00d8341bfb1653ef017d414a710b970c-550wi\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401\\\/#articleImage\"},\"datePublished\":\"2013-02-26T16:23:01+01:00\",\"dateModified\":\"2013-02-26T16:23:01+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":7,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401#webpage\"},\"articleSection\":\"Antibi\\u00f3ticos y medicinas, Enfermedad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/enfermedad#listItem\",\"name\":\"Enfermedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/enfermedad#listItem\",\"position\":2,\"name\":\"Enfermedad\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/enfermedad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401#listItem\",\"name\":\"No solo los virus matan\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401#listItem\",\"position\":3,\"name\":\"No solo los virus matan\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/enfermedad#listItem\",\"name\":\"Enfermedad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\",\"name\":\"microbichitos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia\",\"name\":\"Miguel Vicente\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel Vicente\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401\",\"name\":\"No solo los virus matan - microbichitos\",\"description\":\"Hace poco m\\u00e1s de un a\\u00f1o que se dio por erradicada la poliomielitis en la India, sin ning\\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el comentario que publiqu\\u00e9 en microbichitos ya indicaba que la polio segu\\u00eda activa en tres pa\\u00edses, Afganist\\u00e1n, Pakist\\u00e1n y Nigeria en donde la vacunaci\\u00f3n,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2013\\\/02\\\/26\\\/131401#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"datePublished\":\"2013-02-26T16:23:01+01:00\",\"dateModified\":\"2013-02-26T16:23:01+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"name\":\"microbichitos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"No solo los virus matan - microbichitos","description":"Hace poco m\u00e1s de un a\u00f1o que se dio por erradicada la poliomielitis en la India, sin ning\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el comentario que publiqu\u00e9 en microbichitos ya indicaba que la polio segu\u00eda activa en tres pa\u00edses, Afganist\u00e1n, Pakist\u00e1n y Nigeria en donde la vacunaci\u00f3n,","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401#blogposting","name":"No solo los virus matan - microbichitos","headline":"No solo los virus matan","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/blogs.elpais.com\/.a\/6a00d8341bfb1653ef017d414a710b970c-550wi","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401\/#articleImage"},"datePublished":"2013-02-26T16:23:01+01:00","dateModified":"2013-02-26T16:23:01+01:00","inLanguage":"es-ES","commentCount":7,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401#webpage"},"articleSection":"Antibi\u00f3ticos y medicinas, Enfermedad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad#listItem","name":"Enfermedad"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad#listItem","position":2,"name":"Enfermedad","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401#listItem","name":"No solo los virus matan"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401#listItem","position":3,"name":"No solo los virus matan","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad#listItem","name":"Enfermedad"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization","name":"microbichitos","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia","name":"Miguel Vicente","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel Vicente"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401","name":"No solo los virus matan - microbichitos","description":"Hace poco m\u00e1s de un a\u00f1o que se dio por erradicada la poliomielitis en la India, sin ning\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el comentario que publiqu\u00e9 en microbichitos ya indicaba que la polio segu\u00eda activa en tres pa\u00edses, Afganist\u00e1n, Pakist\u00e1n y Nigeria en donde la vacunaci\u00f3n,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"datePublished":"2013-02-26T16:23:01+01:00","dateModified":"2013-02-26T16:23:01+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","name":"microbichitos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"microbichitos -","og:type":"article","og:title":"No solo los virus matan - microbichitos","og:description":"Hace poco m\u00e1s de un a\u00f1o que se dio por erradicada la poliomielitis en la India, sin ning\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el comentario que publiqu\u00e9 en microbichitos ya indicaba que la polio segu\u00eda activa en tres pa\u00edses, Afganist\u00e1n, Pakist\u00e1n y Nigeria en donde la vacunaci\u00f3n,","og:url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401","og:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","article:published_time":"2013-02-26T15:23:01+00:00","article:modified_time":"2013-02-26T15:23:01+00:00","twitter:card":"summary","twitter:title":"No solo los virus matan - microbichitos","twitter:description":"Hace poco m\u00e1s de un a\u00f1o que se dio por erradicada la poliomielitis en la India, sin ning\u00fan caso de la enfermedad registrado desde el 13 de enero de 2011. En el comentario que publiqu\u00e9 en microbichitos ya indicaba que la polio segu\u00eda activa en tres pa\u00edses, Afganist\u00e1n, Pakist\u00e1n y Nigeria en donde la vacunaci\u00f3n,","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"131401","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-05 03:38:55","updated":"2026-05-29 23:39:22","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad\" title=\"Enfermedad\">Enfermedad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNo solo los virus matan\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia"},{"label":"Enfermedad","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad"},{"label":"No solo los virus matan","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2013\/02\/26\/131401"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/131401"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/comments?post=131401"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/131401\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/media?parent=131401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/categories?post=131401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/tags?post=131401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}