{"id":132611,"date":"2020-06-12T13:00:30","date_gmt":"2020-06-12T12:00:30","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/microbiologia\/?p=132611"},"modified":"2020-06-12T13:00:30","modified_gmt":"2020-06-12T12:00:30","slug":"covid-19-un-triangulo-mortal-entre-ignorancia-bulos-y-politica-2","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611","title":{"rendered":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica"},"content":{"rendered":"<p><strong>La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\u00f3 niveles de pandemia y ha producido m\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio.<\/strong> Hasta ese momento en Espa\u00f1a ha afectado a m\u00e1s de doscientas mil personas de las que m\u00e1s de veinte mil han fallecido.<br \/>\nA la enfermedad se a\u00f1aden problemas cient\u00edficos, sociales y pol\u00edticos que contribuyen a agravar sus consecuencias.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura1.jpg\"><img decoding=\"async\" class=\"alignleft  wp-image-132613\" title=\"figura1\" src=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura1-1024x719.jpg\" alt=\"\" width=\"589\" height=\"414\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura1-1024x719.jpg 1024w, https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura1-300x210.jpg 300w\" sizes=\"(max-width: 589px) 100vw, 589px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #993366;\"><strong>Microhistorieta del coronavirus.<\/strong> Uruguay, adem\u00e1s de haber frenado muy bien al coronavirus, ha publicado material did\u00e1ctico excelente como esta historieta que relata la lucha contra el SARS-CoV-2. A los populares h\u00e9roes Coco y Fran, que son dos bacterias amigas, ya les vimos hace dos a\u00f1os en <a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2018\/06\/17\/132189\" target=\"_blank\">\u201cBacterias: la historia m\u00e1s peque\u00f1a jam\u00e1s contada\u201d<\/a>\u00a0sobreviviendo a la gran desinfecci\u00f3n que ocurri\u00f3 cuando la limpieza de un hogar diezm\u00f3 a los habitantes de Ciudad Bacteria. La historieta del coronavirus est\u00e1 en este <a href=\"https:\/\/www.comicbacterias.com\/wp-content\/uploads\/2020\/05\/Coco-y-Fran-contra-el-Coronavirus.pdf\" target=\"_blank\">enlace<\/a>.<!--more--><br \/>\n<\/span><\/p>\n<p><!--more--><\/p>\n<p><strong>La ignorancia.<\/strong> Ya desde principio del a\u00f1o se sab\u00eda mucho sobre el coronavirus que provoca la COVID-19, entre otras cosas se dispon\u00eda de la informaci\u00f3n completa que porta su genoma ya que se hab\u00eda obtenido la secuencia de su ARN. Era lo f\u00e1cil de saber pero han sido muchas las sorpresas que se han descubierto sobre c\u00f3mo interacciona con nuestro cuerpo para provocar la enfermedad y sobre c\u00f3mo se contagia, y a\u00fan quedan inc\u00f3gnitas sin resolver. Aunque todos los datos indican que se trata de un virus natural que ha evolucionado para transmitirse desde un animal salvaje al ser humano y ser contagioso, no queda claro su origen ni c\u00f3mo ocurri\u00f3 su transmisi\u00f3n inicial a las personas. No es que saberlo con exactitud suponga un gran progreso en c\u00f3mo curar a los enfermos, pero si es importante para tratar de impedir la aparici\u00f3n de nuevas enfermedades parecidas en el futuro. Lo m\u00e1s probable es que, como ha ocurrido con virus parecidos como el SARS, se originase en los murci\u00e9lagos y de ellos haya pasado al ser humano utilizando a otro animal como estaci\u00f3n intermedia. Se ha hablado de serpientes y del pangolin, pero no hay certeza.<\/p>\n<p><strong>El SARS-CoV2.<\/strong> Se trata de un virus, es decir de un pat\u00f3geno que no puede hacer nada por si mismo. A diferencia de lo que hacen las bacterias, un virus ni crece ni se reproduce, es inerte. Para hacer algo semejante a lo que caracteriza a un ser vivo, un virus necesita introducirse en una c\u00e9lula y aprovecharse de ella. Los coronavirus tienen instrucciones para esclavizar a la c\u00e9lula, sus genes, en una mol\u00e9cula de ARN. Nuestras c\u00e9lulas tienen sus propias instrucciones en mol\u00e9culas de ADN y tambi\u00e9n organizadas como genes que se agrupan en varios cromosomas. La diferencia entre tener ADN o ARN es que el ADN, al llevar la informaci\u00f3n en dos cadenas que se controlan una a la otra sufre menos equivocaciones cuando se replica. En el ARN ese control no existe y los virus con ARN tienden a sufrir m\u00e1s mutaciones.<br \/>\nPara invadirla, el virus, que es como una ves\u00edcula microsc\u00f3pica, lleva en su superficie una prote\u00edna que se pega a la c\u00e9lula. Precisamente por su facilidad para mutar, un virus que solo infecte a c\u00e9lulas de un animal puede con el tiempo adquirir la capacidad de adherirse e invadir una c\u00e9lula humana. Es lo que ha ocurrido ya en otras epidemias como la gripe aviar y el SARS.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura22.jpg\"><img decoding=\"async\" class=\"alignleft  wp-image-132616\" title=\"figura2\" src=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura22-1024x719.jpg\" alt=\"\" width=\"589\" height=\"414\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura22-1024x719.jpg 1024w, https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura22-300x210.jpg 300w\" sizes=\"(max-width: 589px) 100vw, 589px\" \/><\/a><\/p>\n<p><span style=\"color: #993366;\"><strong>Virus y enfermedad.<\/strong> COVID-19 es la enfermedad que produce el coronavirus SARS-CoV-2.<\/span><\/p>\n<div>Tras los numerosos estudios contrastados que se han publicado se han desvelado muchas propiedades sorprendentes del SARS-CoV-2. Una de las m\u00e1s peligrosas es que los enfermos que a\u00fan no tienen s\u00edntomas lo pueden contagiar. El virus se propaga as\u00ed de manera larvada en los pacientes dificultando al m\u00e1ximo la detecci\u00f3n de c\u00f3mo aumentan los contagios, algo que ha agravado mucho la pandemia.<\/div>\n<p><strong>La enfermedad.<\/strong> La descripci\u00f3n de como progresa la COVID-19 en los casos m\u00e1s graves parece un relato tr\u00e1gico de una cat\u00e1strofe \u00e9pica. Los intentos que nuestro cuerpo hace para evitar el da\u00f1o que produce el virus son los que en \u00faltima instancia llevan en un cinco por ciento de los enfermos al fracaso que inutiliza no solo a los pulmones, sino a casi todos los \u00f3rganos del cuerpo y a la muerte.<br \/>\nPara empezar el virus penetra en las c\u00e9lulas de las v\u00edas respiratorias superiores, nariz y faringe porque una de las prote\u00ednas de su cubierta interacciona con la prote\u00edna Ace2 de nuestras c\u00e9lulas. Ace2 interviene en nuestro organismo en la regulaci\u00f3n de la tensi\u00f3n arterial y abunda en las c\u00e9lulas del pulm\u00f3n en las que la sangre se oxigena. Una vez dentro secuestra la maquinaria molecular de producir prote\u00ednas y desv\u00eda todo el metabolismo de nuestras c\u00e9lulas para multiplicarse, las destruye y empieza a invadir lugares como los bronquios y alveolos pulmonares. Uno de los s\u00edntomas iniciales es la p\u00e9rdida del gusto y del olfato.<br \/>\nLa respuesta de nuestro sistema inmunitario para combatir al virus puede ser desmesurada y es en esos casos en los que los pulmones fracasan. Ocurre que la respuesta es m\u00e1s desproporcionada en los enfermos que sufren otras afecciones, la hipertensi\u00f3n entre otras.<br \/>\nTambi\u00e9n la abundancia de la prote\u00edna Ace2, que en los ni\u00f1os no es tan alta, va aumentando con la edad. Esto explica por qu\u00e9 la COVID es m\u00e1s grave en los ancianos que sufren otras afecciones.<br \/>\nEn los casos graves al enfermo le falta ox\u00edgeno en la sangre y se ahoga en los fluidos que se acumulan en los pulmones como resultado de la destrucci\u00f3n de sus c\u00e9lulas y del intento de acumular en su entorno a los elementos del sistema inmunitario que fracasan al intentar luchar contra el virus. Se produce lo que se llama una tormenta de citoquinas, las mol\u00e9culas de nuestro cuerpo que en principio deber\u00edan guiar al sistema inmunitario para destruir las c\u00e9lulas infectadas y que se sospecha que se desbocan y llega un punto en el que no distinguen lo sano de lo enfermo.<br \/>\nLos da\u00f1os no se limitan a los pulmones sino que se extienden al sistema circulatorio en donde se pueden formar co\u00e1gulos en la sangre, a los ri\u00f1ones provocando fallos renales e incluso al cerebro.<\/p>\n<p><span style=\"color: #993366;\"><strong><a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figure32.jpg\"><img decoding=\"async\" class=\"alignleft  wp-image-132626\" title=\"figure3\" src=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figure32-1024x716.jpg\" alt=\"\" width=\"614\" height=\"430\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figure32-1024x716.jpg 1024w, https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figure32-300x209.jpg 300w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><\/a><br \/>\nLa amenaza viral.<\/strong> Tropas del ej\u00e9rcito de los coronavirus, agazapadas en una zona contaminada de la casa, se aprestan a invadir a un paciente desprevenido avanzando por las manos sucias hasta la nariz.<\/span><\/p>\n<p><strong>Prevenir y curar.<\/strong> Lo peor de nuestra ignorancia es que todav\u00eda no sabemos c\u00f3mo prevenir ni c\u00f3mo curar la COVID-19. Por ahora no hay ninguna vacuna cuya eficacia se haya probado. Hay varias que se est\u00e1n probando en animales de laboratorio y otras que se est\u00e1n desarrollando, un par de ellas en el Centro Nacional de Biotecnolog\u00eda. Pero su utilizaci\u00f3n cl\u00ednica no se espera que pueda ocurrir en menos de un a\u00f1o.<br \/>\nNo se dispone tampoco de un medicamento que la cure. Se pueden aliviar los s\u00edntomas pero no hay nada que sepamos que elimine el virus. Un poco a la desesperada se han recetado medicamentos que se cre\u00eda, sin pruebas suficientes, que pod\u00edan frenar a este coronavirus. A la larga se ha comprobado que un antimal\u00e1rico, la hidroxicloroquina, preconizado incluso por Donald Trump, no se sabe si produce m\u00e1s problemas que beneficios. Su uso solo estaba avalado por los resultados previos que daban un pu\u00f1ado de casos de un estudio en el que adem\u00e1s faltaban suficientes controles. Vemos que el coronavirus tambi\u00e9n contagia a la integridad de la investigaci\u00f3n cient\u00edfica. Las prisas excesivas conducen a situaciones surrealistas con respecto a la publicaci\u00f3n, en dos prestigiosas revistas, de los ensayos de eficacia de la hidroxicloroquina. Las buenas noticias: que los investigadores tienen mecanismos de control para limitar la difusi\u00f3n de estudios insuficientemente respaldados por las pruebas experimentales. Est\u00e1 ahora por ver cu\u00e1l es el resultado correcto. Solo el trabajo de los estudios cl\u00ednicos bien realizados lo dir\u00e1.<br \/>\nPor ahora, a la espera de tener vacunas y medicamentos eficaces, lo m\u00e1s seguro es evitar el contagio.<\/p>\n<p><span style=\"color: #993366;\"><strong><a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura4.jpg\"><img decoding=\"async\" class=\"alignleft  wp-image-132629\" title=\"figura4\" src=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura4-1024x719.jpg\" alt=\"\" width=\"614\" height=\"431\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura4-1024x719.jpg 1024w, https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura4-300x210.jpg 300w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><\/a>Alarma salvadora.<\/strong> Seguir los consejos, l\u00e1vate las manos con agua y jab\u00f3n, desinfecta las superficies contaminadas y qu\u00e9date en tu casa mientras dure la alarma, consigue derrotar al ej\u00e9rcito invasor y as\u00ed librarse de caer enfermo.<\/span><\/p>\n<p><strong>Los bulos.<\/strong> Como no pod\u00eda ser de otra forma, la numerosa comunidad conspiranoica no pod\u00eda quedarse sin proponer relatos fantasiosos sobre los or\u00edgenes del SARS-CoV-2. Pero las pruebas no los apoyan. El virus no se ha construido a prop\u00f3sito por mentes mal\u00e9volas ni la propagaci\u00f3n de la enfermedad est\u00e1 guiada por las nuevas tecnolog\u00edas de comunicaci\u00f3n inal\u00e1mbrica. Tampoco se ha demostrado que se haya escapado de un laboratorio de alta seguridad ni que conocidos magnates lo hayan distribuido para beneficiarse de una hipot\u00e9tica vacuna que ya tendr\u00edan almacenada. Por el contrario todos los estudios indican que se asemeja mucho a otros coronavirus que en ocasiones han pasado desde los animales silvestres al ser humano.<br \/>\nTambi\u00e9n se han propuesto todo tipo de remedios in\u00fatiles, y a veces perjudiciales, sobre c\u00f3mo curar o prevenir la COVID-19. Junto a los ya cl\u00e1sicos como el peligroso MMS (clorito s\u00f3dico) hay otros harto peregrinos como el de que beber agua templada desactiva al virus. Pi\u00e9nsese que como todos los virus que nos atacan los coronavirus pueden proliferar en nuestras c\u00e9lulas que en el cuerpo est\u00e1n a 37 grados. Inyectarse desinfectante o lej\u00eda, un atajo al MMS, son cosas tan absurdas y perjudiciales que solo se le ha ocurrido proponerlas a los m\u00e1s ignorantes y pocos les han hecho caso.<\/p>\n<p><strong>La pol\u00edtica.<\/strong> Al enfermo le interesa curarse, al sano no enfermar, al est\u00fapido qui\u00e9n tuvo m\u00e1s culpa. Parecer\u00eda viendo los debates en el Congreso que la pol\u00edtica fuese el arte de discutir de todo menos de lo que hay que resolver. En Espa\u00f1a nos ha pillado a todos muy desprevenidos, nos cre\u00edamos muy a salvo, pero la pandemia ha revelado importantes carencias. En la sanidad p\u00fablica, que es buena pero solo cuando no hay una crisis, una d\u00e9cada de recortes ten\u00eda que notarse, y no solo en los medios materiales, tambi\u00e9n en la escasez de personal al que m\u00e1s que trabajadores se ha exigido ser h\u00e9roes. El Gobierno ha tenido fallos. En las etapas iniciales algunos fueron por la falta de conocimientos sobre un virus taimado, otros por los cambios en las recomendaciones de las agencias internacionales, otros por falta de planes para gestionar una cat\u00e1strofe que nos parec\u00eda imposible que ocurriese. Y tambi\u00e9n por no querer alarmar reconociendo la escasez de medios. Pero no creo que nadie lo haya hecho, como parece hacernos creer la oposici\u00f3n, para perjudicarnos. Tampoco hay que pensar que cuando esa oposici\u00f3n estaba en el poder recortase a prop\u00f3sito los fondos destinados a sanidad para perjudicarnos a todos. Escuchando a la oposici\u00f3n espa\u00f1ola es envidiable la situaci\u00f3n pol\u00edtica de Portugal, donde se ha entendido que ahora el acabar con el Gobierno puede esperar porque lo urgente es acabar con el virus.<br \/>\nTambi\u00e9n es envidiable la actitud de los ciudadanos uruguayos que voluntariamente adoptaron medidas de precauci\u00f3n que les han permitido tener un m\u00ednimo n\u00famero de afectados por la pandemia. En nuestro pa\u00eds por lo general los ciudadanos han sido bastante contenidos y responsables, cosa dif\u00edcil por nuestros h\u00e1bitos.<br \/>\nPero no nos flagelemos, hay sitios como Brasil o los todopoderosos Estados Unidos, en donde la situaci\u00f3n parece peor. Suecia eligi\u00f3 no aplicar medidas de aislamiento confiando en que la inmunidad producida al enfermar y recuperarse un n\u00famero alto de personas, la inmunidad llamada de reba\u00f1o, frenar\u00eda los contagios. Como no parece haber sido as\u00ed se demostrar\u00eda que la mejor forma de impedir la epidemia es impedir los contagios con medidas de aislamiento, y que la estrategia del Gobierno de Espa\u00f1a no ha estado muy equivocada.<br \/>\nCon los datos que tenemos parece de todas formas vital el analizar con tranquilidad lo que ha ocurrido para evitar errores si se producen rebrotes o nuevas pandemias.Tambi\u00e9n es urgente volver a financiar la sanidad p\u00fablica y la investigaci\u00f3n hasta niveles como los de Alemania, pa\u00eds en el que m\u00e1s personas se han curado gracias al buen nivel de atenci\u00f3n y recursos m\u00e9dicos. Es l\u00f3gico que reiterar las recriminaciones y descalificaciones entre nuestros pol\u00edticos no van a ayudar mucho a conseguirlo.<\/p>\n<p><span style=\"color: #993366;\"><strong>Aviso:<\/strong> <em>el autor es microbi\u00f3logo, por lo que sus opiniones no pueden considerarse que tengan validez cl\u00ednica. Asimismo la COVID-19 tiene aspectos muy diversos que son de inter\u00e9s pero que para mantener una extensi\u00f3n razonable no se han tratado en este articulo.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\u00f3 niveles de pandemia y ha producido m\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio. Hasta ese momento en Espa\u00f1a ha afectado a m\u00e1s de doscientas mil personas de las que m\u00e1s de veinte mil han fallecido. A la enfermedad se a\u00f1aden problemas cient\u00edficos, sociales y pol\u00edticos que contribuyen a agravar sus consecuencias. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Microhistorieta del coronavirus. Uruguay, adem\u00e1s de\u2026<\/p>\n","protected":false},"author":87,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[257,35307,1519,28139],"tags":[19124,31274,39209],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\u00f3 niveles de pandemia y ha producido m\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio. Hasta ese momento en Espa\u00f1a ha afectado a m\u00e1s\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel Vicente\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"microbichitos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica - microbichitos\" \/>\n\t\t<meta property=\"og:description\" content=\"La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\u00f3 niveles de pandemia y ha producido m\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio. Hasta ese momento en Espa\u00f1a ha afectado a m\u00e1s\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-12T12:00:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-12T12:00:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica - microbichitos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\u00f3 niveles de pandemia y ha producido m\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio. Hasta ese momento en Espa\u00f1a ha afectado a m\u00e1s\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611#blogposting\",\"name\":\"COVID-19: un tri\\u00e1ngulo mortal entre ignorancia, bulos y pol\\u00edtica - microbichitos\",\"headline\":\"COVID-19: un tri\\u00e1ngulo mortal entre ignorancia, bulos y pol\\u00edtica\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/files\\\/2020\\\/06\\\/figura1-1024x719.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611\\\/#articleImage\"},\"datePublished\":\"2020-06-12T13:00:30+01:00\",\"dateModified\":\"2020-06-12T13:00:30+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":16,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611#webpage\"},\"articleSection\":\"Enfermedad, Microbios, Salud, Virus, coronavirus, COVID-19, SARS-CoV-2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/enfermedad#listItem\",\"name\":\"Enfermedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/enfermedad#listItem\",\"position\":2,\"name\":\"Enfermedad\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/enfermedad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611#listItem\",\"name\":\"COVID-19: un tri\\u00e1ngulo mortal entre ignorancia, bulos y pol\\u00edtica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611#listItem\",\"position\":3,\"name\":\"COVID-19: un tri\\u00e1ngulo mortal entre ignorancia, bulos y pol\\u00edtica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/enfermedad#listItem\",\"name\":\"Enfermedad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\",\"name\":\"microbichitos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia\",\"name\":\"Miguel Vicente\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel Vicente\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611\",\"name\":\"COVID-19: un tri\\u00e1ngulo mortal entre ignorancia, bulos y pol\\u00edtica - microbichitos\",\"description\":\"La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\\u00f3 niveles de pandemia y ha producido m\\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio. Hasta ese momento en Espa\\u00f1a ha afectado a m\\u00e1s\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2020\\\/06\\\/12\\\/132611#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"datePublished\":\"2020-06-12T13:00:30+01:00\",\"dateModified\":\"2020-06-12T13:00:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"name\":\"microbichitos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica - microbichitos","description":"La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\u00f3 niveles de pandemia y ha producido m\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio. Hasta ese momento en Espa\u00f1a ha afectado a m\u00e1s","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611#blogposting","name":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica - microbichitos","headline":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2020\/06\/figura1-1024x719.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611\/#articleImage"},"datePublished":"2020-06-12T13:00:30+01:00","dateModified":"2020-06-12T13:00:30+01:00","inLanguage":"es-ES","commentCount":16,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611#webpage"},"articleSection":"Enfermedad, Microbios, Salud, Virus, coronavirus, COVID-19, SARS-CoV-2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad#listItem","name":"Enfermedad"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad#listItem","position":2,"name":"Enfermedad","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611#listItem","name":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611#listItem","position":3,"name":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad#listItem","name":"Enfermedad"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization","name":"microbichitos","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia","name":"Miguel Vicente","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel Vicente"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611","name":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica - microbichitos","description":"La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\u00f3 niveles de pandemia y ha producido m\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio. Hasta ese momento en Espa\u00f1a ha afectado a m\u00e1s","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"datePublished":"2020-06-12T13:00:30+01:00","dateModified":"2020-06-12T13:00:30+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","name":"microbichitos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"microbichitos -","og:type":"article","og:title":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica - microbichitos","og:description":"La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\u00f3 niveles de pandemia y ha producido m\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio. Hasta ese momento en Espa\u00f1a ha afectado a m\u00e1s","og:url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611","og:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","article:published_time":"2020-06-12T12:00:30+00:00","article:modified_time":"2020-06-12T12:00:30+00:00","twitter:card":"summary","twitter:title":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica - microbichitos","twitter:description":"La COVID-19 es una enfermedad grave producida por el virus SARS-CoV-2 que apareci\u00f3 en Wuhan, una ciudad China, a finales de 2019. En la primavera de 2020 alcanz\u00f3 niveles de pandemia y ha producido m\u00e1s de trescientas mil muertes en el mundo hasta primeros de junio. Hasta ese momento en Espa\u00f1a ha afectado a m\u00e1s","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"132611","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 12:55:35","updated":"2026-05-29 23:56:03","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad\" title=\"Enfermedad\">Enfermedad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCOVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia"},{"label":"Enfermedad","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/enfermedad"},{"label":"COVID-19: un tri\u00e1ngulo mortal entre ignorancia, bulos y pol\u00edtica","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2020\/06\/12\/132611"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/132611"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/comments?post=132611"}],"version-history":[{"count":18,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/132611\/revisions"}],"predecessor-version":[{"id":132637,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/132611\/revisions\/132637"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/media?parent=132611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/categories?post=132611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/tags?post=132611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}