{"id":80753,"date":"2007-12-11T22:48:00","date_gmt":"2007-12-11T22:48:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/microbiologia\/archive\/2007\/12\/11\/80753.aspx"},"modified":"2010-01-27T01:49:21","modified_gmt":"2010-01-27T00:49:21","slug":"%c2%bfque-es-la-microbiologia-por-moselio-schaechter","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753","title":{"rendered":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter"},"content":{"rendered":"<div style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.bio.sdsu.edu\/faculty\/schaechter.htm\">Moselio Schaechter,<\/a> Elio para los amigos, naci\u00f3 en <a href=\"http:\/\/www.ciaomilano.it\/e\/index.asp\">Mil\u00e1n<\/a> emigrando con sus padres, jud\u00edos polacos, a <a href=\"http:\/\/www.presidencia.gov.ec\/\">El Ecuador<\/a> y finalmente a los <a href=\"http:\/\/www.state.gov\/\">Estados Unidos<\/a> doctor\u00e1ndose en la <a href=\"http:\/\/www.upenn.edu\/\">Universidad de Pennsylvania<\/a>. Como posdoctoral en <a href=\"http:\/\/www.denmark.dk\/es\/menu\/SobreDinamarca\/Sobre_Dinamarca.htm\">Dinamarca<\/a>, dirigido por <a href=\"http:\/\/www.biokemi.org\/biozoom\/2000_1\/images\/maaloe_2s.jpg\">Ole Maal\u00f8e<\/a>, investig\u00f3 la composici\u00f3n de la bacteria <a href=\"http:\/\/microbewiki.kenyon.edu\/index.php\/Salmonella\"><em>Salmonella<\/em><\/a> cuando crece, en particular los detalles referentes a la s\u00edntesis de prote\u00ednas y ADN. La mayor parte de su carrera la ha ejercido en la <a href=\"http:\/\/www.tufts.edu\/\">Universidad de Tufts<\/a> en <a href=\"http:\/\/www.cityofboston.gov\/\">Boston<\/a>, siendo director del <a href=\"http:\/\/www.tufts.edu\/med\/about\/programs\/academicdepartments\/microbiology.html\">Departamento de Biolog\u00eda Molecular y Microbiolog\u00eda<\/a> durante 23 a\u00f1os. Sus \u00faltimos trabajos experimentales indagaron c\u00f3mo el cromosoma de las bacterias no est\u00e1 fijo en su interior, sino que cuando acaba de duplicarse se pega por un tiempo a la membrana. Moselio es un gran aficionado a las setas, pr\u00e1cticamente su segunda profesi\u00f3n, as\u00ed su libro \u201c<a href=\"http:\/\/www.hup.harvard.edu\/catalog\/SCHMUS.html\">En compa\u00f1\u00eda de las setas<\/a>\u201d, lo public\u00f3 la <a href=\"http:\/\/www.hup.harvard.edu\/\">editorial<\/a> de la <a href=\"http:\/\/www.harvard.edu\/\">Universidad Harvard<\/a>. Entre otras actividades ha presidido la <a href=\"http:\/\/www.asm.org\/\">Sociedad Americana de Microbiolog\u00eda<\/a> y es asesor cient\u00edfico para que la televisi\u00f3n incorpore en su programaci\u00f3n el conocimiento de los microbios.<\/strong><\/div>\n<hr size=\"2\" \/><img decoding=\"async\" src=\"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/910\/o_elio2.jpg\" alt=\"\" \/><\/p>\n<div style=\"text-align: justify;\"><strong>Moselio nos ha dedicado un art\u00edculo para su inclusi\u00f3n en nuestro foro en el que reflexiona sobre la Microbiolog\u00eda y los microbios.<\/strong><\/div>\n<p><!--more--><strong>\u00bfQue es la Microbiolog\u00eda?<br \/>\nautor: <a href=\"http:\/\/www.bio.sdsu.edu\/faculty\/schaechter.htm\">Moselio Schaechter<\/a><br \/>\n<\/strong><\/p>\n<hr size=\"2\" \/><strong>Unos bichos m\u00e1s que ubicuos<\/strong><\/p>\n<div style=\"text-align: justify;\">Seg\u00fan ciertos cient\u00edficos, incluyendo el firmante, la microbiolog\u00eda es la reina de las ciencias.\u00a0 Esta afirmaci\u00f3n es f\u00e1cilmente justificable ya que los microbios abarcan mas o menos la mitad del los organismos que viven en este planeta. Invisibles a simple vista, las bacteria, protozoos, hongos, y otros \u201cbichos\u201d habitan no solo en el cuerpo humano y sus alrededores, tambi\u00e9n se encuentran en gran n\u00famero en sitios inesperados e improbables. Hay bacterias que viven en el fondo del mar en lugares donde el magma de la tierra emerge elevando la temperatura a m\u00e1s de 120\u00b0 o en nichos tan \u00e1cidos que quemar\u00edan la piel. En Espa\u00f1a misma, sin ir m\u00e1s lejos, tales extraordinarias propiedades de supervivencia se encuentran en el estuario del <a href=\"http:\/\/es.wikipedia.org\/wiki\/R%C3%ADo_Tinto\">r\u00edo Tinto<\/a> (<a href=\"http:\/\/www.todohuelva.com\/1\/1.htm\">Huelva<\/a>).\u00a0 Como consecuencia de excavar minas desde las edades del bronce y del hierro, las aguas de ese r\u00edo son muy \u00e1cidas y ricas en minerales extremadamente t\u00f3xicos. Muchas bacterias y protistas viven all\u00ed, indiferentes a condiciones tan extremas. Desde un punto de vista antropom\u00f3rfico, tales organismos ha sido llamados \u201c<a href=\"http:\/\/es.wikipedia.org\/wiki\/Extrem%C3%B3filo\">extrem\u00f3filos<\/a>\u201d. En verdad, para ellos nuestra temperatura y <a href=\"http:\/\/es.wikipedia.org\/wiki\/PH\">pH<\/a> ser\u00edan los realmente artificiales y amenazantes.<\/div>\n<p><strong>Imprescindibles para la vida<\/strong><\/p>\n<div style=\"text-align: justify;\">Se puede afirmar sin peligro de contradicci\u00f3n que microbios existen en todos los sitios del mundo donde hay agua l\u00edquida. La consecuencia de una distribuci\u00f3n ecol\u00f3gica tan variada es que el mundo microbiano forma la m\u00e1s grande de todas las diversidades biol\u00f3gicas. La distancia evolutiva entre las diversas bacterias es enorme y el n\u00famero total de genes microbianos diferentes puede ser m\u00e1s de mil veces el de los genes de organismos \u201csuperiores\u201d. Como consecuencia, la \u201c<a href=\"http:\/\/es.wikipedia.org\/wiki\/Gen%C3%B3mica\">gen\u00f3mica<\/a>\u201d resulta ser una ciencia microbiana. No solo eso, los microbios son los agentes m\u00e1s importantes del \u201cmetabolismo del planeta\u201d. Los ciclos del carbono, ox\u00edgeno y nitr\u00f3geno funcionan gracias a bacterias, algas microsc\u00f3picas y hongos. Su influencia es tan enorme que si los microbios decidieran ponerse en huelga la vida en esta Tierra \u00a1se parar\u00eda en unos siete d\u00edas! No hay peligro de eso ya que los microbios son tenaces y pueden sobrevivir a cambios ambientales que amenazar\u00edan al resto de los seres vivos.<\/div>\n<p><strong>No todos son malignos<\/strong><\/p>\n<div style=\"text-align: justify;\">La visi\u00f3n popular es que los microbios son la causa de enfermedades, incluyendo muchas que ponen en peligro a sus hu\u00e9spedes. Esto no deja de ser cierto, ya que causan toda clase de infecciones, desde la <a href=\"http:\/\/www.kidshealth.org\/parent\/en_espanol\/infecciones\/flu_esp.html\">gripe<\/a> hasta el <a href=\"http:\/\/www.cdc.gov\/hiv\/spanish\/\">SIDA<\/a>. Pero esto enfatiza solo uno de los aspectos del mundo microbiano. Es una descripci\u00f3n imprecisa, \u00a1equivalente a afirmar que todas las sustancias qu\u00edmicas son venenosas! Una visi\u00f3n m\u00e1s exacta incluye el papel beneficioso que los microbios juegan en cada aspecto de nuestra vida. Por cierto, nuestro cuerpo contiene una cantidad enorme de bacterias que son esenciales para mantenernos sanos. Tan solo en el intestino grueso hay diez veces m\u00e1s bacterias que el n\u00famero de c\u00e9lulas de nuestro cuerpo. Adem\u00e1s, las <a href=\"http:\/\/es.wikipedia.org\/wiki\/Mitocondria\">mitocondrias<\/a> (los microsc\u00f3picos motores que producen nuestra energ\u00eda) derivan de bacterias que fueron\u00a0 incorporadas a nuestras c\u00e9lulas en el proceso de su evoluci\u00f3n. De esta manera, nosotros mismos somos en buena parte microbios. Pero hay m\u00e1s razones para estar agradecidos a esos seres diminutos. Los microbios producen muchas sustancias de uso industrial, como disolventes, antibi\u00f3ticos, hormonas, vacunas, etc. Y nos han otorgado la oportunidad de crear nuevas ciencias, como la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Biolog%C3%ADa_molecular\">biolog\u00eda molecular<\/a>, la <a href=\"http:\/\/www.uned.es\/091279\/ingenieria_genetica\/index.html\">ingenier\u00eda gen\u00e9tica<\/a> y la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Gen%C3%B3mica\">gen\u00f3mica<\/a>.<\/div>\n<p><strong>Aprender de los microbios<\/strong><\/p>\n<div style=\"text-align: justify;\">Finalmente, los microbios han sido y siguen siendo los organismos modelo para tratar de entender los procesos fundamentales de la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Biolog%C3%ADa\">Biolog\u00eda<\/a>. Mucho de lo que sabemos sobre la vida misma deriva de estudios llevados a cabo con los microbios. En cierto sentido cada bi\u00f3logo es un microbi\u00f3logo.<\/p>\n<hr size=\"2\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Moselio Schaechter, Elio para los amigos, naci\u00f3 en Mil\u00e1n emigrando con sus padres, jud\u00edos polacos, a El Ecuador y finalmente a los Estados Unidos doctor\u00e1ndose en la Universidad de Pennsylvania. Como posdoctoral en Dinamarca, dirigido por Ole Maal\u00f8e, investig\u00f3 la composici\u00f3n de la bacteria Salmonella cuando crece, en particular los detalles referentes a la s\u00edntesis de prote\u00ednas y ADN. La mayor parte de su carrera la ha ejercido en la Universidad de Tufts en Boston, siendo director del Departamento de Biolog\u00eda Molecular y Microbiolog\u00eda durante 23 a\u00f1os. Sus \u00faltimos trabajos experimentales indagaron c\u00f3mo el cromosoma de las bacterias no est\u00e1\u2026<\/p>\n","protected":false},"author":87,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[248],"tags":[535,486,892,781],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Moselio Schaechter, Elio para los amigos, naci\u00f3 en Mil\u00e1n emigrando con sus padres, jud\u00edos polacos, a El Ecuador y finalmente a los Estados Unidos doctor\u00e1ndose en la Universidad de Pennsylvania. Como posdoctoral en Dinamarca, dirigido por Ole Maal\u00f8e, investig\u00f3 la composici\u00f3n de la bacteria Salmonella cuando crece, en particular los detalles referentes a la s\u00edntesis\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel Vicente\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"microbichitos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter - microbichitos\" \/>\n\t\t<meta property=\"og:description\" content=\"Moselio Schaechter, Elio para los amigos, naci\u00f3 en Mil\u00e1n emigrando con sus padres, jud\u00edos polacos, a El Ecuador y finalmente a los Estados Unidos doctor\u00e1ndose en la Universidad de Pennsylvania. Como posdoctoral en Dinamarca, dirigido por Ole Maal\u00f8e, investig\u00f3 la composici\u00f3n de la bacteria Salmonella cuando crece, en particular los detalles referentes a la s\u00edntesis\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2007-12-11T22:48:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-27T00:49:21+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter - microbichitos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Moselio Schaechter, Elio para los amigos, naci\u00f3 en Mil\u00e1n emigrando con sus padres, jud\u00edos polacos, a El Ecuador y finalmente a los Estados Unidos doctor\u00e1ndose en la Universidad de Pennsylvania. Como posdoctoral en Dinamarca, dirigido por Ole Maal\u00f8e, investig\u00f3 la composici\u00f3n de la bacteria Salmonella cuando crece, en particular los detalles referentes a la s\u00edntesis\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753#blogposting\",\"name\":\"\\u00bfQue es la Microbiolog\\u00eda? por Moselio Schaechter - microbichitos\",\"headline\":\"\\u00bfQue es la Microbiolog\\u00eda? por Moselio Schaechter\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/microbiologia\\\/wp-content\\\/blogs.dir\\\/110\\\/files\\\/910\\\/o_elio2.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753\\\/#articleImage\"},\"datePublished\":\"2007-12-11T22:48:00+01:00\",\"dateModified\":\"2010-01-27T01:49:21+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":28,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753#webpage\"},\"articleSection\":\"Firma invitada, gripe, Microbiolog\\u00eda, mitocondria, SIDA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/firma-invitada#listItem\",\"name\":\"Firma invitada\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/firma-invitada#listItem\",\"position\":2,\"name\":\"Firma invitada\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/firma-invitada\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753#listItem\",\"name\":\"\\u00bfQue es la Microbiolog\\u00eda? por Moselio Schaechter\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753#listItem\",\"position\":3,\"name\":\"\\u00bfQue es la Microbiolog\\u00eda? por Moselio Schaechter\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/category\\\/firma-invitada#listItem\",\"name\":\"Firma invitada\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\",\"name\":\"microbichitos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia\",\"name\":\"Miguel Vicente\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel Vicente\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753\",\"name\":\"\\u00bfQue es la Microbiolog\\u00eda? por Moselio Schaechter - microbichitos\",\"description\":\"Moselio Schaechter, Elio para los amigos, naci\\u00f3 en Mil\\u00e1n emigrando con sus padres, jud\\u00edos polacos, a El Ecuador y finalmente a los Estados Unidos doctor\\u00e1ndose en la Universidad de Pennsylvania. Como posdoctoral en Dinamarca, dirigido por Ole Maal\\u00f8e, investig\\u00f3 la composici\\u00f3n de la bacteria Salmonella cuando crece, en particular los detalles referentes a la s\\u00edntesis\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/2007\\\/12\\\/11\\\/80753#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/author\\\/microbiologia#author\"},\"datePublished\":\"2007-12-11T22:48:00+01:00\",\"dateModified\":\"2010-01-27T01:49:21+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/\",\"name\":\"microbichitos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/microbiologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter - microbichitos","description":"Moselio Schaechter, Elio para los amigos, naci\u00f3 en Mil\u00e1n emigrando con sus padres, jud\u00edos polacos, a El Ecuador y finalmente a los Estados Unidos doctor\u00e1ndose en la Universidad de Pennsylvania. Como posdoctoral en Dinamarca, dirigido por Ole Maal\u00f8e, investig\u00f3 la composici\u00f3n de la bacteria Salmonella cuando crece, en particular los detalles referentes a la s\u00edntesis","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753#blogposting","name":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter - microbichitos","headline":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/microbiologia\/wp-content\/blogs.dir\/110\/files\/910\/o_elio2.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753\/#articleImage"},"datePublished":"2007-12-11T22:48:00+01:00","dateModified":"2010-01-27T01:49:21+01:00","inLanguage":"es-ES","commentCount":28,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753#webpage"},"articleSection":"Firma invitada, gripe, Microbiolog\u00eda, mitocondria, SIDA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/firma-invitada#listItem","name":"Firma invitada"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/firma-invitada#listItem","position":2,"name":"Firma invitada","item":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/firma-invitada","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753#listItem","name":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753#listItem","position":3,"name":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/firma-invitada#listItem","name":"Firma invitada"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization","name":"microbichitos","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia","name":"Miguel Vicente","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/16a28c898ae8ba47d98faea83963583a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel Vicente"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753","name":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter - microbichitos","description":"Moselio Schaechter, Elio para los amigos, naci\u00f3 en Mil\u00e1n emigrando con sus padres, jud\u00edos polacos, a El Ecuador y finalmente a los Estados Unidos doctor\u00e1ndose en la Universidad de Pennsylvania. Como posdoctoral en Dinamarca, dirigido por Ole Maal\u00f8e, investig\u00f3 la composici\u00f3n de la bacteria Salmonella cuando crece, en particular los detalles referentes a la s\u00edntesis","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/author\/microbiologia#author"},"datePublished":"2007-12-11T22:48:00+01:00","dateModified":"2010-01-27T01:49:21+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/","name":"microbichitos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"microbichitos -","og:type":"article","og:title":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter - microbichitos","og:description":"Moselio Schaechter, Elio para los amigos, naci\u00f3 en Mil\u00e1n emigrando con sus padres, jud\u00edos polacos, a El Ecuador y finalmente a los Estados Unidos doctor\u00e1ndose en la Universidad de Pennsylvania. Como posdoctoral en Dinamarca, dirigido por Ole Maal\u00f8e, investig\u00f3 la composici\u00f3n de la bacteria Salmonella cuando crece, en particular los detalles referentes a la s\u00edntesis","og:url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753","og:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png","article:published_time":"2007-12-11T22:48:00+00:00","article:modified_time":"2010-01-27T00:49:21+00:00","twitter:card":"summary","twitter:title":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter - microbichitos","twitter:description":"Moselio Schaechter, Elio para los amigos, naci\u00f3 en Mil\u00e1n emigrando con sus padres, jud\u00edos polacos, a El Ecuador y finalmente a los Estados Unidos doctor\u00e1ndose en la Universidad de Pennsylvania. Como posdoctoral en Dinamarca, dirigido por Ole Maal\u00f8e, investig\u00f3 la composici\u00f3n de la bacteria Salmonella cuando crece, en particular los detalles referentes a la s\u00edntesis","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"80753","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 15:45:21","updated":"2026-05-29 22:56:45","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/firma-invitada\" title=\"Firma invitada\">Firma invitada<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia"},{"label":"Firma invitada","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/category\/firma-invitada"},{"label":"\u00bfQue es la Microbiolog\u00eda? por Moselio Schaechter","link":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/2007\/12\/11\/80753"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/80753"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/comments?post=80753"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/80753\/revisions"}],"predecessor-version":[{"id":130676,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/posts\/80753\/revisions\/130676"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/media?parent=80753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/categories?post=80753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/microbiologia\/wp-json\/wp\/v2\/tags?post=80753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}