{"id":102489,"date":"2008-10-03T05:56:00","date_gmt":"2008-10-03T05:56:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/openaccess\/archive\/2008\/10\/03\/102489.aspx"},"modified":"2008-10-03T05:56:00","modified_gmt":"2008-10-03T05:56:00","slug":"la-comision-europea-lanza-un-proyecto-piloto-de-acceso-abierto-bajo-el-7pm","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489","title":{"rendered":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM"},"content":{"rendered":"<h2><i><span style=\"font-size: 13.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-weight: normal;\">El acceso r\u00e1pido y fiable a los resultados de lainvestigaci\u00f3n, especialmente a trav\u00e9s de Internet, puede impulsar lainnovaci\u00f3n, promover los descubrimientos cient\u00edficos y apoyar el desarrollo deuna fuerte econom\u00eda basada en el conocimiento. La Comisi\u00f3n Europea desea velarpor que los resultados de la investigaci\u00f3n que financia al amparo del 7\u00baprograma marco de investigaci\u00f3n de la UE (7\u00ba PM) con m\u00e1s de 50&nbsp;000millones de euros en el per\u00edodo comprendido entre 2007 y 2013 se difundan tanamplia y eficazmente como sea posible para garantizar su m\u00e1ximo aprovechamientoy efecto en el mundo de la investigaci\u00f3n y fuera de \u00e9l. La Comisi\u00f3n ha puestoen marcha un proyecto piloto que facilitar\u00e1 un acceso en l\u00ednea sinrestricciones a los resultados de la investigaci\u00f3n financiada por la UE,principalmente a los art\u00edculos de investigaci\u00f3n aparecidos en publicaciones conrevisi\u00f3n por colegas independientes, tras un per\u00edodo de retenci\u00f3n de entre seisy doce meses. Este proyecto piloto cubrir\u00e1 alrededor del 20&nbsp;% delpresupuesto del 7\u00ba PM en \u00e1mbitos tales como la salud, la energ\u00eda, el medioambiente, las ciencias sociales y las tecnolog\u00edas de la informaci\u00f3n y lascomunicaciones. <\/span><\/i><span style=\"font-size: 13.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;;\"><o:p><\/o:p><\/span><\/h2>\n<p><\/p>\n<p><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\"><a href=\"http:\/\/erc.europa.eu\/pdf\/ScC_Guidelines_Open_Access_revised_Dec07_FINAL.pdf\"><\/a><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\"><o:p>&nbsp;<\/o:p><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\">JanezPotocnik, Comisario comunitario de Ciencia e Investigaci\u00f3n, ha declarado losiguiente: \u00ab<i>Un acceso<\/i> <i>f\u00e1cil y gratuito a los conocimientos m\u00e1savanzados en \u00e1mbitos estrat\u00e9gicos es crucial para la competitividad de lainvestigaci\u00f3n comunitaria. Este proyecto piloto de libre acceso constituye unpaso importante hacia la realizaci\u00f3n de la \u00abquinta libertad\u00bb<\/i>, <i>la librecirculaci\u00f3n de los conocimientos entre los Estados miembros, losinvestigadores, la industria y el p\u00fablico en general<\/i>. <i>Adem\u00e1s, es unajusta compensaci\u00f3n a la poblaci\u00f3n por una investigaci\u00f3n financiada con eldinero de la UE<\/i>\u00bb<i>.<\/i><o:p><\/o:p><\/span><\/p>\n<p><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\">VivianeReding, Comisaria comunitaria de Sociedad de la Informaci\u00f3n y Medios deComunicaci\u00f3n, ha declarado lo siguiente: \u00ab<i>El r\u00e1pido desarrollo de lastecnolog\u00edas digitales ofrece a los investigadores posibilidades sin precedentesde intercambio oportuno y eficaz de informaci\u00f3n. Nuestro nuevo proyecto pilotoaprovechar\u00e1 ese potencial, facilitando as\u00ed a los investigadores, las empresas ylos responsables pol\u00edticos abordar desaf\u00edos mundiales como el cambio clim\u00e1ticogracias al acceso a la investigaci\u00f3n m\u00e1s reciente. Me congratulo especialmentede que los editores cient\u00edficos hayan empezado a adoptar gradualmente nuevos m\u00e9todosde difusi\u00f3n y que colaboren con los investigadores en materia de libre acceso.Han aportado elementos valiosos a la Comisi\u00f3n sobre estos temas, que hanservido para elaborar el proyecto piloto. Esto permitir\u00e1 una coexistenciabeneficiosa para ambas partes que potencie al m\u00e1ximo los efectos del libreacceso a la investigaci\u00f3n financiada por el sector p\u00fablico dejando sitio a losmodelos editoriales basados en la financiaci\u00f3n privada<\/i>\u00bb<i>. <\/i><o:p><\/o:p><\/span><\/p>\n<p><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\">Elproyecto piloto de libre acceso de la Comisi\u00f3n, v\u00e1lido hasta el final del 7\u00baPM, tiene por objeto velar por que los resultados de la investigaci\u00f3nfinanciada por la UE se pongan progresivamente a disposici\u00f3n de todos. Serequerir\u00e1 que los beneficiarios de subvenciones pongan en un archivo en l\u00edneasus art\u00edculos de investigaci\u00f3n revisados por colegas o sus manuscritos finalesresultado de sus proyectos del 7\u00ba PM. Tambi\u00e9n tendr\u00e1n que hacer todo lo posiblepara facilitar el libre acceso a esos art\u00edculos en el plazo de seis o docemeses desde su publicaci\u00f3n, dependiendo del campo de investigaci\u00f3n. Esteper\u00edodo de retenci\u00f3n permitir\u00e1 a los editores cient\u00edficos obtener unrendimiento por el capital invertido. <o:p><\/o:p><\/span><\/p>\n<p><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\">Ellibre acceso a los art\u00edculos de investigaci\u00f3n, que antes solo se pod\u00edanconseguir suscribi\u00e9ndose a las publicaciones, puede contribuir a aumentar laincidencia de la inversi\u00f3n comunitaria en investigaci\u00f3n y desarrollo, cifradaen 50&nbsp;000 millones de euros, y evitar las p\u00e9rdidas de tiempo y de recursosvaliosos debido a investigaciones duplicadas. Con un acceso a un surtido dedocumentaci\u00f3n m\u00e1s amplio, los investigadores podr\u00e1n aprovechar estosconocimientos para hacer avanzar su propio trabajo. Las peque\u00f1as y medianasempresas y los empresarios tambi\u00e9n podr\u00e1n aprovechar el mejor acceso a los\u00faltimos avances de la investigaci\u00f3n para acelerar la comercializaci\u00f3n y lainnovaci\u00f3n. <o:p><\/o:p><\/span><\/p>\n<p><b><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\">Antecedentes<\/span><\/b><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\"><o:p><\/o:p><\/span><\/p>\n<p><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\">Elproyecto piloto de libre acceso puesto en marcha hoy se anunci\u00f3 en laComunicaci\u00f3n de febrero de 2007 de la Comisi\u00f3n Europea sobre la informaci\u00f3ncient\u00edfica en la era digital: acceso, difusi\u00f3n y preservaci\u00f3n (<a href=\"http:\/\/europa.eu\/rapid\/pressReleasesAction.do?reference=IP\/07\/190&amp;format=HTML&amp;aged=0&amp;language=EN&amp;guiLanguage=en\">IP\/07\/190<\/a>).A ra\u00edz de esta Comunicaci\u00f3n, el Consejo de noviembre de 2007 de ministros deInvestigaci\u00f3n de la UE invit\u00f3 a la Comisi\u00f3n a experimentar con el libre accesoen el 7\u00ba PM. <o:p><\/o:p><\/span><\/p>\n<p><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\">Desde2006, la Comisi\u00f3n ha organizado amplias consultas a las partes interesadassobre las pol\u00edticas de libre acceso, incluida una conferencia de alto nivel delas partes interesadas, con unos 500 participantes, en febrero de 2007. <o:p><\/o:p><\/span><\/p>\n<p><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\">Muchosorganismos de financiaci\u00f3n nacionales, por ejemplo Wellcome Trust en el ReinoUnido o los institutos nacionales de sanidad de los EE&nbsp;UU ya tienen normassobre libre acceso. El Consejo Cient\u00edfico del Consejo Europeo de Investigaci\u00f3nadopt\u00f3 sus directrices sobre el libre acceso en diciembre de 2007. <o:p><\/o:p><\/span><\/p>\n<p>Para acceder a <a href=\"http:\/\/ec.europa.eu\/research\/science-society\/index.cfm?fuseaction=public.topic&amp;id=1680\">toda la informaci\u00f3n<\/a><\/p>\n<p><span style=\"font-size: 9.5pt; font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; color: rgb(0, 51, 153);\"><a href=\"http:\/\/erc.europa.eu\/pdf\/ScC_Guidelines_Open_Access_revised_Dec07_FINAL.pdf\"><\/a><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\"><o:p>&nbsp;<\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acceso r\u00e1pido y fiable a los resultados de lainvestigaci\u00f3n, especialmente a trav\u00e9s de Internet, puede impulsar lainnovaci\u00f3n, promover los descubrimientos cient\u00edficos y apoyar el desarrollo deuna fuerte econom\u00eda basada en el conocimiento. La Comisi\u00f3n Europea desea velarpor que los resultados de la investigaci\u00f3n que financia al amparo del 7\u00baprograma marco de investigaci\u00f3n de la UE (7\u00ba PM) con m\u00e1s de 50&nbsp;000millones de euros en el per\u00edodo comprendido entre 2007 y 2013 se difundan tanamplia y eficazmente como sea posible para garantizar su m\u00e1ximo aprovechamientoy efecto en el mundo de la investigaci\u00f3n y fuera de \u00e9l. La Comisi\u00f3n ha puestoen\u2026<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El acceso r\u00e1pido y fiable a los resultados de lainvestigaci\u00f3n, especialmente a trav\u00e9s de Internet, puede impulsar lainnovaci\u00f3n, promover los descubrimientos cient\u00edficos y apoyar el desarrollo deuna fuerte econom\u00eda basada en el conocimiento. La Comisi\u00f3n Europea desea velarpor que los resultados de la investigaci\u00f3n que financia al amparo del 7\u00baprograma marco de investigaci\u00f3n de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Alicia L\u00f3pez Medina\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Open Access - acceso abierto a la informaci\u00f3n cient\u00edfica\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM - Open Access\" \/>\n\t\t<meta property=\"og:description\" content=\"El acceso r\u00e1pido y fiable a los resultados de lainvestigaci\u00f3n, especialmente a trav\u00e9s de Internet, puede impulsar lainnovaci\u00f3n, promover los descubrimientos cient\u00edficos y apoyar el desarrollo deuna fuerte econom\u00eda basada en el conocimiento. La Comisi\u00f3n Europea desea velarpor que los resultados de la investigaci\u00f3n que financia al amparo del 7\u00baprograma marco de investigaci\u00f3n de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-10-03T05:56:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2008-10-03T05:56:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM - Open Access\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El acceso r\u00e1pido y fiable a los resultados de lainvestigaci\u00f3n, especialmente a trav\u00e9s de Internet, puede impulsar lainnovaci\u00f3n, promover los descubrimientos cient\u00edficos y apoyar el desarrollo deuna fuerte econom\u00eda basada en el conocimiento. La Comisi\u00f3n Europea desea velarpor que los resultados de la investigaci\u00f3n que financia al amparo del 7\u00baprograma marco de investigaci\u00f3n de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489#blogposting\",\"name\":\"La Comisi\\u00f3n Europea lanza un proyecto piloto de \\u00abacceso abierto\\u00bb bajo el 7PM - Open Access\",\"headline\":\"La Comisi\\u00f3n Europea lanza un proyecto piloto de \\u00abacceso abierto\\u00bb bajo el 7PM\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2008-10-03T05:56:00+01:00\",\"dateModified\":\"2008-10-03T05:56:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489#listItem\",\"name\":\"La Comisi\\u00f3n Europea lanza un proyecto piloto de \\u00abacceso abierto\\u00bb bajo el 7PM\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489#listItem\",\"position\":3,\"name\":\"La Comisi\\u00f3n Europea lanza un proyecto piloto de \\u00abacceso abierto\\u00bb bajo el 7PM\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\",\"name\":\"Open Access\",\"description\":\"acceso abierto a la informaci\\u00f3n cient\\u00edfica\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess\",\"name\":\"Alicia L\\u00f3pez Medina\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daf38d7daa39c609bcb4698025c47a2d?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Alicia L\\u00f3pez Medina\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489\",\"name\":\"La Comisi\\u00f3n Europea lanza un proyecto piloto de \\u00abacceso abierto\\u00bb bajo el 7PM - Open Access\",\"description\":\"El acceso r\\u00e1pido y fiable a los resultados de lainvestigaci\\u00f3n, especialmente a trav\\u00e9s de Internet, puede impulsar lainnovaci\\u00f3n, promover los descubrimientos cient\\u00edficos y apoyar el desarrollo deuna fuerte econom\\u00eda basada en el conocimiento. La Comisi\\u00f3n Europea desea velarpor que los resultados de la investigaci\\u00f3n que financia al amparo del 7\\u00baprograma marco de investigaci\\u00f3n de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/10\\\/03\\\/102489#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"datePublished\":\"2008-10-03T05:56:00+01:00\",\"dateModified\":\"2008-10-03T05:56:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/\",\"name\":\"Open Access\",\"description\":\"acceso abierto a la informaci\\u00f3n cient\\u00edfica\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM - Open Access","description":"El acceso r\u00e1pido y fiable a los resultados de lainvestigaci\u00f3n, especialmente a trav\u00e9s de Internet, puede impulsar lainnovaci\u00f3n, promover los descubrimientos cient\u00edficos y apoyar el desarrollo deuna fuerte econom\u00eda basada en el conocimiento. La Comisi\u00f3n Europea desea velarpor que los resultados de la investigaci\u00f3n que financia al amparo del 7\u00baprograma marco de investigaci\u00f3n de la","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489#blogposting","name":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM - Open Access","headline":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#articleImage","width":217,"height":72},"datePublished":"2008-10-03T05:56:00+01:00","dateModified":"2008-10-03T05:56:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/openaccess","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489#listItem","name":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489#listItem","position":3,"name":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization","name":"Open Access","description":"acceso abierto a la informaci\u00f3n cient\u00edfica","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess","name":"Alicia L\u00f3pez Medina","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/daf38d7daa39c609bcb4698025c47a2d?s=96&d=mm&r=g","width":96,"height":96,"caption":"Alicia L\u00f3pez Medina"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489","name":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM - Open Access","description":"El acceso r\u00e1pido y fiable a los resultados de lainvestigaci\u00f3n, especialmente a trav\u00e9s de Internet, puede impulsar lainnovaci\u00f3n, promover los descubrimientos cient\u00edficos y apoyar el desarrollo deuna fuerte econom\u00eda basada en el conocimiento. La Comisi\u00f3n Europea desea velarpor que los resultados de la investigaci\u00f3n que financia al amparo del 7\u00baprograma marco de investigaci\u00f3n de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"datePublished":"2008-10-03T05:56:00+01:00","dateModified":"2008-10-03T05:56:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/","name":"Open Access","description":"acceso abierto a la informaci\u00f3n cient\u00edfica","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Open Access - acceso abierto a la informaci\u00f3n cient\u00edfica","og:type":"article","og:title":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM - Open Access","og:description":"El acceso r\u00e1pido y fiable a los resultados de lainvestigaci\u00f3n, especialmente a trav\u00e9s de Internet, puede impulsar lainnovaci\u00f3n, promover los descubrimientos cient\u00edficos y apoyar el desarrollo deuna fuerte econom\u00eda basada en el conocimiento. La Comisi\u00f3n Europea desea velarpor que los resultados de la investigaci\u00f3n que financia al amparo del 7\u00baprograma marco de investigaci\u00f3n de la","og:url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489","og:image":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","article:published_time":"2008-10-03T05:56:00+00:00","article:modified_time":"2008-10-03T05:56:00+00:00","twitter:card":"summary","twitter:title":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM - Open Access","twitter:description":"El acceso r\u00e1pido y fiable a los resultados de lainvestigaci\u00f3n, especialmente a trav\u00e9s de Internet, puede impulsar lainnovaci\u00f3n, promover los descubrimientos cient\u00edficos y apoyar el desarrollo deuna fuerte econom\u00eda basada en el conocimiento. La Comisi\u00f3n Europea desea velarpor que los resultados de la investigaci\u00f3n que financia al amparo del 7\u00baprograma marco de investigaci\u00f3n de la","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"102489","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-09 03:18:09","updated":"2024-03-13 18:57:31","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general"},{"label":"La Comisi\u00f3n Europea lanza un proyecto piloto de \u00abacceso abierto\u00bb bajo el 7PM","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/10\/03\/102489"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts\/102489"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/comments?post=102489"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts\/102489\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/media?parent=102489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/categories?post=102489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/tags?post=102489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}