{"id":115702,"date":"2009-04-02T04:41:00","date_gmt":"2009-04-02T04:41:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/openaccess\/archive\/2009\/04\/02\/115702.aspx"},"modified":"2009-04-02T04:41:00","modified_gmt":"2009-04-02T04:41:00","slug":"el-progreso-del-open-access","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702","title":{"rendered":"El progreso del Open Access"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\">El crecimiento del acceso abiertoeste \u00faltimo trimestre ha sido espectacular, tanto en el n\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\u00e1s rese\u00f1able, en pol\u00edticas deacceso abierto.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">El Directorio de Revistas OA (<a href=\"http:\/\/www.doaj.org\/\">DOAJ<\/a>) est\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\u00famero de la mayor editorial. DOAJ est\u00e1 creciendo a raz\u00f3n de 2 t\u00edtulos al d\u00eda. <a href=\"http:\/\/www.opendoar.org\/\">OpenDOAR<\/a> (el directorio de archivos deacceso abierto internacional) indiza ya 1.373 repositorios, con un incrementode alrededor de 70 este trimestre. <a href=\"http:\/\/www.scientificcommons.org\/\">ScientificCommons<\/a> incluye ya 26 millones de documentos, con un incremento de 119(22%) este trimestre. 663 revistas est\u00e1n participando voluntariamente en <b><a href=\"http:\/\/www.pubmedcentral.nih.gov\/\">PubMedCentral<\/a><\/b>, con unincremento de 119 (22%) este trimestre. 447 revistas son accesibles gratuitamentedesde PubMedCentral, un incremento de 29 (7%) este trimestre. Hay 11 pol\u00edticasnuevas de acceso abierto, de un total de 73 publicadas en todo el mundo (<a href=\"http:\/\/www.eprints.org\/openaccess\/policysignup\/\">ROARMAP<\/a>)<\/p>\n<p class=\"MsoNormal\">Pod\u00e9is leer la noticia completa (en ingl\u00e9s) <a href=\"http:\/\/poeticeconomics.blogspot.com\/2009\/03\/dramatic-growth-of-open-access-march-31.html\">aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El crecimiento del acceso abiertoeste \u00faltimo trimestre ha sido espectacular, tanto en el n\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\u00e1s rese\u00f1able, en pol\u00edticas deacceso abierto. El Directorio de Revistas OA (DOAJ) est\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\u00famero de la mayor editorial. DOAJ est\u00e1 creciendo a raz\u00f3n de 2 t\u00edtulos al d\u00eda. OpenDOAR (el directorio de archivos deacceso abierto internacional) indiza ya 1.373 repositorios, con un incrementode alrededor de 70 este trimestre. ScientificCommons incluye ya 26 millones de documentos, con un incremento de 119(22%) este\u2026<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El crecimiento del acceso abiertoeste \u00faltimo trimestre ha sido espectacular, tanto en el n\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\u00e1s rese\u00f1able, en pol\u00edticas deacceso abierto. El Directorio de Revistas OA (DOAJ) est\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\u00famero de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Alicia L\u00f3pez Medina\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Open Access - acceso abierto a la informaci\u00f3n cient\u00edfica\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El progreso del Open Access - Open Access\" \/>\n\t\t<meta property=\"og:description\" content=\"El crecimiento del acceso abiertoeste \u00faltimo trimestre ha sido espectacular, tanto en el n\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\u00e1s rese\u00f1able, en pol\u00edticas deacceso abierto. El Directorio de Revistas OA (DOAJ) est\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\u00famero de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2009-04-02T04:41:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2009-04-02T04:41:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El progreso del Open Access - Open Access\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El crecimiento del acceso abiertoeste \u00faltimo trimestre ha sido espectacular, tanto en el n\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\u00e1s rese\u00f1able, en pol\u00edticas deacceso abierto. El Directorio de Revistas OA (DOAJ) est\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\u00famero de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702#blogposting\",\"name\":\"El progreso del Open Access - Open Access\",\"headline\":\"El progreso del Open Access\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2009-04-02T04:41:00+01:00\",\"dateModified\":\"2009-04-02T04:41:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702#listItem\",\"name\":\"El progreso del Open Access\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702#listItem\",\"position\":3,\"name\":\"El progreso del Open Access\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\",\"name\":\"Open Access\",\"description\":\"acceso abierto a la informaci\\u00f3n cient\\u00edfica\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess\",\"name\":\"Alicia L\\u00f3pez Medina\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daf38d7daa39c609bcb4698025c47a2d?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Alicia L\\u00f3pez Medina\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702\",\"name\":\"El progreso del Open Access - Open Access\",\"description\":\"El crecimiento del acceso abiertoeste \\u00faltimo trimestre ha sido espectacular, tanto en el n\\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\\u00e1s rese\\u00f1able, en pol\\u00edticas deacceso abierto. El Directorio de Revistas OA (DOAJ) est\\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\\u00famero de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2009\\\/04\\\/02\\\/115702#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"datePublished\":\"2009-04-02T04:41:00+01:00\",\"dateModified\":\"2009-04-02T04:41:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/\",\"name\":\"Open Access\",\"description\":\"acceso abierto a la informaci\\u00f3n cient\\u00edfica\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El progreso del Open Access - Open Access","description":"El crecimiento del acceso abiertoeste \u00faltimo trimestre ha sido espectacular, tanto en el n\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\u00e1s rese\u00f1able, en pol\u00edticas deacceso abierto. El Directorio de Revistas OA (DOAJ) est\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\u00famero de la","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702#blogposting","name":"El progreso del Open Access - Open Access","headline":"El progreso del Open Access","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#articleImage","width":217,"height":72},"datePublished":"2009-04-02T04:41:00+01:00","dateModified":"2009-04-02T04:41:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/openaccess","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702#listItem","name":"El progreso del Open Access"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702#listItem","position":3,"name":"El progreso del Open Access","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization","name":"Open Access","description":"acceso abierto a la informaci\u00f3n cient\u00edfica","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess","name":"Alicia L\u00f3pez Medina","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/daf38d7daa39c609bcb4698025c47a2d?s=96&d=mm&r=g","width":96,"height":96,"caption":"Alicia L\u00f3pez Medina"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702","name":"El progreso del Open Access - Open Access","description":"El crecimiento del acceso abiertoeste \u00faltimo trimestre ha sido espectacular, tanto en el n\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\u00e1s rese\u00f1able, en pol\u00edticas deacceso abierto. El Directorio de Revistas OA (DOAJ) est\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\u00famero de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"datePublished":"2009-04-02T04:41:00+01:00","dateModified":"2009-04-02T04:41:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/","name":"Open Access","description":"acceso abierto a la informaci\u00f3n cient\u00edfica","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Open Access - acceso abierto a la informaci\u00f3n cient\u00edfica","og:type":"article","og:title":"El progreso del Open Access - Open Access","og:description":"El crecimiento del acceso abiertoeste \u00faltimo trimestre ha sido espectacular, tanto en el n\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\u00e1s rese\u00f1able, en pol\u00edticas deacceso abierto. El Directorio de Revistas OA (DOAJ) est\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\u00famero de la","og:url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702","og:image":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","article:published_time":"2009-04-02T04:41:00+00:00","article:modified_time":"2009-04-02T04:41:00+00:00","twitter:card":"summary","twitter:title":"El progreso del Open Access - Open Access","twitter:description":"El crecimiento del acceso abiertoeste \u00faltimo trimestre ha sido espectacular, tanto en el n\u00famero de revistas enacceso abierto, archivos abiertos y, lo que es m\u00e1s rese\u00f1able, en pol\u00edticas deacceso abierto. El Directorio de Revistas OA (DOAJ) est\u00e1 alcanzando un hito importante, 4.000revistas completamente de acceso abierto (nada de embargo), lo cual duplica eln\u00famero de la","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"115702","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-13 16:39:17","updated":"2024-03-13 18:59:11","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl progreso del Open Access\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general"},{"label":"El progreso del Open Access","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2009\/04\/02\/115702"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts\/115702"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/comments?post=115702"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts\/115702\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/media?parent=115702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/categories?post=115702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/tags?post=115702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}