{"id":39893,"date":"2006-09-06T03:54:00","date_gmt":"2006-09-06T03:54:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/openaccess\/archive\/2006\/09\/06\/39893.aspx"},"modified":"2006-09-06T03:54:00","modified_gmt":"2006-09-06T03:54:00","slug":"un-encuentro-en-la-era-digital","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893","title":{"rendered":"Un encuentro en la era digital"},"content":{"rendered":"<p>Alicia L\u00f3pez Medina<\/p>\n<p>La red de bibliotecas universitarias espa\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\u00e1n y discutir\u00e1n las necesidades de la e-ciencia, la ense\u00f1anza en el nuevo espacio europeo de educaci\u00f3n superior y la convergencia europea en relaci\u00f3n con los contenidos y los servicios digitales de informaci\u00f3n. Tambi\u00e9n hablaremos de la evaluaci\u00f3n de los resultados cient\u00edficos en el entorno digital y de los aspectos legales en relaci\u00f3n con el acceso abierto a las publicaciones cient\u00edficas. Adem\u00e1s, se presentar\u00e1n los \u00faltimos proyectos de bibliotecas digitales.<\/p>\n<p>Estar\u00e1n presentes representantes de los distintos \u00e1mbitos implicados por lo que esperamos que esta sea una oportunidad para intercambiar ideas, comparar desarrollos y soluciones y ponerse al d\u00eda en las \u00faltimas direcciones en lo que se refiere al mundo de la informaci\u00f3n digital.<\/p>\n<p>Os invitamos a participar en nuestro<\/p>\n<p><a href=\"http:\/\/info-fp.uned.es\/biblioteca\/Workshop\/inicio.html\">VI Workshop REBIUN sobre proyectos digitales: las bibliotecas digitales en el espacio global compartido<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alicia L\u00f3pez Medina La red de bibliotecas universitarias espa\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\u00e1n y discutir\u00e1n las necesidades de la e-ciencia, la ense\u00f1anza en el nuevo espacio europeo de educaci\u00f3n superior y la convergencia europea en relaci\u00f3n con los contenidos y los servicios digitales de informaci\u00f3n. Tambi\u00e9n hablaremos de la evaluaci\u00f3n de los resultados cient\u00edficos en el entorno digital y de los aspectos legales en relaci\u00f3n con el acceso abierto a las publicaciones cient\u00edficas. Adem\u00e1s, se presentar\u00e1n los \u00faltimos proyectos de bibliotecas digitales. Estar\u00e1n presentes representantes de los distintos \u00e1mbitos implicados por lo que esperamos que\u2026<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Alicia L\u00f3pez Medina La red de bibliotecas universitarias espa\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\u00e1n y discutir\u00e1n las necesidades de la e-ciencia, la ense\u00f1anza en el nuevo espacio europeo de educaci\u00f3n superior y la convergencia europea en relaci\u00f3n con los contenidos y los servicios digitales de informaci\u00f3n. Tambi\u00e9n hablaremos de la evaluaci\u00f3n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Alicia L\u00f3pez Medina\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Open Access - acceso abierto a la informaci\u00f3n cient\u00edfica\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Un encuentro en la era digital - Open Access\" \/>\n\t\t<meta property=\"og:description\" content=\"Alicia L\u00f3pez Medina La red de bibliotecas universitarias espa\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\u00e1n y discutir\u00e1n las necesidades de la e-ciencia, la ense\u00f1anza en el nuevo espacio europeo de educaci\u00f3n superior y la convergencia europea en relaci\u00f3n con los contenidos y los servicios digitales de informaci\u00f3n. Tambi\u00e9n hablaremos de la evaluaci\u00f3n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-09-06T03:54:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-09-06T03:54:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Un encuentro en la era digital - Open Access\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Alicia L\u00f3pez Medina La red de bibliotecas universitarias espa\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\u00e1n y discutir\u00e1n las necesidades de la e-ciencia, la ense\u00f1anza en el nuevo espacio europeo de educaci\u00f3n superior y la convergencia europea en relaci\u00f3n con los contenidos y los servicios digitales de informaci\u00f3n. Tambi\u00e9n hablaremos de la evaluaci\u00f3n\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893#blogposting\",\"name\":\"Un encuentro en la era digital - Open Access\",\"headline\":\"Un encuentro en la era digital\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-09-06T03:54:00+01:00\",\"dateModified\":\"2006-09-06T03:54:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893#listItem\",\"name\":\"Un encuentro en la era digital\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893#listItem\",\"position\":3,\"name\":\"Un encuentro en la era digital\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\",\"name\":\"Open Access\",\"description\":\"acceso abierto a la informaci\\u00f3n cient\\u00edfica\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess\",\"name\":\"Alicia L\\u00f3pez Medina\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daf38d7daa39c609bcb4698025c47a2d?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Alicia L\\u00f3pez Medina\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893\",\"name\":\"Un encuentro en la era digital - Open Access\",\"description\":\"Alicia L\\u00f3pez Medina La red de bibliotecas universitarias espa\\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\\u00e1n y discutir\\u00e1n las necesidades de la e-ciencia, la ense\\u00f1anza en el nuevo espacio europeo de educaci\\u00f3n superior y la convergencia europea en relaci\\u00f3n con los contenidos y los servicios digitales de informaci\\u00f3n. Tambi\\u00e9n hablaremos de la evaluaci\\u00f3n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2006\\\/09\\\/06\\\/39893#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"datePublished\":\"2006-09-06T03:54:00+01:00\",\"dateModified\":\"2006-09-06T03:54:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/\",\"name\":\"Open Access\",\"description\":\"acceso abierto a la informaci\\u00f3n cient\\u00edfica\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Un encuentro en la era digital - Open Access","description":"Alicia L\u00f3pez Medina La red de bibliotecas universitarias espa\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\u00e1n y discutir\u00e1n las necesidades de la e-ciencia, la ense\u00f1anza en el nuevo espacio europeo de educaci\u00f3n superior y la convergencia europea en relaci\u00f3n con los contenidos y los servicios digitales de informaci\u00f3n. Tambi\u00e9n hablaremos de la evaluaci\u00f3n","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893#blogposting","name":"Un encuentro en la era digital - Open Access","headline":"Un encuentro en la era digital","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#articleImage","width":217,"height":72},"datePublished":"2006-09-06T03:54:00+01:00","dateModified":"2006-09-06T03:54:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/openaccess","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893#listItem","name":"Un encuentro en la era digital"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893#listItem","position":3,"name":"Un encuentro en la era digital","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization","name":"Open Access","description":"acceso abierto a la informaci\u00f3n cient\u00edfica","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess","name":"Alicia L\u00f3pez Medina","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/daf38d7daa39c609bcb4698025c47a2d?s=96&d=mm&r=g","width":96,"height":96,"caption":"Alicia L\u00f3pez Medina"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893","name":"Un encuentro en la era digital - Open Access","description":"Alicia L\u00f3pez Medina La red de bibliotecas universitarias espa\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\u00e1n y discutir\u00e1n las necesidades de la e-ciencia, la ense\u00f1anza en el nuevo espacio europeo de educaci\u00f3n superior y la convergencia europea en relaci\u00f3n con los contenidos y los servicios digitales de informaci\u00f3n. Tambi\u00e9n hablaremos de la evaluaci\u00f3n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"datePublished":"2006-09-06T03:54:00+01:00","dateModified":"2006-09-06T03:54:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/","name":"Open Access","description":"acceso abierto a la informaci\u00f3n cient\u00edfica","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Open Access - acceso abierto a la informaci\u00f3n cient\u00edfica","og:type":"article","og:title":"Un encuentro en la era digital - Open Access","og:description":"Alicia L\u00f3pez Medina La red de bibliotecas universitarias espa\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\u00e1n y discutir\u00e1n las necesidades de la e-ciencia, la ense\u00f1anza en el nuevo espacio europeo de educaci\u00f3n superior y la convergencia europea en relaci\u00f3n con los contenidos y los servicios digitales de informaci\u00f3n. Tambi\u00e9n hablaremos de la evaluaci\u00f3n","og:url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893","og:image":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","article:published_time":"2006-09-06T03:54:00+00:00","article:modified_time":"2006-09-06T03:54:00+00:00","twitter:card":"summary","twitter:title":"Un encuentro en la era digital - Open Access","twitter:description":"Alicia L\u00f3pez Medina La red de bibliotecas universitarias espa\u00f1olas -REBIUN-, organiza un Workshop en el que se presentar\u00e1n y discutir\u00e1n las necesidades de la e-ciencia, la ense\u00f1anza en el nuevo espacio europeo de educaci\u00f3n superior y la convergencia europea en relaci\u00f3n con los contenidos y los servicios digitales de informaci\u00f3n. Tambi\u00e9n hablaremos de la evaluaci\u00f3n","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"39893","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-11 04:12:14","updated":"2024-03-13 18:34:30","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUn encuentro en la era digital\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general"},{"label":"Un encuentro en la era digital","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2006\/09\/06\/39893"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts\/39893"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/comments?post=39893"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts\/39893\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/media?parent=39893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/categories?post=39893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/tags?post=39893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}