{"id":92938,"date":"2008-05-26T08:41:00","date_gmt":"2008-05-26T08:41:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/openaccess\/archive\/2008\/05\/26\/92938.aspx"},"modified":"2008-05-26T08:41:00","modified_gmt":"2008-05-26T08:41:00","slug":"editoriales-cientificas-universidades-open-access-un-dialogo-necesario-para-el-futuro-de-la-comunicacion-cientifica","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938","title":{"rendered":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica"},"content":{"rendered":"<p class=\"MsoBodyText\"><span style=\"font-size: 8pt;\">Elmodelo tradicional de publicaci\u00f3n cient\u00edfica (la publicaci\u00f3n en revistascient\u00edficas de reconocido prestigio) est\u00e1 siendo cuestionado fundamentalmentepor una cuesti\u00f3n econ\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\u00e1neoa la informaci\u00f3n, las revistas cient\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\u00e1s altos a este acceso. Frente a este modelotradicional han surgido otros modelos alternativos de comunicaci\u00f3n de losresultados de la investigaci\u00f3n cient\u00edfica bajo el<span style=\"\">&nbsp; <\/span>paraguas del movimiento \u201cOpen access\u201d. Estos modelos sonfundamentalmente las revistas de acceso abierto y los repositoriosinstitucionales.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 8pt;\"><!--[if !supportEmptyParas]-->&nbsp;<!--[endif]--><o:p><\/o:p>Ambos modelos se encuentran ahora en el centro de undebate sobre el<span style=\"\">&nbsp; <\/span>futuro de lacomunicaci\u00f3n cient\u00edfica en el mundo digital. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 8pt;\"><!--[if !supportEmptyParas]-->&nbsp;<!--[endif]--><o:p><\/o:p>Como contribuci\u00f3n a ese debate os propongo dosdocumentos que acaban de publicarse. Uno es la visi\u00f3n de los editorescomerciales (STM), otro la de las Universidades:<o:p><\/o:p><\/span><\/p>\n<p><!--more--><\/p>\n<p class=\"MsoBodyText3\">La Asociaci\u00f3n Internacional de editores cient\u00edficos,t\u00e9cnicos y m\u00e9dicos<span style=\"\">&nbsp; <\/span>(STM &#8211; InternationalAssociation of Scientific, Technical and Medical Publishers) acaba de publicar(4\/2008) un <a href=\"http:\/\/www.stm-assoc.org\/documents-statements-public-co\/2008.4%20Overview%20of%20STM%20Publishing%20%20Value%20to%20Research.pdf\">documento<\/a> en el que establece su postura en relaci\u00f3n con los nuevosmodelos de publicaci\u00f3n cient\u00edfica en \u201cOpen Access\u201d y defiende su papel en elproceso de la investigaci\u00f3n cient\u00edfica y el valor a\u00f1adido que aporta a susresultados.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 8pt;\"><!--[if !supportEmptyParas]--><!--[endif]--><o:p><\/o:p>El grupo de trabajo sobre \u201cOpen Acces\u201d de laAsociaci\u00f3n Europea de Universidades se reuni\u00f3 el d\u00eda 28 de Marzo en laUniversidad de Barcelona y como resultado ha publicado unas recomendaciones enlas que insta a las Universidades, las Conferencias de Rectores nacionales y laAsociaci\u00f3n Europea de Universidades a establecer pol\u00edticas Open access (atrav\u00e9s de la creaci\u00f3n de repositorios institucionales, mandatos, copyright yfinanciaci\u00f3n) que aseguren el acceso p\u00fablico a los resultados de lainvestigaci\u00f3n financiada con fondos p\u00fablicos para contrarrestar y buscarmodelos alternativos a la publicaci\u00f3n cient\u00edfica tradicional.<o:p><\/o:p><\/span><\/p>\n<pre wrap=\"\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.eua.be\/fileadmin\/user_upload\/files\/Policy_Positions\/Recommendations_Open_Access_adopted_by_the_EUA_Council_on_26th_of_March_2008_final.pdf\">http:\/\/www.eua.be\/fileadmin\/user_upload\/files\/<\/a><br><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.eua.be\/fileadmin\/user_upload\/files\/Policy_Positions\/Recommendations_Open_Access_adopted_by_the_EUA_Council_on_26th_of_March_2008_final.pdf\">Policy_Positions\/Recommendations_Open_Access_adopted_<\/a><br><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.eua.be\/fileadmin\/user_upload\/files\/Policy_Positions\/Recommendations_Open_Access_adopted_by_the_EUA_Council_on_26th_of_March_2008_final.pdf\">by_the_EUA_Council_on_26th_of_March_2008_final.pdf<\/a><\/pre>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 8pt;\"><!--[if !supportEmptyParas]--> Y una peque\u00f1a contribuci\u00f3n personal:<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoBodyText3\"><span style=\"font-size: 8pt;\"><!--[if !supportEmptyParas]-->&nbsp;<!--[endif]--><\/span>Siempre me ha parecido contradictorio el hecho de que unaorganizaci\u00f3n de investigaci\u00f3n (incluidas Universidades y Agencias definanciaci\u00f3n) defienda el acceso abierto a las publicaciones cient\u00edficas, creerepositorios institucionales, declare el mandato del auto-archivo y al mismotiempo considere que el \u00fanico resultado de la investigaci\u00f3n que va a tener encuenta como tal a efectos de evaluaci\u00f3n, promoci\u00f3n, sexenio y prestigio esaqu\u00e9l art\u00edculo o trabajo que se publique en alguna de esas revistas comercialescuyo modelo se est\u00e1 cuestionando. Es el propio sistema el que alimenta el poderde las revistas. Un art\u00edculo se valora no tanto como tal art\u00edculo (peer review)sino en cuanto que est\u00e1 contextualizado en una revista de prestigio. Todo elmundo quiere publicar en una revista de prestigio, por lo que cada vez \u00e9statendr\u00e1 m\u00e1s prestigio. \u00bfEs esto lo de \u201cla pescadilla que se muerde la cola?\u201d. Siuna Universidad o Agencia de financiaci\u00f3n obliga a un investigador a depositarsu trabajo en acceso abierto en alg\u00fan repositorio, pero al mismo tiempo leobliga tambi\u00e9n a publicarlo en una revista indizada por el ISI (por ejemplo) \u2013porque si no no lo tendr\u00e1 en cuenta-, tendr\u00e1 que pensar en la forma de pagarlo,porque, como dicen los editores, esto de la publicaci\u00f3n no es gratis. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elmodelo tradicional de publicaci\u00f3n cient\u00edfica (la publicaci\u00f3n en revistascient\u00edficas de reconocido prestigio) est\u00e1 siendo cuestionado fundamentalmentepor una cuesti\u00f3n econ\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\u00e1neoa la informaci\u00f3n, las revistas cient\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\u00e1s altos a este acceso. Frente a este modelotradicional han surgido otros modelos alternativos de comunicaci\u00f3n de losresultados de la investigaci\u00f3n cient\u00edfica bajo el&nbsp; paraguas del movimiento \u201cOpen access\u201d. Estos modelos sonfundamentalmente las revistas de acceso abierto y los repositoriosinstitucionales. &nbsp;Ambos modelos se encuentran ahora en el centro de undebate sobre el&nbsp;\u2026<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Elmodelo tradicional de publicaci\u00f3n cient\u00edfica (la publicaci\u00f3n en revistascient\u00edficas de reconocido prestigio) est\u00e1 siendo cuestionado fundamentalmentepor una cuesti\u00f3n econ\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\u00e1neoa la informaci\u00f3n, las revistas cient\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\u00e1s altos a este acceso. Frente a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Alicia L\u00f3pez Medina\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Open Access - acceso abierto a la informaci\u00f3n cient\u00edfica\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica - Open Access\" \/>\n\t\t<meta property=\"og:description\" content=\"Elmodelo tradicional de publicaci\u00f3n cient\u00edfica (la publicaci\u00f3n en revistascient\u00edficas de reconocido prestigio) est\u00e1 siendo cuestionado fundamentalmentepor una cuesti\u00f3n econ\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\u00e1neoa la informaci\u00f3n, las revistas cient\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\u00e1s altos a este acceso. Frente a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-05-26T08:41:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2008-05-26T08:41:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica - Open Access\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Elmodelo tradicional de publicaci\u00f3n cient\u00edfica (la publicaci\u00f3n en revistascient\u00edficas de reconocido prestigio) est\u00e1 siendo cuestionado fundamentalmentepor una cuesti\u00f3n econ\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\u00e1neoa la informaci\u00f3n, las revistas cient\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\u00e1s altos a este acceso. Frente a\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938#blogposting\",\"name\":\"Editoriales cient\\u00edficas, Universidades, open access: un di\\u00e1logo necesario para el futuro de la comunicaci\\u00f3n cient\\u00edfica - Open Access\",\"headline\":\"Editoriales cient\\u00edficas, Universidades, open access: un di\\u00e1logo necesario para el futuro de la comunicaci\\u00f3n cient\\u00edfica\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2008-05-26T08:41:00+01:00\",\"dateModified\":\"2008-05-26T08:41:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938#listItem\",\"name\":\"Editoriales cient\\u00edficas, Universidades, open access: un di\\u00e1logo necesario para el futuro de la comunicaci\\u00f3n cient\\u00edfica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938#listItem\",\"position\":3,\"name\":\"Editoriales cient\\u00edficas, Universidades, open access: un di\\u00e1logo necesario para el futuro de la comunicaci\\u00f3n cient\\u00edfica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\",\"name\":\"Open Access\",\"description\":\"acceso abierto a la informaci\\u00f3n cient\\u00edfica\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess\",\"name\":\"Alicia L\\u00f3pez Medina\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daf38d7daa39c609bcb4698025c47a2d?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Alicia L\\u00f3pez Medina\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938\",\"name\":\"Editoriales cient\\u00edficas, Universidades, open access: un di\\u00e1logo necesario para el futuro de la comunicaci\\u00f3n cient\\u00edfica - Open Access\",\"description\":\"Elmodelo tradicional de publicaci\\u00f3n cient\\u00edfica (la publicaci\\u00f3n en revistascient\\u00edficas de reconocido prestigio) est\\u00e1 siendo cuestionado fundamentalmentepor una cuesti\\u00f3n econ\\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\\u00e1neoa la informaci\\u00f3n, las revistas cient\\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\\u00e1s altos a este acceso. Frente a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/2008\\\/05\\\/26\\\/92938#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/author\\\/openaccess#author\"},\"datePublished\":\"2008-05-26T08:41:00+01:00\",\"dateModified\":\"2008-05-26T08:41:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/\",\"name\":\"Open Access\",\"description\":\"acceso abierto a la informaci\\u00f3n cient\\u00edfica\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/openaccess\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica - Open Access","description":"Elmodelo tradicional de publicaci\u00f3n cient\u00edfica (la publicaci\u00f3n en revistascient\u00edficas de reconocido prestigio) est\u00e1 siendo cuestionado fundamentalmentepor una cuesti\u00f3n econ\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\u00e1neoa la informaci\u00f3n, las revistas cient\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\u00e1s altos a este acceso. Frente a","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938#blogposting","name":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica - Open Access","headline":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#articleImage","width":217,"height":72},"datePublished":"2008-05-26T08:41:00+01:00","dateModified":"2008-05-26T08:41:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/openaccess","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938#listItem","name":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938#listItem","position":3,"name":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization","name":"Open Access","description":"acceso abierto a la informaci\u00f3n cient\u00edfica","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess","name":"Alicia L\u00f3pez Medina","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/daf38d7daa39c609bcb4698025c47a2d?s=96&d=mm&r=g","width":96,"height":96,"caption":"Alicia L\u00f3pez Medina"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938","name":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica - Open Access","description":"Elmodelo tradicional de publicaci\u00f3n cient\u00edfica (la publicaci\u00f3n en revistascient\u00edficas de reconocido prestigio) est\u00e1 siendo cuestionado fundamentalmentepor una cuesti\u00f3n econ\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\u00e1neoa la informaci\u00f3n, las revistas cient\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\u00e1s altos a este acceso. Frente a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/author\/openaccess#author"},"datePublished":"2008-05-26T08:41:00+01:00","dateModified":"2008-05-26T08:41:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/","name":"Open Access","description":"acceso abierto a la informaci\u00f3n cient\u00edfica","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Open Access - acceso abierto a la informaci\u00f3n cient\u00edfica","og:type":"article","og:title":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica - Open Access","og:description":"Elmodelo tradicional de publicaci\u00f3n cient\u00edfica (la publicaci\u00f3n en revistascient\u00edficas de reconocido prestigio) est\u00e1 siendo cuestionado fundamentalmentepor una cuesti\u00f3n econ\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\u00e1neoa la informaci\u00f3n, las revistas cient\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\u00e1s altos a este acceso. Frente a","og:url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938","og:image":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png","article:published_time":"2008-05-26T08:41:00+00:00","article:modified_time":"2008-05-26T08:41:00+00:00","twitter:card":"summary","twitter:title":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica - Open Access","twitter:description":"Elmodelo tradicional de publicaci\u00f3n cient\u00edfica (la publicaci\u00f3n en revistascient\u00edficas de reconocido prestigio) est\u00e1 siendo cuestionado fundamentalmentepor una cuesti\u00f3n econ\u00f3mica: mientras que Internet y la disponibilidad de lainformaci\u00f3n en formato digital ofrecen la oportunidad de un acceso instant\u00e1neoa la informaci\u00f3n, las revistas cient\u00edficas contrarrestan esta promesaimponiendo precios cada vez m\u00e1s altos a este acceso. Frente a","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"92938","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-12 10:40:08","updated":"2024-03-13 18:49:29","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEditoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/category\/general"},{"label":"Editoriales cient\u00edficas, Universidades, open access: un di\u00e1logo necesario para el futuro de la comunicaci\u00f3n cient\u00edfica","link":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/2008\/05\/26\/92938"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts\/92938"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/comments?post=92938"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/posts\/92938\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/media?parent=92938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/categories?post=92938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/openaccess\/wp-json\/wp\/v2\/tags?post=92938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}