{"id":50,"date":"2021-06-30T16:42:59","date_gmt":"2021-06-30T15:42:59","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/?p=50"},"modified":"2021-06-30T17:27:57","modified_gmt":"2021-06-30T16:27:57","slug":"escalas-y-acompanamientos-como-tejer-una-red-de-laboratorios-ciudadanos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/","title":{"rendered":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos?"},"content":{"rendered":"<p dir=\"ltr\"><strong>\u00bfC\u00f3mo generar proximidad en la distancia? \u00bfC\u00f3mo personalizar lo masivo de un curso? \u00bfC\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\u00e1cticas existentes en las instituciones?\u00a0<\/strong><\/p>\n<p>Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la Comunidad de Madrid. La propuesta es <strong>promover y apoyar la creaci\u00f3n de laboratorios ciudadanos, lugares donde personas diferentes (por sus saberes, or\u00edgenes, habilidades&#8230;) se puedan encontrar en torno a objetivos comunes<\/strong>. Espacios donde se producen aprendizajes, se desarrolla la experimentaci\u00f3n, se prototipa y ensaya haceres que tienen como fin \u00faltimo generar un impacto positivo, contribuir a la mejora social.<\/p>\n<p>Esto conecta directamente con el trabajo de la investigaci\u00f3n, centros de innovaci\u00f3n, universidades y de la propia Fundaci\u00f3n madri+d.<strong> Existe una gran diversidad de grupos de investigaci\u00f3n, docentes, unidades cient\u00edficas, instituciones como bibliotecas, museos o institutos que ya\u00a0 tienen un foco claro en hacer junto con la sociedad para que la transformaci\u00f3n tenga un impacto real y sostenido<\/strong>. Entidades que aspiran o incluso ya est\u00e1n operando -en parte- bajo l\u00f3gicas de laboratorio ciudadano.<\/p>\n<p dir=\"ltr\">El acompa\u00f1amiento inicial se ha orientado a reconocer a estas entidades cuyo inter\u00e9s se sustenta en abrir la instituci\u00f3n y explorar nuevas formas de hacer desde la participaci\u00f3n (ya sea entre diferentes agentes de la instituci\u00f3n o hacia afuera, con agentes de la sociedad).<\/p>\n<p>Ahora bien, impulsar espacios de este tipo constituye un reto en s\u00ed. Un reto complejo que se propone superar desde el conocimiento. Para ello, se invita al curso masivo <a href=\"https:\/\/curso2021.labsbibliotecarios.es\/\" target=\"_blank\"><strong><em>\u201cC\u00f3mo montar un laboratorio ciudadano y construir redes de colaboraci\u00f3n\u201d<\/em><\/strong><\/a>. Una apuesta por hacer extensivo y abrir pr\u00e1cticas ensayadas en momentos y lugares concretos.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/banner_laboratorios_ciudadanos2021Pagina.png\"><img decoding=\"async\" class=\"alignnone size-large wp-image-63\" title=\"banner_laboratorios_ciudadanos2021Pagina\" src=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/banner_laboratorios_ciudadanos2021Pagina-1024x413.png\" alt=\"\" width=\"720\" height=\"320\" \/><\/a><\/p>\n<p>Pero \u00bfpueden los videotutoriales y textos explicar los detalles y complejidades de las experiencias de laboratorio? \u00bfSon los foros herramientas suficientes para entablar conversaciones, compartir ideas, resolver dudas?<\/p>\n<p>Sin duda, estas son herramientas valiosas y muy necesarias, m\u00e1s en estos tiempos. Sin embargo, por s\u00ed solas no son suficientes para hacer lo general espec\u00edfico. <strong>La labor de acompa\u00f1amiento no ha sido s\u00f3lo guiar por los contenido del curso, sino, provocar espacios donde poner rostro y voz a las palabras escritas en hilos del foro<\/strong> y donde superar una formaci\u00f3n que, si bien es flexible, atomiza la participaci\u00f3n; en definitiva, se ha tratado de promover <strong>espacios de encuentro donde compartir inquietudes y dificultades, donde descubrir iniciativas y experiencias<\/strong> m\u00e1s all\u00e1 de los diferentes contextos desde donde cada persona hace la formaci\u00f3n.<\/p>\n<p dir=\"ltr\">A partir de <strong>tres encuentros abiertos a participantes de la Comunidad de Madrid <\/strong>realizados en colaboraci\u00f3n con los equipos de acompa\u00f1amiento de <a href=\"https:\/\/www.medialab-prado.es\/programas\/laboratorios-ciudadanos-distribuidos-innovacion-ciudadana-en-bibliotecas-y-otras\"><strong>Medialab Prado\u00a0<\/strong><\/a>se ha tratado de facilitar un conocimiento mayor de las motivaciones e intereses de los participantes, aclarar dudas y conceptos, o inspirar y aconsejar desde las experiencias ya existentes:<\/p>\n<p dir=\"ltr\"><strong>I Encuentro: Gymkhana colaborativa de los laboratorios ciudadanos<\/strong> (13 de mayo). <a href=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/Devoluci\u00f3n_sesi\u00f3n_130521.pdf\" target=\"_blank\">Documento resumen<\/a><\/p>\n<p dir=\"ltr\"><strong>II Encuentro: En busca de los laboratorios ciudadanos<\/strong>: un proyecto arqueol\u00f3gico donde queremos contar contigo para encontrar y reencantar tesoros ocultos (3 de junio) <a href=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/Devolucion_sesion_030621_1.pdf\" target=\"_blank\">Documento Resumen<\/a><\/p>\n<p dir=\"ltr\"><strong>III Encuentro: Intercambio de experiencias entre laboratorios ciudadanos<\/strong> (17 de junio) <a href=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/Devoluci\u00f3n_terceraSesion_170621_.pdf\" target=\"_blank\">Documento Resumen<\/a><\/p>\n<p style=\"text-align: center;\" dir=\"ltr\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/ii-Encuentro-online-participantes-CM.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-57\" title=\"ii Encuentro online participantes CM\" src=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/ii-Encuentro-online-participantes-CM.jpg\" alt=\"\" width=\"587\" height=\"282\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/ii-Encuentro-online-participantes-CM.jpg 587w, https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/ii-Encuentro-online-participantes-CM-300x144.jpg 300w\" sizes=\"(max-width: 587px) 100vw, 587px\" \/><\/a><\/p>\n<p dir=\"ltr\">Ahora nos encontramos en una siguiente fase del acompa\u00f1amiento. Una en la que ir situando estos conocimientos en la propia instituci\u00f3n e imbricar la pr\u00e1ctica de los laboratorios en los haceres propios. Un acompa\u00f1amiento m\u00e1s certero y cuidado que pretende propiciar los laboratorios que ser\u00e1n germen de la futura Red de Laboratorios Ciudadanos de la Comunidad de Madrid.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo generar proximidad en la distancia? \u00bfC\u00f3mo personalizar lo masivo de un curso? \u00bfC\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\u00e1cticas existentes en las instituciones?\u00a0 Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la Comunidad de Madrid. La propuesta es promover y apoyar la creaci\u00f3n de laboratorios ciudadanos, lugares donde personas diferentes (por sus saberes, or\u00edgenes, habilidades&#8230;) se puedan encontrar en torno a objetivos comunes. Espacios donde se producen aprendizajes, se desarrolla la experimentaci\u00f3n, se prototipa y ensaya haceres\u2026<\/p>\n","protected":false},"author":234,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[46724],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00bfC\u00f3mo generar proximidad en la distancia? \u00bfC\u00f3mo personalizar lo masivo de un curso? \u00bfC\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\u00e1cticas existentes en las instituciones? Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"redlaboratoriosciudadanoscm\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Red de Laboratorios Ciudadanos de la CM -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos? - Red de Laboratorios Ciudadanos de la CM\" \/>\n\t\t<meta property=\"og:description\" content=\"\u00bfC\u00f3mo generar proximidad en la distancia? \u00bfC\u00f3mo personalizar lo masivo de un curso? \u00bfC\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\u00e1cticas existentes en las instituciones? Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"217\" \/>\n\t\t<meta property=\"og:image:height\" content=\"72\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-06-30T15:42:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-06-30T16:27:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos? - Red de Laboratorios Ciudadanos de la CM\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u00bfC\u00f3mo generar proximidad en la distancia? \u00bfC\u00f3mo personalizar lo masivo de un curso? \u00bfC\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\u00e1cticas existentes en las instituciones? Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#blogposting\",\"name\":\"Escalas y acompa\\u00f1amientos: \\u00bfC\\u00f3mo tejer una red de laboratorios ciudadanos? - Red de Laboratorios Ciudadanos de la CM\",\"headline\":\"Escalas y acompa\\u00f1amientos: \\u00bfC\\u00f3mo tejer una red de laboratorios ciudadanos?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/author\\\/redlaboratoriosciudadanoscm\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/files\\\/2021\\\/06\\\/banner_laboratorios_ciudadanos2021Pagina-1024x413.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#articleImage\"},\"datePublished\":\"2021-06-30T16:42:59+01:00\",\"dateModified\":\"2021-06-30T17:27:57+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#webpage\"},\"articleSection\":\"laboratorios ciudadanos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/category\\\/laboratorios-ciudadanos\\\/#listItem\",\"name\":\"laboratorios ciudadanos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/category\\\/laboratorios-ciudadanos\\\/#listItem\",\"position\":2,\"name\":\"laboratorios ciudadanos\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/category\\\/laboratorios-ciudadanos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#listItem\",\"name\":\"Escalas y acompa\\u00f1amientos: \\u00bfC\\u00f3mo tejer una red de laboratorios ciudadanos?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#listItem\",\"position\":3,\"name\":\"Escalas y acompa\\u00f1amientos: \\u00bfC\\u00f3mo tejer una red de laboratorios ciudadanos?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/category\\\/laboratorios-ciudadanos\\\/#listItem\",\"name\":\"laboratorios ciudadanos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/#organization\",\"name\":\"Red de Laboratorios Ciudadanos de la CM\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/author\\\/redlaboratoriosciudadanoscm\\\/#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/author\\\/redlaboratoriosciudadanoscm\\\/\",\"name\":\"redlaboratoriosciudadanoscm\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e285493230f6e4e8f97584aa5afe6907?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"redlaboratoriosciudadanoscm\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/\",\"name\":\"Escalas y acompa\\u00f1amientos: \\u00bfC\\u00f3mo tejer una red de laboratorios ciudadanos? - Red de Laboratorios Ciudadanos de la CM\",\"description\":\"\\u00bfC\\u00f3mo generar proximidad en la distancia? \\u00bfC\\u00f3mo personalizar lo masivo de un curso? \\u00bfC\\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\\u00e1cticas existentes en las instituciones? Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/2021\\\/06\\\/30\\\/50\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/author\\\/redlaboratoriosciudadanoscm\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/author\\\/redlaboratoriosciudadanoscm\\\/#author\"},\"datePublished\":\"2021-06-30T16:42:59+01:00\",\"dateModified\":\"2021-06-30T17:27:57+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/\",\"name\":\"Red de Laboratorios Ciudadanos de la CM\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/redlaboratoriosciudadanoscm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos? - Red de Laboratorios Ciudadanos de la CM","description":"\u00bfC\u00f3mo generar proximidad en la distancia? \u00bfC\u00f3mo personalizar lo masivo de un curso? \u00bfC\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\u00e1cticas existentes en las instituciones? Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#blogposting","name":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos? - Red de Laboratorios Ciudadanos de la CM","headline":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/author\/redlaboratoriosciudadanoscm\/#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2021\/06\/banner_laboratorios_ciudadanos2021Pagina-1024x413.png","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#articleImage"},"datePublished":"2021-06-30T16:42:59+01:00","dateModified":"2021-06-30T17:27:57+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#webpage"},"articleSection":"laboratorios ciudadanos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/category\/laboratorios-ciudadanos\/#listItem","name":"laboratorios ciudadanos"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/category\/laboratorios-ciudadanos\/#listItem","position":2,"name":"laboratorios ciudadanos","item":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/category\/laboratorios-ciudadanos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#listItem","name":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#listItem","position":3,"name":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/category\/laboratorios-ciudadanos\/#listItem","name":"laboratorios ciudadanos"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/#organization","name":"Red de Laboratorios Ciudadanos de la CM","url":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/author\/redlaboratoriosciudadanoscm\/#author","url":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/author\/redlaboratoriosciudadanoscm\/","name":"redlaboratoriosciudadanoscm","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e285493230f6e4e8f97584aa5afe6907?s=96&d=mm&r=g","width":96,"height":96,"caption":"redlaboratoriosciudadanoscm"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/","name":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos? - Red de Laboratorios Ciudadanos de la CM","description":"\u00bfC\u00f3mo generar proximidad en la distancia? \u00bfC\u00f3mo personalizar lo masivo de un curso? \u00bfC\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\u00e1cticas existentes en las instituciones? Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/author\/redlaboratoriosciudadanoscm\/#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/author\/redlaboratoriosciudadanoscm\/#author"},"datePublished":"2021-06-30T16:42:59+01:00","dateModified":"2021-06-30T17:27:57+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/","name":"Red de Laboratorios Ciudadanos de la CM","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Red de Laboratorios Ciudadanos de la CM -","og:type":"article","og:title":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos? - Red de Laboratorios Ciudadanos de la CM","og:description":"\u00bfC\u00f3mo generar proximidad en la distancia? \u00bfC\u00f3mo personalizar lo masivo de un curso? \u00bfC\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\u00e1cticas existentes en las instituciones? Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la","og:url":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/","og:image":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2022\/02\/logo.png","og:image:width":217,"og:image:height":72,"article:published_time":"2021-06-30T15:42:59+00:00","article:modified_time":"2021-06-30T16:27:57+00:00","twitter:card":"summary","twitter:title":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos? - Red de Laboratorios Ciudadanos de la CM","twitter:description":"\u00bfC\u00f3mo generar proximidad en la distancia? \u00bfC\u00f3mo personalizar lo masivo de un curso? \u00bfC\u00f3mo conjugar las formas de hacer de los laboratorios ciudadanos con las pr\u00e1cticas existentes en las instituciones? Son algunas de las preguntas que nos toca hacernos a la hora de trabajar desde el equipo de la Red de Laboratorios Ciudadanos de la","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"50","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 11:19:45","updated":"2024-01-25 06:36:55","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/category\/laboratorios-ciudadanos\/\" title=\"laboratorios ciudadanos\">laboratorios ciudadanos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEscalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm"},{"label":"laboratorios ciudadanos","link":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/category\/laboratorios-ciudadanos\/"},{"label":"Escalas y acompa\u00f1amientos: \u00bfC\u00f3mo tejer una red de laboratorios ciudadanos?","link":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/2021\/06\/30\/50\/"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/posts\/50"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/users\/234"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":13,"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/posts\/50\/revisions"}],"predecessor-version":[{"id":69,"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/posts\/50\/revisions\/69"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/media?parent=50"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/categories?post=50"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/redlaboratoriosciudadanoscm\/wp-json\/wp\/v2\/tags?post=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}