{"id":133926,"date":"2021-03-26T10:46:36","date_gmt":"2021-03-26T09:46:36","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/remtavares\/?p=133926"},"modified":"2021-03-26T10:46:36","modified_gmt":"2021-03-26T09:46:36","slug":"obtencion-de-estruvita-a-partir-de-lixiviado-de-vertedero","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926","title":{"rendered":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero"},"content":{"rendered":"<p>La transici\u00f3n hacia una econom\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\u00f3n de los residuos, transform\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados de vertedero donde el contenido en nitr\u00f3geno puede ser utilizado como materia prima en la obtenci\u00f3n de estruvita.<\/p>\n<p>Investigadores del Departamento de Ingenier\u00eda Qu\u00edmica de la UAM han conseguido precipitar estruvita a partir de estos efluentes. La calidad de este s\u00f3lido y sus futuros usos como fertilizante obligan a llevar a cabo un tratamiento previo, preferiblemente con persulfato activado con temperatura, que permite reducir el contenido en materia org\u00e1nica y en metales. En esas condiciones, la estruvita que se obtiene cumple con los requerimientos que establece el RD 506\/2013 para su empleo como fertilizante.<\/p>\n<p><em>Departamento Ingenier\u00eda Qu\u00edmica. UAM<\/em><\/p>\n<p><!--more--><\/p>\n<p>La adopci\u00f3n de medidas encaminadas hacia una econom\u00eda circular han supuesto un cambio de paradigma en la gesti\u00f3n de los residuos, convirti\u00e9ndose, en parte, en fuentes de materias primas. Un caso bien conocido es la recuperaci\u00f3n del contenido en f\u00f3sforo de las aguas residuales urbanas mediante la precipitaci\u00f3n de estruvita (MgNH4PO4\u00b76H2O). Debido a su composici\u00f3n, este mineral presenta una elevada capacidad como fertilizante, aportando nutrientes esenciales para el crecimiento de las plantas y la mejora de las propiedades fisicoqu\u00edmicas del suelo.<\/p>\n<p>Los lixiviados de vertedero presentan altos contenidos en nitr\u00f3geno, lo que puede convertir a este residuo en una fuente potencial de uno de los elementos que, junto al Mg y al P, constituyen la estruvita. No obstante, la composici\u00f3n de este efluente (Tabla 1) que incluye una elevada carga org\u00e1nica, adem\u00e1s de la presencia de metales, puede afectar a la calidad final del producto, evitando la reutilizaci\u00f3n de la estruvita como fertilizante.<\/p>\n<p style=\"text-align: center;\"><strong>Tabla 1. <\/strong>Composici\u00f3n del lixiviado de vertedero.<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"9\" valign=\"top\" width=\"402\"><strong>Par\u00e1metros (mg(L)<\/strong><\/td>\n<td rowspan=\"2\" valign=\"top\" width=\"46\">\n<p align=\"left\"><strong>pH<\/strong><\/p>\n<\/td>\n<td rowspan=\"2\" valign=\"top\" width=\"118\">\n<p align=\"left\"><strong>Conductividad<\/strong><strong>\u00a0<\/strong><strong>(mS\/cm)<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"47\"><strong>COD<\/strong><\/td>\n<td valign=\"top\" width=\"44\"><strong>TOC<\/strong><\/td>\n<td valign=\"top\" width=\"48\"><strong>TN<\/strong><\/td>\n<td valign=\"top\" width=\"47\"><strong>Cl<\/strong><strong>&#8211;<\/strong><strong><\/strong><\/td>\n<td valign=\"top\" width=\"51\"><strong>SO<\/strong><strong>42-<\/strong><\/td>\n<td valign=\"top\" width=\"35\">\n<p align=\"left\"><strong>Ti<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"44\"><strong>Fe<\/strong><\/td>\n<td valign=\"top\" width=\"44\"><strong>Pb<\/strong><\/td>\n<td valign=\"top\" width=\"42\"><strong>Zn<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"47\">2610<\/td>\n<td valign=\"top\" width=\"44\">960<\/td>\n<td valign=\"top\" width=\"48\">1350<\/td>\n<td valign=\"top\" width=\"47\">1125<\/td>\n<td valign=\"top\" width=\"51\">280<\/td>\n<td valign=\"top\" width=\"35\">\n<p align=\"left\">0,1<\/p>\n<\/td>\n<td valign=\"top\" width=\"44\">0,18<\/td>\n<td valign=\"top\" width=\"44\">0,03<\/td>\n<td valign=\"top\" width=\"42\">0,28<\/td>\n<td valign=\"top\" width=\"46\">\n<p align=\"left\">8,3<\/p>\n<\/td>\n<td valign=\"top\" width=\"118\">4,6<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>En este estudio se eval\u00faa c\u00f3mo afecta un tratamiento previo del lixiviado, con persulfato activado t\u00e9rmicamente o FotoFenton, sobre el porcentaje de recuperaci\u00f3n de nitr\u00f3geno y la pureza de la estruvita. Hay que indicar que la temperatura necesaria para activar el persulfato se puede obtener a partir del biog\u00e1s generado en el propio vertedero o por intercambio de calor en el caso de disponer de una instalaci\u00f3n de incineraci\u00f3n de residuos s\u00f3lidos urbanos. En todos los casos se emplearon dos fuentes de Mg (MgCl2 y MgSO4) y NaH2PO4. 2H2O como fuente de P.<\/p>\n<p>Se ha trabajado con dos relaciones molares Mg:N:P (1: 1: 1, 1,5: 1: 1). Una vez dosificados los reactivos y ajustado el pH a 9 (adicionando NaOH 1M), la mezcla se agit\u00f3 a 200 rpm durante 15 min y se dej\u00f3 reposar durante 60 min para permitir la precipitaci\u00f3n de la estruvita. El precipitado se lav\u00f3 con agua destilada y se sec\u00f3 a temperatura ambiente. En la Figura 1 se muestran los porcentajes de nitr\u00f3geno recuperado para cada caso. Se puede observar como el pretratamiento del lixiviado y que permite eliminar hasta el 90% del contenido en materia org\u00e1nica (empleando la cantidad estequiom\u00e9trica de H2O2 o PS), se traduce en una mayor recuperaci\u00f3n de nitr\u00f3geno, que alcanza valores superiores al 95% cuando se emplean relaciones Mg:N:P de 1,5:1:1.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2021\/03\/UAM_Marzo_21.jpg2.png\"><img decoding=\"async\" class=\"aligncenter  wp-image-133929\" title=\"UAM_Marzo_21.jpg\" src=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2021\/03\/UAM_Marzo_21.jpg2.png\" alt=\"\" width=\"562\" height=\"375\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2021\/03\/UAM_Marzo_21.jpg2.png 891w, https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2021\/03\/UAM_Marzo_21.jpg2-300x200.png 300w\" sizes=\"(max-width: 562px) 100vw, 562px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong>Figura 1. <\/strong>Porcentaje de recuperaci\u00f3n de nitr\u00f3geno para las diferentes condiciones de operaci\u00f3n (izquierda). Aspecto f\u00edsico de la estruvita precipitada molida sin (dcha. sup.) y con pretratamiento (dcha. inf.).<\/p>\n<p style=\"text-align: center;\">\n<p>Con respecto a la calidad del producto final, los tratamientos previos, sobre todo en el caso del persulfato activado t\u00e9rmicamente, reducen la cantidad de metales en la estruvita, ya que en parte se quedan retenidos en el lodo que se genera durante dicho pretratamiento. En la Tabla 2 se recoge la concentraci\u00f3n de algunos de estos metales, cuyo valor est\u00e1 por debajo de los l\u00edmites que fija el Real Decreto 506\/2013 sobre productos fertilizantes.<\/p>\n<p style=\"text-align: center;\"><strong>Tabla 2. <\/strong>Contenido en metales de la estruvita.<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td rowspan=\"2\" valign=\"top\" width=\"159\"><\/td>\n<td colspan=\"9\" valign=\"top\" width=\"408\">\n<p align=\"left\"><strong>Metales en la estruvita (mg\/kg)<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"38\"><strong>Ca<\/strong><\/td>\n<td valign=\"top\" width=\"37\"><strong>Ti<\/strong><\/td>\n<td valign=\"top\" width=\"47\"><strong>Cr<\/strong><\/td>\n<td valign=\"top\" width=\"47\"><strong>Fe<\/strong><\/td>\n<td valign=\"top\" width=\"42\">\n<p align=\"left\"><strong>Ni<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"47\">\n<p align=\"left\"><strong>Cu<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"56\"><strong>Zn<\/strong><\/td>\n<td valign=\"top\" width=\"47\"><strong>As<\/strong><\/td>\n<td valign=\"top\" width=\"46\"><strong>Pb<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"159\"><strong>Sin pretratamiento<\/strong><\/td>\n<td valign=\"top\" width=\"38\">306<\/td>\n<td valign=\"top\" width=\"37\">21<\/td>\n<td valign=\"top\" width=\"47\">9,2<\/td>\n<td valign=\"top\" width=\"47\">15,4<\/td>\n<td valign=\"top\" width=\"42\">\n<p align=\"right\">29,6<\/p>\n<\/td>\n<td valign=\"top\" width=\"47\">\n<p align=\"left\">12,2<\/p>\n<\/td>\n<td valign=\"top\" width=\"56\">39,6<\/td>\n<td valign=\"top\" width=\"47\">4,2<\/td>\n<td valign=\"top\" width=\"46\">3,7<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"159\"><strong>Despu\u00e9s PS+temp<\/strong><\/td>\n<td valign=\"top\" width=\"38\">192<\/td>\n<td valign=\"top\" width=\"37\">16<\/td>\n<td valign=\"top\" width=\"47\">6,5<\/td>\n<td valign=\"top\" width=\"47\">7,4<\/td>\n<td valign=\"top\" width=\"42\">\n<p align=\"right\">2,2<\/p>\n<\/td>\n<td valign=\"top\" width=\"47\">\n<p align=\"left\">2,4<\/p>\n<\/td>\n<td valign=\"top\" width=\"56\">26,2<\/td>\n<td valign=\"top\" width=\"47\">4,2<\/td>\n<td valign=\"top\" width=\"46\">1,8<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"159\"><strong>Despu\u00e9s Foto-Fenton<\/strong><\/td>\n<td valign=\"top\" width=\"38\">107<\/td>\n<td valign=\"top\" width=\"37\">12<\/td>\n<td valign=\"top\" width=\"47\">6,8<\/td>\n<td valign=\"top\" width=\"47\">138<\/td>\n<td valign=\"top\" width=\"42\">\n<p align=\"right\">12,9<\/p>\n<\/td>\n<td valign=\"top\" width=\"47\">\n<p align=\"left\">1,6<\/p>\n<\/td>\n<td valign=\"top\" width=\"56\">27,7<\/td>\n<td valign=\"top\" width=\"47\">1,2<\/td>\n<td valign=\"top\" width=\"46\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"159\"><strong>RD 506\/2013<\/strong><\/td>\n<td valign=\"top\" width=\"38\">&#8211;<\/td>\n<td valign=\"top\" width=\"37\">&#8211;<\/td>\n<td valign=\"top\" width=\"47\">70<\/td>\n<td valign=\"top\" width=\"47\">&#8211;<\/td>\n<td valign=\"top\" width=\"42\">\n<p align=\"left\">25<\/p>\n<\/td>\n<td valign=\"top\" width=\"47\">\n<p align=\"left\">70<\/p>\n<\/td>\n<td valign=\"top\" width=\"56\">200<\/td>\n<td valign=\"top\" width=\"47\">&#8211;<\/td>\n<td valign=\"top\" width=\"46\">45<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>La transici\u00f3n hacia una econom\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\u00f3n de los residuos, transform\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados de vertedero donde el contenido en nitr\u00f3geno puede ser utilizado como materia prima en la obtenci\u00f3n de estruvita. Investigadores del Departamento de Ingenier\u00eda Qu\u00edmica de la UAM han conseguido precipitar estruvita a partir de estos efluentes. La calidad de este s\u00f3lido y sus futuros usos\u2026<\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[38865,38866,38867],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La transici\u00f3n hacia una econom\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\u00f3n de los residuos, transform\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Remtavares\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Agua -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero - El Agua\" \/>\n\t\t<meta property=\"og:description\" content=\"La transici\u00f3n hacia una econom\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\u00f3n de los residuos, transform\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-03-26T09:46:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-03-26T09:46:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero - El Agua\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La transici\u00f3n hacia una econom\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\u00f3n de los residuos, transform\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926#blogposting\",\"name\":\"Obtenci\\u00f3n de estruvita a partir de lixiviado de vertedero - El Agua\",\"headline\":\"Obtenci\\u00f3n de estruvita a partir de lixiviado de vertedero\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/files\\\/2021\\\/03\\\/UAM_Marzo_21.jpg2.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926\\\/#articleImage\",\"width\":891,\"height\":595},\"datePublished\":\"2021-03-26T10:46:36+01:00\",\"dateModified\":\"2021-03-26T10:46:36+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926#webpage\"},\"articleSection\":\"General, estruvita, lixiviado de vertedero, persulfato activado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926#listItem\",\"name\":\"Obtenci\\u00f3n de estruvita a partir de lixiviado de vertedero\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926#listItem\",\"position\":3,\"name\":\"Obtenci\\u00f3n de estruvita a partir de lixiviado de vertedero\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#organization\",\"name\":\"El Agua\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares\",\"name\":\"Remtavares\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab6792d60f39ca9af5c97503684e70e5?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Remtavares\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926\",\"name\":\"Obtenci\\u00f3n de estruvita a partir de lixiviado de vertedero - El Agua\",\"description\":\"La transici\\u00f3n hacia una econom\\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\\u00f3n de los residuos, transform\\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/03\\\/26\\\/133926#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares#author\"},\"datePublished\":\"2021-03-26T10:46:36+01:00\",\"dateModified\":\"2021-03-26T10:46:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/\",\"name\":\"El Agua\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero - El Agua","description":"La transici\u00f3n hacia una econom\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\u00f3n de los residuos, transform\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926#blogposting","name":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero - El Agua","headline":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2021\/03\/UAM_Marzo_21.jpg2.png","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926\/#articleImage","width":891,"height":595},"datePublished":"2021-03-26T10:46:36+01:00","dateModified":"2021-03-26T10:46:36+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926#webpage"},"articleSection":"General, estruvita, lixiviado de vertedero, persulfato activado"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/remtavares","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926#listItem","name":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926#listItem","position":3,"name":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#organization","name":"El Agua","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares#author","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares","name":"Remtavares","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ab6792d60f39ca9af5c97503684e70e5?s=96&d=mm&r=g","width":96,"height":96,"caption":"Remtavares"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926","name":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero - El Agua","description":"La transici\u00f3n hacia una econom\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\u00f3n de los residuos, transform\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares#author"},"datePublished":"2021-03-26T10:46:36+01:00","dateModified":"2021-03-26T10:46:36+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/","name":"El Agua","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Agua -","og:type":"article","og:title":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero - El Agua","og:description":"La transici\u00f3n hacia una econom\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\u00f3n de los residuos, transform\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados","og:url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926","og:image":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png","article:published_time":"2021-03-26T09:46:36+00:00","article:modified_time":"2021-03-26T09:46:36+00:00","twitter:card":"summary","twitter:title":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero - El Agua","twitter:description":"La transici\u00f3n hacia una econom\u00eda circular pasa por aumentar la eficiencia en el consumo de los recursos disminuyendo las necesidades de materias primas. El mayor aprovechamiento de los recursos impone un cambio en la gesti\u00f3n de los residuos, transform\u00e1ndolos, en la medida de lo posible, en fuente de materias primas. Un ejemplo son los lixiviados","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"133926","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 23:07:12","updated":"2026-05-29 20:10:06","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tObtenci\u00f3n de estruvita a partir de lixiviado de vertedero\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/remtavares"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general"},{"label":"Obtenci\u00f3n de estruvita a partir de lixiviado de vertedero","link":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/03\/26\/133926"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/posts\/133926"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/comments?post=133926"}],"version-history":[{"count":15,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/posts\/133926\/revisions"}],"predecessor-version":[{"id":133944,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/posts\/133926\/revisions\/133944"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/media?parent=133926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/categories?post=133926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/tags?post=133926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}