{"id":133946,"date":"2021-04-09T09:43:13","date_gmt":"2021-04-09T08:43:13","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/remtavares\/?p=133946"},"modified":"2021-04-09T09:46:11","modified_gmt":"2021-04-09T08:46:11","slug":"estrategias-de-valorizacion-de-fangos-de-refineria-subproductos-industriales-y-economia-de-circular","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946","title":{"rendered":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR"},"content":{"rendered":"<p style=\"text-align: justify;\">Investigadores del <a href=\"http:\/\/www.giqa.es\/\">Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental<\/a> (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\u00f3lidos de una refiner\u00eda de petr\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\u00f3n en el marco del Plan de Acci\u00f3n de Econom\u00eda Circular de la Uni\u00f3n Europea.<\/p>\n<p><em>Isabel Pariente &#8211; Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental &#8211; URJC<\/em><\/p>\n<p><!--more--><\/p>\n<p>La industria del petr\u00f3leo actualmente genera grandes cantidades de residuos altamente peligrosos tanto para el medio ambiente como para la salud humana (Liu y col., 2009; Zhao y col, 2019). Entre estos residuos, destacan principalmente los fangos de refiner\u00eda, generados en grandes cantidades durante los procesos de refino de petr\u00f3leo, y durante el tratamiento de sus aguas residuales. Existen diferentes operaciones en el tratamiento de las aguas residuales de refino en las que se generan los diferentes fangos procedentes de: separadores de aceite y agua (API), tratamientos de coagulaci\u00f3n-floculaci\u00f3n, y de los sedimentadores de los reactores biol\u00f3gicos (Hu y col., 2019). El fango de refiner\u00eda generado durante estas operaciones, es un residuo recalcitrante caracterizado por ser una emulsi\u00f3n estable de agua, con una elevada concentraci\u00f3n de part\u00edculas s\u00f3lidas, hidrocarburos procedentes de petr\u00f3leo y metales (Mazlova y Meshcheryakov 1999). Actualmente las refiner\u00edas tienen un fuerte compromiso de reducci\u00f3n y valorizaci\u00f3n de residuos vinculado al Plan de Acci\u00f3n de Econom\u00eda Circular de la UE, dedicando grandes esfuerzos para gestionar este tipo de fangos reduciendo su volumen y proponiendo alternativas para su valorizaci\u00f3n.<\/p>\n<p>Las estrategias actuales en refiner\u00eda para tratar los fangos generados en la industria del petr\u00f3leo tienen como objetivo recuperar la fase aceitosa del fango (la cual puede ser recirculada al proceso de refino) y la gesti\u00f3n final del residuo remanente sin posibilidad de ninguna valorizaci\u00f3n ya que se incinera o acaba en vertedero (Hu y col., 2013; Qin y col., 2016). Sin embargo, se deben estudiar otras alternativas novedosas que permitan reducir los problemas socioecon\u00f3micos y ambientales asociados con su tratamiento actual.<\/p>\n<p>Investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental de la Universidad Rey Juan Carlos, dentro la Red Madrile\u00f1a de Tratamiento de Aguas Residuales (REMTAVARES, 52018\/EMT-4341) financiada por la Comunidad de Madrid, han propuesto la caracterizaci\u00f3n fraccional de un fango de refiner\u00eda de cada una de las fases que lo constituyen (aceitosa, acuosa y s\u00f3lida), con el objeto de determinar sus propiedades fisicoqu\u00edmicas y as\u00ed establecer diferentes estrategias para su valorizaci\u00f3n.<\/p>\n<p>El subproducto industrial objeto de este trabajo es un fango que procede de un separador API de una refiner\u00eda de petr\u00f3leo situada en Espa\u00f1a. Presenta un color oscuro, similar en aspecto y textura a la del crudo de petr\u00f3leo, y consta de tres fases diferenciadas: fase aceitosa, fase acuosa y fase s\u00f3lida (Figura 1a). Los resultados anal\u00edticos obtenidos, <a href=\"https:\/\/doi.org\/10.1016\/j.jenvman.2021.112124\">publicados en la revista cient\u00edfica Journal of Environmental Management<\/a>, indican que la fase aceitosa est\u00e1 formada por hidrocarburos alif\u00e1ticos principalmente con cadenas de carbono desde C<sub>9<\/sub> a C<sub>44<\/sub>, mientras que la fase s\u00f3lida es una mezcla compleja de s\u00f3lidos inorg\u00e1nicos, \u00f3xidos mixtos, y material carbonoso. La fase acuosa presenta una baja concentraci\u00f3n de materia org\u00e1nica y nutrientes, adem\u00e1s de metales disueltos. \u201c<em>Lo m\u00e1s destacable del trabajo es la realizaci\u00f3n por primera vez de una caracterizaci\u00f3n exhaustiva y fraccional de los fangos de refiner\u00eda que permite un mejor conocimiento de la composici\u00f3n del residuo, y las diferentes fases que lo constituyen, permitiendo establecer una estrategia de valorizaci\u00f3n de este subproducto<\/em>\u201d, se\u00f1alan los investigadores del estudio.<\/p>\n<p>Ninguna de las tecnolog\u00edas implantadas a nivel industrial es capaz de valorizar los fangos de refiner\u00eda, pero con los tratamientos propuestos en el trabajo no solo se reducir\u00e1n los gastos econ\u00f3micos asociados a su tratamiento, sino que tambi\u00e9n se minimizar\u00e1 su impacto medioambiental. Para alcanzar este prometedor objetivo, se proponen cuatro estrategias de valorizaci\u00f3n, mostradas en la Figura 1b, que mediante diferentes tratamientos permiten finalmente obtener de los fangos de refiner\u00eda diferentes productos.<\/p>\n<p>La primera estrategia que se plantea consiste en un pretratamiento del fango de refiner\u00eda mediante un tratamiento t\u00e9rmico, como <strong><span style=\"text-decoration: underline;\">la hidr\u00f3lisis t\u00e9rmica o la oxidaci\u00f3n h\u00fameda<\/span><\/strong>. El objetivo es producir la solubilizaci\u00f3n de materia org\u00e1nica, as\u00ed como su transformaci\u00f3n en compuestos m\u00e1s simples (Neyens y Baeyens 2003; Zhao y col., 2018), para posteriormente realizar un tratamiento biol\u00f3gico del efluente acuoso obtenido junto con el agua residual que se produce en refiner\u00eda. As\u00ed, este efluente tendr\u00e1 un mayor contenido en carga org\u00e1nica y en nutrientes, y mejorar\u00e1 el rendimiento del proceso biol\u00f3gico.<\/p>\n<p>La fase s\u00f3lida y aceitosa podr\u00edan tratarse siguiendo la segunda estrategia, mediante <strong><span style=\"text-decoration: underline;\">procesos termoqu\u00edmicos<\/span><\/strong> para finalmente obtener materiales porosos que podr\u00edan emplearse como catalizadores y\/o adsorbentes (Lin y col., 2018) gracias al elevado contenido en metales y compuestos carbonosos de la fase s\u00f3lida. Obteniendo en este caso, por lo tanto, un claro ejemplo de Econom\u00eda Circular en el que los residuos se integran de nuevo en el ciclo productivo.<\/p>\n<p>La estrategia 3 propuesta, consiste en aplicar en primer lugar los procesos de hidr\u00f3lisis t\u00e9rmica u oxidaci\u00f3n h\u00fameda de la estrategia 1, para aumentar la biodegradabilidad del residuo y su valorizaci\u00f3n posterior mediante un proceso de <strong><span style=\"text-decoration: underline;\">digesti\u00f3n anaerobia<\/span><\/strong> para producir biog\u00e1s (60% metano, 40% di\u00f3xido de carbono), f\u00e1cilmente transformable en energ\u00eda el\u00e9ctrica y\/o t\u00e9rmica (Wickham y col., 2016).<\/p>\n<p>Por \u00faltimo, la estrategia 4 se basa en la combinaci\u00f3n de dos tratamientos biol\u00f3gicos, la <strong><span style=\"text-decoration: underline;\">fermentaci\u00f3n<\/span><\/strong> y posteriormente la digesti\u00f3n anaerobia. Ambos tratamientos son capaces de degradar la materia org\u00e1nica contenida en los fangos empleando microorganismos, para producir dos corrientes de gases valorizables como fuentes energ\u00e9ticas, biohidr\u00f3geno y biog\u00e1s (Venkataa y col., 2007).<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2021\/04\/URJC_Abril_Fig1.png\"><img decoding=\"async\" class=\"aligncenter\" title=\"Figura 1\" src=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2021\/04\/URJC_Abril_Fig1.png\" alt=\"\" width=\"682\" height=\"347\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\" align=\"center\">Fig. 1. A) Caracterizaci\u00f3n fraccional del fango de refiner\u00eda B) Estrategias propuestas para su valorizaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\" align=\"center\">Con todo ello, los investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental concluyen que la caracterizaci\u00f3n exhaustiva y estandarizada de las muestras de fango de refiner\u00eda procedentes de diferentes fuentes es un factor clave para su valorizaci\u00f3n, ya que \u00e9sta depende fuertemente de su composici\u00f3n. El \u00e9xito de estas estrategias de valorizaci\u00f3n podr\u00eda permitir un impacto econ\u00f3mico positivo en el esquema de refino de la planta, aline\u00e1ndose adem\u00e1s con los principios de la Econom\u00eda Circular.<\/p>\n<p style=\"text-align: justify;\" align=\"center\"><strong>Referencia bibliogr\u00e1fica del estudio<\/strong><\/p>\n<p>S. Jerez, M. Ventura, R. Molina, M.I. Pariente, F. Mart\u00ednez, J.A. Melero. J. Environ. Manage. 285 (2021) 112124. Available online: <a href=\"https:\/\/doi.org\/10.1016\/j.jenvman.2021.112124\">https:\/\/doi.org\/10.1016\/j.jenvman.2021.112124<\/a><\/p>\n<p><strong>Otras Referencias bibliogr\u00e1ficas <\/strong><\/p>\n<ul>\n<li>G. Hu, J. Li, G. Zeng, J. Hazard. Mater. 261 (2013) 470\u2013490.<\/li>\n<li>B. Lin, Q. Huang, Y. Yang, Y. Chi, J. Anal. Appl. Pyrolysis, 139 (2019) 308\u2013318.<\/li>\n<li>J. Liu, X. Jiang, L. Zhou, X. Han, and Z. Cui, J. Hazard. Mater. 161 (2009) 1208-1215.<\/li>\n<li>E. A. Mazlova y S. V. Meshcheryakov, Chem. Technol. Fuels Oils, 35 (1999) 49-53<\/li>\n<li>E. Neyens y J. Baeyens, J. Hazard. Mater. 98, (2003) 51\u201367.<\/li>\n<li>H. Qin, J. Ma, W. Qing, J. Li, Chinese J. Environ. Eng. 10 (2016) 851\u2013857.<\/li>\n<li>C. E. Santos, A. Fonseca, E. Kumar, A. Bhatnagar, V.J.P. Vilar, C. MS. Botelho, R.A.R. Boaventura.\u00a0 J. Environ. Chem. Eng. 3 (2015) 2095\u20132103.<\/li>\n<li>S. Venkata Mohan, Y. Vijaya Bhaskar, P. Murali Krishna, N. Chandrasekhara Rao, V. Lalit Babu, P. N. Sarma, Int. J. Hydrogen Energy, 32 (2007) 2286\u20132295.<\/li>\n<li>R. Wickham, B. Galway, H. Bustamante, and L. D. Nghiem, Int. Biodeterior. Biodegrad. 113 (2016) 3\u20138.<\/li>\n<li>Y. Zhao, X. Y. Zhou, R. Li, S. Yang, B. Wang, R. Deng, J. Energy Inst. 92 (2018) 1451-1457.<\/li>\n<li>M. Zhao, X. Wang, D. Liu, Z. Li, S. Guo, W. Zhu, N. Shi, F. Wen, J. Dong. J. Hazard. Mater. 389 (2019) 121826.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\u00f3lidos de una refiner\u00eda de petr\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\u00f3n en el marco del Plan de Acci\u00f3n de Econom\u00eda Circular de la Uni\u00f3n Europea. Isabel Pariente &#8211; Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental &#8211; URJC<\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\u00f3lidos de una refiner\u00eda de petr\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\u00f3n en el marco del Plan de Acci\u00f3n de Econom\u00eda Circular de la Uni\u00f3n Europea. Isabel\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Remtavares\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Agua -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR - El Agua\" \/>\n\t\t<meta property=\"og:description\" content=\"Investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\u00f3lidos de una refiner\u00eda de petr\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\u00f3n en el marco del Plan de Acci\u00f3n de Econom\u00eda Circular de la Uni\u00f3n Europea. Isabel\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-09T08:43:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-04-09T08:46:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR - El Agua\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\u00f3lidos de una refiner\u00eda de petr\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\u00f3n en el marco del Plan de Acci\u00f3n de Econom\u00eda Circular de la Uni\u00f3n Europea. Isabel\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946#blogposting\",\"name\":\"ESTRATEGIAS DE VALORIZACI\\u00d3N DE FANGOS DE REFINER\\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\\u00cdA DE CIRCULAR - El Agua\",\"headline\":\"ESTRATEGIAS DE VALORIZACI\\u00d3N DE FANGOS DE REFINER\\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\\u00cdA DE CIRCULAR\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/files\\\/2021\\\/04\\\/URJC_Abril_Fig1.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946\\\/#articleImage\",\"width\":886,\"height\":450},\"datePublished\":\"2021-04-09T09:43:13+01:00\",\"dateModified\":\"2021-04-09T09:46:11+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946#listItem\",\"name\":\"ESTRATEGIAS DE VALORIZACI\\u00d3N DE FANGOS DE REFINER\\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\\u00cdA DE CIRCULAR\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946#listItem\",\"position\":3,\"name\":\"ESTRATEGIAS DE VALORIZACI\\u00d3N DE FANGOS DE REFINER\\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\\u00cdA DE CIRCULAR\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#organization\",\"name\":\"El Agua\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares\",\"name\":\"Remtavares\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab6792d60f39ca9af5c97503684e70e5?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Remtavares\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946\",\"name\":\"ESTRATEGIAS DE VALORIZACI\\u00d3N DE FANGOS DE REFINER\\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\\u00cdA DE CIRCULAR - El Agua\",\"description\":\"Investigadores del Grupo de Ingenier\\u00eda Qu\\u00edmica y Ambiental (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\\u00f3lidos de una refiner\\u00eda de petr\\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\\u00f3n en el marco del Plan de Acci\\u00f3n de Econom\\u00eda Circular de la Uni\\u00f3n Europea. Isabel\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/2021\\\/04\\\/09\\\/133946#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/author\\\/remtavares#author\"},\"datePublished\":\"2021-04-09T09:43:13+01:00\",\"dateModified\":\"2021-04-09T09:46:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/\",\"name\":\"El Agua\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/remtavares\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR - El Agua","description":"Investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\u00f3lidos de una refiner\u00eda de petr\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\u00f3n en el marco del Plan de Acci\u00f3n de Econom\u00eda Circular de la Uni\u00f3n Europea. Isabel","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946#blogposting","name":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR - El Agua","headline":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2021\/04\/URJC_Abril_Fig1.png","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946\/#articleImage","width":886,"height":450},"datePublished":"2021-04-09T09:43:13+01:00","dateModified":"2021-04-09T09:46:11+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/remtavares","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946#listItem","name":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946#listItem","position":3,"name":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#organization","name":"El Agua","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares#author","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares","name":"Remtavares","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ab6792d60f39ca9af5c97503684e70e5?s=96&d=mm&r=g","width":96,"height":96,"caption":"Remtavares"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946","name":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR - El Agua","description":"Investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\u00f3lidos de una refiner\u00eda de petr\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\u00f3n en el marco del Plan de Acci\u00f3n de Econom\u00eda Circular de la Uni\u00f3n Europea. Isabel","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/author\/remtavares#author"},"datePublished":"2021-04-09T09:43:13+01:00","dateModified":"2021-04-09T09:46:11+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/","name":"El Agua","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Agua -","og:type":"article","og:title":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR - El Agua","og:description":"Investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\u00f3lidos de una refiner\u00eda de petr\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\u00f3n en el marco del Plan de Acci\u00f3n de Econom\u00eda Circular de la Uni\u00f3n Europea. Isabel","og:url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946","og:image":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png","article:published_time":"2021-04-09T08:43:13+00:00","article:modified_time":"2021-04-09T08:46:11+00:00","twitter:card":"summary","twitter:title":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR - El Agua","twitter:description":"Investigadores del Grupo de Ingenier\u00eda Qu\u00edmica y Ambiental (GIQA) de la URJC, han realizado un novedoso estudio de las propiedades de los residuos s\u00f3lidos de una refiner\u00eda de petr\u00f3leo y con sus resultados han propuesto cuatro alternativas para su valorizaci\u00f3n en el marco del Plan de Acci\u00f3n de Econom\u00eda Circular de la Uni\u00f3n Europea. Isabel","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"133946","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:47:09","updated":"2026-05-29 20:10:06","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/remtavares"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/category\/general"},{"label":"ESTRATEGIAS DE VALORIZACI\u00d3N DE FANGOS DE REFINER\u00cdA: SUBPRODUCTOS INDUSTRIALES Y ECONOM\u00cdA DE CIRCULAR","link":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/2021\/04\/09\/133946"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/posts\/133946"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/comments?post=133946"}],"version-history":[{"count":13,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/posts\/133946\/revisions"}],"predecessor-version":[{"id":133959,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/posts\/133946\/revisions\/133959"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/media?parent=133946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/categories?post=133946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/remtavares\/wp-json\/wp\/v2\/tags?post=133946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}