{"id":105934,"date":"2008-11-05T15:46:00","date_gmt":"2008-11-05T15:46:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2008\/11\/05\/105934.aspx"},"modified":"2010-01-22T03:49:56","modified_gmt":"2010-01-22T02:49:56","slug":"los-suelos-la-piel-viva-de-la-tierra","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934","title":{"rendered":"Los Suelos: la Piel Viva de la Tierra"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Cuando la <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">prensa<\/SPAN><\/B> patria anunci\u00f3 <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">El a\u00f1o Internacional del Planeta Tierra<\/SPAN><\/B>, o l<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">os suelos no estaban incluidos, o tan solo <\/SPAN><\/B>de manera tangencial. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Busqu\u00e9 propaganda en suahili y aparec\u00eda por todas partes<\/SPAN><\/B>. Insisto en que l<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">os periodistas espa\u00f1oles<\/SPAN><\/B>, en su mayor\u00eda, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">detestan tanto los suelos como yo a ellos<\/SPAN><\/B>. Una y otra vez<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\"> esconden cualquier noticia relacionada con ellos<\/SPAN><\/B> m\u00e1s all\u00e1 del subsuelo, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">neg\u00e1ndole al ciudadano lo que en otros pa\u00edses no dudan en divulgar<\/SPAN><\/B> (confabulaci\u00f3n judeo-mas\u00f3nica que dec\u00eda un caudillo muy famoso del que prefiero olvidarme). Y aunque no os lo cre\u00e1is, muchos d\u00edas no me apetece discutir ni criticar. Por tanto me olvid\u00e9 del tema. Sin embargo, la<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\"> IUSS <\/SPAN><\/B>hizo sus deberes y <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">elabor\u00f3 un boceto divulgativo<\/SPAN><\/B>. Apareci\u00f3 el primero en ingl\u00e9s, luego en otras muchas lenguas y por fin lo ha hecho en espa\u00f1ol. Sin embargo, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">desconoc\u00eda que hubiera uno trabajo m\u00e1s extenso en nuestro idioma<\/SPAN><\/B>. Lo he localizado casualmente en Internet. No tengo clara su procedencia, por lo que pido disculpas. Se trata de una traducci\u00f3n de otro original en suahili escrito por: David Dent (Pa\u00edses Bajos, jefe); Alfred Hartemink (Pa\u00edses Bajos), John Kimble (Estados Unidos), con agradecimientos a Rudi Dudal (B\u00e9lgica) y Donald Sparks (Estados Unidos). Ya he hablado de casi todos ellos en esta bit\u00e1cora. Se trata de <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">una documentaci\u00f3n que puede ser de mucha ayuda para la divulgaci\u00f3n y docencia de la edafolog\u00eda<\/SPAN><\/B> por lo que os ofrezco los enlaces para que los pod\u00e1is bajar, leer o repartir. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><IMG style=\"WIDTH: 442px; HEIGHT: 316px\" height=505 src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/o_Epidermis%20de%20la%20Tierra.png\" width=657><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN>&nbsp;<\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><A href=\"http:\/\/www.iuss.org\/Soil%20Flyer%20IYPE%202008\/Soil%20Flyer%202008%20-%20Spanish.pdf\"><FONT color=#800080>El Suelo-Epidermis Viva de la Tierra<\/FONT><\/A><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Fuente: P\u00e1gina Web de la IUSS<o:p><\/o:p><\/SPAN><\/P><!--more--><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">El <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">documento de la IUSS<\/SPAN><\/B> lleva por t\u00edtulo:<\/SPAN> \u201c<SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><A href=\"http:\/\/www.iuss.org\/Soil%20Flyer%20IYPE%202008\/Soil%20Flyer%202008%20-%20Spanish.pdf\"><FONT color=#800080>El Suelo-Epidermis Viva de la Tierra<\/FONT><\/A>\u201d, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">mientras que el de los autores mentados<\/SPAN><\/B> <A href=\"http:\/\/www.medioambiente.cu\/planeta_Tierra\/download\/Suelos.pdf\"><FONT color=#800080>Los Suelos: La Piel Viva de la Tierra<\/FONT><\/A>. Obviamente debe tratarse de la misma iniciativa en distintos formatos, por que de no ser as\u00ed\u2026.. L\u00f3gicamente se aprende m\u00e1s del extenso, que del editado por la IUSS en color, por cuanto el \u00faltimo es demasiado escueto (a penas 2 p\u00e1ginas). En cualquier caso, aqu\u00ed os los dejo para quien pudiera estar interesado. \u00a1Que los disfrut\u00e9is! <SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN><SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<o:p><\/o:p><\/SPAN><\/P><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Cuando la prensa patria anunci\u00f3 El a\u00f1o Internacional del Planeta Tierra, o los suelos no estaban incluidos, o tan solo de manera tangencial. Busqu\u00e9 propaganda en suahili y aparec\u00eda por todas partes. Insisto en que los periodistas espa\u00f1oles, en su mayor\u00eda, detestan tanto los suelos como yo a ellos. Una y otra vez esconden cualquier noticia relacionada con ellos m\u00e1s all\u00e1 del subsuelo, neg\u00e1ndole al ciudadano lo que en otros pa\u00edses no dudan en divulgar (confabulaci\u00f3n judeo-mas\u00f3nica que dec\u00eda un caudillo muy famoso del que prefiero olvidarme). Y aunque no os lo cre\u00e1is, muchos d\u00edas no me apetece discutir ni\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[590,584,588,587,615,606,617],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cuando la prensa patria anunci\u00f3 El a\u00f1o Internacional del Planeta Tierra, o los suelos no estaban incluidos, o tan solo de manera tangencial. Busqu\u00e9 propaganda en suahili y aparec\u00eda por todas partes. Insisto en que los periodistas espa\u00f1oles, en su mayor\u00eda, detestan tanto los suelos como yo a ellos. Una y otra vez esconden cualquier\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Suelos: la Piel Viva de la Tierra - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Cuando la prensa patria anunci\u00f3 El a\u00f1o Internacional del Planeta Tierra, o los suelos no estaban incluidos, o tan solo de manera tangencial. Busqu\u00e9 propaganda en suahili y aparec\u00eda por todas partes. Insisto en que los periodistas espa\u00f1oles, en su mayor\u00eda, detestan tanto los suelos como yo a ellos. Una y otra vez esconden cualquier\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-11-05T15:46:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-22T02:49:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Suelos: la Piel Viva de la Tierra - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cuando la prensa patria anunci\u00f3 El a\u00f1o Internacional del Planeta Tierra, o los suelos no estaban incluidos, o tan solo de manera tangencial. Busqu\u00e9 propaganda en suahili y aparec\u00eda por todas partes. Insisto en que los periodistas espa\u00f1oles, en su mayor\u00eda, detestan tanto los suelos como yo a ellos. Una y otra vez esconden cualquier\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934#blogposting\",\"name\":\"Los Suelos: la Piel Viva de la Tierra - Un Universo invisible bajo nuestros pies\",\"headline\":\"Los Suelos: la Piel Viva de la Tierra\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2008-11-05T15:46:00+01:00\",\"dateModified\":\"2010-01-22T03:49:56+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934#webpage\"},\"articleSection\":\"Componentes, Estructuras y Procesos en los Suelos, Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces, El Concepto de Suelo y Sus Representaciones, La Crisis de la Edafolog\\u00eda, Notas Breves de Prensa, Prensa y Pol\\u00edtica Cient\\u00edfica, Procesos Superficiales terrestres: Relieve, Geomorfolog\\u00eda y Cuencas de Drenaje:\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"position\":2,\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934#listItem\",\"name\":\"Los Suelos: la Piel Viva de la Tierra\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934#listItem\",\"position\":3,\"name\":\"Los Suelos: la Piel Viva de la Tierra\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934\",\"name\":\"Los Suelos: la Piel Viva de la Tierra - Un Universo invisible bajo nuestros pies\",\"description\":\"Cuando la prensa patria anunci\\u00f3 El a\\u00f1o Internacional del Planeta Tierra, o los suelos no estaban incluidos, o tan solo de manera tangencial. Busqu\\u00e9 propaganda en suahili y aparec\\u00eda por todas partes. Insisto en que los periodistas espa\\u00f1oles, en su mayor\\u00eda, detestan tanto los suelos como yo a ellos. Una y otra vez esconden cualquier\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/11\\\/05\\\/105934#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2008-11-05T15:46:00+01:00\",\"dateModified\":\"2010-01-22T03:49:56+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los Suelos: la Piel Viva de la Tierra - Un Universo invisible bajo nuestros pies","description":"Cuando la prensa patria anunci\u00f3 El a\u00f1o Internacional del Planeta Tierra, o los suelos no estaban incluidos, o tan solo de manera tangencial. Busqu\u00e9 propaganda en suahili y aparec\u00eda por todas partes. Insisto en que los periodistas espa\u00f1oles, en su mayor\u00eda, detestan tanto los suelos como yo a ellos. Una y otra vez esconden cualquier","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934#blogposting","name":"Los Suelos: la Piel Viva de la Tierra - Un Universo invisible bajo nuestros pies","headline":"Los Suelos: la Piel Viva de la Tierra","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#articleImage","width":217,"height":72},"datePublished":"2008-11-05T15:46:00+01:00","dateModified":"2010-01-22T03:49:56+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934#webpage"},"articleSection":"Componentes, Estructuras y Procesos en los Suelos, Documentos sobre Edafolog\u00eda + Instituciones + Enlaces, El Concepto de Suelo y Sus Representaciones, La Crisis de la Edafolog\u00eda, Notas Breves de Prensa, Prensa y Pol\u00edtica Cient\u00edfica, Procesos Superficiales terrestres: Relieve, Geomorfolog\u00eda y Cuencas de Drenaje:"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","position":2,"name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934#listItem","name":"Los Suelos: la Piel Viva de la Tierra"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934#listItem","position":3,"name":"Los Suelos: la Piel Viva de la Tierra","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934","name":"Los Suelos: la Piel Viva de la Tierra - Un Universo invisible bajo nuestros pies","description":"Cuando la prensa patria anunci\u00f3 El a\u00f1o Internacional del Planeta Tierra, o los suelos no estaban incluidos, o tan solo de manera tangencial. Busqu\u00e9 propaganda en suahili y aparec\u00eda por todas partes. Insisto en que los periodistas espa\u00f1oles, en su mayor\u00eda, detestan tanto los suelos como yo a ellos. Una y otra vez esconden cualquier","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2008-11-05T15:46:00+01:00","dateModified":"2010-01-22T03:49:56+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Los Suelos: la Piel Viva de la Tierra - Un Universo invisible bajo nuestros pies","og:description":"Cuando la prensa patria anunci\u00f3 El a\u00f1o Internacional del Planeta Tierra, o los suelos no estaban incluidos, o tan solo de manera tangencial. Busqu\u00e9 propaganda en suahili y aparec\u00eda por todas partes. Insisto en que los periodistas espa\u00f1oles, en su mayor\u00eda, detestan tanto los suelos como yo a ellos. Una y otra vez esconden cualquier","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2008-11-05T15:46:00+00:00","article:modified_time":"2010-01-22T02:49:56+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Los Suelos: la Piel Viva de la Tierra - Un Universo invisible bajo nuestros pies","twitter:description":"Cuando la prensa patria anunci\u00f3 El a\u00f1o Internacional del Planeta Tierra, o los suelos no estaban incluidos, o tan solo de manera tangencial. Busqu\u00e9 propaganda en suahili y aparec\u00eda por todas partes. Insisto en que los periodistas espa\u00f1oles, en su mayor\u00eda, detestan tanto los suelos como yo a ellos. Una y otra vez esconden cualquier","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"105934","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:04:39","updated":"2026-05-26 15:18:53","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces\" title=\"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces\">Documentos sobre Edafolog\u00eda + Instituciones + Enlaces<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos Suelos: la Piel Viva de la Tierra\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces"},{"label":"Los Suelos: la Piel Viva de la Tierra","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/05\/105934"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/105934"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=105934"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/105934\/revisions"}],"predecessor-version":[{"id":134795,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/105934\/revisions\/134795"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=105934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=105934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=105934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}