{"id":109793,"date":"2008-12-19T12:28:00","date_gmt":"2008-12-19T12:28:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2008\/12\/19\/109793.aspx"},"modified":"2010-01-22T03:50:15","modified_gmt":"2010-01-22T02:50:15","slug":"premios-nobeles-jurados-y-corrupcion","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793","title":{"rendered":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">\u00a1<B><SPAN style=\"COLOR: rgb(51,102,255)\">Vaya a\u00f1o<\/SPAN><\/B>!. Ni en navidad nos dejan descansar. <B><SPAN style=\"COLOR: rgb(51,102,255)\">Parece que estamos alcanzando tal cota de corrupci\u00f3n bajo, el desp\u00f3tico imperio de esta econom\u00eda&nbsp;globalizada, como para pensar que <\/SPAN><\/B>son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta.<SPAN>&nbsp; <\/SPAN>Y mientras en Espa\u00f1a nuestros \u201ccient\u00edficos de excelencia\u201d siguen mostrando su cara m\u00e1s santurrona, la prensa internacional se encarga de poner bajo sospecha muchas actividades de sus practicantes, mal que les pese. Sin embargo la <B><SPAN style=\"COLOR: rgb(51,102,255)\">noticia que comentamos hoy<\/SPAN><\/B> es de mayor calado a\u00fan, por cuanto <B><SPAN style=\"COLOR: rgb(51,102,255)\">cuestiona la honradez de c\u00fapula pontificia de la sociedad cient\u00edfica<\/SPAN><\/B>.<SPAN>&nbsp; <\/SPAN><B><SPAN style=\"COLOR: rgb(51,102,255)\">La integridad de los jurados que conceden los Premios N\u00f3bel son sospechosos de fraude \u00bfY quien est\u00e1 detr\u00e1s?<\/SPAN><\/B>. \u00a1Como no!, uno de los sectores industriales que lleva en el punto de mira decenios: <B><SPAN style=\"COLOR: rgb(51,102,255)\">la farmaindustria<\/SPAN><\/B>. Esa a cuyos brazos nos impulsan obsesivamente nuestras autoridades pol\u00edticas en materia de I+D+i. A donde hay dinero all\u00ed nos arrastran, sin realizar la menor reflexi\u00f3n. \u00a1La pasta es la pasta!. <SPAN>&nbsp;<\/SPAN><?xml:namespace prefix = o \/><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><IMG style=\"WIDTH: 438px; HEIGHT: 419px\" height=376 src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/o_medalla_nobel.gif\" width=349><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN>&nbsp;<\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\"><A href=\"http:\/\/planetaconciencia.blogspot.com\/2008_08_01_archive.html\"><FONT color=#800080>La Otra cara de los premios N\u00f3bel<o:p><\/o:p><\/FONT><\/A><\/SPAN><\/P><SPAN class=MsoHyperlink><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\"><A href=\"http:\/\/planetaconciencia.blogspot.com\/2008_08_01_archive.html\"><FONT color=#800080>planetaconciencia.blogspot.com<\/FONT><\/A><\/SPAN><\/SPAN><!--more--><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\">En realidad, desde que comenc\u00e9 a editar post sobre el <A href=\"http:\/\/weblogs.madrimasd.org\/universo\/category\/363.aspx\"><FONT color=#800080>fraude y mala praxis cient\u00edfica<\/FONT><\/A>, abr\u00ed una carpeta en mi PC y comenc\u00e9 a archivar todas las noticias relacionadas con el tema, con independencia de que concernieran a <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">la propia ciencia, o a sectores tecnol\u00f3gicos estrat\u00e9gicos<\/SPAN><\/B>. En verdad que <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">la farmaindustria se lleva el N\u00f3bel de la Corrupci\u00f3n<\/SPAN><\/B>. Eso si, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">no van muy lejos de su estela las agroindustrias, energ\u00e9ticas y multinacionales extractivas<\/SPAN><\/B> (principalmente las compa\u00f1\u00edas mineras en los pa\u00edses m\u00e1s desheredados, contamin\u00e1ndolo todo y mucho, mucho m\u00e1s). Omito a los pol\u00edticos porque eso ya lo sabemos todos. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\">Siempre he pensado que <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">los N\u00f3bel son como los Oscar de Hollywood, o cualquier otro galard\u00f3n. Los jurados son presionados por todos los lados<\/SPAN><\/B> (y por su puesto por escuelas invisibles de sus propios colegas), cuando no sesgados desde el principio. Del mismo modo, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">cabr\u00eda tambi\u00e9n apuntar con el dedo a los responsables de su elecci\u00f3n<\/SPAN><\/B>. \u00bfEs que no se investiga jam\u00e1s si se producen sospechosos conflictos de intereses? (por favor, lean la noticia abajo). Pero da igual. Cada uno que piense lo que quiera. Eso si, otra vez China de por medio. Desconozco si se trata de denostar a cualquier precio a un Estado, o si hay razones para ello. En cualquier caso, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">cuando se habla de corrupci\u00f3n cient\u00edfica nuestras autoridades siempre miran para otro lado. <\/SPAN><\/B>\u00a1Es su costumbre!. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Desde esta bit\u00e1cora ya les reproch\u00e9 la cultura del ladrillazo y mirar como ha terminado la econom\u00eda de este pa\u00eds<\/SPAN><\/B>: \u00a1Por los suelos!, mal que les pese. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 10pt; COLOR: #3366ff; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\">Dudo mucho que al final conozcamos la verdad y toda la verdad. \u00bfEstan algunos de los poderes f\u00e1cticos interesados?<\/SPAN><\/B><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\"> Tan solo les faltaba ahora que los plebeyos atacaran a<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\"> la sacrosanta I+D+i, que seg\u00fan nuestros pol\u00edticos resulta ser la panacea para todos los males <\/SPAN><\/B>que aquejan a las sociedades occidentales<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\"> \u00bfSeguro? \u00bfNo ser\u00e9is vosotros el c\u00e1ncer? No ser\u00e1n \u00e9tica y moral lo que necesitamos, como defiende Obama<\/SPAN><\/B> frente a la indecencia de los gur\u00fas financieros de su pa\u00eds (y de otros muchos). Algo huele muy mal, aunque seguramente jam\u00e1s sepamos lo sucedido. Y sigo teniendo la impresi\u00f3n de que se trata de <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">puntas de iceberg <\/SPAN><\/B>(v\u00e9ase, por ejemplo, la lista de los variopintos y a menudo incomprensibles premios N\u00f3bel de la Paz que denuncian t\u00e1citamente, por decenios, las decisiones de estos irreprochables y honorables jurados de los N\u00f3bel). Os dejo tranquilos por hoy con algunos enlaces y una cualquiera de las noticias que da cuenta de este m\u00e1s que lamentable suceso.<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\">Juan Jos\u00e9 Ib\u00e1\u00f1ez <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Arial\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\"><A href=\"http:\/\/www.adn.es\/mundo\/20081219\/NWS-0562-premios-nobel-corrupcion-medicina.html\">Mundo &#8211; Suecia investiga un posible caso de corrupci\u00f3n en los &#8230;<\/A><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\"><A href=\"http:\/\/www.elmundo.es\/papel\/2003\/06\/11\/espana\/1414353.html\">Premios Nobel y jueces contra la corrupci\u00f3n \/ EL MUNDO<\/A><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\"><A href=\"http:\/\/es.noticias.yahoo.com\/especiales\/noticias-premio-nobel.html\">Los Premios Nobel | Cobertura Especial &#8211; Yahoo! Noticias<\/A><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-FAMILY: 'Comic Sans MS'\"><A href=\"http:\/\/www.20minutos.es\/noticia\/437951\/0\/corrupcion\/premios\/nobel\/\">\u00bfEst\u00e1n corruptos los premios Nobel? &#8211; 20minutos.es<\/A><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 10pt; COLOR: #3366ff; FONT-FAMILY: Arial\">La integridad del jurado que concede los premios Nobel est\u00e1 en tela de juicio<\/SPAN><\/B><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\"> tras la revelaci\u00f3n de que <A title=\"La noticia en The times, en ingl\u00e9s.\" href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/europe\/article5367941.ece\" target=_blank>uno de sus miembros forma parte al mismo tiempo del consejo de direcci\u00f3n<\/A> de una <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">empresa farmac\u00e9utica beneficiada<\/SPAN><\/B> por el galard\u00f3n. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Dos miembros de los comit\u00e9s del Nobel trabajaron con esta farmac\u00e9utica<\/SPAN><\/B>.<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\">La fiscal\u00eda sueca trata de determinar si <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">el gigante farmac\u00e9utico brit\u00e1nico <\/SPAN><\/B><A title=\"Web de esta farmac\u00e9utica.\" href=\"http:\/\/www.astrazeneca.com\/\" target=_blank>AstraZeneca<\/A> ejerci\u00f3 alguna una <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">influencia en la concesi\u00f3n<\/SPAN><\/B> del <A title=\"Los descubridores del papiloma humano y el VIH ganan el premio Nobel de Medicina\" href=\"http:\/\/www.20minutos.es\/noticia\/417528\/0\/premio\/nobel\/medicina\/\">\u00faltimo Nobel de Medicina a Harald Zur Hausen<\/A>, informa este viernes el diario <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">The Times<\/SPAN><\/B>.<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\"><SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 10pt; COLOR: #3366ff; FONT-FAMILY: Arial\">El cient\u00edfico fue recompensado por sus trabajos sobre el virus del papiloma humano<\/SPAN><\/B><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\">, que puede causar el c\u00e1ncer cervical <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">y contra el cual AstraZeneca ha desarrollado dos vacunas muy lucrativas<\/SPAN><\/B>. Dos personajes que <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">ejercieron un papel en el proceso de elecci\u00f3n de Zur Hausen tienen fuertes v\u00ednculos con esa compa\u00f1\u00eda farmac\u00e9utica<\/SPAN><\/B>, que ha comenzado adem\u00e1s a patrocinar el portal de internet del Nobel. Ni la compa\u00f1\u00eda, ni la fundaci\u00f3n Nobel han revelado cu\u00e1nto vale el contrato para ese patrocinio y el de la filial promocional del premio Nobel Media, aunque el peri\u00f3dico cree que ser\u00e1n cientos de miles de d\u00f3lares. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"COLOR: green; FONT-FAMILY: Arial\">La polic\u00eda sueca averigua si hay motivos para una investigaci\u00f3n oficial <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\">Seg\u00fan la radio sueca<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">, Bertil Fredholm, presidente del comit\u00e9 de cinco personas que estudia a los candidatos al premio, trabaj\u00f3 como asesor para AstraZeneca en el 2006. Bo Angelin<\/SPAN><\/B>, miembro del comit\u00e9 de 50 personas que vota al ganador, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">forma tambi\u00e9n parte del consejo de direcci\u00f3n de la farmac\u00e9utica<\/SPAN><\/B>.<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\"><SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\">El a\u00f1o pasado, AstraZeneca compr\u00f3 una compa\u00f1\u00eda que hab\u00eda desarrollado un componente clave para la producci\u00f3n de dos vacunas contra el virus del papiloma humano. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">El director de la divisi\u00f3n anticorrupci\u00f3n de la polic\u00eda sueca<\/SPAN><\/B>, Christer van der Kwast, explic\u00f3 a The Times que hab\u00eda encargado a la fiscal\u00eda averiguar si hab\u00eda motivos para lanzar una investigaci\u00f3n.<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"COLOR: green; FONT-FAMILY: Arial\">Viajes pagados por la autoridades chinas <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: Arial\">El jueves, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">la fiscal\u00eda sueca abri\u00f3 otra investigaci\u00f3n preliminar sobre un supuesto caso de soborno a miembros de varios comit\u00e9s Nobel que <\/SPAN><\/B>aceptaron viajes con todos los gastos pagados por las autoridades chinas. Se trata de dos viajes realizados por cinco representantes de los comit\u00e9s, uno hace dos a\u00f1os y otro en enero pasado, a China, en los que el objetivo era informar de c\u00f3mo se realiza el proceso para designar a los ganadores en las distintas categor\u00edas de los Nobel. El Gobierno chino se hizo cargo en ambos casos de los gastos de viaje, alojamiento y manutenci\u00f3n.<o:p><\/o:p><\/SPAN><\/P><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00a1Vaya a\u00f1o!. Ni en navidad nos dejan descansar. Parece que estamos alcanzando tal cota de corrupci\u00f3n bajo, el desp\u00f3tico imperio de esta econom\u00eda&nbsp;globalizada, como para pensar que son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta.&nbsp; Y mientras en Espa\u00f1a nuestros \u201ccient\u00edficos de excelencia\u201d siguen mostrando su cara m\u00e1s santurrona, la prensa internacional se encarga de poner bajo sospecha muchas actividades de sus practicantes, mal que les pese. Sin embargo la noticia que comentamos hoy es de mayor calado a\u00fan, por cuanto cuestiona la honradez de c\u00fapula pontificia de la sociedad cient\u00edfica.&nbsp;\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[609,605,615,606],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00a1Vaya a\u00f1o!. Ni en navidad nos dejan descansar. Parece que estamos alcanzando tal cota de corrupci\u00f3n bajo, el desp\u00f3tico imperio de esta econom\u00eda globalizada, como para pensar que son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta. Y mientras en Espa\u00f1a nuestros \u201ccient\u00edficos de excelencia\u201d siguen mostrando su\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Premios N\u00f3beles. Jurados y Corrupci\u00f3n - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"\u00a1Vaya a\u00f1o!. Ni en navidad nos dejan descansar. Parece que estamos alcanzando tal cota de corrupci\u00f3n bajo, el desp\u00f3tico imperio de esta econom\u00eda globalizada, como para pensar que son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta. Y mientras en Espa\u00f1a nuestros \u201ccient\u00edficos de excelencia\u201d siguen mostrando su\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-12-19T12:28:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-22T02:50:15+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Premios N\u00f3beles. Jurados y Corrupci\u00f3n - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u00a1Vaya a\u00f1o!. Ni en navidad nos dejan descansar. Parece que estamos alcanzando tal cota de corrupci\u00f3n bajo, el desp\u00f3tico imperio de esta econom\u00eda globalizada, como para pensar que son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta. Y mientras en Espa\u00f1a nuestros \u201ccient\u00edficos de excelencia\u201d siguen mostrando su\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793#blogposting\",\"name\":\"Premios N\\u00f3beles. Jurados y Corrupci\\u00f3n - Un Universo invisible bajo nuestros pies\",\"headline\":\"Premios N\\u00f3beles. Jurados y Corrupci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2008-12-19T12:28:00+01:00\",\"dateModified\":\"2010-01-22T03:50:15+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793#webpage\"},\"articleSection\":\"Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, Fraude y Mala Praxis Cient\\u00edfica, Notas Breves de Prensa, Prensa y Pol\\u00edtica Cient\\u00edfica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fraude-y-mala-praxis-cientifica#listItem\",\"name\":\"Fraude y Mala Praxis Cient\\u00edfica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fraude-y-mala-praxis-cientifica#listItem\",\"position\":2,\"name\":\"Fraude y Mala Praxis Cient\\u00edfica\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fraude-y-mala-praxis-cientifica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793#listItem\",\"name\":\"Premios N\\u00f3beles. Jurados y Corrupci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793#listItem\",\"position\":3,\"name\":\"Premios N\\u00f3beles. Jurados y Corrupci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fraude-y-mala-praxis-cientifica#listItem\",\"name\":\"Fraude y Mala Praxis Cient\\u00edfica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793\",\"name\":\"Premios N\\u00f3beles. Jurados y Corrupci\\u00f3n - Un Universo invisible bajo nuestros pies\",\"description\":\"\\u00a1Vaya a\\u00f1o!. Ni en navidad nos dejan descansar. Parece que estamos alcanzando tal cota de corrupci\\u00f3n bajo, el desp\\u00f3tico imperio de esta econom\\u00eda globalizada, como para pensar que son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta. Y mientras en Espa\\u00f1a nuestros \\u201ccient\\u00edficos de excelencia\\u201d siguen mostrando su\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/12\\\/19\\\/109793#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2008-12-19T12:28:00+01:00\",\"dateModified\":\"2010-01-22T03:50:15+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n - Un Universo invisible bajo nuestros pies","description":"\u00a1Vaya a\u00f1o!. Ni en navidad nos dejan descansar. Parece que estamos alcanzando tal cota de corrupci\u00f3n bajo, el desp\u00f3tico imperio de esta econom\u00eda globalizada, como para pensar que son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta. Y mientras en Espa\u00f1a nuestros \u201ccient\u00edficos de excelencia\u201d siguen mostrando su","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793#blogposting","name":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n - Un Universo invisible bajo nuestros pies","headline":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#articleImage","width":217,"height":72},"datePublished":"2008-12-19T12:28:00+01:00","dateModified":"2010-01-22T03:50:15+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793#webpage"},"articleSection":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, Fraude y Mala Praxis Cient\u00edfica, Notas Breves de Prensa, Prensa y Pol\u00edtica Cient\u00edfica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica#listItem","name":"Fraude y Mala Praxis Cient\u00edfica"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica#listItem","position":2,"name":"Fraude y Mala Praxis Cient\u00edfica","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793#listItem","name":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793#listItem","position":3,"name":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica#listItem","name":"Fraude y Mala Praxis Cient\u00edfica"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793","name":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n - Un Universo invisible bajo nuestros pies","description":"\u00a1Vaya a\u00f1o!. Ni en navidad nos dejan descansar. Parece que estamos alcanzando tal cota de corrupci\u00f3n bajo, el desp\u00f3tico imperio de esta econom\u00eda globalizada, como para pensar que son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta. Y mientras en Espa\u00f1a nuestros \u201ccient\u00edficos de excelencia\u201d siguen mostrando su","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2008-12-19T12:28:00+01:00","dateModified":"2010-01-22T03:50:15+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n - Un Universo invisible bajo nuestros pies","og:description":"\u00a1Vaya a\u00f1o!. Ni en navidad nos dejan descansar. Parece que estamos alcanzando tal cota de corrupci\u00f3n bajo, el desp\u00f3tico imperio de esta econom\u00eda globalizada, como para pensar que son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta. Y mientras en Espa\u00f1a nuestros \u201ccient\u00edficos de excelencia\u201d siguen mostrando su","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2008-12-19T12:28:00+00:00","article:modified_time":"2010-01-22T02:50:15+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n - Un Universo invisible bajo nuestros pies","twitter:description":"\u00a1Vaya a\u00f1o!. Ni en navidad nos dejan descansar. Parece que estamos alcanzando tal cota de corrupci\u00f3n bajo, el desp\u00f3tico imperio de esta econom\u00eda globalizada, como para pensar que son muy escasas las actividades e iniciativas honestas que actualmente se ponen en marcha en el planeta. Y mientras en Espa\u00f1a nuestros \u201ccient\u00edficos de excelencia\u201d siguen mostrando su","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"109793","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:06:42","updated":"2026-05-26 15:21:50","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica\" title=\"Fraude y Mala Praxis Cient\u00edfica\">Fraude y Mala Praxis Cient\u00edfica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPremios N\u00f3beles. Jurados y Corrupci\u00f3n\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Fraude y Mala Praxis Cient\u00edfica","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica"},{"label":"Premios N\u00f3beles. Jurados y Corrupci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/109793"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=109793"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/109793\/revisions"}],"predecessor-version":[{"id":134812,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/109793\/revisions\/134812"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=109793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=109793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=109793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}