{"id":115777,"date":"2009-04-03T09:41:00","date_gmt":"2009-04-03T09:41:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2009\/04\/03\/115777.aspx"},"modified":"2010-01-22T03:51:30","modified_gmt":"2010-01-22T02:51:30","slug":"una-espana-atrasada-el-acuerdo-de-bolonia-y-las-universidades-espanolas","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777","title":{"rendered":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas"},"content":{"rendered":"<link rel=\"File-List\" href=\"file:\/\/\/C:%5CDOCUME%7E1%5CJuanjo%5CCONFIG%7E1%5CTemp%5Cmsohtml1%5C01%5Cclip_filelist.xml\">\n<style> <!--  \/* Font Definitions *\/  @font-face \t{font-family:\"Comic Sans MS\"; \tpanose-1:3 15 7 2 3 3 2 2 2 4; \tmso-font-charset:0; \tmso-generic-font-family:script; \tmso-font-pitch:variable; \tmso-font-signature:647 0 0 0 159 0;}  \/* Style Definitions *\/  p.MsoNormal, li.MsoNormal, div.MsoNormal \t{mso-style-parent:\"\"; \tmargin:0cm; \tmargin-bottom:.0001pt; \tmso-pagination:widow-orphan; \tfont-size:12.0pt; \tfont-family:\"Times New Roman\"; \tmso-fareast-font-family:\"Times New Roman\";} a:link, span.MsoHyperlink \t{\ttext-decoration:underline; \ttext-underline:single;} a:visited, span.MsoHyperlinkFollowed \t{color:purple; \ttext-decoration:underline; \ttext-underline:single;} @page Section1 \t{size:612.0pt 792.0pt; \tmargin:72.0pt 90.0pt 72.0pt 90.0pt; \tmso-header-margin:36.0pt; \tmso-footer-margin:36.0pt; \tmso-paper-source:0;} div.Section1 \t{page:Section1;} --> <\/style>\n<p><!--  \/* Style Definitions *\/  table.MsoNormalTable \t{mso-style-name:\"Tabla normal\"; \tmso-tstyle-rowband-size:0; \tmso-tstyle-colband-size:0; \tmso-style-noshow:yes; \tmso-style-parent:\"\"; \tmso-padding-alt:0cm 5.4pt 0cm 5.4pt; \tmso-para-margin:0cm; \tmso-para-margin-bottom:.0001pt; \tmso-pagination:widow-orphan; \tfont-size:10.0pt; \tfont-family:\"Times New Roman\";} -->  <\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">Llev\u00e1bamos arrastrando en <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Espa\u00f1a<\/span><\/b>, durante los \u00faltimos tiempos, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">una agria pol\u00e9mica sobre la adaptaci\u00f3n de las Universidades Espa\u00f1olas al Espacio Europeo de Educaci\u00f3n<\/span><\/b>. Se trata de un<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> acuerdo<\/span><\/b> alcanzado en <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">1999<\/span><\/b> por el cual <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">todos los pa\u00edses deben adoptar un modelo compatible que garantice que los t\u00edtulos sean equiparables y convalidados<\/span><\/b> a lo largo y ancho de <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">toda la Uni\u00f3n Europea<\/span><\/b>. Esta iniciativa se conoce popularmente como el <b style=\"\"><span style=\"color: green;\">Acuerdo de Bolonia<\/span><\/b>. Empero <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">las Universidades Espa\u00f1olas miraron durante muchos a\u00f1os hacia otro lado y ahora vienen las urgencias<\/span><\/b>, conflictos y disgustos. Del mismo modo, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">las autoridades del Ministerio competente tampoco han estado a la altura de las circunstancias<\/span><\/b>. M\u00e1s aun, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">parte del profesorado Universitario, ha desinformado al alumnado<\/span><\/b> que ha comenzado a tomar las aulas de algunos campus para <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">mostrar su protesta<\/span><\/b>. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Estos j\u00f3venes tienen mucho de que quejarse<\/span><\/b> respecto al funcionamiento de la educaci\u00f3n superior en Espa\u00f1a y sus expectativas de futuro. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Pero se han equivocado de bando<\/span><\/b>. Se que en Espa\u00f1a este post no lo van a leer ni mis m\u00e1s \u00edntimos amigos. Todo el mundo esta aburrido a estas alturas de la mir\u00edada de notas de prensa que se vienen publicando un d\u00eda s\u00ed y otro tambi\u00e9n sobre el tema. Sin embargo, quiero dejar constancia de mi opini\u00f3n por escrito, mal que les pese a algunos. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Espa\u00f1a sigue muy a la zaga en muchas materias respecto a las grandes potencias europeas, pero esta vez se trata de un<span style=\"\">&nbsp; <\/span>\u201cretraso mental colectivo\u201d que muestra las miserias end\u00e9micas de la estructura universitaria del pa\u00eds<\/span><\/b>. Parece que seguimos sin querernos enterar de c\u00f3mo funciona Europa. Todo parece apuntalar el viejo y lamentable dicho de que \u201c<b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Europa termina en los Pirineos<\/span><\/b>\u201d. Al margen de la deficiente y tarda reacci\u00f3n ministerial, existen <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">dos colectivos universitarios que intentan<\/span><\/b> vanamente <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">confundir a los alumnos<\/span><\/b>, con vistas a <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">mantener sus privilegios<\/span><\/b>. Hablamos de <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">algunas facultades de humanidades y muchas Escuelas Polit\u00e9cnicas Superiores<\/span><\/b>. Una vez m\u00e1s, voy a ganar m\u00e1s enemigos que amigos, pero alguien tiene que \u201cponer el cascabel al gato\u201d. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">No soy el \u00fanico, pero <\/span><\/b>probablemente <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">este post ser\u00e1 de los m\u00e1s contundentes<\/span><\/b>. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<img decoding=\"async\" src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/o_Acurdo%20de%20Bolonia2.JPG\" width=\"439\" height=\"273\"><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 8pt; font-family: &quot;Comic Sans MS&quot;;\"><a href=\"http:\/\/www.citop.es\/ceitop\/Documentos%20CEITOP\/sectorial.htm\">Bolonia: Una Ciudad Universitaria Italiana de <o:p><\/o:p><\/a><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span class=\"MsoHyperlink\"><span style=\"font-size: 8pt; font-family: &quot;Comic Sans MS&quot;;\"><a href=\"http:\/\/www.citop.es\/ceitop\/Documentos%20CEITOP\/sectorial.htm\">Impresionante Belleza. Fuente: Documentos CEITOP<\/a><\/span><\/span><span style=\"font-size: 8pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p><\/o:p><\/span><\/p>\n<p>  <!--more--><link rel=\"File-List\" href=\"file:\/\/\/C:%5CDOCUME%7E1%5CJuanjo%5CCONFIG%7E1%5CTemp%5Cmsohtml1%5C01%5Cclip_filelist.xml\">\n<style> <!--  \/* Font Definitions *\/  @font-face \t{font-family:\"Comic Sans MS\"; \tpanose-1:3 15 7 2 3 3 2 2 2 4; \tmso-font-charset:0; \tmso-generic-font-family:script; \tmso-font-pitch:variable; \tmso-font-signature:647 0 0 0 159 0;}  \/* Style Definitions *\/  p.MsoNormal, li.MsoNormal, div.MsoNormal \t{mso-style-parent:\"\"; \tmargin:0cm; \tmargin-bottom:.0001pt; \tmso-pagination:widow-orphan; \tfont-size:12.0pt; \tfont-family:\"Times New Roman\"; \tmso-fareast-font-family:\"Times New Roman\";} a:link, span.MsoHyperlink \t{\ttext-decoration:underline; \ttext-underline:single;} a:visited, span.MsoHyperlinkFollowed \t{color:purple; \ttext-decoration:underline; \ttext-underline:single;} @page Section1 \t{size:612.0pt 792.0pt; \tmargin:72.0pt 90.0pt 72.0pt 90.0pt; \tmso-header-margin:36.0pt; \tmso-footer-margin:36.0pt; \tmso-paper-source:0;} div.Section1 \t{page:Section1;} --> <\/style>\n<p><!--  \/* Style Definitions *\/  table.MsoNormalTable \t{mso-style-name:\"Tabla normal\"; \tmso-tstyle-rowband-size:0; \tmso-tstyle-colband-size:0; \tmso-style-noshow:yes; \tmso-style-parent:\"\"; \tmso-padding-alt:0cm 5.4pt 0cm 5.4pt; \tmso-para-margin:0cm; \tmso-para-margin-bottom:.0001pt; \tmso-pagination:widow-orphan; \tfont-size:10.0pt; \tfont-family:\"Times New Roman\";} -->  <\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">El que en la UE un t\u00edtulo universitario logrado en un pa\u00eds no tuviera validez en otro resultaba absurdo. Y de eso trata del <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">\u201cAcuerdo de Bolonia\u201d: alcanzar unos m\u00ednimos consensos con vistas a que las titulaciones atesoraran un valor a escala continental<\/span><\/b>. Una vez que en <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">1999<\/span><\/b> se logr\u00f3 tal objetivo, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">lleg\u00f3 el obligado momento para que todos los pa\u00edses iniciaran el proceso de modificaci\u00f3n de sus estructuras y materias docentes<\/span><\/b>. Reitero que hablamos <span style=\"\">&nbsp;<\/span>de casi todas las Universidades Europeas, aunque como veremos en algunas mucho m\u00e1s que en otras. <span style=\"\">&nbsp;<\/span>\u00bfQu\u00e9 pretendo se\u00f1alar?<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">Una vez m\u00e1s,<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> los anglosajones<\/span><\/b> (incluidos Holanda y pa\u00edses n\u00f3rdicos) <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">nos ganaron la batalla <\/span><\/b>como resultado de su diligencia, combatividad y habilidad diplom\u00e1tica. Es decir, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">impuso su modelo a todos los dem\u00e1s, incluyendo a las poderosas Francia y Alemania<\/span><\/b>. Por tanto, no estamos hablando de un producto realmente consensuado, sino de la extensi\u00f3n del de unos pa\u00edses a otros, con la anuencia de los \u00faltimos. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">\u00bfResulta negativo? Por un lado podemos decir que s\u00ed, por cuanto<\/span><\/b> tal hecho constata que <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">algunos Estados (y no solo Espa\u00f1a) no se encuentran interesadas en estas nimiedades<\/span><\/b>. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Sin embargo, para todos aquellos que hayan viajado, estudiado o investigado en universidades anglosajones (en sentido amplio) no nos resulta negativo en absoluto<\/span><\/b>.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">Conozco este modelo, y de hecho <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">he inducido a que algunos antiguos estudiantes predoctorales bajo mi cargo, y<\/span><\/b> otros de amigos y familiares, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">probaran sus bondades y debilidades<\/span><\/b>. Y he te aqu\u00ed que <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">la mayor\u00eda se han divertido, adem\u00e1s de haber aprendido<\/span><\/b> otro modo de entender de docencia. M\u00e1s aun,<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> un n\u00famero determinado de estos j\u00f3venes<\/span><\/b>, que en la Universidad Espa\u00f1ola no hab\u00edan finalizado su carrera con buenas calificaciones, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">han logrado all\u00ed<\/span><\/b> \u201cponerse las pilas\u201d y <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">mejorar ostensiblemente su rendimiento y aptitud<\/span><\/b>. Como resultado, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">lograron encontrar trabajo con cierta facilidad<\/span><\/b>, y lo que es m\u00e1s importante, <span style=\"\">&nbsp;<\/span><b style=\"\"><span style=\"color: rgb(51, 102, 255);\">en su \u00e1mbito de inter\u00e9s<\/span><\/b> en Espa\u00f1a.<span style=\"\">&nbsp; <\/span>\u00bfCu\u00e1l fue la raz\u00f3n? \u00bfQu\u00e9 atesoraban un master en uno de aquellos pa\u00edses? Pudiera ser. Sin embargo, me inclino a pensar, que <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">aquellos sistemas educativos son m\u00e1s divertidos, <span style=\"\">&nbsp;<\/span>y aprender con agrado no tiene precio<\/span><\/b>. Del mismo modo, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">tambi\u00e9n fomentan el<\/span><\/b> imprescindible<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> trabajo en equipo<\/span><\/b>, lo cual es <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">otro valor a\u00f1adido<\/span><\/b>. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">El n\u00famero de clases pres\u00e9nciales es ostensiblemente menor<\/span><\/b>. Tal detrimento deviene <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">a favor de una mayor carga de trabajo en equipo y intensas tutor\u00edas por parte del profesorado<\/span><\/b>. Obviamente, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">cualquier docente<\/span><\/b> Espa\u00f1ol (o de otro pa\u00eds) <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">que impartiera sus clases y se dedicara a sestear<\/span><\/b>, o ausentarse el resto del d\u00eda de su lugar de trabajo, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">se encontrar\u00e1 molesto con \u201cBolonia\u201d<\/span><\/b>. No obstante,<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> los contribuyentes no le pagan con vistas a que lleven una vida tan acomodaticia, sino al objeto de que<\/span><\/b> ense\u00f1e adecuadamente a nuestros j\u00f3venes. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Empero la endogamia y otros males end\u00e9micos de la Universidad espa\u00f1ola siguen ah\u00ed<\/span><\/b>. <span style=\"\">&nbsp;<\/span>Obviamente,<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> no debemos generalizar<\/span><\/b> tales problemas al conjunto del colectivo docente universitario, ya que <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">las reacciones han sido muy dispares seg\u00fan<\/span><\/b> la naturaleza de los estudios. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><b style=\"\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;; color: rgb(51, 102, 255);\">En las carreras de ciencias<\/span><\/b><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">, que no en las de las ingenier\u00edas, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">los profesores j\u00f3venes<\/span><\/b> se vieron generalmente obligados (<b style=\"\"><span style=\"color: rgb(51, 102, 255);\">con la salvedad de<\/span><\/b> aquellos departamentos en donde la endogamia sigue incrustada como un c\u00e1ncer cuasi imposible de extirpar) a realizar estancias en el extranjero de unos dos a\u00f1os como m\u00ednimo, con vistas a lograr una posici\u00f3n estable en las plantillas de sus facultades. En consecuencia, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">la mayor\u00eda conocen sobradamente el estilo anglosaj\u00f3n y como corolario han informado debidamente a sus alumnos<\/span><\/b>. Obviamente no todos, pero si una buena parte de ellos.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><b style=\"\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;; color: rgb(51, 102, 255);\">No ha ocurrido generalmente lo mismo en las facultades de humanidades, as\u00ed como en muchas polit\u00e9cnicas<\/span><\/b><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">, por lo que es en precisamente ellas en donde<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> profesores de boina<\/span><\/b> (las primeras) <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">o los que defienden intereses colegiales decimon\u00f3nicos<\/span><\/b> (las segundas) presentan m\u00e1s batalla, al <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">soliviantar a los estudiantes con sus miedos y mezquindades<\/span>, <\/b>en un desesperado <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">intento de torpedear el proceso<\/span><\/b>, siempre que est\u00e9 en sus manos. Reitero que <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">hablo en t\u00e9rminos relativos, por cuento habr\u00e1 muchas y honrosas excepciones<\/span><\/b>. Pero la prensa da una y otra vez cuenta de descabellados argumentos \u201cantibolonia\u201d. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><b style=\"\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;; color: rgb(51, 102, 255);\">Quiz\u00e1s ha llegado el momento de recordar que las universidades espa\u00f1olas son de las que m\u00e1s trabas oponen para convalidar las titulaciones obtenidas en otros pa\u00edses<\/span><\/b><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">, con independencia de su procedencia. Algunos j\u00f3venes latinoamericanos consideran que hay discriminaci\u00f3n contra ellos, pero no es as\u00ed. Lo mismo ocurr\u00eda con los que se licenciaron en Europa o EE.UU. <span style=\"\">&nbsp;<\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">Para todos aquellos que no conozcan el <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">modelo anglosaj\u00f3n<\/span><\/b> tan solo decir, que <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">se da m\u00e1s importancia al aprender a conocer que a los conocimientos que uno atesora<\/span><\/b> en un determinado momento. Este hecho ha inducido a que cierta parte del profesorado alegue que, los estudiantes de intercambio (<b style=\"\"><span style=\"color: rgb(51, 102, 255);\">becas Erasmus<\/span><\/b>) que llegaban de otras universidades europeas a Espa\u00f1a durante una temporada, mostraran ser m\u00e1s ignorantes que los de aqu\u00ed. No me detendr\u00e9 aqu\u00ed a rebatir tama\u00f1a estupidez. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Memoria y capacidad de aprender no son sin\u00f3nimas<\/span><\/b>. Cuanto menos contenido \u201cborrable\u201d se introduzca en el disco duro de los estudiantes tanto mejor para ellos y para todos. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">El sistema de clases pres\u00e9nciales y ex\u00e1menes da lugar a primar la memoria respecto a las habilidades<\/span><\/b>.<span style=\"\">&nbsp; <\/span><span style=\"\">&nbsp;<\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><b style=\"\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;; color: rgb(51, 102, 255);\">Los t\u00edtulos al estilo anglosaj\u00f3n son muy diferentes que los de otros pa\u00edses del continente, con menos carreras y m\u00e1s generales. La infundada alarma de que un t\u00edtulo desaparece debiera matizarse cuando se entiende esta filosof\u00eda<\/span><\/b><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">. Empero no hay m\u00e1s ciego que el que no quiere ver, ni m\u00e1s ignorante que el que no quiere ni escuchar ni informarse. Y ah\u00ed nos encontramos. En el mundo anglosaj\u00f3n <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">la preparaci\u00f3n del alumno y las materias estudiadas<\/span><\/b> (junto con las<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> calificaciones obtenidas<\/span><\/b>) <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">priman sobre el t\u00edtulo en si mismo<\/span><\/b>. Tal situaci\u00f3n es la que parece que muchos profesores y colectivos no quieren entender. Pero es su problema.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">En el caso de las demandas de muchas <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">polit\u00e9cnicas, sus quejas devienen de la \u201cposible\u201d p\u00e9rdida de unos privilegios medievales impropios de la sociedad en donde vivimos<\/span><\/b>. El h\u00e1bito no hace al monje. Es decir, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">que por ser ingeniero no te encuentras m\u00e1s capacitado que por ser licenciado<\/span><\/b>. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Las habilidades ni se determinan por decreto ley: el alumno las atesora o no<\/span><\/b>. Y tanto la Universidad, como la empresa, y <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">la sociedad<\/span><\/b> en su conjunto <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">necesita demandar a los j\u00f3venes m\u00e1s preparados, no a los que atesoran un determinado t\u00edtulo<\/span><\/b>. Por tanto las protestas estudiantiles recientes van por tal camino. Es nocivo pretender mantener <span style=\"\">&nbsp;<\/span>su indecorosa posici\u00f3n de dominancia por decreto ley. Pero hay m\u00e1s. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Son muchos los presuntos docentes de las polit\u00e9cnicas, los que tras impartir sus clases, abandonaban la facultad para trabajar en la empresa privada<\/span><\/b> (cuando no eran los due\u00f1os de sus propias consultor\u00edas) alcanzando as\u00ed<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> un doble sueldo que manten\u00eda un estatus ya fomentado por su poder colegial<\/span><\/b>. Obviamente, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">al exigirles ahora que publiquen ISI papers, as\u00ed como cumplir con su obligaci\u00f3n a dedicar mucho m\u00e1s tiempo a las tutor\u00edas<\/span><\/b> con los alumnos, ven amenazado el doble juego que ejerc\u00edan y disfrutaban. M\u00e1s aun, un amigo profesor en algunas de estas polit\u00e9cnicas me comentaban amargamente como <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">hac\u00edan uso en sus trabajos privados del material de la universidad, alguno del cual desaparec\u00eda tras ser solicitado<\/span><\/b>. Y no estoy hablando de casos singulares, sino de actitudes muy extendidas. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">Con independencia de estos asuntos, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">existen algunos privilegiados en ciertas facultades y polit\u00e9cnicas que tras impartir sus clases se dedican a hacer sus tesis durante decenios<\/span><\/b>, despilfarrando el dinero de los contribuyentes. En otras palabras, que <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">para llevar a cabo su tesis doctoral parecen requerir 15 o 20 a\u00f1os<\/span><\/b>. \u00a1Incre\u00edble!. Lo \u00fanico que puedo pensar de ellos, sin apenas curr\u00edculo, es que nos topamos con <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">vagos y\/o incompetentes<\/span><\/b>. Sin embargo, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">un sistema endog\u00e1mico les mantiene a costa de j\u00f3venes cient\u00edficos muy preparados tras investigar varios a\u00f1os en pa\u00edses punteros<\/span><\/b>. Personalmente conozco a uno indirectamente que a sus 47 a\u00f1itos sigue que dale que dale con su tesis (eso si, no se pierde vacaciones algunas, al contrario que muchos otros que no pueden permit\u00edrselo por necesidades de la propia investigaci\u00f3n. Trabaja sobre el mercado de trabajo y dice ser polit\u00f3logo. \u00a1Hombre de Dios!, si el primero ha variado tanto en las \u00faltimas d\u00e9cadas, que mientras tu sesteas con \u201dEl Pa\u00eds\u201d bajo el brazo, a penas empezar debes cambiar todo el gui\u00f3n, una vez y otra tambi\u00e9n. La sociedad cambia m\u00e1s deprisa que el objetivo de su Tesis. Pues tampoco es un caso singular. Alguien deb\u00eda<span style=\"\">&nbsp; <\/span>elaborar estad\u00edsticas a este respecto. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><b style=\"\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;; color: rgb(51, 102, 255);\">Debe quedar claro que no defiendo la obligatoriedad de investigar en el extranjero cuando el curr\u00edculo avala que se trata de un buen profesional<\/span><\/b><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">. Defiendo que no se puede uno pasar 20 a\u00f1os impart8endo la clase y luego\u2026.. Eso, \u00bfY luego que? No me dejan decir el nombre y le tengo unas ganas\u2026\u2026.. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">Dicho todo esto, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">indiquemos que son tales elementos <\/span><\/b>(los tres colectivos mencionados no solo los \u00faltimos) <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">los que intoxican a los alumnos se\u00f1alando que \u201cBolonia\u201d mercantiliza el conocimiento a favor de las empresas y multinacionales, anulando la posibilidad del libre pensamiento<\/span><\/b>. \u00a1Falso! <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">\u00a1Rotundamente falso!. \u00bflibre pensadores o alegres vividores?<\/span><\/b>. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">El libre pensamiento procede de<\/span><\/b> la personalidad y de la cultura, que hoy en d\u00eda deviene en aprendizaje continuado y convicciones firmes.<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> No vamos a negar que los defensores de la \u201cBobalizaci\u00f3n Econ\u00f3mica\u201d<\/span><\/b> (as\u00ed nos va ahora) <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">lanzan este tipo de propaganda nauseabunda: la Universidad al servicio de los empresarios<\/span><\/b>, por que es cierto. Ahora bien, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">se ha tratado de un proceso sincr\u00f3nico con Bolonia<\/span><\/b> por el puro devenir socioecon\u00f3mico de los acontecimientos: el creciente imperio del capital sobre los ciudadanos. Sin embargo, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">a \u201cBolonia\u201d no le ata\u00f1en tales asuntos sangrantes. No existe relaci\u00f3n causa-efecto<\/span><\/b>. Reitero que son dos tendencias que han coincidido, y debiera ser la obligaci\u00f3n de estos \u201cintelectuales\u201d separar el grano de la paja, ya que si no terminan por hacer v\u00e1lido el dicho espa\u00f1ol de \u201cdime de que presumes y te dir\u00e9 de que careces\u201d. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">Finalmente, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">algunos<\/span><\/b> <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">alumnos confundidos tendenciosamente<\/span><\/b> por alguna de estas tres tendencias (por no hablar de castas en un caso concreto que se sobre entiende), <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">se han lanzado a una protesta sin fundamento<\/span><\/b>. Y <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">lo lamentable de todo este asunto es que los chavales tienen mil y una razones para salir a la calle y protestar ante el panorama que les ha deparado esta \u201cBobalizaci\u00f3n globalizada\u201d durante los \u00faltimos 15 a\u00f1os<\/span><\/b>. Terminar una carrera universitaria para cobrar un salario m\u00ednimo o cercano a \u00e9l, y un empleo precario (temporal), no deja de ser una ignominia. En Espa\u00f1a les llamamos \u201c<b style=\"\"><span style=\"color: rgb(51, 102, 255);\">mileuristas<\/span><\/b>\u201d, pero muchos se dar\u00edan con un canto en los dientes si cobraran 1000 euros, debido a que no suelen sobrepasar los 600. Pues bien, con esa fortuna es imposible vivir en este pa\u00eds y formar una familia, por lo que a menudo se encuentran obligados a vivir \u201ccon pap\u00e1 y mam\u00e1\u201d. Y eso si que es un drama social. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Espa\u00f1a atesora el dudoso honor de ser uno de los Estados de la UE en donde un universitario recibe menores remuneraciones econ\u00f3micas<\/span><\/b>.<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> Y mientras tanto, nuestros empresarios que \u201cde los m\u00e1s retrasados en materia de innovaci\u00f3n y desarrollo tecnol\u00f3gico\u201d claman que no hay vacaciones y que falta personal cualificado<\/span><\/b>. Habr\u00eda que recordar a estos ego\u00edstas cicateros (\u201cen t\u00e9rminos generales, una vez m\u00e1s\u201d) que para percibir 600 euros, es mejor dedicarse a ser obrero o limpiar casas, ya que se gana mucho m\u00e1s. Por tanto <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">nuestros universitarios tienen todos los motivos para protestar y yo lo har\u00eda<\/span><\/b>. Ahora bien, se han equivocado de bando.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><b style=\"\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;; color: rgb(51, 102, 255);\">Existen otros problemas reales que acompa\u00f1an a \u201cBolonia\u201d m\u00e1s peliagudos<\/span><\/b><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">. Un <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">profesorado muy envejecido y numeroso<\/span><\/b> (en t\u00e9rminos de ratio por alumno) no va a adaptarse a la nueva forma de impartir docencia.<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> Son necesarias<\/span><\/b> muchas prejubilaciones anticipadas <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">y un personal docente m\u00e1s rejuvenecido y de mentalidad abierta<\/span><\/b>. Del mismo modo, l<b style=\"\"><span style=\"color: rgb(51, 102, 255);\">as Universidades necesitan imperiosamente una financiaci\u00f3n m\u00e1s generosa para poner en pr\u00e1ctica el \u201cesp\u00edritu de Bolonia\u201d<\/span><\/b> con garant\u00edas. Una vez m\u00e1s, los gobiernos de <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">este pa\u00eds<\/span><\/b> vuelven a<span style=\"\">&nbsp; <\/span>alcanzar el dudoso galard\u00f3n de pertenecer al <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">grupo de la OCDE que menos recursos libera por alumno universitario<\/span><\/b>. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Estas dos trabas, en conjunci\u00f3n con la crisis econ\u00f3mica, el descenso del n\u00famero de universitarios, la desmesurada proliferaci\u00f3n de universidades regionales<\/span><\/b> (aqu\u00ed llamadas guarder\u00eda) <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">amenazan con hacer naufragar las reformas que demanda el esp\u00edritu de Bolonia<\/span><\/b>. Y mientras tanto, nuestros j\u00f3venes deben aprender a identificar con mayor precisi\u00f3n, tanto a sus enemigos como a sus amigos, porque razones para clamar al cielo si las tienen y muchas, pero fuera de \u201cBolonia\u201d.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\">Obviamente no puedo hacer frente a la enorme cantidad de aclaraciones que deber\u00eda abordar con vistas a desmentir a los \u201cantibolonios\u201d, cuya actitud detesto. Pera emprender tal laborar requerir\u00eda un libro, no un modesto post. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Bolonia, es una cuidad maravillosa. Nadie de all\u00ed pensar\u00eda que en este y alg\u00fan otro pa\u00eds, pronunciar su nombre generar\u00eda tanta inquina y\/o desasosiego<\/span><\/b>.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;; color: rgb(204, 0, 0);\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<span style=\"\">&nbsp;&nbsp; <\/span><span style=\"\">&nbsp;&nbsp;<\/span><span style=\"\">&nbsp;&nbsp;&nbsp;<\/span><span style=\"\">&nbsp;&nbsp;&nbsp;<\/span><span style=\"\">&nbsp;&nbsp;&nbsp;&nbsp;<\/span><span style=\"\">&nbsp;&nbsp;<\/span><span style=\"\">&nbsp;<\/span><span style=\"\">&nbsp;<\/span><span style=\"\">&nbsp;&nbsp;&nbsp;<\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: &quot;Comic Sans MS&quot;;\"><b>PD.<\/b> <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">No albergo la menor inquina en contra de los colegios profesionales<\/span><\/b>. De hecho soy colegiado fundador del de Bi\u00f3logos. M\u00e1s a\u00fan, escribo una columna habitual para la <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Revista Bi\u00f3logos<\/span><\/b> del<a href=\"http:\/\/www.cobcm.net\/home.html\"> COBCM<\/a>. Sin embargo, debo a\u00f1adir que luchamos durante a\u00f1os para que fuera reconocido, con vistas a que otros Colegios con gran fuerza y muchos recursos econ\u00f3micos no siguieran impidiendo que los licenciados de esta carrera pudieran acceder a plazas y concursos para los que est\u00e1bamos m\u00e1s capacitados que ellos mismos. El d\u00eda que el COBM luche para entorpecer las leg\u00edtimas exigencias profesionales de otras licenciaturas, estar seguros que me borrar\u00e9 tras denunciarlo. Ahora bien, tengo algunos amigos que se encuentran en las directivas de algunos de los poderosos, y lo que me han narrado me parece espeluznante. Si no hablo es por no perjudicarles ya que se trata de comentarios confidenciales. Porque si por esta boquita comenzaran a salir informaciones\u2026.. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Una cuesti\u00f3n es agrupar a un colectivo para que debata su problem\u00e1tica y defienda sus leg\u00edtimos intereses y otra bien distinta es generar poderosos lobbies de presi\u00f3n pol\u00edtica y medi\u00e1tica, utilizando t\u00e1cticas de dudosa legitimidad, como m\u00ednimo \u00e9tica<\/span><\/b>. <span style=\"\">&nbsp;<\/span>Y son justamente los que defienden las denominadas \u201ccarreras regladas\u201d los m\u00e1s peligrosos e influyentes: gran n\u00famero de ingenier\u00edas, medicina, arquitectura, etc. <span style=\"\">&nbsp;&nbsp;<\/span><o:p><\/o:p><\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Llev\u00e1bamos arrastrando en Espa\u00f1a, durante los \u00faltimos tiempos, una agria pol\u00e9mica sobre la adaptaci\u00f3n de las Universidades Espa\u00f1olas al Espacio Europeo de Educaci\u00f3n. Se trata de un acuerdo alcanzado en 1999 por el cual todos los pa\u00edses deben adoptar un modelo compatible que garantice que los t\u00edtulos sean equiparables y convalidados a lo largo y ancho de toda la Uni\u00f3n Europea. Esta iniciativa se conoce popularmente como el Acuerdo de Bolonia. Empero las Universidades Espa\u00f1olas miraron durante muchos a\u00f1os hacia otro lado y ahora vienen las urgencias, conflictos y disgustos. Del mismo modo, las autoridades del Ministerio competente tampoco han\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[605,615,606],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Llev\u00e1bamos arrastrando en Espa\u00f1a, durante los \u00faltimos tiempos, una agria pol\u00e9mica sobre la adaptaci\u00f3n de las Universidades Espa\u00f1olas al Espacio Europeo de Educaci\u00f3n. Se trata de un acuerdo alcanzado en 1999 por el cual todos los pa\u00edses deben adoptar un modelo compatible que garantice que los t\u00edtulos sean equiparables y convalidados a lo largo y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Llev\u00e1bamos arrastrando en Espa\u00f1a, durante los \u00faltimos tiempos, una agria pol\u00e9mica sobre la adaptaci\u00f3n de las Universidades Espa\u00f1olas al Espacio Europeo de Educaci\u00f3n. Se trata de un acuerdo alcanzado en 1999 por el cual todos los pa\u00edses deben adoptar un modelo compatible que garantice que los t\u00edtulos sean equiparables y convalidados a lo largo y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2009-04-03T09:41:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-22T02:51:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Llev\u00e1bamos arrastrando en Espa\u00f1a, durante los \u00faltimos tiempos, una agria pol\u00e9mica sobre la adaptaci\u00f3n de las Universidades Espa\u00f1olas al Espacio Europeo de Educaci\u00f3n. Se trata de un acuerdo alcanzado en 1999 por el cual todos los pa\u00edses deben adoptar un modelo compatible que garantice que los t\u00edtulos sean equiparables y convalidados a lo largo y\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777#blogposting\",\"name\":\"Una Espa\\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\\u00f1olas - Un Universo invisible bajo nuestros pies\",\"headline\":\"Una Espa\\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\\u00f1olas\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/159\\\/o_Acurdo%20de%20Bolonia2.JPG\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777\\\/#articleImage\"},\"datePublished\":\"2009-04-03T09:41:00+01:00\",\"dateModified\":\"2010-01-22T03:51:30+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":8,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777#webpage\"},\"articleSection\":\"Fraude y Mala Praxis Cient\\u00edfica, Notas Breves de Prensa, Prensa y Pol\\u00edtica Cient\\u00edfica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fraude-y-mala-praxis-cientifica#listItem\",\"name\":\"Fraude y Mala Praxis Cient\\u00edfica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fraude-y-mala-praxis-cientifica#listItem\",\"position\":2,\"name\":\"Fraude y Mala Praxis Cient\\u00edfica\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fraude-y-mala-praxis-cientifica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777#listItem\",\"name\":\"Una Espa\\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\\u00f1olas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777#listItem\",\"position\":3,\"name\":\"Una Espa\\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\\u00f1olas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fraude-y-mala-praxis-cientifica#listItem\",\"name\":\"Fraude y Mala Praxis Cient\\u00edfica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777\",\"name\":\"Una Espa\\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\\u00f1olas - Un Universo invisible bajo nuestros pies\",\"description\":\"Llev\\u00e1bamos arrastrando en Espa\\u00f1a, durante los \\u00faltimos tiempos, una agria pol\\u00e9mica sobre la adaptaci\\u00f3n de las Universidades Espa\\u00f1olas al Espacio Europeo de Educaci\\u00f3n. Se trata de un acuerdo alcanzado en 1999 por el cual todos los pa\\u00edses deben adoptar un modelo compatible que garantice que los t\\u00edtulos sean equiparables y convalidados a lo largo y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2009\\\/04\\\/03\\\/115777#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2009-04-03T09:41:00+01:00\",\"dateModified\":\"2010-01-22T03:51:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas - Un Universo invisible bajo nuestros pies","description":"Llev\u00e1bamos arrastrando en Espa\u00f1a, durante los \u00faltimos tiempos, una agria pol\u00e9mica sobre la adaptaci\u00f3n de las Universidades Espa\u00f1olas al Espacio Europeo de Educaci\u00f3n. Se trata de un acuerdo alcanzado en 1999 por el cual todos los pa\u00edses deben adoptar un modelo compatible que garantice que los t\u00edtulos sean equiparables y convalidados a lo largo y","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777#blogposting","name":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas - Un Universo invisible bajo nuestros pies","headline":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/o_Acurdo%20de%20Bolonia2.JPG","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777\/#articleImage"},"datePublished":"2009-04-03T09:41:00+01:00","dateModified":"2010-01-22T03:51:30+01:00","inLanguage":"es-ES","commentCount":8,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777#webpage"},"articleSection":"Fraude y Mala Praxis Cient\u00edfica, Notas Breves de Prensa, Prensa y Pol\u00edtica Cient\u00edfica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica#listItem","name":"Fraude y Mala Praxis Cient\u00edfica"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica#listItem","position":2,"name":"Fraude y Mala Praxis Cient\u00edfica","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777#listItem","name":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777#listItem","position":3,"name":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica#listItem","name":"Fraude y Mala Praxis Cient\u00edfica"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777","name":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas - Un Universo invisible bajo nuestros pies","description":"Llev\u00e1bamos arrastrando en Espa\u00f1a, durante los \u00faltimos tiempos, una agria pol\u00e9mica sobre la adaptaci\u00f3n de las Universidades Espa\u00f1olas al Espacio Europeo de Educaci\u00f3n. Se trata de un acuerdo alcanzado en 1999 por el cual todos los pa\u00edses deben adoptar un modelo compatible que garantice que los t\u00edtulos sean equiparables y convalidados a lo largo y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2009-04-03T09:41:00+01:00","dateModified":"2010-01-22T03:51:30+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas - Un Universo invisible bajo nuestros pies","og:description":"Llev\u00e1bamos arrastrando en Espa\u00f1a, durante los \u00faltimos tiempos, una agria pol\u00e9mica sobre la adaptaci\u00f3n de las Universidades Espa\u00f1olas al Espacio Europeo de Educaci\u00f3n. Se trata de un acuerdo alcanzado en 1999 por el cual todos los pa\u00edses deben adoptar un modelo compatible que garantice que los t\u00edtulos sean equiparables y convalidados a lo largo y","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2009-04-03T09:41:00+00:00","article:modified_time":"2010-01-22T02:51:30+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas - Un Universo invisible bajo nuestros pies","twitter:description":"Llev\u00e1bamos arrastrando en Espa\u00f1a, durante los \u00faltimos tiempos, una agria pol\u00e9mica sobre la adaptaci\u00f3n de las Universidades Espa\u00f1olas al Espacio Europeo de Educaci\u00f3n. Se trata de un acuerdo alcanzado en 1999 por el cual todos los pa\u00edses deben adoptar un modelo compatible que garantice que los t\u00edtulos sean equiparables y convalidados a lo largo y","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"115777","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:13:47","updated":"2026-05-26 15:33:48","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica\" title=\"Fraude y Mala Praxis Cient\u00edfica\">Fraude y Mala Praxis Cient\u00edfica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUna Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Fraude y Mala Praxis Cient\u00edfica","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica"},{"label":"Una Espa\u00f1a Atrasada: El Acuerdo de Bolonia y las Universidades Espa\u00f1olas","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/03\/115777"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/115777"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=115777"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/115777\/revisions"}],"predecessor-version":[{"id":134879,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/115777\/revisions\/134879"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=115777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=115777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=115777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}