{"id":11693,"date":"2006-01-07T14:35:00","date_gmt":"2006-01-07T14:35:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2006\/01\/07\/11693.aspx"},"modified":"2023-02-22T13:13:47","modified_gmt":"2023-02-22T12:13:47","slug":"edafodiversidad-y-biodiversidad-10-sobre-los-modelos-de-distribucion-de-abundancia-descripcion","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693","title":{"rendered":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: center\" align=\"center\"><b><span lang=\"ES\" style=\"font-size: 14pt;color: #cc0000;font-family: 'Comic Sans MS'\">Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n<\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><i><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/i><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><b><i><span lang=\"ES\" style=\"font-size: 11pt;color: blue;font-family: 'Comic Sans MS'\">Series Geom\u00e9tricas<\/span><\/i><\/b><b><\/b><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\">Si suponemos que el primer <i>taxa<\/i> ocupa una fracci\u00f3n (<i>K<\/i>) de un h\u00e1bitat previamente vac\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\u00f3n <i>K<\/i> del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\u00e1fico de rango abundancia obtenemos la l\u00ednea recta que corresponde a una serie geom\u00e9trica, tal como mostr\u00f3 Motoruma en 1932.<span style=\"color: blue\"> Este modelo tambi\u00e9n ha sido denominado hip\u00f3tesis de \u00abapropiaci\u00f3n\u00bb o \u00abrelleno\u00bb del nicho<\/span> (<i>niche-pre-emption hypothesis<\/i>)\u00bb. El modelo fue muy utilizado en la descripci\u00f3n de la diversidad de plantes vasculares en los ambientes templados. Como ya mentamos en la contribuci\u00f3n anterior, se trata del modelo menos equitativo y que suele asociarse a situaci\u00f3n de estr\u00e9s biocen\u00f3tico y a peque\u00f1as muestras de comunidades estables que se ajustan a una lognormal. <\/span><\/p>\n<p><!--more--><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;color: blue;font-family: 'Comic Sans MS'\"><em><strong>Series logar\u00edtmicas (o logseries)<\/strong><\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">Originalmente propuestas por Fisher (Fisher <em>et al<\/em>. 1943), como una de las mejores distribuciones para describir la abundancia de las especies, ha sido posteriormente criticada por la ausencia de bases biol\u00f3gicas (teor\u00eda) en lo concerniente a la interacci\u00f3n de las especies. Al principio fue ampliamente aceptado, debido a que la abundancia en el reino animal, especialmente de insectos, se ajustaba bastante bien a este modelo, cuando se representaba en gr\u00e1ficos de rango-abundancia, Las especies, estar\u00edan alineadas de mayor a menos abundancia, siguiendo la siguiente serie: <\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: center\" align=\"center\"><em><span style=\"color: #000000\">ax, ax<sup>2<\/sup>\/2, ax<sup>3<\/sup>\/3<\/span><\/em><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"color: #000000\">Cabe se\u00f1alar que <em>a <\/em><\/span><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">tambi\u00e9n ha sido propuesta por diversos autores como \u00edndice de diversidad, con independencia de que la distribuci\u00f3n de los datos se ajuste a la serie o no. <\/span><span style=\"color: blue\">Las logseries tambi\u00e9n podr\u00edan considerarse como una aproximaci\u00f3n adecuada a las distribuciones de tipo gamma<\/span><span style=\"color: #000000\">, de m\u00e1xima varianza, poco utilizadas en los estudios de biodiversidad y de las cuales la<\/span><span style=\"color: blue\"> binomial negativa<\/span><span style=\"color: #000000\"> es una de las m\u00e1s conocidas. <\/span><span style=\"color: blue\">Los modelos de tipo gamma suelen aparecer como resultado de fen\u00f3menos en los que interaccionan dos procesos distintos<\/span><span style=\"color: #000000\">. <\/span><span style=\"color: #cc0000\">May (1975) sugiere que las series geom\u00e9tricas, o lo que es lo mismo, la hip\u00f3tesis de \u00abapropiaci\u00f3n\u00bb de nicho, se adapta a situaciones en las que el h\u00e1bitat se va rellenando secuencialmente, suponiendo que las especies alcanzaran dicho h\u00e1bitat a intervalos uniformes de tiempo: Por el contrario, la aparici\u00f3n de las logseries tendr\u00eda lugar cuando las mencionadas especies llegaran a intervalos de tiempo irregulares, o mejor dicho al azar<\/span><span style=\"color: #000000\">.&nbsp; <\/span><span style=\"color: #cc0000\">Como ya se ha indicado, las logseries se aproximan a una l\u00ednea recta, al representarse en un gr\u00e1fico de rango-abundancia<\/span><span style=\"color: #000000\">. En t\u00e9rminos m\u00e1s formales, la relaci\u00f3n entre el n\u00famero de especies <em>S<\/em> y el de individuos <em>N<\/em> puede expresarse mediante la siguiente ecuaci\u00f3n:<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: center\" align=\"center\"><em><span style=\"color: #000000\">S = a log<sub>e<\/sub> [ 1 + N\/a],<\/span><\/em><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"color: #000000\">en donde, como ya comentamos, <em>a<\/em><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"> puede considerarse como un \u00edndice de diversidad. Alternativamente, si se hace m\u00e1s \u00e9nfasis en el par\u00e1metro de muestreo <em>X<\/em>, el n\u00famero esperado de especies en una muestra de <em>N <\/em>individuos, <em>S<sub>N<\/sub><\/em>, puede obtenerse a partir de la siguiente expresi\u00f3n:<\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: center\" align=\"center\"><em><span style=\"color: #000000\">aX<sup>N<\/sup>\/ N<\/span><\/em><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"color: #000000\">Williams , en 1947, elabor\u00f3 una tabla y un gr\u00e1fico con vistas a estimar <em>a,<\/em><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"> partiendo del n\u00famero total de especies e individuos recolectados (obviamente en aquella \u00e9poca no se dispon\u00eda de ordenadores.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;color: blue;font-family: 'Comic Sans MS'\"><strong><em>Distribuci\u00f3n logaritmo-normal (Lognormal)<\/em><\/strong><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;color: blue;font-family: 'Comic Sans MS'\">Preston<\/span><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">, en 1948, sugiri\u00f3 que<\/span><span style=\"color: blue\"> las distribuciones<\/span><span style=\"color: #000000\"> logaritmo-normales o l<\/span><span style=\"color: blue\">ognormales<\/span><span style=\"color: #000000\">, eran las que mejor explicaban las pautas de distribuci\u00f3n de abundancia de las especies, bajo las siguientes premisas: (<strong>i<\/strong>) que los individuos se distribuyeran entre las especies normalmente (es decir seg\u00fan una campana de Gauss) y (<strong>ii<\/strong>) que el crecimiento de las poblaciones fuera geom\u00e9trico. May, en 1975 detalla el conjunto de \u00abrazones\u00bb biol\u00f3gicas por las que las distribuciones lognormales pueden aplicarse tanto a comunidades en equilibrio como a otras oportunistas. <\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">Preston en trabajos secuenciados que van desde 1948 a 1962b, analiz\u00f3 el ajuste de numerosos muestreos, confeccionando gr\u00e1ficos cartesianos en los cuales se representaban las frecuencias de las especies frente a sus respectivas clases de abundancia en escala logar\u00edtmica (<\/span><span style=\"color: blue\">ver Gr\u00e1fico 13 de la Galer\u00eda de edafodiversidad en esta weblog<\/span><span style=\"color: #000000\">). Este autor hizo uso de los logaritmos en base 2, de tal modo que cada clase u \u00aboctava\u00bb significaba una duplicaci\u00f3n del tama\u00f1o de la poblaci\u00f3n. En este tipo de representaciones, la abundancia de las especies en el pico de la curva corresponde a la moda de la distribuci\u00f3n (<em>N<sub>0 <\/sub><\/em>) mientras que las \u00aboctavas\u00bb (<em>R<\/em>) se calculan mediante la siguiente expresi\u00f3n matem\u00e1tica:<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: center\" align=\"center\"><span style=\"color: #000000\"><em>R<sub>i<\/sub> = <\/em>Log<sub>2<\/sub> (<em>N<sub>i<\/sub>\/ N<sub>0<\/sub>)<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;color: blue;font-family: 'Comic Sans MS'\">Preston se\u00f1al\u00f3 que el tama\u00f1o de la muestra suele ser demasiado peque\u00f1o para detectar las especies<\/span><span style=\"color: #000000\"> que debieran aparecer en las octavas, que incluir\u00edan las especies <\/span><span style=\"color: blue\">m\u00e1s raras<\/span><span style=\"color: #000000\">. M\u00e1s concretamente Preston comentaba que tales especies quedaban <\/span><span style=\"color: blue\">ocultas tras la \u00abl\u00ednea de velo\u00bb<\/span><span style=\"color: #000000\">. En otras palabras, lo m\u00e1s normal es que los muestreos s\u00f3lo recogieran aquellas especies que se sit\u00faen a la derecha de la l\u00ednea imaginaria. En el <\/span><span style=\"color: blue\">gr\u00e1fico 13<\/span><span style=\"color: #000000\">, puede observarse que, si la l\u00ednea de velo alcanza <\/span><span style=\"color: #000000\"><em>N<sub>0<\/sub><\/em> o cualquiera de las octavas de signo positivo, la curva se aproxima a una l\u00ednea recta como se muestra en <\/span><span style=\"color: blue\">el gr\u00e1fico 9<\/span><span style=\"color: #000000\">, con los ejes invertidos. Pero si los muestreos fueran lo suficientemente intensos, se apreciar\u00eda una curva en campana bastante completa, siendo la clases menos abundantes (<\/span><span style=\"color: #000000\"><em>singletons<\/em>) las que corresponden a las<\/span><span style=\"color: blue\"> especies<\/span><span style=\"color: #000000\"> denominadas \u00ab<\/span><span style=\"color: blue\">vagabundas<\/span><span style=\"color: #000000\">\u00ab, \u00ab<\/span><span style=\"color: blue\">turistas<\/span><span style=\"color: #000000\">\u00bb u \u00ab<\/span><span style=\"color: blue\">ocasionales<\/span><span style=\"color: #000000\">\u00ab, seg\u00fan las preferencias de vocabulario. Preston reconoci\u00f3 que los gr\u00e1ficos de individuos agrupados por clase, frente a las clases de abundancia podr\u00edan no describir la curva de campana completa, sino que quedar\u00eda <\/span><span style=\"color: blue\">truncada e<\/span><span style=\"color: #000000\">n su cresta la denominada \u00ab<\/span><span style=\"color: blue\">condici\u00f3n can\u00f3nica<\/span><span style=\"color: #000000\">\u00ab. En estas condiciones<\/span><span style=\"color: #000000\"><em>, R<sub>N <\/sub>= Rmax<\/em> (<\/span><span style=\"color: blue\">gr\u00e1fico 13<\/span><span style=\"color: #000000\">). Dicho de otro modo, seg\u00fan Preston, <\/span><span style=\"color: #cc0000\">la distribuci\u00f3n<\/span> <span style=\"color: #cc0000\">logaritmo-normal truncada<\/span><span style=\"color: #000000\"> finaliza en la mencionada cresta (a diferencia de lo que puede observarse en el <\/span><span style=\"color: blue\">gr\u00e1fico 13<\/span><span style=\"color: #000000\">), y dificulta el ajuste de los datos. &nbsp;Otros autores mostraron con posterioridad&nbsp; que el problema es m\u00e1s f\u00e1cil de abordar si, como en las distribuciones lognormales de Poisson, se abordan los par\u00e1metros <em>Sobs&nbsp; <\/em>y<em> s<\/em><\/span><span style=\"color: #000000\"><sup><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"font-size: xx-small\">2<\/span><\/span><\/sup><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"> (la varianza).<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span style=\"color: #000000\"><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\">Preston (1962) analiz\u00f3 una amplia cantidad de datos (para una \u00e9poca en la que no se dispon\u00eda de los potentes ordenadores actuales) y comprob\u00f3 que, para grandes valores de S<\/span><span lang=\"ES\" style=\"font-size: 8pt;font-family: 'Comic Sans MS';letter-spacing: -0.15pt\">obs<\/span>, por t\u00e9rmino general se cumpl\u00eda que <em>g \u00bb<\/em><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"> 1. Del mismo modo, y bajo id\u00e9nticas circunstancias (S<\/span><span lang=\"ES\" style=\"font-size: 8pt;font-family: 'Comic Sans MS';letter-spacing: -0.15pt\">obs<\/span><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"> altos), Por su parte otra reputada experta en ecolog\u00eda matem\u00e1tica (Hutchison en1953) hab\u00eda observado que, en la mayor\u00eda de los casos, &nbsp;la pendiente del tama\u00f1o muestral <em>a<\/em> <\/span><\/span><span lang=\"ES\" style=\"font-family: Symbol;letter-spacing: -0.15pt\"><span style=\"color: #000000\">\u00bb<\/span><\/span><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\"> 0.2. Una explicaci\u00f3n plausible de estos resultados fue aportada posteriormente por May (1975). <\/span><span style=\"color: #cc0000\">En consecuencia los datos parec\u00edan ajustarse preferentemente a un tipo muy concreto de distribuci\u00f3n logaritmo-normal, denominada can\u00f3nica truncada<\/span><span style=\"color: #000000\">. <\/span><span style=\"color: #cc0000\">Todos estos desarrollos matem\u00e1ticos son actualmente conocidos bajo la denominaci\u00f3n de Teor\u00eda Lognormal<\/span><span style=\"color: #000000\">.<\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"color: #cc0000;font-family: 'Comic Sans MS';letter-spacing: -0.15pt\">Finalmente, cabe mentar, que, la distribuci\u00f3n lognormal equivale a la de palo quebrado, asumiendo que el palo no se rompa aleatoria y simult\u00e1neamente en trozos de todos los tama\u00f1os, sino de forma secuencial o iterativa<\/span><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\">. <\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"color: blue;font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><strong><em>Modelo de palo quebrado de MacArthur (MacArthur&#8217;s broken stick model)<\/em><\/strong><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"color: #cc0000;font-family: 'Comic Sans MS';letter-spacing: -0.15pt\">Al desarrollar un an\u00e1lisis te\u00f3rico de c\u00f3mo un nicho ecol\u00f3gico evoluciona mediante un proceso de fragmentaci\u00f3n, que tambi\u00e9n podr\u00eda aplicarse a una superficie del modelado terrestre que, partiendo de unos sedimentos j\u00f3venes, m\u00e1s o menos homog\u00e9neos en su composici\u00f3n, da lugar a distintos <em>edafotaxa<\/em> seg\u00fan avanza la edafog\u00e9nesis<\/span><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\">, MacArthur, el padre de la Teor\u00eda de la Biogeograf\u00eda insular, postul\u00f3 entre 1957, 1960, 1964, 1965 (poco antes de su prematuro fallecimiento) tres diferentes modelos. Uno de ellos fue el que recibi\u00f3 m\u00e1s atenci\u00f3n y se le denomina \u00abbroken stick model\u00bb (traducido al castellano como palo quebrado, vara quebrada, bast\u00f3n roto, etc.). <\/span><span style=\"color: #cc0000\">Este asume que el nicho se divide como un palo que se fragmenta simult\u00e1neamente al azar en piezas de todos los tama\u00f1os<\/span><span style=\"color: #000000\">. La abundancia del trozo m\u00e1s frecuente (especie, <em>edafotaxa<\/em> o cualquier otra categor\u00eda) puede obtenerse mediante&nbsp; una expresi\u00f3n matem\u00e1tica&nbsp; que por su relativa complejidad no mostraremos aqu\u00ed, si bien es f\u00e1cil de buscar en Internet.<\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"Standaard\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span style=\"color: #000000\">La estructura matem\u00e1tica del modelo fue investigada posteriormente por otros autores. <\/span><span style=\"color: #cc0000\">Este modelo da lugar a una distribuci\u00f3n de abundancia de especies m\u00e1s equitativa que en los descritos anteriormente.<\/span><span style=\"color: #000000\"> La distribuci\u00f3n s\u00f3lo presenta un par\u00e1metro (<em>Sobs<\/em><\/span><span lang=\"ES\" style=\"font-family: 'Comic Sans MS';letter-spacing: -0.15pt\"><span style=\"color: #000000\">)<em>.<\/em> Este administrador y colegas, (Ib\u00e1\u00f1ez <\/span><span style=\"color: #000000\"><em>et al<\/em>. 1998) muestran como<\/span><span style=\"color: #cc0000\"> la fragmentaci\u00f3n de la edafosfera a escala global en diferentes tipos de <em>edafotaxa<\/em>, de acuerdo a las Claves de Suelos de la FAO (1971\/1981), se ajusta al 100% a este modelo<\/span><span style=\"color: #000000\">.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">El modelo descrito, parece ser el m\u00e1s equitativo de todos los detectados, hasta el momento, en la naturaleza, siendo m\u00e1s frecuente en algunas comunidades de aves y ciertos ensamblajes edafol\u00f3gicos.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"font-size: 11pt;font-family: 'Comic Sans MS'\"><span style=\"color: #000000\">&nbsp;<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\" align=\"justify\"><span lang=\"ES\" style=\"font-size: 11pt;color: #cc0000;font-family: 'Comic Sans MS'\">Juanjo Ib\u00e1\u00f1ez, el tost\u00f3n insufrible.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n &nbsp; Series Geom\u00e9tricas &nbsp; Si suponemos que el primer taxa ocupa una fracci\u00f3n (K) de un h\u00e1bitat previamente vac\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\u00f3n K del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\u00e1fico de rango abundancia obtenemos la l\u00ednea recta que corresponde a una serie geom\u00e9trica, tal como mostr\u00f3 Motoruma en 1932. Este modelo tambi\u00e9n ha sido denominado hip\u00f3tesis de \u00abapropiaci\u00f3n\u00bb o \u00abrelleno\u00bb del nicho (niche-pre-emption hypothesis)\u00bb. El modelo fue muy utilizado en la descripci\u00f3n de la diversidad\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[586],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n Series Geom\u00e9tricas Si suponemos que el primer taxa ocupa una fracci\u00f3n (K) de un h\u00e1bitat previamente vac\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\u00f3n K del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\u00e1fico\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n Series Geom\u00e9tricas Si suponemos que el primer taxa ocupa una fracci\u00f3n (K) de un h\u00e1bitat previamente vac\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\u00f3n K del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\u00e1fico\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-01-07T14:35:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-02-22T12:13:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n Series Geom\u00e9tricas Si suponemos que el primer taxa ocupa una fracci\u00f3n (K) de un h\u00e1bitat previamente vac\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\u00f3n K del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\u00e1fico\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693#blogposting\",\"name\":\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\\u00f3n de Abundancia. Descripci\\u00f3n - Un Universo invisible bajo nuestros pies\",\"headline\":\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\\u00f3n de Abundancia. Descripci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-01-07T14:35:00+01:00\",\"dateModified\":\"2023-02-22T13:13:47+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":11,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693#webpage\"},\"articleSection\":\"Diversidad, Complejidad y Fractales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"position\":2,\"name\":\"Diversidad, Complejidad y Fractales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693#listItem\",\"name\":\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\\u00f3n de Abundancia. Descripci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693#listItem\",\"position\":3,\"name\":\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\\u00f3n de Abundancia. Descripci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693\",\"name\":\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\\u00f3n de Abundancia. Descripci\\u00f3n - Un Universo invisible bajo nuestros pies\",\"description\":\"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\\u00f3n de Abundancia. Descripci\\u00f3n Series Geom\\u00e9tricas Si suponemos que el primer taxa ocupa una fracci\\u00f3n (K) de un h\\u00e1bitat previamente vac\\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\\u00f3n K del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\\u00e1fico\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/01\\\/07\\\/11693#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2006-01-07T14:35:00+01:00\",\"dateModified\":\"2023-02-22T13:13:47+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n - Un Universo invisible bajo nuestros pies","description":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n Series Geom\u00e9tricas Si suponemos que el primer taxa ocupa una fracci\u00f3n (K) de un h\u00e1bitat previamente vac\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\u00f3n K del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\u00e1fico","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693#blogposting","name":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n - Un Universo invisible bajo nuestros pies","headline":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#articleImage","width":217,"height":72},"datePublished":"2006-01-07T14:35:00+01:00","dateModified":"2023-02-22T13:13:47+01:00","inLanguage":"es-ES","commentCount":11,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693#webpage"},"articleSection":"Diversidad, Complejidad y Fractales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","position":2,"name":"Diversidad, Complejidad y Fractales","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693#listItem","name":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693#listItem","position":3,"name":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693","name":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n - Un Universo invisible bajo nuestros pies","description":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n Series Geom\u00e9tricas Si suponemos que el primer taxa ocupa una fracci\u00f3n (K) de un h\u00e1bitat previamente vac\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\u00f3n K del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\u00e1fico","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2006-01-07T14:35:00+01:00","dateModified":"2023-02-22T13:13:47+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n - Un Universo invisible bajo nuestros pies","og:description":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n Series Geom\u00e9tricas Si suponemos que el primer taxa ocupa una fracci\u00f3n (K) de un h\u00e1bitat previamente vac\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\u00f3n K del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\u00e1fico","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2006-01-07T14:35:00+00:00","article:modified_time":"2023-02-22T12:13:47+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n - Un Universo invisible bajo nuestros pies","twitter:description":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n Series Geom\u00e9tricas Si suponemos que el primer taxa ocupa una fracci\u00f3n (K) de un h\u00e1bitat previamente vac\u00edo, y los siguientes taxa colonizan secuencialmente la misma fracci\u00f3n K del espacio restante dejado por las anteriores, hasta terminar por colmatarlo, en un gr\u00e1fico","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"11693","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":"default","local_seo":null,"created":"2022-06-03 09:59:07","updated":"2026-05-26 12:58:12","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales\" title=\"Diversidad, Complejidad y Fractales\">Diversidad, Complejidad y Fractales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEdafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Diversidad, Complejidad y Fractales","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales"},{"label":"Edafodiversidad y Biodiversidad 10: Sobre los Modelos de Distribuci\u00f3n de Abundancia. Descripci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/07\/11693"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/11693"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=11693"}],"version-history":[{"count":6,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/11693\/revisions"}],"predecessor-version":[{"id":154015,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/11693\/revisions\/154015"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=11693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=11693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=11693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}