{"id":12870,"date":"2006-02-03T14:19:00","date_gmt":"2006-02-03T14:19:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2006\/02\/03\/12870.aspx"},"modified":"2010-01-22T03:39:26","modified_gmt":"2010-01-22T02:39:26","slug":"sobre-la-autocensura-y-las-falsas-refutaciones-en-ciencia-un-ejemplo-extraido-de-las-relaciones-biodiversidad-edafodiversidad","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870","title":{"rendered":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 5<o:p><\/o:p><\/SPAN><\/B><\/P> <P class=MsoNormal style=\"MARGIN: 0cm -0.05pt 0pt 0cm; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\">Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\u00edficos que se adelantaron a su tiempo<o:p><\/o:p><\/SPAN><\/B><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">El caso que vamos a exponer seguidamente es de lo m\u00e1s singular. Les ruego que presten atenci\u00f3n con vistas a comprender como la actividad cient\u00edfica no puede entenderse fuera de un contexto sociol\u00f3gico-cient\u00edfico de lo m\u00e1s acient\u00edfico que pueda imaginarse. Lo hemos dejado para el final, por su inter\u00e9s. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #cc0000\">Johnson y Simberloff<\/SPAN><\/B><SPAN style=\"COLOR: #cc0000\">, en 1974<\/SPAN>, observaron sorprendidos que, al menos <SPAN style=\"COLOR: #cc0000\">en<\/SPAN> el caso de <SPAN style=\"COLOR: #cc0000\">las Islas Brit\u00e1nicas, la edafodiversidad de los paisajes de suelos predice mejor la riqueza en plantas vasculares que el \u00e1rea, latitud, distancia al continente, y otras variables abi\u00f3ticas, <\/SPAN>s\u00ed tenidas en cuenta por la Teor\u00eda de la Biogeograf\u00eda Insular.<o:p><\/o:p><\/SPAN><\/P><!--more--><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Estos autores sugieren que el papel jugado por los suelos en la biodiversidad vegetal podr\u00eda indicar que la heterogeneidad de las estructuras abi\u00f3ticas del h\u00e1bitat, m\u00e1s que el \u00e1rea <I style=\"mso-bidi-font-style: normal\">per se<\/I>, o los postulados de la Teor\u00eda de la Biogeograf\u00eda Insular, ser\u00edan los mecanismos subyacentes generadores de la diversidad biol\u00f3gica. En consecuencia el \u00e1rea podr\u00eda ser en s\u00ed misma s\u00f3lo un indicador indirecto de la diversidad de h\u00e1bitats. <SPAN style=\"COLOR: #cc0000\">Sin embargo, Johnson y Simberloff no se atrevieron a postular ninguna hip\u00f3tesis articulada, sugiriendo que<\/SPAN>:<SPAN style=\"COLOR: blue\"> \u00ab<I style=\"mso-bidi-font-style: normal\">las pruebas definitivas deber\u00e1n esperar la investigaci\u00f3n de cient\u00edficos ingeniosos que dise\u00f1aran un experimento cr\u00edtico a este respecto<\/I>\u00ab<\/SPAN>. Es decir, que parece que nos esperaban a nosotros (que de ingeniosos no tenemos nada), ya que en 2001 reanalizamos los datos de Johnson y Simberloff, detectando que tanto las SPARs, como las relaciones edafodiversidad-\u00e1rea, se ajustan a una ley potencial con un exponente cercano (plantas vasculares) o igual (edafotaxa) <SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN>a 0.25 (<SPAN style=\"COLOR: blue\">ver gr\u00e1fico 19 de la galer\u00eda de edafodiversidad<\/SPAN>), tal como postula la Teor\u00eda de la Biogeograf\u00eda Insular, pero no basada en los argumentos que esta \u00faltima propone. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Del mismo modo, y en el mismo archipi\u00e9lago, detectamos una relaci\u00f3n potencial entre el \u00e1rea y el relieve (altitud m\u00e1xima). Seguidamente, abundando en el tema, vimos como los valores de los \u00edndices de diversidad incrementaban con el \u00e1rea de estas islas, lo mismo que los de los algoritmos que utilizamos para la estimaci\u00f3n de la Smax (riqueza m\u00e1xima), mientras que sus representaciones gr\u00e1ficas son id\u00e9nticas a las mostradas para los datos biol\u00f3gicos en la literatura. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Paralelamente, en un estudio publicado para las <SPAN style=\"COLOR: blue\">Islas del Egeo (Ib\u00e1\u00f1ez et al. 2004)<\/SPAN>, al margen de corroborar los rasurados previamente obtenidos para el <SPAN style=\"COLOR: blue\">Archipi\u00e9lago Brit\u00e1nico<\/SPAN>, comprobamos que sus modelos de distribuci\u00f3n de abundancia se ajustaban a series geom\u00e9tricas (equivalentes a peque\u00f1as muestras de una poblaci\u00f3n m\u00e1s grande) en las islas de menor tama\u00f1o y\/o m\u00e1s erosionadas (equivalente a el impacto ambiental sugerido por los ec\u00f3logos), mientras que los ensamblajes de las islas grandes (y del conjunto de todas las islas, equivalente a una muestra grande) se ajustan a la distribuci\u00f3n lognormal, como lo hacen los datos ecol\u00f3gicos bajo las mismas circunstancias. <SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN>En otras palabras, pudimos comprobar como los argumentos esgrimidos por <SPAN style=\"COLOR: blue\">Robert May<\/SPAN> en 1975, respecto a los DAMs para los organismos biol\u00f3gicos, tambi\u00e9n son v\u00e1lidos para entidades abi\u00f3ticas, como son los suelos. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Como hemos dicho, en otra publicaci\u00f3n de 2004, encontramos, una vez m\u00e1s una relaci\u00f3n potencial, con un exponente de 0.25, entre la edafodiversidad taxon\u00f3mica y el \u00e1rea de las Islas del Egeo. Finalmente. Postulamos, como <SPAN style=\"COLOR: #cc0000\">Cody <\/SPAN>(ver la contribuci\u00f3n precedente dedicada a la obra de este autor) que <SPAN style=\"COLOR: #cc0000\">el incremento del tipo de suelos con el tama\u00f1o de la isla podr\u00eda deberse al aumento paralelo del n\u00famero de unidades geomorfol\u00f3gicas<\/SPAN>. Del mimo modo, encontramos, de nuevo relaciones potenciales entre el \u00e1rea y el relieve (altitud m\u00e1xima de las Islas). Estamos convencidos, por diversas razones que ya detallaremos, que de disponer de un a buena clasificaci\u00f3n de unidades geomorfol\u00f3gicas, obtendr\u00edamos los mismos resultados que las aqu\u00ed mostradas con los suelos, en todo lo concerniente a la diversidad. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; LINE-HEIGHT: 12pt; TEXT-ALIGN: justify; tab-stops: -36.0pt\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; LINE-HEIGHT: 12pt; TEXT-ALIGN: justify; tab-stops: -36.0pt\"><B style=\"mso-bidi-font-weight: normal\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">Una breve lecci\u00f3n<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN>m\u00e1s sobre la racional irracionalidad de la ciencia<o:p><\/o:p><\/SPAN><\/B><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; LINE-HEIGHT: 12pt; TEXT-ALIGN: justify; tab-stops: -36.0pt\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">Johnson y Simberloff, pusieron el dedo en la llaga. <\/SPAN><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Sin embargo, como en el caso de <SPAN style=\"COLOR: blue\">Williamson,<\/SPAN> fueron <SPAN style=\"COLOR: blue\">muy tibios<\/SPAN> en sus argumentaciones, ocultando las relaciones edafodiversidad-\u00e1rea <SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN>(tan solo publicaron unos breves comentarios y una matriz de correlaci\u00f3n entre las distintas variables observadas). \u00bf<SPAN style=\"COLOR: #cc0000\">Por qu\u00e9 fueron tan tibios<\/SPAN>? Simplemente <SPAN style=\"COLOR: #cc0000\">por razones de autoridad<\/SPAN>.<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN><SPAN style=\"COLOR: blue\">Simberloff<\/SPAN> colabor\u00f3 previamente con <SPAN style=\"COLOR: blue\">E. O. Wilson<\/SPAN> (uno de los padres de la Teor\u00eda de la Biogeograf\u00eda Insular) en ciertos experimentos cruciales para corroborar su teor\u00eda, desforestando y fumigando ciertos islotes con vistas a analizar despu\u00e9s como la vida colonizaba estas miniaturas naturales. Aquellos trabajos con el gran Wilson hab\u00edan sido los que le otorgaron a la postre una mayor popularidad. <SPAN style=\"COLOR: #cc0000\">No era cuesti\u00f3n de atacar a su maestro<\/SPAN>.&nbsp;<\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; LINE-HEIGHT: 12pt; TEXT-ALIGN: justify; tab-stops: -36.0pt\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><\/SPAN><FONT size=3>&nbsp;<\/P><\/FONT> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; LINE-HEIGHT: 12pt; TEXT-ALIGN: justify; tab-stops: -36.0pt\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">A pesar de toda su prudencia, <SPAN style=\"COLOR: #cc0000\">pronto comenzaron a lloverles cr\u00edticas<\/SPAN> por parte de sus colegas. En trabajos posteriores, otros bioge\u00f3grafos aludieron (falsamente) refutar las conclusiones de <SPAN style=\"COLOR: #cc0000\">Johnson y Simberloff<\/SPAN>, argumentando prosaicamente, que los resultados de \u00e9stos no eran v\u00e1lidos por no haber incluido Irlanda, ya que formaba parte del archipi\u00e9lago. Como todos ustedes saben, este \u00faltimo pa\u00eds no pertenece a UK, por lo que sus inventarios de suelos y vegetaci\u00f3n no eran equiparables. Nosotros hemos realizado el tes con la base de datos de suelos de Europa, encontrando que<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN><SPAN style=\"COLOR: #cc0000\">Johnson y Simberloff ten\u00edan toda la raz\u00f3n<\/SPAN>. Sin embargo no protestaron, por las razones anteriormente aludidas. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; LINE-HEIGHT: 12pt; TEXT-ALIGN: justify; tab-stops: -36.0pt\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; LINE-HEIGHT: 12pt; TEXT-ALIGN: justify; tab-stops: -36.0pt\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\">Una verdadera refutaci\u00f3n, hubiera requerido <\/SPAN><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">analizar otros archipi\u00e9lagos para los que s\u00ed hab\u00eda datos homog\u00e9neos. Los detractores no lo hicieron, por lo que sus cr\u00edticas fueron tendenciosas y carentes del rigor cient\u00edfico que estipulan los c\u00e1nones de la ciencia. Hace unos a\u00f1os hicimos nuestro propio tes enviando un trabajo posteriormente publicado en otra revista al \u00ab<I style=\"mso-bidi-font-style: normal\"><SPAN style=\"COLOR: blue\">Journal of Biogeography<\/SPAN><\/I><SPAN style=\"COLOR: blue\">\u00ab<\/SPAN>, el principal \u00f3rgano de expresi\u00f3n y publicaci\u00f3n de los biogeogr\u00e1fos, en los que expl\u00edcitamente diversas notas editoriales suscriben que la Teor\u00eda de MacArthur y Willson es su paradigma.<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN>La respuesta fue la misma que recibieron <SPAN style=\"COLOR: blue\">Johnson y Simberloff , <\/SPAN>a pesar de que uno de sus editores nos comunic\u00f3, en un mail personal, que hab\u00eda sido como poner \u00ab<I style=\"mso-bidi-font-style: normal\">perlas delante de cerdos<\/I>\u00bb (traducci\u00f3n literal). Pudimos entrar en un debate, pero esperamos obtener m\u00e1s evidencias en otros archipi\u00e9lagos. Es decir, los referees de esta revista seria e indexada, en lugar de leer nuestros trabajos previos que ya o refutaban la Teor\u00eda de la Biogeograf\u00eda Insular, o como m\u00ednimo la pon\u00edan en aprietos, <SPAN style=\"COLOR: #cc0000\">se contentaron con las refutaciones previas, defendiendo su Teor\u00eda como un Dogma, postura a todas luces acient\u00edfica<\/SPAN>. De nuevo, como en el caso de la Teor\u00eda sint\u00e9tica de la Evoluci\u00f3n (ya abordada en otra contribuci\u00f3n precedente), los bi\u00f3logos \u00ab<SPAN style=\"COLOR: blue\">sacralizan sus teor\u00edas\u00bb, impidiendo el paso a cualquiera que pretenda refutarla. Parece mentira pero es cierto<\/SPAN>. No es un caso \u00fanico. Desgraciadamente es moneda de uso corriente<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN>en ciencia.<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN><SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN>Ya el Fil\u00f3sofo de la Ciencia <SPAN style=\"COLOR: blue\">Thomas Kuhn<\/SPAN>, entre otros, mostr\u00f3 numerosos casos en los que las <SPAN style=\"COLOR: #cc0000\">Teor\u00edas vigentes permanecen \u00abaparentemente\u00bb firmes a pasera de haber sido refutadas, incluso poco tiempo despu\u00e9s de su aceptaci\u00f3n por la comunidad cient\u00edfica. Una nueva prueba m\u00e1s de la irracionalidad de la racionalidad cient\u00edfica<\/SPAN>. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; LINE-HEIGHT: 12pt; TEXT-ALIGN: justify; tab-stops: -36.0pt\"><SPAN lang=ES style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; LINE-HEIGHT: 12pt; TEXT-ALIGN: justify; tab-stops: -36.0pt\"><B style=\"mso-bidi-font-weight: normal\"><SPAN lang=ES style=\"FONT-SIZE: 11pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">Juan Jos\u00e9 Ib\u00e1\u00f1ez sobre la humanidad de la empresa cient\u00edfica<o:p><\/o:p><\/SPAN><\/B><\/P><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 5 Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\u00edficos que se adelantaron a su tiempo El caso que vamos a exponer seguidamente es de lo m\u00e1s singular. Les ruego que presten atenci\u00f3n con vistas a comprender como la actividad cient\u00edfica no puede entenderse fuera de un contexto sociol\u00f3gico-cient\u00edfico de lo m\u00e1s acient\u00edfico que pueda imaginarse. Lo hemos dejado para el final, por su inter\u00e9s. Johnson y Simberloff, en 1974, observaron sorprendidos que, al menos en el caso de las Islas Brit\u00e1nicas, la edafodiversidad\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[586,597,605],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 5 Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\u00edficos que se adelantaron a su tiempo El caso que vamos a exponer seguidamente es de lo m\u00e1s singular. Les ruego que presten atenci\u00f3n con vistas a comprender como la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 5 Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\u00edficos que se adelantaron a su tiempo El caso que vamos a exponer seguidamente es de lo m\u00e1s singular. Les ruego que presten atenci\u00f3n con vistas a comprender como la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-02-03T14:19:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-22T02:39:26+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 5 Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\u00edficos que se adelantaron a su tiempo El caso que vamos a exponer seguidamente es de lo m\u00e1s singular. Les ruego que presten atenci\u00f3n con vistas a comprender como la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870#blogposting\",\"name\":\"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\\u00eddo de las Relaciones Biodiversidad-Edafodiversidad) - Un Universo invisible bajo nuestros pies\",\"headline\":\"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-02-03T14:19:00+01:00\",\"dateModified\":\"2010-01-22T03:39:26+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870#webpage\"},\"articleSection\":\"Diversidad, Complejidad y Fractales, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Fraude y Mala Praxis Cient\\u00edfica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"position\":2,\"name\":\"Diversidad, Complejidad y Fractales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870#listItem\",\"name\":\"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870#listItem\",\"position\":3,\"name\":\"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870\",\"name\":\"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\\u00eddo de las Relaciones Biodiversidad-Edafodiversidad) - Un Universo invisible bajo nuestros pies\",\"description\":\"La Edafodiversidad: Una historia Repleta de Grandes Cient\\u00edficos Olvidados 5 Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\\u00edficos que se adelantaron a su tiempo El caso que vamos a exponer seguidamente es de lo m\\u00e1s singular. Les ruego que presten atenci\\u00f3n con vistas a comprender como la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/03\\\/12870#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2006-02-03T14:19:00+01:00\",\"dateModified\":\"2010-01-22T03:39:26+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad) - Un Universo invisible bajo nuestros pies","description":"La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 5 Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\u00edficos que se adelantaron a su tiempo El caso que vamos a exponer seguidamente es de lo m\u00e1s singular. Les ruego que presten atenci\u00f3n con vistas a comprender como la","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870#blogposting","name":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad) - Un Universo invisible bajo nuestros pies","headline":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#articleImage","width":217,"height":72},"datePublished":"2006-02-03T14:19:00+01:00","dateModified":"2010-01-22T03:39:26+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870#webpage"},"articleSection":"Diversidad, Complejidad y Fractales, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Fraude y Mala Praxis Cient\u00edfica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","position":2,"name":"Diversidad, Complejidad y Fractales","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870#listItem","name":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870#listItem","position":3,"name":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870","name":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad) - Un Universo invisible bajo nuestros pies","description":"La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 5 Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\u00edficos que se adelantaron a su tiempo El caso que vamos a exponer seguidamente es de lo m\u00e1s singular. Les ruego que presten atenci\u00f3n con vistas a comprender como la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2006-02-03T14:19:00+01:00","dateModified":"2010-01-22T03:39:26+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad) - Un Universo invisible bajo nuestros pies","og:description":"La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 5 Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\u00edficos que se adelantaron a su tiempo El caso que vamos a exponer seguidamente es de lo m\u00e1s singular. Les ruego que presten atenci\u00f3n con vistas a comprender como la","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2006-02-03T14:19:00+00:00","article:modified_time":"2010-01-22T02:39:26+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad) - Un Universo invisible bajo nuestros pies","twitter:description":"La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 5 Edafodiversidad y Biodiversidad 20e. Antecedentes sobre Geodiversidad como ejemplo de las voces silenciadas de los cient\u00edficos que se adelantaron a su tiempo El caso que vamos a exponer seguidamente es de lo m\u00e1s singular. Les ruego que presten atenci\u00f3n con vistas a comprender como la","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"12870","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 13:36:33","updated":"2026-05-26 13:01:50","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales\" title=\"Diversidad, Complejidad y Fractales\">Diversidad, Complejidad y Fractales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Diversidad, Complejidad y Fractales","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales"},{"label":"Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/12870"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=12870"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/12870\/revisions"}],"predecessor-version":[{"id":133916,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/12870\/revisions\/133916"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=12870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=12870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=12870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}