{"id":13526,"date":"2006-02-13T16:19:00","date_gmt":"2006-02-13T16:19:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2006\/02\/13\/13526.aspx"},"modified":"2010-01-22T03:39:32","modified_gmt":"2010-01-22T02:39:32","slug":"hacia-un-cambio-de-paradigma-en-edafologia","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526","title":{"rendered":"Hacia un Cambio de Paradigma en Edafolog\u00eda"},"content":{"rendered":"<p><P align=justify><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES; mso-fareast-font-family: 'Times New Roman'; mso-fareast-language: ES; mso-bidi-language: AR-SA; mso-bidi-font-family: 'Times New Roman'\">Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\u00f3logos ya formados, como lo es mi amigo Luis Fern\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, <SPAN style=\"COLOR: blue\">la edafolog\u00eda se encuentra en una crisis y en una encrucijada<\/SPAN>. La <SPAN style=\"COLOR: blue\">sociedad<\/SPAN> demanda nuevas concepciones del suelo con vistas a cumplir con las actuales demandas de informaci\u00f3n edafol\u00f3gica. Del mismo modo, muchos investigadores venimos denunciando que tal <SPAN style=\"COLOR: blue\">cambio de paradigma<\/SPAN> tambi\u00e9n se encuentra cient\u00edficamente justificado en base a los conocimientos acumulados en las \u00faltimas d\u00e9cadas.<\/SPAN><\/P><!--more--><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\" align=justify><SPAN style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\">Sin embargo<\/SPAN><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">, tambi\u00e9n hemos recalcado, que <SPAN style=\"COLOR: blue\">las comunidades cient\u00edficas<\/SPAN> <SPAN style=\"COLOR: blue\">son extremadamente reacias a rechazar el paradigma vigente y adoptar otro nuevo<\/SPAN>. Las posiciones que defendemos, cada vez m\u00e1s expertos, se encuentran bien detalladas en el siguiente documento: \u00ab<B><SPAN lang=EN style=\"FONT-SIZE: 10pt; COLOR: black; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: EN-GB; mso-bidi-font-family: Arial\"><A href=\"http:\/\/eusoils.jrc.it\/ESDB_Archive\/eusoils_docs\/esb_rr\/n07_ESBResRep07\/304Ibanez.pdf\">The search for a new Paradigm in Pedology: a driving force for new<SPAN style=\"FONT-WEIGHT: normal\"> <\/SPAN>..<\/A>.\u00bb<\/SPAN><\/B><\/SPAN><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\">&nbsp;<\/SPAN><\/B><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\">Se trata ya de un cap\u00edtulo de libro para edaf\u00f3logos o para estudiantes con conocimientos avanzados en la materia. Hoy por hoy, existe un cruce de caminos entre la crisis, y la encrucijada. Por mucho que se empe\u00f1en los m\u00e1s conservadores, se trata del consabido lema de \u00ab<SPAN style=\"COLOR: blue\">renovarse o morir<\/SPAN>\u00ab.<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\">Los retos Principales que defiende en nuevo paradigma ser\u00edan entre otras<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <UL style=\"MARGIN-TOP: 0cm\" type=disc> <LI class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify; tab-stops: list 36.0pt; mso-list: l0 level1 lfo1\"> <DIV align=justify><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\">Considerar el sistema suelo-regolito en lugar del metro superficial de la cobertura edafol\u00f3gica<o:p><\/o:p><\/SPAN><\/DIV> <LI class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify; tab-stops: list 36.0pt; mso-list: l0 level1 lfo1\"> <DIV align=justify><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\">Analizar y considerar como suelos los sedimentos de los humedales y superficies sumergidos por aguas someras<o:p><\/o:p><\/SPAN><\/DIV> <LI class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify; tab-stops: list 36.0pt; mso-list: l0 level1 lfo1\"> <DIV align=justify><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\">Inventariar, cartografiar, clasificar y monitorizar toda la superficie terrestre emergida (litoderma), con independencia de que podamos hablar de suelos <I style=\"mso-bidi-font-style: normal\">sensu stricto o no<\/I><o:p><\/o:p><\/SPAN><\/DIV> <LI class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify; tab-stops: list 36.0pt; mso-list: l0 level1 lfo1\"> <DIV align=justify><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\">Elaborar un corpus doctrinal que sobrepase las limitaciones del actual paradigma agron\u00f3mico (considerando las CC. de la Tierra y la Conservaci\u00f3n de la Naturaleza)<o:p><\/o:p><\/SPAN><\/DIV> <LI class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify; tab-stops: list 36.0pt; mso-list: l0 level1 lfo1\"> <DIV align=justify><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\">Utilizar tal corpus con vistas a superar la paradoja tecnol\u00f3gica de Burrough<o:p><\/o:p><\/SPAN><\/DIV><\/LI><\/UL> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; LAYOUT-GRID-MODE: line; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-size: 12.0pt\">Juanjo Ib\u00e1\u00f1ez<\/SPAN><SPAN style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN><\/P><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\u00f3logos ya formados, como lo es mi amigo Luis Fern\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, la edafolog\u00eda se encuentra en una crisis y en una encrucijada. La sociedad demanda nuevas concepciones del suelo con vistas a cumplir con las actuales demandas de informaci\u00f3n edafol\u00f3gica. Del mismo modo, muchos investigadores venimos denunciando que tal cambio de paradigma tambi\u00e9n se encuentra cient\u00edficamente justificado en base a los conocimientos acumulados en las \u00faltimas d\u00e9cadas. Im\u00e1genes Relacionadas:<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[588,597,587],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\u00f3logos ya formados, como lo es mi amigo Luis Fern\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, la edafolog\u00eda se encuentra en una crisis y en una encrucijada. La sociedad demanda nuevas concepciones del suelo con vistas a cumplir con\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hacia un Cambio de Paradigma en Edafolog\u00eda - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\u00f3logos ya formados, como lo es mi amigo Luis Fern\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, la edafolog\u00eda se encuentra en una crisis y en una encrucijada. La sociedad demanda nuevas concepciones del suelo con vistas a cumplir con\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-02-13T16:19:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-22T02:39:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hacia un Cambio de Paradigma en Edafolog\u00eda - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\u00f3logos ya formados, como lo es mi amigo Luis Fern\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, la edafolog\u00eda se encuentra en una crisis y en una encrucijada. La sociedad demanda nuevas concepciones del suelo con vistas a cumplir con\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526#blogposting\",\"name\":\"Hacia un Cambio de Paradigma en Edafolog\\u00eda - Un Universo invisible bajo nuestros pies\",\"headline\":\"Hacia un Cambio de Paradigma en Edafolog\\u00eda\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-02-13T16:19:00+01:00\",\"dateModified\":\"2010-01-22T03:39:32+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":7,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526#webpage\"},\"articleSection\":\"El Concepto de Suelo y Sus Representaciones, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, La Crisis de la Edafolog\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"name\":\"La Crisis de la Edafolog\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"position\":2,\"name\":\"La Crisis de la Edafolog\\u00eda\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526#listItem\",\"name\":\"Hacia un Cambio de Paradigma en Edafolog\\u00eda\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526#listItem\",\"position\":3,\"name\":\"Hacia un Cambio de Paradigma en Edafolog\\u00eda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"name\":\"La Crisis de la Edafolog\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526\",\"name\":\"Hacia un Cambio de Paradigma en Edafolog\\u00eda - Un Universo invisible bajo nuestros pies\",\"description\":\"Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\\u00f3logos ya formados, como lo es mi amigo Luis Fern\\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, la edafolog\\u00eda se encuentra en una crisis y en una encrucijada. La sociedad demanda nuevas concepciones del suelo con vistas a cumplir con\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/02\\\/13\\\/13526#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2006-02-13T16:19:00+01:00\",\"dateModified\":\"2010-01-22T03:39:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Hacia un Cambio de Paradigma en Edafolog\u00eda - Un Universo invisible bajo nuestros pies","description":"Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\u00f3logos ya formados, como lo es mi amigo Luis Fern\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, la edafolog\u00eda se encuentra en una crisis y en una encrucijada. La sociedad demanda nuevas concepciones del suelo con vistas a cumplir con","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526#blogposting","name":"Hacia un Cambio de Paradigma en Edafolog\u00eda - Un Universo invisible bajo nuestros pies","headline":"Hacia un Cambio de Paradigma en Edafolog\u00eda","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#articleImage","width":217,"height":72},"datePublished":"2006-02-13T16:19:00+01:00","dateModified":"2010-01-22T03:39:32+01:00","inLanguage":"es-ES","commentCount":7,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526#webpage"},"articleSection":"El Concepto de Suelo y Sus Representaciones, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, La Crisis de la Edafolog\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","name":"La Crisis de la Edafolog\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","position":2,"name":"La Crisis de la Edafolog\u00eda","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526#listItem","name":"Hacia un Cambio de Paradigma en Edafolog\u00eda"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526#listItem","position":3,"name":"Hacia un Cambio de Paradigma en Edafolog\u00eda","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","name":"La Crisis de la Edafolog\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526","name":"Hacia un Cambio de Paradigma en Edafolog\u00eda - Un Universo invisible bajo nuestros pies","description":"Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\u00f3logos ya formados, como lo es mi amigo Luis Fern\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, la edafolog\u00eda se encuentra en una crisis y en una encrucijada. La sociedad demanda nuevas concepciones del suelo con vistas a cumplir con","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2006-02-13T16:19:00+01:00","dateModified":"2010-01-22T03:39:32+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Hacia un Cambio de Paradigma en Edafolog\u00eda - Un Universo invisible bajo nuestros pies","og:description":"Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\u00f3logos ya formados, como lo es mi amigo Luis Fern\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, la edafolog\u00eda se encuentra en una crisis y en una encrucijada. La sociedad demanda nuevas concepciones del suelo con vistas a cumplir con","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2006-02-13T16:19:00+00:00","article:modified_time":"2010-01-22T02:39:32+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Hacia un Cambio de Paradigma en Edafolog\u00eda - Un Universo invisible bajo nuestros pies","twitter:description":"Hoy nos toca presentar una nota breve, del tipo que gustan a los edaf\u00f3logos ya formados, como lo es mi amigo Luis Fern\u00e1ndez Seoane. Como hemos venido defendiendo reiteradamente en esta weblog, la edafolog\u00eda se encuentra en una crisis y en una encrucijada. La sociedad demanda nuevas concepciones del suelo con vistas a cumplir con","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"13526","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 13:38:44","updated":"2026-05-26 13:04:48","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia\" title=\"La Crisis de la Edafolog\u00eda\">La Crisis de la Edafolog\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHacia un Cambio de Paradigma en Edafolog\u00eda\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"La Crisis de la Edafolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia"},{"label":"Hacia un Cambio de Paradigma en Edafolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/13\/13526"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/13526"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=13526"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/13526\/revisions"}],"predecessor-version":[{"id":133933,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/13526\/revisions\/133933"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=13526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=13526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=13526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}