{"id":135480,"date":"2010-02-25T11:22:16","date_gmt":"2010-02-25T10:22:16","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=135480"},"modified":"2010-02-26T12:58:19","modified_gmt":"2010-02-26T11:58:19","slug":"genesis-de-las-dunas-de-yeso-terresres-implicaciones-en-el-estudio-de-las-dunas-de-marte-olympia-undae","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480","title":{"rendered":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae)"},"content":{"rendered":"<p style=\"text-align: justify;\">Ya hemos hablado en otros post de las singulares <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/12\/30\/130563\">dunas de yeso de Cuantroic\u00e9negas<\/a>, que tambi\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\u00f3n denominada <a href=\"http:\/\/www.nasa.gov\/mission_pages\/MRO\/multimedia\/pia09094.html\">Olympia Undae<\/a>. Recientemente, se ha publicado en la revista Geomorphology, un interesante art\u00edculo articulo sobre este tema. Se trata de estudiar la g\u00e9nesis de estos sistemas en la Tierra e inferir como se pudieron formar en Marte. De acuerdo a los autores, en ambos casos, su g\u00e9nesis acaece en un ambiente m\u00e1s h\u00famedo que lo que suele ser normal para otras formaciones similares, pero constituidas por part\u00edculas m\u00e1s estables, como el cuarzo. El art\u00edculo constata que en La Tierra, estas estructuras geomorfol\u00f3gicas debieron comenzar a originarse hace unos 7.000 a\u00f1os, siendo su f\u00e1cil estabilizaci\u00f3n producto de la r\u00e1pida cementaci\u00f3n de los materiales de yeso, humectados por aguas superficiales someras o subterr\u00e1neas a escasa profundidad. Como nos comentaron en nuestra visita a Cuatroci\u00e9negas, la desecaci\u00f3n de lagos someros durante las estaciones secas induce a que las part\u00edculas de yeso sean arrastradas por los vientos hasta los lugares en donde se forman los cordones. As\u00ed pues, se trata de un proceso e\u00f3lico de tipo subh\u00famedo, que no \u00e1rido, como es usual. Abajo os muestro el resumen de la mentada publicaci\u00f3n, primero en ingl\u00e9s y luego en espa\u00f1ol castellano, p\u00e1rrafo por p\u00e1rrafo. Al parecer los datos de estas formaciones terrestres ayudan a explicar como se originaron las marcianas.<\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/162\/dunas-de-marte-nasa.jpg\" alt=\"Dunas de Yeso Marte( Olympia Undae). Foto NASA\" width=\"400\" height=\"357\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.nasa.gov\/mission_pages\/MRO\/multimedia\/pia09094.html\">Dunas de Yeso en Marte\u00a0 (Olympia Undae). Fuente: Nasa<\/a><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #008000;\">Origin of terrestrial gypsum dunes\u2014Implications for Martian gypsum-rich dunes of Olympia Undae<\/span><\/strong><\/p>\n<p>Fuente: <a href=\"http:\/\/www.elsevier.com\/wps\/find\/journaldescription.cws_home\/503334\/description\">Geomorphologhy<\/a> Anna Szynkiewicz et al. 2009<\/p>\n<p><strong>Abstract-<\/strong><strong>Resumen<\/strong><strong> <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>The Estancia<\/strong>, <strong>White Sands<\/strong>, <strong>Guadalupe<\/strong> and<strong> Cuatroci\u00e9negas<\/strong> <strong>Dune Fields are among the largest known aeolian gypsum sand-dune accumulations on Earth and occupy closed-drainage basins within the <\/strong><strong>Rio Grande<\/strong><strong> Rift.<\/strong> <strong>High sedimentation rates of lacustrine gypsum occur in topographic depressions within the closed basins<\/strong>. <strong>The gypsum accumulations result from <\/strong>long-term, complex, interaction between tectonism, climate, and a hydrologic cycle that <strong>involves geochemical recycling of sulfur from older sedimentary rocks<\/strong> flanking and underlying the basins. <strong>Gypsum precipitation in lacustrine environments is strongly controlled by local groundwater\/bedrock interaction<\/strong>. The ranges of \u03b434S values (per mil, vs. VCDT) for gypsum sand in the <strong>White Sands Dune Field<\/strong> (12.1 to 13.9\u2030), <strong>Guadalupe Dune Field <\/strong>(10.2 to 12.5\u2030) and <strong>Cuatroci\u00e9negas Dune Field<\/strong> (14.6 to 15.9\u2030) indicate that <strong>the main sources of dissolved sulfate are evaporite strata of Lower Permian, Middle Permian and Cretaceous ages, respectively<\/strong>. A spatial increase of \u03b434S values across the White Sands Dune Field, in the direction of prevailing winds, matches well with a stratigraphically upward increase of \u03b434S values recorded in Lake Otero (an ancient lake in the basin) strata. <strong>This finding supports previous suggestions that White Sands Dune Field evolved as a result of the step-wise deflation of previously stored sediments in Lake Otero<\/strong>.<strong> <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><br \/>\n<\/strong>La Estancia, White Sands, Guadalupe y Cuatroci\u00e9negas se encuentran algunos de los m\u00e1s extensos sistemas de cordones dunares yes\u00edferos de origen e\u00f3lico en la Tierra, ocupando las cuencas de drenaje endorreicas (cerradas o sin salida al mar) en el Rift del R\u00edo Grande. Las elevadas tasas de sedimentaci\u00f3n de yeso lacustres acaecen en las depresiones topogr\u00e1ficas de estas cuencas. La acumulaci\u00f3n de yeso a largo plazo es el resultado de complejas interacciones entre tectonismo, el clima y ciclo hidrol\u00f3gico que implica el reciclaje geoqu\u00edmico de azufre de las rocas sedimentarias antiguas que flanquean y conforman el piso de esta cuenca. La precipitaci\u00f3n de yeso en ambientes lacustres est\u00e1 fuertemente controlada por la interacci\u00f3n entre las aguas subterr\u00e1neas locales y las rocas. Los rangos de valores \u03b434S (por mil, vs. a VCDT) para la arena gips\u00edfera en el campo de dunas de White Sands (Arenas Blancas) (12,1 a 13,9 \u2030), Guadalupe (10,2 a 12,5 \u2030) y Cuatroci\u00e9negas (14,6 a 15,9 \u2030) indican que de las principales fuentes de sulfato disueltos proceden de estratos de evaporitas del P\u00e9rmico Inferior, Medio y Cret\u00e1cico, respectivamente. Un incremento espacial de los valores \u03b434S en la direcci\u00f3n de los vientos dominantes se ajusta adecuadamente a los datos estratigr\u00e1ficos registrados en el Lago Otero (un antiguo lago de la cuenca). Este hallazgo apoya la sugerencia anterior de que el campo de Dunas de White Sands evolucion\u00f3 como resultado de la etapa de deflaci\u00f3n de los sedimentos previamente almacenados en el lago aludido.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/162\/dunas-blancas-11.jpg\" alt=\"Estabilizaci\u00f3n de de las dunas de Yeso por la vegetaci\u00f3n (Cuatroci\u00e9negas, M\u00e9xico)\" width=\"446\" height=\"332\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">Dunas de Cuatroci\u00e9negas (M\u00e9xico). Foto: Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>The modern gypsum dune fields are primarily wet eolian systems in which dune accumulation is controlled by a near-surface groundwater table, which promotes early cementation of the dune accumulations<\/strong>. <strong>Early cementation in the interdune surfaces and, to a lesser degree, on the dune surfaces reduces the amount of sand available for transport and slows rates of dune migration<\/strong>. Based on an average migration rate of 2\u00a0m\/year, the time needed for a dune at White Sands to migrate the downwind distance of the dune field is approximately 6500\u00a0years, which matches well with other estimates of the initiation of the <strong>dune field at approximately 7000\u00a0years ago and indicates that White Sands likely evolved as a wet aeolian system<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Los campos de dunas de yeso son modernos sistemas e\u00f3licos que se desarrollan bajo clima h\u00famedo (o al menos sin aridez acusada) en los que tal acumulaci\u00f3n es controlada por una capa de agua subterr\u00e1nea cercana a la superficie, la cual promueve la temprana cementaci\u00f3n del material dunar. Al comienzo de de cementaci\u00f3n, en los espacios interdunares y, en menor grado, sobre ellas reduce la cantidad de arena disponible para ser transportada, ralentizando las tasas de migraci\u00f3n de las dunas. Basado en una tasa de emigraci\u00f3n promedio de 2 m\/a\u00f1o, el tiempo necesario con vistas a que una duna en White Sands emigre a una cierta distancia resulta ser de aproximadamente 6500 a\u00f1os. Esta cifra coincide tambi\u00e9n con otras estimaciones acerca del inicio de la g\u00e9nesis de estos sistemas, hace aproximadamente 7000 a\u00f1os, e indica que White Sands probablemente evolucion\u00f3 como un sistema e\u00f3lico h\u00famedo.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/162\/dunas-blancas-55.jpg\" alt=\"Cementaci\u00f3n de las dunas de Yeso (Cuatroci\u00e9negas, M\u00e9xico)\" width=\"456\" height=\"337\" \/><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">R\u00e1pida cementaci\u00f3n de las dunas de Cuatroci\u00e9negas. Foto: J. J. Ib\u00e1\u00f1ez<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>As on Earth, gypsum-rich dune fields apparently are rare on Mars. Gypsum has been identified only within the Olympia Undae Dune Field which encircles a<\/strong> portion of the Martian north polar residual ice cap. <strong>Analogous to terrestrial gypsum dunes, the gypsum within the <\/strong><strong>Olympia<\/strong><strong> Undae gypsum-rich dunes might have originated from transport and deposition via aeolian processes<\/strong>. In this model, gypsum-rich source sediment <strong>could have been formed by confined groundwater or surface water activity and later transported by the wind. Any subsequent gypsum precipitation in the source area could have been initiated by episodic melting of the Martian polar ice cap<\/strong>. It is likely that the gypsum was deposited in the Olympia Undae dunes after the main deflation events that led to formation of the siliciclastic components of the dune field.<\/p>\n<p style=\"text-align: justify;\">Keywords: Terrestrial gypsum dunes; Sulfates; Sulfur isotopes; Eolian transport; Mars<\/p>\n<p style=\"text-align: justify;\">Como en la Tierra, los campos de dunas ricos en yeso aparentemente son poco frecuentes en Marte. Estos han sido identificados exclusivamente en el lugar denominado \u201cOlympia Dune Undae\u201d que rodea una parte del casquete de hielo polar residual del norte de la superficie marciana. An\u00e1logas a las dunas de yeso terrestres, el yeso de los cordones de arena de \u201cUndae Olimpia\u201d podr\u00edan tener su origen en el transporte y deposici\u00f3n e\u00f3licas. En este modelo, los sedimentos ricos en este mineral podr\u00edan haber sido formadas por las aguas subterr\u00e1neas confinadas o superficiales y posteriormente transportados por el viento. Cualquier precipitaci\u00f3n de yeso posterior en el \u00e1rea de origen podr\u00eda haber sido iniciada por la fusi\u00f3n epis\u00f3dica de la capa de hielo polar de Marte. Probablemente el yeso se deposit\u00f3 en las dunas \u201cUndae Olimpia\u201d tras la deflaci\u00f3n de los acontecimientos principales que llevaron a la formaci\u00f3n de los componentes de silicicl\u00e1stico del campo de dunas.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Ya hemos hablado en otros post de las singulares dunas de yeso de Cuantroic\u00e9negas, que tambi\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\u00f3n denominada Olympia Undae. Recientemente, se ha publicado en la revista Geomorphology, un interesante art\u00edculo articulo sobre este tema. Se trata de estudiar la g\u00e9nesis de estos sistemas en la Tierra e inferir como se pudieron formar en Marte. De acuerdo a los autores, en ambos casos, su g\u00e9nesis acaece en un ambiente m\u00e1s h\u00famedo que\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[603,1,607,600,617,598],"tags":[1369,1379,46692,1381],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ya hemos hablado en otros post de las singulares dunas de yeso de Cuantroic\u00e9negas, que tambi\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\u00f3n denominada Olympia Undae. Recientemente, se ha publicado en la revista\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Ya hemos hablado en otros post de las singulares dunas de yeso de Cuantroic\u00e9negas, que tambi\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\u00f3n denominada Olympia Undae. Recientemente, se ha publicado en la revista\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-02-25T10:22:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-02-26T11:58:19+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ya hemos hablado en otros post de las singulares dunas de yeso de Cuantroic\u00e9negas, que tambi\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\u00f3n denominada Olympia Undae. Recientemente, se ha publicado en la revista\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480#blogposting\",\"name\":\"G\\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae) - Un Universo invisible bajo nuestros pies\",\"headline\":\"G\\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/162\\\/dunas-de-marte-nasa.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480\\\/#articleImage\"},\"datePublished\":\"2010-02-25T11:22:16+01:00\",\"dateModified\":\"2010-02-26T12:58:19+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480#webpage\"},\"articleSection\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, General, Historia de la Tierra y de los Suelos., Los Suelos las Plantas y la Vegetaci\\u00f3n, Procesos Superficiales terrestres: Relieve, Geomorfolog\\u00eda y Cuencas de Drenaje:, Suelos de Zonas \\u00c1ridas, Semi\\u00e1ridas y desertificaci\\u00f3n, Dunas, La Tierra, Marte, Yeso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480#listItem\",\"name\":\"G\\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480#listItem\",\"position\":3,\"name\":\"G\\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480\",\"name\":\"G\\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae) - Un Universo invisible bajo nuestros pies\",\"description\":\"Ya hemos hablado en otros post de las singulares dunas de yeso de Cuantroic\\u00e9negas, que tambi\\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\\u00f3n denominada Olympia Undae. Recientemente, se ha publicado en la revista\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/02\\\/25\\\/135480#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2010-02-25T11:22:16+01:00\",\"dateModified\":\"2010-02-26T12:58:19+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae) - Un Universo invisible bajo nuestros pies","description":"Ya hemos hablado en otros post de las singulares dunas de yeso de Cuantroic\u00e9negas, que tambi\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\u00f3n denominada Olympia Undae. Recientemente, se ha publicado en la revista","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480#blogposting","name":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae) - Un Universo invisible bajo nuestros pies","headline":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/162\/dunas-de-marte-nasa.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480\/#articleImage"},"datePublished":"2010-02-25T11:22:16+01:00","dateModified":"2010-02-26T12:58:19+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480#webpage"},"articleSection":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, General, Historia de la Tierra y de los Suelos., Los Suelos las Plantas y la Vegetaci\u00f3n, Procesos Superficiales terrestres: Relieve, Geomorfolog\u00eda y Cuencas de Drenaje:, Suelos de Zonas \u00c1ridas, Semi\u00e1ridas y desertificaci\u00f3n, Dunas, La Tierra, Marte, Yeso"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480#listItem","name":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480#listItem","position":3,"name":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480","name":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae) - Un Universo invisible bajo nuestros pies","description":"Ya hemos hablado en otros post de las singulares dunas de yeso de Cuantroic\u00e9negas, que tambi\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\u00f3n denominada Olympia Undae. Recientemente, se ha publicado en la revista","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2010-02-25T11:22:16+01:00","dateModified":"2010-02-26T12:58:19+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae) - Un Universo invisible bajo nuestros pies","og:description":"Ya hemos hablado en otros post de las singulares dunas de yeso de Cuantroic\u00e9negas, que tambi\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\u00f3n denominada Olympia Undae. Recientemente, se ha publicado en la revista","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2010-02-25T10:22:16+00:00","article:modified_time":"2010-02-26T11:58:19+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae) - Un Universo invisible bajo nuestros pies","twitter:description":"Ya hemos hablado en otros post de las singulares dunas de yeso de Cuantroic\u00e9negas, que tambi\u00e9n se extienden por el sur de EE.UU., en ambientes similares. En el Planeta Rojo, es decir en Marte, tales sistemas de cordones dunares, aunque raros, acaecen en la regi\u00f3n denominada Olympia Undae. Recientemente, se ha publicado en la revista","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"135480","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:34:44","updated":"2026-05-26 16:03:51","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tG\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general"},{"label":"G\u00e9nesis de las Dunas de Yeso Terrestres: Implicaciones en el Estudio de las Dunas de Yeso de Marte (Olympia Undae)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/25\/135480"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/135480"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=135480"}],"version-history":[{"count":13,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/135480\/revisions"}],"predecessor-version":[{"id":135532,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/135480\/revisions\/135532"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=135480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=135480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=135480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}