{"id":135769,"date":"2010-04-21T11:20:23","date_gmt":"2010-04-21T10:20:23","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=135769"},"modified":"2010-04-21T11:20:23","modified_gmt":"2010-04-21T10:20:23","slug":"los-suelos-de-haiti-y-vulnerabilidad-a-la-desertificacion","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769","title":{"rendered":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">En su momento, ya hablamos acerca de los suelos de Hiat\u00ed, as\u00ed como de las razones de que este desventurado pa\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\u00f3n de la FAO que ofrecimos en su momento, era m\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que os mostramos ahora, procedente del Departamento de Agricultura de USA, fue elaborado a principios de este a\u00f1o (2010). Los paisajes de suelos, son t\u00edpicos de otras islas del Caribe. Del mismo modo\u00a0la vulnerabilidad a la desertificaci\u00f3n es moderadamente preocupante, que no alarmante. Todo ello vuelve a demostrarnos que los terribles padecimientos que sufren los ciudadanos del pa\u00eds son\u00a0simple fruto de una planificaci\u00f3n territorial nefasta, tanto en lo concerniente al medio urbano como natural. Los riesgos naturales afectan a todas las Islas del caribe, en mayor o menor medida. Contar con una buena ordenaci\u00f3n territorial, as\u00ed como\u00a0los distintos grados de pobreza, marcan las diferencias entre unos y otros.<\/p>\n<p style=\"text-align: center;\">\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/818\/paisaje-de-haiti.jpg\" alt=\"paisaje-de-haiti\" width=\"518\" height=\"335\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.asia.com\/country\/haiti\">Paisaje de Hait\u00ed. Fuente: Asia.com<\/a><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La informaci\u00f3n me la envi\u00f3 mi entra\u00f1able amigo <span style=\"color: #3366ff;\"><strong>Dick Arnold<\/strong><\/span>, antiguo capo del <strong><span style=\"color: #3366ff;\">Soil Survey Staff<\/span><\/strong>, previa solicitud a <strong><span style=\"color: #3366ff;\">Paul Reich<\/span><\/strong>, ge\u00f3grafo de suelos de esta instituci\u00f3n y colaborador del archiconocido (para los edaf\u00f3logos) <strong><span style=\"color: #3366ff;\">Hari Eswaran<\/span><\/strong>. Gracias a todos ellos. Una relaci\u00f3n de todos los post escritos sobre el tema, con sus respectivos enlaces la ofrecemos al final de esta contribuci\u00f3n.\u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\">Reiteramos que la vulnerabilidad a la desertificaci\u00f3n, si bien es alta, no podr\u00eda dar cuenta del desastre natural y humanitario que resulta ser Hait\u00ed. Obviamente, lo que debemos echar en falta es una cartograf\u00eda de la degradaci\u00f3n actual de sus suelos, que no de vulnerabilidades, pero que yo sepa, no ha sido realizada.<\/p>\n<p style=\"text-align: justify;\">El mapa de suelos, muy general, plasma los sub\u00f3rdenes conforme a la taxonom\u00eda americana de suelos. Por tanto no es detallada. No obstante, por el contrario, s\u00ed ofrece la posibilidad de explicar a los lectores no expertos en el tema ciertos aspectos que son dignos de se\u00f1alar. Nueve son los sub\u00f3rdenes plasmados en el mapa (a cuya versi\u00f3n original, de mejor resoluci\u00f3n, pod\u00e9is acceder pinchando con el rat\u00f3n en el pie de las foto), a saber, Argids, Cambids, Udults, Ustults, Ustalfs, Udalfs, Ustepts, Udepts y Fluvents.<\/p>\n<p style=\"text-align: center;\">\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/370\/mapa-de-suelos-de-haiti-subordenes-usda-nrcs.jpg\" alt=\"mapa-de-suelos-de-haiti-subordenes-usda-nrcs\" width=\"515\" height=\"337\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">Mapa de los Subordenes de Suelos de Hait\u00ed. Fuente: USDA NRCS<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<span style=\"color: #800080;\"><strong>Argids y Cambids<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Se trata de suelos bajo clima \u00e1rido (aridisoles), evolucionados y con lavado de arcilla en profundidad (Argids) o de escaso desarrollo edafogen\u00e9tico (Cambids). En ausencia de riego, son suelos escasamente productivos. Sin embargo, bajo regad\u00edo pueden dar lugar a buenas producciones, siempre que el riego sea generoso e impida que se acumulen las sales en superficie. No obstante, la extensi\u00f3n ocupara por los mismos, en esta parte de la Isla Espa\u00f1ola, es escasa.<\/p>\n<p><strong><span style=\"color: #800080;\">Udults y Ustults<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Estos tipos de suelos son muy evolucionados pero tambi\u00e9n de escasa fertilidad, dando lugar a malos rendimientos si no son previa y correctamente abonados. Se trata de edafotaxa t\u00edpicos de estos ambientes tropicales y subtropicales. \u201cUd\u201d nos informa de un edafoclima h\u00famedo, es decir sin d\u00e9ficit estacional de agua en el medio ed\u00e1fico. Por el contrario \u201cUst\u201d nos viene a decir, en lenguaje llano, que sufren stress h\u00eddrico en los periodos secos, que por aquellos lares suelen coincidir con las estaciones moderadamente fr\u00edas. Su extensi\u00f3n superficial en la isla es considerable.<\/p>\n<p style=\"text-align: center;\">\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/370\/mapa-de-vulnerabilidad-a-la-desertificacion-en-haiti-usda-nrc.jpg\" alt=\"mapa-de-vulnerabilidad-a-la-desertificacion-en-haiti-usda-nrc\" width=\"505\" height=\"345\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">Mapa de la Vulnerabilidad a la Desertificaci\u00f3n. Fuente USDA NRCS<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #800080;\">Ustalfs y Udalfs<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Nos encontramos ahora frente a suelos evolucionados (Alfisoles), aunque en menor medida menos que los \u201cult\u201d (Ultisoles), arcillosos en profundidad y ricos en nutrientes, siendo pues m\u00e1s aptos para la agricultura. Ya os hemos explicado, los significados de \u201cud\u201d y \u201cust\u201d. Hablamos pues de suelos bastante aptos para las producciones agrarias, ya sea de secano y mejor aun si lo fueran de regad\u00edo.\u00a0 Se trata de edafotaxa que tambi\u00e9n son muy abundantes en Hait\u00ed.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #800080;\">Ustepts y Udepts<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Se trata de suelos m\u00e1s j\u00f3venes y menos desarrollados (Inceptisoles), y que por lo tanto suelen atesorar m\u00e1s nutrientes (aunque no siempre), pero sin acumulaci\u00f3n de arcilla en profundidad. Respecto a su uso agrario, tambi\u00e9n son aceptables, siempre que se fertilicen cuando sea necesario. Tambi\u00e9n son abundantes en esta parte de la Isla Espa\u00f1ola.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #800080;\">Fluvents<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Se trata de edafotaxa de origen aluvial (Entisoles), muy poco evolucionados y que pueden ser ricos o pobres en nutrientes. Sin embargo, en ausencia de caracter\u00edsticas desfavorables (que no pueden inferirse a nivel de suborden) pueden dar lugar a abundantes cosechas, teniendo en cuenta, adem\u00e1s, que, por su origen, generalmente se ubican en zonas llanas pr\u00f3ximas al mar, o de grandes cauces fluviales.<\/p>\n<p style=\"text-align: justify;\">Resumiendo, los suelos de la isla no son los responsables de las hambrunas del pa\u00eds, sino la fantasmag\u00f3rica gesti\u00f3n que se ha hecho de los mismos. Respecto al riego en zonas costeras, es obvio que la instalaci\u00f3n de desaladoras podr\u00eda ser una soluci\u00f3n, como tambi\u00e9n con vistas a la obtenci\u00f3n de agua potable, tras los debidos tratamientos (uno de los problemas m\u00e1s graves en Hait\u00ed). Lo que desconozco es si huracanes y tsunamis, y en menor medida terremotos (m\u00e1s raros a largo plazo), hacen viables su instalaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Los denominados desastre naturales, son menos naturales y m\u00e1s de origen humano de suele imaginar el ciudadano.<\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez\u00a0 \u00a0<\/strong><\/span><\/p>\n<p>\u00a0<span style=\"color: #008080;\"><strong>Otros post relacionados con Hait\u00ed pueden leerse escribiendo el nombre del pa\u00eds en el buscador interno de este blog.<\/strong><\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>En su momento, ya hablamos acerca de los suelos de Hiat\u00ed, as\u00ed como de las razones de que este desventurado pa\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\u00f3n de la FAO que ofrecimos en su momento, era m\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que os mostramos ahora, procedente del Departamento de Agricultura de USA, fue elaborado a principios de este a\u00f1o (2010). Los paisajes de suelos, son t\u00edpicos de otras islas del Caribe. Del mismo modo\u00a0la vulnerabilidad a la desertificaci\u00f3n es moderadamente preocupante, que no alarmante. Todo ello vuelve\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[603,591,604,598],"tags":[46739,46744,46738,46740],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En su momento, ya hablamos acerca de los suelos de Hiat\u00ed, as\u00ed como de las razones de que este desventurado pa\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\u00f3n de la FAO que ofrecimos en su momento, era m\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"En su momento, ya hablamos acerca de los suelos de Hiat\u00ed, as\u00ed como de las razones de que este desventurado pa\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\u00f3n de la FAO que ofrecimos en su momento, era m\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-04-21T10:20:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-04-21T10:20:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En su momento, ya hablamos acerca de los suelos de Hiat\u00ed, as\u00ed como de las razones de que este desventurado pa\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\u00f3n de la FAO que ofrecimos en su momento, era m\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769#blogposting\",\"name\":\"Los Suelos de Hait\\u00ed y Vulnerabilidad a la Desertificaci\\u00f3n - Un Universo invisible bajo nuestros pies\",\"headline\":\"Los Suelos de Hait\\u00ed y Vulnerabilidad a la Desertificaci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/818\\\/paisaje-de-haiti.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769\\\/#articleImage\"},\"datePublished\":\"2010-04-21T11:20:23+01:00\",\"dateModified\":\"2010-04-21T11:20:23+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769#webpage\"},\"articleSection\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Edafolog\\u00eda y Pol\\u00edtica, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, Suelos de Zonas \\u00c1ridas, Semi\\u00e1ridas y desertificaci\\u00f3n, desertificaci\\u00f3n, geograf\\u00eda de suelos, Hait\\u00ed, Mapa de Suelos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/edafologia-y-politica#listItem\",\"name\":\"Edafolog\\u00eda y Pol\\u00edtica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/edafologia-y-politica#listItem\",\"position\":2,\"name\":\"Edafolog\\u00eda y Pol\\u00edtica\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/edafologia-y-politica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769#listItem\",\"name\":\"Los Suelos de Hait\\u00ed y Vulnerabilidad a la Desertificaci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769#listItem\",\"position\":3,\"name\":\"Los Suelos de Hait\\u00ed y Vulnerabilidad a la Desertificaci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/edafologia-y-politica#listItem\",\"name\":\"Edafolog\\u00eda y Pol\\u00edtica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769\",\"name\":\"Los Suelos de Hait\\u00ed y Vulnerabilidad a la Desertificaci\\u00f3n - Un Universo invisible bajo nuestros pies\",\"description\":\"En su momento, ya hablamos acerca de los suelos de Hiat\\u00ed, as\\u00ed como de las razones de que este desventurado pa\\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\\u00f3n de la FAO que ofrecimos en su momento, era m\\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/04\\\/21\\\/135769#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2010-04-21T11:20:23+01:00\",\"dateModified\":\"2010-04-21T11:20:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n - Un Universo invisible bajo nuestros pies","description":"En su momento, ya hablamos acerca de los suelos de Hiat\u00ed, as\u00ed como de las razones de que este desventurado pa\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\u00f3n de la FAO que ofrecimos en su momento, era m\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769#blogposting","name":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n - Un Universo invisible bajo nuestros pies","headline":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/818\/paisaje-de-haiti.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769\/#articleImage"},"datePublished":"2010-04-21T11:20:23+01:00","dateModified":"2010-04-21T11:20:23+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769#webpage"},"articleSection":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Edafolog\u00eda y Pol\u00edtica, Geograf\u00eda de Suelos y Megaedafolog\u00eda, Suelos de Zonas \u00c1ridas, Semi\u00e1ridas y desertificaci\u00f3n, desertificaci\u00f3n, geograf\u00eda de suelos, Hait\u00ed, Mapa de Suelos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica#listItem","name":"Edafolog\u00eda y Pol\u00edtica"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica#listItem","position":2,"name":"Edafolog\u00eda y Pol\u00edtica","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769#listItem","name":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769#listItem","position":3,"name":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica#listItem","name":"Edafolog\u00eda y Pol\u00edtica"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769","name":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n - Un Universo invisible bajo nuestros pies","description":"En su momento, ya hablamos acerca de los suelos de Hiat\u00ed, as\u00ed como de las razones de que este desventurado pa\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\u00f3n de la FAO que ofrecimos en su momento, era m\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2010-04-21T11:20:23+01:00","dateModified":"2010-04-21T11:20:23+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n - Un Universo invisible bajo nuestros pies","og:description":"En su momento, ya hablamos acerca de los suelos de Hiat\u00ed, as\u00ed como de las razones de que este desventurado pa\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\u00f3n de la FAO que ofrecimos en su momento, era m\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2010-04-21T10:20:23+00:00","article:modified_time":"2010-04-21T10:20:23+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n - Un Universo invisible bajo nuestros pies","twitter:description":"En su momento, ya hablamos acerca de los suelos de Hiat\u00ed, as\u00ed como de las razones de que este desventurado pa\u00eds sea presa de todo tipo de males y desastres ambientales. La informaci\u00f3n de la FAO que ofrecimos en su momento, era m\u00e1s pobre y menos actualizada que la que analizaremos hoy. El material que","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"135769","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 11:33:58","updated":"2026-05-26 16:10:09","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica\" title=\"Edafolog\u00eda y Pol\u00edtica\">Edafolog\u00eda y Pol\u00edtica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Edafolog\u00eda y Pol\u00edtica","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica"},{"label":"Los Suelos de Hait\u00ed y Vulnerabilidad a la Desertificaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/21\/135769"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/135769"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=135769"}],"version-history":[{"count":30,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/135769\/revisions"}],"predecessor-version":[{"id":135992,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/135769\/revisions\/135992"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=135769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=135769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=135769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}