{"id":136050,"date":"2010-05-01T09:37:18","date_gmt":"2010-05-01T08:37:18","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=136050"},"modified":"2010-05-07T13:22:08","modified_gmt":"2010-05-07T12:22:08","slug":"ciencia-confusa-el-papel-de-las-controversias-cientificas","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050","title":{"rendered":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales)"},"content":{"rendered":"<p style=\"text-align: justify;\">Las grandes controversias cient\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\u00f3gicos. Durante d\u00e9cadas, los defensores de hip\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto para la indagaci\u00f3n cient\u00edfica en general, el problema nos lleva al \u201c<em>delirium tremens<\/em>\u201d\u00a0 en el contexto de las ciencias hist\u00f3ricas, por cuanto los datos son escasos, fragmentarios y casi nunca concluyentes. Sin embargo, tales reyertas son fragantemente confundentes para el ciudadano, desde que los medios de comunicaci\u00f3n se hacen eco sistem\u00e1ticamente de las mismas. Tras la publicaci\u00f3n \u00a0de un hallazgo que parece corroborar una de las tesis, aparece otro que constata todo lo contrario. Sin embargo los periodistas, poco versados en estos temas, a menudo, los presentan al p\u00fablico como verdades absolutas. \u201cDesconcierto total\u201d<\/p>\n<p><img decoding=\"async\" class=\"ngg-singlepic ngg-center alignleft\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/humanos-modernos-y-neardentales-fuente-blog-el-origen-del-ser-humano.jpg\" alt=\"humanos-modernos-y-neardentales-fuente-blog-el-origen-del-ser-humano\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/laevoluvindelserhumano.blogspot.com\/2008\/11\/homo-sapiens.html\">Hombres Modernos y Neandertales. Fuente: Blog La Evoluci\u00f3n del Ser Humano<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0Hoy hablaremos sobre los hombres modernos y los neandertales. \u00bfSe cruzaron en el pasado? \u00bfSomos una misma especie? \u00bfEl hombre moderno extermin\u00f3 a los neandertales? \u00bfExistieron intercambios culturales? \u00bfGuerreaban entre ellos? \u00bfAlguna infecci\u00f3n del humano moderno acab\u00f3 con aquellos hom\u00ednidos tan feos? \u00bfDesaparecieron por falta de adaptaci\u00f3n a los cambios clim\u00e1ticos? \u00bfSomos los humanos modernos h\u00edbridos de croma\u00f1ones y neandertales?<\/p>\n<p style=\"text-align: justify;\">Tras miles de estudios publicados, al parecer seguimos sin respuestas que satisfagan a toda la comunidad cient\u00edfica. Y los interrogantes son muchos, como hab\u00e9is podido observar. Todo se me antoja un tanto sorprendente, por cuanto no hablamos de procesos ocurridos hace millones de a\u00f1os, sino en un periodo breve y muy reciente en t\u00e9rminos evolutivos.<\/p>\n<p style=\"text-align: justify;\">El registro f\u00f3sil, en este caso, partiendo de que se encuentre adecuadamente interpretado, resulta un tanto desconcertante. Al parecer, por lo que sabemos hasta ahora (muy poco) cohabitaron en el mismo espacio, o en territorios pr\u00f3ximos. Sin embargo, no se encuentran pruebas contundentes que avalen su interacci\u00f3n, y menos aun del tipo que fuera. Cuando en una cueva se detectan ejemplares de ambos hom\u00ednidos, siempre aparecen en ocupaciones diacr\u00f3nicas. Permitirme pues que os manifieste mi opini\u00f3n, muy personal por supuesto, por cuanto no soy experto en el tema.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Dada la naturaleza del ser humano, su territorialismo, ardua competencia por los recursos y agresividad, es dif\u00edcil digerir mentalmente, que coexistieran sin interacci\u00f3n, fuera la que fuera: del exterminio a la hibridaci\u00f3n. Conforme uno lee noticias sobre el tema, da la impresi\u00f3n de que los unos fueran invisibles a los otros y viceversa, cuando coexist\u00edan en un mismo espacio geogr\u00e1fico (que al parecer no suced\u00eda siempre). Son muchos los estudios que defienden tal invisibilidad (obviamente apelando a otros t\u00e9rminos). Sin embargo, si algo distingue al ser humano resulta ser su curiosidad, a veces sana y otras insana. \u00bfC\u00f3mo es posible que no se detectara ni un croma\u00f1on, ni un neandertal muerto en manos de sus competidores, o al menos vecinos, cuando nos matamos entre nosotros mismos?<\/p>\n<p style=\"text-align: justify;\">Ante tal desconcierto, algunos investigadores parecen haber aplicado el dicho de \u201ca r\u00edo revuelto ganancia de pescadores?. \u00a0Y dale que dale, publicaci\u00f3n tras publicaci\u00f3n, m\u00e1s de lo mismo, una y otra vez:<em> ad nausean<\/em>\u201d. No entiendo como las revistas denominadas de prestigio, se saltan los c\u00e1nones de la ciencia a la torera, una y otra vez. Ni corroboraciones ni refutaciones serias. Siempre m\u00e1s de lo mismo.<\/p>\n<p style=\"text-align: justify;\">La noticia que ofrecemos hoy atesora dos aspectos de inter\u00e9s, al menos para m\u00ed.<\/p>\n<p style=\"text-align: justify;\">En primer lugar, los \u201ctoca genes\u201d nos informan que, de hecho somos h\u00edbridos de aquella cohabitaci\u00f3n, aunque sea \u201cun poquito\u201d. Finalmente, nos vuelven a anunciar que en breve se publicar\u00e1 el ansiado genoma del neandertal. \u00bfTendremos tras ello pruebas definitivas con vistas a contestar los interrogantes que plantemos al principio? \u00bfSabremos al fin cuales son nuestros or\u00edgenes? \u00bfSon los africanos la \u00fanica raza (en un sentido figurado; no me gustan tales distinciones, al menos como se entienden hoy por hoy) libre de los genes de esos monstruosos trogloditas (seg\u00fan se muestran tendenciosamente pintados por la mano del <em>\u00bfHomo tecnologicus<\/em>?) Habr\u00e1 encontrado finalmente <a href=\"http:\/\/es.wikipedia.org\/wiki\/Ra\u00ed\u00adces_(miniserie)\">Kunta Kinde sus ra\u00edces<\/a>, y se carcajear\u00e1 de la supremac\u00eda aria (como me gustar\u00eda, jajaja). Pues bien, me temo que no. Es decir, que tras la publicaci\u00f3n de tan ansiado genoma, continuar\u00e1 el debate. Existen demasiados tintes raciales como para que tal investigaci\u00f3n no sea contaminada, aun obteniendo\u00a0pruebas \u201cirrefutables\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00bfC\u00f3mo se puede publicar tanto y con tan escasas evidencias en revistas cient\u00edficas de prestigio? Es palmario que de aplicar criterios rigurosos (\u2026\u2026). Empero hay ciencias \u201csexy\u201d (como\u00a0dec\u00eda Antonio Lafuente en su blog <a href=\"http:\/\/www.madrimasd.org\/blogs\/tecnocidanos\">Tecnocidanos<\/a>) y otras rastreras (como el estudio de los suelos).<\/p>\n<p style=\"text-align: justify;\">Eso s\u00ed, de confirmarse la hibridaci\u00f3n, los mediterr\u00e1neos nos sentiremos orgullosos de ser no s\u00f3lo crisol de mezclas culturales, sino de mucho m\u00e1s. Empero all\u00e1 por el norte de Europa, y en especial ante la alarmante emergencia de los partidos racistas Y\/o neonazis\u2026\u2026\u2026\u2026<\/p>\n<p style=\"text-align: justify;\">Ya hablaremos en otra ocasi\u00f3n sobre el enigm\u00e1tico tema de \u201cqu\u00e9\u201d extermin\u00f3 a los dinosaurios, si los cuerpos alien\u00edgenas (meteoritos), o las m\u00e1s misteriosas legiones de fuerzas tel\u00faricas (volcanes), o\u00a0 extraterrestres realmente inteligentes, y por tanto despiadados, como los <a href=\"http:\/\/es.wikipedia.org\/wiki\/The_Terminator\">Terminador<\/a>, \u00a0porqu\u00e9 tambi\u00e9n aqu\u00ed\u2026\u2026\u2026..<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez\u00a0\u00a0\u00a0\u00a0<\/span><\/strong>\u00a0\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p align=\"center\"><strong><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=43602&amp;origen=notiweb\"><span style=\"color: #008000;\">Los neandertales pudieron tener hijos con los sapiens<\/span><\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><em><strong>\u00a0<span style=\"color: #008080;\">\u00a1Que Mal Gusto!. Nota de este blogger<\/span><\/strong><\/em><\/p>\n<p><strong>Los ancestros de los humanos actuales y sus primos los neandertales se cruzaron en dos ocasiones y tuvieron descendencia hace miles de a\u00f1os<\/strong>, seg\u00fan un estudio presentado en EE.UU.\u00a0 FUENTE | <a href=\"http:\/\/www.publico.es\/\" target=\"_blank\">P\u00fablico<\/a> 22\/04\/2010<\/p>\n<p style=\"text-align: justify;\">Los autores del trabajo, de la <a href=\"http:\/\/www.unm.edu\/\" target=\"_blank\">Universidad de Nuevo M\u00e9xico<\/a>, se\u00f1alan que, como testimonio, <strong>la mayor\u00eda de humanos actuales lleva rastros de neandertal en su ADN. \u00abEsto significa que los neandertales no han desaparecido por completo<\/strong>\u00ab, explic\u00f3 a <a href=\"http:\/\/www.nature.com\/\" target=\"_blank\">Nature<\/a> News Jeffrey Long, investigador principal del estudio.<\/p>\n<p style=\"text-align: justify;\">El trabajo fue presentado el pasado s\u00e1bado durante la reuni\u00f3n anual de la <a href=\"http:\/\/physanth.org\/\" target=\"_blank\">Asociaci\u00f3n Americana de Antropolog\u00eda F\u00edsica<\/a>, que se celebr\u00f3 en Albuquerque. <strong>Vuelve a formular grandes preguntas sobre la naturaleza de humanos modernos y neandertales. Una de las m\u00e1s evidentes es que, si ambos pudieron aparearse y tener hijos, no eran en realidad especies diferentes<\/strong>.<\/p>\n<p style=\"text-align: justify;\">El trabajo ha analizado <strong>el ADN de 1.983 personas en \u00c1frica, Asia, Europa, Am\u00e9rica y Ocean\u00eda<\/strong> en busca de huellas caracter\u00edsticas de neandertales u otras especies extintas del g\u00e9nero Homo, como el Homo heidelbergensis.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #008080;\">ENCUENTRO EN EL MEDITERR\u00c1NEO<\/span><\/strong><br \/>\n<strong>Los resultados mantienen que hubo dos grandes episodios de cruce entre especies despu\u00e9s de que el sapiens abandonase \u00c1frica. El primero sucedi\u00f3 hace 60.000 a\u00f1os en las costas del Mediterr\u00e1neo<\/strong>.<strong> El segundo encuentro sucedi\u00f3 hace 45.000 a\u00f1os en el este de Asia<\/strong>. Los expertos <strong>no encontraron rastros de hibridaci\u00f3n en las poblaciones africanas<\/strong>. Los autores creen que los <strong>primeros mestizos que nacieron en el Mediterr\u00e1neo migraron despu\u00e9s al<\/strong> resto de Europa, Norteam\u00e9rica y Asia. Las poblaciones del segundo cruce migraron despu\u00e9s a Ocean\u00eda.<\/p>\n<p style=\"text-align: justify;\">El trabajo se ha centrado en <strong>m\u00e1s de 600 microsat\u00e9lites de ADN<\/strong>. Son marcadores en el genoma que se usan para diferenciar gen\u00e9ticamente a diferentes poblaciones actuales y emparentarlas con las poblaciones ancestrales que vivieron hace miles de a\u00f1os. Los expertos compararon esos microsat\u00e9lites con la tasa de cambio gen\u00e9tico que ser\u00eda de esperar en ellos despu\u00e9s de miles de a\u00f1os de evoluci\u00f3n, y tambi\u00e9n con datos del registro f\u00f3sil. <strong>Reconstruyeron despu\u00e9s un \u00e1rbol evolutivo que llevaba hasta las poblaciones actuales analizadas<\/strong>. La \u00fanica manera de explicar los resultados era a trav\u00e9s de esos dos momentos de hibridaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan <strong>Nature News<\/strong>, el trabajo fue recibido con inter\u00e9s y sorpresa por expertos que llevan a\u00f1os intentando explicar incoherencias en los genes de las poblaciones actuales y su conexi\u00f3n con sus ancestros.<\/p>\n<p style=\"text-align: justify;\">\u00abEs una conclusi\u00f3n llamativa\u00bb, explica Carles Lalueza, profesor de la Unidad de Biolog\u00eda Evolutiva de la <a href=\"http:\/\/www.upf.edu\/es\" target=\"_blank\">Universidad Pompeu Fabra<\/a> de Barcelona. <strong>El experto recomienda cautela<\/strong>. Aunque el trabajo se ha presentado en un congreso que re\u00fane a expertos de todo el mundo, no se ha publicado en una revista cient\u00edfica. \u00abH<strong>ay que esperar a que aparezcan todos los datos\u00bb, advierte. Tambi\u00e9n apunta que este tipo de estudio puede estar viciado, pues<\/strong> se hace en funci\u00f3n de la tasa de variaci\u00f3n de los sapiens, y no de los neandertales. Estos \u00faltimos podr\u00edan tener una tasa diferente, <strong>lo que volver\u00eda a poner patas arriba las interpretaciones<\/strong>. Lalueza ser\u00e1 uno de los que puedan aportar nuevas respuestas, pues su equipo, liderado por el experto en gen\u00e9tica neandertal Svante P\u00e4\u00e4bo, <strong>ya ha secuenciado el primer genoma completo de neandertal, a la espera de publicaci\u00f3n<\/strong>.<br \/>\nAutor: \u00a0 Nu\u00f1o Dom\u00ednguez<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Las grandes controversias cient\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\u00f3gicos. Durante d\u00e9cadas, los defensores de hip\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto para la indagaci\u00f3n cient\u00edfica en general, el problema nos lleva al \u201cdelirium tremens\u201d\u00a0 en el contexto de las ciencias hist\u00f3ricas, por cuanto los datos son escasos, fragmentarios y casi nunca concluyentes. Sin embargo, tales reyertas son fragantemente confundentes para el ciudadano, desde que los medios\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[609,615,606],"tags":[1682,46785,1683,1684],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las grandes controversias cient\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\u00f3gicos. Durante d\u00e9cadas, los defensores de hip\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Las grandes controversias cient\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\u00f3gicos. Durante d\u00e9cadas, los defensores de hip\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-05-01T08:37:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-05-07T12:22:08+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las grandes controversias cient\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\u00f3gicos. Durante d\u00e9cadas, los defensores de hip\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050#blogposting\",\"name\":\"Ciencia Confusa: El Papel de las Controversias Cient\\u00edficas (sobre hombres modernos y neandertales) - Un Universo invisible bajo nuestros pies\",\"headline\":\"Ciencia Confusa: El Papel de las Controversias Cient\\u00edficas (sobre hombres modernos y neandertales)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/1123\\\/humanos-modernos-y-neardentales-fuente-blog-el-origen-del-ser-humano.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050\\\/#articleImage\"},\"datePublished\":\"2010-05-01T09:37:18+01:00\",\"dateModified\":\"2010-05-07T13:22:08+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":5,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050#webpage\"},\"articleSection\":\"Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, Notas Breves de Prensa, Prensa y Pol\\u00edtica Cient\\u00edfica, ciencias hist\\u00f3ricas, controversias cient\\u00edficas, hombres modernos, neardentales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/prensa-y-politica-cientifica#listItem\",\"name\":\"Prensa y Pol\\u00edtica Cient\\u00edfica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/prensa-y-politica-cientifica#listItem\",\"position\":2,\"name\":\"Prensa y Pol\\u00edtica Cient\\u00edfica\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/prensa-y-politica-cientifica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050#listItem\",\"name\":\"Ciencia Confusa: El Papel de las Controversias Cient\\u00edficas (sobre hombres modernos y neandertales)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050#listItem\",\"position\":3,\"name\":\"Ciencia Confusa: El Papel de las Controversias Cient\\u00edficas (sobre hombres modernos y neandertales)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/prensa-y-politica-cientifica#listItem\",\"name\":\"Prensa y Pol\\u00edtica Cient\\u00edfica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050\",\"name\":\"Ciencia Confusa: El Papel de las Controversias Cient\\u00edficas (sobre hombres modernos y neandertales) - Un Universo invisible bajo nuestros pies\",\"description\":\"Las grandes controversias cient\\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\\u00f3gicos. Durante d\\u00e9cadas, los defensores de hip\\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/05\\\/01\\\/136050#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2010-05-01T09:37:18+01:00\",\"dateModified\":\"2010-05-07T13:22:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales) - Un Universo invisible bajo nuestros pies","description":"Las grandes controversias cient\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\u00f3gicos. Durante d\u00e9cadas, los defensores de hip\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050#blogposting","name":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales) - Un Universo invisible bajo nuestros pies","headline":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/humanos-modernos-y-neardentales-fuente-blog-el-origen-del-ser-humano.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050\/#articleImage"},"datePublished":"2010-05-01T09:37:18+01:00","dateModified":"2010-05-07T13:22:08+01:00","inLanguage":"es-ES","commentCount":5,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050#webpage"},"articleSection":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, Notas Breves de Prensa, Prensa y Pol\u00edtica Cient\u00edfica, ciencias hist\u00f3ricas, controversias cient\u00edficas, hombres modernos, neardentales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica#listItem","name":"Prensa y Pol\u00edtica Cient\u00edfica"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica#listItem","position":2,"name":"Prensa y Pol\u00edtica Cient\u00edfica","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050#listItem","name":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050#listItem","position":3,"name":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica#listItem","name":"Prensa y Pol\u00edtica Cient\u00edfica"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050","name":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales) - Un Universo invisible bajo nuestros pies","description":"Las grandes controversias cient\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\u00f3gicos. Durante d\u00e9cadas, los defensores de hip\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2010-05-01T09:37:18+01:00","dateModified":"2010-05-07T13:22:08+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales) - Un Universo invisible bajo nuestros pies","og:description":"Las grandes controversias cient\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\u00f3gicos. Durante d\u00e9cadas, los defensores de hip\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2010-05-01T08:37:18+00:00","article:modified_time":"2010-05-07T12:22:08+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales) - Un Universo invisible bajo nuestros pies","twitter:description":"Las grandes controversias cient\u00edficas han existido desde que la ciencia es ciencia, y a veces no parecen diferir en la forma (prefiero no hablar de fondo) de los seculares debates teol\u00f3gicos. Durante d\u00e9cadas, los defensores de hip\u00f3tesis rivales se enzarzan en discusiones interminables, a menudo bizantinas, y a veces tendenciosas. Si tal hecho es cierto","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136050","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:38:44","updated":"2026-05-26 16:10:09","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica\" title=\"Prensa y Pol\u00edtica Cient\u00edfica\">Prensa y Pol\u00edtica Cient\u00edfica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCiencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Prensa y Pol\u00edtica Cient\u00edfica","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica"},{"label":"Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136050"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=136050"}],"version-history":[{"count":18,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136050\/revisions"}],"predecessor-version":[{"id":136088,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136050\/revisions\/136088"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=136050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=136050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=136050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}