{"id":136476,"date":"2010-06-28T13:20:59","date_gmt":"2010-06-28T12:20:59","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=136476"},"modified":"2010-06-28T18:12:23","modified_gmt":"2010-06-28T17:12:23","slug":"suelos-minerales-condicionados-por-la-topografia-o-fisiografia-leptosoles-regosoles-fluvisoles-y-gleysoles","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476","title":{"rendered":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles."},"content":{"rendered":"<p style=\"text-align: justify;\">La<strong> <span style=\"color: #3366ff;\">distribuci\u00f3n geogr\u00e1fica<\/span><\/strong> de distintos tipos de<strong><span style=\"color: #3366ff;\"> suelos<\/span><\/strong> (o edafotaxa) en el paisaje se encuentra condicionada por sus <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/01\/77889\">factores formadores<\/a>. <strong><span style=\"color: #3366ff;\">En algunos casos, el relieve y la fisiograf\u00eda determinan que aparezcan unos determinados con mucha frecuencia<\/span><\/strong>. Dos situaciones concretas son dignas de rese\u00f1ar. La primera concierne a aquellos casos <strong><span style=\"color: #3366ff;\">en donde la una abrupta pendiente del terreno exporta continuamente los materiales ed\u00e1ficos (erosi\u00f3n)<\/span><\/strong>, de tal modo que el <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/10\/02\/102439\">perfil del suelo<\/a> se mantiene <strong><span style=\"color: #3366ff;\">poco<\/span><\/strong> <strong><span style=\"color: #3366ff;\">profundo y escasamente evolucionado<\/span><\/strong>. En estos casos, <strong><span style=\"color: #3366ff;\">sobre rocas duras o consolidadas<\/span><\/strong> suelen aparecer los <strong><span style=\"color: #3366ff;\">Leptosoles<\/span><\/strong>, mientras que sobre las <strong><span style=\"color: #3366ff;\">blandas y deleznables<\/span><\/strong> lo hacen los <strong><span style=\"color: #3366ff;\">Regosoles<\/span><\/strong>. Por el contrario,<strong> <span style=\"color: #3366ff;\">en las zonas bajas del paisaje<\/span><\/strong>, caracterizadas por la <strong><span style=\"color: #3366ff;\">deposici\u00f3n de materiales<\/span><\/strong>, cerca de los<span style=\"color: #3366ff;\"> <strong>cursos fluviales y llanuras costeras<\/strong><\/span> los paisajes de suelos se caracterizan por la presencia de edafotaxa\u00a0 <strong><span style=\"color: #3366ff;\">profundos, aunque tambi\u00e9n poco evolucionados<\/span><\/strong>, caracterizados por la estratificaci\u00f3n de materiales que aportan las deposiciones fluviales. Hablamos entonces de <strong><span style=\"color: #3366ff;\">Fluvisoles<\/span><\/strong>. <span style=\"color: #3366ff;\"><strong>En<\/strong> <\/span><strong><span style=\"color: #3366ff;\">hondonadas<\/span> <\/strong>originadas por el relieve y\/o cuando el terreno se encuentra <strong><span style=\"color: #3366ff;\">anegado de agua<\/span><\/strong>, se forman los denominados <span style=\"color: #3366ff;\"><strong>Gleysoles (suelos hidrom\u00f3rficos)<\/strong>.\u00a0\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1283\/o_Kalipedia2.png\" alt=\"o_Kalipedia2\" width=\"317\" height=\"426\" \/>\u00a0<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.kalipedia.com\/tecnologia\/tema\/rios-partes.html?x=20070417klpcnatun_119.Kes&amp;ap=2\">Cuenca de Drenaje. Fuente: Kalipedia: En zonas altas abundan Leptosoles y Regosoles, a lo lago del curso del r\u00edo y en la desembocadura los Fluvisoles, y en las zonas encharcadas los Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Estos edafotaxa<span style=\"color: #3366ff;\"> <strong>corresponden a<\/strong><\/span> la categor\u00eda de los denominados <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/10\/15\/46305\">Suelos intrazonales<\/a>, por cuanto \u201cen general\u201d<span style=\"color: #3366ff;\"> <\/span><strong><span style=\"color: #3366ff;\">su presencia est\u00e1<\/span> <span style=\"color: #3366ff;\">determinada por el modelado del terreno<\/span><\/strong>, m\u00e1s que la vegetaci\u00f3n, clima, litolog\u00eda, etc. Sin embargo, siempre deben matizarse tales asertos contundentes. Cuando por la raz\u00f3n que sea los suelos originales son completa o casi completamente erosionados, los<strong> <span style=\"color: #3366ff;\">Leptosoles y\/o Regosoles<\/span> <\/strong>hacen acto de presencia, ya que se trata de materiales ed\u00e1ficos que desprende la roca al interaccionar con la atm\u00f3sfera y biosfera. Hablamos pues de<span style=\"color: #3366ff;\"> <strong>suelos que caracterizan muchos paisajes profundamente erosionados con escasa vegetaci\u00f3n<\/strong><\/span>. Del mismo modo, los <strong><span style=\"color: #3366ff;\">Gleysoles pueden surgir por degradaci\u00f3n del suelo en ambientes hiper-h\u00famedos<\/span><\/strong> en los que la degradaci\u00f3n de la vegetaci\u00f3n genera que la<strong> <span style=\"color: #3366ff;\">tasa de evapotranspiraci\u00f3n sea menor que la recibida por las lluvias<\/span><\/strong>. Bajo tales circunstancias <strong><span style=\"color: #3366ff;\">el suelo original se encharca<\/span><\/strong> cambiando paulatinamente sus propiedades y morfolog\u00eda para dar lugar a Gleysoles u otros edafotaxa con caracter\u00edsticas gleycas.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #3366ff;\">Los Fluvisoles suelen localizarse en<\/span> <\/strong>las llanuras de inundaci\u00f3n de los grandes cursos de agua, es decir muy pr\u00f3ximos a los r\u00edos. Del mismo modo, cuando consideramos intervalos de tiempo extenso, entre miles y cientos de miles de a\u00f1os, <strong><span style=\"color: #3366ff;\">la erosi\u00f3n de los suelos de<\/span> <span style=\"color: #3366ff;\">las monta\u00f1as<\/span><\/strong> (ya sea natural o inducida por el hombre)<span style=\"color: #3366ff;\"> <strong>acarrea los materiales hasta<\/strong><\/span> los bordes de los niveles de base locales, ya sean los propios <strong><span style=\"color: #3366ff;\">oc\u00e9anos, ya lagunas o mares interiores<\/span><\/strong>. Aqu\u00ed tambi\u00e9n se sit\u00faan, en muchos lugares, amplias zonas con <strong><span style=\"color: #3366ff;\">Fluvisoles<\/span><\/strong> que, por tanto, se encuentran espacialmente relacionados con los Leptosoles de las zonas de monta\u00f1a que les ofrecen sus materiales por la erosi\u00f3n, transporte y sedimentaci\u00f3n de la cuenca de drenaje en la que se ubican.\u00a0\u00a0\u00a0\u00a0<\/p>\n<p>La Monograf\u00eda <a href=\"http:\/\/www.fao.org\/DOCREP\/003\/Y1899E\/Y1899E00.HTM\">Lecture notes on the major soils of the world<\/a>, es decir la traducida al Espa\u00f1ol Castellano por Francisco nos dice de ellos (Conjunto 4)<\/p>\n<p><strong><span style=\"color: #008080;\">Suelos minerales en los cuales la formaci\u00f3n es notoriamente influenciada por su ubicaci\u00f3n topogr\u00e1fica-fisiogr\u00e1fica<\/span><\/strong>.<\/p>\n<p>\u00a0Este conjunto incluye suelos en posiciones de terrenos bajos asociados con formaci\u00f3n de suelos debidas a bajas temperaturas o erosi\u00f3n. Este conjunto incluye cuatro Grupos de Suelos de Referencia.<\/p>\n<p><strong>&#8211;<span style=\"color: #008080;\"> Suelos en tierras bajas (anegadas) con nivel topogr\u00e1fico<\/span>: <span style=\"color: #3366ff;\">Fluvisoles y Gleysoles<\/span><\/strong><\/p>\n<p><strong>&#8211; <span style=\"color: #008080;\">Suelos en regiones elevadas sin nivel topogr\u00e1fico<\/span>. <span style=\"color: #3366ff;\">Leptosoles y Regosoles<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #008080;\">En \u00e1reas elevadas y\/o erosionadas<\/span><\/strong>:<\/p>\n<p style=\"text-align: justify;\">3.<span style=\"color: #3366ff;\"> <strong>LEPTOSOLES<\/strong><\/span>: someros sobre roca dura o material altamente calc\u00e1reo, y<\/p>\n<p style=\"text-align: justify;\">4.<strong> <span style=\"color: #3366ff;\">REGOSOLES<\/span>:<\/strong> profundos, los cuales ocurren en material no consolidado y s\u00f3lo presentan un desarrollo superficial del perfil, ejemplo: debido a las bajas temperaturas del suelo, sequ\u00edas prolongadas o erosi\u00f3n<\/p>\n<p><strong><span style=\"color: #008080;\">En posici\u00f3n de tierras bajas<\/span><\/strong>:<\/p>\n<p style=\"text-align: justify;\">1. <strong><span style=\"color: #3366ff;\">FLUVISOLES<\/span><\/strong>: aluviales j\u00f3venes, los cuales muestran estratificaci\u00f3n o alguna otra evidencia de sedimentaci\u00f3n reciente y<\/p>\n<p style=\"text-align: justify;\">2.<strong> <span style=\"color: #3366ff;\">GLEYSOLES<\/span><\/strong><span style=\"color: #3366ff;\">:<\/span> no estratificados en \u00e1reas con nivel fre\u00e1tico que no reciben aportaciones regulares de sedimentos.<\/p>\n<p style=\"text-align: justify;\">En los pr\u00f3ximos post, iremos analizando las caracter\u00edsticas y distribuci\u00f3n de cada uno de estos Grupos de Suelos de Referencia de la WRB por separado, con especial \u00e9nfasis en Latinoam\u00e9rica y Europa.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez y<\/span><\/strong><strong><span style=\"color: #008000;\">Javier Manr\u00edquez Cos\u00edo<\/span><\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong><span style=\"color: #008080;\">Material Bibliogr\u00e1fico de Base<\/span><\/strong><\/p>\n<p><a href=\"http:\/\/www.fao.org\/nr\/land\/soils\/soil\/en\">P\u00e1gina Web de la WRB<\/a><\/p>\n<p><a href=\"ftp:\/\/ftp.fao.org\/docrep\/fao\/011\/a0510s\/a0510s00.pdf\">Clasificaci\u00f3n WRB 2006.2007<\/a><\/p>\n<p><a href=\"http:\/\/www.fao.org\/DOCREP\/003\/Y1899E\/Y1899E00.HTM\">Lecture notes on the major soils of the world<\/a> (versi\u00f3n personal traducida al espa\u00f1ol por Javier Manr\u00edquez Cos\u00edo<\/p>\n<p><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/esdb_archive\/eusoils_docs\/other\/EUR23439.pdf\">Soils of The Euroean Uni\u00f3n IRC-ESB)<\/a><\/p>\n<p><a href=\"http:\/\/www.inegi.org.mx\/prod_serv\/contenidos\/espanol\/bvinegi\/productos\/integracion\/especiales\/BoletinSNEIG\/2010\/Bsnieg14_b.pdf\">Los suelos de Latinoam\u00e9rica: retos y oportunidades de uso y estudio<\/a> (ir al titulo correspondiente) Autores: Francisco Bautista, Alfred J. Zinck y Silke Cram. Boleti\u00f3n del Sistema Nacional de Informaci\u00f3n Estad\u00edstica y Geogr\u00e1fica: VII(3) Septiembre-Diciembre 2009, p\u00e1ginas 94-142<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>La distribuci\u00f3n geogr\u00e1fica de distintos tipos de suelos (o edafotaxa) en el paisaje se encuentra condicionada por sus factores formadores. En algunos casos, el relieve y la fisiograf\u00eda determinan que aparezcan unos determinados con mucha frecuencia. Dos situaciones concretas son dignas de rese\u00f1ar. La primera concierne a aquellos casos en donde la una abrupta pendiente del terreno exporta continuamente los materiales ed\u00e1ficos (erosi\u00f3n), de tal modo que el perfil del suelo se mantiene poco profundo y escasamente evolucionado. En estos casos, sobre rocas duras o consolidadas suelen aparecer los Leptosoles, mientras que sobre las blandas y deleznables lo hacen los\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1929,604,585,617,601],"tags":[1933,46824,46825,46823,46822,1934,46676],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La distribuci\u00f3n geogr\u00e1fica de distintos tipos de suelos (o edafotaxa) en el paisaje se encuentra condicionada por sus factores formadores. En algunos casos, el relieve y la fisiograf\u00eda determinan que aparezcan unos determinados con mucha frecuencia. Dos situaciones concretas son dignas de rese\u00f1ar. La primera concierne a aquellos casos en donde la una abrupta pendiente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles. - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"La distribuci\u00f3n geogr\u00e1fica de distintos tipos de suelos (o edafotaxa) en el paisaje se encuentra condicionada por sus factores formadores. En algunos casos, el relieve y la fisiograf\u00eda determinan que aparezcan unos determinados con mucha frecuencia. Dos situaciones concretas son dignas de rese\u00f1ar. La primera concierne a aquellos casos en donde la una abrupta pendiente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-06-28T12:20:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-06-28T17:12:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles. - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La distribuci\u00f3n geogr\u00e1fica de distintos tipos de suelos (o edafotaxa) en el paisaje se encuentra condicionada por sus factores formadores. En algunos casos, el relieve y la fisiograf\u00eda determinan que aparezcan unos determinados con mucha frecuencia. Dos situaciones concretas son dignas de rese\u00f1ar. La primera concierne a aquellos casos en donde la una abrupta pendiente\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476#blogposting\",\"name\":\"Suelos Minerales Condicionados por la Topograf\\u00eda o Fisiograf\\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles. - Un Universo invisible bajo nuestros pies\",\"headline\":\"Suelos Minerales Condicionados por la Topograf\\u00eda o Fisiograf\\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles.\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/1283\\\/o_Kalipedia2.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476\\\/#articleImage\"},\"datePublished\":\"2010-06-28T13:20:59+01:00\",\"dateModified\":\"2010-06-28T18:12:23+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":84,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476#webpage\"},\"articleSection\":\"Curso B\\u00e1sico: Tipos de Suelos del Mundo, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n, Procesos Superficiales terrestres: Relieve, Geomorfolog\\u00eda y Cuencas de Drenaje:, Taxonom\\u00edas y Clasificaciones, fisiograf\\u00eda, Fluvisoles, Gleysoles, Leptosoles, Regosoles, relieve, suelos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"position\":2,\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476#listItem\",\"name\":\"Suelos Minerales Condicionados por la Topograf\\u00eda o Fisiograf\\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476#listItem\",\"position\":3,\"name\":\"Suelos Minerales Condicionados por la Topograf\\u00eda o Fisiograf\\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476\",\"name\":\"Suelos Minerales Condicionados por la Topograf\\u00eda o Fisiograf\\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles. - Un Universo invisible bajo nuestros pies\",\"description\":\"La distribuci\\u00f3n geogr\\u00e1fica de distintos tipos de suelos (o edafotaxa) en el paisaje se encuentra condicionada por sus factores formadores. En algunos casos, el relieve y la fisiograf\\u00eda determinan que aparezcan unos determinados con mucha frecuencia. Dos situaciones concretas son dignas de rese\\u00f1ar. La primera concierne a aquellos casos en donde la una abrupta pendiente\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/06\\\/28\\\/136476#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2010-06-28T13:20:59+01:00\",\"dateModified\":\"2010-06-28T18:12:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles. - Un Universo invisible bajo nuestros pies","description":"La distribuci\u00f3n geogr\u00e1fica de distintos tipos de suelos (o edafotaxa) en el paisaje se encuentra condicionada por sus factores formadores. En algunos casos, el relieve y la fisiograf\u00eda determinan que aparezcan unos determinados con mucha frecuencia. Dos situaciones concretas son dignas de rese\u00f1ar. La primera concierne a aquellos casos en donde la una abrupta pendiente","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476#blogposting","name":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles. - Un Universo invisible bajo nuestros pies","headline":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles.","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1283\/o_Kalipedia2.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\/#articleImage"},"datePublished":"2010-06-28T13:20:59+01:00","dateModified":"2010-06-28T18:12:23+01:00","inLanguage":"es-ES","commentCount":84,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476#webpage"},"articleSection":"Curso B\u00e1sico: Tipos de Suelos del Mundo, Geograf\u00eda de Suelos y Megaedafolog\u00eda, P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n, Procesos Superficiales terrestres: Relieve, Geomorfolog\u00eda y Cuencas de Drenaje:, Taxonom\u00edas y Clasificaciones, fisiograf\u00eda, Fluvisoles, Gleysoles, Leptosoles, Regosoles, relieve, suelos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","position":2,"name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476#listItem","name":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476#listItem","position":3,"name":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476","name":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles. - Un Universo invisible bajo nuestros pies","description":"La distribuci\u00f3n geogr\u00e1fica de distintos tipos de suelos (o edafotaxa) en el paisaje se encuentra condicionada por sus factores formadores. En algunos casos, el relieve y la fisiograf\u00eda determinan que aparezcan unos determinados con mucha frecuencia. Dos situaciones concretas son dignas de rese\u00f1ar. La primera concierne a aquellos casos en donde la una abrupta pendiente","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2010-06-28T13:20:59+01:00","dateModified":"2010-06-28T18:12:23+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles. - Un Universo invisible bajo nuestros pies","og:description":"La distribuci\u00f3n geogr\u00e1fica de distintos tipos de suelos (o edafotaxa) en el paisaje se encuentra condicionada por sus factores formadores. En algunos casos, el relieve y la fisiograf\u00eda determinan que aparezcan unos determinados con mucha frecuencia. Dos situaciones concretas son dignas de rese\u00f1ar. La primera concierne a aquellos casos en donde la una abrupta pendiente","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2010-06-28T12:20:59+00:00","article:modified_time":"2010-06-28T17:12:23+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles. - Un Universo invisible bajo nuestros pies","twitter:description":"La distribuci\u00f3n geogr\u00e1fica de distintos tipos de suelos (o edafotaxa) en el paisaje se encuentra condicionada por sus factores formadores. En algunos casos, el relieve y la fisiograf\u00eda determinan que aparezcan unos determinados con mucha frecuencia. Dos situaciones concretas son dignas de rese\u00f1ar. La primera concierne a aquellos casos en donde la una abrupta pendiente","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136476","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:42:41","updated":"2026-05-26 16:16:50","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion\" title=\"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n\">P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSuelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion"},{"label":"Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles.","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136476"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=136476"}],"version-history":[{"count":9,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136476\/revisions"}],"predecessor-version":[{"id":136544,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136476\/revisions\/136544"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=136476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=136476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=136476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}