{"id":136908,"date":"2010-10-28T17:35:58","date_gmt":"2010-10-28T16:35:58","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=136908"},"modified":"2010-10-28T17:35:58","modified_gmt":"2010-10-28T16:35:58","slug":"regosoles-en-europa","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908","title":{"rendered":"Regosoles en Europa"},"content":{"rendered":"<p style=\"text-align: justify;\">Desde Pereira en Colombia (cadenas monta\u00f1osas andinas), tras miles de kil\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\u00ed vamos. \u00a0Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados\u00a0 (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/06\/136490\">Leptosoles<\/a> lo hacen en el <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/11\/136703\">sur del continente<\/a>. Estos cinco Edafotaxa llegan a cubrir alrededor del 5% de la edafosfera Europea. La raz\u00f3n estriba tanto en la mayor aridez clim\u00e1tica, como en el uso milenario antr\u00f3pico de los territorios que rodean la cuenca mediterr\u00e1nea y el mar negro. Por el contrario los tres primeros grupos de suelos de referencia conciernen a edafotaxa relacionados con el agua y en menor medida con la deposici\u00f3n de materiales arrastrados por el viento (erosi\u00f3n-deposici\u00f3n e\u00f3lica). De este modo, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/02\/14677\">el continente europeo muestra dos edafosferas<\/a> bien contrastadas, una al norte cuyo principal problema deviene del exceso de agua <a href=\"http:\/\/www.ensayistas.org\/critica\/ecologia\/diccionario\/pa.htm\">(paludificaci\u00f3n<\/a>) y otra cuyas penurias conciernen a su defecto. <strong><span style=\"color: #3366ff;\">La paludificaci\u00f3n ser\u00eda a los\u00a0ambientes h\u00famedos lo que la desertificaci\u00f3n lo es en los \u00e1ridos y semi\u00e1ridos<\/span><\/strong>.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/regosols-fuente-soils-of-the-eu-european-soil-buro.jpg\" alt=\"Regosoles Europa Fuente: European Soil Buro\" \/>\u00a0<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">Mapa de los Regosoles en Europa. Fuente: European Soil Buro<\/span><\/p>\n<p><strong>\u00a0<!--more--><\/strong><\/p>\n<p><strong><span style=\"color: #008080;\">Regosoles<\/span><\/strong><\/p>\n<p>El grupo de referencia de los Regosoles se supera la extensi\u00f3n de los 220,000 km<sup>2 <\/sup>en la Uni\u00f3n Europea (UE), siendo muy abundantes en la regi\u00f3n biogeogr\u00e1fica mediterr\u00e1nea y los Balcanes, no obstante aparecen en mayor o menor medida en todos o casi todos los pa\u00edses. A nivel de subunidades (segundo nivel de las WRB), tres de los cuatro tipos de suelos con que cuenta la EU, llegan a ocupar el 99% de este espacio geogr\u00e1fico, como podemos ver a continuaci\u00f3n:<\/p>\n<p><span style=\"color: #0000ff;\">Regosol Calc\u00e1rico (RGca) 70391 Km<sup>2<\/sup><\/span><\/p>\n<p><span style=\"color: #0000ff;\">Regosol D\u00edstrico (RGdy) 85733 Km<sup>2<\/sup><\/span><\/p>\n<p><span style=\"color: #0000ff;\">Regosol E\u00fatrico (RGeu) 63740 Km<sup>2<\/sup><\/span><\/p>\n<p><span style=\"color: #0000ff;\">Regosol H\u00e1plico (RGha) 2457 Km<sup>2<\/sup><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0Los <strong><span style=\"color: #3366ff;\">Regosoles calc\u00e1ricos<\/span> <\/strong>se esparcen por muchas regiones de la UE si bien se encuentran ausentes en Escandinavia.<strong> <\/strong>B\u00e9lgica, Holanda, Luxemburgo, Francia, Portugal y Polonia. En este sentido cabe se\u00f1alar que aunque el lavado de carbonatos es menor conforme aumenta la aridez, la mayor extensi\u00f3n de rocas calizas se concentra alrededor de la Cuenca Mediterr\u00e1nea como consecuencia de atesorar-padecer una tect\u00f3nica de placas muy activa (colisi\u00f3n entre Europa y \u00c1frica que tiene como resultado que a lo largo del tiempo sedimentos marinos ricos en carbonatos afloren a tierra asociados a los l\u00edmites de la placa continental emergida. Por el contrario los <strong><span style=\"color: #3366ff;\">Regosoles<\/span> <span style=\"color: #3366ff;\">d\u00edstricos<\/span><\/strong> se ubican esencialmente en amplias extensiones de Finlandia, Suecia, Portugal, Espa\u00f1a y B\u00e9lgica, Luxemburgo y Holanda. En este caso, la raz\u00f3n es la opuesta a la ya apuntada para los Regosoles Calc\u00e1ricos. Por ejemplo, en la Pen\u00ednsula Ib\u00e9rica, se asocian a las regiones cuya litolog\u00eda y tect\u00f3nica obedece a la presencia de cr\u00e1tones antiguos, en los que las rocas calizas se encuentran pr\u00e1cticamente ausentes. Tal hecho ocurre en el oeste de esta pen\u00ednsula, mientras que al este, se entra en el dominio de la orog\u00e9nesis alpina levantada por el choque de los continentes africano y europeo, en donde las rocas carbonatadas (margas, calizas, dolom\u00edas, etc.) dominan la geolog\u00eda regional. Por su parte, los<span style=\"color: #3366ff;\"> <strong>Regosoles E\u00fatricos<\/strong><\/span> se distribuyen al este de una l\u00ednea imaginaria que va desde el sureste de Madrid hasta Varsovia. Digamos que los materiales originarios que dan lugar a este tipo de edafotaxon son m\u00e1s variados. Finalmente, los <strong><span style=\"color: #3366ff;\">Regosoles H\u00e1plicos<\/span><\/strong> aparecen esencialmente en Chipre, Rep\u00fablica Checa y Francia, asociados a otros materiales geol\u00f3gicos diferentes y no asociados directamente con los m\u00e1s representativos dimanantes de la tect\u00f3nica de placas. Los<strong><span style=\"color: #3366ff;\"> Regosoles G\u00e9licos<\/span><\/strong>, tan solo aparecen, en los territorios de la UE, como end\u00e9micos en Escandinavia. La Leyenda Del Mapa de Suelos del Mundo de la FAO consideraba a algunos de los suelos poco evolucionados pero con un grueso horizonte A (superficial),\u00a0 rico en materia org\u00e1nica y oscuro como Regosoles \u00dambricos (FAO), Cambisoles h\u00famicos y Rankers (estos \u00faltimos sobre roca dura) (Umbrepts y Humitropepts de la USDA Soil Taxonomy). Tal terminolog\u00eda ha cambiado, y la presencia de un horizonte \u00fambrico y espeso excluye a los suelos que los atesoran de ser considerados como Regosoles.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #008080;\">Contesto Mundial de la distribuci\u00f3n de los Leptosoles<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Aunque ya tratamos este tema en un post precedente (ver relaci\u00f3n y enlaces al final del post), cabe se\u00f1alar que <strong>los Regosoles, como la mayor parte de los<\/strong> t\u00edpicos <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/10\/15\/46305\">suelos azonales<\/a>, s<strong>e presentan en todas los biomas, continentes y zonas biogeogr\u00e1ficas del mundo, excluyendo aquellas en los que se ubican los Criosuelos o Gelisuelos<\/strong> (suelos helados con permafrost). Resultan ser particularmente a<strong>bundantes en los tr\u00f3picos secos y \u00e1reas de monta\u00f1a<\/strong>. A nivel cartogr\u00e1fico son <strong>muy frecuentes, como inclusiones, en las asociaciones de suelos de los mapas a peque\u00f1a escala<\/strong> (poco detallados). En cualquier caso, debemos recordar que, en la pr\u00e1ctica, incluyen suelos que a dem\u00e1s de los t\u00edpicos ya descritos, no pueden encajar por su singularidad en otros grupos de referencia de la WRB (1998), por lo que este grupo de referencia es conocido como la \u201ccaja de Pandora\u201d. <strong>Son idiosincr\u00e1sicos de los paisajes erosionados, especialmente en los que acusan una mayor aridez<\/strong> (ya sufran altas o bajas temperaturas) y <strong>geolog\u00edas caracterizadas por la presencia de rocas blandas muy erosionables<\/strong>. Su escasa productividad aconseja utilizarlos para pastos, \u00a0reforestaci\u00f3n o permitir que crezca la vegetaci\u00f3n natural. Su puesta en cultivo tan solo es aconsejable si se dispone de riego, salvo excepciones que ya describimos en post precedentes. \u00a0<\/p>\n<p>\u00a0<strong><span style=\"color: #008080;\">Relaci\u00f3n con la nomenclatura de otras clasificaciones de suelos<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Los Regosoles corresponden, m\u00e1s o menos con los <strong>Entisoles<\/strong> de la USDA-Soil Taxonomy, los <strong>suelos esquel\u00e9ticos<\/strong> de la clasificaci\u00f3n australiana, los <strong>Rohb\u00f6den <\/strong>de la Alemana, as\u00ed como con los denominados suelos poco evolucionados regos\u00f3licos de Erosi\u00f3n de la Francesa.<\/p>\n<p>\u00a0<strong><span style=\"color: #339966;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez y Francisco Manr\u00edquez Cos\u00edo<\/span><\/strong><\/p>\n<p>\u00a0\u00a0<strong><span style=\"color: #008080;\">Material\u00a0 Bibliogr\u00e1fico<\/span><\/strong><\/p>\n<p>\u00a0<a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/esdb_archive\/eusoils_docs\/other\/EUR23439.pdf\">Soils of the European Union<\/a> (en Ingles)<\/p>\n<p>\u00a0<strong><span style=\"color: #008080;\">Post Previos y a Publicar en Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/06\/136490\">Leptosoles<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/13\/136682\">Leptosoles: Geograf\u00eda Ambiente y Paisaje<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/28\/136691\">Leptosoles Uso y Manejo<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/04\/136695\">Leptosoles en Latinoam\u00e9rica<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/11\/136703\">Leptosoles en Europa<\/a><\/p>\n<p>Tipos de Leptosoles y sus Mapas de Distribuci\u00f3n en Europa<\/p>\n<p>Regosoles<\/p>\n<p>Regosoles: Geograf\u00eda Ambiente y Paisaje<\/p>\n<p>Regosoles: Uso y Manejo<\/p>\n<p>Regosoles en Europa<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Desde Pereira en Colombia (cadenas monta\u00f1osas andinas), tras miles de kil\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\u00ed vamos. \u00a0Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados\u00a0 (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los Leptosoles lo hacen en el sur del continente. Estos cinco Edafotaxa llegan a cubrir alrededor del 5% de la edafosfera Europea. La raz\u00f3n estriba tanto en la mayor aridez clim\u00e1tica, como en el uso milenario antr\u00f3pico de los territorios que rodean la cuenca mediterr\u00e1nea y el mar negro. Por el contrario\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1929,1,604],"tags":[2173,46744,2172],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Desde Pereira en Colombia (cadenas monta\u00f1osas andinas), tras miles de kil\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\u00ed vamos. Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los Leptosoles lo hacen en el sur\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Regosoles en Europa - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Desde Pereira en Colombia (cadenas monta\u00f1osas andinas), tras miles de kil\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\u00ed vamos. Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los Leptosoles lo hacen en el sur\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-10-28T16:35:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-10-28T16:35:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Regosoles en Europa - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Desde Pereira en Colombia (cadenas monta\u00f1osas andinas), tras miles de kil\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\u00ed vamos. Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los Leptosoles lo hacen en el sur\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908#blogposting\",\"name\":\"Regosoles en Europa - Un Universo invisible bajo nuestros pies\",\"headline\":\"Regosoles en Europa\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/mapas-de-los-suelos-de-europa-wrb\\\/regosols-fuente-soils-of-the-eu-european-soil-buro.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908\\\/#articleImage\"},\"datePublished\":\"2010-10-28T17:35:58+01:00\",\"dateModified\":\"2010-10-28T17:35:58+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":34,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908#webpage\"},\"articleSection\":\"Curso B\\u00e1sico: Tipos de Suelos del Mundo, General, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, Cartograg\\u00eda de los Regosoles en Europa, geograf\\u00eda de suelos, Regosoles en Europa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908#listItem\",\"name\":\"Regosoles en Europa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908#listItem\",\"position\":3,\"name\":\"Regosoles en Europa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908\",\"name\":\"Regosoles en Europa - Un Universo invisible bajo nuestros pies\",\"description\":\"Desde Pereira en Colombia (cadenas monta\\u00f1osas andinas), tras miles de kil\\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\\u00ed vamos. Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los Leptosoles lo hacen en el sur\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/10\\\/28\\\/136908#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2010-10-28T17:35:58+01:00\",\"dateModified\":\"2010-10-28T17:35:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Regosoles en Europa - Un Universo invisible bajo nuestros pies","description":"Desde Pereira en Colombia (cadenas monta\u00f1osas andinas), tras miles de kil\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\u00ed vamos. Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los Leptosoles lo hacen en el sur","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908#blogposting","name":"Regosoles en Europa - Un Universo invisible bajo nuestros pies","headline":"Regosoles en Europa","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/regosols-fuente-soils-of-the-eu-european-soil-buro.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\/#articleImage"},"datePublished":"2010-10-28T17:35:58+01:00","dateModified":"2010-10-28T17:35:58+01:00","inLanguage":"es-ES","commentCount":34,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908#webpage"},"articleSection":"Curso B\u00e1sico: Tipos de Suelos del Mundo, General, Geograf\u00eda de Suelos y Megaedafolog\u00eda, Cartograg\u00eda de los Regosoles en Europa, geograf\u00eda de suelos, Regosoles en Europa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908#listItem","name":"Regosoles en Europa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908#listItem","position":3,"name":"Regosoles en Europa","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908","name":"Regosoles en Europa - Un Universo invisible bajo nuestros pies","description":"Desde Pereira en Colombia (cadenas monta\u00f1osas andinas), tras miles de kil\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\u00ed vamos. Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los Leptosoles lo hacen en el sur","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2010-10-28T17:35:58+01:00","dateModified":"2010-10-28T17:35:58+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Regosoles en Europa - Un Universo invisible bajo nuestros pies","og:description":"Desde Pereira en Colombia (cadenas monta\u00f1osas andinas), tras miles de kil\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\u00ed vamos. Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los Leptosoles lo hacen en el sur","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2010-10-28T16:35:58+00:00","article:modified_time":"2010-10-28T16:35:58+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Regosoles en Europa - Un Universo invisible bajo nuestros pies","twitter:description":"Desde Pereira en Colombia (cadenas monta\u00f1osas andinas), tras miles de kil\u00f3metros de viaje, seguimos en contacto con nuestros lectores. All\u00ed vamos. Mientras ciertos Grupos de Suelos de Referencia de la WRB poco evolucionados (Fluvisoles, Gleysoles y Arenosoles) se ubican preferentemente en el norte de Europa, los Regosoles, como los Leptosoles lo hacen en el sur","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136908","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 14:11:30","updated":"2026-05-26 16:26:49","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRegosoles en Europa\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general"},{"label":"Regosoles en Europa","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136908"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=136908"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136908\/revisions"}],"predecessor-version":[{"id":137317,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136908\/revisions\/137317"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=136908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=136908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=136908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}