{"id":136914,"date":"2010-08-15T11:02:56","date_gmt":"2010-08-15T10:02:56","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=136914"},"modified":"2010-08-15T18:06:44","modified_gmt":"2010-08-15T17:06:44","slug":"el-papel-de-la-heterodoxia-y-la-trasgresion-en-el-progreso-cientifico","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914","title":{"rendered":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico"},"content":{"rendered":"<p style=\"text-align: justify;\">El <span style=\"color: #3366ff;\"><strong>establishment<\/strong> <\/span>y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\u00f3n cient\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia,<strong> <span style=\"color: #3366ff;\">constituyen tanto la ortodoxia como la imagen de la ciencia<\/span><\/strong> en un momento dado. Se tratar\u00eda de lo que el fil\u00f3sofo <strong><span style=\"color: #3366ff;\">Thomas Kuhn, denominaba ciencia normal<\/span><\/strong>. Sus estudios consisten en profundizar y progresar, pero <strong><span style=\"color: #3366ff;\">r<\/span><span style=\"color: #3366ff;\">aramente dan lugar a cambios conceptuales de enorme importancia, esos que transforman el destino de una especialidad<\/span><\/strong>, a lo cual el mencionado fil\u00f3sofo denomina <strong><span style=\"color: #3366ff;\">cambios de paradigma<\/span><\/strong>. Su papel, en el fondo resulta ser bastante conservador.<strong> <span style=\"color: #3366ff;\">De vez en cuando, surgen heterodoxos, generalmente j\u00f3venes, que desaf\u00edan con conjeturas e hip\u00f3tesis las teor\u00edas que los denominados sacerdotes defienden tal perros de presa<\/span><\/strong><span style=\"color: #3366ff;\">. <strong>Comienza pues su \u201cv\u00eda crucis\u201d<\/strong><\/span>, de perseverar en su empe\u00f1o. Desdenes, descalificaciones, incredulidad por sus trabajos, etc., jalonar\u00e1n un destino que puede llevarlos a la fama o al fracaso. Por tanto, <span style=\"color: #3366ff;\"><strong>al margen de talento y buenas ideas, se necesita tenacidad y fortaleza de esp\u00edritu ante todo tipo de adversidades<\/strong><\/span> y aun de dejaciones. Obviamente, <strong><span style=\"color: #3366ff;\">los senderos de la ciencia se encuentran repletos de sus cad\u00e1veres<\/span><\/strong>. Sin embargo,<strong><span style=\"color: #3366ff;\"> la grandeza de la indagaci\u00f3n cient\u00edfica depende esencialmente de su genialidad y esp\u00edritu intr\u00e9pido<\/span><\/strong>.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/el-via-crucis-de-muchas-grandes-cientificos-fuente-absolutmexicopuntocom-iztapalapa.jpg\" alt=\"el-via-crucis-de-muchas-grandes-cientificos-fuente-absolutmexicopuntocom-iztapalapa\" width=\"430\" height=\"322\" \/>\u00a0<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/feeds.feedburner.com\/AbsolutMexico\">El V\u00eda Crucis de muchos grandes cient\u00edficos. Fuente: AbsolutMexico.com<\/a><\/p>\n<p>\u00a0<!--more--><\/p>\n<p style=\"text-align: justify;\">Personalmente<span style=\"color: #3366ff;\">, <strong>distingo tres tipos de investigadores<\/strong>: <strong>(i)<\/strong><\/span> los que una vez embarcados en las tareas cient\u00edficas realizan su trabajo con normalidad, siendo su m\u00e1xima ilusi\u00f3n alcanzar un d\u00eda una c\u00e1tedra, o alg\u00fan protagonismo de segunda fila;<strong> <span style=\"color: #3366ff;\">(ii)<\/span> <\/strong>aquellos que ocupan un lugar relevante en la ciencia normal, es decir los destinados a guiar y hacer progresar a las ciencias por las veredas trilladas, erigi\u00e9ndose en sus m\u00e1ximos exponentes y valedores;<strong> <span style=\"color: #3366ff;\">(iii)<\/span><\/strong> los intr\u00e9pidos heterodoxos, cuyo misi\u00f3n consiste en cambiar los destinos de la ciencia con ideas revolucionarias y provocadoras, si finalmente resultan ser ciertas. Sean sus propuestas acertadas o no, les espera un verdadero calvario.<span style=\"color: #3366ff;\"> <strong>Resulta l\u00f3gico, aunque no razonable, que los defensores del establishment les pongan todo tipo de zancadillas, por cuanto<\/strong><\/span> son los editores y \u00e1rbitros de las revistas en donde pretenden publicar sus provocativas ideas los transgresores. Tambi\u00e9n ser\u00e1n los que juzguen si son merecedores de financiaci\u00f3n para llevar a cabo sus proyectos. Y digo que resulta l\u00f3gico porque es humano (aunque poco \u201cobjetivo\u201d) que los que ostentan el poder intenten aferrarse al mismo, con vistas a evitar que sus ideas se consideren obsoletas.<strong> <span style=\"color: #3366ff;\">Y esta es la cruel realidad que salpica la sociolog\u00eda de la ciencia. Nadie regala nada a nadie<\/span><\/strong><span style=\"color: #3366ff;\">. <span style=\"color: #3366ff;\"><strong>M\u00e1s aun,<\/strong> <\/span><strong>los transgresores y\/o heterodoxos, comienzan a cruzar el desierto en absoluta soledad<\/strong><\/span>, en tanto que los ostentan el poder cuentan con hordas de al\u00e1teres encargadas de llevar a cabo el trabajo sucio con vistas a que sus popes les valoren m\u00e1s. Ya de por s\u00ed,<strong> <span style=\"color: #3366ff;\">son pocos los que se atreven a iniciar una lucha tan desigual<\/span><\/strong>: \u00a1David contra Goliat! <strong><span style=\"color: #3366ff;\">Pero si logran alcanzar el \u00e9xito, inscribir\u00e1n sus nombres con letras de oro en los anales de la ciencia<\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0Me he encontrado en numerosas ocasiones con colegas desmoralizados y\/o indignados porque sus \u201ctalentosas ideas\u201d no eran valoradas por nadie, recibiendo constantemente burlas y desdenes. Cuando escucho sus quejas, suelo replicar \u201cno hay otra v\u00eda: o luchas o te rindes, pero no esperes que nadie de de palmaditas en el hombro\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0Nos olvidamos pues, que <strong><span style=\"color: #008000;\">para triunfar en ciencia el talante es tan importante como el talento<\/span><\/strong>. Si el primero te permite desarrollar hip\u00f3tesis audaces, el segundo resulta casi siempre imprescindible a la hora de \u00a0imponerlas bajo la artiller\u00eda pesada de un enemigo, bien armado y numeroso. Quien se encuentre versado en historia de la ciencia dif\u00edcilmente podr\u00e1 discutir que mis argumentaciones son can\u00f3nicas, aunque <strong><span style=\"color: #3366ff;\">siempre se den excepciones que confirman la regla<\/span><\/strong>. Personalmente, decid\u00ed en su momento arrojarme al ruedo y ya se lo que se padece. Otra cuesti\u00f3n bien distinta es que mis ideas triunfen o terminen en el gigantesco ba\u00fal de los recuerdos. Siempre he defendido que<span style=\"color: #3366ff;\"> <strong>es hermoso intentarlo. Al fin y al cabo, si no lo consigues, tu destino es el de la mayor\u00eda, la mediocridad<\/strong><\/span>. Nada que perder salvo la imagen ante los colegas. Sin embargo, reitero que la soledad del exc\u00e9ntrico (nombre de un blog con el que me topo asiduamente en el ciberespacio) es dif\u00edcil de soportar, si no la asumes de antemano.<\/p>\n<p style=\"text-align: justify;\">\u00a0Pues bien, hace un par de d\u00edas, <strong><span style=\"color: #3366ff;\">Robert J. Lefkowitz<\/span><\/strong>, afamado investigador que decidi\u00f3, \u201cCruzar el Mar Muerto andando sobre sus aguas\u201d, <strong><span style=\"color: #3366ff;\">describ\u00eda as\u00ed su trayectoria vital<\/span><\/strong>. Su heterodoxia e intrepidez lleg\u00f3, en este caso, a buen puerto, por lo que se permite narrar la historia con mucha tranquilidad y cierta condescendencia, <strong><span style=\"color: #3366ff;\">fortuna que no atesoraron ni atesoran la inmensa mayor\u00eda de estos exploradores de tierras inc\u00f3gnitas<\/span><\/strong>. Empero<span style=\"color: #3366ff;\"> <strong>finalmente \u00e9l<\/strong><\/span> y sus posibles seguidores <strong><span style=\"color: #3366ff;\">alcanzan el establishment<\/span><\/strong>, ocupando el lugar de otros, a la espera de que aparezcan en el horizonte nuevos aventureros que amenacen su trono. <strong><span style=\"color: #3366ff;\">Y vuelta a empezar.\u00a0 La irrazonable racionalidad de la ciencia<\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0Lamentablemente en el pasado, <strong><span style=\"color: #3366ff;\">muchos h\u00e9roes de la ciencia actual fallecieron (o se suicidaron), no pudiendo ver culminado su \u00e9xito<\/span><\/strong>. Actualmente se suelen soslayar sus desventuras, salvo en las buenas biograf\u00edas. La siguiente pintura de cuenta de su destino.<\/p>\n<p style=\"text-align: center;\">\u00a0\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/viacrucis-fuente-blog-pintura-religiosa-de-fernan-sator.jpg\" alt=\"viacrucis-fuente-blog-pintura-religiosa-de-fernan-sator\" width=\"400\" height=\"514\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/artereligioso.blogspot.es\/rss2.xml\">Pintura Religiosa. Fuente: Blog Pintura Religiosa de Fernan Sator<\/a>.<\/p>\n<p>\u00a0<strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez\u00a0\u00a0\u00a0 \u00a0\u00a0<\/span><\/strong><\/p>\n<p>\u00a0\u00a0<\/p>\n<p align=\"center\"><strong><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=44961\">Lograremos que los enfermos no se hagan resistentes a sus medicinas<\/a><\/strong><\/p>\n<p>\u00a0<strong>Entrevista a Robert J. Lefkowitz<\/strong>, investigador del <a href=\"http:\/\/www.hhmi.org\/\" target=\"_blank\">Howard Hughes Institute<\/a> (EE.UU.) que <strong>encontr\u00f3 la \u00abcerradura\u00bb celular en la que encajan m\u00e1s de la mitad de los medicamentos actuales. Su pr\u00f3ximo reto<\/strong>: f\u00e1rmacos m\u00e1s eficaces sin efectos secundarios.<\/p>\n<p>\u00a0FUENTE | <a href=\"http:\/\/www.abc.es\/\" target=\"_blank\">ABC Peri\u00f3dico Electr\u00f3nico S.A.<\/a> 13\/08\/2010<\/p>\n<p>\u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\">El nombre de <strong>Robert J. Lefkowitz<\/strong> (Nueva York, 1943) se ha convertido en<strong> un cl\u00e1sico en las quinielas de posibles premios N\u00f3bel. Su candidatura no ha prosperado aunque sus investigaciones han impactado en casi todos los campos de la medicina<\/strong>. De <strong>su trabajo<\/strong> en el laboratorio ha salido una <strong>interminable lista de medicamentos que combaten enfermedades tan comunes como<\/strong> la hipertensi\u00f3n, las alergias, la depresi\u00f3n o el dolor. <strong>La clave de su \u00e9xito est\u00e1 en el descubrimiento de unos receptores que utilizan los f\u00e1rmacos y las hormonas como puerta de entrada a las c\u00e9lulas<\/strong>. El jurado del premio de la Fundaci\u00f3n BBVA \u00abFronteras del Conocimiento\u00bb no dud\u00f3 este a\u00f1o en reconocer su trayectoria.<br \/>\nPregunta. <strong>Al principio pocos apostaban por su teor\u00eda. \u00bfLo suyo fue una carrera en solitario?<\/strong><\/p>\n<p style=\"text-align: justify;\">Respuesta. <strong>Cuando empec\u00e9 mi investigaci\u00f3n en la d\u00e9cada de los 70 mucha gente no cre\u00eda que los receptores existiesen. Yo no estaba solo con mi teor\u00eda, pero estaba claro que hab\u00eda ciertas reticencias. Por aquel entonces era muy joven,<\/strong> apenas ten\u00eda 30 a\u00f1os<strong> y<\/strong> era <strong>arrogante<\/strong>. T<strong>en\u00eda ese deseo de poner en tela de juicio las creencias y desafiarlas<\/strong>. <strong>Si entonces hubiera sabido lo dif\u00edcil que era lograrlo, no hubiera tenido el coraje de emprender la tarea<\/strong>.<br \/>\nP. \u00bfSin j\u00f3venes cient\u00edficos que desaf\u00eden al resto de la comunidad no hay avance?<\/p>\n<p style=\"text-align: justify;\">R. Cierto.<strong> Cuanto m\u00e1s experimentado soy, m\u00e1s cerca estoy del \u00abestablishment\u00bb y menos dispuesto a imponerles mis ideas. El cient\u00edfico m\u00e1s innovador es siempre el m\u00e1s joven<\/strong>.<br \/>\nP. Su primer flechazo fue la cardiolog\u00eda, \u00bfc\u00f3mo pas\u00f3 de la consulta al laboratorio?<br \/>\nR. Mi objetivo era ser m\u00e9dico. S\u00f3lo despu\u00e9s de terminar la residencia tuve la oportunidad de entrar en el <a href=\"http:\/\/www.nih.gov\/\" target=\"_blank\">NIH<\/a> (Institutos Nacionales de Investigaci\u00f3n de EE.UU) y empezar a investigar. Entonces no pensaba que ser\u00eda el objetivo central de mi carrera. Sin embargo, <strong>una vez que haces un descubrimiento y experimentas esa emoci\u00f3n es como una droga. Me enganch\u00e9 al descubrimiento<\/strong>.<\/p>\n<p style=\"text-align: justify;\">P. <strong>\u00bfY sigue tan enganchado?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Claro. <strong>Como cualquier adicto necesito cada vez m\u00e1s dosis<\/strong>.<\/p>\n<p style=\"text-align: justify;\">P. <strong>Ahora busca f\u00f3rmulas que eviten que los medicamentos pierdan su efecto y generen resistencia. \u00bfEstamos cerca de encontrar la f\u00f3rmula?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. <strong>S\u00ed, creo que ser\u00e1 posible<\/strong>. Lograremos que los enfermos no se hagan resistentes a los f\u00e1rmacos, <strong>pero es un gran reto. Esto implica trabajar con uno de los mecanismos fundamentales incorporados a las propias c\u00e9lulas: la homeostasis.<\/strong> Este mecanismo permite que las c\u00e9lulas vuelvan a su estado original cuando est\u00e1n sometidas a la presencia de un est\u00edmulo. Si estimulas una c\u00e9lula con un f\u00e1rmaco, la c\u00e9lula buscar\u00e1 la f\u00f3rmula de resistirse y retornar a la situaci\u00f3n que ten\u00eda antes de ser estimulada. Una gran parte de mi investigaci\u00f3n se basa en comprender los mecanismos mediante los cuales esa desensibilizaci\u00f3n tiene lugar y hemos encontrado las rutas que les lleva a dejar de responder a los medicamentos actuales. Ahora es posible empezar a interrumpir estos mecanismos.<br \/>\nP. \u00bfTendr\u00e1 una aplicaci\u00f3n generalizada?<\/p>\n<p style=\"text-align: justify;\">R. Tendr\u00e1 un efecto muy general sobre todos los f\u00e1rmacos que interact\u00faan con los receptores que yo he estudiado. Como \u00e9stos act\u00faan sobre la mitad o m\u00e1s de todos los medicamentos ser\u00e1 una estrategia aplicable a nivel general.<\/p>\n<p style=\"text-align: justify;\">P. Se <strong>acaban de cumplir diez a\u00f1os del genoma humano. \u00bfHemos progresado a un buen ritmo o ha habido m\u00e1s promesas que avances?<\/strong><br \/>\nR. Creo que la velocidad ha sido la adecuada. <strong>Lo que no era razonable eran las expectativas<\/strong>, lo <strong>que algunos cient\u00edficos<\/strong> que eran responsables de la secuenciaci\u00f3n del genoma <strong>generaron<\/strong> como expectativas. Yo creo que <strong>presentaron esperanzas no realistas sobre los beneficios que se podr\u00edan obtener<\/strong>. Por eso <strong>ahora tenemos cierta sensaci\u00f3n de fracaso. Las expectativas estaban infladas<\/strong>.<br \/>\nP. Por eso se dice que <strong>Craig Venter, \u00abpadre\u00bb del genoma y<\/strong> creador de la primera c\u00e9lula artificial, es un gran hombre de negocios. \u00bfC\u00f3mo le ve?<\/p>\n<p style=\"text-align: justify;\">R<strong>. Craig Venter<\/strong> es un buen amigo m\u00edo. Nos conocemos desde hace d\u00e9cadas. Le voy a contar una an\u00e9cdota. Cada vez que da una conferencia, si yo estoy presente entre el p\u00fablico, suele se\u00f1alarme y decir que me debe su \u00e9xito en el genoma. En los 80 \u00e9l tambi\u00e9n trabajaba en el campo de los receptores y lo dej\u00f3 despu\u00e9s de mi descubrimiento. Le venc\u00ed y busc\u00f3 otro campo de investigaci\u00f3n, por eso dice que me debe su \u00e9xito. Una vez le pregunt\u00e9 que por qu\u00e9 no compart\u00eda las ganancias del genoma conmigo. Pero no, <strong>\u00e9l no comparte beneficios<\/strong> (risas).<br \/>\nP. Pues ya que no comparten beneficios insisto: \u00bf<strong>Qu\u00e9 pesa m\u00e1s en Venter su ciencia o su marketing?<\/strong><\/p>\n<p style=\"text-align: justify;\">R. Creo que <strong>es un excelente hombre de negocios<\/strong>, est\u00e1 claro.<strong> Pero tambi\u00e9n<\/strong> que es <strong>un aut\u00e9ntico visionario<\/strong>. Ve objetivos fundamentales y se rodea de los mejores. Ah\u00ed reside su \u00e9xito.<br \/>\n<strong>Autor: \u00a0 Nuria Ram\u00edrez de Castro <\/strong><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>El establishment y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\u00f3n cient\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia, constituyen tanto la ortodoxia como la imagen de la ciencia en un momento dado. Se tratar\u00eda de lo que el fil\u00f3sofo Thomas Kuhn, denominaba ciencia normal. Sus estudios consisten en profundizar y progresar, pero raramente dan lugar a cambios conceptuales de enorme importancia, esos que transforman el destino de una especialidad, a lo cual el mencionado fil\u00f3sofo denomina cambios de paradigma. Su papel, en el fondo resulta ser bastante\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[609,1,606],"tags":[2174,2175],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El establishment y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\u00f3n cient\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia, constituyen tanto la ortodoxia como la imagen de la ciencia en un momento dado. Se tratar\u00eda de lo que el fil\u00f3sofo Thomas Kuhn, denominaba\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"El establishment y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\u00f3n cient\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia, constituyen tanto la ortodoxia como la imagen de la ciencia en un momento dado. Se tratar\u00eda de lo que el fil\u00f3sofo Thomas Kuhn, denominaba\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-08-15T10:02:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-08-15T17:06:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El establishment y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\u00f3n cient\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia, constituyen tanto la ortodoxia como la imagen de la ciencia en un momento dado. Se tratar\u00eda de lo que el fil\u00f3sofo Thomas Kuhn, denominaba\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914#blogposting\",\"name\":\"El papel de la Heterodoxia y la Trasgresi\\u00f3n en el Progreso Cient\\u00edfico - Un Universo invisible bajo nuestros pies\",\"headline\":\"El papel de la Heterodoxia y la Trasgresi\\u00f3n en el Progreso Cient\\u00edfico\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/159\\\/el-via-crucis-de-muchas-grandes-cientificos-fuente-absolutmexicopuntocom-iztapalapa.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914\\\/#articleImage\"},\"datePublished\":\"2010-08-15T11:02:56+01:00\",\"dateModified\":\"2010-08-15T18:06:44+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914#webpage\"},\"articleSection\":\"Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, General, Prensa y Pol\\u00edtica Cient\\u00edfica, Prograso de la ciencia y heterodoxia, trangresi\\u00f3n en ciencia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914#listItem\",\"name\":\"El papel de la Heterodoxia y la Trasgresi\\u00f3n en el Progreso Cient\\u00edfico\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914#listItem\",\"position\":3,\"name\":\"El papel de la Heterodoxia y la Trasgresi\\u00f3n en el Progreso Cient\\u00edfico\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914\",\"name\":\"El papel de la Heterodoxia y la Trasgresi\\u00f3n en el Progreso Cient\\u00edfico - Un Universo invisible bajo nuestros pies\",\"description\":\"El establishment y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\\u00f3n cient\\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia, constituyen tanto la ortodoxia como la imagen de la ciencia en un momento dado. Se tratar\\u00eda de lo que el fil\\u00f3sofo Thomas Kuhn, denominaba\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/08\\\/15\\\/136914#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2010-08-15T11:02:56+01:00\",\"dateModified\":\"2010-08-15T18:06:44+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico - Un Universo invisible bajo nuestros pies","description":"El establishment y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\u00f3n cient\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia, constituyen tanto la ortodoxia como la imagen de la ciencia en un momento dado. Se tratar\u00eda de lo que el fil\u00f3sofo Thomas Kuhn, denominaba","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914#blogposting","name":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico - Un Universo invisible bajo nuestros pies","headline":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/el-via-crucis-de-muchas-grandes-cientificos-fuente-absolutmexicopuntocom-iztapalapa.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914\/#articleImage"},"datePublished":"2010-08-15T11:02:56+01:00","dateModified":"2010-08-15T18:06:44+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914#webpage"},"articleSection":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, General, Prensa y Pol\u00edtica Cient\u00edfica, Prograso de la ciencia y heterodoxia, trangresi\u00f3n en ciencia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914#listItem","name":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914#listItem","position":3,"name":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914","name":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico - Un Universo invisible bajo nuestros pies","description":"El establishment y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\u00f3n cient\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia, constituyen tanto la ortodoxia como la imagen de la ciencia en un momento dado. Se tratar\u00eda de lo que el fil\u00f3sofo Thomas Kuhn, denominaba","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2010-08-15T11:02:56+01:00","dateModified":"2010-08-15T18:06:44+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico - Un Universo invisible bajo nuestros pies","og:description":"El establishment y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\u00f3n cient\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia, constituyen tanto la ortodoxia como la imagen de la ciencia en un momento dado. Se tratar\u00eda de lo que el fil\u00f3sofo Thomas Kuhn, denominaba","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2010-08-15T10:02:56+00:00","article:modified_time":"2010-08-15T17:06:44+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico - Un Universo invisible bajo nuestros pies","twitter:description":"El establishment y aquellos que trabajan en sus equipos, avanzan por los senderos de la indagaci\u00f3n cient\u00edfica que ellos, u otros antes que ellos, los surcaron por primera vez. En consecuencia, constituyen tanto la ortodoxia como la imagen de la ciencia en un momento dado. Se tratar\u00eda de lo que el fil\u00f3sofo Thomas Kuhn, denominaba","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136914","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:44:57","updated":"2026-05-26 16:20:09","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general"},{"label":"El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136914"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=136914"}],"version-history":[{"count":14,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136914\/revisions"}],"predecessor-version":[{"id":136928,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136914\/revisions\/136928"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=136914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=136914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=136914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}