{"id":136982,"date":"2010-09-04T18:07:42","date_gmt":"2010-09-04T17:07:42","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=136982"},"modified":"2010-09-06T10:02:09","modified_gmt":"2010-09-06T09:02:09","slug":"los-cientificos-la-religion-la-prensa-y-el-marketing","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982","title":{"rendered":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing"},"content":{"rendered":"<p style=\"TEXT-ALIGN: justify\">A L. Rivas Lado, en un articulo publicado el a\u00f1o 2001 (revista \u00c1gora), nos recordaba un fragmento archiconocido en la historia\u00a0 de la ciencia. \u201c<strong><span style=\"color: #3366ff;\">Laplace, ante la pregunta de Napole\u00f3n de porqu\u00e9 en su \u201cMec\u00e1nica Celeste\u201d no aparece el nombre de Dios: \u201cSire, je n\u2019avais pas besoin de cette hypoth\u00e8se<\/span><\/strong>\u201d. Es decir en ciencia la causaci\u00f3n divina es incuestionablemente \u201c<a href=\"http:\/\/dspace.usc.es\/bitstream\/10347\/1195\/1\/pg_185-216_agora20-2.pdf\">una hip\u00f3tesis innecesaria<\/a>\u201d. El revuelo montado por los \u00faltimos comentarios vertidos en su nuevo libro por \u00a0<a href=\"http:\/\/www.elpais.com\/todo-sobre\/persona\/Stephen\/William\/Hawking\/6568\/\">Stephen Hawking<\/a>, resulta est\u00fapido y contraproducente. Debemos recordar que una cuesti\u00f3n es la <a href=\"http:\/\/buscon.rae.es\/draeI\/SrvltGUIBusUsual\">ciencia<\/a>, otra la <a href=\"http:\/\/buscon.rae.es\/draeI\/SrvltGUIBusUsual\">epistemolog\u00eda<\/a>, otra la<a href=\"http:\/\/buscon.rae.es\/draeI\/SrvltConsulta?TIPO_BUS=3&amp;LEMA=ontolog\u00eda\"> ontolog\u00eda<\/a> y otra la<a href=\"http:\/\/buscon.rae.es\/draeI\/SrvltGUIBusUsual\"> teolog\u00eda<\/a> (buscar en la RAE). Por tanto, si las dos primeras se encuentran relacionadas entre si, como tambi\u00e9n lo est\u00e1n la tercera y la cuarta\u201d, generar controversias entre ambos planos del acervo cultural humano,\u00a0actualmente inconmensurables, deviene en mezclar churras y merinas, como defienden ciertas autoridades eclesi\u00e1sticas. De aqu\u00ed que encabezar un post apelando a frases de la siguiente g\u00fcisa: \u201c<a title=\"Enlace permanente: Existencia de Dios en entredicho\" href=\"http:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2010\/09\/04\/131631\">Existencia de Dios en entredicho<\/a>\u201d se me antoja contraproducente para los intereses de la ciencia.\u00a0!Tirar piedras contra tu propio tejado!. Y como esta vez s\u00ed, acertadamente apunta <a href=\"http:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/feed\">JAL en su blog<\/a>: <em>Su nuevo libro \u201c<a href=\"http:\/\/www.elsemanaldigital.com\/blog.asp?idarticulo=109265\">The Grand Design<\/a>\u201d (El Gran Dise\u00f1o, en cristiano, nunca mejor dicho), escrito junto al f\u00edsico <a href=\"http:\/\/en.wikipedia.org\/wiki\/Leonard_Mlodinow\">Leonard Mlodinow<\/a>, y que saldr\u00e1 al p\u00fablico en breve, no ha podido tener mejor pre-estreno que las pol\u00e9micas declaraciones de los autores sobre la plausible NO existencia de Dios. <span style=\"color: #3366ff;\"><strong>Esto es publicidad gratuita y lo dem\u00e1s son tonter\u00edas<\/strong>\u2026\u00bb <\/span><\/em>Sin embargo, debemos discrepar de JAL en que\u00a0 <a href=\"http:\/\/www.elpais.com\/todo-sobre\/persona\/Stephen\/William\/Hawking\/6568\/\">Stephen Hawking<\/a> ha cambiado de opini\u00f3n. Del mismo modo no\u00a0existe <strong><span style=\"color: #3366ff;\">novedad alguna en las opiniones recientes de este f\u00edsico, por cuanto son tan antiguas como la propia ciencia contempor\u00e1nea<\/span><\/strong> (<a href=\"http:\/\/es.wikipedia.org\/wiki\/Pierre_Simon_Laplace\">hablamos de Pierre Simon Laplace<\/a>). Levantar <strong><span style=\"color: #3366ff;\">pol\u00e9micas<\/span><\/strong> de esta catadura, <strong><span style=\"color: #3366ff;\">como estrategia de marketing<\/span><\/strong>, justamente d\u00edas antes de que el m\u00e1ximo exponente de la Iglesia Cat\u00f3lica viaje a Londres, parece <span style=\"color: #3366ff;\"><strong>a todas luces inoportuno<\/strong>. <strong>La prensa ha aportado su granito de arena<\/strong><\/span> con vistas a vender m\u00e1s ejemplares, gener\u00e1ndose as\u00ed <strong><span style=\"color: #3366ff;\">un nuevo episodio de conflicto entre Iglesia y \u201cciertos sectores cient\u00edficos\u201d<\/span><\/strong> que, lo quieran o no, <strong><span style=\"color: #3366ff;\">se desacreditan as\u00ed mismos<\/span><\/strong>, a la hora de quejarse de los comportamientos \u201canticient\u00edficos\u201d de los representantes y creyentes de casi todas las religiones.<\/p>\n<p align=\"center\">\u00a0<\/p>\n<p style=\"TEXT-ALIGN: center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/imagenes-del-cosmos-desde-el-telescopio-hubble.jpg\" alt=\"imagenes-del-cosmos-desde-el-telescopio-hubble\" \/>\u00a0<\/p>\n<p style=\"TEXT-ALIGN: center\"><span style=\"color: #0000ff;\">Una Imagen del Cosmos desde el Telescopio Hubble<\/span><\/p>\n<p style=\"TEXT-ALIGN: center\"><span style=\"color: #0000ff;\"><!--more--><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0Vaya por delante que soy agn\u00f3stico (se me invit\u00f3 \u201cliteralmente\u201d a abandonar el seno de la Iglesia Cat\u00f3lica por defender la interrupci\u00f3n del embarazo y el divorcio a mis 17 a\u00f1os, es decir all\u00e1 por 1972), as\u00ed como que <strong><span style=\"color: #3366ff;\">detesto todos los fundamentalismos religiosos<\/span><\/strong>. Ahora bien: \u201cno se puede ser m\u00e1s papista que el Papa\u201d, ya que \u201c<strong><span style=\"color: #3366ff;\">el que siembra vientos cosecha tempestades<\/span><\/strong>\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0Y todo apunta que <strong><span style=\"color: #3366ff;\">han sido justamente los responsables del marketing del nuevo libro, y la propia prensa los que han puesto tanto la mecha como el detonante<\/span><\/strong>, al que se han unido a la postre, con regocijo, ciertos cient\u00edficos.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #3366ff;\">Desde que el hombre es hombre<\/span><\/strong>, ya sea por necesidad, angustia, o a saber\u2026.., <span style=\"color: #3366ff;\"><strong>todos los pueblos han erigido sus propias religiones y deidades<\/strong>. <strong>Mutatis mutandis, todo apunta a que se trata de una irrefrenable propensi\u00f3n inherente a la condici\u00f3n humana<\/strong><\/span>. Discrepe uno o no,<span style=\"color: #3366ff;\"> <strong>\u201clas creencias son creencias\u201d y la ciencia es ciencia\u201d<\/strong>. <strong>No son miscibles<\/strong><\/span>. Se trata de dos planos claramente<span style=\"color: #3366ff;\"> <strong>diferenciados e inconexos del acervo cultural humano<\/strong><\/span>. <strong><span style=\"color: #3366ff;\">Por lo tanto, estas guerras de guerrillas, no propician una cohabitaci\u00f3n relativamente pac\u00edfica<\/span><\/strong><strong> <\/strong>(siempre habr\u00e1 disensiones), que resulta<span style=\"color: #3366ff;\"> <strong>beneficiosa para la propia actividad investigadora<\/strong><\/span>. Y como se trata de dos aspectos que<span style=\"color: #3366ff;\"> <strong>no se relacionan entre si por nexo l\u00f3gico alguno<\/strong><\/span>, deviene rid\u00edculo que los muchos cient\u00edficos entren al saco. Habr\u00eda que recordar que muchos investigadores profesan su propia fe en alguna religi\u00f3n y est\u00e1n en todo su derecho. Por lo tanto, este tipo de altercados, les puede situar en posiciones muy inc\u00f3modas en muchas culturas (incluso en la nuestra).<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #3366ff;\">La ciencia<\/span><\/strong> se construye d\u00eda a d\u00eda, y por definici\u00f3n consiste en construir y corroborar teor\u00edas, que en su d\u00eda ser\u00e1n refutadas y reemplazadas por otras con mayor poder predictivo. Por lo tanto, en t\u00e9rminos generales,<span style=\"color: #3366ff;\"> <strong>las verdades cient\u00edficas son ef\u00edmeras<\/strong><\/span>, ya que de no ser as\u00ed su propia esencia se desvanecer\u00eda, para convertirse en un nuevo tipo de religi\u00f3n (y algunos parecen haberse puesto tal meta). Por su parte,<span style=\"color: #3366ff;\"> <strong>las creencias, colectivas o individuales, no son demostrables ni indemostrables, sino actos de fe<\/strong><\/span>. Para las religiones sus creencias son<span style=\"color: #3366ff;\"> <strong>inmutables<\/strong><\/span>. Empero como hablamos de <strong><span style=\"color: #3366ff;\">cosas distintas, jam\u00e1s deber\u00edan mezclarse<\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0Es comprensible que ciertos cient\u00edficos ateos o agn\u00f3sticos, se encuentren crispados cuando, desde muchas religiones, se les criminaliza al entender sus seguidores que la investigaci\u00f3n viola la voluntad de sus dioses (caso del uso de embriones humanos en biomedicina). Se trata de un tipo de debates agrios que, por su esencia resultan dif\u00edciles de soslayar. Empero <strong><span style=\"color: #3366ff;\">si los investigadores hacen gala de su cacareado \u201cesp\u00edritu\u201d objetivo, deber\u00edan dar lecciones de tolerancia<\/span><\/strong>, no atizar la hoguera, es decir <strong><span style=\"color: #3366ff;\">vestirse de fundamentalistas<\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0Ya que <strong><span style=\"color: #3366ff;\">la religiosidad es inherente a la esencia humana<\/span><\/strong> (recordemos por ejemplo que aproximadamente el 50% de los senadores de USA se han declarado creacionistas) y dif\u00edcilmente cambiar\u00e1n las cosas (al menos a medio y largo plazo), enfurecer a personas en cuyos destinos recala o recalar\u00e1 (seg\u00fan pa\u00edses) la financiaci\u00f3n cient\u00edfica, me parece una actitud poco inteligente. Del mismo modo,<span style=\"color: #3366ff;\"> <strong>tan solo una peque\u00f1a parte de la poblaci\u00f3n mundial entiende en que consiste la indagaci\u00f3n cient\u00edfica, mientras que la inmensa mayor\u00eda profesan alg\u00fan tipo de fe<\/strong><\/span>. Hablamos pues de <strong><span style=\"color: #3366ff;\">mayor\u00edas y de minor\u00edas<\/span><\/strong>. \u00bfNos entendemos? Que cada uno extraiga sus\u00a0 propias conclusiones.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\">\u00a0<strong>Cuando<\/strong><\/span> <a href=\"http:\/\/www.elpais.com\/todo-sobre\/persona\/Stephen\/William\/Hawking\/6568\/\">Stephen Hawking<\/a> <strong><span style=\"color: #3366ff;\">intent\u00f3 predecir el futuro de la f\u00edsica patin\u00f3 estrepitosamente<\/span><\/strong> (la f\u00edsica tal cual la conocemos desaparecer\u00e1 en el a\u00f1o 2000 tras explicar, todo lo explicable). Me re\u00ed mucho ya al leer sus devaneos como <a href=\"http:\/\/es.wikipedia.org\/wiki\/Nostradamus\">Nostradamus<\/a>. Y esto a pesar de que los<strong> <span style=\"color: #3366ff;\">investigadores brillantes<\/span><\/strong> deben ser escuchados seriamente cuando hablan de sus respectivas disciplinas. Ahora bien, <strong><span style=\"color: #3366ff;\">cuando se les interpela sobre otros aspectos de la cultura humana debe entenderse que sus posiciones no tienen la menor relevancia en la mayor\u00eda de los casos<\/span><\/strong>, por cuanto nos equivocamos con harta frecuencia. Y ahora, nuestro querido <strong><span style=\"color: #3366ff;\">Stephen, tambi\u00e9n anda preocupado porque teme una actitud hostil de los posibles extraterrestres que \u201cquiz\u00e1s alg\u00fan d\u00eda\u201d aterricen por estos lares<\/span><\/strong>, tema que por su calado, no me permitir\u00e1 dormir esta noche. Luego apunta que el futuro de la humanidad se encuentra en el espacio. No lo dudo, o quiz\u00e1s s\u00ed, ya que mucho tienen que correr ciencia y\u00a0tecnolog\u00eda con vistas a permitirnos emigrar a \u201cotros posibles y accesibles mundos felices\u201d antes de que terminemos por devastar el nuestro.\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0Me resulta parad\u00f3jico que a una persona como yo, que no lee la Biblia desde que era ni\u00f1o, le venga a la mente en estos momentos un pasaje de las \u201cNuevas Escrituras\u201d. Me refiero de ese que se\u00f1ala que\u00a0 <strong><span style=\"color: #3366ff;\">Jesucristo<\/span><\/strong> aleg\u00f3 en una situaci\u00f3n \u201crelativamente equiparable\u201d: <strong><span style=\"color: #3366ff;\">\u201cdar al Cesar lo que es del Cesar (l\u00e9ase aqu\u00ed la ciencia) y a Dios lo que es de Dios\u201d<\/span><\/strong> (crea o no usted en \u00e9l, dado que la ciencia no tiene absolutamente nada que decir al respecto).<\/p>\n<p style=\"text-align: justify;\">\u00a0Pero<span style=\"color: #3366ff;\"> <strong>lo m\u00e1s lamentable de todos estos sucesos deriva de que por vender m\u00e1s libros y algunos ejemplares m\u00e1s de peri\u00f3dicos, la sociedad se encuentre ante otra nueva pol\u00e9mica de esta caladura<\/strong><\/span>. Recordemos que los \u201cTextos Sagrados\u201d pueden ser interpretados de m\u00faltiples formas. No son las religiones en su mismas el n\u00facleo de las pasadas y actuales fricciones, sino como dictan que deben ser entendidas, seg\u00fan la opini\u00f3n de sus \u201clegisladores\u201d. No es necesario ofrecer ejemplos \u00bfverdad? Quien ostenta el poder impone la ley. \u00a1cuidado!.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #3366ff;\">Dudo que el nuevo libro de<\/span><\/strong> <a href=\"http:\/\/www.elpais.com\/todo-sobre\/persona\/Stephen\/William\/Hawking\/6568\/\">Stephen Hawking<\/a><strong> <span style=\"color: #3366ff;\">sea el problema<\/span><\/strong>. M\u00e1s aun, se encuentra con todo el derecho de escribir sus ideas y \u201ccreencias\u201d. Ahora bien, todo depender\u00e1 de que trate a unas y a otras por igual, o que separe debidamente las \u201cactuales verdades cient\u00edficas\u201d de sus creencias personales. Ya dio fe en su anterior monograf\u00eda de que su \u201cbola de cristal\u201d no le funcion\u00f3 ni en su propia especialidad (como nos ocurrir\u00eda al 99,99% de los investigadores).\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #3366ff;\">No es la primera vez que la comunidad cient\u00edfica<\/span><\/strong> (y en espacial algunos cosm\u00f3logos) <strong><span style=\"color: #3366ff;\">se desliza indebidamente por caminos escabrosos<\/span><\/strong>, como tratamos en nuestro post: \u201c<a title=\"Enlace permanente: Ciencia, Religi\u00f3n y Filosof\u00eda: Evoluci\u00f3n, Creacionismo, Teor\u00eda del Dise\u00f1o Inteligente y las Elucubraciones de Cient\u00edficos y Fil\u00f3sofos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/08\/80527\">Ciencia, Religi\u00f3n y Filosof\u00eda: Evoluci\u00f3n, Creacionismo, Teor\u00eda del Dise\u00f1o Inteligente y las Elucubraciones de Cient\u00edficos y Fil\u00f3sofos<\/a>\u201d.<span style=\"color: #3366ff;\"> <strong>Debi\u00e9ramos evitar este tipo totalmente innecesario de fricciones<\/strong><\/span> entre poderes que, si no logran cohabitar, pueden hacernos desembocar en un futuro muy sombr\u00edo para toda la humanidad, totalmente distinto del que el inefable Stephen tiene en mente (ver noticias que abajo reproducimos).\u00a0 \u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/strong><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0<\/p>\n<h3><a href=\"http:\/\/www.elpais.com\/articulo\/sociedad\/Dios\/creo\/Universo\/afirma\/Stephen\/Hawking\/elpepusoc\/20100902elpepusoc_6\/Tes\">Dios no cre\u00f3 el Universo, afirma Stephen Hawking<\/a><\/h3>\n<p>\u00a0El cient\u00edfico brit\u00e1nico explica en un libro que el Big Bang es una consecuencia inevitable de las leyes de la f\u00edsica<\/p>\n<p><strong>Diario ABC: REUTERS &#8211; Londres<\/strong> &#8211; 02\/09\/2010<\/p>\n<p>\u00a0El cient\u00edfico brit\u00e1nico <a href=\"http:\/\/www.elpais.com\/todo-sobre\/persona\/Stephen\/William\/Hawking\/6568\/\">Stephen Hawking<\/a> afirma en su nuevo libro, The Grand Design (El Magn\u00edfico Dise\u00f1o), que el Big Bang fue una consecuencia inevitable de las leyes de la f\u00edsica, que Dios no cre\u00f3 el Universo y que las teor\u00edas cient\u00edficas m\u00e1s actuales convierten en redundante la figura de un creador. El libro, del que el peri\u00f3dico brit\u00e1nico <a href=\"http:\/\/www.thetimes.co.uk\/tto\/news\/\" target=\"_blank\">The Times<\/a> adelanta hoy algunos extractos, se\u00f1ala: \u00abDado que existe una ley como la de la gravedad, el Universo pudo crearse a s\u00ed mismo -y de hecho lo hizo- de la nada. La creaci\u00f3n espont\u00e1nea es la raz\u00f3n de que exista algo, de que exista el Universo, de que nosotros existamos\u00bb. Por tanto, a\u00f1ade, \u00abno es necesario invocar a Dios\u00bb para que haya cosmos.<\/p>\n<p>\u00a0<a href=\"http:\/\/www.elpais.com\/articulo\/sociedad\/Stephen\/Hawking\/ciencia\/deja\/mucho\/espacio\/milagros\/Dios\/elpepusoc\/20080924elpepusoc_2\/Tes\">Stephen Hawking: &#8216;La ciencia no deja mucho espacio ni para milagros ni para Dios&#8217;<\/a><\/p>\n<p><a href=\"http:\/\/www.elpais.com\/articulo\/sociedad\/Hawking\/afirma\/extraterrestres\/pueden\/ser\/hostiles\/elpepusoc\/20100427elpepisoc_8\/Tes\">Hawking afirma que los extraterrestres pueden ser hostiles<\/a><\/p>\n<p>\u00a0<a href=\"http:\/\/www.elpais.com\/todo-sobre\/persona\/Stephen\/William\/Hawking\/6568\/\">Stephen William Hawking: <\/a>Nacimiento: 08-01-1942; Lugar: Oxford<\/p>\n<p>La noticia en otros webs: <a href=\"http:\/\/www.elpais.com\/archivo\/buscando.html?query=Dios%20no%20cre\u00f3%20el%20Universo,%20afirma%20Stephen%20Hawking&amp;donde=enotros&amp;idioma=es\">webs en espa\u00f1ol<\/a>; <a href=\"http:\/\/www.elpais.com\/archivo\/buscando.html?query=Dios%20no%20cre\u00f3%20el%20Universo,%20afirma%20Stephen%20Hawking&amp;donde=enotros&amp;idioma=nes\">en otros idiomas<\/a><\/p>\n<p>\u00a0En su obra m\u00e1s popular, A Brief History of Time (Una Breve Historia del Tiempo), un texto de divulgaci\u00f3n sobre el Universo y su evoluci\u00f3n, Hawking, f\u00edsico te\u00f3rico reconocido internacionalmente por sus aportaciones en cuestiones de<strong> cosmolog\u00eda<\/strong>, agujeros negros y gravitaci\u00f3n cu\u00e1ntica, suger\u00eda que \u00ab<strong>si llegamos a descubrir una teor\u00eda completa, ser\u00eda el triunfo definitivo de la raz\u00f3n humana porque entonces conocer\u00edamos la mente de Dios<\/strong>\u00ab. Ahora sostiene que, del mismo modo que<strong> el darwinismo elimin\u00f3 la necesidad de un creador en el campo de la biolog\u00eda, las nuevas teor\u00edas de la f\u00edsica hacen redundante el papel de un creador del Universo<\/strong>. <strong>El \u00faltimo libro<\/strong>, escrito junto al f\u00edsico estadounidense Leonard Mlodinow, <strong>saldr\u00e1 a la venta el pr\u00f3ximo 9 de septiembre, una semana antes de la visita del Papa a Reino Unido<\/strong>.<\/p>\n<p>\u00a0<strong>Los argumentos actuales de Hawking sugieren que ha roto con su visi\u00f3n anterior acerca de la religi\u00f3n, cuando sosten\u00eda que las leyes de la f\u00edsica significaban que sencillamente no era necesario creer que Dios hubiera intervenido en el Big Bang. Ahora destaca<\/strong>, por ejemplo, que el descubrimiento del primer planeta extrasolar, en 1992, ayud\u00f3 a desmontar<strong> la visi\u00f3n de Isaac Newton de que el Universo no pudo surgir del caos sino que fue creado por Dios<\/strong>. <strong>Ese hallazgo \u00abhace que las precisas condiciones de nuestro sistema planetario -el Sol \u00fanico, la afortunada combinaci\u00f3n de la distancia Sol-Tierra y la masa solar- sean mucho menos llamativas y en absoluto evidencias convincentes de que la Tierra fuera cuidadosamente dise\u00f1ada para satisfacer a los seres humanos<\/strong>\u00ab, escriben Hawking y su colega en el nuevo libro.<\/p>\n<p>\u00a0El f\u00edsico brit\u00e1nico ha cumplido 68 a\u00f1os y padece desde hace d\u00e9cadas una grav\u00edsima enfermedad neurol\u00f3gica, <strong>esclerosis lateral amiotr\u00f3fica (ELA)<\/strong>, que paraliz\u00f3 su cuerpo casi por completo. Debido a una traqueotom\u00eda de urgencia que se le practic\u00f3 hace unos a\u00f1os, perdi\u00f3 la capacidad de hablar y se expresa con enorme dificultad a trav\u00e9s de un ordenador que maneja con sus ojos y un sintetizador de voz artificial.<\/p>\n<p>\u00a0Hawking ocup\u00f3, desde 1979 y hasta su reciente jubilaci\u00f3n, la C\u00e1tedra Lucasiana de Matem\u00e1ticas de la Universidad de Cambridge, que hab\u00eda sido de su hist\u00f3rico colega Isaac Newton.<\/p>\n<h3><a title=\"Hawking, en el centro de la pol\u00e9mica \" href=\"http:\/\/www.abc.es\/20100903\/sociedad\/hawking-dios-201009030819.html\" target=\"_self\">Hawking, en el centro de la pol\u00e9mica <\/a><\/h3>\n<p>\u00a0<a href=\"http:\/\/www.elpais.com\/todo-sobre\/persona\/Stephen\/William\/Hawking\/6568\/\">Personaje: Stephen William Hawking <\/a><\/p>\n<p><a title=\"Stephen Hawking: 'La ciencia no deja mucho espacio ni para milagros ni para Dios'\" href=\"http:\/\/www.elpais.com\/articulo\/sociedad\/Stephen\/Hawking\/ciencia\/deja\/mucho\/espacio\/milagros\/Dios\/elpepusoc\/20080924elpepusoc_2\/Tes\">Stephen Hawking: &#8216;La ciencia no deja mucho espacio ni para milagros ni para Dios&#8217;<\/a><\/p>\n<p><a title=\"Hawking afirma que los extraterrestres pueden ser hostiles\" href=\"http:\/\/www.elpais.com\/articulo\/sociedad\/Hawking\/afirma\/extraterrestres\/pueden\/ser\/hostiles\/elpepisoc\/20100427elpepisoc_8\/Tes\">Hawking afirma que los extraterrestres pueden ser hostiles<\/a><\/p>\n<p>\u00a0<\/p>\n<p><strong>Su \u00faltimo libro vuelve a abrir la heridas de la vieja disputa entre Ciencia y Religi\u00f3n <\/strong><\/p>\n<p><strong>JOSE MANUEL NIEVES<\/strong> \/ MADRID; D\u00eda 03\/09\/2010 &#8211; 09.38h<\/p>\n<p>\u00a0El \u00faltimo libro de <strong>Stephen Hawking \u00abThe grand design\u00bb<\/strong>, cuyo avance se ha publicado estos d\u00edas en The Times, parece haber reabierto las nunca del todo bien cicatrizadas heridas de la vieja disputa entre Ciencia y Religi\u00f3n. La pregunta fundamental sigue siendo la misma: \u00bfEs Dios necesario para explicar el mundo en que vivimos? Las respuestas, sin embargo, seg\u00fan el punto de vista desde el que se aborden, pueden ser, y son, completamente diferentes.<\/p>\n<p>\u00a0<strong>Para Hawking, sencillamente, Dios no tiene lugar alguno en las actuales teor\u00edas cient\u00edficas sobre la creaci\u00f3n del universo<\/strong>. Los avances conseguidos en<strong> F\u00edsica<\/strong>, dice el cient\u00edfico, <strong>bastan para explicar, por s\u00ed mismos, el origen y la naturaleza de nuestro universo, sin necesidad de recurrir a ninguna clase de intervenci\u00f3n divina.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Y no es que el f\u00edsico brit\u00e1nico niegue la existencia de Dios, cosa que no ha hecho nunca directamente, sino que<\/strong> <strong>se limita a afirmar que su intervenci\u00f3n no es necesaria para explicar la existencia del mundo y de todo cuanto le rodea<\/strong>. Una idea que puede parecer, pero que no es, contradictoria. Por lo menos desde el punto de vista cient\u00edfico.<\/p>\n<p>\u00a0Pero veamos.<strong> \u00bfEst\u00e1 la mano de Dios detr\u00e1s de cada fen\u00f3meno natural, manejando los hilos a su antojo en cada momento?<\/strong> Decir que s\u00ed equivale a afirmar que es Dios en persona quien decide si va a llover o no, si habr\u00e1 un hurac\u00e1n o si, por ejemplo, un volc\u00e1n va a entrar o no en erupci\u00f3n.<\/p>\n<p>\u00a0Afortunadamente, los tiempos en que la mano divina se buscaba detr\u00e1s de cada rayo, nube, sequ\u00eda o terremoto quedan ya muy lejos. La Ciencia, paso a paso, ha ido explicando c\u00f3mo y por qu\u00e9 se producen los distintos fen\u00f3menos naturales, sean o no beneficiosos para el hombre, desvelando las leyes que subyacen en cada caso para producir los efectos que observamos.<\/p>\n<p>\u00a0<strong><span style=\"color: #008080;\">Dios no aparece en ninguna teor\u00eda<\/span><\/strong><\/p>\n<p>Pero la Ciencia, hoy, no se limita a eso. Muy al contrario, los avances del \u00faltimo siglo la han llevado hasta la mism\u00edsima frontera del conocimiento y la comprensi\u00f3n humanas, desde lo m\u00e1s grande a lo m\u00e1s peque\u00f1o. <strong>La F\u00edsica por un lado y la Cosmolog\u00eda por otro<\/strong> han llegado tan lejos que est\u00e1n al borde mismo de explicar c\u00f3mo surgi\u00f3 y se desarroll\u00f3 el universo en que vivimos. <strong>Y resulta que Dios, en esas teor\u00edas, no aparece por ninguna parte<\/strong>.<\/p>\n<p>\u00a0<strong>Ese es precisamente el terreno en que se mueve Stephen Hawking<\/strong>, uno de los f\u00edsicos te\u00f3ricos m\u00e1s brillantes de nuestro tiempo. <strong>Hace casi tres d\u00e9cadas, Hawking<\/strong> en persona cre\u00eda (y as\u00ed lo declar\u00f3 a este periodista en una entrevista publicada en ABC), <strong>que para el a\u00f1o 2000 la F\u00edsica dejar\u00eda de existir como Ciencia, ya que no le quedar\u00eda nada por explicar<\/strong>.<\/p>\n<p>\u00a0<strong>Hoy, en 2010, el f\u00edsico ha cambiado de opini\u00f3n al respecto y reconoce que, al final, es posible que no exista una teor\u00eda del todo, un cuerpo te\u00f3rico unificado que sirva, por si solo, para dar cuenta de todos los fen\u00f3menos de la Naturaleza. A medida que el conocimiento avanza, esa \u00abteor\u00eda total\u00bb ha dejado de ser tan necesaria como se pensaba en los a\u00f1os 80<\/strong>. De hecho, opina Hawking en su nuevo libro, es perfectamente posible explicarlo todo sin necesidad de ese cuerpo te\u00f3rico global.<\/p>\n<p>\u00a0<strong><span style=\"color: #008080;\">La Ciencia ha arrinconado a Dios<\/span><\/strong><\/p>\n<p><strong>Pero, \u00bfY Dios? \u00bfC\u00f3mo encaja exactamente la figura de un Creador en un Universo que parece explicarse a s\u00ed mismo en virtud de una serie de leyes inmutables? <\/strong>A lo largo de la Historia, y a base de conocimientos cada vez m\u00e1s abundantes y precisos, la figura de un Dios que est\u00e1 detr\u00e1s de todas las cosas ha ido cediendo terreno.<strong> La Ciencia, opina Hawking, ha ido \u00abarrinconando\u00bb a Dios<\/strong>, encontrando una explicaci\u00f3n concreta para cada uno de los fen\u00f3menos naturales que nos rodean, desde el nacimiento de una estrella a la formaci\u00f3n de una tormenta.<\/p>\n<p>\u00a0<strong>Una l\u00ednea de razonamiento que mantiene desde siempre<\/strong> y que es, precisamente, la que le ha llevado a concluir que no se necesita la intervenci\u00f3n de Dios para explicar la existencia y el devenir del universo que concemos.<\/p>\n<p>\u00a0<strong>Es importante subrayar, en contra de lo publicado estos d\u00edas por numerosos medios de comunicaci\u00f3n, que el f\u00edsico brit\u00e1nico no ha tenido nunca otra opini\u00f3n diferente a \u00e9sta<\/strong>. Cuando Hawking escribi\u00f3, como colof\u00f3n a su \u00abBreve historia del tiempo\u00bb que <strong>\u00absi descubrimos una teor\u00eda del todo comprenderemos la mente de Dios\u00bb<\/strong> se refer\u00eda a \u00c9l como a <strong>una met\u00e1fora, y no de forma literal<\/strong>. Corr\u00eda el <strong>a\u00f1o 1988<\/strong> y <strong>por aqu\u00e9l entonces la b\u00fasqueda de la teor\u00eda del todo estaba en pleno apogeo<\/strong>.<\/p>\n<p>\u00a0<strong>Tambi\u00e9n Einstein, que no era precisamente religioso, recurri\u00f3 al Creador<\/strong> en la c\u00e9lebre frase de \u00abDios no juega a los dados\u00bb, pero lo hizo para rebelarse contra el caos que la entonces incipiente F\u00edsica cu\u00e1ntica inyectaba en un universo que hasta ese momento se cre\u00eda perfectamente ordenado y previsible.<\/p>\n<p>\u00a0Las ideas de Stephen Hawking a este respecto, pues, no han cambiado en absoluto. De hecho, en aquella misma entrevista publicada en ABC hace m\u00e1s de veinte a\u00f1os, el cient\u00edfico ya dec\u00eda que la figura de <strong>un Creador no se necesita para explicar el universo en que vivimos<\/strong>. Para eso ya <strong>bastan las leyes de la F\u00edsica<\/strong>.<\/p>\n<p>\u00a0Siempre podemos pensar, <strong>dec\u00eda (y sigue diciendo) Hawking, que Dios podr\u00eda ser el autor de esas mismas leyes que hicieron posible todo lo dem\u00e1s, pero entonces estar\u00edamos hablando de un Dios muy lejano y apartado del hombre<\/strong>, que se limit\u00f3 a escribir las reglas b\u00e1sicas a partir de las cuales surgi\u00f3 y pudo desarrollarse todo lo que existe. <strong>Si lo pensamos bien, eso equivale a decir que, desde que naci\u00f3 el universo, hace 13.700 millones de a\u00f1os, Dios no ha vuelto a tener ninguna intervenci\u00f3n en su devenir,<\/strong> ya que todo lo que sucedi\u00f3 despu\u00e9s del Big Bang se puede explicar en virtud de esas mismas leyes creadas por \u00c9l.<\/p>\n<p>\u00a0No es cierto, pues, que Stephen Hawking haya cambiado de idea con respecto a la existencia de Dios. Sigue pensando y diciendo las mismas cosas que dec\u00eda y pensaba hace varias d\u00e9cadas. S\u00ed que es cierto, sin embargo, que h<strong>ace ya diez a\u00f1os largos que el f\u00edsico brit\u00e1nico public\u00f3 su \u00faltimo best seller, del que por cierto consigui\u00f3 vender m\u00e1s de seis millones de copias en todo el mundo<\/strong>.<\/p>\n<p>\u00a0En los \u00faltimos meses, la figura de Stephen Hawking ha aparecido varias veces en los medios de todo el planeta por <strong>sus declaraciones, en un caso, sobre la peligrosidad de un eventual encuentro con una hipot\u00e9tica inteligencia extraterrestre; y por su convicci\u00f3n, en otro, de que la \u00fanica posibilidad de supervivencia del hombre es abandonar nuestro planeta<\/strong>, moribundo, y salir a conquistar las estrellas.<\/p>\n<p>\u00a0Parecer\u00eda, pues, que de alguna forma, y a punto de salir su nuevo libro,<strong> resulta muy conveniente que la figura de Stephen Hawking rellene peri\u00f3dicamente las p\u00e1ginas de los peri\u00f3dicos del mundo. \u00bfPor qu\u00e9 si no se iba a generar justo ahora una pol\u00e9mica sobre unas ideas que no han cambiado un \u00e1pice en las \u00faltimas dos d\u00e9cadas?<\/strong><\/p>\n<p>\u00a0<strong>En resumen: Hawking, que se mueve en las fronteras mismas del conocimiento, es y ha sido hasta ahora perfectamente coherente con sus ideas y sus convicciones<\/strong>. Y sus opiniones sobre la necesidad o no de un Creador para explicar la realidad en que vivimos no han cambiado en absoluto. <strong>Por eso, jugar ahora con un supuesto \u00abcambio de actitud\u00bb del cient\u00edfico con respecto de lo religioso con la intenci\u00f3n de generar ruido y publicidad para su nuevo libro supone un flaco favor para la Ciencia y tambi\u00e9n para el propio Hawking<\/strong>, que a pesar de sus numerosas apariciones p\u00fablicas y su sentido del humor dista mucho de ser un simple fen\u00f3meno medi\u00e1tico.<\/p>\n<p>\u00a0<strong>Se trata, no lo olvidemos, de uno de los cient\u00edficos m\u00e1s brillantes y prolijos de los \u00faltimos cien a\u00f1os<\/strong>, y sus trabajos han contribuido enormemente a nuestra comprensi\u00f3n profunda del universo en el que nos ha tocado vivir. Sus aportaciones han creado escuela y algunas de ellas ocupan por derecho propio un lugar destacado entre las mejores p\u00e1ginas de la historia de la Ciencia.<\/p>\n<p>\u00a0Esa es la imagen de Stephen Hawking que debe perdurar y servir de ejemplo a las futuras generaciones de cient\u00edficos y de amantes del conocimiento. Y no la de un personaje superficial siempre en busca de la pol\u00e9mica y cuyas convicciones m\u00e1s profundas est\u00e1n al albur de los intereses materiales de cada momento.<\/p>\n<p>\u00a0<\/p>\n<h3><a href=\"http:\/\/www.lavanguardia.es\/free\/edicionimpresa\/res\/20100904\/53994384961.html?urlback=http:\/\/www.lavanguardia.es\/premium\/edicionimpresa\/20100904\/53994384961.html\">Los l\u00edderes religiosos critican a Hawking<\/a><\/h3>\n<p style=\"TEXT-ALIGN: justify\"><strong>\u00a0La Vanguaria 4 <\/strong>de septiembre de 2006 Niegan la exclusi\u00f3n de Dios en el origen del cosmos<\/p>\n<p style=\"TEXT-ALIGN: justify\">\u00a0<strong>RAFAEL RAMOS\u00a0&#8211;\u00a0Londres. Corresponsal<\/strong> \u00a0&#8211;\u00a004\/09\/2010<\/p>\n<p style=\"TEXT-ALIGN: justify\">\u00a0\u00abA la Biblia no le interesan los detalles t\u00e9cnicos de c\u00f3mo se cre\u00f3 el universo\u00bb, dice el rabino Sacks<\/p>\n<p style=\"TEXT-ALIGN: justify\"><strong>\u00a0<\/strong><strong>Las fuerzas de la raz\u00f3n y de la fe son con frecuencia dos trenes que viajan en direcci\u00f3n contraria, y han vuelto inevitablemente a chocar<\/strong> tras la publicaci\u00f3n de un adelanto del pr\u00f3ximo libro del reconocido cient\u00edfico ingl\u00e9s Stephen Hawking en el que afirma que la creaci\u00f3n del universo no tiene nada que ver con Dios, sino tan s\u00f3lo con el big bang y la teor\u00eda de la gravedad. <strong>L\u00edderes religiosos anglicanos, cat\u00f3licos, musulmanes y jud\u00edos han unido fuerzas para criticar a Hawking, cuya negaci\u00f3n del papel divino en el origen del mundo hace m\u00e1s da\u00f1o todav\u00eda por tratarse de una revisi\u00f3n de su anterior posici\u00f3n<\/strong>, formulada en Una breve historia del mundo, que consideraba compatibles la visi\u00f3n religiosa y cient\u00edfica. <strong>\u00abCreer en Dios no consiste en c\u00f3mo taponar un agujero y explicar c\u00f3mo unas cosas se relacionan con otras en el universo, sino que es la creencia de que hay un agente inteligente y vivo de cuya actividad depende en \u00faltima instancia todo lo que existe\u00bb<\/strong>, ha declarado el arzobispo de Canterbury, Rowan Williams, al diario The Times&#8230;.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>A L. Rivas Lado, en un articulo publicado el a\u00f1o 2001 (revista \u00c1gora), nos recordaba un fragmento archiconocido en la historia\u00a0 de la ciencia. \u201cLaplace, ante la pregunta de Napole\u00f3n de porqu\u00e9 en su \u201cMec\u00e1nica Celeste\u201d no aparece el nombre de Dios: \u201cSire, je n\u2019avais pas besoin de cette hypoth\u00e8se\u201d. Es decir en ciencia la causaci\u00f3n divina es incuestionablemente \u201cuna hip\u00f3tesis innecesaria\u201d. El revuelo montado por los \u00faltimos comentarios vertidos en su nuevo libro por \u00a0Stephen Hawking, resulta est\u00fapido y contraproducente. Debemos recordar que una cuesti\u00f3n es la ciencia, otra la epistemolog\u00eda, otra la ontolog\u00eda y otra la teolog\u00eda (buscar\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[609,1,606],"tags":[2199,46785],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"A L. Rivas Lado, en un articulo publicado el a\u00f1o 2001 (revista \u00c1gora), nos recordaba un fragmento archiconocido en la historia de la ciencia. \u201cLaplace, ante la pregunta de Napole\u00f3n de porqu\u00e9 en su \u201cMec\u00e1nica Celeste\u201d no aparece el nombre de Dios: \u201cSire, je n\u2019avais pas besoin de cette hypoth\u00e8se\u201d. Es decir en ciencia la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"A L. Rivas Lado, en un articulo publicado el a\u00f1o 2001 (revista \u00c1gora), nos recordaba un fragmento archiconocido en la historia de la ciencia. \u201cLaplace, ante la pregunta de Napole\u00f3n de porqu\u00e9 en su \u201cMec\u00e1nica Celeste\u201d no aparece el nombre de Dios: \u201cSire, je n\u2019avais pas besoin de cette hypoth\u00e8se\u201d. Es decir en ciencia la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-09-04T17:07:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-09-06T09:02:09+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A L. Rivas Lado, en un articulo publicado el a\u00f1o 2001 (revista \u00c1gora), nos recordaba un fragmento archiconocido en la historia de la ciencia. \u201cLaplace, ante la pregunta de Napole\u00f3n de porqu\u00e9 en su \u201cMec\u00e1nica Celeste\u201d no aparece el nombre de Dios: \u201cSire, je n\u2019avais pas besoin de cette hypoth\u00e8se\u201d. Es decir en ciencia la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982#blogposting\",\"name\":\"Los Cient\\u00edficos, la Religi\\u00f3n, la Prensa y el Marketing - Un Universo invisible bajo nuestros pies\",\"headline\":\"Los Cient\\u00edficos, la Religi\\u00f3n, la Prensa y el Marketing\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/159\\\/imagenes-del-cosmos-desde-el-telescopio-hubble.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982\\\/#articleImage\"},\"datePublished\":\"2010-09-04T18:07:42+01:00\",\"dateModified\":\"2010-09-06T10:02:09+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":9,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982#webpage\"},\"articleSection\":\"Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, General, Prensa y Pol\\u00edtica Cient\\u00edfica, Ciencia frente a religi\\u00f3n, controversias cient\\u00edficas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982#listItem\",\"name\":\"Los Cient\\u00edficos, la Religi\\u00f3n, la Prensa y el Marketing\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982#listItem\",\"position\":3,\"name\":\"Los Cient\\u00edficos, la Religi\\u00f3n, la Prensa y el Marketing\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982\",\"name\":\"Los Cient\\u00edficos, la Religi\\u00f3n, la Prensa y el Marketing - Un Universo invisible bajo nuestros pies\",\"description\":\"A L. Rivas Lado, en un articulo publicado el a\\u00f1o 2001 (revista \\u00c1gora), nos recordaba un fragmento archiconocido en la historia de la ciencia. \\u201cLaplace, ante la pregunta de Napole\\u00f3n de porqu\\u00e9 en su \\u201cMec\\u00e1nica Celeste\\u201d no aparece el nombre de Dios: \\u201cSire, je n\\u2019avais pas besoin de cette hypoth\\u00e8se\\u201d. Es decir en ciencia la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/09\\\/04\\\/136982#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2010-09-04T18:07:42+01:00\",\"dateModified\":\"2010-09-06T10:02:09+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing - Un Universo invisible bajo nuestros pies","description":"A L. Rivas Lado, en un articulo publicado el a\u00f1o 2001 (revista \u00c1gora), nos recordaba un fragmento archiconocido en la historia de la ciencia. \u201cLaplace, ante la pregunta de Napole\u00f3n de porqu\u00e9 en su \u201cMec\u00e1nica Celeste\u201d no aparece el nombre de Dios: \u201cSire, je n\u2019avais pas besoin de cette hypoth\u00e8se\u201d. Es decir en ciencia la","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982#blogposting","name":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing - Un Universo invisible bajo nuestros pies","headline":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/imagenes-del-cosmos-desde-el-telescopio-hubble.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982\/#articleImage"},"datePublished":"2010-09-04T18:07:42+01:00","dateModified":"2010-09-06T10:02:09+01:00","inLanguage":"es-ES","commentCount":9,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982#webpage"},"articleSection":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, General, Prensa y Pol\u00edtica Cient\u00edfica, Ciencia frente a religi\u00f3n, controversias cient\u00edficas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982#listItem","name":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982#listItem","position":3,"name":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982","name":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing - Un Universo invisible bajo nuestros pies","description":"A L. Rivas Lado, en un articulo publicado el a\u00f1o 2001 (revista \u00c1gora), nos recordaba un fragmento archiconocido en la historia de la ciencia. \u201cLaplace, ante la pregunta de Napole\u00f3n de porqu\u00e9 en su \u201cMec\u00e1nica Celeste\u201d no aparece el nombre de Dios: \u201cSire, je n\u2019avais pas besoin de cette hypoth\u00e8se\u201d. Es decir en ciencia la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2010-09-04T18:07:42+01:00","dateModified":"2010-09-06T10:02:09+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing - Un Universo invisible bajo nuestros pies","og:description":"A L. Rivas Lado, en un articulo publicado el a\u00f1o 2001 (revista \u00c1gora), nos recordaba un fragmento archiconocido en la historia de la ciencia. \u201cLaplace, ante la pregunta de Napole\u00f3n de porqu\u00e9 en su \u201cMec\u00e1nica Celeste\u201d no aparece el nombre de Dios: \u201cSire, je n\u2019avais pas besoin de cette hypoth\u00e8se\u201d. Es decir en ciencia la","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2010-09-04T17:07:42+00:00","article:modified_time":"2010-09-06T09:02:09+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing - Un Universo invisible bajo nuestros pies","twitter:description":"A L. Rivas Lado, en un articulo publicado el a\u00f1o 2001 (revista \u00c1gora), nos recordaba un fragmento archiconocido en la historia de la ciencia. \u201cLaplace, ante la pregunta de Napole\u00f3n de porqu\u00e9 en su \u201cMec\u00e1nica Celeste\u201d no aparece el nombre de Dios: \u201cSire, je n\u2019avais pas besoin de cette hypoth\u00e8se\u201d. Es decir en ciencia la","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136982","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:45:42","updated":"2026-05-26 16:21:49","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general"},{"label":"Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136982"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=136982"}],"version-history":[{"count":12,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136982\/revisions"}],"predecessor-version":[{"id":136987,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/136982\/revisions\/136987"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=136982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=136982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=136982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}