{"id":137004,"date":"2010-11-09T11:14:48","date_gmt":"2010-11-09T10:14:48","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=137004"},"modified":"2010-11-09T11:14:48","modified_gmt":"2010-11-09T10:14:48","slug":"cultivos-en-cobertera-y-cortinas-de-yeso-para-mitigar-la-contaminacion-de-aguas-por-el-uso-de-fertilizantes","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004","title":{"rendered":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><span style=\"color: #3366ff;\">El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\u00f3n de aguas<\/span><\/strong>, incluyendo las marinas, causando la degradaci\u00f3n de las aguas litorales, as\u00ed como la proliferaci\u00f3n de floraciones algales y puntos muertos. Tal hecho <strong><span style=\"color: #3366ff;\">preocupa a las agencias ambientales de numerosos pa\u00edses<\/span><\/strong>. Por esta raz\u00f3n, numerosos equipos de investigaci\u00f3n realizan actualmente investigaciones con vistas a mitigar el proceso, en la medida de lo posible. El <strong><span style=\"color: #3366ff;\">monitoreo de su concentraci\u00f3n en cuencas de drenaje<\/span><\/strong> comienza a extenderse en ciertos pa\u00edses como EE.UU. Hoy<strong><span style=\"color: #3366ff;\"> os mostraremos dos ejemplos extra\u00eddos del noticiero ARS<\/span> <span style=\"color: #3366ff;\">(USDA)<\/span><\/strong> que nos muestran dos v\u00edas distintas de atacar el problema (<a href=\"http:\/\/www.3tres3.com\/especial_purines\/pdfs\/Codigo_bpa_Madrid.pdf\">cultivos en cobertera<\/a> y \u201c<strong><span style=\"color: #3366ff;\">cortinas de yeso<\/span><\/strong>\u201d) que pudieran servir para <strong><span style=\"color: #3366ff;\">disminuir el lixiviado de f\u00f3sforo y nitr\u00f3geno de los suelos recientemente fertilizados hacia las aguas corrientes y<\/span> <span style=\"color: #3366ff;\">subterr\u00e1neas<\/span><\/strong>. Sin embargo, como demandan numerosos organismos e instituciones, <strong><span style=\"color: #3366ff;\">se requiere urgentemente un cambio radical a la hora de mejorar la producci\u00f3n agr\u00edcola que soslayen este grav\u00edsimo problema ambiental<\/span><\/strong>.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/804\/cultivos-en-cobertera-fuente-sagarpa.jpg\" alt=\"cultivos en cobertera Fuente: SAGARPA\" width=\"405\" height=\"270\" \/>\u00a0<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.sagarpa.gob.mx\/desarrolloRural\/Publicaciones\/Lists\/Agrcolas\/Attachments\/8\/A-02-1.pdf\">Cultivos en Cobertera. Fuente: SAGARPA<\/a><\/p>\n<p align=\"center\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Las noticias que hoy ofrecemos del<strong> <span style=\"color: #3366ff;\">noticiero ARS<\/span><\/strong> en espa\u00f1ol castellano, afortunadamente, resultan ser mucho m\u00e1s claras y \u201cdescifrables\u201d que otras de las que ya nos quejamos <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/31\/136797\">en post anteriores<\/a>.\u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0Como veremos m\u00e1s abajo, los <a href=\"http:\/\/www.3tres3.com\/especial_purines\/pdfs\/Codigo_bpa_Madrid.pdf\">cultivos en cobertera<\/a> han venido utiliz\u00e1ndose (incluso desde la antig\u00fcedad) con vistas a <strong><span style=\"color: #3366ff;\">mejorar la fertilidad del suelo<\/span><\/strong>, as\u00ed como a la hora de <strong><span style=\"color: #3366ff;\">paliar la erosi\u00f3n y degradaci\u00f3n f\u00edsica del mismo<\/span><\/strong>, al impedir que permanezca desnudo durante los periodos de barbecho. Del mismo modo, son<strong> <span style=\"color: #3366ff;\">un procedimiento muy eficaz para el control biol\u00f3gico de las muchas plagas<\/span><\/strong>. M\u00e1s<strong> <span style=\"color: #3366ff;\">recientemente<\/span><\/strong>, como hoy veremos, <strong><span style=\"color: #3366ff;\">se investiga su uso con vistas a mitigar<\/span><\/strong>, al menos en parte,<strong> <span style=\"color: #3366ff;\">el lixiviado de los fertilizantes hacia las aguas corrientes y oce\u00e1nicas<\/span><\/strong>. Se trata de que las plantas de este sistema de manejo absorban o secuestren el exceso de los nutrientes solubles de estas enmiendas, al objeto de evitar la mencionada poluci\u00f3n de las aguas.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\">\u00a0<strong>El problema de los fertilizantes reside en que<\/strong><\/span> gran parte de los mismos no son aprovechados por los vegetales cultivados, por lo que tras las lluvias van a parar directamente a las aguas superficiales y subterr\u00e1neas, alterando los ecosistemas, poniendo en riesgo la salud humana y devastando la ecolog\u00eda marina de las \u00e1reas en donde drenan las grandes cuencas que acumulan cauces arriba tierras amplias extensiones de tierras cultivadas bajo agricultura industrial. Si bien los <strong><span style=\"color: #3366ff;\">fertilizantes inorg\u00e1nicos<\/span><\/strong> (espacialmente los liberan r\u00e1pidamente sus nutrientes) resultan ser los m\u00e1s peligrosos, el problema tambi\u00e9n afecta a las enmiendas org\u00e1nicas, como el<strong> <span style=\"color: #3366ff;\">esti\u00e9rcol<\/span><\/strong> y la <a href=\"http:\/\/www.fao.org\/teca\/content\/uso-de-la-gallinaza-esti\u00c3\u00a9rcol-de-aves-como-abono-org\u00c3\u00a1nico\">gallinaza<\/a>.<\/p>\n<p style=\"text-align: justify;\">\u00a0Seg\u00fan la primera de las notas de prensa que os exponemos abajo, <strong><span style=\"color: #3366ff;\">los cultivos en cobertera, efectivamente pueden mitigar la poluci\u00f3n de las aguas por el uso de enmiendas, si bien<\/span><\/strong> no todas las plantas que los constituyen son igualmente eficaces, en funci\u00f3n de su periodo de crecimiento y ambiente en el que se siembran.<strong><span style=\"color: #3366ff;\"> Por tanto<\/span><\/strong> resulta recomendable realizar investigaciones previas en cada regi\u00f3n y no copiar acr\u00edticamente las espacies que la noticia relata.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\">\u00a0<strong>La \u00faltima noticia, ofrece otra alternativa bien diferente<\/strong>. Se trata de <strong>aprovechar el yeso desprendido como residuo por ciertas actividades industriales, y<\/strong><\/span> hacer uso de peque\u00f1as obras adicionales de ingenier\u00eda hidr\u00e1ulica a las ya existentes en las granjas.<\/p>\n<p style=\"text-align: justify;\">\u00a0Finalmente, tan solo hacernos notar que <strong><span style=\"color: #3366ff;\">ambas noticias proceden de la misma cuenca de drenaje: Bah\u00eda de Chesapeake<\/span><\/strong>, en el noroeste de EE.UU. Al parecer, se trata de <strong><span style=\"color: #3366ff;\">un programa multidisciplinar encaminado a<\/span><\/strong> poner a punto un sistema de monitoreo y auxilio a los agricultores, con visitas a paliar la grave contaminaci\u00f3n que sufre el lugar mentado, para lo cual se hace uso de <strong><span style=\"color: #3366ff;\">procedimientos de campo, sensores satelitales, etc<\/span><\/strong>. Con vistas a entender lo que es la\u00a0 <a href=\"http:\/\/www.fao.org\/teca\/content\/uso-de-la-gallinaza-esti\u00c3\u00a9rcol-de-aves-como-abono-org\u00c3\u00a1nico\">gallinaza<\/a> (residuos av\u00edcolas, por lo general de granjas industriales) basta pinchar sobre el vocablo. Seguidamente, y <strong><span style=\"color: #008080;\">antes de dar cuenta de las noticias comentadas, os ofrecemos unas breves notas did\u00e1cticas sobre el significado e importancia de las pr\u00e1cticas de manejo mediante cultivos de cobertera<\/span><\/strong>.<\/p>\n<p>\u00a0<strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez \u00a0\u00a0<\/span><\/strong><\/p>\n<p>\u00a0De acuerdo a la<a href=\"http:\/\/www.engormix.com\/MA-agricultura\/pasturas\/articulos\/cultivos-cobertura-agricultura-sostenible-t1868\/089-p0.htm\"> p\u00e1gina Web de Engormix<\/a> Art\u00edculo amplio muy recomendable):<\/p>\n<p>\u00a0<\/p>\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/www.engormix.com\/MA-agricultura\/pasturas\/articulos\/cultivos-cobertura-agricultura-sostenible-t1868\/089-p0.htm\">Cultivos de Cobertura para la Agricultura Sostenible en Am\u00e9rica<\/a><\/h3>\n<p>\u00a0<strong><span style=\"color: #008080;\">Cultivos de Cobertura: \u00bfQue son?<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Para los fines de esta revisi\u00f3n, un cultivo de cobertura es definido como \u00ab<em><strong>una cobertura vegetal viva que cubre el suelo y que es temporal o permanente, el cual est\u00e1 cultivado en asociaci\u00f3n con otras plantas (intercalado, en relevo o en rotaci\u00f3n)\u00bb<\/strong><\/em>. Aunque los cultivos de cobertura pueden pertenecer a cualquier familia de plantas, la mayor\u00eda son leguminosas. Ejemplos de cultivos de cobertura no-leguminosas son avena negra (<em>Avena strigosa<\/em>), avena amarilla (<em>Avena byzantina<\/em>), <em>Raphinus sativus<\/em> var. <em>oleiferus<\/em> y el ryegrass italiano (<em>Lolium multiflorum<\/em>), los cuales son usados como cultivos de cobertura invernales en el sur de Brasil para suprimir malezas y reducir la erosi\u00f3n en la estaci\u00f3n previa al la siembra de ma\u00edz o soya. (Tropical Soybean: improvement and production. FAO Plant Production and Protection Series No. 27, 1994).<\/p>\n<p style=\"text-align: justify;\"><strong>Los t\u00e9rminos \u00abcultivos de cobertura\u00bb y \u00ababono verde\u00bb se han usado en el pasado como sin\u00f3nimos; sin embargo, los cultivos de cobertura est\u00e1n caracterizados por sus funciones m\u00e1s amplias y multi-prop\u00f3sitos<\/strong>, las cuales incluyen la supresi\u00f3n de malezas, conservaci\u00f3n de suelo y agua, control de plagas y enfermedades, alimentaci\u00f3n humana y para el ganado.<\/p>\n<p style=\"text-align: justify;\"><strong>Los cultivos de cobertura no son una tecnolog\u00eda nueva<\/strong>. El uso de la <em>Mucuna<\/em> ha sido registrado<strong> desde el siglo 17 en Java, Bali y Sumatra, para recuperar los suelos degradados<\/strong> (Burkhill, 1968). <strong>Mucho m\u00e1s anteriormente hay registros de que los Griegos y Romanos han practicado la rotaci\u00f3n de cultivos, y Plinio menciona el cultivado de lupinos (<em>Lupinus albus<\/em>) y arveja (<em>Vicia sativa<\/em>) como abonos verdes y para la supresi\u00f3n de malezas <\/strong>(Karlen <em>et al.<\/em>, 1994). Aparentemente, lo que sucede es que con el tiempo surge la combinaci\u00f3n de circunstancias que coinciden con las ventajas que pueden ofrecer los cultivos de cobertura. Un ejemplo de un conjunto amplio de tales circunstancias es el intento de intensificaci\u00f3n por parte de los agricultores de peque\u00f1a escala y con pocos recursos de Centro y Sur Am\u00e9rica. Tal situaci\u00f3n constituye el foco de esta publicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00a0Se usa el <strong>esti\u00e9rcol animal como abono org\u00e1nico con la finalidad de acondicionar el suelo mejorando su<\/strong> contenido de humus y estructura, estimulando la vida micro y mesobiol\u00f3gica del suelo. Al mismo tiempo se fertiliza el suelo cono micro y macro nutrientes.<strong> En el caso de esti\u00e9rcol de aves se observa una liberaci\u00f3n inmediata de nutrientes y en seguida una liberaci\u00f3n paulatina del resto de los nutrientes durante 1 a 2 a\u00f1os<\/strong>. El contenido de nutrientes en el esti\u00e9rcol var\u00eda dependiendo de la clase de animal, su dieta y el m\u00e9todo de almacenamiento y aplicaci\u00f3n. En laderas es esencial combinar la aplicaci\u00f3n de esti\u00e9rcol para mejorar la fertilidad del suelo con otras pr\u00e1cticas de control de erosi\u00f3n<\/p>\n<p style=\"text-align: justify;\">\u00a0Como se indica que en<a href=\"http:\/\/mazinger.sisib.uchile.cl\/repositorio\/lb\/ciencias_agronomicas\/montealegre_j\/19.html\"> este enlace<\/a>:<\/p>\n<p style=\"text-align: justify;\">\u00a0Dentro de este sistema, un punto muy importante <strong>es el manejo del suelo por medio de una cobertura vegetal (\u2026), con varios objetivos, entre ellos evitar la erosi\u00f3n y compactaci\u00f3n, mejorar el drenaje, aireaci\u00f3n y textura del suelo, incrementar la fertilidad a\u00f1adiendo material org\u00e1nico durante la descomposici\u00f3n de las plantas mejorando la <\/strong>disponibilidad de los nutrientes, favorecer la diversidad biol\u00f3gica, controlar el crecimiento de malezas y manejar la entre hilera a fin de lograr beneficios para el cultivo como el manejo de plagas, entre ellas los nem\u00e1todos fitopar\u00e1sitos<\/p>\n<p style=\"text-align: center;\">\u00a0<strong><span style=\"color: #008080;\">Cultivos en cobertera para prevenir la contaminaci\u00f3n de suelos y aguas en cuencas hidrogr\u00e1ficas<\/span><\/strong><\/p>\n<h3 style=\"text-align: center;\">\u00a0<span style=\"color: #008080;\">Limpiando la Bah\u00eda de Chesapeake&#8211;desde el espacio<\/span><\/h3>\n<p>Servicio Noticiero del Servicio de Investigaci\u00f3n Agr\u00edcola (ARS siglas en ingl\u00e9s)<br \/>\nDepartamento de Agricultura (USDA siglas en ingl\u00e9s); \u00a030 de agosto de 2010<br \/>\n&#8211;Vea esta historia en Internet en <a href=\"http:\/\/www.ars.usda.gov\/is\/espanol\/pr\">www.ars.usda.gov\/is\/espanol\/pr<\/a><\/p>\n<p style=\"text-align: justify;\">Una prueba piloto del uso innovador de nuevas <strong>tecnolog\u00edas del sensoramiento remoto para ayudar a limpiar la Bah\u00eda de Chesapeake<\/strong> est\u00e1 comenzando este a\u00f1o en el condado Talbot en la costa oriental de la Bah\u00eda.<\/p>\n<p style=\"text-align: justify;\">Greg McCarty, quien es cient\u00edfico del suelo con el Servicio de Investigaci\u00f3n Agr\u00edcola (ARS), y Dean Hively, cient\u00edfico con el Servicio Geol\u00f3gico de EE.UU., c<strong>ombinaron el sensoramiento remoto, informaci\u00f3n derivada de muestras de suelo de los campos agr\u00edcolas, y archivos de granjas para evaluar la eficacia de utilizaci\u00f3n de cultivos de cobertura durante el invierno para controlar las p\u00e9rdidas de nitr\u00f3geno y f\u00f3sforo de las granjas a la Bah\u00eda<\/strong>.<\/p>\n<p style=\"text-align: justify;\">McCarty y Hively son l\u00edderes de un grupo de investigaci\u00f3n de m\u00faltiples agencias que trabaja estrechamente con el Departamento de Agricultura del estado de Maryland. McCarty trabaja en el Laboratorio de Hidrolog\u00eda y Sensoramiento Remoto mantenido por el ARS en Beltsville, Maryland. ARS es la agencia principal de investigaciones cient\u00edficas del Departamento de Agricultura de EE.UU. (USDA por sus siglas en ingl\u00e9s).<\/p>\n<p style=\"text-align: justify;\">Los <strong>cultivos de cobertura<\/strong>&#8211;principalmente el centeno, la cebada y el trigo&#8211;son una herramienta importante para controlar el flujo de nitr\u00f3geno y f\u00f3sforo de los campos agr\u00edcolas a la Bah\u00eda de Chesapeake. <strong>Los cultivos capturan el nitr\u00f3geno y f\u00f3sforo sobrante del esti\u00e9rcol y los fertilizantes usados para producir el ma\u00edz, la soja y otros cultivos de verano<\/strong>.<\/p>\n<p style=\"text-align: justify;\">En un estudio de cuatro a\u00f1os usando esta combinaci\u00f3n de herramientas, McCarty y Hively mostraron que, entre los tres cultivos principales,<strong> el trigo es el menos eficaz en absorber el nitr\u00f3geno, debido a <\/strong>su crecimiento lento durante el oto\u00f1o. Pero el 60 por ciento de los campos con cultivos de cobertura tienen el trigo de invierno. Maryland paga a los granjeros una porci\u00f3n de los gastos de plantar los cultivos de cobertura, con remuneraci\u00f3n adicional para los cultivos plantados temprano y los cultivos aparte del trigo.<\/p>\n<p style=\"text-align: justify;\">\u00a0El proyecto piloto permitir\u00e1 al distrito de <strong>conservaci\u00f3n de suelo<\/strong> del condado Talbot a evaluar los campos menos eficaces para planear una implementaci\u00f3n mejorada en el pr\u00f3ximo a\u00f1o.<\/p>\n<p style=\"text-align: justify;\">\u00a0Los cient\u00edficos est\u00e1n desarrollando software para resumir los datos, por condado y por cuenca hidrogr\u00e1fica, para producir informes para los socios en la protecci\u00f3n de la cuenca hidrogr\u00e1fica de la Bah\u00eda de Chesapeake, incluyendo agencias de los condados, del estado y del gobierno federal.<\/p>\n<p style=\"text-align: justify;\">\u00a0Este proyecto es parte de un sistema de proveer informaci\u00f3n \u00fatil para hacer <strong>ajustes en estrategias estatales y federales de implementaci\u00f3n de programas de conservaci\u00f3n de recursos naturales<\/strong>. Con \u00e9xito, este proyecto podr\u00eda ser extendido a cada de los 24 distritos de conservaci\u00f3n de suelo en el estado de Maryland.<br \/>\nLea m\u00e1s sobre esta investigaci\u00f3n en la revista &#8216;Agricultural Research&#8217; de septiembre del 2010, disponible en l\u00ednea en:<br \/>\n<a href=\"http:\/\/www.ars.usda.gov\/is\/AR\/archive\/august10\/cleanup0810.htm\" target=\"_blank\">http:\/\/www.ars.usda.gov\/is\/AR\/archive\/august10\/cleanup0810.htm<\/a><br \/>\n\u00a0<br \/>\n\u00a0<br \/>\nServicio Noticiero, Oficina de Informaci\u00f3n, Servicio de Investigaci\u00f3n Agr\u00edcola<br \/>\nNoticias@ars.usda.gov | www.ars.usda.gov\/noticias<br \/>\nTel\u00e9fono (301) 504-1636 | Fax (301) 504-1486<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #008080;\">Reduciendo el escurrimiento del f\u00f3sforo<\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>\u00a0Servicio Noticiero; del Servicio de Investigaci\u00f3n Agr\u00edcola (ARS siglas en ingl\u00e9s)<br \/>\n<\/strong>Departamento de Agricultura (USDA siglas en ingl\u00e9s); Ann Perry, (301) 504-1628, <a href=\"mailto:ann.perry@ars.usda.gov\">ann.perry@ars.usda.gov<\/a> 9 de agosto de 2010 -Vea esta historia en Internet, junto con fotos y otros art\u00edculos relacionados, en <a href=\"http:\/\/www.ars.usda.gov\/is\/espanol\/pr\">www.ars.usda.gov\/is\/espanol\/pr<\/a>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Un subproducto industrial podr\u00eda ayudar a limpiar el agua de la Bah\u00eda de Chesapeake atrapando algunos de los contaminantes en el escurrimiento de los campos agr\u00edcolas<\/strong>, seg\u00fan un cient\u00edfico del <strong>Servicio de Investigaci\u00f3n Agr\u00edcola (ARS)<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Por muchos a\u00f1os, los granjeros en la llanura costera de la Bah\u00eda de Chesapeake han agregado los desperdicios av\u00edcolas a sus suelos arenosos<\/strong>.<strong> Este fertilizante natural provee nitr\u00f3geno y f\u00f3sforo a los cultivos. Pero el f\u00f3sforo que no es utilizado por las plantas se queda en el suelo, y con el tiempo lixivia a la red inmensa de zanjas de desag\u00fce, y finalmente a la bah\u00eda<\/strong>. Debido a los niveles altos de f\u00f3sforo actualmente en los suelos de la regi\u00f3n, esta descarga continuar\u00e1 a\u00fan si los granjeros dejan de utilizar el <strong>esti\u00e9rcol y los desperdicios av\u00edcolas<\/strong> como fertilizante.<\/p>\n<p style=\"text-align: justify;\">\u00a0Ray Bryant es cient\u00edfico del suelo con el ARS, el cual es la agencia principal de investigaciones cient\u00edficas del Departamento de Agricultura de EE.UU. (USDA por sus siglas en ingl\u00e9s). \u00c9l ha desarrollado <strong>un sistema innovador para mitigar esta descarga excavando una zanja auxiliar paralela a una zanja existente de desag\u00fce. Luego \u00e9l llen\u00f3 la nueva zanja con el yeso sint\u00e9tico, el cual es un subproducto del proceso de limpiar el azufre de las chimeneas de las plantas de energ\u00eda a carb\u00f3n<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Cuando el agua fluy\u00f3 del campo agr\u00edcola a la zanja llena de yeso, el calcio soluble en el yeso \u00abcaptur\u00f3\u00bb el f\u00f3sforo soluble en el agua combinandose con el f\u00f3sforo y formando el fosfato de calcio<\/strong>. Bryant <strong>descubri\u00f3 que la zanja con yeso ten\u00eda la capacidad de tratar todo el escurrimiento de un campo y redujo el f\u00f3sforo soluble en el escurrimiento debajo de la superficie del suelo por lo menos el 50 por ciento<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0Estas<strong> \u00abcortinas\u00bb de yeso pueden durar por 10 a\u00f1os. Luego se pueden excavarlas y utilizar el f\u00f3sforo atrapado como fertilizante. Otro beneficio: Las plantas de energ\u00eda no tienen que pagar para transportar el yeso a un vertedero. Estas zanjas auxiliares, en combinaci\u00f3n con otras pr\u00e1cticas de manejo y conservaci\u00f3n, podr\u00edan ayudar a los granjeros a controlar la lixiviaci\u00f3n del f\u00f3sforo sin alterar<\/strong> las operaciones actuales de producci\u00f3n agr\u00edcola.<\/p>\n<p style=\"text-align: justify;\">\u00a0Bryant trabaja en la Unidad de Investigaci\u00f3n de Sistemas de Pastizales y Manejo de Cuencas Hidrogr\u00e1ficas mantenida por el ARS en University Park, Pensilvania.<br \/>\n\u00a0<br \/>\nLea m\u00e1s sobre esta investigaci\u00f3n y otras para proteger la Bah\u00eda de Chesapeake in la revista &#8216;Agricultural Research&#8217; de agosto del 2010.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.ars.usda.gov\/is\/AR\/archive\/aug10\/bay0810.htm\" target=\"_blank\">http:\/\/www.ars.usda.gov\/is\/AR\/archive\/aug10\/bay0810.htm<\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\u00f3n de aguas, incluyendo las marinas, causando la degradaci\u00f3n de las aguas litorales, as\u00ed como la proliferaci\u00f3n de floraciones algales y puntos muertos. Tal hecho preocupa a las agencias ambientales de numerosos pa\u00edses. Por esta raz\u00f3n, numerosos equipos de investigaci\u00f3n realizan actualmente investigaciones con vistas a mitigar el proceso, en la medida de lo posible. El monitoreo de su concentraci\u00f3n en cuencas de drenaje comienza a extenderse en ciertos pa\u00edses como EE.UU. Hoy os mostraremos dos ejemplos extra\u00eddos del noticiero ARS (USDA) que nos muestran dos v\u00edas\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[594,613,585,617],"tags":[46813,46769,46866,2208,2209,1381],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\u00f3n de aguas, incluyendo las marinas, causando la degradaci\u00f3n de las aguas litorales, as\u00ed como la proliferaci\u00f3n de floraciones algales y puntos muertos. Tal hecho preocupa a las agencias ambientales de numerosos pa\u00edses. Por esta raz\u00f3n, numerosos equipos de investigaci\u00f3n realizan actualmente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\u00f3n de aguas, incluyendo las marinas, causando la degradaci\u00f3n de las aguas litorales, as\u00ed como la proliferaci\u00f3n de floraciones algales y puntos muertos. Tal hecho preocupa a las agencias ambientales de numerosos pa\u00edses. Por esta raz\u00f3n, numerosos equipos de investigaci\u00f3n realizan actualmente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-11-09T10:14:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-11-09T10:14:48+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\u00f3n de aguas, incluyendo las marinas, causando la degradaci\u00f3n de las aguas litorales, as\u00ed como la proliferaci\u00f3n de floraciones algales y puntos muertos. Tal hecho preocupa a las agencias ambientales de numerosos pa\u00edses. Por esta raz\u00f3n, numerosos equipos de investigaci\u00f3n realizan actualmente\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004#blogposting\",\"name\":\"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\\u00f3n de Aguas por el Uso de Fertilizantes - Un Universo invisible bajo nuestros pies\",\"headline\":\"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\\u00f3n de Aguas por el Uso de Fertilizantes\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/804\\\/cultivos-en-cobertera-fuente-sagarpa.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004\\\/#articleImage\"},\"datePublished\":\"2010-11-09T11:14:48+01:00\",\"dateModified\":\"2010-11-09T11:14:48+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004#webpage\"},\"articleSection\":\"Degradaci\\u00f3n de Suelos: Contaminaci\\u00f3n, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n, Procesos Superficiales terrestres: Relieve, Geomorfolog\\u00eda y Cuencas de Drenaje:, contaminaci\\u00f3n de aguas, contaminaci\\u00f3n de suelos, Cultivos en cobertera, ferilizantes, tecnolog\\u00edas de remediaci\\u00f3n, Yeso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"position\":2,\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004#listItem\",\"name\":\"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\\u00f3n de Aguas por el Uso de Fertilizantes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004#listItem\",\"position\":3,\"name\":\"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\\u00f3n de Aguas por el Uso de Fertilizantes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004\",\"name\":\"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\\u00f3n de Aguas por el Uso de Fertilizantes - Un Universo invisible bajo nuestros pies\",\"description\":\"El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\\u00f3n de aguas, incluyendo las marinas, causando la degradaci\\u00f3n de las aguas litorales, as\\u00ed como la proliferaci\\u00f3n de floraciones algales y puntos muertos. Tal hecho preocupa a las agencias ambientales de numerosos pa\\u00edses. Por esta raz\\u00f3n, numerosos equipos de investigaci\\u00f3n realizan actualmente\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/09\\\/137004#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2010-11-09T11:14:48+01:00\",\"dateModified\":\"2010-11-09T11:14:48+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes - Un Universo invisible bajo nuestros pies","description":"El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\u00f3n de aguas, incluyendo las marinas, causando la degradaci\u00f3n de las aguas litorales, as\u00ed como la proliferaci\u00f3n de floraciones algales y puntos muertos. Tal hecho preocupa a las agencias ambientales de numerosos pa\u00edses. Por esta raz\u00f3n, numerosos equipos de investigaci\u00f3n realizan actualmente","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004#blogposting","name":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes - Un Universo invisible bajo nuestros pies","headline":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/804\/cultivos-en-cobertera-fuente-sagarpa.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004\/#articleImage"},"datePublished":"2010-11-09T11:14:48+01:00","dateModified":"2010-11-09T11:14:48+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004#webpage"},"articleSection":"Degradaci\u00f3n de Suelos: Contaminaci\u00f3n, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n, Procesos Superficiales terrestres: Relieve, Geomorfolog\u00eda y Cuencas de Drenaje:, contaminaci\u00f3n de aguas, contaminaci\u00f3n de suelos, Cultivos en cobertera, ferilizantes, tecnolog\u00edas de remediaci\u00f3n, Yeso"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","position":2,"name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004#listItem","name":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004#listItem","position":3,"name":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004","name":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes - Un Universo invisible bajo nuestros pies","description":"El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\u00f3n de aguas, incluyendo las marinas, causando la degradaci\u00f3n de las aguas litorales, as\u00ed como la proliferaci\u00f3n de floraciones algales y puntos muertos. Tal hecho preocupa a las agencias ambientales de numerosos pa\u00edses. Por esta raz\u00f3n, numerosos equipos de investigaci\u00f3n realizan actualmente","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2010-11-09T11:14:48+01:00","dateModified":"2010-11-09T11:14:48+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes - Un Universo invisible bajo nuestros pies","og:description":"El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\u00f3n de aguas, incluyendo las marinas, causando la degradaci\u00f3n de las aguas litorales, as\u00ed como la proliferaci\u00f3n de floraciones algales y puntos muertos. Tal hecho preocupa a las agencias ambientales de numerosos pa\u00edses. Por esta raz\u00f3n, numerosos equipos de investigaci\u00f3n realizan actualmente","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2010-11-09T10:14:48+00:00","article:modified_time":"2010-11-09T10:14:48+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes - Un Universo invisible bajo nuestros pies","twitter:description":"El abusivo uso de fertilizantes es una de las principales fuentes de la poluci\u00f3n de aguas, incluyendo las marinas, causando la degradaci\u00f3n de las aguas litorales, as\u00ed como la proliferaci\u00f3n de floraciones algales y puntos muertos. Tal hecho preocupa a las agencias ambientales de numerosos pa\u00edses. Por esta raz\u00f3n, numerosos equipos de investigaci\u00f3n realizan actualmente","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"137004","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 14:30:20","updated":"2026-05-26 16:26:49","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion\" title=\"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n\">P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion"},{"label":"Cultivos en Cobertera y Cortinas de Yeso para Mitigar la Contaminaci\u00f3n de Aguas por el Uso de Fertilizantes","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/09\/137004"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/137004"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=137004"}],"version-history":[{"count":7,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/137004\/revisions"}],"predecessor-version":[{"id":137360,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/137004\/revisions\/137360"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=137004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=137004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=137004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}