{"id":137382,"date":"2010-11-14T18:55:17","date_gmt":"2010-11-14T17:55:17","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=137382"},"modified":"2010-11-14T18:55:17","modified_gmt":"2010-11-14T17:55:17","slug":"sobre-el-mapa-digital-de-los-suelos-del-mundo-contestando-a-d-g-rossiter-y-a-hartemink","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382","title":{"rendered":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink"},"content":{"rendered":"<p style=\"text-align: justify;\">A lo largo de esto a\u00f1os de andadura en nuestra bit\u00e1cora, los post de los fines de semana versaban sobre temas de inter\u00e9s general, filosof\u00eda y sociolog\u00eda de la ciencia, as\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\u00e9 aplicarme durante las pr\u00f3ximas dos o tres semanas a un tema m\u00e1s espinoso, t\u00e9cnico y doloso. Ya os coment\u00e9 de que iba el asunto en nuestra entrega anterior: \u201c<a title=\"Enlace permanente: Blogs de Ciencia: Los \u00c9xitos y sus Problemas Inherentes\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/06\/137327\">Blogs de Ciencia: Los \u00c9xitos y sus Problemas Inherentes<\/a>\u201d. En el os narraba como <span style=\"color: #3366ff;\"><strong>lo que escribimos en este \u201cblog personal\u201d hab\u00eda molestado seriamente al establishment de la IUSS<\/strong> <\/span>(la sociedad internacional de cient\u00edficos a la que pertenezco), si bien <strong><span style=\"color: #3366ff;\">no se si a t\u00edtulo personal o institucional<\/span><\/strong>. El malestar de estos derivaba del contenido de un post, que ciertamente escrib\u00ed en un tono muy duro, muy pocos d\u00edas antes. M\u00e1s concretamente me refiero a este: <a title=\"Enlace permanente: Presunto Mapa Global Digital de Suelos del Mundo \u201cGlobalSoilMap.net\u201d, buscan informaci\u00f3n Edafol\u00f3gica Desesperadamente\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/12\/136650\">Presunto Mapa Global Digital de Suelos del Mundo \u201cGlobalSoilMap.net\u201d, buscan informaci\u00f3n Edafol\u00f3gica Desesperadamente<\/a>. Como os mencion\u00e9 Hace 8 d\u00edas, existen varios aspectos que deben diferenciarse en la iniciativa <a href=\"http:\/\/www.globalsoilmap.net\/\">GlobalSoilMap.net &#8211; New Digital Soil Map of the World<\/a>. Unos son t\u00e9cnicos, otros pol\u00edticos, algunos sociol\u00f3gicos, y finalmente, \u00bfporqu\u00e9 no decirlo?, tambi\u00e9n de \u00edndole personal. Eso si, <strong><span style=\"color: #3366ff;\">es un honor que este humilde blog de divulgaci\u00f3n cient\u00edfica comienza a tener tal calado mundial<\/span><\/strong>. Como os promet\u00ed, hoy reproduzco el comentario que borr\u00e9 de <a href=\"http:\/\/www.itc.nl\/~rossiter\/index.html\">D. G. Rossiter<\/a> (ITC Holanda) en su d\u00eda, as\u00ed como los mails de Alfred Hartemink (ISRIC, Holanda) y secretario General de la IUSS, as\u00ed como mis replicas a sus cr\u00edticas y\/o acusaciones.<span style=\"color: #3366ff;\"> <strong>En esta entrega tan solo abordaremos los aspectos m\u00e1s t\u00e9cnicos, dejando los restantes para ulteriores post<\/strong><\/span>.<\/p>\n<p style=\"text-align: center;\">\u00a0<span style=\"color: #0000ff;\">\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/152\/juanjo-eje-cafetalero-de-colombia_0.jpg\" alt=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez en el Eje Cafetalero de Colombia\" width=\"505\" height=\"436\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez\u00a0visitando el eje cafetalero de Colombia y pensando que argumentos deb\u00eda utilizar en estos post (supongo, porque no me acuerdo)<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><!--more--><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0And\u00e1bamos descansando por Cuzco (si no recuerdo mal), el <strong><span style=\"color: #3366ff;\">13 de Octubre de 2010 <\/span><span style=\"color: #3366ff;\">cuando en la bandeja de correos recibo el siguiente mail, bastante extra\u00f1o, dicho sea de paso de<\/span> <\/strong>Alfred Hartemink:\u00a0\u00a0 \u00a0\u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0<strong><span style=\"color: #3366ff;\">13 de Octubre de 2010<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0Dear Juan,<\/p>\n<p style=\"text-align: justify;\">Just saw this:<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/12\/136650#comments\" target=\"_blank\">https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/12\/136650#comments<\/a><\/p>\n<p style=\"text-align: justify;\">can you translate it for me? Thanks, Alfred<\/p>\n<p style=\"text-align: justify;\">\u00a0Como pod\u00e9is observar, <strong><span style=\"color: #3366ff;\">me habla de un post que acababa \u201cEl d\u00eda anterior<\/span><\/strong>\u201d. Alfred solicitaba que se lo tradujera al lenguaje del imperio (es decir el<em> suahili<\/em>, como le denominamos en esta bit\u00e1cora).<strong><span style=\"color: #3366ff;\"> Y al entrar me encuentro sorprendido con el duro y descalificador comentario de Rossiter<\/span><\/strong>. Primero,\u00a0fraccionar\u00e9 este \u00faltimo con vistas a dar r\u00e9plica a sus argumentos, para\u00a0luego dej\u00e1roslo\u00a0completo al final de este post. Deb\u00e9is comprender que su espa\u00f1ol no sea muy correcto (como mi ingl\u00e9s, m\u00e1s o menos) ya que no es su lengua materna.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.itc.nl\/~rossiter\/index.html\">D. G. Rossiter<\/a><\/p>\n<p>\u00a0Nuevo comentario en tu entrada #136650 \u00abPresunto Mapa Global Digital de Suelos del Mundo \u201cGlobalSoilMap.net\u201d, buscan informaci\u00f3n Edafol\u00f3gica Desesperadamente\u00bb<br \/>\nAutor : D G Rossiter). Correo electr\u00f3nico : <a href=\"mailto:rossiter@itc.nl\">rossiter@itc.nl<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong><em>Hay tantos errores de concepto, ni hablar del exceso de invectiva, que s\u00f3lo me da tiempo de corregir algunos<\/em><\/strong><em>.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0T\u00edpica entrada en la que no dice nada, intentando <strong><span style=\"color: #3366ff;\">descalificar gratuitamente<\/span><\/strong>. Se trata de una mera declaraci\u00f3n de intenciones: Voy a por ti. \u201c<em>Capisco<\/em>\u201d. Mal comenzamos. <span style=\"color: #3366ff;\"><strong>\u00bfSabr\u00e1 Rossiter lo que son errores de concepto?<\/strong>.<\/span> Pero sigamos.\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<em>En primer lugar, el nombrado proyecto no tiene nada contra levantamiento de suelos nuevo, pero dice que \u00e9sto depende de las instituciones responsable. <span style=\"color: #3366ff;\"><strong>El iniciativo GSM.net es de poner datos disponibles (y muchisimos que han sido olvidados o no usados) en una forma para que los que demanden datos de suelo para hacer correr sus modelos, que hoy en d\u00eda usan datos a veces casi adivinados y siempre de muy baja resoluci\u00f3n, tendr\u00e1n un producto confiable y con sus l\u00edmites de confianze. Se trata de entregar a un grupo importante de usarios de datos el producto que necesitan. Nunca se ha dicho que es un nuevo levantamiento, sino que es poner datos en forma acessible y usable<\/strong>.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\">\u00a0Cabr\u00eda recordar a D G. Rossiter (en adelante D G<\/span>) que <strong><span style=\"color: #3366ff;\">el marketing del programa eleva las expectativas del producto a un nivel excelso<\/span><\/strong>. Ah\u00ed est\u00e1n como testimonio sus propios documentos de Internet, alguno de los cuales os expongo m\u00e1s abajo. Y comenzamos con los problemas conceptuales: \u00bfSe trata pues de un <a href=\"http:\/\/www.alfredhartemink.nl\/PDF\/2010%20-%20GlobalSoilMap.net%20-%20book%20chapter.pdf\">GlobalSoilMap.net \u2013 A New Digital Soil Map of the World<\/a>? \u00bfSe puede decir que nos encontramos ante un\u00a0 genuino nuevo producto? \u00bfErrores de concepto? Los levantamientos de suelos son las tareas realizadas generalmente con vistas a elaborar una nueva cartograf\u00eda. El Actual Mapa Digitalizado de los Suelos de Europa se basa en modificaciones y posibles mejoras de los anteriores, pero en ning\u00fan caso es nuevo. <strong><span style=\"color: #3366ff;\">\u00bfError de concepto? \u00bfMejorado es lo mismo que nuevo? \u00a1No!<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0Tanto D G. como Alfred alegar\u00e1n que \u201cel digital Soil Mapping\u201d (cartograf\u00eda digital de suelos, en adelante DSM), como ya lo hace este \u00faltimo en un\u00a0 documento que \u201c<em>A digitized map does not constitute a digital map<\/em>\u201d. Soslayare abundar sobre el juego de palabras para, efectivamente se\u00f1alar, que no es lo mismo digitalizar un mapa (que tampoco es el caso de Europa) que aplicar las nuevas tecnolog\u00edas con vistas a mejorar productos previos, ya sean individualmente o mezclando varios. <strong><span style=\"color: #3366ff;\">Por mucho que se pretenda vender el uso de las\u00a0 nuevas tecnolog\u00edas como trabajar en una disciplina novel no es as\u00ed. Eso si es un error de concepto<\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0Defendimos en nuestro post: \u201c<a title=\"Enlace permanente: Cartograf\u00eda Digital de Suelos y Cartograf\u00eda Predictiva de Suelos (Digital Soil Mapping and Predictive Soil Mapping)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/11\/114284\">Cartograf\u00eda Digital de Suelos y Cartograf\u00eda Predictiva de Suelos (Digital Soil Mapping and Predictive Soil Mapping)<\/a>\u201d <strong><span style=\"color: #3366ff;\">que bajo tal vocablo no se esconde una nueva disciplina, sino la aplicaci\u00f3n de nuevos instrumentos a la cartograf\u00eda, geograf\u00eda y an\u00e1lisis espaciales de suelos<\/span><\/strong>. Se tratar\u00eda de<strong> <span style=\"color: #3366ff;\">un progreso normal de estos \u00e1mbitos del conocimiento edafol\u00f3gico, a no ser que<\/span><\/strong>, \u201ccon raz\u00f3n o sin ella\u201d, se incluya ineludiblemente a la geoestad\u00edstica en el paquete, as\u00ed como \u00a0otras herramientas matem\u00e1ticas que actualmente defienden los miembros de la comisi\u00f3n de edafolog\u00eda de la IUSS (pero no todos los edaf\u00f3logos matem\u00e1ticos, ni mucho menos), frente a otras posibles alternativas. Y al hacerlo llegamos<strong><span style=\"color: #3366ff;\"> al \u201csue\u00f1o de Alex McBratney\u201d: sustituir los mapas tipol\u00f3gicos de suelos por los de propiedades de los mismos. Pero tal reemplazo adolece de algunas ventajas y serios inconvenientes<\/span><\/strong>. Debido a que ya hemos abundado sobre este asunto en diferentes ocasiones, no nos repetiremos. El meollo de la cuesti\u00f3n reside en: <span style=\"color: #3366ff;\"><strong>\u00bfse pueden llevar a cabo mejoras de los mapas antiguos mediante DSM; sin requerir necesariamente el uso de la geoestad\u00edstica?. \u00bfQui\u00e9n a dicho que es imperativo?<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0Hemos defendido en otros post, como en este: \u201c<a title=\"Enlace permanente: Agricultura de Precisi\u00f3n  y Suelos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/09\/114118\">Agricultura de Precisi\u00f3n y Suelos<\/a>\u201d que las herramientas geoestad\u00edsticas son muy interesantes para an\u00e1lisis a escala detalladas, pero que no lo son a otras m\u00e1s groseras. Se trata de un tema que bien podemos discutir. Todo depende de para qu\u00e9 deseemos el nuevo producto, no de sus bondades intr\u00ednsecas.<\/p>\n<p style=\"text-align: justify;\">\u00a0Alega D G que el objetivo del <a href=\"http:\/\/www.alfredhartemink.nl\/PDF\/2010%20-%20GlobalSoilMap.net%20-%20book%20chapter.pdf\">GlobalSoilMap.net \u2013 A New Digital Soil Map of the World<\/a> consiste en <span style=\"color: #3366ff;\"><strong>poner a disposici\u00f3n del p\u00fablico datos rescatados o no accesibles con anterioridad a los potenciales usuarios. Pero al hacerlo se corre un gran peligro: (i)<\/strong> <\/span>Las determinaciones de un mismo dato (digamos por ejemplo el carbono del suelo, o el complejo de cambio) mediante distintas metodolog\u00edas da lugar a resultados dispares; <strong><span style=\"color: #3366ff;\">(ii)<\/span><\/strong> como se compar\u00f3 en un proyecto europeo sobre suelos forestales, incluso utilizando los mismos protocolos, distintos laboratorios obten\u00edan resultados que resultaban ser francamente preocupantes por su \u201cvariabilidad\u201d. As\u00ed pues cabe preguntarse: \u00bfno estamos a\u00f1adiendo ruido o incertidumbre? Pero hay m\u00e1s, mucho m\u00e1s.<\/p>\n<p style=\"text-align: justify;\">\u00a0Uno de las herramientas de la geoestad\u00edstica consiste en ofrecer datos de variables dif\u00edciles de estimar mediante el uso de otras m\u00e1s simples y unos tes estad\u00edsticos que las relacionan con una peque\u00f1a muestra de las segundas. De este modo se obtienen las denominadas <strong><span style=\"color: #3366ff;\">funciones de edafotransferencia<\/span><\/strong> (habr\u00eda un d\u00eda que explicar el origen de este t\u00e9rmino, que no es propio de los expertos en ciencias del suelo, salvo a\u00f1adir \u201cedafo\u201d a lo denominado previamente en otras disciplinas funciones de transferencia) cuyos resultados (inferencia de las propiedades de compleja estima desde las senillas) se extrapolan a otras \u00e1reas de caracter\u00edsticas ambientales \u201cparecidas\u201d en la que no existe informaci\u00f3n de las variables dif\u00edciles de cuantificar. De nuevo, el problema deviene que <strong><span style=\"color: #3366ff;\">\u201c<\/span><span style=\"color: #3366ff;\"><span style=\"color: #3366ff;\">fallan<\/span> con demasiada frecuencia\u201d fuera del \u00e1mbito en donde fueron testadas<\/span><\/strong>. D G una cosa es publicar papers y otra enfrentarse a la cruda realidad de abordar estudios globales. Resumiendo,<strong> <span style=\"color: #3366ff;\">m\u00e1s ruido, se mire por don de se mire<\/span><\/strong>. Lo mismo puede alegarse de los <strong><span style=\"color: #3366ff;\">sensores (muchos de ellos satelitales): o se calibran en las \u00e1reas de estudio con buenos datos de campo o generamos aun m\u00e1s ruido en la Caja de Pan<\/span><span style=\"color: #3366ff;\">dora<\/span><\/strong> <strong><span style=\"color: #3366ff;\">en la que puede terminar convirti\u00e9ndose el GSM<\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0Resumiendo una vez m\u00e1s,<span style=\"color: #3366ff;\"> <strong>sin nuevos datos a escala global, que es lo que necesitamos, no puede decirse que disponemos de producto novedoso, sino de un producto mejorado (en el mejor de los casos)<\/strong>,<\/span> si es que no resulta ser tan mejorar la apariencia (el conteninente prima sobre el contenido). Me gustar\u00eda pensar que el producto final, al menos atesore ciertas ventajas fehacientes. Pero si observamos tan solo lo hasta aqu\u00ed comentado, no es extra\u00f1o personalmente que albergue dudas. Pero sigamos con las opiniones de D G.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><em><span style=\"color: #3366ff;\">Incluso, el proyecto se base en muchas investigaciones que han mostrado que se puede mejorar levantamientos existentes. Estuve contratado en un proyecto de un gran \u00abproveedor\u00bb de mapas de suelos de un pa\u00eds latinoamer\u00edcano que no nombro; mi tarea era de evaluar sus productos. Result\u00f3 que la geometr\u00eda de los pol\u00edgonos era mal\u00edssimo<\/span><\/em><\/strong><em>, que se pudo ver por sobreponer el modelo de terreno (DTM) del STRM. Sin embargo, se pudo ver d\u00f3nde se deb\u00eda trasladar las l\u00edneas para que se cuadren. <strong><span style=\"color: #3366ff;\">As\u00ed se pudo hacer del mapa viejo un mapa nuevo y ahora listo para incorporarse en el SIG<\/span><\/strong>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\">\u00a0<strong>Aqu\u00ed D G mezcla lo obvio con una soberana torpeza<\/strong>. <strong>Resulta trivial que<\/strong><\/span> los modelos digitales del terreno ayudan sobremanera a mejorar la calidad de las cartograf\u00edas (especialmente la delimitaci\u00f3n de los pol\u00edgonos). Dudo que alguien discuta un hecho tan palmario. El problema resid\u00eda en que en muchos pa\u00edses o no exist\u00edan tales coberturas o eran excesivamente caras a la hora de llevar a cabo problemas de territorios extensos. Con el tiempo, tales problemas est\u00e1n desapareciendo de muchos pa\u00edses y su uso es inexcusable. Totalmente de acuerdo. <strong><span style=\"color: #3366ff;\">Pero tal hecho en si mismo no es DSM<\/span><\/strong>, conforme a los dictados de los propios edafometras. Se trata de sobreponer dos capas de informaci\u00f3n con la ayuda de GIS.<\/p>\n<p style=\"text-align: justify;\">\u00a0<span style=\"color: #3366ff;\"><strong>Sin embargo, D G patina estepitosamente al tirar la piedra y esconder la mano cuando escribe<\/strong>: \u201c<\/span><strong><em><span style=\"color: #3366ff;\">un pa\u00eds latinoamer\u00edcano que no nombro; mi tarea era de evaluar sus productos. Result\u00f3 que la geometr\u00eda de los pol\u00edgonos era mal\u00edsimo\u2026\u201d<\/span> <\/em><\/strong>Como leer\u00e9is m\u00e1s abajo, Rossiter me acusa de \u201c<em>Me ofendi\u00f3 sus comentarios personales dirigido a personas que no se atreve mencionar\u201d.<\/em> Sin embargo el se permite hacer lo mismo. <strong><span style=\"color: #3366ff;\">\u00bfA que pa\u00eds se refiere? \u00bfNo quiera quedar mal con ellos, que se ofendan?. Pues bien usted me pidi\u00f3 un nombre que si me atravo a mencionar, como lo hice en el post anterior<\/span><\/strong> (\u201c<a title=\"Enlace permanente: Blogs de Ciencia: Los \u00c9xitos y sus Problemas Inherentes\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/06\/137327\">Blogs de Ciencia: Los \u00c9xitos y sus Problemas Inherentes<\/a>\u201d). <strong><span style=\"color: #3366ff;\">Y lo repito otra vez: Alex McBratney<\/span><\/strong> al que respeto como cient\u00edfico pero con el que<strong> <span style=\"color: #3366ff;\">no comparto muchas de sus opiniones y maneras de prodecer \u00bfEntendido?<\/span><\/strong><span style=\"color: #3366ff;\">.<strong> Ahora le conmino a usted a que tenga el mismo valor y diga p\u00fablicamente a que pa\u00eds se refer\u00eda de Latinoam\u00e9rica<\/strong>. <strong>Si no el cobarde ser\u00e1 usted y el \u201cofendido yo\u201d<\/strong><\/span>. Eso aqu\u00ed lo llamamos<strong> <span style=\"color: #3366ff;\">\u201ctirar la piedra y esconder la mano\u201d. No me de lecciones de honestidad, \u00a1por favor!<\/span><\/strong><span style=\"color: #3366ff;\">.<\/span> Pero continuemos con los comentarios de D G.<\/p>\n<p style=\"text-align: justify;\"><strong><em><span style=\"color: #3366ff;\">Las t\u00e9cnicas semi-automatizados pueden hacer a\u00fan m\u00e1s: una vez entendido la relaci\u00f3n suelo-paisaje (de los levantamientos existentes y s\u00ed, la experiencia del edaf\u00f3logo)<\/span><\/em><\/strong><em><span style=\"color: #3366ff;\">,<\/span> se puede aplicar el modelo a dividir el paisjae basado en <strong><span style=\"color: #3366ff;\">DTM y classificaci\u00f3n del uso de suleo (sensores remotos) para \u00f3 extrapolar en \u00e1reas no levantados \u00f3 dividir asociaciones en<\/span> <span style=\"color: #3366ff;\">sus components<\/span><\/strong> (\u00abdeconvoluci\u00f3n\u00bb), as\u00ed produciendo nueva informaci\u00f3n basado en el viejo. Ver p.ej. SoLIM de Prof. Zhu.<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0Vaya por Dios, Sr. Rossiter, aqu\u00ed si los edaf\u00f3logos de campo tienen algo que decir. \u00a1Menos mal! \u00a1Muchas gracias! Ahora bien, <strong><span style=\"color: #3366ff;\">el procedimiento que usted comenta se ha utilizado siempre, con mayor o menor acierto. Pero como usted dice se trata de la \u201csemiatomatizaci\u00f3n\u201d de tareas que con antig\u00fcedad se realizaban manualmente<\/span><\/strong>. Hablamos de <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/15\/13724\">la paradoja tecnol\u00f3gica<\/a><strong> <span style=\"color: #3366ff;\">de<\/span><\/strong> un investigador al que usted con toda seguridad admira, <span style=\"color: #3366ff;\"><strong>Burrough<\/strong>. <strong>Los modelos suelo-paisaje son fundamentales en los relevamientos (realizaci\u00f3n de inventarios) de suelos<\/strong><\/span>. La imaginer\u00eda satelital ni tan siquiera es necesaria cuando se conoce la regi\u00f3n en particular. Pero <span style=\"color: #3366ff;\"><strong>en ausencia de un experto edaf\u00f3logo de campo y buenos datos el producto final no resulta mejor por estar \u201csemiautomatizado\u201d<\/strong>. <strong>Existen edafometras que ingenuamente creen que se puede hacer una buena cartograf\u00eda sin salir al campo<\/strong><\/span>, sentaditos en el laboratorio o despacho. Lo \u00fanico que demuestra con frases que van en tales direcciones es su ignorancia en mataria de edafolog\u00eda. Se trata de un ejemplo parecido al que nos muestran los expertos de c\u00f3digos de barra gen\u00e9ticos dando lecciones a los genuinamente tax\u00f3nomos de lo que es una especie biol\u00f3gica. Estulticia total.\u00a0<\/p>\n<p style=\"text-align: justify;\"><em>Sobre el futuro de ISRIC y su orientaci\u00f3n, lo dejo a ISRIC. Cabe destacar que<strong> <span style=\"color: #3366ff;\">ISRIC no es GSM.net, solo que el sede de GSM.net se encuentra en ISRIC<\/span><\/strong>. Pero <strong><span style=\"color: #3366ff;\">la mayor\u00eda del esfuerzo, por dise\u00f1o, se hace en los nodos, p.ej. EMBRAPA<\/span><\/strong>.<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0D G perm\u00edtame que deje este tema, aun m\u00e1s espinoso que el t\u00e9cnico, para el pr\u00f3ximo post, en donde lo analizaremos detenidamente. Es justamente en estos detalles en donde el GSM resulta m\u00e1s pernicioso. Ya lo veremos. \u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong><em><span style=\"color: #3366ff;\">Me ofendi\u00f3 sus comentarios personales dirigido a personas que no se atreve mencionar. Tambi\u00e9n me ofendi\u00f3 su implicaci\u00f3n que todos que no estemos contra GSM.net somos corderos silenciosos<\/span><\/em><\/strong><em>. Tiene que darle conciencia a muchos de nosotros, no parte del proyecto GSM.net, quienes <strong><span style=\"color: #3366ff;\">sin embargo veen que aquello proyecto tiene grandes posibilidades de revitalizar la demanda para datos de suelos, que en fin dar\u00e1 el impulso pol\u00edtico al nivel nacional para iniciar nuevos levantamientos de campo<\/span><\/strong>.<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<h1 style=\"text-align: justify;\">\u00a0He dicho.<\/h1>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #3366ff;\">Ya le he dado respuesta a la raz\u00f3n de su primera ofensa. He explicitado el nombre. Ahora reitero que<\/span> <span style=\"color: #3366ff;\">debe usted ser igual de franco y responder en que pa\u00eds latinoamericano se hac\u00edan los pol\u00edgonos \u201cmal\u00edsimos\u201d. En caso contrario demostrara la hipocres\u00eda de su comentario<\/span><\/strong><span style=\"color: #3366ff;\">. <strong>Sobre la segunda causa de ofensa<\/strong><\/span>, tan solo se\u00f1alarle que se encuentra exclusivamente en su cabeza. Pero aqu\u00ed si hay disculpa. Aunque escribe en un espa\u00f1ol bastante aceptable, no ha terminado de entender correctamente mi texto. \u201cEl silencio de los corderos\u201d va dirigido a todos aquellos que piensan lo mismo que yo (y son much\u00edsimos), al contrario que usted, pero callan. No les critico. Cada uno vive la ciencia de manera diferente y bajo situaciones distintas. Lo que lamento es que por no meternos en l\u00edos hayamos permitido proyectos \u201crevolucionarios\u201d como el GSM.\u00a0 Eso si <strong><span style=\"color: #3366ff;\">su gloriosa frase final debo reconocer que me ha hecho re\u00edr en m\u00e1s de una vez. \u00a1He dicho! \u00a1Pues vale!, efectivamente lo ha dicho usted, \u00bfy que? \u00bfDebo ponerme a temblar de miedo?<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0Y aun quedan asertos de documentaci\u00f3n del GSM que se me antojan o retorcidos o como m\u00ednimo discutibles. <strong><span style=\"color: #3366ff;\">\u00bfSe pueden llevar a cabo mapas fidedignos m\u00e1s detallados partiendo de otros m\u00e1s groseros con lo argumentado por ambos hasta aqu\u00ed?. Lo dudo<\/span><\/strong> mucho, mucho, mucho.\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0Para finalizar os <strong><span style=\"color: #3366ff;\">expondr\u00e9 el segundo y \u00faltimo lac\u00f3nico mail de Alfred<\/span><\/strong> (con el que reitero que no albergo inquina alguna, al, menos hasta el momento), por cuanto o se expres\u00f3 mal, le entend\u00ed mal o se me antoja fuera de contexto y lugar. Obviamente no le traduje nada al ingl\u00e9s por cuanto se sobradamente que tiene personal a su alrededor para tal fin. Vemos pues su contestaci\u00f3n:<\/p>\n<p style=\"text-align: justify;\">\u00a020 de Octubre de 2010<\/p>\n<p style=\"text-align: justify;\">\u00a0<em>Juanjo,<\/em><em>\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><em>I had your blog translated by a\u00a0native-speaking colleague who was shocked by your use of the language. Indeed, I also noticed no irony<\/em><em>. <strong><span style=\"color: #3366ff;\">I have no doubt that the blog will be more damaging for you than for the project or global soil science<\/span><\/strong><\/em><em>. <\/em><em><\/em><\/p>\n<p style=\"text-align: justify;\"><em>Alfred<\/em><em><\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #3366ff;\">Lamento much\u00edsimo el susodicho estado de shock a causa de un post en mi humilde blog personal. Le puedo asegurar que desconoc\u00eda totalmente sus perniciosos efectos sobre la salud mental de los colegas<\/span><\/strong>. Me tendr\u00e9 que replantear seguir esta iniciativa. Estoy totalmente de acuerdo con usted cuando se\u00f1ala que mi blog me pueda hacer m\u00e1s da\u00f1o a m\u00ed que al <a href=\"http:\/\/www.alfredhartemink.nl\/PDF\/2010%20-%20GlobalSoilMap.net%20-%20book%20chapter.pdf\">GlobalSoilMap.net \u2013 A New Digital Soil Map of the World<\/a>. Ni soy tan ingenuo ni tan pretencioso. <strong><span style=\"color: #3366ff;\">En un blog personal se comenta la actualidad bajo una \u00f3ptica personal<\/span><\/strong>, como su denominaci\u00f3n indica. Sencillamente <strong><span style=\"color: #3366ff;\">se dice lo que uno piensa<\/span><\/strong>. En el mejor de los casos a unos les abrir\u00e1 los ojos, a otros no les gustar\u00e1 y finalmente a otros \u201cal parecer\u201d les sumir\u00e1 en un estado de shock (no es mi intenci\u00f3n). Ahora bien, <strong>que <span style=\"color: #3366ff;\">\u201c Un Universo Invisible\u201d da\u00f1e a la ciencia global del suelo, o que se haga equivaler al GSM con esta \u00faltima, me parece un desatino terrible<\/span><\/strong>. Esta bit\u00e1cora o blog atesora muchos post de divulgaci\u00f3n cient\u00edfica que <strong><span style=\"color: #3366ff;\">leen miles de estudiantes (desde los ocho a\u00f1os) diariamente<\/span><\/strong> (obviamente estos soslayan la lectura de uno como este). <strong><span style=\"color: #3366ff;\">Algunas decenas de j\u00f3venes han dejado constancia de que se han inclinado a elegir la edafolog\u00eda para su especializaci\u00f3n profesional, gracias a los contenidfos que ofrecemos. Sr. Hartemink, usted no puede decir tal barbaridad: \u00bfYo estoy en contra de la edafolog\u00eda y escribo este blog para da\u00f1arla<\/span><span style=\"color: #3366ff;\">?<\/span><\/strong>. En el mejor de los casos ser\u00eda al rev\u00e9s ya que se trata de una actividad altruista, por la que no percivo ni un solo euro. \u00a1Por favor (\u2026\u2026.)!<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\">\u00a0<strong>Finalmente tan solo comentar a Alfred dos temas que debe cuidar<\/strong><\/span>. En primer lugar, <strong><span style=\"color: #3366ff;\">cuando se dirige a un miembro de la IUSS, debe entender que, a partir de ahora, por su cargo, debe explicitar si lo hace como Secretario General, a t\u00edtulo de la Instituci\u00f3n a la que pertenece, como rector de un proyecto (en este caso el DSM) o a t\u00edtulo personal<\/span><\/strong>. De no hacerlo as\u00ed, corre el riesgo que su \u00faltima frase que he comentado se interprete como una amenaza velada. Entiendo que no ha sido su intenci\u00f3n pero (\u2026).<\/p>\n<p style=\"text-align: justify;\">\u00a0Personalmente observo a nivel mundial dos iniciativas mundiales de signo distinto.<strong><span style=\"color: #3366ff;\"> Mientras que<\/span><\/strong>\u00a0 <a href=\"http:\/\/www.alfredhartemink.nl\/PDF\/2010%20-%20GlobalSoilMap.net%20-%20book%20chapter.pdf\">GlobalSoilMap.net \u2013 A New Digital Soil Map of the World<\/a>, <strong><span style=\"color: #3366ff;\">se dedica a suplir con parches, m\u00e1s o menos atinados, la falta de informaci\u00f3n edafol\u00f3gica genuina, a costa de graves da\u00f1os que relatar\u00e9 en el pr\u00f3ximo post, la denominada<\/span><\/strong> <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/zona-critica-terrestre-y-el-futuro-de-la-edafologia\">\u201cEarth Critical Zone\u201d o \u201cZona Cr\u00edtica Terrestre\u201d<\/a>, <strong><span style=\"color: #3366ff;\">intenta avanzar conceptual e instrumentalmente, proponiendo un genuino cambio de paradigma que podr\u00eda cambiar el futuro de la edafolog\u00eda<\/span><\/strong>. \u00a1Una gran diferencia!, \u00bfNo le parece Rossiter?.\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0Continuaremos en nuestro pr\u00f3ximo post hablando de los entresijos pol\u00edticos de esta iniciativa. <span style=\"color: #3366ff;\">\u00bf<strong>Qu\u00e9 est\u00e1 ganando o perdiendo la comunidad de edaf\u00f3logos con iniciativas como la aqu\u00ed debatida? \u00bfQu\u00e9 nos jugamos?<\/strong><\/span>. Espero poder convenceros de que hay mucho en juego,<span style=\"color: #3366ff;\"> <strong>demasiado<\/strong><\/span>.\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\">\u00a0<strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0<strong><span style=\"color: #008080;\">Comentario \u00cdntegro de<\/span><\/strong> <a href=\"http:\/\/www.itc.nl\/~rossiter\/index.html\">D. G. Rossiter<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0Nuevo comentario en tu entrada #136650 \u00abPresunto Mapa Global Digital de Suelos del Mundo \u201cGlobalSoilMap.net\u201d, buscan informaci\u00f3n Edafol\u00f3gica Desesperadamente\u00bb<br \/>\nAutor : D G Rossiter). Correo electr\u00f3nico :&#8230;<\/p>\n<p style=\"text-align: justify;\"><strong>Hay tantos errores de concepto, ni hablar del exceso de invectiva, que s\u00f3lo me da tiempo de corregir algunos<\/strong>.<\/p>\n<p style=\"text-align: justify;\">En primer lugar, el nombrado proyecto no tiene nada contra levantamiento de suelos nuevo, pero dice que \u00e9sto depende de las instituciones responsable. El iniciativo GSM.net es de poner datos disponibles (y muchisimos que han sido olvidados o no usados) en una forma para que los que demanden datos de suelo para hacer correr sus modelos, que hoy en d\u00eda usan datos a veces casi adivinados y siempre de muy baja resoluci\u00f3n, tendr\u00e1n un producto confiable y con sus l\u00edmites de confianze. Se trata de entregar a un grupo importante de usarios de datos el producto que necesitan. Nunca se ha dicho que es un nuevo levantamiento, sino que es poner datos en forma acessible y usable.<\/p>\n<p style=\"text-align: justify;\">\u00a0Incluso, el proyecto se base en muchas investigaciones que han mostrado que se puede mejorar levantamientos existentes. Estuve contratado en un proyecto de un gran \u00abproveedor\u00bb de mapas de suelos de un pa\u00eds latinoamer\u00edcano que no nombro; mi tarea era de evaluar sus productos. Result\u00f3 que la geometr\u00eda de los pol\u00edgonos era mal\u00edssimo, que se pudo ver por sobreponer el modelo de terreno (DTM) del STRM. Sin embargo, se pudo ver d\u00f3nde se deb\u00eda trasladar las l\u00edneas para que se cuadren. As\u00ed se pudo hacer del mapa viejo un mapa nuevo y ahora listo para incorporarse en el SIG.<\/p>\n<p style=\"text-align: justify;\">\u00a0Las t\u00e9cnicas semi-automatizados pueden hacer a\u00fan m\u00e1s: una vez entendido la relaci\u00f3n suelo-paisaje (de los levantamientos existentes y s\u00ed, la experiencia del edaf\u00f3logo), se puede aplicar el modelo a dividir el paisjae basado en DTM y classificaci\u00f3n del uso de suleo (sensores remotos) para \u00f3 extrapolar en \u00e1reas no levantados \u00f3 dividir asociaciones en sus components (\u00abdeconvoluci\u00f3n\u00bb), as\u00ed produciendo nueva informaci\u00f3n basado en el viejo. Ver p.ej. SoLIM de Prof. Zhu.<\/p>\n<p style=\"text-align: justify;\">\u00a0Sobre el futuro de ISRIC y su orientaci\u00f3n, lo dejo a ISRIC. Cabe destacar que ISRIC no es GSM.net, solo que el sede de GSM.net se encuentra en ISRIC. Pero la mayor\u00eda del esfuerzo, por dise\u00f1o, se hace en los nodos, p.ej. EMBRAPA.<\/p>\n<p style=\"text-align: justify;\">\u00a0Me ofendi\u00f3 sus comentarios personales dirigido a personas que no se atreve mencionar. Tambi\u00e9n me ofendi\u00f3 su implicaci\u00f3n que todos que no estemos contra GSM.net somos corderos silenciosos. Tiene que darle conciencia a muchos de nosotros, no parte del proyecto GSM.net, quienes sin embargo veen que aquello proyecto tiene grandes posibilidades de revitalizar la demanda para datos de suelos, que en fin dar\u00e1 el impulso pol\u00edtico al nivel nacional para iniciar nuevos levantamientos de campo.<\/p>\n<h1 style=\"text-align: justify;\">\u00a0<br \/>\nHe dicho.<\/h1>\n<p style=\"text-align: justify;\">\u00a0\u00a0<strong><span style=\"color: #008080;\">Informaci\u00f3n Adicional<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0<a href=\"http:\/\/www.iisd.ca\/mea-l\/guestarticle71.html\">GlobalSoilMap.net \u2013 A New Digital Soil Map of the World &#8211; Guest &#8230;<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.alfredhartemink.nl\/PDF\/2010%20-%20GlobalSoilMap.net%20-%20book%20chapter.pdf\">GlobalSoilMap.net \u2013 A New Digital Soil Map of the World<\/a> (pdf de AFMED Hartemink)<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>A lo largo de esto a\u00f1os de andadura en nuestra bit\u00e1cora, los post de los fines de semana versaban sobre temas de inter\u00e9s general, filosof\u00eda y sociolog\u00eda de la ciencia, as\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\u00e9 aplicarme durante las pr\u00f3ximas dos o tres semanas a un tema m\u00e1s espinoso, t\u00e9cnico y doloso. Ya os coment\u00e9 de que iba el asunto en nuestra entrega anterior: \u201cBlogs de Ciencia: Los \u00c9xitos y sus Problemas Inherentes\u201d. En el os narraba como lo que escribimos en este \u201cblog personal\u201d hab\u00eda molestado seriamente al establishment de la IUSS (la\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[597,604,587,611],"tags":[2555,2554],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"A lo largo de esto a\u00f1os de andadura en nuestra bit\u00e1cora, los post de los fines de semana versaban sobre temas de inter\u00e9s general, filosof\u00eda y sociolog\u00eda de la ciencia, as\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\u00e9 aplicarme durante las pr\u00f3ximas dos o tres semanas a un tema m\u00e1s espinoso,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"A lo largo de esto a\u00f1os de andadura en nuestra bit\u00e1cora, los post de los fines de semana versaban sobre temas de inter\u00e9s general, filosof\u00eda y sociolog\u00eda de la ciencia, as\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\u00e9 aplicarme durante las pr\u00f3ximas dos o tres semanas a un tema m\u00e1s espinoso,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-11-14T17:55:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-11-14T17:55:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A lo largo de esto a\u00f1os de andadura en nuestra bit\u00e1cora, los post de los fines de semana versaban sobre temas de inter\u00e9s general, filosof\u00eda y sociolog\u00eda de la ciencia, as\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\u00e9 aplicarme durante las pr\u00f3ximas dos o tres semanas a un tema m\u00e1s espinoso,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382#blogposting\",\"name\":\"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink - Un Universo invisible bajo nuestros pies\",\"headline\":\"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/152\\\/juanjo-eje-cafetalero-de-colombia_0.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382\\\/#articleImage\"},\"datePublished\":\"2010-11-14T18:55:17+01:00\",\"dateModified\":\"2010-11-14T18:55:17+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":4,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382#webpage\"},\"articleSection\":\"Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, La Crisis de la Edafolog\\u00eda, Zona Cr\\u00edtica Terrestre y El Futuro de la Edafolog\\u00eda, \\u00bfNuevo Mapa Digital de los Suelos del Mundo?, New Digital Soil Map of the World\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"name\":\"La Crisis de la Edafolog\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"position\":2,\"name\":\"La Crisis de la Edafolog\\u00eda\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382#listItem\",\"name\":\"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382#listItem\",\"position\":3,\"name\":\"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"name\":\"La Crisis de la Edafolog\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382\",\"name\":\"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink - Un Universo invisible bajo nuestros pies\",\"description\":\"A lo largo de esto a\\u00f1os de andadura en nuestra bit\\u00e1cora, los post de los fines de semana versaban sobre temas de inter\\u00e9s general, filosof\\u00eda y sociolog\\u00eda de la ciencia, as\\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\\u00e9 aplicarme durante las pr\\u00f3ximas dos o tres semanas a un tema m\\u00e1s espinoso,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2010\\\/11\\\/14\\\/137382#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2010-11-14T18:55:17+01:00\",\"dateModified\":\"2010-11-14T18:55:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink - Un Universo invisible bajo nuestros pies","description":"A lo largo de esto a\u00f1os de andadura en nuestra bit\u00e1cora, los post de los fines de semana versaban sobre temas de inter\u00e9s general, filosof\u00eda y sociolog\u00eda de la ciencia, as\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\u00e9 aplicarme durante las pr\u00f3ximas dos o tres semanas a un tema m\u00e1s espinoso,","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382#blogposting","name":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink - Un Universo invisible bajo nuestros pies","headline":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/152\/juanjo-eje-cafetalero-de-colombia_0.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382\/#articleImage"},"datePublished":"2010-11-14T18:55:17+01:00","dateModified":"2010-11-14T18:55:17+01:00","inLanguage":"es-ES","commentCount":4,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382#webpage"},"articleSection":"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Geograf\u00eda de Suelos y Megaedafolog\u00eda, La Crisis de la Edafolog\u00eda, Zona Cr\u00edtica Terrestre y El Futuro de la Edafolog\u00eda, \u00bfNuevo Mapa Digital de los Suelos del Mundo?, New Digital Soil Map of the World"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","name":"La Crisis de la Edafolog\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","position":2,"name":"La Crisis de la Edafolog\u00eda","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382#listItem","name":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382#listItem","position":3,"name":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","name":"La Crisis de la Edafolog\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382","name":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink - Un Universo invisible bajo nuestros pies","description":"A lo largo de esto a\u00f1os de andadura en nuestra bit\u00e1cora, los post de los fines de semana versaban sobre temas de inter\u00e9s general, filosof\u00eda y sociolog\u00eda de la ciencia, as\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\u00e9 aplicarme durante las pr\u00f3ximas dos o tres semanas a un tema m\u00e1s espinoso,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2010-11-14T18:55:17+01:00","dateModified":"2010-11-14T18:55:17+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink - Un Universo invisible bajo nuestros pies","og:description":"A lo largo de esto a\u00f1os de andadura en nuestra bit\u00e1cora, los post de los fines de semana versaban sobre temas de inter\u00e9s general, filosof\u00eda y sociolog\u00eda de la ciencia, as\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\u00e9 aplicarme durante las pr\u00f3ximas dos o tres semanas a un tema m\u00e1s espinoso,","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2010-11-14T17:55:17+00:00","article:modified_time":"2010-11-14T17:55:17+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink - Un Universo invisible bajo nuestros pies","twitter:description":"A lo largo de esto a\u00f1os de andadura en nuestra bit\u00e1cora, los post de los fines de semana versaban sobre temas de inter\u00e9s general, filosof\u00eda y sociolog\u00eda de la ciencia, as\u00ed como de otros afines. Me resultaba un placer escribirlos. Desgraciadamente, deber\u00e9 aplicarme durante las pr\u00f3ximas dos o tres semanas a un tema m\u00e1s espinoso,","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"137382","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 15:49:43","updated":"2026-05-26 16:27:51","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia\" title=\"La Crisis de la Edafolog\u00eda\">La Crisis de la Edafolog\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"La Crisis de la Edafolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia"},{"label":"Sobre el Mapa Digital de los Suelos del Mundo: Contestando a D. G. Rossiter y A. Hartemink","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/14\/137382"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/137382"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=137382"}],"version-history":[{"count":13,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/137382\/revisions"}],"predecessor-version":[{"id":137395,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/137382\/revisions\/137395"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=137382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=137382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=137382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}