{"id":137981,"date":"2011-05-17T10:45:04","date_gmt":"2011-05-17T09:45:04","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=137981"},"modified":"2011-05-17T10:45:04","modified_gmt":"2011-05-17T09:45:04","slug":"conservacion-de-suelos-fundacion-de-una-ciencia-y-su-reliquia-bibliografica","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981","title":{"rendered":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica"},"content":{"rendered":"<p style=\"text-align: justify;\">Cuando uno busca los or\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, <strong><span style=\"color: #3366ff;\">los albores de las disciplinas cient\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \u00bfC\u00f3mo se origin\u00f3 la conservaci\u00f3n de suelos? \u00bfA quien se le atribuye el trabajo seminal?<\/span><\/strong> A menudo, parece ser que, <strong><span style=\"color: #3366ff;\">es dif\u00edcil ser objetivo. Los nacionalismos entrar en juego<\/span><\/strong>, politizando estos asuntos hasta l\u00edmites nauseabundos. Sin embargo, con independencia, de estos temas, me <strong><span style=\"color: #3366ff;\">he topado en Internet con un libreto de 1928, que para muchos colegas resulta ser la\u00a0 publicaci\u00f3n seminal que dio lugar<\/span><\/strong> a esa rama de las ciencias aplicadas a la que denominamos <span style=\"color: #3366ff;\"><strong>\u201cconservaci\u00f3n de suelos\u201d. Una verdadera joya<\/strong>.<span style=\"color: #333333;\"> De hecho, soslayando la cuesti\u00f3n de la <\/span><strong>presunta paternidad<\/strong><\/span> que hoy en d\u00eda se le atribuye en estos temas al norteamericano <a href=\"http:\/\/en.wikipedia.org\/wiki\/Hugh_Hammond_Bennett\">Hugh Hammond Bennett<\/a> (April 15, 1881 \u2013 July 7, 1960), no cabe duda que<span style=\"color: #3366ff;\"> <strong>topamos con un trabajo visionario y un escrito asombrosamente vigente<\/strong><\/span>. La USDA ha tenido a bien ponerlo a disposici\u00f3n de todos en Internet. Abajo os ofrezco el enlace.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/158\/bennett-1928.jpg\" alt=\"bennett-1928\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">Portada de la publicaci\u00f3n de Bennett. Fuente:<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"> <\/span><a href=\"http:\/\/www.historycooperative.org\/journals\/ht\/41.1\/smith.html\">Saving the Dust Bowl: \u00abBig Hugh\u00bb Bennett&#8217;s Triumph over Tragedy by Rebecca Smith, Fuente: The Story Teacher<\/a><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">All\u00e1 <strong><span style=\"color: #3366ff;\">por los a\u00f1os 1920<\/span><\/strong>, <a href=\"http:\/\/en.wikipedia.org\/wiki\/Hugh_Hammond_Bennett\">Hugh Hammond Bennett <\/a>comenz\u00f3 a dar la lata, tanto a los pol\u00edticos como al p\u00fablico en general, tras <strong><span style=\"color: #3366ff;\">observar reiteradamente la degradaci\u00f3n de suelos que sufr\u00eda buena parte del territorio americano debido a las malas pr\u00e1cticas agropecuarias de los colonos. Y result\u00f3 ser un visionario<\/span><\/strong>, como analizaremos en otro post. Por aquellos tiempos no hab\u00eda lugar al uso intensivo de agroqu\u00edmicos, por lo que <strong><span style=\"color: #3366ff;\">la principal amenaza resultaba ser\u00a0 la erosi\u00f3n<\/span><\/strong>. Las T\u00e9cnicas que recomendaba Bennett siguen siendo vigentes en muchos casos (laboreo de contorno, cultivos en franjas, terrazas, etc.etc.). Os recomiendo v\u00edvidamente su lectura, ya que atesora poco m\u00e1s de 40 p\u00e1ginas. Despu\u00e9s, <strong><span style=\"color: #3366ff;\">recapacitar si hemos progresado mucho o poco desde los \u201cpresuntos albores\u201d de la disciplina a la que hoy denominamos conservaci\u00f3n de suelos<\/span><\/strong>.<\/p>\n<p>La publicaci\u00f3n en cuesti\u00f3n resulta ser la siguiente:<\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #008000;\">Bennet, H.H., Chapline, W.R. 1928. Soil erosion a nNanional Menace.USDA Circular, N\u00ba 33. United States Government Printing Office Washington D.C. April 1928. 36 pp<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"> <strong>Pod\u00e9is baj\u00e1rosla de Internet siguiendo las directrices que os muestro al final del post. A\u00f1os despu\u00e9s, ya<\/strong> <\/span>como autor en solitario, utilizar\u00eda el mismo t\u00edtulo en otra publicaci\u00f3n, de la cual desconozco si es una mera r\u00e9plica de los contenidos del trabajo precedente, o si por el contrario atesora otros nuevos. Me refiero m\u00e1s concretamente a esta:<\/p>\n<p><em><span style=\"color: #008000;\">Bennett, H.H. 1934. Soil erosion &#8211; A national menace. The Scientific Monthly 39(5):385-404.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Pero ya <span style=\"color: #3366ff;\"><strong>retornaremos a este tema m\u00e1s adelante, por cuanto lo ocurrido entre 1928 y principios de los a\u00f1os 40 resulta ser apasionante y dram\u00e1tico<\/strong> <\/span>a un mismo tiempo.<strong> <span style=\"color: #3366ff;\">Y Bennett, adem\u00e1s de visionario,\u00a0 estuvo en el lugar adecuado, el momento adecuado y con la idea adecuada, al margen de que la fortuna travi\u00e9samente le sonr\u00edo en los aspectos m\u00e1s pol\u00edticamente aviesos<\/span><\/strong> de lo que ocurri\u00f3 por aqu\u00e9l entonces.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"> <strong>Sin embargo cabe recordar que las pr\u00e1cticas emp\u00edricas de conservaci\u00f3n de suelos se remontan milenios atr\u00e1s<\/strong><\/span>. Recordemos que numerosos <strong><span style=\"color: #3366ff;\">pueblos ind\u00edgenas<\/span><\/strong> mostraron un<span style=\"color: #3366ff;\"> <strong>gran ingenio<\/strong><\/span> con vistas a evitar y paliar la erosi\u00f3n de sus paisajes agrarios, como os hemos mostrado reiteradamente en los post que alberga nuestra categor\u00eda: <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/etnoedafologia-y-conocimiento-campesino\">Etnoedafolog\u00eda y Conocimiento Campesino<\/a>.<\/p>\n<p><span style=\"color: #008080;\"><strong><em>Continuar\u00e1\u2026\u2026\u2026\u2026..<\/em><\/strong><strong><\/strong><\/span><\/p>\n<p><span style=\"color: #008000;\"><strong> <\/strong><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #808000;\">Para Bajarse la Publicaci\u00f3n<\/span><\/strong>:<\/p>\n<p style=\"text-align: justify;\">Desconozco las razones por las cuales, al menos desde mi PC, no puedo enlazar bien el pdf del libreto desde dentro del sistema de bit\u00e1coras, tanto m\u00e1s cuando parece ser un servidor de la USDA y el manuscrito se encuentra en acceso abierto. <strong><span style=\"color: #3366ff;\">Abajo os escribo la direcci\u00f3n fragmentada. Tan solo deb\u00e9is eliminar los espacios y pegar la primera y la segunda l\u00ednea, con vistas a reconstruir la original y a\u00f1adirlo a b\u00fasquedas, no a la URL<\/span><\/strong>. Tener paciencia. Probarlo ya que funciona y merece la pena. Espero no cometer ningun delito, ya que as\u00ed me apereci\u00f3 en las b\u00fasquedas.<\/p>\n<p>ftp:\/\/ ftp-fc.sc.egov.usda.gov\/ WY\/PAS\/<\/p>\n<p>Soil_Erosion_A_National_Menace1928. pdf<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Cuando uno busca los or\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, los albores de las disciplinas cient\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \u00bfC\u00f3mo se origin\u00f3 la conservaci\u00f3n de suelos? \u00bfA quien se le atribuye el trabajo seminal? A menudo, parece ser que, es dif\u00edcil ser objetivo. Los nacionalismos entrar en juego, politizando estos asuntos hasta l\u00edmites nauseabundos. Sin embargo, con independencia, de estos temas, me he topado en Internet con un libreto de 1928, que para muchos colegas resulta ser la\u00a0 publicaci\u00f3n seminal que dio lugar a esa rama de las ciencias aplicadas\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[609,591,597,585],"tags":[2961,46966,46842,2962,46967],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cuando uno busca los or\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, los albores de las disciplinas cient\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \u00bfC\u00f3mo se origin\u00f3 la conservaci\u00f3n de suelos? \u00bfA quien se le atribuye el trabajo seminal? A menudo, parece ser que, es dif\u00edcil ser objetivo. Los nacionalismos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Cuando uno busca los or\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, los albores de las disciplinas cient\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \u00bfC\u00f3mo se origin\u00f3 la conservaci\u00f3n de suelos? \u00bfA quien se le atribuye el trabajo seminal? A menudo, parece ser que, es dif\u00edcil ser objetivo. Los nacionalismos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-05-17T09:45:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-05-17T09:45:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cuando uno busca los or\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, los albores de las disciplinas cient\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \u00bfC\u00f3mo se origin\u00f3 la conservaci\u00f3n de suelos? \u00bfA quien se le atribuye el trabajo seminal? A menudo, parece ser que, es dif\u00edcil ser objetivo. Los nacionalismos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981#blogposting\",\"name\":\"Conservaci\\u00f3n de Suelos: Fundaci\\u00f3n de una Ciencia y su Reliquia Bibliogr\\u00e1fica - Un Universo invisible bajo nuestros pies\",\"headline\":\"Conservaci\\u00f3n de Suelos: Fundaci\\u00f3n de una Ciencia y su Reliquia Bibliogr\\u00e1fica\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/158\\\/bennett-1928.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981\\\/#articleImage\"},\"datePublished\":\"2011-05-17T10:45:04+01:00\",\"dateModified\":\"2011-05-17T10:45:04+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981#webpage\"},\"articleSection\":\"Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, Edafolog\\u00eda y Pol\\u00edtica, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n, art\\u00edculo seminal, Conservaci\\u00f3n de Suelos, erosi\\u00f3n de suelos, fundaci\\u00f3n de una ciencia, Hugh Hammond Bennett\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"position\":2,\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981#listItem\",\"name\":\"Conservaci\\u00f3n de Suelos: Fundaci\\u00f3n de una Ciencia y su Reliquia Bibliogr\\u00e1fica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981#listItem\",\"position\":3,\"name\":\"Conservaci\\u00f3n de Suelos: Fundaci\\u00f3n de una Ciencia y su Reliquia Bibliogr\\u00e1fica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981\",\"name\":\"Conservaci\\u00f3n de Suelos: Fundaci\\u00f3n de una Ciencia y su Reliquia Bibliogr\\u00e1fica - Un Universo invisible bajo nuestros pies\",\"description\":\"Cuando uno busca los or\\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, los albores de las disciplinas cient\\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \\u00bfC\\u00f3mo se origin\\u00f3 la conservaci\\u00f3n de suelos? \\u00bfA quien se le atribuye el trabajo seminal? A menudo, parece ser que, es dif\\u00edcil ser objetivo. Los nacionalismos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/05\\\/17\\\/137981#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2011-05-17T10:45:04+01:00\",\"dateModified\":\"2011-05-17T10:45:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica - Un Universo invisible bajo nuestros pies","description":"Cuando uno busca los or\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, los albores de las disciplinas cient\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \u00bfC\u00f3mo se origin\u00f3 la conservaci\u00f3n de suelos? \u00bfA quien se le atribuye el trabajo seminal? A menudo, parece ser que, es dif\u00edcil ser objetivo. Los nacionalismos","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981#blogposting","name":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica - Un Universo invisible bajo nuestros pies","headline":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/158\/bennett-1928.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981\/#articleImage"},"datePublished":"2011-05-17T10:45:04+01:00","dateModified":"2011-05-17T10:45:04+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981#webpage"},"articleSection":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, Edafolog\u00eda y Pol\u00edtica, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n, art\u00edculo seminal, Conservaci\u00f3n de Suelos, erosi\u00f3n de suelos, fundaci\u00f3n de una ciencia, Hugh Hammond Bennett"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","position":2,"name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981#listItem","name":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981#listItem","position":3,"name":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981","name":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica - Un Universo invisible bajo nuestros pies","description":"Cuando uno busca los or\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, los albores de las disciplinas cient\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \u00bfC\u00f3mo se origin\u00f3 la conservaci\u00f3n de suelos? \u00bfA quien se le atribuye el trabajo seminal? A menudo, parece ser que, es dif\u00edcil ser objetivo. Los nacionalismos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2011-05-17T10:45:04+01:00","dateModified":"2011-05-17T10:45:04+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica - Un Universo invisible bajo nuestros pies","og:description":"Cuando uno busca los or\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, los albores de las disciplinas cient\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \u00bfC\u00f3mo se origin\u00f3 la conservaci\u00f3n de suelos? \u00bfA quien se le atribuye el trabajo seminal? A menudo, parece ser que, es dif\u00edcil ser objetivo. Los nacionalismos","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2011-05-17T09:45:04+00:00","article:modified_time":"2011-05-17T09:45:04+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica - Un Universo invisible bajo nuestros pies","twitter:description":"Cuando uno busca los or\u00edgenes de una disciplina concreta, suele toparse con muchas sorpresas. Frecuentemente, los albores de las disciplinas cient\u00edficas suelen resultar bastante difusos, y muchas veces arbitrarios. \u00bfC\u00f3mo se origin\u00f3 la conservaci\u00f3n de suelos? \u00bfA quien se le atribuye el trabajo seminal? A menudo, parece ser que, es dif\u00edcil ser objetivo. Los nacionalismos","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"137981","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 13:16:54","updated":"2026-05-26 16:46:52","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion\" title=\"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n\">P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tConservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion"},{"label":"Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/137981"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=137981"}],"version-history":[{"count":38,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/137981\/revisions"}],"predecessor-version":[{"id":139300,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/137981\/revisions\/139300"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=137981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=137981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=137981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}