{"id":138034,"date":"2011-01-17T09:58:49","date_gmt":"2011-01-17T08:58:49","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=138034"},"modified":"2011-04-08T19:38:08","modified_gmt":"2011-04-08T18:38:08","slug":"las-miserias-del-capitalismo-la-obsolescencia-programada-o-el-porque-vivimos-en-una-sociedad-anti-sustentable%e2%80%9d","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034","title":{"rendered":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d)"},"content":{"rendered":"<p style=\"text-align: justify;\">No hab\u00eda visto este<strong> <span style=\"color: #3366ff;\">magn\u00edfico documental<\/span><\/strong><span style=\"color: #3366ff;\"> <\/span>(\u201c<a title=\"Comprar, tirar, comprar\" href=\"http:\/\/www.rtve.es\/mediateca\/videos\/20110109\/comprar-tirar-comprar\/983391.shtml\">comprar, tirar, comprar<\/a>\u201d), fruto de la colaboraci\u00f3n entre \u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a, que ha sido emitido hace algunos d\u00edas. Una cuesti\u00f3n es conocer, m\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\u00e1s <span style=\"color: #3366ff;\"><strong>sinceras felicidades a los responsables de esta iniciativa<\/strong>. <strong>\u00a0Quien desee saber los males que acucian a la sociedad actual, as\u00ed como el porque de la gran mentira del desarrollo sostenible, no tiene m\u00e1s que pinchar en los enlaces de abajo<\/strong><\/span>. En menos de una hora entender\u00e1 que el mundo en que vivimos es un enorme desatino. Del mismo modo, comprobar\u00e1 como<strong> <span style=\"color: #3366ff;\">todos los residuos electr\u00f3nicos terminan en los pa\u00edses del tercer mundo<\/span><\/strong>, como ya os indicamos en nuestro post de hace cuatro a\u00f1os: \u201c<a title=\"Enlace permanente: Contaminaci\u00f3n del Suelo por Basura Electr\u00f3nica: Una Nueva Pandemia Ambiental en el Tercer Mundo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/06\/54158\">Contaminaci\u00f3n del Suelo por Basura Electr\u00f3nica: Una Nueva Pandemia Ambiental en el Tercer Mundo<\/a>\u201d. Incre\u00edble. No dej\u00e9is pues de visionarlo.<\/p>\n<p style=\"text-align: center;\">\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/obsolescencia-programada-documental-de-rtve.jpg\" alt=\"obsolescencia-programada-documental-de-rtve\" width=\"459\" height=\"104\" \/><\/p>\n<p style=\"text-align: center;\"><a title=\"Comprar, tirar, comprar\" href=\"http:\/\/www.rtve.es\/mediateca\/videos\/20110109\/comprar-tirar-comprar\/983391.shtml\">Comprar, tirar, comprar<\/a>:<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">\u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><!--more--><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00bfSabe usted que hay una relaci\u00f3n inversa entre la vida \u00fatil de los aparatos electr\u00f3nicos y nuestro modelo econ\u00f3mico?. El problema estriba en lo que se conoce como <a href=\"http:\/\/es.wikipedia.org\/wiki\/Obsolescencia_planificada\">obsolescencia programada<\/a> (ver tambi\u00e9n esta rese\u00f1a <a href=\"http:\/\/blogs.lavozdegalicia.es\/javiersanz\/2011\/01\/15\/rebajas-cuesta-de-enero-y-la-insostenible-practica-de-la-\u00e2\u20ac\u0153obsolescencia-programada\u00e2\u20ac\u009d\/\">en otro blog<\/a>). Todo est\u00e1 preparado para <a title=\"Comprar, tirar, comprar\" href=\"http:\/\/www.rtve.es\/mediateca\/videos\/20110109\/comprar-tirar-comprar\/983391.shtml\">comprar, tirar, comprar<\/a>, de tal modo que<strong> <span style=\"color: #3366ff;\">un sistema econ\u00f3mico a todas luces insustentable se perpetu\u00e9 hasta que muera por las inevitables causas naturales: inviabilidad a largo plazo<\/span><\/strong>.\u00a0 Y mientras tanto, <strong><span style=\"color: #3366ff;\">la basura se esconde en esa<\/span><\/strong> \u201c<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/06\/13\/94576\">\u00c1frica Olvidada<\/a>\u201d y otros pa\u00edses pobres esparcidos por el mundo a los que llega bajo <span style=\"color: #3366ff;\"><strong>el truco de \u201cproductos de segunda mano\u201d<\/strong>,<\/span> cuando en realidad se encuentran totalmente inservibles. El enviar este tipo de inmundicia se encuentra prohibido por un tratado internacional. Sin embargo, all\u00ed termina \u00bfConnivencia de los pol\u00edticos? En cualquier caso, como venimos insistiendo y tambi\u00e9n se defiende en este documental, <strong><span style=\"color: #3366ff;\">llegar\u00e1 un momento en que nos ahoguemos en nuestros propios detritus electrizantes<\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0Al parecer, uno debe <strong><span style=\"color: #3366ff;\">retrotraerse al a\u00f1o 1924<\/span><\/strong> en el primer \u201censayo\u201d para imponernos una <a href=\"http:\/\/es.wikipedia.org\/wiki\/Obsolescencia_planificada\">obsolescencia programada<\/a> (\u201c<em><a href=\"http:\/\/en.wikipedia.org\/wiki\/Planned_obsolescence\">planned obsolescence<\/a><\/em>\u201d), gracias a un c\u00e1rtel o lobby que consolidaron en la sombra las grandes empresas que fabricaban bombillas de luz, con vistas a acortar su duraci\u00f3n o ciclo de vida. De no ser as\u00ed se les acababa el negocio. Sin embargo, <span style=\"color: #3366ff;\"><strong>el modelo se impone definitivamente en los a\u00f1os 50. Dicho de otro modo, desde los albores de la producci\u00f3n en masa, o lo que es lo mismo \u201cla sociedad de consumo\u201d<\/strong>:<\/span> <a title=\"Comprar, tirar, comprar\" href=\"http:\/\/www.rtve.es\/mediateca\/videos\/20110109\/comprar-tirar-comprar\/983391.shtml\">comprar, tirar, comprar<\/a>. \u00a1Ese es el lema!. Y por ello, <span style=\"color: #3366ff;\"><strong>nosotros no somos ciudadanos sino simplemente consumidores, <\/strong><span style=\"color: #000000;\">p<\/span><\/span>ero nos quedamos tan tranquilos. Estos \u201c<strong><span style=\"color: #3366ff;\">c\u00e1rteles industriales<\/span><\/strong>\u201d siguen ah\u00ed, y el ciudadano perdiendo calidad de vida para que ellos mantengan sus suculentos y avariciosos negocios, incluso en los momentos que padecemos las crisis que ellos generan. Este es el \u201c<a href=\"http:\/\/www.openart.com\/obras\/manolo-zambrano-american-style-of-way\">american style of way<\/a>\u201d. <a title=\"Comprar, tirar, comprar\" href=\"http:\/\/www.rtve.es\/mediateca\/videos\/20110109\/comprar-tirar-comprar\/983391.shtml\">Comprar, tirar, comprar<\/a> (<strong><span style=\"color: #3366ff;\">sobreproducci\u00f3n y sobreconsumo<\/span><\/strong>), as\u00ed se nos dice que se acelera la econom\u00eda (\u00bfQu\u00e9 causo la depresi\u00f3n econ\u00f3mica de los a\u00f1os 29?: vea el documental),<span style=\"color: #3366ff;\"> <strong>as\u00ed se ense\u00f1a a los futuros dirigentes empresariales y tecn\u00f3logos del sector privado<\/strong>. <strong>Generar consumidores insatisfechos, que compren una y otra vez<\/strong><\/span>, lo que podr\u00eda durar cien a\u00f1os o m\u00e1s.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\">\u00a0<\/span><strong><span style=\"color: #3366ff;\">\u00bfTiene usted un ipod de Apple?<\/span> <\/strong>\u00bfSab\u00eda que en sus inicios las bater\u00edas de litio estaban preparados para que ese \u201cecon\u00f3mico\u201d aparatito durara poco m\u00e1s de un a\u00f1o?. \u00bfPorqu\u00e9 ahora dura dos? \u00bfSabe usted lo que es el \u201c<strong><span style=\"color: #3366ff;\">caso Westley contra Apple<\/span><\/strong>\u201d. Vea el documental por favor. <span style=\"color: #3366ff;\"><strong>\u00bfQu\u00e9 ocurr\u00eda mientras tanto en el modelo econ\u00f3mico comunista?<\/strong>.<\/span> Vea el documental por favor.<\/p>\n<p style=\"text-align: justify;\">\u00a0Existen <strong><span style=\"color: #3366ff;\">organizaciones de ciudadanos<\/span><\/strong>, que no de \u201cconsumidores\u201d que <strong><span style=\"color: #3366ff;\">se encuentran denunciando las vilezas de nuestro insustentable modelo de desarrollo<\/span><\/strong>.\u00a0 Estos son los casos, por ejemplo, de \u201c<a href=\"http:\/\/www.doorsofperception.com\/\">Doors of Perception<\/a>\u201d y \u201c<a href=\"http:\/\/www.mcdonough.com\/cradle_to_cradle.htm\">Cradle to Cradle<\/a>\u201d (\u201cde la cuna a la cuna\u201d). Como argumentan,<strong> <span style=\"color: #3366ff;\">en la naturaleza no hay desperdicios, tan solo nutrientes gracias a los organismos que alberga el ecosistema suelo, esa perfecta m\u00e1quina de reciclado biosf\u00e9rico<\/span><\/strong><span style=\"color: #3366ff;\">. <strong>\u00bfPor que no aprender de ella?, \u00bfpor que no convertir nuestros residuos en \u201cnutrientes\u201d?.<\/strong>\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: center;\">\u00a0<span style=\"color: #ff6600;\">Producir sin limites = consumir sin l\u00edmites = insustentabilidad en un mundo finito con recursos limitados. Hablamos pues de la <\/span><a href=\"http:\/\/es.wikipedia.org\/wiki\/Obsolescencia_planificada\">obsolescencia programada<\/a>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\">\u00a0<strong>El desarrollo y crecimiento sostenibles son una pura patra\u00f1a, una gran mentira<\/strong><\/span>. De ah\u00ed que algunos defiendan <strong><span style=\"color: #3366ff;\">una revoluci\u00f3n, tanto cultural\u00a0 como social, basada en las leyes de la naturaleza, as\u00ed como en el llamado \u201cdecrecimiento\u201d. Un paso atr\u00e1s, para poder dar 100 hacia adelante<\/span><\/strong>. \u00a1Vea el documental por favor!. El desarrollo sostenible basado en el modelo econ\u00f3mico actual es como intentar violar, a largo plazo, el segundo principio de la termodin\u00e1mica.\u00a0\u00a0<\/p>\n<p style=\"text-align: center;\">\u00a0<strong><span style=\"color: #ff9900;\">Los Nemes del\u00a0capitalismo tiene su propia obsolescencia programada<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0<strong><span style=\"color: #008000;\">Como visionar el documental <\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">En la p\u00e1gina Web de TVE se dice que el programa va a durar muy pocos d\u00edas m\u00e1s. Posiblemente ampl\u00eden algo el plazo, <strong>dado el enorme \u00e9xito de audiencia<\/strong>. Ahora bien, si ya llega tarde o prefiere verlo en trocitos, algo m\u00e1s digerible para los que no atesoren Internet de banda ancha, puede ir ya a <strong>Youtube <\/strong>y buscar (\u2026.)<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.youtube.com\/watch?v=HV_rBFCsI9Q&amp;feature=related\">Comprar-tirar-comprar (1\/5)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.youtube.com\/watch?v=9DVsvliy5q0&amp;feature=related\">Comprar-tirar-comprar (2\/5)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.youtube.com\/watch?v=XcaCh3qCdmE&amp;feature=related\">Comprar-tirar-comprar (3\/5)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.rtve.es\/television\/documentales\/comprar-tirar-comprar\">Comprar-tirar-comprar (4\/5)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.youtube.com\/watch?v=n2xGNqKBibY&amp;feature=related\">Comprar-tirar-comprar (5\/5)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #008080;\">Televisi\u00f3n espa\u00f1ola<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Comprar, tirar, comprar\" href=\"http:\/\/www.rtve.es\/mediateca\/videos\/20110109\/comprar-tirar-comprar\/983391.shtml\">Comprar, tirar, comprar<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.rtve.es\/television\/documentales\/comprar-tirar-comprar\/directo\/\">http:\/\/www.rtve.es\/television\/documentales\/comprar-tirar-comprar\/directo\/<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><strong>En la p\u00e1gina Web Introductoria de RTVE se puede leer:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>\u00bfPor qu\u00e9 los productos electr\u00f3nicos duran cada vez menos? \u00bfC\u00f3mo es posible que en 1911 una bombilla tuviera una duraci\u00f3n certificada de 2500 horas y cien a\u00f1os despu\u00e9s su vida \u00fatil se haya visto reducida a la mitad?\u00bfEs compatible un sistema de producci\u00f3n infinito en un planeta con recursos limitados?<\/strong>.<\/p>\n<p>\u00c9stas y otras preguntas surgen en el documental <a href=\"http:\/\/www.rtve.es\/television\/documentales\/comprar-tirar-comprar\/\">\u00abComprar, tirar, comprar\u00bb<\/a>, que ya puedes ver aqu\u00ed completo <strong>El documental permanecer\u00e1\u00a0disponible en la web durante las dos semanas posteriores a su emisi\u00f3n en televisi\u00f3n<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0A la derecha de esta p\u00e1gina hay un espacio en el que podr\u00e1s introducir tu usuario y tus claves de Facebook (a las que en ning\u00fan momento rtve.es tendr\u00e1 acceso). Inmediatamente ver\u00e1s como tu perfil se integra en nuestra web y podr\u00e1s comentar el programa en directo.<\/p>\n<p style=\"text-align: justify;\">Si todav\u00eda no tienes un perfil en Facebook <a href=\"http:\/\/www.facebook.com\/\">puedes cre\u00e1rtelo aqu\u00ed<\/a> y <a href=\"http:\/\/www.facebook.com\/rtve\">hacerte seguidor de la p\u00e1gina de rtve.es en la red social<\/a>.\u00a0<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>No hab\u00eda visto este magn\u00edfico documental (\u201ccomprar, tirar, comprar\u201d), fruto de la colaboraci\u00f3n entre \u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a, que ha sido emitido hace algunos d\u00edas. Una cuesti\u00f3n es conocer, m\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\u00e1s sinceras felicidades a los responsables de esta iniciativa. \u00a0Quien desee saber los males que acucian a la sociedad actual, as\u00ed como el porque de la gran mentira del desarrollo sostenible, no tiene m\u00e1s que pinchar en los enlaces de abajo. En menos de una hora entender\u00e1 que\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[594,618,605,1,615,606],"tags":[2965,46674,46831,2967,2966],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"No hab\u00eda visto este magn\u00edfico documental (\u201ccomprar, tirar, comprar\u201d), fruto de la colaboraci\u00f3n entre \u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a, que ha sido emitido hace algunos d\u00edas. Una cuesti\u00f3n es conocer, m\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\u00e1s sinceras felicidades\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"No hab\u00eda visto este magn\u00edfico documental (\u201ccomprar, tirar, comprar\u201d), fruto de la colaboraci\u00f3n entre \u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a, que ha sido emitido hace algunos d\u00edas. Una cuesti\u00f3n es conocer, m\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\u00e1s sinceras felicidades\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-01-17T08:58:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-04-08T18:38:08+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"No hab\u00eda visto este magn\u00edfico documental (\u201ccomprar, tirar, comprar\u201d), fruto de la colaboraci\u00f3n entre \u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a, que ha sido emitido hace algunos d\u00edas. Una cuesti\u00f3n es conocer, m\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\u00e1s sinceras felicidades\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034#blogposting\",\"name\":\"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\\u00e9 vivimos en una Sociedad Anti-sustentable\\u201d) - Un Universo invisible bajo nuestros pies\",\"headline\":\"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\\u00e9 vivimos en una Sociedad Anti-sustentable\\u201d)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/1123\\\/obsolescencia-programada-documental-de-rtve.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034\\\/#articleImage\"},\"datePublished\":\"2011-01-17T09:58:49+01:00\",\"dateModified\":\"2011-04-08T19:38:08+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":11,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034#webpage\"},\"articleSection\":\"Degradaci\\u00f3n de Suelos: Contaminaci\\u00f3n, Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, Fraude y Mala Praxis Cient\\u00edfica, General, Notas Breves de Prensa, Prensa y Pol\\u00edtica Cient\\u00edfica, c\\u00e1rteles industriales, contaminaci\\u00f3n, insustentabilidad, miserias del capitalismo, obsolescencia programada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034#listItem\",\"name\":\"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\\u00e9 vivimos en una Sociedad Anti-sustentable\\u201d)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034#listItem\",\"position\":3,\"name\":\"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\\u00e9 vivimos en una Sociedad Anti-sustentable\\u201d)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034\",\"name\":\"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\\u00e9 vivimos en una Sociedad Anti-sustentable\\u201d) - Un Universo invisible bajo nuestros pies\",\"description\":\"No hab\\u00eda visto este magn\\u00edfico documental (\\u201ccomprar, tirar, comprar\\u201d), fruto de la colaboraci\\u00f3n entre \\u201cArte France\\u201d, Televisi\\u00f3n Espa\\u00f1ola y Televisi\\u00f3n de Catalu\\u00f1a, que ha sido emitido hace algunos d\\u00edas. Una cuesti\\u00f3n es conocer, m\\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\\u00e1s sinceras felicidades\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/01\\\/17\\\/138034#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2011-01-17T09:58:49+01:00\",\"dateModified\":\"2011-04-08T19:38:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d) - Un Universo invisible bajo nuestros pies","description":"No hab\u00eda visto este magn\u00edfico documental (\u201ccomprar, tirar, comprar\u201d), fruto de la colaboraci\u00f3n entre \u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a, que ha sido emitido hace algunos d\u00edas. Una cuesti\u00f3n es conocer, m\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\u00e1s sinceras felicidades","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034#blogposting","name":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d) - Un Universo invisible bajo nuestros pies","headline":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/obsolescencia-programada-documental-de-rtve.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034\/#articleImage"},"datePublished":"2011-01-17T09:58:49+01:00","dateModified":"2011-04-08T19:38:08+01:00","inLanguage":"es-ES","commentCount":11,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034#webpage"},"articleSection":"Degradaci\u00f3n de Suelos: Contaminaci\u00f3n, Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, Fraude y Mala Praxis Cient\u00edfica, General, Notas Breves de Prensa, Prensa y Pol\u00edtica Cient\u00edfica, c\u00e1rteles industriales, contaminaci\u00f3n, insustentabilidad, miserias del capitalismo, obsolescencia programada"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034#listItem","name":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034#listItem","position":3,"name":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034","name":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d) - Un Universo invisible bajo nuestros pies","description":"No hab\u00eda visto este magn\u00edfico documental (\u201ccomprar, tirar, comprar\u201d), fruto de la colaboraci\u00f3n entre \u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a, que ha sido emitido hace algunos d\u00edas. Una cuesti\u00f3n es conocer, m\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\u00e1s sinceras felicidades","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2011-01-17T09:58:49+01:00","dateModified":"2011-04-08T19:38:08+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d) - Un Universo invisible bajo nuestros pies","og:description":"No hab\u00eda visto este magn\u00edfico documental (\u201ccomprar, tirar, comprar\u201d), fruto de la colaboraci\u00f3n entre \u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a, que ha sido emitido hace algunos d\u00edas. Una cuesti\u00f3n es conocer, m\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\u00e1s sinceras felicidades","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2011-01-17T08:58:49+00:00","article:modified_time":"2011-04-08T18:38:08+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d) - Un Universo invisible bajo nuestros pies","twitter:description":"No hab\u00eda visto este magn\u00edfico documental (\u201ccomprar, tirar, comprar\u201d), fruto de la colaboraci\u00f3n entre \u201cArte France\u201d, Televisi\u00f3n Espa\u00f1ola y Televisi\u00f3n de Catalu\u00f1a, que ha sido emitido hace algunos d\u00edas. Una cuesti\u00f3n es conocer, m\u00e1s o menos las cosas y otra bien distinta visionar el problema de una manera amena, casi exquisita. Mis m\u00e1s sinceras felicidades","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"138034","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 22:51:08","updated":"2026-05-26 16:32:56","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLas Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general"},{"label":"Las Miserias del Capitalismo: La Obsolescencia Programada (o el porqu\u00e9 vivimos en una Sociedad Anti-sustentable\u201d)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/138034"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=138034"}],"version-history":[{"count":11,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/138034\/revisions"}],"predecessor-version":[{"id":138897,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/138034\/revisions\/138897"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=138034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=138034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=138034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}