{"id":138539,"date":"2011-06-16T11:18:46","date_gmt":"2011-06-16T10:18:46","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=138539"},"modified":"2024-02-25T17:59:05","modified_gmt":"2024-02-25T16:59:05","slug":"riesgos-de-las-repoblaciones-con-eucaliptos-y-pinos-en-latinoamerica-silvicultura-clonal","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539","title":{"rendered":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal)"},"content":{"rendered":"<p style=\"text-align: justify\">Cuando viajaba en 2008 por el<strong> <span style=\"color: #3366ff\">valle central del sur Chile<\/span><\/strong>, observ\u00e9 un tanto sorprendido como <strong><span style=\"color: #3366ff\">algunas antiguas parcelas agr\u00edcolas estaban siendo sembradas de Eucaliptos<\/span><\/strong>. Al preguntar a los colegas chilenos, en aquella excursi\u00f3n de campo, me comentaron que <strong><span style=\"color: #3366ff\">el pa\u00eds necesitaba ampliar su producci\u00f3n maderera<\/span><\/strong>. Seguidamente les interpel\u00e9 si all\u00ed ten\u00edan noticia de los <strong><span style=\"color: #3366ff\">devastadores efectos sobre el suelo y recursos h\u00eddricos de este g\u00e9nero de \u00e1rboles, as\u00ed como tambi\u00e9n de numerosas especies de pino<\/span><\/strong>. Tem\u00eda la respuesta. Y efectivamente corroboraron mis sospechas. \u00a1No!. Este a\u00f1o, <strong><span style=\"color: #3366ff\">en Colombia me ocurri\u00f3 lo mismo<\/span><\/strong>. Sin embargo,<strong> <span style=\"color: #3366ff\">En Espa\u00f1a, llevamos unos 40 a\u00f1os protestando por tal tipo de repoblaciones. Las razones cient\u00edficas son bien conocidas aqu\u00ed<\/span><\/strong> y corroboradas hasta la saciedad.&nbsp;&nbsp; Se trata de especies que <strong><span style=\"color: #3366ff\">acidifican el suelo a la par que diezman su actividad biol\u00f3gica y biodiversidad<\/span><\/strong>. Del mismo modo, requieren una<strong> <span style=\"color: #3366ff\">enorme demanda de agua<\/span><\/strong> con vistas a mantener un r\u00e1pido crecimiento, por lo que su<span style=\"color: #3366ff\"> <strong>humedad desciende dram\u00e1ticamente impidiendo<\/strong><\/span> (junto a las <strong><span style=\"color: #3366ff\">sustancias alelop\u00e1ticas<\/span> <\/strong>que producen)<strong> <span style=\"color: #3366ff\">el desarrollo de otras especies del ecosistema<\/span><\/strong>. En algunos lugares de Espa\u00f1a, los <strong><span style=\"color: #3366ff\">potentes sistemas radiculares de los eucaliptos<\/span><\/strong> penetran muchos metros de profundidad, <strong><span style=\"color: #3366ff\">llegando a veces a romper las conducciones de agua<\/span><\/strong>. M\u00e1s aun, en el noroeste de la Pen\u00ednsula Ib\u00e9rica (l\u00e9ase Galicia, por ejemplo)<span style=\"color: #3366ff\"> <strong>han llegado a&nbsp; naturalizarse, destrozando los hermosos paisajes precedentes<\/strong>. <strong>Decir Eucaliptos<\/strong><\/span> (y en menor medida repoblaciones de pinos) <strong><span style=\"color: #3366ff\">es hablar <\/span><\/strong><a href=\"http:\/\/es.wikipedia.org\/wiki\/Othar\">Othar, el Caballo de Atila: \u201cpor donde pisaba, no volv\u00eda a crecer la hierba<\/a>. <strong><span style=\"color: #3366ff\">Plantar Eucaliptos es encender la mecha de los incendios forestales<\/span><\/strong>. Vaya este post como advertencia de una decisi\u00f3n gubernamental desatinada y alimentada por las compa\u00f1\u00edas nacionales y\/o multinacionales de los \u201ctocagenes\u201d, es decir, las empresas biotecnol\u00f3gicas, como podr\u00e9is observar en la noticia que hoy os muestro.<\/p>\n<p style=\"text-align: center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-right\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/818\/eucaliptos-en-chile-2-foto-juan-jose-ibanez.jpg\" alt=\"eucaliptos-en-chile-2-foto-juan-jose-ibanez\" width=\"510\" height=\"316\"><\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\">Vegetaci\u00f3n Natural en Chile. Bosque de Nothofagus (Hayas) Ascendiendo al Volc\u00e1n Chillan. Foto: Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\"><!--more--><\/span><\/p>\n<p style=\"text-align: justify\">Lamentablemente, no tuve mucho tiempo para explicarles m\u00e1s que someramente el problema que se les avecinaba. <strong><span style=\"color: #3366ff\">Las razones de Estado fueron las mismas que alegaron los gobernantes Espa\u00f1oles hace m\u00e1s de 50 a\u00f1os<\/span><\/strong>. Autoabastecerse de papel y madera de mala calidad.<span style=\"color: #3366ff\"> <strong>Empero no tardaron mucho en comenzar los problemas ambientales<\/strong><\/span>.<\/p>\n<p style=\"text-align: justify\">Por algo, a menudo, cuando nos duele la garganta ingerimos caramelos de <a href=\"http:\/\/www.botanical-online.com\/medicinalseucalipto.htm\">eucaliptol<\/a> <strong>\u00a1<span style=\"color: #3366ff\">Es desinfectante!. La misma labor realiza en el suelo, masacrar las comunidades ed\u00e1ficas responsables del reciclado de nutrientes y generaci\u00f3n de humus<\/span><\/strong>. Si se analizan los organismos del suelo, actividades enzim\u00e1ticas y sustancias h\u00famicas entre dos parcelas colindantes, una bajo cultivo de eucaliptos y otra con vegetaci\u00f3n natural, se constata el <strong><span style=\"color: #3366ff\">efecto demoledor de estos \u00e1rboles. Los pinos suelen seguir la misma t\u00f3nica, aunque<\/span><\/strong> son algo menos agresivos. M\u00e1s aun, <strong><span style=\"color: #3366ff\">en el sur de Chile, que yo sepa, no aparecen los pinares de forma natural<\/span><\/strong>. De plantar estos o el eucalipto se corre el riesgo de que, al naturalizarse, terminen por <strong><span style=\"color: #3366ff\">amenazar seriamente a la vegetaci\u00f3n aut\u00f3ctona y el conjunto del paisaje<\/span>.<\/strong> Las sustancias antibacterianas y anti-germinativas de sus hojas impiden una r\u00e1pida descomposici\u00f3n de la materia org\u00e1nica generando un<strong> <span style=\"color: #3366ff\">humus de mala calidad que a la postre empeorar\u00e1 la estructura del suelo<\/span><\/strong>. Pero hay m\u00e1s.<\/p>\n<p style=\"text-align: center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-right\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/818\/eucalipus-en-chile-foto-juan-jose-ibanez.jpg\" alt=\"eucalipus-en-chile-foto-juan-jose-ibanez\" width=\"515\" height=\"427\"><\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\">Paisaje antropizado con Eucaliptos y pinos espor\u00e1dicos en el sur de Chile. Foto: Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/p>\n<p style=\"text-align: justify\">Si los enclaves a repoblar no&nbsp;atesoran mucha agua, los <strong><span style=\"color: #3366ff\">recursos h\u00eddricos disminuir\u00e1n sobremanera<\/span><\/strong>. Pero hay m\u00e1s.<\/p>\n<p style=\"text-align: justify\">Muchas especies de <strong><span style=\"color: #3366ff\">eucaliptos y pinos son plantas pirof\u00edticas<\/span><\/strong>, es decir amantes del fuego, por cuanto a menudo les resulta indispensable con vistas a poder perpetuarse. <strong><span style=\"color: #3366ff\">De uno u otro modo<\/span><\/strong> (pi\u00f1as que solo dispersan sus semillas a elevad\u00edsimas temperaturas, tras ser lanzadas a decenas de metros de distancia como antorchas; hojarasca que se acumula sobre el suelo y que arde con suma facilidad) <strong><span style=\"color: #3366ff\">propician<\/span><\/strong> la aparici\u00f3n de <strong><span style=\"color: #3366ff\">incendios forestales<\/span><\/strong>, por lo que de plantarse a lo largo de grandes extensiones pueden causar<strong> <span style=\"color: #3366ff\">estragos ambientales<\/span><\/strong>, y tras el fuego iniciar <strong><span style=\"color: #3366ff\">serios episodios erosivos<\/span><\/strong>. Sobre este tema trabaj\u00e9 unos a\u00f1os y os puedo garantizar que no exagero ni una pizca. Cuando era joven, particip\u00e9 en varias manifestaciones en contra de tales tipos de reforestaciones en Espa\u00f1a. Cada a\u00f1o, tras los veranos, cuando contabilizamos aqu\u00ed las hect\u00e1reas perdidas `por ser presa del fuego, <span style=\"color: #3366ff\"><strong>los datos son contundentes<\/strong>. <strong>No existe ec\u00f3logo profesional, edaf\u00f3logo o movimiento conservacionista que defienda lo contrario<\/strong><\/span>.<\/p>\n<p style=\"text-align: justify\">En consecuencia, genera tristeza leer la noticia que os mostramos hoy, en la que todo son parabienes para los \u201cpeque\u00f1os propietarios\u201d, pero no se les alerta en absoluto de los riesgos que conllevan tales<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/01\/17\/82570\"> \u201cmonocultivos\u201d, que no bosques<\/a>. Rogar\u00eda a los colegas chilenos que se informen sobre el tema y alerten tanto a sus gobernantes, movimientos ecologistas y ciudadan\u00eda que <strong><span style=\"color: #3366ff\">\u201cno se puede jugar con fuego sin quemarse\u201d<\/span><\/strong>, y nunca mejor dicho. De la<strong> <span style=\"color: #3366ff\">selvicultura clonal<\/span><\/strong> mejor me callo, no sea que pierda la compostura con tanta falacia. Lo dicho, parece ser que los \u00e1rboles no dejan ver el bosque.<\/p>\n<p><strong><span style=\"color: #008000\">Juan Jos\u00e9 Ib\u00e1\u00f1ez <\/span><\/strong><\/p>\n<p><a href=\"http:\/\/www.madrimasd.org\/iberoamerica\/actualidad\/mostrar_info.asp?id=47469\">Invertir en silvicultura clonal Eucaliptos y Pinos en Chile<\/a><\/p>\n<p><strong>Neosylva<\/strong>, empresa dedicada a desarrollar la <strong>silvicultura clonal<\/strong>, asigna el 30% de su presupuesto anual a I+D y espera facturar unos $ 100 millones este a\u00f1o.<\/p>\n<p>FUENTE | <a href=\"http:\/\/diariofinanciero.cl\/portal2\/\" target=\"_blank\" rel=\"noopener\">Diario Financiero<\/a>; 14\/02\/2011. Chile<\/p>\n<p style=\"text-align: justify\"><strong>Incorporar la innovaci\u00f3n tecnol\u00f3gica a la cadena productiva de los peque\u00f1os y medianos agricultores, es el principal objetivo de la empresa Neosylva<\/strong>, que <strong>desde 2007 opera en el sur de nuestro pa\u00eds<\/strong>. Para lograr este prop\u00f3sito, la firma destina anualmente el 30% de su presupuesto para <strong>potenciar la I+D y transferir a los productores del sector forestal y frut\u00edcola, material gen\u00e9tico de plantas que permitan el crecimiento de la silvicultura clonal<\/strong>. Estas especies son generadas a partir de<strong> herramientas biotecnol\u00f3gicas de \u00faltima generaci\u00f3n<\/strong>, tales como embriog\u00e9nesis som\u00e1tica (producci\u00f3n de embriones o pl\u00e1ntulas a partir de c\u00e9lulas de genotipos elites) o <strong>variedades<\/strong> de berries certificadas,<strong> libres de virus y hongos, importadas desde su lugar de origen<\/strong>. Estas plantas se orientan a <strong>satisfacer las necesidades de medianos y peque\u00f1os propietarios<\/strong>, permiti\u00e9ndoles acceder a un producto de primera calidad, tanto en lo referido a composici\u00f3n gen\u00e9tica como de planta producida, explica V\u00edctor Sierra, gerente general de Neosylva.<\/p>\n<p><strong>En la actualidad, la compa\u00f1\u00eda cuenta con licencia para comercializar pino radiata de las forestales Arauco y Mininco, y con el respaldo de la Cooperativa de Mejoramiento Gen\u00e9tico de Nueva Zelanda<\/strong>. Su vivero est\u00e1 localizado en Villa Santa Fe, en Los \u00c1ngeles, y su laboratorio de cultivo de tejidos, an\u00e1lisis molecular e invernaderos, en Valdivia. <strong>Para este a\u00f1o, uno de los mayores proyectos de Neosylva es comenzar a desarrollar la silvicultura clonal de eucalyptus, tal como ocurre en Brasil<\/strong>. Nuestras especies de inter\u00e9s comercial, tales como <em>eucalyptus globulus y e. nitens<\/em>, son <strong>dif\u00edciles de propagar en forma asexual (sin semillas) y estamos focalizando nuestro esfuerzo en quebrar esta barrera<\/strong>, para lo cual hemos desarrollado un plan de trabajo con un horizonte de seis a\u00f1os, en el que <strong>esperamos contar con el apoyo tanto de empresas forestales como de las agencias p\u00fablicas que asignan recursos para estas innovaciones que llevan una alta cuota de riesgo<\/strong>, comenta Sierra. Con estas iniciativas en carpeta, la empresa espera facturar alrededor de $100 millones en 2011 y continuar masificando variedades vegetales de primer nivel.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Cuando viajaba en 2008 por el valle central del sur Chile, observ\u00e9 un tanto sorprendido como algunas antiguas parcelas agr\u00edcolas estaban siendo sembradas de Eucaliptos. Al preguntar a los colegas chilenos, en aquella excursi\u00f3n de campo, me comentaron que el pa\u00eds necesitaba ampliar su producci\u00f3n maderera. Seguidamente les interpel\u00e9 si all\u00ed ten\u00edan noticia de los devastadores efectos sobre el suelo y recursos h\u00eddricos de este g\u00e9nero de \u00e1rboles, as\u00ed como tambi\u00e9n de numerosas especies de pino. Tem\u00eda la respuesta. Y efectivamente corroboraron mis sospechas. \u00a1No!. Este a\u00f1o, en Colombia me ocurri\u00f3 lo mismo. Sin embargo, En Espa\u00f1a, llevamos unos 40\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,603,590,612,618,591,613,600,585],"tags":[46814,46770,7188,47015,7190,7189],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cuando viajaba en 2008 por el valle central del sur Chile, observ\u00e9 un tanto sorprendido como algunas antiguas parcelas agr\u00edcolas estaban siendo sembradas de Eucaliptos. Al preguntar a los colegas chilenos, en aquella excursi\u00f3n de campo, me comentaron que el pa\u00eds necesitaba ampliar su producci\u00f3n maderera. Seguidamente les interpel\u00e9 si all\u00ed ten\u00edan noticia de los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Cuando viajaba en 2008 por el valle central del sur Chile, observ\u00e9 un tanto sorprendido como algunas antiguas parcelas agr\u00edcolas estaban siendo sembradas de Eucaliptos. Al preguntar a los colegas chilenos, en aquella excursi\u00f3n de campo, me comentaron que el pa\u00eds necesitaba ampliar su producci\u00f3n maderera. Seguidamente les interpel\u00e9 si all\u00ed ten\u00edan noticia de los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-06-16T10:18:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-25T16:59:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cuando viajaba en 2008 por el valle central del sur Chile, observ\u00e9 un tanto sorprendido como algunas antiguas parcelas agr\u00edcolas estaban siendo sembradas de Eucaliptos. Al preguntar a los colegas chilenos, en aquella excursi\u00f3n de campo, me comentaron que el pa\u00eds necesitaba ampliar su producci\u00f3n maderera. Seguidamente les interpel\u00e9 si all\u00ed ten\u00edan noticia de los\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539#blogposting\",\"name\":\"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\\u00e9rica (Silvicultura Clonal) - Un Universo invisible bajo nuestros pies\",\"headline\":\"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\\u00e9rica (Silvicultura Clonal)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/818\\\/eucaliptos-en-chile-2-foto-juan-jose-ibanez.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539\\\/#articleImage\"},\"datePublished\":\"2011-06-16T11:18:46+01:00\",\"dateModified\":\"2024-02-25T17:59:05+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":11,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Componentes, Estructuras y Procesos en los Suelos, Degradaci\\u00f3n de Suelos: Salinizaci\\u00f3n y Acidificaci\\u00f3n, Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, Edafolog\\u00eda y Pol\\u00edtica, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, Los Suelos las Plantas y la Vegetaci\\u00f3n, P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n, degradaci\\u00f3n ambiental, degradaci\\u00f3n del suelo, eucaliptos, incendios forestales, monocultivos, pinos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"position\":2,\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539#listItem\",\"name\":\"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\\u00e9rica (Silvicultura Clonal)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539#listItem\",\"position\":3,\"name\":\"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\\u00e9rica (Silvicultura Clonal)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539\",\"name\":\"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\\u00e9rica (Silvicultura Clonal) - Un Universo invisible bajo nuestros pies\",\"description\":\"Cuando viajaba en 2008 por el valle central del sur Chile, observ\\u00e9 un tanto sorprendido como algunas antiguas parcelas agr\\u00edcolas estaban siendo sembradas de Eucaliptos. Al preguntar a los colegas chilenos, en aquella excursi\\u00f3n de campo, me comentaron que el pa\\u00eds necesitaba ampliar su producci\\u00f3n maderera. Seguidamente les interpel\\u00e9 si all\\u00ed ten\\u00edan noticia de los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/16\\\/138539#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2011-06-16T11:18:46+01:00\",\"dateModified\":\"2024-02-25T17:59:05+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal) - Un Universo invisible bajo nuestros pies","description":"Cuando viajaba en 2008 por el valle central del sur Chile, observ\u00e9 un tanto sorprendido como algunas antiguas parcelas agr\u00edcolas estaban siendo sembradas de Eucaliptos. Al preguntar a los colegas chilenos, en aquella excursi\u00f3n de campo, me comentaron que el pa\u00eds necesitaba ampliar su producci\u00f3n maderera. Seguidamente les interpel\u00e9 si all\u00ed ten\u00edan noticia de los","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539#blogposting","name":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal) - Un Universo invisible bajo nuestros pies","headline":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/818\/eucaliptos-en-chile-2-foto-juan-jose-ibanez.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539\/#articleImage"},"datePublished":"2011-06-16T11:18:46+01:00","dateModified":"2024-02-25T17:59:05+01:00","inLanguage":"es-ES","commentCount":11,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Componentes, Estructuras y Procesos en los Suelos, Degradaci\u00f3n de Suelos: Salinizaci\u00f3n y Acidificaci\u00f3n, Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, Edafolog\u00eda y Pol\u00edtica, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, Los Suelos las Plantas y la Vegetaci\u00f3n, P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n, degradaci\u00f3n ambiental, degradaci\u00f3n del suelo, eucaliptos, incendios forestales, monocultivos, pinos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","position":2,"name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539#listItem","name":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539#listItem","position":3,"name":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539","name":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal) - Un Universo invisible bajo nuestros pies","description":"Cuando viajaba en 2008 por el valle central del sur Chile, observ\u00e9 un tanto sorprendido como algunas antiguas parcelas agr\u00edcolas estaban siendo sembradas de Eucaliptos. Al preguntar a los colegas chilenos, en aquella excursi\u00f3n de campo, me comentaron que el pa\u00eds necesitaba ampliar su producci\u00f3n maderera. Seguidamente les interpel\u00e9 si all\u00ed ten\u00edan noticia de los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2011-06-16T11:18:46+01:00","dateModified":"2024-02-25T17:59:05+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal) - Un Universo invisible bajo nuestros pies","og:description":"Cuando viajaba en 2008 por el valle central del sur Chile, observ\u00e9 un tanto sorprendido como algunas antiguas parcelas agr\u00edcolas estaban siendo sembradas de Eucaliptos. Al preguntar a los colegas chilenos, en aquella excursi\u00f3n de campo, me comentaron que el pa\u00eds necesitaba ampliar su producci\u00f3n maderera. Seguidamente les interpel\u00e9 si all\u00ed ten\u00edan noticia de los","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2011-06-16T10:18:46+00:00","article:modified_time":"2024-02-25T16:59:05+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal) - Un Universo invisible bajo nuestros pies","twitter:description":"Cuando viajaba en 2008 por el valle central del sur Chile, observ\u00e9 un tanto sorprendido como algunas antiguas parcelas agr\u00edcolas estaban siendo sembradas de Eucaliptos. Al preguntar a los colegas chilenos, en aquella excursi\u00f3n de campo, me comentaron que el pa\u00eds necesitaba ampliar su producci\u00f3n maderera. Seguidamente les interpel\u00e9 si all\u00ed ten\u00edan noticia de los","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"138539","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","tabs":null,"priority":0,"frequency":"default","local_seo":null,"created":"2022-06-03 16:02:38","updated":"2026-05-26 16:48:57","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion\" title=\"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n\">P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRiesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion"},{"label":"Riesgos de las Repoblaciones con Eucaliptos y Pinos en Latinoam\u00e9rica (Silvicultura Clonal)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/16\/138539"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/138539"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=138539"}],"version-history":[{"count":13,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/138539\/revisions"}],"predecessor-version":[{"id":155357,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/138539\/revisions\/155357"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=138539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=138539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=138539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}