{"id":139469,"date":"2011-06-04T17:14:07","date_gmt":"2011-06-04T16:14:07","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=139469"},"modified":"2011-06-04T17:46:52","modified_gmt":"2011-06-04T16:46:52","slug":"voceros-de-la-ciencia-versus-periodismo-cientifico-independiente-curso-de-periodismo-cientifico-y-7","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469","title":{"rendered":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7)"},"content":{"rendered":"<p style=\"text-align: justify;\">Continuamos con nuestro <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-breve-sobre-periodismo-cientifico\">Curso Breve sobre Periodismo Cient\u00edfico<\/a>, haciendo hoy referencia a<span style=\"color: #3366ff;\"><strong> un punto crucial entre dos perspectivas de hacer periodismo cient\u00edfico. Estas discernir\u00e1n si el \u201c<em>plumillas<\/em>\u201d se pode del lado de los poderes f\u00e1cticos, o de los intereses del ciudadano<\/strong>. <strong>Hoy por hoy<\/strong><\/span>, las noticias sobre la ciencia que podemos leer el los rotativos y notas de prensa institucionales, suelen colocar al <span style=\"color: #3366ff;\"><strong>periodista<\/strong><\/span> (voluntaria o involuntariamente) <strong><span style=\"color: #3366ff;\">del lado de los poderes f\u00e1cticos<\/span><\/strong>. Y as\u00ed <span style=\"color: #3366ff;\"><strong>el ciudadano consume propaganda, alej\u00e1ndose de la verdadera esencia de c\u00f3mo funciona la indagaci\u00f3n investigadora<\/strong><\/span>. Tambi\u00e9n defenderemos <span style=\"color: #3366ff;\"><strong>la necesidad de cambiar el vocabulario y la elecci\u00f3n de unos titulares zafios<\/strong><\/span>, por no alegar que falaces (de nuevo, voluntaria o involuntariamente). Ahora bien,<span style=\"color: #3366ff;\"> <strong>\u00bfdisfruta el ciudadano de un periodismo independiente en general?<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><strong><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/eusebio-sempere-haz-de-septifolios-1972.jpg\" alt=\"eusebio-sempere-haz-de-septifolios-1972\" width=\"516\" height=\"673\" \/><br \/>\n<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.eusebio-sempere.com\/\">Eusebio Sempere Haz de Septifolios 1972. Fuente: Eusebio Sempere, Poeta de la Geometr\u00eda<\/a><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>La respuesta a la \u00faltima pregunta<\/strong><\/span> debe ser necesariamente un contundente <strong><span style=\"color: #3366ff;\">\u00a1NO!<\/span><\/strong><span style=\"color: #3366ff;\">. <strong>Los rotativos de prensa padecen de claras inclinaciones pol\u00edticas, a menudo tendenciosamente ocultas bajo una falsa propaganda de independencia<\/strong><\/span>. Basta con visitar un kiosco o comercio en donde se vendan peri\u00f3dicos y leer como cada uno de ellos expone los titulares sobre la actualidad. Francamente se me antoja escandaloso. Si en su pa\u00eds las cadenas de televisi\u00f3n disponen de teletexto, posiblemente alguna de ellas atesora una p\u00e1gina que incluya los titulares de cada uno de los principales rotativos nacionales. Personalmente, en RTVE (p\u00e1gina 185), todas las ma\u00f1anas, mientras desayuno, leo los mismos. Ante la tendenciosidad de cada uno de ellos no cabe m\u00e1s que re\u00edr o a llorar (seg\u00fan el estado an\u00edmico de cada uno en un instante dado). Y esto es v\u00e1lido desde las noticias pol\u00edticas y econ\u00f3micas, hasta las deportivas. <span style=\"color: #3366ff;\"><strong>Pru\u00e9belo, no hay quien me pueda discutir tal aserto. Empero cuando llegamos a las noticias cient\u00edficas (\u2026.)<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Pues s\u00ed, en el momento que rebuscamos con vistas a encontrar las escasas notas de prensa que versan sobre ciencia, <span style=\"color: #3366ff;\"><strong>ya no podemos discernir ideolog\u00eda alguna<\/strong>, <\/span><strong><span style=\"color: #3366ff;\">dando lugar a pensar que la actividad investigadora resulta ser tan objetiva que no da lugar para ello.\u00a0 Se trata de una apreciaci\u00f3n rotundamente falsa<\/span><\/strong>. Simplemente, <span style=\"color: #3366ff;\"><strong>nos enfrentamos a los voceros de las noticias de prensa institucionales e investigadores populares<\/strong><\/span>. Empero<span style=\"color: #3366ff;\"><strong> un vocero dista mucho de ser un genuino <em>\u201cplumillas<\/em>\u201d<\/strong><\/span>. Y as\u00ed<span style=\"color: #3366ff;\"><strong> el ciudadano<\/strong><\/span> queda m\u00e1s desorientado que\u00a0 una abeja en medio de un campo de ondas electromagn\u00e9ticas. En otras palabras, <span style=\"color: #3366ff;\"><strong>no es informado debidamente, por lo que tampoco puede hacerse una opini\u00f3n sobre la relevancia de lo que lee<\/strong><\/span>. Pero sigamos con nuestra narraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Os recordamos<\/strong><\/span> de nuevo que partiremos del material proporcionado en el art\u00edculo en acceso abierto denominado <a href=\"http:\/\/jcom.sissa.it\/archive\/09\/04\/Jcom0904(2010)A02\/Jcom0904(2010)A02.pdf\">Let\u2019s follow the actors! Does Actor-Network Theory have anything to contribute to science journalism?<\/a> (International for Advanced Studies Journal of Science Communication, cuyos autores resultan ser <span style=\"color: #3366ff;\"><strong>Carlos Fioravanti, Lea Velho<\/strong><\/span>. Estos autores basan sus argumentaciones en la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Teor%C3%ADa_del_Actor-Red\">Teor\u00eda-Actor Red<\/a> propuesta por dos de los m\u00e1s prominentes expertos de los denominados \u201c<a href=\"http:\/\/sociotecno2.wordpress.com\/latour-y-callon\">estudios sociales de la ciencia<\/a>\u201d. Hablamos de <a href=\"http:\/\/es.wikipedia.org\/wiki\/Bruno_Latour\">Bruno Latour<\/a> y <a href=\"http:\/\/es.wikipedia.org\/wiki\/Michel_Callon\">Michell Callon<\/a>.<\/p>\n<p style=\"text-align: justify;\">Por en\u00e9sima vez nos vemos obligado a recordaros tambi\u00e9n que este modesto curso parte del material contenido en el art\u00edculo <a href=\"http:\/\/jcom.sissa.it\/archive\/09\/04\/Jcom0904(2010)A02\/Jcom0904(2010)A02.pdf\">Let\u2019s follow the actors! Does Actor-Network Theory have anything to contribute to science journalism?<\/a> (International for Advanced Studies Journal of Science Communication), cuyos autores resultan ser Carlos Fioravanti y Lea Velho. En base a una traducci\u00f3n muy libre del mismo (aunque aparezca en cursiva) iremos a\u00f1adiendo material de nuestra propia cosecha. Comencemos pues (\u2026)<\/p>\n<p><span style=\"color: #008080;\"><strong><em>5.<\/em><\/strong><em> <strong>No m\u00e1s descubrimientos o indagaciones m\u00e1gicas. Se necesita un nuevo vocabulario<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong><em>La ciencia, ahora se percibe como<\/em><\/strong><\/span><em> una construcci\u00f3n social, colectiva, que no surge simplemente de una mente privilegiada trabajando aisladamente. <strong><span style=\"color: #3366ff;\">Un\u00a0 proceso social largo y agotador resulta ser necesario<\/span>.<\/strong> Todos los cient\u00edficos saben que <span style=\"color: #3366ff;\"><strong>no hay magia alguna en la producci\u00f3n de la ciencia, pero muchas veces optan por simplificar el verdadero curso de una investigaci\u00f3n<\/strong><\/span>, que de por s\u00ed es largo y sinuoso, soslayando detalles que los periodistas apresurados descartan como irrelevantes.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Cuando un investigador entra todas las ma\u00f1anas en su centro de trabajo, lo hace como cualquier ciudadano al acudir al suyo. Conforme tome asiento en su despacho o laboratorio comenzar\u00e1 a <\/strong><\/span>actuar como cualquier otro trabajador. Deber\u00e1 enfrentarse a m\u00faltiples problemas log\u00edsticos y combatir con sus competidores. Del mismo modo, necesitar\u00e1 imperiosamente convencer a sus superiores institucionales y organismos financiadores que cubran sus necesidades. Tras ello, y si es jefe de alg\u00fan equipo, repasar\u00e1 como act\u00faa cada uno de sus lacayos, si se van consiguiendo los resultados esperables o existen retrasos, as\u00ed como tambi\u00e9n si alguna de sus ovejas se le ha descarriado, con vistas a volverla a introducir en el redil o tomar las medidas coercitivas oportunas. <span style=\"color: #3366ff;\"><strong>Y as\u00ed sucesivamente. Realmente cada colectivo profesional, atesora alguna idiosincrasia, empero\u00a0 permanecen los estructuras y procesos t\u00edpicos de cada sociedad en un momento dado<\/strong>. <strong>Al fin y al cabo<\/strong><\/span>, como venimos defendiendo, <span style=\"color: #3366ff;\"><strong>la ciencia es un constructo social, por lo que dif\u00edcilmente podr\u00eda entenderse la conducta de los investigadores como algo muy especial<\/strong><\/span>, si bien muchos de ellos adoran tan apreciaci\u00f3n. Cuando un gobierno adopta recortes en la financiaci\u00f3n de la ciencia, el colectivo bramar\u00e1 al un\u00edsono, alegando la importancia de su actividad, del mismo modo que los empresarios lo hacen cuando las medidas gubernamentales no les resultan ventajosas. Si el poder se retracta, todo vuelve a su cauce. N\u00f3tese que tal modo de proceder es id\u00e9ntico al de otros colectivos, como los sindicatos, etc., etc., etc.\u00a0 Nada especial distingue la defensa de los intereses que afectan a un colectivo, aunque en sus senos, las batallas entre competidores resulten encarnizadas.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/eusebio-sempere-haz-de-septifolios-variacion.jpg\" alt=\"eusebio-sempere-haz-de-septifolios-variacion\" width=\"489\" height=\"655\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.eusebio-sempere.com\/\">Eusebio Sempere Haz de Septifolios 1972 Variaci\u00f3n. Fuente: Eusebio Sempere, Poeta de la Geometr\u00eda<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"http:\/\/es.wikipedia.org\/wiki\/Teor%C3%ADa_del_Actor-Red\">Teor\u00eda-Actor Red<\/a> (aproximaci\u00f3n ANT) <strong>demanda unos pocos cambios en los verbos m\u00e1s utilizados en las noticias cient\u00edficas<\/strong>. <strong>En lugar de decir que un cient\u00edfico descubre algo, como un hecho sorprendente, podr\u00edamos alegar que el cient\u00edfico ha puesto en evidencia o ha verificado algo. <\/strong>Ahora bien, <strong>un experimento no muestra ni revelar nada, simplemente sugiere o indica, ya que con otro equipamiento o aproximaci\u00f3n te\u00f3rica se obtendr\u00edan resultados distintos<\/strong>. Se trata de <strong>un cambio sutil (pero no trivial), que ayudar\u00eda a construir una narraci\u00f3n m\u00e1s amigable o menos dirigida (patrocinada) <\/strong>noticia, es decir m\u00e1s neutral. Se trata de <strong>un problema real y muy serio<\/strong>, por cuanto <strong>los periodistas intentan convencer a sus editores <\/strong>acerca de la importancia de las noticias <strong>apelando a sentencias contundentes y llamativas en lugar de otras m\u00e1s mesuradas<\/strong> de periodista para convencer a sus editores sobre la importancia de las noticias que han escrito.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em>En peri\u00f3dicos y revistas de prensa general, los titulares contienen las noticias m\u00e1s importantes y llamativas, mientras que las que versan sobre noticias de ciencia, normalmente son relegadas discretamente para las p\u00e1ginas interiores, excepto si<\/em><\/strong><em> alguna de las \u00faltimas puede cambiar el mundo, siendo a la par de f\u00e1cil comprensi\u00f3n por el ciudadano.<strong> Cuanto m\u00e1s sensacionalista sea una noticia tanto mejor, siendo escrita o abundando en la misma de un modo superficial<\/strong>.<\/em><\/p>\n<p style=\"text-align: justify;\">No puedo m\u00e1s que coincidir con Carlos Fioravanti, Lea Velho. Pero incluso<strong><span style=\"color: #3366ff;\"> el problema es m\u00e1s grave de lo que estos autores apuntan<\/span><\/strong><span style=\"color: #3366ff;\">, <span style=\"color: #333333;\">por cuanto<\/span><strong> la mayor parte de los titulares, al \u201cfantasearlos\u201d con vistas a hacerlos m\u00e1s epatantes faltan a la verdad<\/strong><\/span>, son embusteros. El propio <a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/default.asp\">bolet\u00edn de noticias diaria de mi+d<\/a>, muestra como <span style=\"color: #3366ff;\"><strong>muchas notas de prensa<\/strong><\/span> y, especialmente sus titulares, <span style=\"color: #3366ff;\"><strong>indignan a los lectores m\u00e1s avezados en la materia<\/strong><\/span>, algunos de cuyos comentarios no tienen desperdicio. Sin embargo, <span style=\"color: #3366ff;\"><strong>otras de gran calado son publicadas tal cual proceden de sus fuentes, sin analizar la gravedad de sus repercusiones. Como las siguientes que he le\u00eddo hoy mismo<\/strong><\/span> (porque si tirara de archivo\u2026\u2026) los contenidos expuestos abajo devienen en \u201c<em>pecata minuta<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=48668\">China exporta reactores at\u00f3micos &#8216;low cost&#8217;<\/a>. Mientras se discute en estos momentos la seguridad de la energ\u00eda nuclear, China pretende vender reactores nucleares a pa\u00edses emergentes o pobres, algunos de los cuales, para m\u00e1s INRI, se encuentran en zonas sustentas a una alta sismicidad, tsunamis, etc. Y el organismo nuclear cometerte que tato ha criticado al Jap\u00f3n:\u00a0 \u00bfNo tiene nada que alegar? \u00bfTiene el gobierno chino patente de corso (puede hacer lo que le venga en gana)?<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=48706\">Es como el caf\u00e9 y los polvos de talco<\/a>. Cuando la organizaci\u00f3n Mundial de la Salud acaba de advertir que la telefon\u00eda m\u00f3vil puede general c\u00e1ncer de cerebro, las empresas de telecomunicaciones, un d\u00eda despu\u00e9s, espetan esta est\u00fapida e irresponsable frase. \u00bfEn donde se muestra la documentaci\u00f3n de tales sesudas y prolongadas investigaciones (\u00a124 horas despu\u00e9s!)?.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=48707\">La UE proh\u00edbe los biberones con bisfenol A<\/a>. Otra de las jugarretas de la farmaindustria: un d\u00eda nos venden por bueno lo que \u00a1mil a\u00f1os despu\u00e9s nuestras autoridades alegan que puede ser peligroso para la salud! \u00bfDe quien nos podemos fiar?<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=48701\">El trepidante viaje de vuelta de Paolo<\/a>. Estoy convencido que por su relevancia la experiencia de Paolo (ya narrada mil veces) entusiasmar\u00e1 a m\u00e1s de un analfabeto. \u00bfSe trata de una noticia de calado? \u00bfQu\u00e9 aporta esta estupidez a la ciudadan\u00eda? Seguro que hoy gran parte de la poblaci\u00f3n se encuentra \u201ctrepidantemente fascinada\u201d por tan fabuloso notici\u00f3n que cambiar\u00e1 el mundo.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/investigadores-en-accion-fuente-puzzle-com.jpg\" alt=\"investigadores-en-accion-fuente-puzzle-com\" width=\"418\" height=\"395\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.buzzle.com\/articles\/science-lab-safety-rules.html\">Como nos gusta que nos muestren a los Investigadores. Puzzle.com<\/a><\/p>\n<p style=\"text-align: justify;\">Pero hay m\u00e1s, mucho m\u00e1s. Reiteremos que <span style=\"color: #3366ff;\"><strong>confundir los resultados de un modelo num\u00e9rico con una realidad incuestionable ser\u00eda algo as\u00ed como<\/strong><\/span> visionar \u201cBambi\u201d y apuntar que es el mejor reportaje sobre c\u00e9rvidos que ha llevado a cabo National Geographic. Eso si, no difiere mucho de un \u201cpalabro muy de moda\u201d, como resulta ser \u201cexigir\u201d. \u201clos emigrantes ilegales exigen que el gobierno les de asilo\u201d. Se trata de un mero ejemplo. \u00bfPuede exigir un soldado a su general que le cambie de destino? Solo es permisible exigir cuando uno est\u00e1 en posici\u00f3n de permit\u00edrselo (supremac\u00eda, posici\u00f3n de privilegio, un as debajo de la manga que pueda atemorizar al que ostenta el poder, etc.), en caso contrario, \u201cprotesta\u201d, \u201csolicita\u201d (\u2026.) son los vocablos pertinentes. Sin embargo, al parecer, \u201cexigir\u201d vende muchos peri\u00f3dicos (francamente desconozco la raz\u00f3n). \u00a1Los investigadores exigimos que las noticias de prensa sean siembre veraces! \u00bfNos har\u00e1n caso? \u00a1Pues va a ser que no!.<\/p>\n<p style=\"text-align: justify;\"><strong><em>La b\u00fasqueda de un vocabulario apropiado<\/em><\/strong><em>, incluso si no es adecuado o conveniente para competir con otras noticias, <strong>puede a\u00f1adir un considerable valor a\u00f1adido al esfuerzo de los periodistas cient\u00edficos<\/strong>. Afirma Franzoni que: \u00abM\u00e1s que en cualquier otra rama del periodismo, el escritor de ciencia debe investigar al m\u00e1ximo en el menor tiempo posible. En este proceso, <strong>el periodista se convierte en una especie de \u00abmini-investigador<\/strong>, acerc\u00e1ndose m\u00e1s estrechamente a su interlocutor principal, el cient\u00edfico\u00bb.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Quiz\u00e1s lleve raz\u00f3n Franzoni, empero ni siquiera es necesario llegar a tales extremos. Yo me conformar\u00eda con que al periodismo cient\u00edfico y tecnol\u00f3gico los rotativos de prensa le ofrecieran el mismo tratamiento que a otro tipo de noticias<\/strong>. <strong>Me explico<\/strong><\/span>. Si uno lee sobre pol\u00edtica, cada noticia que ofrece un pol\u00edtico con sus declaraciones, se encuentra sabrosamente enriquecida con la que espetan sus contrincantes y analistas pol\u00edticos, como m\u00ednimo. Lo mismo es v\u00e1lido en lo que concierne a la econom\u00eda. M\u00e1s aun, si un deportista realiza unas manifestaciones, pronto surgir\u00e1n una pl\u00e9tora de \u201c<em>plumill<\/em>as\u201d deportivos, analizando, alabando, o denostando sus contenidos. <span style=\"color: #3366ff;\"><strong>\u00bfOcurre algo parecido con el periodismo cient\u00edfico y tecnol\u00f3gico?. \u00a1NO!. No hace falta, en primera instancia solicitar un tratamiento especial, sino denunciar el discriminatorio, por zafio y pobre en contenidos que ofrece, la prensa en general e incluso a manudo la especializada<\/strong><\/span> (ver numerosos ejemplos incluidos en nuestra <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica\">categor\u00eda prensa y pol\u00edtica cient\u00edfica<\/a>).<\/p>\n<p><span style=\"color: #008080;\"><strong><em>6. El Periodista como mediador y no un mero intermediario<\/em><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><em>Muchos de los estudios acad\u00e9micos basados en la aproximaci\u00f3n ANT adoptan dos conceptos &#8211; <strong>intermediario y mediador<\/strong> &#8211; cuyo significado preciso resulta relevante para los periodistas. Muy brevemente, <strong>un intermediario es como un cartero, transmite la informaci\u00f3n sin realizar transformaci\u00f3n alguna<\/strong>. Lo que el intermediario recibe es lo que \u00e9l o ella entregar\u00e1n a sus editores. <strong>Los mediadores, en cambio son creativos e impredecibles, en tanto que ellos \u00abtransformar, traducen, modifican y distorsionan el significado o los elementos que se supone que deben transmitir<\/strong>. Lo que un mediador tiene entre manos <strong>puede llegar a ser muy diferente de lo que \u00e9l o ella recibieron<\/strong>.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em>Mientras que se examina a la ciencia como un trabajo colectivo y se da entrada (y voz) a otros actores m\u00e1s all\u00e1 del m\u00e1s poderoso, el periodista cient\u00edfico tiende a transformar su papel de intermediario en el de mediador<\/em><\/strong><em>. Si lo hace, el periodista puede <strong>dilucidar la relevancia de las noticias cient\u00edficas en su justa medida<\/strong>, al exponer las conexiones establecidas y estimular otras nuevas,<strong> creando sus propios caminos y conclusiones<\/strong>.<\/em><\/p>\n<p style=\"text-align: justify;\">Completamente de acuerdo, como ya hemos ido viendo hasta el momento, y seguiremos haci\u00e9ndolo (ver post sobre el tema pinchando aqu\u00ed: \u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-breve-sobre-periodismo-cientifico\">Curso Breve sobre Periodismo Cient\u00edfico<\/a>). Sin embargo, al menos en Espa\u00f1a <span style=\"color: #3366ff;\"><strong>son habas contadas los profesionales que enfocan as\u00ed las noticias de prensa sobre investigaci\u00f3n, tecnolog\u00eda y pol\u00edtica cient\u00edfica. Hablar de periodismo de investigaci\u00f3n son palabras mayores. Tal actividad es imprescindible. Ahora bien<\/strong>, <strong>si a\u00fan debemos convencer a que los\u00a0 \u201c<em>plumill<\/em>as\u201d, que se desvinculen de su labor de voceros<\/strong><\/span> (es decir intermediarios) <span style=\"color: #3366ff;\"><strong>para convertirse en genuinos mediadores <\/strong><\/span>(profesionales de altura),<span style=\"color: #3366ff;\"><strong> incidir reiteradamente sobre periodismo de investigaci\u00f3n<\/strong> <span style=\"color: #333333;\">(salvo extraordinarias excepciones)<\/span> <strong>deviene en una mera quimera<\/strong><\/span> (al menos en el mundo hispanoparlante). Eso si, <span style=\"color: #3366ff;\"><strong>gran parte de la culpa la tienen los editores<\/strong><\/span>, como ya trataremos en su momento.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Los cient\u00edficos tradicionales, prefieren ver a los periodistas como intermediarios,<\/em><\/strong><em> escribiendo sobre la ciencia y los cient\u00edficos con la \u201cprecisi\u00f3n\u201d que ellos desean. As\u00ed pues <strong>no disfrutar\u00e1n de este nuevo estilo period\u00edstico<\/strong>. Sin embargo <strong>el lector (ciudadano) opinar\u00e1 todo lo contrario<\/strong>, siendo la noticia de su agrado. Los periodistas, c<strong>omo mediadores, deben mantener un di\u00e1logo entre el mundo de la ciencia por un lado y el mundo de la sociedad y los medios de comunicaci\u00f3n<\/strong> por el otro.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Os puedo asegurar que muchos colegas no aparecer\u00edan ante los periodistas cient\u00edficos,\u00a0 si estos realizaran su labor como profesionales cualificados que entienden de ciencia<\/strong><\/span>. De este modo, <span style=\"color: #3366ff;\"><strong>comenzar\u00edamos a separar el grano de la paja<\/strong><\/span>, ya que muchos mequetrefes eludir\u00edan alegar que han descubierto le dinamita a bombo y platillo. \u00bfCu\u00e1ntos \u201c<em>plumill<\/em>as\u201d se acuerdan del ciudadano? <span style=\"color: #3366ff;\"><strong>Cuando un investigador publicita sus investigaciones alegando \u201cesto podr\u00eda servir\u201d y los periodistas le espetaran \u201c\u00bfpero sirve o no sirve?, si es \u00fatil, \u00bfcuando estar\u00e1 a disposici\u00f3n del p\u00fablico? \u00bfQu\u00e9 beneficios aportar\u00e1 respecto a lo que actualmente ya disponemos?\u201d (\u2026.), tengan por seguro que mucho \u201cvendemotos\u201d no bajar\u00eda de su torre de marfil, continuando con su \u201cinvestigaci\u00f3n de vanguardia\u201d <\/strong><\/span>\u00bfexiste la investigaci\u00f3n de retaguardia? Solo as\u00ed los ciudadanos recibir\u00edan buena informaci\u00f3n, aunque afortunadamente en menor cantidad, ya que una buena parte de las abundantes proclamas panfletarias de muchos colegas se esfumar\u00edan por arte de magia. El lector debe tener en cuenta que los cient\u00edficos (y m\u00e1s aun los procedentes de las universidades) hablan en p\u00fablico con harta frecuencia, y algunos casi diariamente. En consecuencia, no deber\u00edan padecer de miedo esc\u00e9nico. Por tanto si lo tienen (\u2026.). <strong><span style=\"color: #3366ff;\">Alegar la mala calidad de la prensa y\/o tergiversaci\u00f3n de sus palabras, es justificable a posteriori, jam\u00e1s a priori. Eso si. De producirse el caso<\/span><\/strong><span style=\"color: #3366ff;\"><span style=\"color: #333333;\"> (que dicho sea de paso no resulta ser infrecuente)<\/span> <strong>requiere que los editores y periodistas ineludiblemente se encuentren obligados a rectificar, actitud que lamentablemente tampoco resulta ser frecuente<\/strong><\/span>. \u00a1Quien est\u00e9 libre de pecado que tire la primera piedra!: ver\u00e9is como no surgir\u00e1 ning\u00fan lapidado. Pero sigamos con el texto de Fioravanti y Velho (\u2026.)<\/p>\n<p style=\"text-align: justify;\"><strong><em>Ser un mediador en lugar de un intermediario implica pensar de forma independiente y sopesando simult\u00e1neamente muchos puntos de vista, no s\u00f3lo el del descubridor\u00bb, ampliando la comprensi\u00f3n p\u00fablica de la ciencia y la mostrando la actividad cient\u00edfica como algo apasionante<\/em><\/strong><em>. De hecho, los <strong>cient\u00edficos suelen actuar de la manera opuesta<\/strong>. Franzoni advierte que los <strong>periodistas cient\u00edficos \u00abdeben adoptar una postura m\u00e1s neutral y cr\u00edtica, siendo conscientes de sus propias decisiones y perspectivas, informando al p\u00fablico de la implicaciones del descubrimiento, tanto positivas como negativas\u00bb<\/strong>. Resumiendo el periodista <strong>debe permanecer independiente<\/strong> tanto como le sea posible <strong>de todos los agentes implicados<\/strong>\u00ab. El enfoque propuesto por esta autora resulta ser mucho m\u00e1s amplio que el que defiende Meyers, quien pone de relieve la importancia de los intermediarios del conocimiento de tal modo, que no dejar\u00edan de ser un tipo especial de intermediarios.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em>Estas precisiones<\/em><\/strong><em> sobre la funci\u00f3n del periodista <strong>ayudar\u00e1n a aclarar la diferencia entre la comunicaci\u00f3n (diseminaci\u00f3n) de la ciencia y periodismo cient\u00edfico<\/strong>. Hollingham y Loder afirman que existe\u00a0 una de las grandes diferencias entre el periodismo y la comunicaci\u00f3n de la ciencia estriba en que el primero tiene <strong>la posibilidad de incluir puntos de vista m\u00e1s amplios<\/strong>, mientras que los cient\u00edficos implicados no tendr\u00edan que compartir tales opiniones necesariamente. Hollingham y Loder argumentan que a menudo, <strong>las iniciativas de los organismos o agencias gubernamentales en materia de periodismo cient\u00edfico, a menudo espetan las noticias como mera propaganda, socavando\u00a0 el inter\u00e9s y la confianza del p\u00fablico en los propios\u00a0 periodistas<\/strong>.<strong> El auge de los bloggers y la globosfera cient\u00edfica<\/strong>, muchos de los cuales son liderados por j\u00f3venes cient\u00edficos, <strong>ha creado una forma nueva y democr\u00e1tica para difundir noticias cient\u00edficas, reduciendo el rol del periodista como intermediario esencial<\/strong>. Al ser un mediador, va m\u00e1s all\u00e1 de la noticia com\u00fan pudiendo ayudar a los periodistas profesionales especializados en el tratamiento de la informaci\u00f3n con mayor profundidad.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Todos estos temas ya los hemos venido tratando en post precedentes\u00a0 (ver post pinchando aqu\u00ed<\/strong><\/span>: \u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-breve-sobre-periodismo-cientifico\">Curso Breve sobre Periodismo Cient\u00edfico<\/a>), por lo que no abundaremos en el tema. Eso s\u00ed, permitirme que para finalizar apostille la siguiente sentencia:<\/p>\n<p style=\"text-align: center;\"><strong><em><span style=\"color: #800000;\">El auge de los bloggers y la globosfera cient\u00edfica, muchos de los cuales son liderados por j\u00f3venes cient\u00edficos, ha creado una forma nueva y democr\u00e1tica para difundir noticias cient\u00edficas, reduciendo el rol del periodista como intermediario esencial<\/span><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Si analizamos los<span style=\"color: #3366ff;\"><strong> rotativos de prensa<\/strong><\/span>, al menos en Espa\u00f1a, podemos observar que, <span style=\"color: #3366ff;\"><strong>en sus versiones digitales, se han incluido numerosos blogs paulatinamente. Ahora bien, \u00bfCu\u00e1ntos de ellos son de ciencia, cuantos de pol\u00edtica, cuantos de deporte cuantos de econom\u00eda, cuentos de prensa \u201cdel coraz\u00f3n\u201d?. \u00bfCon que frecuencia se actualizan? <\/strong><\/span>Pues bien, aqu\u00ed las directrices de las editoriales muestran con toda su crudeza la realidad. Estos \u00faltimos padecen un palmario desinter\u00e9s por la ciencia, cuando no alergia.\u00a0 <span style=\"color: #3366ff;\"><strong>Somos muchos los investigadores los que aceptar\u00edamos de buen grado tal actividad que, dicho se de paso, no debiera ser una onerosa iniciativa, dada a la desigualdad entre oferta y demanda<\/strong><\/span> (los investigadores que aceptaran adquirir\u00edan mucho prestigio). Y dicho esto,<span style=\"color: #3366ff;\"> <strong>uno estar\u00eda tentado en echar toda la culpa a los editores. Ahora bien<\/strong><\/span>, esta \u00faltima sentencia de Fioravanti y Velho choca con <span style=\"color: #3366ff;\"><strong>la cruda realidad de los desdenes y descalificaciones de numerosos \u201c<em>plumillas<\/em>\u201d por el mundo de la blogosfera. En lugar de vernos como aliados nos alinean como enemigos. \u00bfMi opini\u00f3n? <\/strong><\/span>Se sienten inferiores y a menudo acomplejados (salvo honrosas excepciones). Y al adoptar este modo de proceder, quedan en evidencia sus enormes carencias y limitaciones, as\u00ed como un acusado gremialismo defensivo. Siempre existen honrosas excepciones, por supuesto.<\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-breve-sobre-periodismo-cientifico\">Otros post de nuestro Curso Breve sobre Periodismo Cient\u00edfico<\/a><\/p>\n<p><span style=\"color: #008080;\"><strong><em>Continuar\u00e1 (\u2026.)<\/em><\/strong><\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Continuamos con nuestro Curso Breve sobre Periodismo Cient\u00edfico, haciendo hoy referencia a un punto crucial entre dos perspectivas de hacer periodismo cient\u00edfico. Estas discernir\u00e1n si el \u201cplumillas\u201d se pode del lado de los poderes f\u00e1cticos, o de los intereses del ciudadano. Hoy por hoy, las noticias sobre la ciencia que podemos leer el los rotativos y notas de prensa institucionales, suelen colocar al periodista (voluntaria o involuntariamente) del lado de los poderes f\u00e1cticos. Y as\u00ed el ciudadano consume propaganda, alej\u00e1ndose de la verdadera esencia de c\u00f3mo funciona la indagaci\u00f3n investigadora. Tambi\u00e9n defenderemos la necesidad de cambiar el vocabulario y la\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[7651,615,606],"tags":[9016,47045,9017,47035],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Continuamos con nuestro Curso Breve sobre Periodismo Cient\u00edfico, haciendo hoy referencia a un punto crucial entre dos perspectivas de hacer periodismo cient\u00edfico. Estas discernir\u00e1n si el \u201cplumillas\u201d se pode del lado de los poderes f\u00e1cticos, o de los intereses del ciudadano. Hoy por hoy, las noticias sobre la ciencia que podemos leer el los rotativos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Continuamos con nuestro Curso Breve sobre Periodismo Cient\u00edfico, haciendo hoy referencia a un punto crucial entre dos perspectivas de hacer periodismo cient\u00edfico. Estas discernir\u00e1n si el \u201cplumillas\u201d se pode del lado de los poderes f\u00e1cticos, o de los intereses del ciudadano. Hoy por hoy, las noticias sobre la ciencia que podemos leer el los rotativos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-06-04T16:14:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-06-04T16:46:52+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Continuamos con nuestro Curso Breve sobre Periodismo Cient\u00edfico, haciendo hoy referencia a un punto crucial entre dos perspectivas de hacer periodismo cient\u00edfico. Estas discernir\u00e1n si el \u201cplumillas\u201d se pode del lado de los poderes f\u00e1cticos, o de los intereses del ciudadano. Hoy por hoy, las noticias sobre la ciencia que podemos leer el los rotativos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469#blogposting\",\"name\":\"Voceros de la Ciencia versus Periodismo Cient\\u00edfico Independiente (Curso de Periodismo Cient\\u00edfico y 7) - Un Universo invisible bajo nuestros pies\",\"headline\":\"Voceros de la Ciencia versus Periodismo Cient\\u00edfico Independiente (Curso de Periodismo Cient\\u00edfico y 7)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/159\\\/eusebio-sempere-haz-de-septifolios-1972.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469\\\/#articleImage\"},\"datePublished\":\"2011-06-04T17:14:07+01:00\",\"dateModified\":\"2011-06-04T17:46:52+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":7,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469#webpage\"},\"articleSection\":\"Curso breve sobre Periodismo Cient\\u00edfico, Notas Breves de Prensa, Prensa y Pol\\u00edtica Cient\\u00edfica, calidad, curso breve, noticias cient\\u00edficas, periodismo cient\\u00edfico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/prensa-y-politica-cientifica#listItem\",\"name\":\"Prensa y Pol\\u00edtica Cient\\u00edfica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/prensa-y-politica-cientifica#listItem\",\"position\":2,\"name\":\"Prensa y Pol\\u00edtica Cient\\u00edfica\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/prensa-y-politica-cientifica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469#listItem\",\"name\":\"Voceros de la Ciencia versus Periodismo Cient\\u00edfico Independiente (Curso de Periodismo Cient\\u00edfico y 7)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469#listItem\",\"position\":3,\"name\":\"Voceros de la Ciencia versus Periodismo Cient\\u00edfico Independiente (Curso de Periodismo Cient\\u00edfico y 7)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/prensa-y-politica-cientifica#listItem\",\"name\":\"Prensa y Pol\\u00edtica Cient\\u00edfica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469\",\"name\":\"Voceros de la Ciencia versus Periodismo Cient\\u00edfico Independiente (Curso de Periodismo Cient\\u00edfico y 7) - Un Universo invisible bajo nuestros pies\",\"description\":\"Continuamos con nuestro Curso Breve sobre Periodismo Cient\\u00edfico, haciendo hoy referencia a un punto crucial entre dos perspectivas de hacer periodismo cient\\u00edfico. Estas discernir\\u00e1n si el \\u201cplumillas\\u201d se pode del lado de los poderes f\\u00e1cticos, o de los intereses del ciudadano. Hoy por hoy, las noticias sobre la ciencia que podemos leer el los rotativos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/06\\\/04\\\/139469#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2011-06-04T17:14:07+01:00\",\"dateModified\":\"2011-06-04T17:46:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7) - Un Universo invisible bajo nuestros pies","description":"Continuamos con nuestro Curso Breve sobre Periodismo Cient\u00edfico, haciendo hoy referencia a un punto crucial entre dos perspectivas de hacer periodismo cient\u00edfico. Estas discernir\u00e1n si el \u201cplumillas\u201d se pode del lado de los poderes f\u00e1cticos, o de los intereses del ciudadano. Hoy por hoy, las noticias sobre la ciencia que podemos leer el los rotativos","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469#blogposting","name":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7) - Un Universo invisible bajo nuestros pies","headline":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/eusebio-sempere-haz-de-septifolios-1972.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469\/#articleImage"},"datePublished":"2011-06-04T17:14:07+01:00","dateModified":"2011-06-04T17:46:52+01:00","inLanguage":"es-ES","commentCount":7,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469#webpage"},"articleSection":"Curso breve sobre Periodismo Cient\u00edfico, Notas Breves de Prensa, Prensa y Pol\u00edtica Cient\u00edfica, calidad, curso breve, noticias cient\u00edficas, periodismo cient\u00edfico"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica#listItem","name":"Prensa y Pol\u00edtica Cient\u00edfica"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica#listItem","position":2,"name":"Prensa y Pol\u00edtica Cient\u00edfica","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469#listItem","name":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469#listItem","position":3,"name":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica#listItem","name":"Prensa y Pol\u00edtica Cient\u00edfica"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469","name":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7) - Un Universo invisible bajo nuestros pies","description":"Continuamos con nuestro Curso Breve sobre Periodismo Cient\u00edfico, haciendo hoy referencia a un punto crucial entre dos perspectivas de hacer periodismo cient\u00edfico. Estas discernir\u00e1n si el \u201cplumillas\u201d se pode del lado de los poderes f\u00e1cticos, o de los intereses del ciudadano. Hoy por hoy, las noticias sobre la ciencia que podemos leer el los rotativos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2011-06-04T17:14:07+01:00","dateModified":"2011-06-04T17:46:52+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7) - Un Universo invisible bajo nuestros pies","og:description":"Continuamos con nuestro Curso Breve sobre Periodismo Cient\u00edfico, haciendo hoy referencia a un punto crucial entre dos perspectivas de hacer periodismo cient\u00edfico. Estas discernir\u00e1n si el \u201cplumillas\u201d se pode del lado de los poderes f\u00e1cticos, o de los intereses del ciudadano. Hoy por hoy, las noticias sobre la ciencia que podemos leer el los rotativos","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2011-06-04T16:14:07+00:00","article:modified_time":"2011-06-04T16:46:52+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7) - Un Universo invisible bajo nuestros pies","twitter:description":"Continuamos con nuestro Curso Breve sobre Periodismo Cient\u00edfico, haciendo hoy referencia a un punto crucial entre dos perspectivas de hacer periodismo cient\u00edfico. Estas discernir\u00e1n si el \u201cplumillas\u201d se pode del lado de los poderes f\u00e1cticos, o de los intereses del ciudadano. Hoy por hoy, las noticias sobre la ciencia que podemos leer el los rotativos","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"139469","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:01:37","updated":"2026-05-26 16:47:53","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica\" title=\"Prensa y Pol\u00edtica Cient\u00edfica\">Prensa y Pol\u00edtica Cient\u00edfica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVoceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Prensa y Pol\u00edtica Cient\u00edfica","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica"},{"label":"Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/139469"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=139469"}],"version-history":[{"count":11,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/139469\/revisions"}],"predecessor-version":[{"id":139479,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/139469\/revisions\/139479"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=139469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=139469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=139469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}