{"id":140114,"date":"2011-10-28T13:00:48","date_gmt":"2011-10-28T12:00:48","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=140114"},"modified":"2011-10-29T13:02:05","modified_gmt":"2011-10-29T12:02:05","slug":"vertisoles-en-latinoamerica","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114","title":{"rendered":"Vertisoles en Latinoam\u00e9rica"},"content":{"rendered":"<p style=\"text-align: justify;\">Como ya os comentamos en alg\u00fan post precedente, <span style=\"color: #3366ff;\"><strong>Am\u00e9rica del Sur es el continente m\u00e1s h\u00famedo del mundo<\/strong><\/span>. Por el contrario, los <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/06\/140062\">Vertisoles<\/a> se <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/13\/140087\">distribuyen esencialmente<\/a>, bajo ciertas condiciones fisiogr\u00e1ficas y sobre materiales parentales muy concretos en los <span style=\"color: #3366ff;\"><strong>ambientes<\/strong> <strong>tropicales<\/strong> <strong>semi\u00e1ridos<\/strong><\/span>. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB, <strong><span style=\"color: #3366ff;\">no resulta muy abundante en Latinoam\u00e9rica, ocupando el quinceavo lugar, con aproximadamente 30.000.000 millones de hect\u00e1reas<\/span><\/strong>, de acuerdo al estudio llevado a cabo por Francisco Bautista y colaboradores (ver referencia y enlace al final de post). Los pa\u00edses en los que este tipo de suelos cubre mayores extensiones resultan ser: <span style=\"color: #3366ff;\"><strong>M\u00e9xico, Nicaragua, Cuba, Jamaica, Venezuela y Uruguay<\/strong><\/span>. En t\u00e9rminos relativos, que no absolutos, son importantes en los siguientes: <span style=\"color: #3366ff;\"><strong>Cuba, El Salvador, Hait\u00ed, M\u00e9xico y Uruguay<\/strong><\/span>. Abajo os muestro de nuevo el mapa de distribuci\u00f3n mundial de los Vertisoles. Este \u00faltimo nos informa que <span style=\"color: #3366ff;\"><strong>los paisajes m\u00e1s extensos con este edafotaxon podr\u00edan estar ubicados en M\u00e9xico y Uruguay<\/strong><\/span>. En consecuencia, se localizan preferentemente en <strong><span style=\"color: #3366ff;\">Mesoam\u00e9rica, Caribe y regi\u00f3n Austral de Sudam\u00e9rica<\/span>.<\/strong> Se trata de suelos <span style=\"color: #3366ff;\"><strong>muy productivos cuando se dispone de la adecuada tecnolog\u00eda. De no ser as\u00ed, tan solo es permisible una ganader\u00eda extensiva y\/o un uso forestal moderado<\/strong><\/span>.\u00a0 \u00a0<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/145\/vertisuelos-isric-grumi-pellic_vertisol_ni9.jpg\" alt=\"vertisuelos-isric-grumi-pellic_vertisol_ni9\" width=\"510\" height=\"662\" \/>\u00a0<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.isric.eu\/about-soils\/world-soil-distribution\/vertisols\">Vertisoles con propiedades gr\u00famicas y p\u00e9licas. Fuente: ISRIC<\/a><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">De acuerdo a Bautista y colaboradores<span style=\"color: #3366ff;\"> <strong>los Vertisoles son suelos que <\/strong><\/span>presentan un horizonte v\u00e9rtico dentro de los 100 cm. desde la superficies. Despu\u00e9s de los primeros 20 cm., todos los horizontes tienen 30% de <span style=\"color: #3366ff;\"><strong>arcilla <\/strong><\/span>hasta el contacto l\u00edtico o los 100 cm. de profundidad; los agregados son en forma de cu\u00f1a o paralelep\u00edpedos, muestran caras de deslizamiento y deben presentar <span style=\"color: #3366ff;\"><strong>grietas que se abren y cierran peri\u00f3dicamente<\/strong><\/span>. Se desarrollan en zonas en las que predomina la presencia de<span style=\"color: #3366ff;\"><strong> arcillas expandibles 2:1<\/strong><\/span> del grupo de la esmectita y se localizan en las partes bajas del relieve. <span style=\"color: #3366ff;\"><strong>Los Vertisoles se localizan en M\u00e9xico, Nicaragua, Cuba, Jamaica, Venezuela y Uruguay<\/strong><\/span>. Son muy pesados en la \u00e9poca de secas y pegajosos en la de <span style=\"color: #3366ff;\"><strong>lluvias, por lo que la labranza se realiza al comienzo de esta \u00faltima<\/strong><\/span>. El manejo del agua en estos suelos es clave para lograr altos rendimientos agr\u00edcolas. En diversos lugares, <span style=\"color: #3366ff;\"><strong>las siembras se realizan al final de las lluvias debido a <\/strong><\/span>que la cantidad de agua residual puede ser suficiente para algunos cultivos.<span style=\"color: #3366ff;\"><strong> Se utilizan para cultivos de ca\u00f1a de azucar, algodon, trigo, sorgo, ma\u00edz y arroz<\/strong>. Son comunes las <strong>aplicaciones de nitr\u00f3geno (N) y f\u00f3sforo (P) y, ocasionalmente, azufre (S) y zinc (Zn)<\/strong>.<\/span><\/p>\n<p style=\"text-align: center;\">\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/370\/vertisols-world-map-fao.gif\" alt=\"vertisols-world-map-fao\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">Mapa de Distribuci\u00f3n del Mundo de los Vertisoles. Fuente: FAO<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez \u00a0y Francisco Javier Manr\u00edquez Cosio <\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Material\u00a0 Bibliogr\u00e1fico<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/nr\/land\/soils\/soil\/en\">P\u00e1gina Web de la WRB<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"ftp:\/\/ftp.fao.org\/docrep\/fao\/011\/a0510s\/a0510s00.pdf\">Clasificaci\u00f3n WRB 2006-2007<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/DOCREP\/003\/Y1899E\/Y1899E00.HTM\">Lecture notes on the major soils of the world<\/a> (versi\u00f3n personal traducida al espa\u00f1ol por Javier Manr\u00edquez Cos\u00edo<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.inegi.org.mx\/prod_serv\/contenidos\/espanol\/bvinegi\/productos\/integracion\/especiales\/BoletinSNEIG\/2010\/Bsnieg14_b.pdf\">Los suelos de Latinoam\u00e9rica: retos y oportunidades de uso y estudio<\/a> (ir al titulo correspondiente) Autores: Francisco Bautista, Alfred J. Zinck y Silke Cram. Boleti\u00f3n del Sistema Nacional de Informaci\u00f3n Estad\u00edstica y Geogr\u00e1fica: VII(3) Septiembre-Diciembre 2009, p\u00e1ginas 94-142<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/esdb_archive\/eusoils_docs\/other\/EUR23439.pdf\">Soils of the European Union<\/a> (en Ingles)<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Post Previos y a Publicar en Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo hasta el 10 de Junio de 2011<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Leptosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/06\/136490\">Leptosoles<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/13\/136682\">Leptosoles: Geograf\u00eda Ambiente y Paisaje<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/28\/136691\">Leptosoles Uso y Manejo<\/a>;<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/04\/136695\">Leptosoles en Latinoam\u00e9rica<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/11\/136703\">Leptosoles en Europa<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/22\/136503\">Tipos de Leptosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Regosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/02\/136720\">Regosoles<\/a>; \u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/09\/136869\">Regosoles: Geograf\u00eda, Ambiente y Paisaje<\/a>;\u00a0<a title=\"Enlace permanente a Regosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/16\/136876\">Regosoles: Uso y Manejo<\/a>:\u00a0<a title=\"Enlace permanente a Regosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/24\/136882\">Regosoles en Latinoam\u00e9rica<\/a>;\u00a0<a title=\"Enlace permanente a Regosoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\">Regosoles en Europa<\/a>;\u00a0<a title=\"Enlace permanente a Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/04\/136894\">Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Fluvisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/06\/137193\">Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/13\/137830\">Deltas, Estuarios y Marismas<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/19\/137847\">Geoformas de las L\u00edneas de Costa Generadas por la Din\u00e1mica Marina (WRB-FAO 2000)<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/26\/137868\">Fluvisoles<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/02\/138188\">Fluvisoles ti\u00f3nicos<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/01\/137894\">Distribuci\u00f3n geogr\u00e1fica de los Fluvisoles<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/03\/137903\">Fluvisoles uso y manejo<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/04\/137912\">Fluvisoles en Latinoam\u00e9rica<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/07\/137923\">Fluvisoles en Europa<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/08\/137936\">Mapas de los tipos de suelos de Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Gleysoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/16\/138132\">Gleysoles<\/a>;\u00a0<a title=\"Enlace permanente a Gleysoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/24\/138158\">Gleysoles: Geograf\u00eda Ambiente y Paisaje<\/a> <a title=\"Enlace permanente a Gleysoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/25\/138174\">Gleysoles: Uso y Manejo<\/a>,\u00a0<a title=\"Enlace permanente a Gleysoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/28\/138196\">Gleysoles en Latinoam\u00e9rica<\/a>,\u00a0<a title=\"Enlace permanente a Gleysoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/01\/138204\">Gleysoles en Europa<\/a>,\u00a0<a title=\"Enlace permanente a Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/03\/138117\">Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Stagnosoles (WRB 2006-2007)<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/17\/138151\">Stagnosoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Histosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Histosoles (WRB 1998): Las Turberas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/30\/138691\">Histosoles (WRB 1998): Las Turberas<\/a>;\u00a0<a title=\"Enlace permanente a Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/05\/138702\">Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje<\/a>;\u00a0<a title=\"Enlace permanente a Histosoles Uso y Manejo (Turberas) (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/06\/138714\">Histosoles Uso y Manejo (Turberas) (WRB 1998)<\/a>;\u00a0<a title=\"Enlace permanente a Histosoles en Latinoam\u00e9rica Tropical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/08\/138760\">Histosoles en Latinoam\u00e9rica Tropical<\/a>;\u00a0<a title=\"Enlace permanente a Histosoles en Europa (Turberas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/11\/138742\">Histosoles en Europa (Turberas)<\/a>;\u00a0<a title=\"Enlace permanente a Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/20\/138751\">Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Cambisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/09\/139388\">Cambisoles<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/15\/139402\">Cambisoles: Geograf\u00eda Ambiente y Paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/22\/139434\">Cambisoles: Uso y Manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/23\/139458\">Cambisoles en Latinoam\u00e9rica<\/a>;\u00a0 <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/30\/139418\">Cambisoles en Europa<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/07\/139426\">Tipos de Cambisoles y Sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Arenosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Dunas y Paisajes Arenosos (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/12\/139706\">Dunas y Paisajes Arenosos (WRB 1998)<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/13\/139746\">Arenosoles<\/a>; <a title=\"Enlace permanente a Arenosoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/18\/139756\">Arenosoles: Geograf\u00eda; Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Arenosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/21\/139772\">Arenosoles: Uso y Manejo<\/a>; <a title=\"Enlace permanente a Arenosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/28\/139786\">Arenosoles en Latinoam\u00e9rica<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/04\/139794\">Arenosoles en Europa<\/a>; <a title=\"Enlace permanente a Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/11\/139800\">Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Vertisoles<\/strong><\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Como ya os comentamos en alg\u00fan post precedente, Am\u00e9rica del Sur es el continente m\u00e1s h\u00famedo del mundo. Por el contrario, los Vertisoles se distribuyen esencialmente, bajo ciertas condiciones fisiogr\u00e1ficas y sobre materiales parentales muy concretos en los ambientes tropicales semi\u00e1ridos. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB, no resulta muy abundante en Latinoam\u00e9rica, ocupando el quinceavo lugar, con aproximadamente 30.000.000 millones de hect\u00e1reas, de acuerdo al estudio llevado a cabo por Francisco Bautista y colaboradores (ver referencia y enlace al final de post). Los pa\u00edses en los que este tipo de suelos\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[603,1929,613,604],"tags":[1815,47092],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Como ya os comentamos en alg\u00fan post precedente, Am\u00e9rica del Sur es el continente m\u00e1s h\u00famedo del mundo. Por el contrario, los Vertisoles se distribuyen esencialmente, bajo ciertas condiciones fisiogr\u00e1ficas y sobre materiales parentales muy concretos en los ambientes tropicales semi\u00e1ridos. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vertisoles en Latinoam\u00e9rica - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Como ya os comentamos en alg\u00fan post precedente, Am\u00e9rica del Sur es el continente m\u00e1s h\u00famedo del mundo. Por el contrario, los Vertisoles se distribuyen esencialmente, bajo ciertas condiciones fisiogr\u00e1ficas y sobre materiales parentales muy concretos en los ambientes tropicales semi\u00e1ridos. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-10-28T12:00:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-10-29T12:02:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vertisoles en Latinoam\u00e9rica - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Como ya os comentamos en alg\u00fan post precedente, Am\u00e9rica del Sur es el continente m\u00e1s h\u00famedo del mundo. Por el contrario, los Vertisoles se distribuyen esencialmente, bajo ciertas condiciones fisiogr\u00e1ficas y sobre materiales parentales muy concretos en los ambientes tropicales semi\u00e1ridos. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114#blogposting\",\"name\":\"Vertisoles en Latinoam\\u00e9rica - Un Universo invisible bajo nuestros pies\",\"headline\":\"Vertisoles en Latinoam\\u00e9rica\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/145\\\/vertisuelos-isric-grumi-pellic_vertisol_ni9.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114\\\/#articleImage\"},\"datePublished\":\"2011-10-28T13:00:48+01:00\",\"dateModified\":\"2011-10-29T13:02:05+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":30,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114#webpage\"},\"articleSection\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Curso B\\u00e1sico: Tipos de Suelos del Mundo, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, Suelos de Latinoam\\u00e9rica, Vertisoles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem\",\"name\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem\",\"position\":2,\"name\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114#listItem\",\"name\":\"Vertisoles en Latinoam\\u00e9rica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114#listItem\",\"position\":3,\"name\":\"Vertisoles en Latinoam\\u00e9rica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem\",\"name\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114\",\"name\":\"Vertisoles en Latinoam\\u00e9rica - Un Universo invisible bajo nuestros pies\",\"description\":\"Como ya os comentamos en alg\\u00fan post precedente, Am\\u00e9rica del Sur es el continente m\\u00e1s h\\u00famedo del mundo. Por el contrario, los Vertisoles se distribuyen esencialmente, bajo ciertas condiciones fisiogr\\u00e1ficas y sobre materiales parentales muy concretos en los ambientes tropicales semi\\u00e1ridos. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2011\\\/10\\\/28\\\/140114#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2011-10-28T13:00:48+01:00\",\"dateModified\":\"2011-10-29T13:02:05+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Vertisoles en Latinoam\u00e9rica - Un Universo invisible bajo nuestros pies","description":"Como ya os comentamos en alg\u00fan post precedente, Am\u00e9rica del Sur es el continente m\u00e1s h\u00famedo del mundo. Por el contrario, los Vertisoles se distribuyen esencialmente, bajo ciertas condiciones fisiogr\u00e1ficas y sobre materiales parentales muy concretos en los ambientes tropicales semi\u00e1ridos. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB,","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114#blogposting","name":"Vertisoles en Latinoam\u00e9rica - Un Universo invisible bajo nuestros pies","headline":"Vertisoles en Latinoam\u00e9rica","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/145\/vertisuelos-isric-grumi-pellic_vertisol_ni9.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\/#articleImage"},"datePublished":"2011-10-28T13:00:48+01:00","dateModified":"2011-10-29T13:02:05+01:00","inLanguage":"es-ES","commentCount":30,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114#webpage"},"articleSection":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Curso B\u00e1sico: Tipos de Suelos del Mundo, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, Geograf\u00eda de Suelos y Megaedafolog\u00eda, Suelos de Latinoam\u00e9rica, Vertisoles"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem","name":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem","position":2,"name":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114#listItem","name":"Vertisoles en Latinoam\u00e9rica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114#listItem","position":3,"name":"Vertisoles en Latinoam\u00e9rica","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem","name":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114","name":"Vertisoles en Latinoam\u00e9rica - Un Universo invisible bajo nuestros pies","description":"Como ya os comentamos en alg\u00fan post precedente, Am\u00e9rica del Sur es el continente m\u00e1s h\u00famedo del mundo. Por el contrario, los Vertisoles se distribuyen esencialmente, bajo ciertas condiciones fisiogr\u00e1ficas y sobre materiales parentales muy concretos en los ambientes tropicales semi\u00e1ridos. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2011-10-28T13:00:48+01:00","dateModified":"2011-10-29T13:02:05+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Vertisoles en Latinoam\u00e9rica - Un Universo invisible bajo nuestros pies","og:description":"Como ya os comentamos en alg\u00fan post precedente, Am\u00e9rica del Sur es el continente m\u00e1s h\u00famedo del mundo. Por el contrario, los Vertisoles se distribuyen esencialmente, bajo ciertas condiciones fisiogr\u00e1ficas y sobre materiales parentales muy concretos en los ambientes tropicales semi\u00e1ridos. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB,","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2011-10-28T12:00:48+00:00","article:modified_time":"2011-10-29T12:02:05+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Vertisoles en Latinoam\u00e9rica - Un Universo invisible bajo nuestros pies","twitter:description":"Como ya os comentamos en alg\u00fan post precedente, Am\u00e9rica del Sur es el continente m\u00e1s h\u00famedo del mundo. Por el contrario, los Vertisoles se distribuyen esencialmente, bajo ciertas condiciones fisiogr\u00e1ficas y sobre materiales parentales muy concretos en los ambientes tropicales semi\u00e1ridos. En consecuencia, a escala global, este Grupo de Suelos de Referencia de la WRB,","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"140114","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:10:51","updated":"2026-05-26 17:01:53","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje\" title=\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje\">Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVertisoles en Latinoam\u00e9rica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje"},{"label":"Vertisoles en Latinoam\u00e9rica","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140114"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=140114"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140114\/revisions"}],"predecessor-version":[{"id":140678,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140114\/revisions\/140678"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=140114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=140114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=140114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}