{"id":140305,"date":"2012-03-07T15:12:47","date_gmt":"2012-03-07T14:12:47","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=140305"},"modified":"2012-03-07T15:12:47","modified_gmt":"2012-03-07T14:12:47","slug":"las-simbiosis-de-las-plantas-con-las-micorrizas-comercio-justo-y-teoria-de-juegos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305","title":{"rendered":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos"},"content":{"rendered":"<p style=\"text-align: justify;\">La simbiosis resulta ser una cooperaci\u00f3n entre dos o m\u00e1s especies.\u00a0Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo (&#8216;<em>fairer trading<\/em>&#8216;). Este es b\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos. Ya os hemos hablado de las <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/07\/04\/33555\">micorrizas<\/a>, as\u00ed como del <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/07\/03\/33416\">enorme entramado de cables<\/a> que generan por los que se intercambian los nutrientes y alimentos org\u00e1nicos <span style=\"color: #3366ff;\"><strong>entre las plantas y este tipo hongos, respectivamente<\/strong><\/span>. Hablamos de un componente vital de la<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/20\/31785\"> rizosfera<\/a>. Las hifas de estos hongos interaccionan y unen a las ra\u00edces, ramific\u00e1ndose por los\u00a0poros del suelo en busca de nutrientes. De este modo, la capacidad de exploraci\u00f3n de nutrimientos por los sistemas radiculares\u00a0de las plantas se agiganta sobre manera. Por su parte, las plantas exudan carbohidratos obtenidos mediante la fotos\u00edntesis con vistas a alimentar s esos hongos beneficiosos, gener\u00e1ndose una cooperaci\u00f3n que favorece a ambas especies. Recordar que los hongos no tienen tal capacidad de obtener energ\u00eda del sol. Ahora bien: <strong><span style=\"color: #3366ff;\">\u00bfQu\u00e9 mecanismos rigen tales intercambios? \u00bfDominan e imponen su poder las plantas sobre los hongos?.\u00a0 Pues va a ser que no<\/span><\/strong><span style=\"color: #3366ff;\">,<\/span> al menos en este caso. Al parecer, <span style=\"color: #3366ff;\"><strong>unas y otras cooperar\u00e1n si ambas maximizan sus beneficios potenciales, gener\u00e1ndose una especie de \u201ccomercio justo\u201d. De no ser as\u00ed, \u201cno hay negocio\u201d<\/strong>. <\/span>Tanto las plantas como los <a href=\"http:\/\/www.adesper.com\/biodiversidadfungica\/06.3.hongos_micorrizogenos.php\">hongos micorriz\u00f3genos<\/a> parecen jugar a la\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/01\/01\/110466\">teor\u00eda de juegos<\/a>. Se trata de algo as\u00ed como una especie de feria de ganado en el que se intercambian productos entre unos y otros (aqu\u00ed no hay dinero)<strong>, <span style=\"color: #3366ff;\">sonde\u00e1ndose mutuamente antes de llegar a un acuerdo mutuo que beneficie a ciertos pares de participantes. Y al hacerlo, las ofertas de las especies involucradas quiz\u00e1s cambien<\/span><\/strong>.<strong> <\/strong>Obviamente no defiendo una estricta relaci\u00f3n por pares, sino que tanto<span style=\"color: #3366ff;\"><strong> unos organismos como otros pueden negociar a m\u00e1s de dos bandas alcanzando\u00a0acuerdos semejantes\u00a0a una red comercial cualquiera<\/strong><\/span>. \u00a0\u00a0\u00a0<strong><\/strong><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/micorrizas-comercio-justo.jpg\" alt=\"micorrizas-comercio-justo\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.academicjournals.org\/AJB\/manuscripts\/manuscripts2003\/Decembermanuscripts2003\/Diop\/Diop.htm\">Micorrizas arbusculares y ra\u00edces de las plantas. Fuente: African Journal of Biotechnology<strong> <\/strong>Tahir Abdoulaye<\/a><\/p>\n<p style=\"text-align: justify;\"><!--more--><span style=\"color: #3366ff;\"><strong>Los autores defienden, como se mostrar\u00e1, que se trata de una diferencia que distingue la simbiosis de otro tipo de relaciones de mutualismo<\/strong><\/span>. Soslayo\u00a0pronunciarme sobre este asunto. No soy experto, por lo que desconozco los avances recientes en <a href=\"http:\/\/es.wikipedia.org\/wiki\/Fijaci\u00f3n_de_nitr\u00f3geno\">fijaci\u00f3n simbi\u00f3tica del nitr\u00f3geno<\/a> a cerca de <span style=\"color: #3366ff;\"><strong>como se genera la interacci\u00f3n beneficiosa entre los sistemas radiculares de las plantas y los microorganismos de tipo<em> rhizobium<\/em><\/strong><\/span>, por ejemplo. Sin embargo, parecen darse diversas posibilidades. <span style=\"color: #3366ff;\"><strong>\u00bfQu\u00e9 es mejor: la especificidad o el mercadeo? Incluso esta pregunta puede estar mal planteada. Me atrevo a conjeturar que el mercadeo entre varias especies confiere una mayor plasticidad de adaptaci\u00f3n al entorno, pero (\u2026..)<\/strong><\/span>. Tampoco estoy seguro que los resultados obtenidos por estos investigadores sean generalizables a todo un mundo tan diverso y antiguo como el de la relaci\u00f3n entre ra\u00edces y micorrizas, que se remonta tan atr\u00e1s (o casi) como al periodo de la invasi\u00f3n de la tierra emergida por las plantas vasculares. En cualquier caso, se me antoja una investigaci\u00f3n muy interesante, aunque tal vez sea por mi propia ignorancia. Eso s\u00ed, los autores hablan tanto de semejanzas con la econom\u00eda de mercado como con el comercio justo, lo cual demuestra su ignorancia de la econom\u00eda que sufrimos, que de justa no tiene nada.<\/p>\n<p><strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez <\/span> <\/strong><\/p>\n<p><span style=\"color: #008080;\"><strong>Resumen del trabajo original<\/strong><\/span><\/p>\n<p><a href=\"http:\/\/www.sciencemag.org\/content\/333\/6044\/880.abstract\">Reciprocal Rewards Stabilize Cooperation in the Mycorrhizal Simbiosis Kiers et al. (2011) Sience<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Plants and their arbuscular mycorrhizal fungal symbionts interact in complex underground networks involving multiple partners<\/strong>. This increases the potential for exploitation and defection by individuals, raising the question of how partners maintain a fair, two-way transfer of resources. <strong>We manipulated cooperation in plants and fungal partners to show that plants can detect, discriminate, and reward the best fungal partners with more carbohydrates. In turn, their fungal partners enforce cooperation by increasing nutrient transfer only to those roots providing more carbohydrates<\/strong>. On the basis of these observations we conclude that, <strong>unlike many other mutualisms, the symbiont cannot be \u201censlaved.\u201d Rather, the mutualism is evolutionarily stable because control is bidirectional, and partners offering the best rate of exchange are rewarded<\/strong>.<\/p>\n<p><span style=\"color: #008080;\"><strong>Traducci\u00f3n al Espa\u00f1ol-Castellano<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Las plantas y sus simbiontes de hongos micorriz\u00f3genos arbusculares interact\u00faan en complejas redes subterr\u00e1neas en las que participan socios m\u00faltiples<\/strong><\/span>. Tal proceso aumenta el potencial para la explotaci\u00f3n y comportamiento de los individuos, planteando la cuesti\u00f3n de <span style=\"color: #3366ff;\">c<strong>\u00f3mo act\u00faan los socios a la hora de mantener o no el juego de cooperaci\u00f3n de la transferencia de sus respectivos potenciales-recursos<\/strong><\/span>. Hemos manipulado la cooperaci\u00f3n entre las plantas y sus potenciales socios <a href=\"http:\/\/www.uv.mx\/cienciahombre\/revistae\/vol22num3\/articulos\/hongos\/index.html\">micorriz\u00f3genos<\/a>, demostrando que <span style=\"color: #3366ff;\"><strong>las plantas pueden detectar, discriminar, y premiar a los mejores socios de hongos prim\u00e1ndoles con m\u00e1s hidratos de carbono. A su vez, sus parejas f\u00fangicas inducen la cooperaci\u00f3n mediante el aumento de la transferencia de nutrientes a las ra\u00edces que les s\u00f3lo proporcionan m\u00e1s hidratos de carbono. Sobre la base de estas observaciones se concluye que, a diferencia de muchos otros mutualismos, los simbiontes no pueden ser \u00abesclavizados\u00bb<\/strong>. <strong>Por el contrario, el mutualismo es evolutivamente estable ya que el control resulta ser bidireccional<\/strong><\/span>, y los socios que ofrecen mejores intercambios son los premiados.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.sciencedaily.com\/releases\/2011\/08\/110821210224.htm\">Plants and Fungi Play the &#8216;Underground Market&#8217;<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>ScienceDaily (Aug. 22, 2011)<\/strong><\/span> \u2014 <strong>Plants and fungi co-operate and trade with each other on a biological &#8216;underground market&#8217;, changing their trading partners if they don&#8217;t get a fair deal<\/strong>.<\/p>\n<p style=\"text-align: justify;\">The finding was made by an international team, including Oxford University scientists, <strong>examining how plants trade energy-rich carbohydrate they make using photosynthesis for phosphorus fungi collect from the soil<\/strong>. They found that <strong>plants use their roots to actively search out fungi to trade with but will attempt to avoid &#8216;cheating&#8217; fungi which &#8216;hoard&#8217; phosphorus instead of paying their fair share in return for carbohydrate<\/strong>. A report of the research is published in this week&#8217;s Science.<\/p>\n<p style=\"text-align: justify;\">&#8216;This <strong>is one of the first recorded examples of a &#8216;biological market&#8217; <\/strong>operating in which both partners reward fair trading rather than one partner having the advantage and exploiting the other,&#8217; said Professor Stuart West of Oxford University&#8217;s Department of Zoology, an author of the paper. &#8216;<strong>We&#8217;ve shown that both plants and fungi can be choosy, &#8216;playing the market&#8217; and looking for a better trading partner if they aren&#8217;t getting a good deal<\/strong>.<\/p>\n<p style=\"text-align: justify;\">&#8216;The team used the plant<strong><em> Medicago truncatula<\/em>, which is related to alfalfa, and then observed its interactions with three different species of fungi<\/strong>; <em>Glomus intraradices, Glomus custos, and Glomus aggregatum<\/em>, <strong>which exhibit different levels of cooperation<\/strong>. They used radioactive tags to track the <strong>carbon produced by the plant and the phosphorus harvested by the fungi.<\/strong> The results showed that <strong>not only was more carbon supplied to the more cooperative &#8212; &#8216;fairer trading&#8217; &#8212; species of fungi but also that more phosphorus was supplied to more cooperative plants<\/strong>.<\/p>\n<p style=\"text-align: justify;\">&#8216;<strong>We think that this sort of biological market, reminiscent of a market economy<\/strong>, has arisen because there are so many different individuals either partner could trade with,&#8217; said Professor West. &#8216;Rather like with human traders, if they are given a chance both plants and fungi will go elsewhere to get a better deal.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Story Source<\/strong>:<\/span> The above story is reprinted (with editorial adaptations by ScienceDaily staff) from materials provided by <a href=\"http:\/\/www.ox.ac.uk\/\" target=\"_blank\">University of Oxford<\/a>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Journal Reference<\/strong><\/span>: E. T. Kiers, M. Duhamel, Y. Beesetty, J. A. Mensah, O. Franken, E. Verbruggen, C. R. Fellbaum, G. A. Kowalchuk, M. M. Hart, A. Bago, T. M. Palmer, S. A. West, P. Vandenkoornhuyse, J. Jansa, H. Bucking. Reciprocal Rewards Stabilize Cooperation in the Mycorrhizal Symbiosis. Science, 2011; 333 (6044): 880 DOI: <a href=\"http:\/\/dx.doi.org\/10.1126\/science.1208473\" target=\"_blank\">10.1126\/science.1208473<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.uv.mx\/cienciahombre\/revistae\/vol22num3\/articulos\/hongos\/index.html\">Sobre la coevoluci\u00f3n de Plantas y Micorrizas<\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>La simbiosis resulta ser una cooperaci\u00f3n entre dos o m\u00e1s especies.\u00a0Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo (&#8216;fairer trading&#8216;). Este es b\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos. Ya os hemos hablado de las micorrizas, as\u00ed como del enorme entramado de cables que generan por los que se intercambian los nutrientes y alimentos org\u00e1nicos entre las plantas y este tipo hongos, respectivamente. Hablamos de un componente vital de la rizosfera. Las hifas de\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,590,586,600],"tags":[47117,46936,9876,47118,9877],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La simbiosis resulta ser una cooperaci\u00f3n entre dos o m\u00e1s especies. Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo (&#039;fairer trading&#039;). Este es b\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"La simbiosis resulta ser una cooperaci\u00f3n entre dos o m\u00e1s especies. Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo (&#039;fairer trading&#039;). Este es b\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-03-07T14:12:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-03-07T14:12:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La simbiosis resulta ser una cooperaci\u00f3n entre dos o m\u00e1s especies. Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo (&#039;fairer trading&#039;). Este es b\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305#blogposting\",\"name\":\"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\\u00eda de Juegos - Un Universo invisible bajo nuestros pies\",\"headline\":\"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\\u00eda de Juegos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/163\\\/micorrizas-comercio-justo.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305\\\/#articleImage\"},\"datePublished\":\"2012-03-07T15:12:47+01:00\",\"dateModified\":\"2012-03-07T15:12:47+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":4,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Componentes, Estructuras y Procesos en los Suelos, Diversidad, Complejidad y Fractales, Los Suelos las Plantas y la Vegetaci\\u00f3n, comercio justo, micorrizas arbusculares, mutualismo, simbiosis, teor\\u00eda de juegos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"position\":2,\"name\":\"Diversidad, Complejidad y Fractales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305#listItem\",\"name\":\"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\\u00eda de Juegos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305#listItem\",\"position\":3,\"name\":\"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\\u00eda de Juegos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305\",\"name\":\"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\\u00eda de Juegos - Un Universo invisible bajo nuestros pies\",\"description\":\"La simbiosis resulta ser una cooperaci\\u00f3n entre dos o m\\u00e1s especies. Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo ('fairer trading'). Este es b\\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/03\\\/07\\\/140305#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2012-03-07T15:12:47+01:00\",\"dateModified\":\"2012-03-07T15:12:47+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos - Un Universo invisible bajo nuestros pies","description":"La simbiosis resulta ser una cooperaci\u00f3n entre dos o m\u00e1s especies. Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo ('fairer trading'). Este es b\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos.","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305#blogposting","name":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos - Un Universo invisible bajo nuestros pies","headline":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/micorrizas-comercio-justo.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305\/#articleImage"},"datePublished":"2012-03-07T15:12:47+01:00","dateModified":"2012-03-07T15:12:47+01:00","inLanguage":"es-ES","commentCount":4,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Componentes, Estructuras y Procesos en los Suelos, Diversidad, Complejidad y Fractales, Los Suelos las Plantas y la Vegetaci\u00f3n, comercio justo, micorrizas arbusculares, mutualismo, simbiosis, teor\u00eda de juegos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","position":2,"name":"Diversidad, Complejidad y Fractales","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305#listItem","name":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305#listItem","position":3,"name":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305","name":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos - Un Universo invisible bajo nuestros pies","description":"La simbiosis resulta ser una cooperaci\u00f3n entre dos o m\u00e1s especies. Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo ('fairer trading'). Este es b\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2012-03-07T15:12:47+01:00","dateModified":"2012-03-07T15:12:47+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos - Un Universo invisible bajo nuestros pies","og:description":"La simbiosis resulta ser una cooperaci\u00f3n entre dos o m\u00e1s especies. Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo ('fairer trading'). Este es b\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos.","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2012-03-07T14:12:47+00:00","article:modified_time":"2012-03-07T14:12:47+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos - Un Universo invisible bajo nuestros pies","twitter:description":"La simbiosis resulta ser una cooperaci\u00f3n entre dos o m\u00e1s especies. Ahora bien cada una de ellas debe velar por sus propios intereses, actuando todos los agentes involucrados en un juego que prime al comercio justo ('fairer trading'). Este es b\u00e1sicamente el mensaje que nos ofrece la noticia de hoy sobre el universo de los suelos.","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"140305","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:17:55","updated":"2026-05-26 17:11:49","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales\" title=\"Diversidad, Complejidad y Fractales\">Diversidad, Complejidad y Fractales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLas Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Diversidad, Complejidad y Fractales","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales"},{"label":"Las Simbiosis de Las Plantas con las Micorrizas: Comercio Justo y Teor\u00eda de Juegos","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/07\/140305"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140305"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=140305"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140305\/revisions"}],"predecessor-version":[{"id":141513,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140305\/revisions\/141513"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=140305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=140305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=140305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}