{"id":140771,"date":"2012-06-19T14:02:35","date_gmt":"2012-06-19T13:02:35","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=140771"},"modified":"2012-06-19T14:02:35","modified_gmt":"2012-06-19T13:02:35","slug":"biochar-personalizados-para-todo-tipo-de-suelos-y-cultivos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771","title":{"rendered":"Biochar Personalizados Para todo tipo de Suelos y Cultivos"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Una buena noticia para quien no sepa toda la verdad acerca de\u00a0este nuevo tipo de enmienda<\/strong><\/span>. Ahora bien, en esta bit\u00e1cora ya os hemos informado acerca de <span style=\"color: #3366ff;\"><strong>la historia del descubrimiento <\/strong><\/span>de tales compuestos sobradamente. Como vimos, las <span style=\"color: #3366ff;\"><strong>Terras Pretas do indio<\/strong> <strong>de la cuenca Amaz\u00f3nica atesoran un secreto que<\/strong><\/span>, si los cient\u00edficos estuvieran en lo cierto, <span style=\"color: #3366ff;\"><strong>podr\u00eda cambiar la agricultura del mundo<\/strong><\/span>. Todo comenz\u00f3 cuando el\u00a0explorador espa\u00f1ol <a title=\"Enlace permanente: Francisco de Orellana y la Cultura Perdida del Amazon\u00eda: Del Origen de las Terras Pretas a los Fertilizantes del Futuro\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/04\/90873\">Francisco de Orellana se encontr\u00f3 una cultura muy sofisticada, actualmente perdida en el Amazon\u00eda<\/a>. Nadie le crey\u00f3 en Espa\u00f1a. Ya <span style=\"color: #3366ff;\"><strong>en la d\u00e9cada de los a\u00f1os 60, investigadores brasile\u00f1os y holandeses descubrieron unos suelos antr\u00f3picos muy f\u00e9rtiles pero impropios de las condiciones edafogen\u00e9ticas que se dan naturalmente en el Amazon\u00eda<\/strong><\/span>. Y as\u00ed algunos cient\u00edficos del suelo <span style=\"color: #3366ff;\"><strong>recordaron la denominada leyenda de Orellana<\/strong><\/span>, que tras su regreso a las Cortes de Valladolid, describi\u00f3 unos cultivos y producciones impresionantes llevados a cabo por una cultura muy sofisticada hacia la desembocadura de la cuenca amaz\u00f3nica. Tales procedimientos se basaban en<span style=\"color: #3366ff;\"><strong> las sorprendentes propiedades que ellos incorporaban\u00a0a los suelos mediante una tecnolog\u00eda aun por descifrar en sus detalles<\/strong><\/span>. Es decir hablamos de\u00a0<a title=\"Enlace permanente: Francisco de Orellana y la Cultura Perdida del Amazon\u00eda: Del Origen de las Terras Pretas a los Fertilizantes del Futuro\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/04\/90873\">las Terras Pretas<\/a>. Sus propiedades y distribuci\u00f3n geogr\u00e1fica original os las desgranamos en los siguientes post: \u201c<a title=\"Enlace permanente: Terras Pretas: Propiedades y Fertilidad (Biochar o Agrichar)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/11\/91490\">Terras Pretas: Propiedades y Fertilidad (Biochar o Agrichar)<\/a>\u201dy \u201d<a title=\"Enlace permanente: Terras Pretas del Amazonas: Distribuci\u00f3n y Caracter\u00edsticas Generales\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/07\/91198\">Terras Pretas del Amazonas: Distribuci\u00f3n y Caracter\u00edsticas Generales<\/a>\u201d. Sin embargo,<span style=\"color: #3366ff;\"> <strong>como actualmente el negocio doblega a la buena ciencia, pronto se comenz\u00f3 a <\/strong><\/span>\u201cver el plumero\u201d a quienes <span style=\"color: #3366ff;\"><strong>comenzaron a patentar productos semejantes, elaborados con tecnolog\u00eda moderna, que ni de lejos igualaban las propiedades originales de<\/strong> <\/span>la materia org\u00e1nica que atesoraban las Terras Pretas (que tardaba miles de a\u00f1os en descomponerse, entre otras numerosas sorpresas) elaboradas por los ind\u00edgenas como os hicimos ver en el siguiente post: \u201c<a title=\"Enlace permanente: Biocarb\u00f3n, Fertilidad de Suelos y Cambio Clim\u00e1tico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/05\/25\/118840\">Biocarb\u00f3n, Fertilidad de Suelos y Cambio Clim\u00e1tico<\/a>\u201d. De hecho, si uno atiende a las descripciones originales que se publicaron en las revistas cient\u00edficas del mayor prestigio, <span style=\"color: #3366ff;\"><strong>no puede hablarse de un fertilizante<\/strong> <span style=\"color: #000000;\">propiamente dicho,<\/span> <strong>sino de un<\/strong> \u201c<strong>estructurador de las propiedades f\u00edsicas del suelo<\/strong><\/span>\u201d. Es decir, un compuesto elaborado bajo combusti\u00f3n lenta y bajas concentraciones de ox\u00edgeno (la noticia que os ofrecemos hoy parece incorrecta, en este sentido) de ciclo de vida ilimitado a escala humana, que mejoraba incre\u00edblemente las propiedades de los horizontes superficiales con vistas a retener agua, nutrientes etc. En consecuencia, <span style=\"color: #3366ff;\"><strong>cuando los abor\u00edgenes les a\u00f1ad\u00edan genuinos fertilizantes org\u00e1nicos, estos eran retenidos durante\u00a0 mucho m\u00e1s tiempo y de una forma extraordinariamente eficiente<\/strong><\/span>. Pues bien, <span style=\"color: #3366ff;\"><strong>ninguna de tales propiedades han sido demostradas por los nuevos productos comerciales, que tan solo mejoran \u201cun poco\u201d las condiciones del suelo<\/strong>. <strong>Pero la historia no termina aqu\u00ed (\u2026)<\/strong><\/span>.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/949\/biocharproject-proyect-austalia.jpg\" alt=\"biocharproject-proyect-austalia\" width=\"526\" height=\"108\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/biocharproject.org\/tag\/biochar-conditioning\">Estructura interna del Biochar Tecnol\u00f3gico. Fuente: Biocharproject Proyect Austalia<\/a><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>En vista que a los investigadores y compa\u00f1\u00edas no les sal\u00edan las cuentas de lo que hab\u00edan comentado al p\u00fablico, comenz\u00f3 una maniquea campa\u00f1a de marketing, que por desgracia no aun no ha terminado. En principio<\/strong><\/span>, tras el fracaso de las expectativas, se hac\u00eda ver que, al margen de su eficacia fertilizante o de enmienda (aun buena parte de los expertos no parecen percatarse de que no se trata de eso, sino de un producto mucho m\u00e1s interesante que la tecnolog\u00eda moderna no sabe emular) secuestraba carbono de la atm\u00f3sfera, animando a la ONU a que lo recomendara en la lucha contra el cambio clim\u00e1tico (<span style=\"color: #800000;\"><strong>estrategia 2 en 1<\/strong><\/span>). Sin embargo, la estratagema no debi\u00f3 conseguir los fines perseguidos por la industria implicada. Seguidamente, se logr\u00f3 obtener un residuo org\u00e1nico en la elaboraci\u00f3n del bioetanol, por lo que de los mismos residuos org\u00e1nicos se produc\u00eda combustible, biochar y de paso (\u201cindirectamente\u201d) el secuestro de carbono atmosf\u00e9rico (<span style=\"color: #800000;\"><strong>estrategia 3 en 1<\/strong><\/span>). A pesar de todo, los resultados en parcelas experimentales no han debido ser tan claros en lo concerniente a las bondades del <span style=\"color: #3366ff;\"><strong>biochar tecnol\u00f3gico<\/strong><\/span>. Tanto es as\u00ed que en el \u201c<a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/news.xml\">Soil Portal<\/a>\u201d del Bur\u00f3 Europeo de Suelos se muestra un proyecto para llevar a cabo en <a href=\"https:\/\/www.google.com\/search?q=meta+analisis+Wikipedia&amp;hl=es&amp;tbm=shop&amp;aq=f\">Metaan\u00e1lisis<\/a> <span style=\"color: #3366ff;\"><strong>que aclare los beneficios del biochar<\/strong><\/span>, ya que los beneficios obtenidos hasta la fecha sobre esta sustancia den resultar un tanto confusos. Si pinch\u00e1is sobre lo que significa tal tipo de an\u00e1lisis os dar\u00e9is cuenta que no se trata, ni m\u00e1s ni menos, que de <span style=\"color: #3366ff;\"><strong>herramientas matem\u00e1ticas con vistas a extraer \u201corden del ruido\u201d, es decir patrones de una serie de experiencias cuyos resultados se antojan ambiguos<\/strong><\/span>.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/949\/biochar-terra-preta-fuente-terrabiochar.jpg\" alt=\"biochar-terra-preta-fuente-terrabiochar\" width=\"506\" height=\"289\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.terrabiochar.com\/biochar\">Las Aparentes Ventajas del Biochar. Fuente: Terra&amp;Biochar<\/a><\/p>\n<p style=\"text-align: justify;\">Y as\u00ed, <span style=\"color: #3366ff;\"><strong>a d\u00eda de hoy, el secreto de las Terras Pretas permanece siendo un misterio, mientras que los productos comerciales que se venden en el mercado defraudan las expectativas prometidas<\/strong>.<strong> Y para m\u00e1s INRI, en este contexto<\/strong><\/span>, como ver\u00e9is seguidamente con resultados m\u00e1s bien pobres,<span style=\"color: #3366ff;\"> <strong>sigue la huida hacia delante<\/strong> <\/span>aunque esta vez haciendo uso de la m\u00e1s <strong><span style=\"color: #3366ff;\">pura demagogia<\/span> <span style=\"color: #800000;\">(estrategia 1000 en 1)<\/span><\/strong>.\u00a0 La nota de Prensa que ha lanzado el<span style=\"color: #3366ff;\"> <strong>Noticiero ARS<\/strong><\/span>, en base a unos resultados que nos informan de unas propiedades \u201cligeramente\u201d mejorantes, <span style=\"color: #3366ff;\"><strong>se defiende que en el futuro se elaborar\u00e1 biochar a la carta para todas las necesidades y tipos de suelos<\/strong><\/span>.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/949\/biochar_benefits_tree-fuente-dairy-biochar.jpg\" alt=\"biochar_benefits_tree-fuente-dairy-biochar\" width=\"472\" height=\"741\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.dairybiocharcompost.com\/Biochar_Benefits_Tree.html\">Las Ventajas del biochar Puro Marketing. Fuente DairyBiocharCompost<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Incre\u00edble estrategia de marketing empresarial que lo \u00fanico que muestra es (i)<\/strong><\/span> la incapacidad de nuestra portentosa tecnolog\u00eda y brillantes cerebros con vistas a lograr\u00a0 arrebatar el secreto de c\u00f3mo\u00a0 aquellos ind\u00edgenas del Amazon\u00eda elaboraban el biochar (algo que deber\u00eda sonrojar a toda la comunidad cient\u00edfica)<span style=\"color: #3366ff;\"> <strong>y (ii)<\/strong><\/span> que es mejor una huida hacia adelante que seguir indagando en las entra\u00f1as de estos maravillosos suelos antr\u00f3picos. <span style=\"color: #3366ff;\"><strong>A esta \u201cporcanda\u201d la denominan<\/strong> <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/17\/138981\">investigaci\u00f3n trasnacional<\/a>. \u00bfY debemos creer que la ciencia contempor\u00e1nea se conduce por los derroteros correctos?.\u00a0 \u00a1No cuela!. Parte de la indagaci\u00f3n cient\u00edfica de nuestros d\u00edas se torna chapucera por momentos.<\/p>\n<p style=\"text-align: justify;\">Debe quedar constancia que, cuando hace a\u00f1os comenc\u00e9 a leer sobre el tema, yo tambi\u00e9n me entusiasm\u00e9. Y <span style=\"color: #3366ff;\"><strong>si las descripciones originales son correctas, el secreto aun se encuentra ah\u00ed, por esclarecer<\/strong><\/span>. Y de conseguirlo, reiteramos que <span style=\"color: #3366ff;\"><strong>podr\u00eda cambiar la agricultura mundial, eliminando los costosos y contaminantes fertilizantes derivados del petr\u00f3leo<\/strong><\/span>. Ahora bien, personalmente comienzo a albergar dudas. <span style=\"color: #3366ff;\"><strong>\u00bfFueron las descripciones originalmente publicadas en las revistas de alto impacto un reflejo de la verdadera naturaleza del biochar?<\/strong><\/span> \u00bfSe exageraron por razones comerciales? \u00a0\u00bfNo se tratar\u00eda entonces de una mala praxis cient\u00edfica?. Francamente no tengo respuesta.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/949\/biochar-fertilizacion-biochar-tecnologico-biocharproject-proyect-austalia.jpg\" alt=\"biochar-fertilizacion-biochar-tecnologico-biocharproject-proyect-austalia\" width=\"502\" height=\"336\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/biocharproject.org\/tag\/biochar-conditioning\">Enmienda de un Biochar Tecnol\u00f3gico. Fuente: Biocharproject Proyect Austalia<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>De esta historia extraigo alguna lecci\u00f3n que espero que pueda serviros a vosotros<\/strong><\/span>. \u00a0A menudo, en nuestros d\u00edas, un experto debe seguir tanto las investigaciones publicadas, como las estrategias de marketing que lanzan al p\u00fablico los cient\u00edficos y empresas implicadas. De no ser as\u00ed no entender\u00e1 la verdadera naturaleza del problema. Finalmente, las susodichas estratagemas empresariales se fijan en la mente de la comunidad cient\u00edfica como \u201cleyendas\u201d, avanzando sin mirar atr\u00e1s, lo que significa que se pierde la verdadera esencia de los motivos que originaron tal prospecci\u00f3n por varios equipos de investigaci\u00f3n. \u00a0Ahora bien, \u00bfes que el vocablo biochar es sin\u00f3nimo de poder publicar en revistas indexadas con mayor facilidad que si nos dedicamos a otros menesteres? \u00a1Bien pudiera ser el caso!, por cuanto actualmente el continente (envoltorio) prima sobre el contenido.<\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<h3><strong>Utilizaci\u00f3n del biochar para aumentar la humedad del suelo<\/strong><\/h3>\n<p>Por <a href=\"http:\/\/is\/contacts.htm#Ann\" target=\"_blank\">Ann Perry<\/a>; 8 de noviembre de 2011<\/p>\n<p style=\"text-align: justify;\">Cient\u00edficos del <a href=\"http:\/\/www.ars.usda.gov\/main\/main.htm?language=spanish\" target=\"_blank\">Servicio de Investigaci\u00f3n Agr\u00edcola<\/a> (ARS) est\u00e1n dirigiendo los esfuerzos de <strong>aprender m\u00e1s sobre &#8216;biochar&#8217;, el cual es la biomasa carbonizada a base de madera, otro material vegetal, y el esti\u00e9rcol<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Estos estudios por cient\u00edficos del ARS en laboratorios en todas partes de EE.UU. apoyan las prioridades del <a href=\"http:\/\/www.usda.gov\/wps\/portal\/usda\/usdahome?navid=EN_ESPANOL\" target=\"_blank\">Departamento de Agricultura de EE.UU.<\/a> (USDA por sus siglas en ingl\u00e9s) de <strong>promover la seguridad alimentaria internacional y responder al cambio clim\u00e1tico global<\/strong>. <strong>ARS es la agencia principal de investigaciones cient\u00edficas del USDA<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Cient\u00edfico del suelo <a href=\"http:\/\/www.ars.usda.gov\/pandp\/people\/people.htm?personid=24434\" target=\"_blank\">Jeff Novak<\/a> en el <a href=\"http:\/\/www.ars.usda.gov\/main\/site_main.htm?modecode=66-57-00-00\" target=\"_blank\">Centro de las Llanuras Costeras para la Investigaci\u00f3n de Suelo, Agua y Plantas<\/a> mantenido por el ARS en Florence, Carolina del Sur, est\u00e1 coordinando el proyecto, el cual involucra m\u00faltiples sitios. <strong>\u00c9l dirigi\u00f3 un estudio de laboratorio para determinar si diferentes biochars podr\u00edan mejorar los suelos arenosos de las llanuras costeras de las Carolinas, y los suelos derivados de la ceniza volc\u00e1nica en la regi\u00f3n del Pac\u00edfico Noroeste de EE.UU<\/strong>.<\/p>\n<p style=\"text-align: justify;\">El grupo dirigido por Novak u<strong>s\u00f3 c\u00e1scaras de cacahuetes y pacanas<\/strong>, los desperdicios av\u00edcolas, el c\u00e9sped<em> Panicum virgatum<\/em> y <strong>desechos de maderas duras para producir nueve tipos de biochars<\/strong>. Todas las materias primas pasaron por<strong> el proceso llamado pir\u00f3lisis en dos diferentes temperaturas para producir los biochars<\/strong>. <strong>La pir\u00f3lisis es<\/strong> un proceso de descomposici\u00f3n que resulta del calentamiento r\u00e1pido de las materias primas en ausencia de ox\u00edgeno. Luego <strong>los investigadores mezclaron los biochars con uno tipo de suelo arenoso y dos tipos de suelo a base de la ceniza volc\u00e1nica en una tasa de aproximadamente 20 toneladas por acre<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Despu\u00e9s de cuatro meses, el grupo descubri\u00f3 que<strong> los biochars producidos del c\u00e9sped<em> P. virgatum<\/em> y de las maderas duras aumentaron la humedad del suelo en todos los tres tipos de suelo. El aumento m\u00e1s grande ocurri\u00f3 en los suelos enmendados con el biochar a base del c\u00e9sped y producido con la pir\u00f3lisis con las temperaturas altas<\/strong>. Estos suelos <strong>contuvieron casi el 3 al 6 por ciento m\u00e1s humedad que los niveles en una muestra de suelo no enmendado<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Los biochars producidos con temperaturas m\u00e1s altas tambi\u00e9n aumentaron los niveles del pH en el suelo<\/strong>, y el biochar a base de los desperdicios av\u00edcolas significativamente a<strong>umentaron los niveles de f\u00f3sforo y sodio disponibles en el suel<\/strong>o. Los cient\u00edficos calcularon que las enmiendas a base de biochar del c\u00e9sped <em>P. virgatum<\/em> <strong>podr\u00edan prolongar la disponibilidad de la humedad del suelo de 1 a 3,6 d\u00edas<\/strong> para un cultivo de soja en Florence, <strong>y podr\u00edan prolongar la disponibilidad de la humedad del suelo de 0,4 a 2,5 d\u00edas para l<\/strong>os cultivos en los suelos a base de la ceniza volc\u00e1nico en la regi\u00f3n del Pac\u00edfico Noroeste.<\/p>\n<p style=\"text-align: justify;\">Basado en sus resultados, el grupo cree que los productores agr\u00edcolas alg\u00fan d\u00eda podr\u00edan seleccionar las materias primas y los procesos espec\u00edficos de pir\u00f3lisis para <strong>crear biochars \u00abhechos a la medida\u00bb <\/strong>con caracter\u00edsticas que <strong>ayudan a resolver deficiencias espec\u00edficas en diferentes tipos de suelo<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Los resultados de esta investigaci\u00f3n han sido publicados en &#8216;<a href=\"http:\/\/www.aes.neu.edu\/\" target=\"_blank\">Annals of Environmental Science<\/a>&#8216; (Anales de Ciencia Ambiental) y &#8216;<a href=\"https:\/\/www.agronomy.org\/publications\/jeq\" target=\"_blank\">Journal of Environmental Quality<\/a>&#8216; (Revista de Calidad Ambiental).<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.ars.usda.gov\/is\/AR\/archive\/nov11\/biochar1111.htm\" target=\"_blank\">Lea m\u00e1s<\/a> sobre esta investigaci\u00f3n en la revista &#8216;Agricultural Research&#8217; de noviembre-diciembre del 2011.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Una buena noticia para quien no sepa toda la verdad acerca de\u00a0este nuevo tipo de enmienda. Ahora bien, en esta bit\u00e1cora ya os hemos informado acerca de la historia del descubrimiento de tales compuestos sobradamente. Como vimos, las Terras Pretas do indio de la cuenca Amaz\u00f3nica atesoran un secreto que, si los cient\u00edficos estuvieran en lo cierto, podr\u00eda cambiar la agricultura del mundo. Todo comenz\u00f3 cuando el\u00a0explorador espa\u00f1ol Francisco de Orellana se encontr\u00f3 una cultura muy sofisticada, actualmente perdida en el Amazon\u00eda. Nadie le crey\u00f3 en Espa\u00f1a. Ya en la d\u00e9cada de los a\u00f1os 60, investigadores brasile\u00f1os y holandeses descubrieron\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,608,591,599,613,597,605,587,606,595],"tags":[7732,47175,47176,46775,47177,47180,47178,47179],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Una buena noticia para quien no sepa toda la verdad acerca de este nuevo tipo de enmienda. Ahora bien, en esta bit\u00e1cora ya os hemos informado acerca de la historia del descubrimiento de tales compuestos sobradamente. Como vimos, las Terras Pretas do indio de la cuenca Amaz\u00f3nica atesoran un secreto que, si los cient\u00edficos estuvieran en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Biochar Personalizados Para todo tipo de Suelos y Cultivos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Una buena noticia para quien no sepa toda la verdad acerca de este nuevo tipo de enmienda. Ahora bien, en esta bit\u00e1cora ya os hemos informado acerca de la historia del descubrimiento de tales compuestos sobradamente. Como vimos, las Terras Pretas do indio de la cuenca Amaz\u00f3nica atesoran un secreto que, si los cient\u00edficos estuvieran en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-06-19T13:02:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-06-19T13:02:35+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Biochar Personalizados Para todo tipo de Suelos y Cultivos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Una buena noticia para quien no sepa toda la verdad acerca de este nuevo tipo de enmienda. Ahora bien, en esta bit\u00e1cora ya os hemos informado acerca de la historia del descubrimiento de tales compuestos sobradamente. Como vimos, las Terras Pretas do indio de la cuenca Amaz\u00f3nica atesoran un secreto que, si los cient\u00edficos estuvieran en\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771#blogposting\",\"name\":\"Biochar Personalizados Para todo tipo de Suelos y Cultivos - Un Universo invisible bajo nuestros pies\",\"headline\":\"Biochar Personalizados Para todo tipo de Suelos y Cultivos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/949\\\/biocharproject-proyect-austalia.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771\\\/#articleImage\"},\"datePublished\":\"2012-06-19T14:02:35+01:00\",\"dateModified\":\"2012-06-19T14:02:35+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Biomasa y Necromasa en los Suelos: Ra\\u00edces y Materia Org\\u00e1nica, Edafolog\\u00eda y Pol\\u00edtica, Etnoedafolog\\u00eda y Conocimiento Campesino, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Fraude y Mala Praxis Cient\\u00edfica, La Crisis de la Edafolog\\u00eda, Prensa y Pol\\u00edtica Cient\\u00edfica, Suelos y Cambio Clim\\u00e1tico, amazon\\u00eda, Biochar, corrector del suelo, etnoedafolog\\u00eda, fertilizante, la estrategia del capital, misterio sin descubrir, Terra Preta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"name\":\"La Crisis de la Edafolog\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"position\":2,\"name\":\"La Crisis de la Edafolog\\u00eda\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771#listItem\",\"name\":\"Biochar Personalizados Para todo tipo de Suelos y Cultivos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771#listItem\",\"position\":3,\"name\":\"Biochar Personalizados Para todo tipo de Suelos y Cultivos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"name\":\"La Crisis de la Edafolog\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771\",\"name\":\"Biochar Personalizados Para todo tipo de Suelos y Cultivos - Un Universo invisible bajo nuestros pies\",\"description\":\"Una buena noticia para quien no sepa toda la verdad acerca de este nuevo tipo de enmienda. Ahora bien, en esta bit\\u00e1cora ya os hemos informado acerca de la historia del descubrimiento de tales compuestos sobradamente. Como vimos, las Terras Pretas do indio de la cuenca Amaz\\u00f3nica atesoran un secreto que, si los cient\\u00edficos estuvieran en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/06\\\/19\\\/140771#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2012-06-19T14:02:35+01:00\",\"dateModified\":\"2012-06-19T14:02:35+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Biochar Personalizados Para todo tipo de Suelos y Cultivos - Un Universo invisible bajo nuestros pies","description":"Una buena noticia para quien no sepa toda la verdad acerca de este nuevo tipo de enmienda. Ahora bien, en esta bit\u00e1cora ya os hemos informado acerca de la historia del descubrimiento de tales compuestos sobradamente. Como vimos, las Terras Pretas do indio de la cuenca Amaz\u00f3nica atesoran un secreto que, si los cient\u00edficos estuvieran en","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771#blogposting","name":"Biochar Personalizados Para todo tipo de Suelos y Cultivos - Un Universo invisible bajo nuestros pies","headline":"Biochar Personalizados Para todo tipo de Suelos y Cultivos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/949\/biocharproject-proyect-austalia.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771\/#articleImage"},"datePublished":"2012-06-19T14:02:35+01:00","dateModified":"2012-06-19T14:02:35+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Biomasa y Necromasa en los Suelos: Ra\u00edces y Materia Org\u00e1nica, Edafolog\u00eda y Pol\u00edtica, Etnoedafolog\u00eda y Conocimiento Campesino, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Fraude y Mala Praxis Cient\u00edfica, La Crisis de la Edafolog\u00eda, Prensa y Pol\u00edtica Cient\u00edfica, Suelos y Cambio Clim\u00e1tico, amazon\u00eda, Biochar, corrector del suelo, etnoedafolog\u00eda, fertilizante, la estrategia del capital, misterio sin descubrir, Terra Preta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","name":"La Crisis de la Edafolog\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","position":2,"name":"La Crisis de la Edafolog\u00eda","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771#listItem","name":"Biochar Personalizados Para todo tipo de Suelos y Cultivos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771#listItem","position":3,"name":"Biochar Personalizados Para todo tipo de Suelos y Cultivos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","name":"La Crisis de la Edafolog\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771","name":"Biochar Personalizados Para todo tipo de Suelos y Cultivos - Un Universo invisible bajo nuestros pies","description":"Una buena noticia para quien no sepa toda la verdad acerca de este nuevo tipo de enmienda. Ahora bien, en esta bit\u00e1cora ya os hemos informado acerca de la historia del descubrimiento de tales compuestos sobradamente. Como vimos, las Terras Pretas do indio de la cuenca Amaz\u00f3nica atesoran un secreto que, si los cient\u00edficos estuvieran en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2012-06-19T14:02:35+01:00","dateModified":"2012-06-19T14:02:35+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Biochar Personalizados Para todo tipo de Suelos y Cultivos - Un Universo invisible bajo nuestros pies","og:description":"Una buena noticia para quien no sepa toda la verdad acerca de este nuevo tipo de enmienda. Ahora bien, en esta bit\u00e1cora ya os hemos informado acerca de la historia del descubrimiento de tales compuestos sobradamente. Como vimos, las Terras Pretas do indio de la cuenca Amaz\u00f3nica atesoran un secreto que, si los cient\u00edficos estuvieran en","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2012-06-19T13:02:35+00:00","article:modified_time":"2012-06-19T13:02:35+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Biochar Personalizados Para todo tipo de Suelos y Cultivos - Un Universo invisible bajo nuestros pies","twitter:description":"Una buena noticia para quien no sepa toda la verdad acerca de este nuevo tipo de enmienda. Ahora bien, en esta bit\u00e1cora ya os hemos informado acerca de la historia del descubrimiento de tales compuestos sobradamente. Como vimos, las Terras Pretas do indio de la cuenca Amaz\u00f3nica atesoran un secreto que, si los cient\u00edficos estuvieran en","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"140771","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 14:50:09","updated":"2026-05-26 17:19:57","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia\" title=\"La Crisis de la Edafolog\u00eda\">La Crisis de la Edafolog\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBiochar Personalizados Para todo tipo de Suelos y Cultivos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"La Crisis de la Edafolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia"},{"label":"Biochar Personalizados Para todo tipo de Suelos y Cultivos","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/19\/140771"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140771"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=140771"}],"version-history":[{"count":9,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140771\/revisions"}],"predecessor-version":[{"id":142272,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140771\/revisions\/142272"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=140771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=140771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=140771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}